{"id":72189,"date":"2010-08-16T11:30:01","date_gmt":"2010-08-16T11:30:01","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/08\/16\/le-fantome-qui-ne-veut-pas-mourir\/"},"modified":"2010-08-16T11:30:01","modified_gmt":"2010-08-16T11:30:01","slug":"le-fantome-qui-ne-veut-pas-mourir","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/08\/16\/le-fantome-qui-ne-veut-pas-mourir\/","title":{"rendered":"Le fant\u00f4me qui ne veut pas mourir"},"content":{"rendered":"<p><p>Le fant\u00f4me, c&rsquo;est la Grande D\u00e9pression. Divers \u00e9conomistes US de gauche (interventionnistes, rooseveltiens, keyn\u00e9siens, etc.) d\u00e9noncent plus que jamais une situation qui a aujourd&rsquo;hui, <strong>aux USA<\/strong>, des similitudes <strong>structurelles<\/strong> avec la Grande D\u00e9pression. Cela signifie qu&rsquo;ils se r\u00e9f\u00e8rent \u00e0 cet \u00e9v\u00e9nement \u00e9conomique catastrophique qui dura bien plus que les ann\u00e9es 1931-1933 habituellement cit\u00e9es, mais, au moins, durant les ann\u00e9es 1931-1941. On se r\u00e9f\u00e8re aujourd&rsquo;hui au commentaire furieux de Robert Reich, que nous citions ce <a href=\"http:\/\/www.dedefensa.org\/article-le_spectre_de_la_grande_depression_plus_que_jamais_16_08_2010.html?admin=1\" class=\"gen\">16 ao\u00fbt 2010<\/a> en rubrique <em>Ouverture libre<\/em>.<\/p>\n<\/p>\n<p><p>\tCette r\u00e9f\u00e9rence de la Grande D\u00e9pression est infiniment plus puissante aux USA que dans le reste du monde. Elle a cette force parce qu&rsquo;elle a une double signification. Il y a la dimension \u00e9conomique, celle \u00e0 laquelle Reich se r\u00e9f\u00e8re, mais il y a aussi une dimension historique qui est unique aux USA. De ce point de vue historique, notre appr\u00e9ciation est que l&rsquo;\u00e9v\u00e9nement de la Grande D\u00e9pression, cette sensation vertigineuse et apocalyptique de l&rsquo;in\u00e9luctable d\u00e9sint\u00e9gration des USA naissant et acc\u00e9l\u00e9rant \u00e0 partir de 1931, eut lieu effectivement dans les seules ann\u00e9es <a href=\"http:\/\/www.dedefensa.org\/article-fdr_au_secours_18_09_2008.html\" class=\"gen\">1931-1933<\/a>, et que le ph\u00e9nom\u00e8ne fut interrompu par l&rsquo;arriv\u00e9e de Roosevelt (FDR). Le nouveau pr\u00e9sident parvint \u00e0 susciter un choc psychologique d&rsquo;une telle force qu&rsquo;il interrompit effectivement cette sensation catastrophique qui avait une r\u00e9elle dimension historique et risquait d&#8217;emporter l&rsquo;Am\u00e9rique.<\/p>\n<\/p>\n<p><p>\tSi Reich parle ici de la seule dimension \u00e9conomique, il n&rsquo;en reste pas moins que les deux dimensions s&rsquo;influencent l&rsquo;une l&rsquo;autre. Ainsi, la dimension \u00e9conomique a une telle allure de catastrophe parce qu&rsquo;il y a, greff\u00e9e sur elle, ou au-dessus d&rsquo;elle, la dimension historique qu&rsquo;on a signal\u00e9e. Du coup, l&rsquo;\u00e9pisode \u00e9conomique de la Grande D\u00e9pression aux USA est sans commune mesure avec ce qui fut ressenti dans le reste du monde, notamment en Europe, de la Grande D\u00e9pression. Nous parlons bien ici de la perception, et non pas des \u00e9v\u00e9nements eux-m\u00eames. M\u00eame si les \u00e9v\u00e9nements engendr\u00e9s par la Grande D\u00e9pression furent catastrophiques en Europe, la perception de la Grande D\u00e9pression elle-m\u00eame reste beaucoup plus catastrophique aux USA. Pour cette raison, la Grande D\u00e9pression est la r\u00e9f\u00e9rence am\u00e9ricaniste centrale de la catastrophe au XX\u00e8me si\u00e8cle, bien plus que les deux Guerres mondiales.<\/p>\n<\/p>\n<p><p>\tLe rapprochement que fait Reich de la Grande D\u00e9pression est aujourd&rsquo;hui beaucoup plus valable que celui que firent la plupart des commentateurs (dont lui d&rsquo;ailleurs) lors de la crise du 15 septembre 2008. Dans ce cas, la r\u00e9f\u00e9rence \u00e9tait plut\u00f4t celle du krach d&rsquo;octobre 1929, qui doit \u00eatre d\u00e9tach\u00e9 de la Grande D\u00e9pression. Ce qui caract\u00e9risa la Grande D\u00e9pression aux USA, ce fut l&rsquo;exacerbation des tares du syst\u00e8me, c&rsquo;est-\u00e0-dire, essentiellement, la rupture entre la haute structure financi\u00e8re du pays, l&rsquo;oligarchie, et les conditions \u00e9conomiques g\u00e9n\u00e9rales pour la population. M\u00eame si cette structure financi\u00e8re (souvent avec les grandes conglom\u00e9rats du <em>corporate power<\/em>) souffrit \u00e0 l&rsquo;une ou l&rsquo;autre occasion, elle tint n\u00e9anmoins d&rsquo;une fa\u00e7on assez satisfaisante, surtout pour les grands \u00e9tablissements et pour les grandes fortunes du pays qui contr\u00f4lent directement ou indirectement cette structure. Par contre la structure sociale, son \u00e9conomie et son armature financi\u00e8re moyenne et petite (notamment le r\u00e9seau des banques locales et r\u00e9gionales), subit de plein fouet le choc de la Grande D\u00e9pression, plongeant dans une d\u00e9structuration et un d\u00e9sarroi \u00e9pouvantable qui fit effectivement penser, particuli\u00e8rement \u00e0 l&rsquo;hiver 1932-1933, \u00e0 une d\u00e9sint\u00e9gration du pays.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est selon ce point de vue, notamment avec le ch\u00f4mage qui est en train de devenir structurel \u00e0 un tr\u00e8s haut niveau, que Robert Reich pense en mettant \u00e0 nouveau en \u00e9vidence le parall\u00e8le de la Grande D\u00e9pression. Il s&rsquo;agit toujours de ce spectre de la division antagoniste entre la structure de domination oligarchique du pays et le gros (l&rsquo;immense majorit\u00e9) de la population. M\u00eame si cette division existe dans nombre de pays, elle est cruciale aux USA parce que ce pays n&rsquo;a pas la coh\u00e9sion et l&rsquo;exp\u00e9rience historiques qui donnent en g\u00e9n\u00e9ral une mati\u00e8re suffisante pour pr\u00e9server l&rsquo;unit\u00e9 et la coh\u00e9sion. Il est bien connu \u00e0 cet \u00e9gard que l&rsquo;actuel effritement, voire l&rsquo;actuelle <a href=\"http:\/\/www.commondreams.org\/headline\/2010\/08\/15\" class=\"gen\">destruction<\/a> de la classe moyenne avec la multiplication du ch\u00f4mage et la chute dans le trou noir de la pauvret\u00e9 est un signe d&rsquo;une extr\u00eame gravit\u00e9 pour les USA. La classe moyenne n&rsquo;est pas un miracle de l&rsquo;<em>American Dream<\/em> ni rien de cette sorte, mais le ciment qui a \u00e9t\u00e9 invent\u00e9, surtout apr\u00e8s la Grande D\u00e9pression, pour tenter de souder ces deux parties antinomiques de la structure des USA,  l&rsquo;oligarchie dominante et la population qui lui est soumise.<\/p>\n<\/p>\n<p><p>\tReich reste plus que jamais un interventionniste parce qu&rsquo;il pense, justement, que l&rsquo;oligarchie ne voudra pas et, surtout, qu&rsquo;elle est totalement incapable de jouer le r\u00f4le d&rsquo;une puissance publique, m\u00eame an\u00e9mi\u00e9e, pour tenter de restaurer un semblant de substance de cette classe moyenne, et par cons\u00e9quent le lien entre l&rsquo;oligarchie et les \u00e9lites et, d&rsquo;autre part, la population. Mais son espoir d&rsquo;interventionnisme se heurte \u00e9videmment \u00e0 l&rsquo;\u00e9tat catastrophique des finances publiques et \u00e0 une classe politique plong\u00e9e dans un \u00e9tat de d\u00e9sordre proche de l&rsquo;anarchie compl\u00e8te, avec un pr\u00e9sident qui semble consacrer toute sa brillante intelligence \u00e0 agir avec la plus grande pusillanimit\u00e9 possible. Il est \u00e9vident qu&rsquo;il faudrait aujourd&rsquo;hui aux USA un super-FDR et que BHO s&rsquo;est finalement r\u00e9v\u00e9l\u00e9 comme m\u00eame pas le dixi\u00e8me d&rsquo;un FDR dans la t\u00e2che de restaurer les conditions de l&rsquo;\u00e9quilibre pr\u00e9caire de la coh\u00e9sion structurelle des USA. Dans les conditions actuelles, l&rsquo;alternative \u00e0 cette situation est plus que jamais la d\u00e9sint\u00e9gration du pays et les signes \u00e0 cet \u00e9gard sont beaucoup plus marqu\u00e9s qu&rsquo;au temps de la Grande D\u00e9pression, avec un puissant mouvement de d\u00e9volution (les Etats contre le centre) s&rsquo;exprimant de diverses mani\u00e8res.<\/p>\n<\/p>\n<p><p>\tDu point de vue g\u00e9n\u00e9ral \u00e9conomiques g\u00e9n\u00e9rales, les habituelles analyses complaisantes des intellectuels de l&rsquo;am\u00e9ricanisme, doctrinaires de l&rsquo;ultra-lib\u00e9ralisme bien plus qu&rsquo;un Robert Reich, favorisaient une sortie de crise favorable aux USA pour l&rsquo;automne 2009. (L&rsquo;historien et mage de service Niall Ferguson, le 27 d\u00e9cembre 2008 dans le <em>Financial Times<\/em>, faisant une projection\/pr\u00e9diction de l&rsquo;ann\u00e9e 2009 : \u00ab<em>By year end <\/em>[2009]<em>, it was possible for the first time to detect  rather than just to hope for  the beginning of the end of the Great Repression. The downward spiral in America&rsquo;s real estate market and the banking system had finally been halted by radical steps that the administration had initially hesitated to take. At the same time, the far larger economic problems in the rest of the world had given Obama a unique opportunity to reassert American leadership.<\/em>\u00bb) Leur erreur n&rsquo;est pas \u00e9conomique, mais historique et psychologique, et d&rsquo;ailleurs tenant \u00e9galement \u00e0 leur propre psychologie absolument am\u00e9ricanis\u00e9e (y compris quand on est anglais, comme Ferguson). La fragilit\u00e9 des USA, qui se mesure en r\u00e9f\u00e9rences historiques et psychologiques, est infiniment plus grande que celle des autres pays du syst\u00e8me. La psychologie et l&rsquo;intelligence de ses commentateurs-serviteurs pr\u00e9sentent une vuln\u00e9rabilit\u00e9 \u00e0 mesure : ils sont les jouets de leur servilit\u00e9 pour l&rsquo;am\u00e9ricanisme.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 16 ao\u00fbt 2010 \u00e0 11H33<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le fant\u00f4me, c&rsquo;est la Grande D\u00e9pression. Divers \u00e9conomistes US de gauche (interventionnistes, rooseveltiens, keyn\u00e9siens, etc.) d\u00e9noncent plus que jamais une situation qui a aujourd&rsquo;hui, aux USA, des similitudes structurelles avec la Grande D\u00e9pression. Cela signifie qu&rsquo;ils se r\u00e9f\u00e8rent \u00e0 cet \u00e9v\u00e9nement \u00e9conomique catastrophique qui dura bien plus que les ann\u00e9es 1931-1933 habituellement cit\u00e9es, mais, au&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[8823,3083,3907,4048,5466,2891,8824,5248,3099,3182,3080,9942],"class_list":["post-72189","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-classe","tag-depression","tag-destructuration","tag-ferguson","tag-fragilite","tag-grande","tag-moyenne","tag-oligarchie","tag-psychologie","tag-reich","tag-roosevelt","tag-srrvilite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72189","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72189"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72189\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72189"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72189"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72189"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}