{"id":72212,"date":"2010-08-25T09:16:39","date_gmt":"2010-08-25T09:16:39","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/08\/25\/la-fragilite-extreme-de-bho-deja-pour-2012\/"},"modified":"2010-08-25T09:16:39","modified_gmt":"2010-08-25T09:16:39","slug":"la-fragilite-extreme-de-bho-deja-pour-2012","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/08\/25\/la-fragilite-extreme-de-bho-deja-pour-2012\/","title":{"rendered":"La fragilit\u00e9 extr\u00eame de BHO, \u2013 d\u00e9j\u00e0 pour 2012"},"content":{"rendered":"<p><p>Les hypoth\u00e8ses et supputations ont commenc\u00e9 \u00e0 circuler concernant la position d&rsquo;Hillary Clinton, en connexion avec ce qui est consid\u00e9r\u00e9 par l&rsquo;\u00e9quipe Obama comme la tr\u00e8s mauvaise situation du vice-pr\u00e9sident Biden en termes de popularit\u00e9. L&rsquo;id\u00e9e est notamment d&rsquo;envisager que Biden c\u00e8de sa place \u00e0 Hillary comme candidate vice-pr\u00e9sident avec Obama pour la campagne de r\u00e9\u00e9lection de 2012. Une autre hypoth\u00e8se, plus imm\u00e9diate, est de faire passer Hillary au Pentagone si Gates <a href=\"http:\/\/www.dedefensa.org\/article-les_saints_quittent_le_navire_17_08_2010.html\" class=\"gen\">s&rsquo;en va<\/a>. Les deux hypoth\u00e8ses combin\u00e9es suscitent l&rsquo;interpr\u00e9tation suppl\u00e9mentaire d&rsquo;une tentative de renforcement d&rsquo;Obama pour les pr\u00e9sidentielles de 2012, avec une neutralisation d&rsquo;Hillary Clinton comme adversaire potentielle de m\u00eame Obama pour la d\u00e9signation comme candidat d\u00e9mocrate en 2012.<\/p>\n<\/p>\n<p><p>\tLe Washington <em>Times<\/em>, notamment, reprend toutes ces rumeurs dans un \u00e9dito du <a href=\"http:\/\/www.washingtontimes.com\/news\/2010\/aug\/23\/the-hillary-coup\/\" class=\"gen\">23 ao\u00fbt 2010<\/a>. Apr\u00e8s avoir \u00e9voqu\u00e9 le cas Biden, le journal conclut de cette fa\u00e7on :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>On Sunday, David Ignatius wrote in The Washington Post that making Mrs. Clinton vice president would be Mr. Obama&rsquo;s second term masterstroke. Mr. Ignatius is no Hillary fan. After the election in November 2008, he called her a big, hungry, needy ego\u00a0\u00bb and said that making her secretary of state would be a mistake of potentially enormous proportions. Trading the vice president&rsquo;s office to forestall Hillary&rsquo;s shot at the top spot  placating her needy ego with a symbolic office of no importance  certainly would be a masterstroke.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Another option getting batted around is to sideline Mrs. Clinton at the Pentagon. Secretary of Defense Robert Gates announced he&rsquo;ll probably retire in December 2011 after the Afghanistan policy review, and Mrs. Clinton might be beguiled at being the \u00ab\u00a0historic\u00a0\u00bb first woman defense secretary. Former Council on Foreign Relations President Leslie Gelb pitched the idea earlier this year and contends the military loves her, a crush which is likely to fade if Hillary actually becomes the civilian leader to those in uniform.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Although sporting, none of the speculation means much at this stage. The size of the expected Democrat debacle in this fall&rsquo;s elections has yet to play out, and that election will set the initial terms for 2012. Mrs. Clinton has no pressing need to change jobs. Meanwhile, the new documentary We Will Not Be Silenced, detailing alleged fraud involved in Mr. Obama&rsquo;s 2008 nomination, has been gaining more attention in Democratic circles. If Hillary supporters are going to mount a party coup against the first black president, they will need a better argument than that he is a complete disaster in his job.<\/em>\u00bb<\/p>\n<h4>Notre commentaire<\/h4>\n<p> Il y a bien entendu eu des pr\u00e9c\u00e9dents d&rsquo;un pr\u00e9sident changeant de vice-pr\u00e9sident pour renforcer ses chances d&rsquo;\u00eatre r\u00e9\u00e9lu. (Notamment, le pr\u00e9c\u00e9dent fameux de Roosevelt se d\u00e9barrassant de Henry Wallace, son vice-pr\u00e9sident en fonction, pour Truman, en septembre 1944, pour sa troisi\u00e8me r\u00e9\u00e9lection de novembre 1944. La raison en \u00e9tait que Wallace \u00e9tait trop \u00e0 gauche et que la position de FDR \u00e9tait extr\u00eamement difficile \u00e0 cet \u00e9gard,  malgr\u00e9 les succ\u00e8s de la guerre en cours, qui comptaient assez peu pour la situation politique int\u00e9rieure US, contrairement \u00e0 l&rsquo;image qui est habituellement entretenue \u00e0 cet \u00e9gard.) Mais jamais les sp\u00e9culations \u00e0 propos d&rsquo;un nouveau vice-pr\u00e9sident pour sauver un deuxi\u00e8me mandat du pr\u00e9sident en place n&rsquo;avaient \u00e9t\u00e9 d\u00e9velopp\u00e9es alors qu&rsquo;on n&rsquo;a pas encore atteint la moiti\u00e9 du premier mandat (novembre 2010). Cela mesure sans aucun doute la fragilit\u00e9 de la situation d&rsquo;Obama, et, surtout, la perception extr\u00eame de cette fragilit\u00e9 par Obama et son \u00e9quipe.<\/p>\n<\/p>\n<p><p>\tBien entendu, il faut admettre que ces rumeurs ne sont nullement spontan\u00e9es, qu&rsquo;elles sont autant de ballons d&rsquo;essai, directement ou indirectement venus de l&rsquo;administration, pour tester l&rsquo;id\u00e9e de telles possibilit\u00e9s. C&rsquo;est une technique habituelle. Ce qui est extr\u00eamement surprenant, encore une fois, c&rsquo;est la chronologie ; que ces rumeurs soient r\u00e9pandues maintenant implique un risque \u00e9norme de d\u00e9sunion, de confusion, d&rsquo;affrontement et de m\u00e9fiance g\u00e9n\u00e9ralis\u00e9e au sein de l&rsquo;administration Obama, entre Obama, Biden, Clinton notamment. Chacun verra d\u00e9sormais ses relations de travail avec les autres entach\u00e9es du soup\u00e7on largement substantiv\u00e9 de manuvres pour les pr\u00e9sidentielles de 2012. Les interf\u00e9rences sur la politique de l&rsquo;administration, int\u00e9rieure et ext\u00e9rieure, vont \u00eatre massives, alors que cette politique n&rsquo;est d\u00e9j\u00e0 pas brillante dans la confusion g\u00e9n\u00e9rale r\u00e9gnant \u00e0 Washington. Plus encore,  que ces rumeurs apparaissent <strong>avant<\/strong> les \u00e9lections <em>mid-term<\/em> de novembre, qui promettent des bouleversements dont nul ne sait l&rsquo;orientation, alors qu&rsquo;Obama est lui-m\u00eame en position tr\u00e8s d\u00e9licate, voil\u00e0 un signe de plus du d\u00e9sarroi r\u00e9gnant. (Si Biden est critiqu\u00e9 au sein de l&rsquo;\u00e9quipe Obama pour son impopularit\u00e9, que dire d&rsquo;Obama lui-m\u00eame ? Une majorit\u00e9 de 43% d&rsquo;Am\u00e9ricains jugent que Biden remplit mal ses fonctions, mais cette majorit\u00e9 passe \u00e0 50% pour Obama)<\/p>\n<\/p>\n<p><p>\tAutre \u00e9l\u00e9ment, mentionn\u00e9 en passant dans l&rsquo;\u00e9dito du Washington <em>Times<\/em>,  l&rsquo;offensive des partisans d&rsquo;Hillary Clinton concernant les conditions de la d\u00e9signation d&rsquo;Obama comme candidat d\u00e9mocrate en ao\u00fbt 2008 par la convention d\u00e9mocrate. (Le documentaire <em>We Will Not Be Silenced<\/em> sur des all\u00e9gations de fraude pour la nomination d&rsquo;Obama.) On ne peut croire tout \u00e0 fait qu&rsquo;Hillary n&rsquo;\u00e9tait pas au moins un peu au courant et qu&rsquo;elle a laiss\u00e9 faire, ce qui pourrait \u00eatre une indication sur son agr\u00e9ment, ou plut\u00f4t sa r\u00e9ticence face \u00e0 toute manuvre qui tenterait de la priver de la possibilit\u00e9 de figurer comme candidate \u00e0 la d\u00e9signation d\u00e9mocrate contre Obama, \u00e0 l&rsquo;\u00e9t\u00e9 2012. La fragilisation d&rsquo;Obama se mesure d&rsquo;ailleurs au simple fait de l&rsquo;\u00e9volution des positions relatives des uns et des autres en termes politiciens. Lorsque Hillary Clinton accepta le poste de secr\u00e9taire d&rsquo;Etat, on consid\u00e9ra qu&rsquo;elle abdiquait toute pr\u00e9tention \u00e0 une candidature pour 2012, acceptant <em>de facto<\/em> la sup\u00e9riorit\u00e9 d&rsquo;Obama. Aujourd&rsquo;hui, cette position n&rsquo;est plus consid\u00e9r\u00e9e comme suffisante \u00e0 cet \u00e9gard, et l&rsquo;on envisage de la neutraliser en lui donnant une fonction obligatoire dans l&rsquo;\u00e9lection, dont on attend d&rsquo;autre part qu&rsquo;elle renforce Obama pour 2012. Bien \u00e9videmment et dans cette hypoth\u00e8se, il est loin d&rsquo;\u00eatre acquis qu&rsquo;Hillary Clinton joue n\u00e9cessairement ce jeu.<\/p>\n<\/p>\n<p><p>\tDe toutes les fa\u00e7ons, nous sommes bien loin du compte, et 2012 est encore tr\u00e8s loin, \u00e0 la vitesse o\u00f9 vont les \u00e9v\u00e9nements et les bouleversements. On peut seulement mesurer l&rsquo;extr\u00eame volatilit\u00e9 de la situation am\u00e9ricaniste aujourd&rsquo;hui, o\u00f9 une \u00e9quipe dirigeante ne semble pouvoir tenir deux ans dans sa coh\u00e9sion interne et sa structure m\u00eame, tant les pressions des incertitudes politiques sont grandes. Cette situation-l\u00e0 est, chronologiquement, sans pr\u00e9c\u00e9dent, et mesure encore plus l&rsquo;extraordinaire inconsistance et la paralysie du pouvoir US, par cons\u00e9quent l&rsquo;inexistence de toute politique US suivie. Les rumeurs concernant Hillary vont contribuer encore \u00e0 accro\u00eetre la confusion et la fragilit\u00e9 g\u00e9n\u00e9rales.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 25 ao\u00fbt 2010 \u00e0 09H26<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les hypoth\u00e8ses et supputations ont commenc\u00e9 \u00e0 circuler concernant la position d&rsquo;Hillary Clinton, en connexion avec ce qui est consid\u00e9r\u00e9 par l&rsquo;\u00e9quipe Obama comme la tr\u00e8s mauvaise situation du vice-pr\u00e9sident Biden en termes de popularit\u00e9. L&rsquo;id\u00e9e est notamment d&rsquo;envisager que Biden c\u00e8de sa place \u00e0 Hillary comme candidate vice-pr\u00e9sident avec Obama pour la campagne de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[7928,1235,934,4141,3278,8503,3340,9979],"class_list":["post-72212","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-7928","tag-biden","tag-clinton","tag-elections","tag-hillary","tag-joe","tag-presidentielles","tag-vice-presidence"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72212"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72212\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}