{"id":72214,"date":"2010-08-26T05:22:02","date_gmt":"2010-08-26T05:22:02","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/08\/26\/22-aout-budget-ecologique-depasse\/"},"modified":"2010-08-26T05:22:02","modified_gmt":"2010-08-26T05:22:02","slug":"22-aout-budget-ecologique-depasse","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/08\/26\/22-aout-budget-ecologique-depasse\/","title":{"rendered":"22 ao\u00fbt, \u201cbudget \u00e9cologique\u201d d\u00e9pass\u00e9"},"content":{"rendered":"<p><h4>22 ao\u00fbt, budget \u00e9cologique d\u00e9pass\u00e9<\/h4>\n<p>Le <a href=\"http:\/\/fr.rian.ru\/discussion\/20100825\/187292471.html<D\" class=\"gen\">25 ao\u00fbt 2010<\/a>, Nikolay Zaitzev, de Novosti, a fait un rapport sur l&rsquo;annonce par le <em>Global Footprint Network<\/em> du d\u00e9passement du budget \u00e9cologique de la terre le 21 ao\u00fbt 2010.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Le 21 ao\u00fbt, la population de la Terre aura gaspill\u00e9 tout le capital mis \u00e0 sa disposition par la plan\u00e8te. La population a d\u00e9finitivement consomm\u00e9 l&rsquo;eau qui se renouvelait d&rsquo;elle-m\u00eame dans les r\u00e9servoirs, l&rsquo;herbe qui poussait dans les p\u00e2turages, le poisson des mers et des lacs, les r\u00e9coltes des terres fertiles, les dons de la for\u00eat. En m\u00eame temps, les espaces d\u00e9di\u00e9s au stockage des d\u00e9chets sont arriv\u00e9s \u00e0 saturation, en commen\u00e7ant par les gaz \u00e0 effet de serre qui g\u00e9n\u00e8rent le chaos climatique.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Cette statistique effrayante a \u00e9t\u00e9 publi\u00e9e par l&rsquo;organisation gouvernementale ind\u00e9pendante Global Footprint Network qui calcule depuis plusieurs ann\u00e9es l&rsquo;impact de divers modes de vie sur l&rsquo;environnement. Elle compare la consommation annuelle de l&rsquo;humanit\u00e9 et les capacit\u00e9s de la plan\u00e8te \u00e0 restaurer ses ressources apr\u00e8s cette consommation. L&rsquo;organisation compare cet impact \u00e0 l&#8217;empreinte d&rsquo;un pied laiss\u00e9e par l&rsquo;humanit\u00e9 sur l&rsquo;\u00e9cologie fragile de la plan\u00e8te.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Le 22 ao\u00fbt, le lendemain de l&rsquo;\u00e9puisement des ressources naturelles de la Terre, il convient de reconna\u00eetre la population en faillite \u00e9cologique. Mais puisqu&rsquo;il est impossible de s&rsquo;arr\u00eater et les alternatives ne sont toujours pas mises en uvre, nous allons r\u00e9soudre le probl\u00e8me en le transmettant \u00e0 nos g\u00e9n\u00e9rations futures, repoussant ainsi le probl\u00e8me. Nous allons puiser l&rsquo;eau des couches souterraines qui ne sont pas aliment\u00e9es en eau de pluie. Nous allons renforcer le pastoralisme en sacrifiant les champs et les pr\u00e9s au profit du d\u00e9sert. Nous allons vider les mers et les rivi\u00e8res en p\u00eachant plus de poissons et de fruits de mer que la reproduction naturelle ne peut assurer. Nous allons continuer \u00e0 perdre chaque minute les for\u00eats d&rsquo;une superficie \u00e9quivalente \u00e0 65 terrains de football. En outre, nous allons permettre aux gaz \u00e0 effet de serre d&rsquo;absorber l&rsquo;atmosph\u00e8re et ils vont nous inonder de chaleur en contribuant \u00e0 l&rsquo;apparition d&rsquo;incendies et d&rsquo;inondations plus fr\u00e9quents.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDivers autres organes d&rsquo;information ont repris l&rsquo;annonce du <em>Global Footprint Network<\/em>. On peut trouver notamment un d\u00e9veloppement sur le site de Radio-Canada, le <a href=\"http:\/\/www.radio-canada.ca\/nouvelles\/environnement\/2010\/08\/20\/001-budget-ressources.shtml\" class=\"gen\">20 ao\u00fbt 2010<\/a>.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Le 21 ao\u00fbt marque une triste \u00e9tape : celle du jour o\u00f9 nous aurons \u00e9puis\u00e9 notre budget \u00e9cologique annuel.<\/em> [&#8230;] <em>Apr\u00e8s cette date, nous satisferons nos besoins \u00e9cologiques en liquidant les stocks de ressources et en laissant s&rsquo;accumuler le dioxyde de carbone dans l&rsquo;atmosph\u00e8re.  Extrait du site web du Global Footprint Network<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>D&rsquo;un point de vue \u00e9cologique, nous vivrons donc plus du quart de l&rsquo;ann\u00e9e \u00e0 cr\u00e9dit, conclut le Global Footprint Network.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Le calcul tient compte de l&rsquo;\u00e9nergie que nous consommons, des habitations construites, des ressources foresti\u00e8res utilis\u00e9es, ainsi que de la nourriture produite sur terre et p\u00each\u00e9e en mer. La consommation humaine des ressources tient par ailleurs compte des d\u00e9chets et des \u00e9missions polluantes, comme le CO2.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Si vous d\u00e9pensez votre revenu annuel total en neuf mois, vous seriez sans doute extr\u00eamement pr\u00e9occup\u00e9, estime le pr\u00e9sident de l&rsquo;organisation, Mathis Wackernagel. La situation est aussi pire quand il s&rsquo;agit de notre budget \u00e9cologique. Le changement climatique, la perte de biodiversit\u00e9, la d\u00e9forestation, les p\u00e9nuries d&rsquo;eau et de nourriture sont autant de signes \u00e9vidents que nous ne pouvons plus financer notre consommation \u00e0 cr\u00e9dit.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>L&rsquo;organisation note que jusqu&rsquo;\u00e0 il y a trois d\u00e9cennies, la consommation des ressources par l&rsquo;humanit\u00e9 respectait le rythme auquel la nature parvenait \u00e0 les produire. Or, ajoute-t-elle, l&rsquo;\u00e9cart entre la demande et l&rsquo;offre, connue sous le nom de d\u00e9passement \u00e9cologique, a depuis cr\u00fb chaque ann\u00e9e de fa\u00e7on r\u00e9guli\u00e8re. \u00c0 la fin des ann\u00e9es 1980, notre empreinte \u00e9cologique \u00e9tait globalement \u00e9quivalente \u00e0 la taille de la terre. Aujourd&rsquo;hui, c&rsquo;est 50 % de plus<\/em>\u00bb<\/p>\n<\/p>\n<p>\n<p class=\"signature\"><em>dedefensa.org<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>22 ao\u00fbt, budget \u00e9cologique d\u00e9pass\u00e9 Le 25 ao\u00fbt 2010, Nikolay Zaitzev, de Novosti, a fait un rapport sur l&rsquo;annonce par le Global Footprint Network du d\u00e9passement du budget \u00e9cologique de la terre le 21 ao\u00fbt 2010. \u00abLe 21 ao\u00fbt, la population de la Terre aura gaspill\u00e9 tout le capital mis \u00e0 sa disposition par la&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3127,9744,9980,4237,9983,9981,5204,9982,7598],"class_list":["post-72214","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-budget","tag-ecologique","tag-footprint","tag-global","tag-naturelles","tag-network","tag-novosti","tag-renouvellement","tag-reserves"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72214"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72214\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}