{"id":72280,"date":"2010-09-15T09:20:17","date_gmt":"2010-09-15T09:20:17","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/09\/15\/odonnell-et-tea-party-politique-ou-symbole\/"},"modified":"2010-09-15T09:20:17","modified_gmt":"2010-09-15T09:20:17","slug":"odonnell-et-tea-party-politique-ou-symbole","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/09\/15\/odonnell-et-tea-party-politique-ou-symbole\/","title":{"rendered":"O&rsquo;Donnell et <em>Tea Party<\/em> : politique ou symbole ?"},"content":{"rendered":"<p><p>Il y a eu, hier, une grande journ\u00e9e de plus pour l&rsquo;expansion du <strong>d\u00e9sordre<\/strong> aux USA, avec la victoire dans les primaires r\u00e9publicaines (d\u00e9signation du candidat pour les \u00e9lections de novembre) de divers candidats <em>Tea Party<\/em>, notamment de la parfaite <em>outsider<\/em>, extr\u00e9miste, soutenue par <em>Tea Party<\/em>, Christine O&rsquo;Donnell, dans le Delaware. (Pour avoir une id\u00e9e de la victoire de <em>Tea Party<\/em>, par rapport \u00e0 laquelle la victoire de O&rsquo;Donnell doit \u00eatre appr\u00e9ci\u00e9e essentiellement comme l&rsquo;expression la plus remarquable, on peut lire <em>RAW Story<\/em> du <a href=\"http:\/\/www.rawstory.com\/rs\/2010\/09\/big-night-tea-party-odonnell-wins-delaware\/\" class=\"gen\">15 septembre 2010<\/a>.) La pr\u00e9sentation classique de O&rsquo;Donnell est faite par le <em>Guardian<\/em> du <a href=\"http:\/\/www.guardian.co.uk\/world\/2010\/sep\/15\/christine-odonnell-delaware-midterms\" class=\"gen\">15 septembre 2010<\/a>. Le chapeau de l&rsquo;article suffit \u00e0 nous convaincre que O&rsquo;Donnell est le Diable en personne f\u00e9minine : \u00ab<em>Christine O&rsquo;Donnell, who is pro-gun, anti- abortion, and believes masturbation is a sin, won by 53 per cent.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tBien plus int\u00e9ressante pour fixer les choses et nous sugg\u00e9rer un commentaire plus approfondi, la r\u00e9action de Charles Krauthammer, sur <em>Politico.com<\/em>, ce <a href=\"http:\/\/www.politico.com\/news\/stories\/0910\/42133.html\" class=\"gen\">14 septembre 2010<\/a>. Krauthammer est l&rsquo;un des plus fameux <em>neocons<\/em>, partisan de toutes les guerres, de toutes les entreprises de d\u00e9stabilisation et de d\u00e9structuration depuis 9\/11, partisan forcen\u00e9 d&rsquo;une attaque de l&rsquo;Iran, partisan hyst\u00e9rique d&rsquo;Isra\u00ebl et du <em>Likoud<\/em>. Eh bien, ce personnage si r\u00e9volutionnaire, comme il aime \u00e0 se faire appr\u00e9cier, si partisan des entreprises les plus r\u00e9volutionnairement d\u00e9structurantes, c&rsquo;est-\u00e0-dire les plus cruelles et les plus irresponsables et se terminant en d\u00e9sastre, se lamente de la victoire de O&rsquo;Donnell parce qu&rsquo;il estime qu&rsquo;elle a peu de chances de l&#8217;emporter contre le candidat d\u00e9mocrate et qu&rsquo;elle contribuerait \u00e0 r\u00e9duire la repr\u00e9sentation r\u00e9publicaine. Il se r\u00e9v\u00e8le ainsi comme une cr\u00e9ature absolument partie int\u00e9grante de l&rsquo;<em>establishment<\/em>, du conformisme et de l&rsquo;\u00e9lectoralisme qui y r\u00e8gnent, bref une cr\u00e9ature du syst\u00e8me \u00e0 100%. La chose a le m\u00e9rite d&rsquo;\u00eatre claire, en confirmant ce que sont vraiment les <em>neocons<\/em>,  cr\u00e9atures au service du syst\u00e8me, rien d&rsquo;autre.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Leading conservative commentator Charles Krauthammer has rebuked former Alaska Gov. Sarah Palin and Sen. Jim DeMint (R-S.C.) for making the irresponsible choice of endorsing Christine O&rsquo;Donnell over Rep. Mike Castle in the Delaware GOP Senate primary.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>The Palin endorsement, I think, is disruptive and capricious, Krauthammer said Monday night on Fox News&rsquo; Special Report. Bill Buckley had a rule that he always supported the most conservative candidate who was electable, otherwise the vote is simply self-indulgence.<\/em> [] <\/p>\n<\/p>\n<p><p>\t\u00bb<em>When Fox anchor Bret Baier pointed out the DeMint has also endorsed O&rsquo;Donnell, Krauthammer branded the senator&rsquo;s move equally capricious and irresponsible.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>I&rsquo;m not sexist on this, the conservative columnist said. It&rsquo;s a big mistake. Mike Castle is a shoo-in. He wins. O&rsquo;Donnell is very problematic. She probably will lose.<\/em>\u00bb<\/p>\n<h4>Notre commentaire<\/h4>\n<p>Il y a plusieurs fa\u00e7ons de voir la victoire de O&rsquo;Donnell (ceci encore une fois pr\u00e9cis\u00e9, cette victoire effectivement prise comme exemplaire de celle de <em>Tea Party<\/em> en g\u00e9n\u00e9ral dans les primaires d&rsquo;hier). Il y a d&rsquo;abord la fa\u00e7on politique, qui est de dire qu&rsquo;en devenant la candidate du parti r\u00e9publicain, elle d\u00e9force ce parti parce qu&rsquo;elle a moins de chance que le cacique du parti (Castle) qu&rsquo;elle a battu ; a ou aurait moins de chances ? C&rsquo;est \u00e0 d\u00e9battre, comme l&rsquo;on verra plus loin. Il y a la fa\u00e7on id\u00e9ologique, qui est une sous-branche convenue de la politique et du syst\u00e8me, qui est de d\u00e9noncer le diable en personne, populiste d&rsquo;extr\u00eame-droite, qui voit la masturbation comme un p\u00e9ch\u00e9,  ce qui signifie, pour ce dernier point, un recul de la civilisation d&rsquo;au moins cinq si\u00e8cles, plus peut-\u00eatre, et qui sera certainement l&rsquo;objet de commentaires sans fin, assur\u00e9s, moraux, lib\u00e9rateurs, sarcastiques et surtout persiflants,  n&rsquo;en doutons pas. Il y a une troisi\u00e8me fa\u00e7on, qui est symbolique, et qui nous lib\u00e8re de la chape de plomb des jugements oblig\u00e9s du syst\u00e8me,  et une bonne approche de ce point de vue est de se reporter au texte de Chris Hedges, que nous pr\u00e9sentions et commentions le <a href=\"http:\/\/www.dedefensa.org\/article-rupture_sans_retour_14_09_2010.html\" class=\"gen\">14 septembre 2010<\/a>.<\/p>\n<\/p>\n<p><p>\tNous devons avouer notre bien peu de go\u00fbt pour d\u00e9battre de la dame O&rsquo;Donnell en fonction de ce qu&rsquo;elle dit de la masturbation. Plus int\u00e9ressante, par contre, est l&rsquo;ambivalence des dirigeants d\u00e9mocrates vis-\u00e0-vis de <em>Tea Party<\/em>, et cette ambivalence bien visible dans de r\u00e9centes sorties du vice-pr\u00e9sident Biden (le Delaware, o\u00f9 op\u00e8re O&rsquo;Donnell, est l&rsquo;Etat dont Biden fut le s\u00e9nateur pendant deux d\u00e9cennies) D&rsquo;une part, Biden a tenu \u00e0 rendre public <a href=\"http:\/\/www.foxnews.com\/politics\/2010\/07\/18\/tea-party-racist-organization-biden-says\/\" class=\"gen\">son jugement<\/a> (qui est celui d&rsquo;Obama \u00e9galement) selon lequel <em>Tea Party<\/em> n&rsquo;est pas raciste ; d&rsquo;autre part, il <a href=\"http:\/\/www.msnbc.msn.com\/id\/38782569\/\" class=\"gen\">attaque<\/a> le <em>republican tea party<\/em>, comme d\u00e9pass\u00e9, obsol\u00e8te, \u00ab<em>out of step with where the American people are<\/em>\u00bb. Plus r\u00e9cemment, ce week-end dans le Delaware et avec \u00e0 l&rsquo;esprit la progression de O&rsquo;Donnell dans les sondages, Biden a d\u00e9nonc\u00e9 <em>Tea Party<\/em>, cette fois sans r\u00e9f\u00e9rence au parti r\u00e9publicain, comme populiste et peu soucieux des r\u00e8gles d\u00e9mocratiques (lire : des r\u00e8gles du syst\u00e8me). Il y a donc, chez les d\u00e9mocrates, le d\u00e9sir de favoriser \u00e9lectoralement <em>Tea Party<\/em>, vis-\u00e0-vis et \u00e0 l&rsquo;int\u00e9rieur du camp r\u00e9publicain, parce qu&rsquo;il y a leur conviction (peut-\u00eatre discutable) que les candidats avec le label <em>Tea Party<\/em> sont moins \u00e9ligibles contre un d\u00e9mocrate qu&rsquo;un candidat classique du parti r\u00e9publicain ; il y a d&rsquo;autre part la crainte, assez nouvelle et qui ne fera que s&rsquo;accentuer, que <em>Tea Party<\/em> acquiert malgr\u00e9 tout un poids et une dimension de repr\u00e9sentation nationale avec une capacit\u00e9 de peser \u00e0 Washington, parce que cette organisation est per\u00e7ue comme antisyst\u00e8me.<\/p>\n<\/p>\n<p><p>\tCe dernier point nous am\u00e8ne \u00e0 l&rsquo;aspect symbolique de la victoire de O&rsquo;Donnell. Il s&rsquo;agit alors d&rsquo;observer qu&rsquo;il s&rsquo;agit moins d&rsquo;un \u00e9v\u00e9nement politique partisan que d&rsquo;un \u00e9v\u00e9nement qui doit \u00eatre plac\u00e9 dans la probl\u00e9matique de l&rsquo;affrontement entre le syst\u00e8me et la population US, de plus en plus furieuse et consciente que la voie \u00e0 suivre est d&rsquo;attaquer le syst\u00e8me dans sa globalit\u00e9, par quelque moyen que ce soit. Dans ce cas, comme on l&rsquo;a dit d\u00e9j\u00e0 \u00e0 plusieurs reprises \u00e0 propos de <em>Tea Party<\/em>, l&rsquo;analyse id\u00e9ologique n&rsquo;a aucun int\u00e9r\u00eat et appara\u00eet surtout comme une arme du syst\u00e8me pour tenter d&rsquo;affaiblir <em>Tea Party<\/em> , c&rsquo;est-\u00e0-dire la col\u00e8re antisyst\u00e8me qui est derri\u00e8re <em>Tea Party<\/em>; l&rsquo;analyse politique n&rsquo;a d&rsquo;int\u00e9r\u00eat que tactique, pour mesurer la fa\u00e7on dont <em>Tea Party<\/em> peut intervenir \u00e0 l&rsquo;int\u00e9rieur du syst\u00e8me (entrisme) pour y exprimer ses vues, la fa\u00e7on dont il risque d&rsquo;\u00eatre r\u00e9cup\u00e9r\u00e9 par le syst\u00e8me (le parti r\u00e9publicain classique) o\u00f9 la fa\u00e7on dont il parviendrait au contraire \u00e0 introduire le d\u00e9sordre dans le cur du syst\u00e8me (du parti r\u00e9publicain classique mais aussi du syst\u00e8me l\u00e9gislatif). La dimension symbolique est toute autre, qui fait percevoir <em>Tea Party<\/em> comme une r\u00e9action de fureur et de r\u00e9sistance contre le syst\u00e8me, cette dimension qui fait penser \u00e0 certains dissidents de gauche qu&rsquo;il devrait y avoir une alliance de la fureur et de la r\u00e9sistance antisyst\u00e8mes de gauche et de droite, pour mener une attaque frontale contre le syst\u00e8me. (On en revient \u00e0 la logique de Hedges, homme de gauche.)<\/p>\n<\/p>\n<p><p>\tL&rsquo;int\u00e9r\u00eat de la situation encore plus renforc\u00e9e par ce mardi des primaires et la victoire de O&rsquo;Donnelly est double.<\/p>\n<\/p>\n<p><p>\t Les r\u00e9sultats d&rsquo;hier (O&rsquo;Donnelly et quelques autres) montre la rapidit\u00e9 de l&rsquo;\u00e9volution de la situation. Il y a trois mois, il \u00e9tait impensable, structurellement et statistiquement, que O&rsquo;Donnelly soit d\u00e9sign\u00e9e comme candidate r\u00e9publicaine dans le Delaware. Elle l&rsquo;est, et cela montre que le courant de contestation antisyst\u00e8me, plus que <em>Tea Party<\/em> lui-m\u00eame, est en train de se renforcer dans une situation de crise g\u00e9n\u00e9rale de plus en plus bloqu\u00e9e. Cette dynamique implique une tension en constant renforcement, des attentes et un esprit renforc\u00e9 de revendication, des exigences, etc. Elle implique \u00e9galement que tout pronostic est impossible, notamment celui qui fait d&rsquo;un candidat venu de <em>Tea Party<\/em> (O&rsquo;Donnell) un moins bon candidate contre les d\u00e9mocrates que le cacique du parti r\u00e9publicain qu&rsquo;il a battu aux primaires. Quand on voit d&rsquo;o\u00f9 vient O&rsquo;Donnell, en quelques semaines, on r\u00e9alise qu&rsquo;il n&rsquo;y a absolument rien d&rsquo;assur\u00e9 en aucun sens d&rsquo;ici novembre.<\/p>\n<\/p>\n<p><p>\t La logique inverse de la dynamique <em>Tea Party<\/em> reste valable (puisque tout est possible). Les r\u00e9sultats de novembre ne montreront pas n\u00e9cessairement une forte pr\u00e9sence, voire une pr\u00e9sence d&rsquo;influence significative de <em>Tea Party<\/em>. Tout comme la victoire par surprise de O&rsquo;Donnell (pour rester \u00e0 son cas) est possible, sa d\u00e9faite l&rsquo;est \u00e9galement, notamment parce qu&rsquo;il est loin d&rsquo;\u00eatre assur\u00e9 que le parti r\u00e9publicain, d\u00e9chir\u00e9 entre son d\u00e9sir de l&#8217;emporter et sa crainte d&rsquo;\u00eatre phagocyt\u00e9 par <em>Tea Party<\/em>, la soutiendra \u00e0 fond, notamment financi\u00e8rement, par l&rsquo;interm\u00e9diaire de ses <em>sponsors<\/em> habituels qui pourraient devenir h\u00e9sitants (c&rsquo;est bien un cas incertain). Or, une telle issue peut avoir des cons\u00e9quences importantes, dans le cadre constant de l&rsquo;aggravation de la crise. On a vu qu&rsquo;il y a, dans le parti r\u00e9publicain, un courant non n\u00e9gligeable pour envisager des alternatives <a href=\"http:\/\/www.dedefensa.org\/article-les_elections_us_et_les_hypotheses_d_insurrection__14_09_2010.html\" class=\"gen\">insurrectionnelles<\/a> si le Congr\u00e8s ne change pas de majorit\u00e9. Ce courant est \u00e9videmment typiquement d&rsquo;ob\u00e9dience <em>Tea Party<\/em>. Une situation de semi-\u00e9chec de l&rsquo;influence de <em>Tea Party<\/em> \u00e0 Washington, ou d&rsquo;\u00e9chec des candidats <em>Tea Party<\/em> dont la responsabilit\u00e9 serait attribu\u00e9e \u00e0 l&rsquo;attitude du parti r\u00e9publicain officiel ou \u00e0 d&rsquo;autres consid\u00e9rations du m\u00eame ordre (sabotage de leurs \u00e9lection par le syst\u00e8me), conduirait \u00e0 des opportunit\u00e9s int\u00e9ressantes. L&rsquo;affrontement politique actuel risquerait de s&rsquo;\u00e9largir \u00e0 la mise en danger de l&rsquo;ordre public, et la dimension symbolique (antisyst\u00e8me) de cette situation deviendrait pr\u00e9dominante. <\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 15 septembre 2010 \u00e0 09H23<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il y a eu, hier, une grande journ\u00e9e de plus pour l&rsquo;expansion du d\u00e9sordre aux USA, avec la victoire dans les primaires r\u00e9publicaines (d\u00e9signation du candidat pour les \u00e9lections de novembre) de divers candidats Tea Party, notamment de la parfaite outsider, extr\u00e9miste, soutenue par Tea Party, Christine O&rsquo;Donnell, dans le Delaware. (Pour avoir une id\u00e9e&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4646,1235,10044,4141,10043,7069,7347,3014,8256,3248],"class_list":["post-72280","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-antisysteme","tag-biden","tag-delaware","tag-elections","tag-odonnell","tag-party","tag-primaires","tag-systeme","tag-tea","tag-washington"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72280"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72280\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}