{"id":72285,"date":"2010-09-16T16:56:05","date_gmt":"2010-09-16T16:56:05","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/09\/16\/metaphysique-de-tea-party\/"},"modified":"2010-09-16T16:56:05","modified_gmt":"2010-09-16T16:56:05","slug":"metaphysique-de-tea-party","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/09\/16\/metaphysique-de-tea-party\/","title":{"rendered":"M\u00e9taphysique de <em>Tea Party<\/em>"},"content":{"rendered":"<p><p>Le mouvement <em>Tea Party<\/em> est le ph\u00e9nom\u00e8ne politique US \u00e0 la fois le plus original, le plus puissant, le plus suspect, le plus d\u00e9cri\u00e9 et peut-\u00eatre le plus myst\u00e9rieux de ces derni\u00e8res ann\u00e9es. (Nous entendons myst\u00e9rieux non dans le sens d&rsquo;une volont\u00e9 de myst\u00e8re, comme dans la composition d&rsquo;une soci\u00e9t\u00e9 secr\u00e8te ou d&rsquo;un complot, mais bien myst\u00e9rieux par sa <strong>nature<\/strong> m\u00eame, pourtant op\u00e9rant et s&rsquo;exposant en plein jour.) <em>Tea Party<\/em> est plein de surprises, \u00e0 la fois insaisissable dans ses origines, sa composition et ses buts, myst\u00e9rieux dans sa structure et son \u00e9volution, absolument incertain dans ses connexions, ses pr\u00e9f\u00e9rences, ses engagements, semblant sans direction bien identifi\u00e9e. La r\u00e9alit\u00e9 de <em>Tea Party<\/em> est \u00e0 l&rsquo;image de son \u00e9poque, compl\u00e8tement \u00e9lusive, peut-\u00eatre virtualiste, peut-\u00eatre double, triple, etc Reste \u00e0 voir, et c&rsquo;est ce qui nous importe ici parce que c&rsquo;est effectivement le plus important, s&rsquo;il y a une <strong>v\u00e9rit\u00e9<\/strong> de <em>Tea Party<\/em>.<\/p>\n<\/p>\n<p><p>\t Le plus souvent jusqu&rsquo;ici, <em>Tea Party<\/em> a \u00e9t\u00e9 appr\u00e9ci\u00e9 et jug\u00e9 selon trois crit\u00e8res : le crit\u00e8re politique, le crit\u00e8re id\u00e9ologique et le crit\u00e8re moral. Ces trois crit\u00e8res, juge-t-on selon les normes d&rsquo;appr\u00e9ciation de notre temps, devraient permettre de rendre compte de la r\u00e9alit\u00e9 de <em>Tea Party<\/em>. (On omet souvent de pr\u00e9ciser, bien que ce soit l&rsquo;\u00e9vidence, que ces trois crit\u00e8res employ\u00e9s selon les normes d&rsquo;appr\u00e9ciation de notre temps, renvoient tous \u00e0 une m\u00eame source qui est le syst\u00e8me en place, qui est la r\u00e9f\u00e9rence g\u00e9n\u00e9rale ; il faut le savoir pour comprendre que ces trois crit\u00e8res suivent une m\u00eame logique rationnelle, selon une raison humaine dont nous nous permettons de juger qu&rsquo;elle est elle-m\u00eame fort <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_crise_de_la_raison_humaine_ddecrisis_18_07_2010.html\" class=\"gen\">suspecte<\/a>, et pour les meilleures raisons du monde, si l&rsquo;on peut dire, parce qu&rsquo;\u00e9videmment manipul\u00e9e pour le syst\u00e8me, pour servir le syst\u00e8me.)<\/p>\n<\/p>\n<p><p>\tForce est de constater qu&rsquo;il n&rsquo;en est rien pour la compr\u00e9hension de <em>Tea Party<\/em> ; ou, dit autrement, et plus pr\u00e9cis\u00e9ment accord\u00e9 \u00e0 l&rsquo;\u00e9v\u00e9nement qui suscite cette r\u00e9flexion : <strong>rien<\/strong> dans ces trois formes de jugement (politique, id\u00e9ologique, moral) ne permettait d&rsquo;appr\u00e9hender, non pas les r\u00e9sultats obtenus ce 14 septembre 2010 par <em>Tea Party<\/em>, ou par la n\u00e9buleuse myst\u00e9rieuse que forme <em>Tea Party<\/em>, mais, bien plus encore, le choc psychologique fondamental obtenu par <em>Tea Party<\/em>. Ce choc psychologique fondamental implique essentiellement la perception que l&rsquo;\u00e9v\u00e9nement du 14 septembre 2010 ouvre pour la premi\u00e8re fois de fa\u00e7on s\u00e9rieuse dans l&rsquo;histoire des USA une br\u00e8che effectivement fondamentale dans la structure formidablement puissante, aussi bien dans le contr\u00f4le politique que dans la communication qui pr\u00e9sente avantageusement ce contr\u00f4le politique, du syst\u00e8me de l&rsquo;am\u00e9ricanisme tel qu&rsquo;il existe aux USA depuis l&rsquo;origine.<\/p>\n<\/p>\n<p><p>\tLes trois formes de jugement renvoient tous \u00e0 des conclusions similaires, bien entendu potentiellement ou ouvertement n\u00e9gatives. Politiquement, le mouvement <em>Tea Party<\/em> est jug\u00e9 comme un mouvement extr\u00e9miste mais aussi populiste, ce qui contient sans doute une contradiction interne. (Le populisme est, par d\u00e9finition, surtout dans son acception US, un mouvement caract\u00e9ris\u00e9 par sa largeur, par son amplitude, touchant diff\u00e9rents milieux unis par une m\u00eame r\u00e9action, qui ont en commun d&rsquo;\u00eatre populaires ; il n&rsquo;est finalement jug\u00e9 extr\u00e9miste que dans la mesure o\u00f9 l&rsquo;on d\u00e9termine qu&rsquo;il refuse les normes du syst\u00e8me oligarchique en place, notamment les normes d&rsquo;all\u00e9geance aux principes du syst\u00e8me, etc.) Id\u00e9ologiquement, <em>Tea Party<\/em> est appr\u00e9ci\u00e9 comme un mouvement d&rsquo;extr\u00eame droite. Cette appr\u00e9ciation est fond\u00e9e sur le fait qu&rsquo;il se manifeste surtout en marge du parti r\u00e9publicain, ou sur l&rsquo;aile droite de ce m\u00eame parti, plut\u00f4t comme une dissidence de ce parti, marqu\u00e9e par des appr\u00e9ciations caract\u00e9ris\u00e9es par le radicalisme et l&rsquo;absence de coh\u00e9rence et de r\u00e9alisme, et aussi par le refus du gouvernement comme centre actif du syst\u00e8me. Moralement, il est appr\u00e9ci\u00e9 comme un mouvement de tendance x\u00e9nophobe, voire raciste, donc hautement condamnable, sans pourtant qu&rsquo;aucune certitude ne puisse \u00eatre avanc\u00e9 \u00e0 cet \u00e9gard. Aujourd&rsquo;hui encore, 18 mois apr\u00e8s son apparition publique (en avril 2009), le jugement \u00e0 cet \u00e9gard est compl\u00e8tement incertain, et le vice-pr\u00e9sident Biden, qui est pourtant en principe tr\u00e8s hostile \u00e0 <em>Tea Party<\/em>, a pu affirmer encore le 20 ao\u00fbt 2010 qu&rsquo;il estimait que <em>Tea Party<\/em> n&rsquo;est pas raciste, ajoutant que le pr\u00e9sident Obama juge de m\u00eame.<\/p>\n<\/p>\n<p><p>\tRien dans tout cela ne rend compte de ce qu&rsquo;on per\u00e7oit et ressent de puissance v\u00e9ridique dans les effets de son action sur la situation am\u00e9ricaniste. Pour en juger, il faut donc se d\u00e9gager de ces diff\u00e9rentes appr\u00e9ciations contingentes, qui ne sont faites que pour renforcer le syst\u00e8me de l&rsquo;am\u00e9ricanisme (et notre syst\u00e8me en g\u00e9n\u00e9ral) comme r\u00e9f\u00e9rence centrale, dans ce cas en jetant l&rsquo;opprobre ou le doute sur <em>Tea Party<\/em>. La v\u00e9rit\u00e9 du mouvement <em>Tea Party<\/em>, sans que cela n&rsquo;implique le moindre jugement politique, id\u00e9ologique ou moral de ce mouvement, qui devient alors inutile et m\u00eame inf\u00e9cond, se mesure essentiellement aux effets qu&rsquo;il est en train de produire. Peu importe \u00e9galement si le mouvement d\u00e9sire ou ne d\u00e9sire pas obtenir ces effets, si les hommes et les femmes qui y participent ont de telles intentions ou, au contraire, des ambitions diff\u00e9rentes. Le fait appara\u00eet \u00e9vident que le 14 septembre a renforc\u00e9 de fa\u00e7on d\u00e9cisive un cycle de r\u00e9v\u00e9lation qui donne \u00e0 <em>Tea Party<\/em> la capacit\u00e9 d&rsquo;exprimer un sentiment collectif extr\u00eamement profond, contre la tyrannie que l&rsquo;<em>establishment<\/em> du syst\u00e8me fait peser sur la population US. Il n&rsquo;est pas assur\u00e9 du tout que cette population le ressente de la sorte et aussi clairement, \u00e0 l&rsquo;image de l&rsquo;ind\u00e9cision qu&rsquo;on a signal\u00e9e concernant les participants sup\u00e9rieurs et divers meneurs de <em>Tea Party<\/em>. L&rsquo;essentiel, qui \u00e9chappe donc aux diff\u00e9rents d\u00e9sirs manuvriers et volont\u00e9s diverses, est que le mouvement r\u00e9v\u00e8le et exprime \u00e0 la fois une <strong>v\u00e9rit\u00e9<\/strong> extr\u00eamement importante. Alors qu&rsquo;elle n&rsquo;\u00e9tait que latente, il la substantive dans le jeu politique qui n&rsquo;a jusqu&rsquo;ici \u00e9tait anim\u00e9 que pour \u00e9touffer l&rsquo;apparition, et, encore plus, la substantivation de cette v\u00e9rit\u00e9. De ce point de vue, on peut dire qu&rsquo;il existe un effet m\u00e9taphysique de <em>Tea Party<\/em>, \u00e9chappant \u00e0 tous les acteurs, qui change de fa\u00e7on substantielle la situation fondamentale des USA. Ce qui n&rsquo;\u00e9tait jusqu&rsquo;ici qu&rsquo;hypoth\u00e8se, sp\u00e9culation, intuition \u00e0 propos de cette situation, devient une \u00e9vidence, passant ainsi, insensiblement, de l&rsquo;\u00e9tat de substance que l&rsquo;on devinait, \u00e0 un \u00e9tat d&rsquo;essence, constitu\u00e9e de fa\u00e7on coh\u00e9rente et formelle. En quelque sorte, <em>Tea Party<\/em>, en m\u00eame temps qu&rsquo;il r\u00e9v\u00e8le cette v\u00e9rit\u00e9, sert \u00e0 faire \u00e9voluer cette situation dans le sens d&rsquo;une structuration.<\/p>\n<\/p>\n<p><p>\tA cette lumi\u00e8re, il appara\u00eet \u00e9vident que les caract\u00e8res identifi\u00e9es ci-dessus pour marquer la nature en apparence insaisissable du mouvement, qui para\u00eetraient \u00e0 premi\u00e8re vue avoir desservi <em>Tea Party<\/em>, l&rsquo;ont au contraire pr\u00e9serv\u00e9 de toute la rigueur anath\u00e9matique des jugements politiques, id\u00e9ologiques et moraux dont les serviteurs du syst\u00e8me se servent d&rsquo;habitude pour r\u00e9cup\u00e9rer des mouvements ext\u00e9rieurs au syst\u00e8me, ou pour les briser. Ainsi, <em>Tea Party<\/em> a pu jusqu&rsquo;ici passer au travers des mailles du filet pour parvenir d&rsquo;ores et d\u00e9j\u00e0 \u00e0 un r\u00e9sultat important, qui est la mise en lumi\u00e8re et l&rsquo;animation d&rsquo;une v\u00e9rit\u00e9 fondamentale. <em>Tea Party<\/em> a \u00e9t\u00e9 un outil,  inconscient sans doute, cela n&rsquo;importe pas,  d&rsquo;une \u00e9volution importante de la soci\u00e9t\u00e9, dans le cadre de la grande crise du syst\u00e8me g\u00e9n\u00e9ral. Il en a r\u00e9v\u00e9l\u00e9 des aspects dissimul\u00e9s ou \u00e9touff\u00e9s. Il a mis \u00e0 jour des v\u00e9rit\u00e9s m\u00e9taphysiques sans que le syst\u00e8me ait r\u00e9ussi \u00e0 le subvertir suffisamment pour le neutraliser. Le parcours de <em>Tea Party<\/em> jusqu&rsquo;\u00e0 maintenant (jusqu&rsquo;au 14 septembre),  sans pr\u00e9juger <strong>en rien<\/strong> de ce qu&rsquo;il en adviendra (ni m\u00eame de ce qu&rsquo;il est lui-m\u00eame),  a montr\u00e9 qu&rsquo;un refus explicite ou implicite d&rsquo;affronter le syst\u00e8me sur son terrain (politique, id\u00e9ologique et moral), c&rsquo;est-\u00e0-dire la volont\u00e9 d&rsquo;aborder les probl\u00e8mes \u00e0 un niveau diff\u00e9rent, d&rsquo;un point de vue n\u00e9cessairement m\u00e9taphysique, plonge le syst\u00e8me dans l&#8217;embarras le plus extr\u00eame et le conduit \u00e0 l&rsquo;impuissance et \u00e0 la confusion. La subversion compl\u00e8te de la politique, de l&rsquo;id\u00e9ologie et de la morale par le syst\u00e8me, avec comme cons\u00e9quence la subversion \u00e9galement compl\u00e8te de la r\u00e9alit\u00e9, conduit effectivement et efficacement \u00e0 cet appel \u00e0 la m\u00e9taphysique pour rendre compte de la juste mesure des \u00e9v\u00e9nements,  ce que l&rsquo;on nomme en g\u00e9n\u00e9ral v\u00e9rit\u00e9&#8230;<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 16 septembre 2010 \u00e0 16H51<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le mouvement Tea Party est le ph\u00e9nom\u00e8ne politique US \u00e0 la fois le plus original, le plus puissant, le plus suspect, le plus d\u00e9cri\u00e9 et peut-\u00eatre le plus myst\u00e9rieux de ces derni\u00e8res ann\u00e9es. (Nous entendons myst\u00e9rieux non dans le sens d&rsquo;une volont\u00e9 de myst\u00e8re, comme dans la composition d&rsquo;une soci\u00e9t\u00e9 secr\u00e8te ou d&rsquo;un complot, mais&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3522,2673,7069,3321,6258,8049,8256,5445],"class_list":["post-72285","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-3522","tag-metaphysique","tag-party","tag-septembre","tag-structuration","tag-subversion","tag-tea","tag-verite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72285","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72285"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72285\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72285"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72285"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72285"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}