{"id":72312,"date":"2010-09-24T06:27:30","date_gmt":"2010-09-24T06:27:30","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/09\/24\/prisonniers-de-la-guerre-et-du-systeme\/"},"modified":"2010-09-24T06:27:30","modified_gmt":"2010-09-24T06:27:30","slug":"prisonniers-de-la-guerre-et-du-systeme","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/09\/24\/prisonniers-de-la-guerre-et-du-systeme\/","title":{"rendered":"Prisonniers de la guerre (et du syst\u00e8me)"},"content":{"rendered":"<p><p>Plus personne n&rsquo;h\u00e9site \u00e0 qualifier Bob Woodward, du Washington <em>Post<\/em> et du Watergate r\u00e9unis, d&rsquo;historien officiel de la Maison-Blanche, quel que soit le pr\u00e9sident et le parti. Homme de pi\u00e8tre qualit\u00e9 morale, totalement acquis au syst\u00e8me, mais avec les excellentes qualit\u00e9s techniques du bon professionnel, couvert d&rsquo;or pour ses succ\u00e8s de librairie, Woodward s&rsquo;est donc ex\u00e9cut\u00e9 pour la premi\u00e8re p\u00e9rip\u00e9tie majeure de l&rsquo;administration Obama, dans son livre intitul\u00e9 sans grande originalit\u00e9 mais d&rsquo;une fa\u00e7on elliptique <em>Obama&rsquo;s War<\/em>. Rupert Cornwell, dans <em>The Independent<\/em>, en fait un excellent rapport ce <a href=\"http:\/\/www.independent.co.uk\/news\/world\/asia\/karzai-was-diagnosed-with-manic-depression-new-book-on-war-claims-2087038.html\" class=\"gen\">23 septembre 2010<\/a>. Il nous indique les principales r\u00e9v\u00e9lations de Woodward, excellemment servi par ses nombreuses sources officielles, y compris celles qui veulent faire savoir certaines choses sans \u00eatre n\u00e9cessairement identifi\u00e9es. En effet, Woodward sert \u00e9galement, souvent, de courroie de transmission pour les gens du pouvoir (quel que soit l&rsquo;aile du parti unique concern\u00e9e).<\/p>\n<\/p>\n<p><p>\tCornwell observe qu&rsquo;il y a, justement, peu de r\u00e9v\u00e9lations explosives dans le livre, dont le titre fait allusion aux guerres internes de l&rsquo;\u00e9quipe pr\u00e9sidentielles \u00e0 propos de l&rsquo;Afghanistan et des quatre mois (ao\u00fbt-novembre 2009) qui aboutirent aux d\u00e9cisions de poursuites de la guerre dans des conditions bureaucratiques chaotiques. Certes, il y est fait mention de l&rsquo;\u00e9quipe de 3.000 assassins (l&rsquo;expression dit tout) que la CIA entretient pour le contre-terrorisme, et du jugement m\u00e9dical port\u00e9 par la m\u00eame CIA sur Karza\u00ef (maniaco-d\u00e9pressif) qui ressemble au diagnostic d&rsquo;un docteur lui-m\u00eame en traitement pour la m\u00eame affection,  donc excellent connaisseur en ce sens, mais sans doute avec l&rsquo;\u00e9quilibre du jugement compromis. On suivra sans aucun doute Cornwell lorsqu&rsquo;il d\u00e9taille essentiellement les tourments d&rsquo;Obama, sa frustration, finalement son \u00e9chec \u00e0 imposer sa volont\u00e9 de disposer, essentiellement du Pentagone, des options diverses, notamment d&rsquo;une strat\u00e9gie de sortie de la guerre.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>President Obama fought hard but in vain to force the Pentagon to come up with an exit strategy for the deepening war in Afghanistan  his difficulties compounded by fierce disputes within his national security team and the need to deal with an Afghan leader they trusted little and who, according to US intelligence, was a manic depressive.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>What emerges is a President desperate not to be trapped in a war without end  a cool, rational and analytical man faced with a choice between bad options. \u00ab\u00a0I&rsquo;m not doing 10 years; I&rsquo;m not doing nation building; I&rsquo;m not spending a trillion dollars,\u00a0\u00bb Mr Obama is quoted as saying to Robert Gates, the Defence Secretary, and the Secretary of State Hillary Clinton, during one key meeting in October 2009.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Nonetheless, the appearance now of Obama&rsquo;s Wars, and its detailing of bitter arguments at the summit of US government, will not do Mr Obama and his Democratic Party any good less than six weeks before the midterm elections.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>If anything, it can only further weaken public support for an unpopular and ever deadlier war  and for a strategy that, according to the Woodward account, even close advisers like Richard Holbrooke, the President&rsquo;s special envoy for Afghanistan and Pakistan, and Lt- Gen Douglas E Lute, the President&rsquo;s Afghanistan adviser, doubt will work.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Meanwhile, confusion reigns over Mr Obama&rsquo;s plan for a start in the drawdown of US troops by July 2011. Some officials have publicly stated the date is a mere target and any force reduction will be purely symbolic, but the President himself is quoted as insisting on a firm timetable, because I can&rsquo;t lose the whole Democratic Party.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Mr Biden, rarely one to mince words, described the hard-charging Mr Holbrooke as the most egotistical bastard I&rsquo;ve ever met, while several administration officials expressed scorn for General James Jones, the national security adviser  who reputedly referred in turn to some of Mr Obama&rsquo;s political aides as the water bugs or the Politburo.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>But most poignant is Mr Obama&rsquo;s quest for a way out of what has become one of America&rsquo;s longest wars. I want an exit strategy, he is said to have implored at one meeting. But the Pentagon never produced one. Fearful of continuing attempts by the military to expand the mission, Mr Obama eventually personally dictated a six-page terms sheet setting out precisely what the military could and could not do. A copy of the document is printed in the book.<\/em>\u00bb<\/p>\n<h4>Notre commentaire<\/h4>\n<p> Les d\u00e9tails abondent, comme Cornwell nous le fait sentir, et des d\u00e9tails qui vont tous dans le sens d&rsquo;une confirmation du double constat, dont le premier est qu&rsquo;il s&rsquo;agit d&rsquo;une direction politique absolument atomis\u00e9e, laiss\u00e9e aux tensions internes et aux querelles de personnes parce que personne n&rsquo;est capable d&rsquo;imposer une ligne de conduite, et certainement pas le pr\u00e9sident \u00e0 qui revient cette t\u00e2che. Faut-il le bl\u00e2mer ? A ce stade, sans doute pas, car le pr\u00e9sident se trouve,  c&rsquo;est le deuxi\u00e8me point \u00e9vident, le deuxi\u00e8me constat,  dans une situation o\u00f9 le syst\u00e8me a pris absolument le contr\u00f4le de l&rsquo;analyse strat\u00e9gique et du processus de d\u00e9cision. Cela \u00e9tait le cas avant qu&rsquo;Obama n&rsquo;arrive pas au pouvoir, et n&rsquo;avoir pas compris qu&rsquo;il s&rsquo;agissait du principal probl\u00e8me auquel il fallait s&rsquo;attaquer en priorit\u00e9, m\u00eame par des moyens violents \u00e0 la limite de ses pr\u00e9rogatives constitutionnels, repr\u00e9sente sa faute majeure, la faute originelle qui a compromis d\u00e9finitivement son mandat \u00e0 son d\u00e9but.<\/p>\n<\/p>\n<p><p>\tNous ne parlons certainement pas d&rsquo;un complot du Pentagone et d&rsquo;un pr\u00e9sident marionnette de forces obscures et conscientes de leur action, mais bien d&rsquo;une dynamique m\u00e9canique totalement irr\u00e9sistible, engendr\u00e9 pas ce syst\u00e8me de la mati\u00e8re d\u00e9cha\u00een\u00e9e que nous ne cessons de d\u00e9crire (voir notamment notre <a href=\"http:\/\/www.dedefensa.org\/section-la_grace_de_l_histoire.html\" class=\"gen\">ouvrage<\/a> <em>La gr\u00e2ce de l&rsquo;Histoire<\/em>) ; ce syst\u00e8me g\u00e9n\u00e9ral fait du syst\u00e8me du technologisme et du syst\u00e8me de communication et exprim\u00e9 dans ce cas par la pouss\u00e9e effectivement irr\u00e9sistible de la m\u00e9canique de la bureaucratie du Pentagone que Rumsfeld d\u00e9non\u00e7ait le <a href=\"http:\/\/www.dedefensa.org\/article-le_courage_de_rumsfeld_et_un_discours_qui_merite_de_faire_date_11_09_2001.html\" class=\"gen\">10 septembre 2001<\/a>. Comme le disait Rumsfeld, il ne s&rsquo;agit pas des \u00eatres humains, des bureaucrates eux-m\u00eames, encore moins d&rsquo;une sorte de direction qui aurait un plan selon l&rsquo;acception humaine du terme, mais bien d&rsquo;un processus m\u00e9canique qui les domine tous et limite les possibilit\u00e9s de changement \u00e0 la seule possibilit\u00e9 d&rsquo;un \u00e9clat, d&rsquo;un coup d&rsquo;Etat int\u00e9rieur que seul le pr\u00e9sident, en l&rsquo;occurrence, pourrait conduire, arguant de son autorit\u00e9 et cherchant \u00e0 l&rsquo;imposer par l&rsquo;ext\u00e9rieur, hors du processus bureaucratique auquel il est soumis, sinon encha\u00een\u00e9 (l&rsquo;option <em>American<\/em> <a href=\"http:\/\/www.dedefensa.org\/article-american_gorbatchev_29_10_2008.html\" class=\"gen\">Gorbatchev<\/a>).<\/p>\n<\/p>\n<p><p>\tLe livre de Woodward nous montre, ou plut\u00f4t nous confirme cette situation, par rapport \u00e0 ce qui nous est souvent apparu. Il nous confirme<\/p>\n<\/p>\n<p><p>\t Qu&rsquo;Obama a d\u00e9sesp\u00e9r\u00e9ment lutt\u00e9 pour obtenir rationnellement une palette d&rsquo;options claires, y compris cette fameuse strat\u00e9gie de sortie. La m\u00e9thode choisie par lui \u00e9tait \u00e9videmment vou\u00e9e \u00e0 l&rsquo;\u00e9chec puisque Obama utilise la raison pour lutter contre un syst\u00e8me auquel <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_crise_de_la_raison_humaine_ddecrisis_18_07_2010.html\" class=\"gen\">la raison humaine<\/a>, justement, est compl\u00e8tement soumise, renvoyant \u00e0 la subversion profonde \u00e0 laquelle elle a succomb\u00e9. La faute cardinale d&rsquo;Obama, nous dirions la faiblesse psychologique d&rsquo;une intelligence brillante qui croit un peu trop \u00e0 elle-m\u00eame, est d&rsquo;avoir cru que, justement, la raison humaine imposerait sa logique, sans r\u00e9aliser qu&rsquo;il utilise un outil que le syst\u00e8me manipule depuis longtemps \u00e0 son avantage. De ce point de vue, et tant qu&rsquo;il suivra cette m\u00e9thode (en fait, une non-m\u00e9thode), Obama ne fera qu&rsquo;accentuer l&#8217;emprisonnement o\u00f9 il se trouve,  mais le suggestion qu&rsquo;il existe une possibilit\u00e9 qu&rsquo;il change est sans doute d\u00e9plac\u00e9e et l&rsquo;on voit mal d\u00e9sormais qu&rsquo;il puisse jamais en changer. Obama n&rsquo;est pas une marionnette sinon par capitulation inconsciente, il est plut\u00f4t un homme qui manque d&rsquo;intuition, qui est aveugl\u00e9 par ses propres qualit\u00e9s intellectuelles, il est prisonnier de lui-m\u00eame en ignorant que l&rsquo;exceptionnelle situation pr\u00e9sente requiert \u00e9videmment de d\u00e9passer une raison et une intelligence qui sont totalement subverties par le syst\u00e8me. A ce point rien n&rsquo;est possible qu&rsquo;il puisse faire, et l&rsquo;on craint fort que rien ne change si lui-m\u00eame ne change pas, et que la marche vers la catastrophe (pour l&rsquo;Afghanistan et pour le reste) se poursuive sans d\u00e9semparer. (Vraiment, l&rsquo;option <em>American<\/em> <a href=\"http:\/\/www.dedefensa.org\/article-american_gorbatchev_29_10_2008.html\" class=\"gen\">Gorbatchev<\/a> ne semble plus \u00eatre qu&rsquo;un pauvre souvenir, avec tous les regrets divers que certains pourraient entretenir Mais le sentiment doit \u00eatre nuanc\u00e9 par la notion de l&rsquo;int\u00e9r\u00eat tactique en l&rsquo;occurrence, au service de la strat\u00e9gie de r\u00e9sistance au syst\u00e8me et de destruction de ce syst\u00e8me. L&rsquo;\u00e9chec d&rsquo;Obama \u00e0 cet \u00e9gard est aussi un acc\u00e9l\u00e9rateur indirect de cet effondrement du syst\u00e8me, en privant ce syst\u00e8me d&rsquo;une chance que l&rsquo;un des hommes cens\u00e9s assurer sa gestion et son op\u00e9rationalit\u00e9 aurait pu lancer une tentative de r\u00e9forme radicale.)<\/p>\n<\/p>\n<p><p>\t Woodward nous confirme qu&rsquo;autour d&rsquo;Obama, c&rsquo;est l&rsquo;irresponsabilit\u00e9 compl\u00e8te, la foire aux vanit\u00e9s dans\u00e9e sur le mode du conformisme et des int\u00e9r\u00eats particuliers qui n&rsquo;ont aucun rapport direct avec le sujet, avec la politique en g\u00e9n\u00e9ral. Personne ne croit vraiment que cette guerre puisse \u00eatre gagn\u00e9e mais tout le monde continue \u00e0 agir pour sa poursuite, selon ses propres conceptions et pour ses int\u00e9r\u00eats autant que pour sa propre vanit\u00e9. Nul n&rsquo;a conscience, l\u00e0 aussi, encore moins qu&rsquo;Obama bien s\u00fbr, d&rsquo;\u00eatre emport\u00e9 par un syst\u00e8me d&rsquo;une puissance sup\u00e9rieure,  et, \u00e0 la limite, tout le monde s&rsquo;en fout L&rsquo;entourage d&rsquo;Obama est d\u00e9crit comme un Politburo par le g\u00e9n\u00e9ral Jones, impliquant effectivement que chacun ne cherche qu&rsquo;\u00e0 renforcer sa position aupr\u00e8s du pr\u00e9sident tout en suivant les consignes du Parti (du syst\u00e8me m\u00e9caniste de la mati\u00e8re d\u00e9cha\u00een\u00e9e). Holbrooke, l&rsquo;ambassadeur sp\u00e9cial pour l&rsquo;Afghanistan et le Pakistan, se confirme comme cet homme insupportable de suffisance et de brutalit\u00e9 que tout le monde conna\u00eet bien depuis la signature de l&rsquo;accord de Dayton sur la Bosnie, en 1995. Rien de nouveau sous le soleil pour ce personnage, sinon une aggravation irr\u00e9sistible des choses.<\/p>\n<\/p>\n<p><p>\tD&rsquo;apr\u00e8s les \u00e9l\u00e9ments que nous communique Cornwell, <em>Obama&rsquo;s Wars<\/em> est une description passionnante de la crise centrale du syst\u00e8me,  paradoxalement sous la pression constante de ce syst\u00e8me, qui s&rsquo;av\u00e8re indirectement suicidaire dans ce cas, confirmant sa tendance g\u00e9n\u00e9rale,  qui est la crise de l&#8217;emprisonnement, de l&rsquo;impuissance et de l&rsquo;aveuglement des directions politiques, avec la perte totale des priorit\u00e9s imp\u00e9ratives qui vont avec (ce qu&rsquo;on nommerait dans d&rsquo;autres cas int\u00e9r\u00eat du bien public, mais expression sans signification pour le syst\u00e8me de l&rsquo;am\u00e9ricanisme). De ce point de vue, le processus d&rsquo;effondrement du syst\u00e8me, dans le chef de la d\u00e9cadence acc\u00e9l\u00e9r\u00e9e de l&rsquo;outil essentiel de ce syst\u00e8me qu&rsquo;est la direction politique, est patent. Qu&rsquo;on compare ce que Woodward d\u00e9crit avec ce qu&rsquo;on conna\u00eet en abondance, d&rsquo;une fa\u00e7on extr\u00eamement pr\u00e9cise, du comportement exceptionnellement f\u00e9cond de la direction politique US durant la crise de Cuba en octobre 1962, autour du pr\u00e9sident Kennedy, et l&rsquo;on a une mesure de cette d\u00e9cadence vers l&rsquo;impuissance, la paralysie et l&rsquo;aveuglement. La question n&rsquo;est nullement ici de signaler des manigances, des manuvres, de disserter autour des vertus ou pas de ces hommes, mais de constater l&rsquo;extraordinaire pr\u00e9pond\u00e9rance qu&rsquo;a acquis ce syst\u00e8me automatique et m\u00e9caniste sur les hommes, qui ne sont plus que des pantins d\u00e9sarticul\u00e9s, des personnage <a href=\"http:\/\/www.dedefensa.org\/article-a_propos_de_maistre_de_sarko_de_l_histoire_et_du_reste_21_05_2007.html?admin=1\" class=\"gen\">maistriens<\/a>  sans la moindre influence sur les \u00e9v\u00e9nements. Cette guerre, que tout le monde juge au fond stupide et sans aucun espoir d&rsquo;une victoire, est donc poursuivie parce que la dynamique puissante du syst\u00e8me le veut ainsi. M\u00eame un Robert Gates doit penser ainsi (guerre sans espoir), m\u00eame lui, bien entendu, est totalement prisonnier du processus bureaucratique dont il lui arrive parfois, dans des moments de lucidit\u00e9 vite r\u00e9prim\u00e9s, de proclamer que la t\u00e2che essentielle est de le vaincre pour en reprendre le contr\u00f4le. A lire ces impressions et extraits du bouquin de Woodward, qui s&rsquo;annonce aussi clair que de l&rsquo;eau de roche sans que lui-m\u00eame s&rsquo;en avise, on ne fait que lire une phase particuli\u00e8rement marquante de l&rsquo;agonie brutale des derniers espoirs d&rsquo;influence des hommes du syst\u00e8me, en g\u00e9n\u00e9ral mis en place pour assurer la gestion du syst\u00e8me \u00e0 l&rsquo;avantage de celui-ci et qui sont interdits de le faire par la pression brutale et sans compromis de ce m\u00eame syst\u00e8me qui suscite tout ce qu&rsquo;il y a de plus bas chez les hommes qui doivent le servir.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 24 septembre 2010 \u00e0 06H16<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Plus personne n&rsquo;h\u00e9site \u00e0 qualifier Bob Woodward, du Washington Post et du Watergate r\u00e9unis, d&rsquo;historien officiel de la Maison-Blanche, quel que soit le pr\u00e9sident et le parti. Homme de pi\u00e8tre qualit\u00e9 morale, totalement acquis au syst\u00e8me, mais avec les excellentes qualit\u00e9s techniques du bon professionnel, couvert d&rsquo;or pour ses succ\u00e8s de librairie, Woodward s&rsquo;est donc&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3236,3612,3015,4926,2631,10042,2651,3483,4300,9827,583,2622,4576,8855,6208,10089,3194,10088,5535,3014,4268,6693,4847],"class_list":["post-72312","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-afghanistan","tag-american","tag-communication","tag-complot","tag-de","tag-dechainee","tag-du","tag-gorbatchev","tag-holbrooke","tag-humaine","tag-jones","tag-la","tag-marionnette","tag-matiere","tag-obama","tag-obamas","tag-pentagone","tag-politburo","tag-raison","tag-systeme","tag-technologisme","tag-wars","tag-woodward"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72312"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72312\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}