{"id":72314,"date":"2010-09-24T12:30:29","date_gmt":"2010-09-24T12:30:29","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/09\/24\/internet-etou-google-recablent-t-ils-nos-cerveaux\/"},"modified":"2010-09-24T12:30:29","modified_gmt":"2010-09-24T12:30:29","slug":"internet-etou-google-recablent-t-ils-nos-cerveaux","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/09\/24\/internet-etou-google-recablent-t-ils-nos-cerveaux\/","title":{"rendered":"Internet et\/ou Google rec\u00e2blent-t-ils nos cerveaux?"},"content":{"rendered":"<p><h2 class=\"common-article2\">Internet et\/ou Google rec\u00e2blent-t-ils nos cerveaux? <\/h2>\n<\/p>\n<p><p>\t<strong>Les technologies de communication touchent d\u00e9sormais pratiquement l&rsquo;ensemble des humains. L&rsquo;une de celle qui, sans \u00eatre aussi universelle que le t\u00e9l\u00e9phone mobile, attire de plus en plus l&rsquo;int\u00e9r\u00eat des chercheurs par son caract\u00e8re structurant, est l&rsquo;Internet.<\/strong><\/p>\n<\/p>\n<p><p>\tNous avons dans notre essai <em>Le paradoxe du Sapiens<\/em>, fait  l&rsquo;hypoth\u00e8se que les humains co-\u00e9voluent avec les technologies qu&rsquo;ils utilisent, au sein de superorganismes que nous avons nomm\u00e9s des syst\u00e8mes anthropotechniques. Ces superorganismes sont tr\u00e8s diff\u00e9rents les uns des autres, compte tenu de ce que les technologies sont elles-m\u00eames tr\u00e8s diff\u00e9rentes et que les humains entrant en symbiose avec elles peuvent \u00eatre \u00e9ventuellement aussi tr\u00e8s diff\u00e9rents, par l&rsquo;\u00e2ge, le sexe, les origines sociales, etc. Pour pr\u00e9ciser le concept de syst\u00e8mes anthropotechnique, il faut donc en \u00e9tudier des vari\u00e9t\u00e9s diff\u00e9rentes.<\/p>\n<\/p>\n<p><p>\tNous avions dans le livre insist\u00e9 sur l&rsquo;influence des technologies d&rsquo;armement mais \u00e9voqu\u00e9 aussi celle des technologies de communication. Celles-ci touchent d\u00e9sormais pratiquement l&rsquo;ensemble des humains. L&rsquo;une de celle qui, sans \u00eatre aussi universelle que le t\u00e9l\u00e9phone mobile, attire de plus en plus l&rsquo;int\u00e9r\u00eat des chercheurs par son caract\u00e8re structurant, est l&rsquo;Internet. On estime que le nombre des personnes connect\u00e9es de par le monde d\u00e9passe d\u00e9sormais le milliard et s&rsquo;accro\u00eet tous les jours. Il est donc l\u00e9gitime de se demander si l&rsquo;ensemble constitu\u00e9 par les usagers de l&rsquo;Internet et par l&rsquo;ensemble des technologies et des acteurs industriels qui les relient n&rsquo;a pas donn\u00e9 naissance \u00e0 l&rsquo;un de ces superorganismes que nous nommons pour notre part des syst\u00e8mes anthropotechniques.<\/p>\n<\/p>\n<p><p>\tLes \u00e9tudes consacr\u00e9es \u00e0 l&rsquo;Internet et \u00e0 ses cons\u00e9quences soci\u00e9tales sont nombreuses. Ceux qui les conduisent ne s&rsquo;inspirent \u00e9videmment pas de notre approche syst\u00e9mique. Il se trouve cependant que certains chercheurs, sans nous avoir lu, reprennent et parfois illustrent nos postulats. C&rsquo;est le cas de <a href=\"http:\/\/en.wikipedia.org\/wiki\/Nicholas_G._Carr\" class=\"gen\"> Nicholas Carr<\/a>, \u00e9crivain am\u00e9ricain qui s&rsquo;est sp\u00e9cialis\u00e9 dans l&rsquo;analyse de l&rsquo;impact social des technologies . Il vient de publier <em>The Shallows: How the Internet is changing the way we think, read and remember<\/em>, Atlantic Books. Au del\u00e0 de l&rsquo;Internet en g\u00e9n\u00e9ral, il s&rsquo;est r\u00e9cemment fait conna\u00eetre en s&rsquo;en prenant \u00e0 Google, qu&rsquo;il accuse de nous rendre stupides (\u00ab<em>Is Google Making Us Stupid?<\/em>\u00bb). (1)<\/p>\n<\/p>\n<p><p>\tIl a \u00e9galement vivement critiqu\u00e9 le syst\u00e8me global d&rsquo;information Wikipedia \u00e0 qui il reproche de g\u00e9n\u00e9raliser la facilit\u00e9 dans la recherche de l&rsquo;information. Pour lui, la blogosph\u00e8re dans son ensemble peut susciter le m\u00eame reproche, dans la mesure o\u00f9 beaucoup d&rsquo;internautes dor\u00e9navant s&rsquo;en tiennent aux blogs pour s&rsquo;informer et s&rsquo;exprimer. Inutile de dire que ces critiques ont suscit\u00e9 de nombreux d\u00e9bats. Nicholas Carr a \u00e9t\u00e9 pr\u00e9sent\u00e9 comme le Cassandre des nouvelles technologies. Mais comme l&rsquo;on sait, Cassandre avait de bonnes raisons de s&rsquo;inqui\u00e9ter. Pour notre part, nous le suivrons pas cependant dans son pessimisme. Sans Internet, nous serions sans voix ni oreilles.<\/p>\n<\/p>\n<p><p>\tPour y voir plus clair, il convient de distinguer l&rsquo;influence que peut avoir l&rsquo;Internet, dit aussi le web, en g\u00e9n\u00e9ral et celle plus sp\u00e9cifique qu&rsquo;exercent certains acteurs puissants qui s&rsquo;y d\u00e9ploient, le plus \u00e9vident aujourd&rsquo;hui, et le plus inqui\u00e9tant aussi, \u00e9tant effectivement, comme le souligne Nicolas Carr, Google. Que pouvons nous en dire ici, \u00e0 la lumi\u00e8re de notre concept de syst\u00e8me anthropotechnique? <\/p>\n<h3>Le cerveau de l&rsquo;utilisateur d&rsquo;Internet<\/h3>\n<\/p>\n<p><p>\tUn des points essentiel soulign\u00e9 dans Le paradoxe du Sapiens concerne l&rsquo;action de transformation des bases neurales des utilisateurs des outils, quels que soient ceux-ci. Par bases neurales, il faut entendre les circuits du cortex associatif mais aussi ceux des cortex sensoriels et moteurs qui s&rsquo;activent dans la manipulation des outils et souvent, sous l&rsquo;influence des neurones dits miroirs, \u00e0 la simple vue de personnes utilisant ces outils. Ces circuits sont dot\u00e9s \u00e0 la naissance d&rsquo;une certaine organisation transmise g\u00e9n\u00e9tiquement. Ils se sp\u00e9cialisent et se diversifient au long de la vie de l&rsquo;individu compte tenu des acquis dits culturels. Il n&rsquo;est pas exclu, comme l&rsquo;a montr\u00e9 le biologiste Jean-Jacques Kupiec que certaines des sp\u00e9cialisations dues aux usages culturels puissent, si elles se mettent en place assez t\u00f4t dans la vie de l&rsquo;individu, se traduire par des modifications plus ou moins profondes du g\u00e9nome reproductif et se transmettre \u00e0 la descendance, comme le font de nombreuses autres acquisitions. <\/p>\n<\/p>\n<p><p>\tUn des points sur lequel insiste Nicholas Carr concerne pr\u00e9cis\u00e9ment la modification des bases neurales de la cognition qu&rsquo;entra\u00eene la fr\u00e9quentation de l&rsquo;Internet. Il consid\u00e8re en effet que l&rsquo;utilisation de celui-ci fait appel \u00e0 une tendance tr\u00e8s primitive de notre esprit, consistant \u00e0 s&rsquo;int\u00e9resser \u00e0 tous les changements fussent-ils rapides de notre environnement, afin d&rsquo;en obtenir une image globale \u00e0 partir de laquelle nous pourrions adapter instantan\u00e9ment nos conduites. Cette situation est celle de l&rsquo;individu vivant dans une jungle mena\u00e7ante. Pour survivre, il doit avoir l&rsquo;oeil \u00e0 tout afin de fuir les dangers et exploiter instantan\u00e9ment les opportunit\u00e9s favorables. Mais avec le d\u00e9veloppement des connaissances collectives et de la recherche rationnelle, les individus ont appris \u00e0 focaliser leur attention, approfondir leurs repr\u00e9sentations, transf\u00e9rer de l&rsquo;information de la m\u00e9moire de travail imm\u00e9diate \u00e0 la m\u00e9moire durable. Le renforcement de celle-ci entra\u00eene le d\u00e9veloppement de la pens\u00e9e conceptuelle, la philosophie critique, la cr\u00e9ation. Pour Nicholas Carr, les livres-papier, s&rsquo;ils sont convenablement utilis\u00e9s, que ce soit dans les activit\u00e9s p\u00e9dagogiques ou dans la vie courante, jouent un r\u00f4le essentiel \u00e0 cette fin.<\/p>\n<\/p>\n<p><p>\tAu contraire, Internet favorise et renforce les circuits mentaux qui permettent la collecte multidirectionnelle et rapide d&rsquo;informations, le travail en temps partag\u00e9, la cat\u00e9gorisation sommaire. Ces circuits sont loin d&rsquo;\u00eatre inutiles, mais ils ne doivent pas se d\u00e9velopper au d\u00e9triment de ceux permettant la contemplation et la r\u00e9flexion en profondeur. Il n&rsquo;existe pas encore beaucoup d&rsquo;observations faisant appel \u00e0 l&rsquo;imagerie c\u00e9r\u00e9brale qui permettraient de confirmer ces hypoth\u00e8ses. Mais on commence \u00e0 en trouver. L&rsquo;une d&rsquo;elles, r\u00e9alis\u00e9e \u00e0 l&rsquo;universit\u00e9 de Californie, montrerait les changements dans les processus d&rsquo;activation du cerveau r\u00e9sultant d&rsquo;un usage dit mod\u00e9r\u00e9 des moteurs de recherche. Il n&rsquo;est pas exclu que certains d\u00e9sordres se caract\u00e9risant par le d\u00e9ficit d&rsquo;attention et la suractivit\u00e9 c\u00e9r\u00e9brale puissent en d\u00e9couler, chez l&rsquo;enfant comme chez l&rsquo;adulte. Les \u00e9l\u00e9ments apport\u00e9s sont suffisamment convergents pour nous alerter. Nicholas Carr pour sa part ne nie pas les avantages qu&rsquo;apportent le renouvellement permanent et la diversification des sources d&rsquo;informations r\u00e9sultant de la consultation \u00e0 haute dose de l&rsquo;Internet, mais il craint que ne se perdent en contrepartie les capacit\u00e9s d&rsquo;attention approfondie et de r\u00e9flexion indispensables aux individus et aux soci\u00e9t\u00e9s.<\/p>\n<\/p>\n<p><p>\tNous pourrions personnellement r\u00e9pondre que l&rsquo;Internet permet aussi d&rsquo;acc\u00e9der \u00e0 des contenus de connaissances, livres et articles, qui seraient en pratique hors de port\u00e9e s&rsquo;ils n&rsquo;\u00e9taient pas num\u00e9ris\u00e9s. En ce qui concerne l&rsquo;expression, s&rsquo;il encourage les prises de positions rapides et sommaires qui s&rsquo;\u00e9panouissent sur les blogs interactifs, il n&#8217;emp\u00eache pas les auteurs d\u00e9sireux de r\u00e9flexions plus approfondies de s&rsquo;y exprimer et trouver des audiences qu&rsquo;ils ne pourraient avoir autrement. Il faudrait seulement sans doute, pour que les bons effets du travail en r\u00e9seau se fassent sentir, que les diff\u00e9rents supports et modes d&rsquo;usage des informations ne s&rsquo;excluent pas mais se compl\u00e8tent&#8230;ce qui est encore le cas pour le moment.<\/p>\n<\/p>\n<p><p>\tCe dont par contre il conviendrait de se m\u00e9fier serait la transformation du web tout entier en une sorte d&rsquo;intelligence artificielle globale au service d&rsquo;int\u00e9r\u00eats \u00e9conomiques et politiques voulant imposer aux individus des formes et contenus de pens\u00e9e servant directement leurs objectifs de conqu\u00eate des cerveaux. Certains observateurs du web soup\u00e7onnent \u00e0 cet \u00e9gard Google de jouer d\u00e9j\u00e0 ce r\u00f4le \u00e0 grande \u00e9chelle, sans susciter ni inqui\u00e9tudes ni r\u00e9actions.<\/p>\n<h3>Google<\/h3>\n<\/p>\n<p><p>\tDans l&rsquo;article cit\u00e9 de Nicholas Carr, le lecteur prenant le temps de le lire attentivement verra que l&rsquo;auteur souligne la volont\u00e9 des cr\u00e9ateurs de Google de transformer leur moteur de recherche en une intelligence artificielle qui pourrait \u00eatre connect\u00e9e directement \u00e0 nos cerveaux. Ayant rassembl\u00e9 toutes les informations disponibles, cette IA globale serait capable de r\u00e9pondre imm\u00e9diatement \u00e0 toutes les questions, superficielles ou profondes, que nous nous poserions. Est-ce pour autant que cela nous dispenserait de penser par nous-m\u00eames, afin le cas \u00e9ch\u00e9ant d&rsquo;aller au del\u00e0 de ces r\u00e9ponses afin d&rsquo;envisager des questions suffisamment originales pour ne pas trouver de solutions dans les informations actuellement disponibles? Oui diront les critiques de Google, car le moteur est con\u00e7u (avec les milliers de serveurs interconnect\u00e9s dont il dispose et qu&rsquo;il ne faut jamais oublier) pour enfermer ses utilisateurs dans les produits et services que la soci\u00e9t\u00e9 de consommation met aujourd&rsquo;hui \u00e0 sa disposition, afin de l&rsquo;obliger \u00e0 ne pas chercher ailleurs. C&rsquo;est ce que fait en g\u00e9n\u00e9ral la publicit\u00e9, visant \u00e0 transformer les individus en consommateurs de marques, excluant de leur part toute distanciation critique tant \u00e0 l&rsquo;\u00e9gard de ces marques que de la consommation en g\u00e9n\u00e9ral. Google avec le syst\u00e8me des liens commerciaux qui a fait sa fortune, r\u00e9alise cet enfermement avec une efficacit\u00e9 jamais atteinte jusqu&rsquo;\u00e0 pr\u00e9sent.<\/p>\n<\/p>\n<p><p>\tDans un <a href=\"http:\/\/www.nytimes.com\/2010\/09\/01\/opinion\/01gibson.html?_r=4\" class=\"gen\">article r\u00e9cent du New York Times<\/a>, <a href=\"http:\/\/fr.wikipedia.org\/wiki\/William_Gibson\" class=\"gen\">William Gibson<\/a>, romancier de science fiction, auteur de <em>Neuromancien<\/em> (1984) et d&rsquo;un nouveau roman \u00e0 para\u00eetre, <em>Zero History<\/em>, va plus loin dans l&rsquo;analyse. Il s&rsquo;appuie sur le contenu d&rsquo;une interview de Eric Schmidt, directeur ex\u00e9cutif (CEO) de Google, pour commenter le r\u00f4le qu&rsquo;a pris celui-ci dans nos vies. Pour Gibson, Google est le produit de nos activit\u00e9s, comme un r\u00e9cif de corail l&rsquo;est de l&rsquo;activit\u00e9 des organismes qui le composent. Cela tient au fait que d\u00e9sormais nos faits, gestes et pens\u00e9es sont enregistr\u00e9s par d&rsquo;innombrables capteurs qui nous rep\u00e8rent en permanence dans le temps et dans l&rsquo;espace. Ce n&rsquo;est pas Google qui est responsable de cette organisation sociale envahissante, mais plus g\u00e9n\u00e9ralement la soci\u00e9t\u00e9 technologique dans laquelle nous baignons. Avec les traces qu&rsquo;y laissent nos ordinateurs, t\u00e9l\u00e9phones mobiles et GPS, notre participation aux r\u00e9seaux sociaux ou au sites de rencontre dans lesquels nous nous d\u00e9crivons exhaustivement, nous laissons dor\u00e9navant derri\u00e8re nous de quoi construire des portraits de plus en plus r\u00e9v\u00e9lateurs.&#8232;Cependant Google a su, mieux que tous ses concurrents, faire de nous les collaborateurs directs de sa d\u00e9marche commerciale, en recueillant, agr\u00e9geant et et tirant parti de toutes ces traces, au lieu de les laisser se perdre dans l&rsquo;anonymat de l&rsquo;Internet. Ainsi il nous r\u00e9v\u00e8le \u00e0 nous-m\u00eames en permanence ce que nous d\u00e9sirons vraiment, sans parfois oser nous l&rsquo;avouer. Il nous conseille ensuite, gr\u00e2ce notamment aux liens promotionnels \u00e9voqu\u00e9s ci-dessus, liens que l&rsquo;on retrouve d\u00e9sormais sur pratiquement tous les sites Web, les meilleurs produits, activit\u00e9s et comportements susceptibles de satisfaire ces d\u00e9sirs.<\/p>\n<\/p>\n<p><p>\tCeci ne se limite pas \u00e0 proposer des adresses de restaurants ou de mus\u00e9es, non plus que les r\u00e9f\u00e9rences de sites pornographiques. De plus en plus, notamment par la connaissance qu&rsquo;il a de nos lectures, \u00e9changes, \u00e9crits, Google nous indique ce que nous devons penser et les formes par lesquelles cette pens\u00e9e pourra le mieux se manifester. En d&rsquo;autres termes, nous sommes les contributeurs non r\u00e9mun\u00e9r\u00e9s non seulement de la fortune que Google amasse gr\u00e2ce \u00e0 notre bonne volont\u00e9, mais de toutes les entreprises commerciales ou politiques qui vivent de notre impuissance \u00e0 se passer d&rsquo;elles pour satisfaire nos aspirations. Nous sommes pris dans un cercle ferm\u00e9.<\/p>\n<\/p>\n<p><p>\tOn dira que la chose n&rsquo;est pas nouvelle. Depuis toujours, l&rsquo;individu a \u00e9t\u00e9 enserr\u00e9 dans le r\u00e9seau des influences qui structurent la soci\u00e9t\u00e9, celles du pouvoir, des entreprises, des id\u00e9ologies. Si j&rsquo;\u00e9prouve des angoisses existentielles et si je suis \u00e0 la recherche de r\u00e9ponses, ce ne sera pas en moi que je les trouverai mais dans toutes les ressources qui m&rsquo;entourent, qu&rsquo;elles soient fournies par les \u00e9glises, les biblioth\u00e8ques, les grands ou petits penseurs. Ma seule libert\u00e9, \u00e0 supposer que je puisse l&rsquo;exercer, sera de choisir les r\u00e9ponses les plus appropri\u00e9es \u00e0 mes inqui\u00e9tudes du moment. Mais je n&rsquo;aurai que tr\u00e8s rarement la possibilit\u00e9 de b\u00e2tir \u00e0 moi tout seul des philosophies et syst\u00e8mes du monde capables d&rsquo;\u00e9chapper vraiment \u00e0 toutes ces influences. Cette contrainte s&rsquo;impose \u00e0 tous, y compris aux chercheurs scientifiques et aux cr\u00e9ateurs artistiques qui se croient pouss\u00e9s par une pulsion v\u00e9ritablement originale. Google ne change rien \u00e0 cela. Il ouvre au contraire, peut-on croire, le champ des possibles, sans rien imposer de pr\u00e9cis ou d\u00e9finitif. Rien ne m&rsquo;oblige \u00e0 suivre les conseils obligeamment dispens\u00e9s par Google, que ce soit pour trouver un restaurant, un livre ou un(e) partenaire. Beaucoup de gens fuient syst\u00e9matiquement les placards publicitaires sur les pages qu&rsquo;ils consultent.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est l\u00e0 cependant que William Gibson demande que l&rsquo;on y regarde \u00e0 deux fois. Pour lui, au contraire, Google ne laisse pas le choix. Il para\u00eet vous conna\u00eetre si bien que vous vous ralliez \u00e0 ses injonctions. Elles vous semblent inspir\u00e9es par les meilleurs intentions \u00e0 votre \u00e9gard. Vous y retrouvez l&rsquo;essentiel de vous-m\u00eames. Pourquoi s&rsquo;en d\u00e9fier? Google est comme un parent bienveillant. Ses conseils doivent \u00eatre suivis parce qu&rsquo;ils correspondent \u00e0 vos besoins profonds: Je suis ta maman qui t&rsquo;aime. Je te connais mieux que tu ne te connais toi-m\u00eame. Fais ce que ta maman te dit de faire. Pour Gibson, Google est plus encore. C&rsquo;est votre propre bon g\u00e9nie, presque votre ange gardien, votre vrai Moi. Mais sa bienveillance affich\u00e9e vous cache le fait que ce sont finalement vos propres faiblesses, vos propres d\u00e9mons que vous retrouvez (\u00e0 vos frais, ne l&rsquo;oubliez pas) dans les conseils de Google, sans espoir de voir jamais s&rsquo;entrouvrir une fen\u00eatre sur un monde vraiment ext\u00e9rieur \u00e0 l&rsquo;enfer de votre Moi.<\/p>\n<\/p>\n<p><p>\tDans le <a href=\"http:\/\/online.wsj.com\/article\/SB10001424052748704901104575423294099527212.html\" class=\"gen\">Wall Street Journal, Holman Jenkins Jr<\/a>, responsable de la chronique hebdomadaire Business World, propose un diagnostic tr\u00e8s voisin, bien qu&rsquo;il ne s&rsquo;aventure pas comme Gibson aux confins de la psychologie des profondeurs. Ni Holman Jenkins ni le Wall Street Journal ne sont de dangereux agitateurs gauchistes. Ils ont certes quelques raisons de redouter la concurrence de Google, dont l&rsquo;ambition non dissimul\u00e9e est de rendre tous les journaux classiques inutiles et de transformer toutes les entreprises industrielles et commerciales en acheteurs de liens publicitaires, retirant ainsi aux journaux-papier leur manne traditionnelle. Cependant la critique port\u00e9e par Jenkins va au del\u00e0 de l&rsquo;auto-d\u00e9fense et m\u00e9rite r\u00e9flexion, d&rsquo;autant plus qu&rsquo;elle conforte les inqui\u00e9tudes de Nicholas Carr.<\/p>\n<\/p>\n<p><p>\tSelon Jenkins, apr\u00e8s quelques mois difficiles, Google b\u00e9n\u00e9ficie aujourd&rsquo;hui d&rsquo;un renouveau de croissance. Il multiplie les produits exploitant son nom et ses r\u00e9f\u00e9rences: le smartphone Andro\u00efd par exemple dont 100.000 exemplaire seraient mis en service chaque jour, d\u00e9passant largement l&rsquo;iPhone de Apple. Android est distribu\u00e9 pour presque rien mais Google se rattrape sur les multiples usages et services que permet cette nouvelle plateforme. Par ailleurs, avec le navigateur et l&rsquo;OS Chrome, Google esp\u00e8re \u00e9branler la domination de Microsoft dans les syst\u00e8mes d&rsquo;exploitation. Plus g\u00e9n\u00e9ralement, selon les propos de Eric Schmidt lui-m\u00eame, que Holman Jenkins commente \u00e0 son tour, Google veut, apr\u00e8s avoir maitris\u00e9 la vague porteuse des moteurs de recherche, maitriser la vague des mobiles connect\u00e9s \u00e0 Internet et aux moteurs. Il esp\u00e8re pouvoir produire et distribuer l&rsquo;essentiel de ces mobiles, \u00e9tendant ainsi la <em>googolisation<\/em> de la soci\u00e9t\u00e9.<\/p>\n<\/p>\n<p><p>\tJenkins voit ainsi venir un monde o\u00f9 chaque lieu, chaque objet disposera d&rsquo;un petit terminal qui lui permettra de dialoguer avec le citoyen de base, lui-m\u00eame en permanence branch\u00e9 sur Google. \u00ab<em>Google ne se bornera plus \u00e0 r\u00e9pondre aux questions des utilisateurs, il ne leur demandera m\u00eame plus ce qu&rsquo;ils veulent faire, il leur dictera ce qu&rsquo;ils doivent faire<\/em>\u00bb. Pour cela, il devra entrer dans les consciences pour en d\u00e9crypter les d\u00e9sirs. On passera de la recherche syntaxique \u00e0 la recherche s\u00e9mantique, autrement dit, \u00e0 la recherche des contenus de connaissance susceptibles de r\u00e9pondre aux exigences les plus secr\u00e8tes des croyances et des pens\u00e9es individuelles. L&rsquo;outil en sera plus que jamais la publicit\u00e9 cibl\u00e9e (<em>targeted advertising<\/em>) qui va la source des tendances et d\u00e9sirs tels que chacun les r\u00e9v\u00e8le par les traces qu&rsquo;il laisse en permanence dans le monde dit aussi de l&rsquo;Internet des objets, qui sera domin\u00e9 par Google, \u00e9videmment.<\/p>\n<\/p>\n<p><p>\tHolman Jenkins ne pense pas que cette ambition de Google, exprim\u00e9e si clairement par son CEO, puisse aboutir \u00e0 l&rsquo;\u00e9chelle esp\u00e9r\u00e9e. Les journaux-papier, les autres acteurs du web et des technologies de l&rsquo;information, vont r\u00e9agir. Les citoyens, les institutions vont s&rsquo;inqui\u00e9ter et fixer des limites. Mais pour Jenkins comme pour Gibson et Carr, Google pr\u00e9figure de toutes fa\u00e7on un monde global qui se met en place  qui est d\u00e9j\u00e0 en place  et sur lequel il serait bon que davantage de bons esprits s&rsquo;interrogent. <\/p>\n<\/p>\n<p><p>\tOn remarquera aussi que les trois auteurs ici cit\u00e9s ne mentionnent pas les liens qui peuvent s&rsquo;\u00e9tablir entre un moteur de recherche dominant tel Google et les Agences de renseignement (CIA, NSA, etc. pour ce qui concerne les Etats-Unis). Ces agences ont leur propres r\u00e9seaux s\u00e9curis\u00e9s, tel Echelon, qui collationnent tout ce qui s&rsquo;\u00e9change dans le monde num\u00e9rique. Cependant elles tirent le plus grand profit \u00e0 consulter les moteurs de recherche, qui font pour elles une partie du travail. Elles peuvent aussi dans certains cas contribuer \u00e0 cr\u00e9er des tendances. On a vu r\u00e9cemment comment en France un mouvement politique a rachet\u00e9 \u00e0 Google divers termes associ\u00e9s \u00e0 ce groupe, afin de conduire l&rsquo;utilisateur sur des sites vantant les m\u00e9rites de ce mouvement. La d\u00e9marche est rest\u00e9e marginale, mais elleest r\u00e9v\u00e9latrice d&rsquo;une d\u00e9rive possible. <\/p>\n<\/p>\n<p><p>\tAjoutons que le salut ne viendra pas de la Chine ou d&rsquo;autres r\u00e9gimes autoritaires qui voudraient comme la Chine fermer leurs portes \u00e0 Google. Ces r\u00e9gimes mettront en place des variantes nationales de Google qui seront encore plus convaincantes, aux yeux des usagers locaux, que ne l&rsquo;est celui-ci. Elles mobiliseront sans h\u00e9siter pour conqu\u00e9rir les esprits toutes les ressources du nationalisme et de la religion. Ainsi se construisent les grands consensus.<\/p>\n<\/p>\n<p><p>\tPour nous, en tous cas, le syst\u00e8me Google illustre parfaitement une des formes les plus insidieuses et envahissantes que peuvent prendre les organismes anthropotechniques auxquels nous faisions allusion au d\u00e9but de cet article. (2)<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Jean-Paul Baquiast<\/p>\n<\/p>\n<h4>Notes<\/h4>\n<p>(1) Cet article a \u00e9t\u00e9 traduit et discut\u00e9 en 2009 par le site Internet actu o\u00f9 nous conseillons de l&rsquo;\u00e9tudier attentivement. (<a href=\"http:\/\/www.internetactu.net\/2009\/01\/23\/nicolas-carr-est-ce-que-google-nous-rend-idiot\/\" class=\"gen\">http:\/\/www.internetactu.net\/2009\/01\/23\/nicolas-carr-est-ce-que-google-nous-rend-idiot\/<\/a>.)<\/p>\n<\/p>\n<p><p>\t2) Voir aussi sur l&rsquo;univers tel que simul\u00e9 par Google. (<a href=\"http:\/\/www.readwriteweb.com\/archives\/google_shows_off_chrome_html5_with_interactive_mus.php\" class=\"gen\">http:\/\/www.readwriteweb.com\/archives\/google_shows_off_chrome_html5_with_interactive_mus.php<\/a>.)<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Internet et\/ou Google rec\u00e2blent-t-ils nos cerveaux? Les technologies de communication touchent d\u00e9sormais pratiquement l&rsquo;ensemble des humains. L&rsquo;une de celle qui, sans \u00eatre aussi universelle que le t\u00e9l\u00e9phone mobile, attire de plus en plus l&rsquo;int\u00e9r\u00eat des chercheurs par son caract\u00e8re structurant, est l&rsquo;Internet. Nous avons dans notre essai Le paradoxe du Sapiens, fait l&rsquo;hypoth\u00e8se que les&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[7895,10092,5378,10091,60,6672,3865],"class_list":["post-72314","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-baquiast","tag-carr","tag-gibson","tag-google","tag-internet","tag-nicolas","tag-william"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72314","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72314"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72314\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}