{"id":72332,"date":"2010-10-01T19:59:16","date_gmt":"2010-10-01T19:59:16","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/10\/01\/le-bon-dieu-is-in-the-details\/"},"modified":"2010-10-01T19:59:16","modified_gmt":"2010-10-01T19:59:16","slug":"le-bon-dieu-is-in-the-details","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/10\/01\/le-bon-dieu-is-in-the-details\/","title":{"rendered":"Le Bon Dieu <em>is in the details<\/em>"},"content":{"rendered":"<p><p>Il \u00e9tait donc in\u00e9vitable que l&rsquo;on en parl\u00e2t, sinon qu&rsquo;on l&rsquo;envisage\u00e2t : un certain partage nucl\u00e9aire franco-britannique, au niveau des patrouilles des SNLE (ou SSBN),  les sous-marins lanceurs d&rsquo;engins strat\u00e9giques \u00e0 t\u00eates nucl\u00e9aires. Les Britanniques en ont quatre, avec des engins <em>Trident<\/em> (US), les Fran\u00e7ais en ont quatre \u00e9galement, enti\u00e8rement de leur fait. Ce sont John Lichfield \u00e0 Paris et Kim Sengupta \u00e0 Londres, qui publient un article sur ce th\u00e8me dans <em>The Independent<\/em> du <a href=\"http:\/\/www.independent.co.uk\/news\/world\/politics\/britain-and-france-may-share-nuclear-deterrent-2093539.html\" class=\"gen\">30 septembre 2010<\/a>. Les deux journalistes, surtout Sengupta, sont en g\u00e9n\u00e9ral tr\u00e8s bien inform\u00e9s.<\/p>\n<\/p>\n<p><p>\tLe texte affirme que des discussions pr\u00e9liminaires sont en cours et que le sujet sera abord\u00e9 entre Sarkozy et Cameron au prochain sommet France-UK, en novembre. Bien entendu, tout cela concerne d&rsquo;abord les consid\u00e9rables r\u00e9ductions qui touchent les budgets de la d\u00e9fense des deux pays, particuli\u00e8rement le Royaume-Uni. L&rsquo;id\u00e9e serait notamment que, dans certaines circonstances o\u00f9 un seul SNLE (fran\u00e7ais ou britanniques) serait en station \u00e9loign\u00e9e des deux pays, parce qu&rsquo;aucun autre ne serait disponible, ce navire assurerait la dissuasion pour les deux pays. L&rsquo;article signale notamment ceci :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The idea is believed to have been discussed by Mr Brown and Mr Sarkozy in March this year and ultimately sunk by Mr Brown as politically unfeasible in an election year. Similar discussions on Anglo-French nuclear co-operation are believed to have occurred in the past, going back to the Edward Heath government in the early 1970s.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Officials in Paris say that new impetus has been given to the idea by the huge budget deficits, and swingeing defence spending cuts, faced by both nations. Other ideas for military pooling said to be under discussion before the Franco-British summit include a revised version of a recently rejected proposal for a shared use of aircraft carriers and a joint programme for building a new generation of frigates.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Discussions in the past have been hampered by mutual suspicion and fear of negative domestic political and media reactions. The French did not like America&rsquo;s control over the supposedly independent UK nuclear deterrent. Britain suspected France of wanting to create a European defence policy to undermine Nato. These doubts have now been eased, on both sides of the Channel (and the Atlantic), by President Sarkozy&rsquo;s decision to return France to the joint military command of the Atlantic alliance. Politically, however, it is accepted that the idea might still be difficult to swallow in both countries.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Could France be relied upon to retaliate against an attack on the UK, if that might then mean nuclear retaliation against France? And vice versa.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Officials draw attention, however, to an interesting but little-reported comment by President Sarkozy in a speech in Cherbourg in March 2008, just after talks with Mr Brown. Together with the United Kingdom, he said, we have taken a major decision: it is our assessment that there can be no situation in which the vital interests of either of our two nations could be threatened without the vital interests of the other also being threatened.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDans le m\u00eame <em>Independent<\/em> du <a href=\"http:\/\/www.independent.co.uk\/opinion\/commentators\/tom-peck-why-sharing-with-the-french-would-present-a-number-of-problems-2093541.html\" class=\"gen\">30 septembre 2010<\/a>, Tom Peck fait un commentaire s&rsquo;attachant aux consid\u00e9rables difficult\u00e9s d&rsquo;un tel projet. Il s&rsquo;agit des questions essentiellement politiques, concernant la souverainet\u00e9 nationale en g\u00e9n\u00e9ral, la souverainet\u00e9 nationale tr\u00e8s particuli\u00e8re (authentifi\u00e9e US) des Britanniques, etc. La fin de l&rsquo;extrait ci-dessous est \u00e9galement croustillante, qui r\u00e9v\u00e8le les consignes ultimes d&rsquo;un commandant d&rsquo;un SSBN britannique en cas d&rsquo;affrontement nucl\u00e9aire, du temps de la Guerre froide,  rappelant un peu un capitaine Folamour sous-marinier.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Sharing the system with the French would present a number of problems. Both countries see their independent nuclear deterrent as an important component of national sovereignty, said Malcolm Chalmers, a professorial fellow in British Security Policy at the Royal United Services Institute and an expert in international burden sharing.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Then there&rsquo;s the special relationship. Britain and the US co-operate on several different components of the programme, including warheads and missiles, with a close exchange of information  much closer than either country has with France. If the arrangement were to trespass into areas in which we already co-operate with the US, we would have to have their permission. All these situations are extremely hypothetical, but what if the US and the UK, or even the US and France for that matter, were to engage bilaterally in a war with a nuclear power, and that power were to attack France or the UK while the other&rsquo;s submarine was on patrol. Would the other retaliate on their behalf?<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>During the long years of the Cold War, the prime ministerial letter was believed to have given the commanders four choices: put yourself under US command, if it still exists; go to Australia, if it is still there; fire your nuclear missiles at the enemy; and, finally, use your own judgement.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Les Anglais disent <em>The devil is in the details<\/em>, les Fran\u00e7ais Le Bon Dieu est dans les d\u00e9tails,  au choix. Mais il faut convenir que ces d\u00e9tails ne sont pas rien, et l&rsquo;id\u00e9e du partage des patrouilles de SNLE semble \u00eatre la plus complexe qu&rsquo;on puisse imaginer, sur la mati\u00e8re la plus sensible qu&rsquo;on puisse imaginer, dans la situation politique la plus d\u00e9licate qu&rsquo;on puisse imaginer. Les liens existant entre les USA et UK dans ce domaine, la position d&rsquo;ind\u00e9pendance nationale de la France d&rsquo;autre part, constituent des obstacles si redoutables qu&rsquo;on croirait qu&rsquo;on a effectivement choisi la voie la plus encombr\u00e9e d&rsquo;obstacles pour l&rsquo;id\u00e9e d&rsquo;une coop\u00e9ration France-UK marquante et exceptionnelle Mais l&rsquo;id\u00e9e, justement, est d&rsquo;abord un pur produit de n\u00e9cessit\u00e9s extrapolitiques et extramilitaire, c&rsquo;est-\u00e0-dire de n\u00e9cessit\u00e9s budg\u00e9taires ; et c&rsquo;est bien la logique des urgences budg\u00e9taires qui conduit \u00e0 un projet de coop\u00e9ration militaire dans son aspect le plus inextricable en l&rsquo;absence d&rsquo;une volont\u00e9 politique structurante fondamentale. En d&rsquo;autres mots, un tel projet n\u00e9cessiterait des d\u00e9cisions politiques radicales, de l&rsquo;un ou l&rsquo;autre pays, avant qu&rsquo;il soit envisag\u00e9,  et encore, si de telles d\u00e9cisions sont possibles. (Il suffit de songer au contr\u00f4le absolu des USA sur les t\u00eates nucl\u00e9aires britanniques ; ce pourquoi, \u00e0 notre sens, un tel projet de coop\u00e9ration nucl\u00e9aire franco-britannique n&rsquo;aurait de chance v\u00e9ritable d&rsquo;aboutir que si les Britanniques prenaient d&rsquo;abord la d\u00e9cision de ne plus d\u00e9pendre des syst\u00e8mes US, et donc du contr\u00f4le US, pour une coop\u00e9ration avec la France au niveau de la production de nouveaux syst\u00e8mes nucl\u00e9aires qui seraient alors le produit d&rsquo;une coop\u00e9ration France-UK.) Mais il s&rsquo;agit, l\u00e0 encore, de l&rsquo;urgence de la tr\u00e9sorerie, ou, dans tous les cas, d&rsquo;une situation pr\u00e9sent\u00e9e comme telle.<\/p>\n<\/p>\n<p><p>\tIl est par cons\u00e9quent plus judicieux d&rsquo;aborder le sujet par un autre biais, qui concerne essentiellement le Royaume-Uni. On sait que des tensions sont r\u00e9cemment apparues, \u00e0 propos de la force nucl\u00e9aire UK sous chaperonnage US, d&rsquo;une part entre <a href=\"http:\/\/www.dedefensa.org\/article-menace_discrete_mais_sans_vergogne_15_09_2010.html\" class=\"gen\">Londres et Washington<\/a>, d&rsquo;autre part entre <a href=\"http:\/\/www.dedefensa.org\/article-la_crise_budgetaire_londres-washington__27_09_2010.html\" class=\"gen\">conservateurs et conservateurs<\/a> \u00e0 Londres. Une lettre du ministre de la d\u00e9fense Liam Fox au Premier ministre Cameron, obtenue par le <em>Telegraph<\/em>, a officialis\u00e9 la tension entre les conservateurs pro-US comme Fox et ceux qui ont d&rsquo;autres pr\u00e9occupations, comme Cameron,  tension bien r\u00e9elle malgr\u00e9 la mise au point rassurante de Cameron (voir le <em>Guardian<\/em> du <a href=\"http:\/\/www.guardian.co.uk\/politics\/2010\/sep\/30\/cameron-dismisses-fears-over-defence-cuts\" class=\"gen\">30 septembre 2010<\/a>). Ces p\u00e9rip\u00e9ties ont montr\u00e9 l&rsquo;extraordinaire sensibilit\u00e9 du Pentagone \u00e0 la question du nucl\u00e9aire britannique et, par voie de cons\u00e9quence, l&rsquo;extraordinaire sensibilit\u00e9 des Britanniques pro-US \u00e0 la m\u00eame question. C&rsquo;est d&rsquo;abord dans ce contexte, nous semble-t-il, qu&rsquo;il faut consid\u00e9rer les bruits de patrouilles communes franco-britannique.<\/p>\n<\/p>\n<p><p>\tQuelles que soient les difficult\u00e9s innombrables qui sont \u00e9voqu\u00e9es entre Fran\u00e7ais et Britanniques, y compris, pour les Fran\u00e7ais, l&rsquo;\u00e9ventuelle pr\u00e9occupation (si la chose, nous voulons dire ce sentiment-l\u00e0, existe encore dans Sarko<em>land<\/em>) de coop\u00e9rer avec un pays si compl\u00e8tement sous contr\u00f4le US, dans un tel domaine sp\u00e9cifiquement,  la plus grande de toutes les difficult\u00e9s se trouve sans aucun doute \u00e0 Washington, au Pentagone. Pour les USA, une coop\u00e9ration britannique avec les Fran\u00e7ais dans le domaine absolument sacro-saint du nucl\u00e9aire est compl\u00e8tement impensable, quelles que soient les \u00e9ventuelles paroles diplomatiques arrangeantes qui sont \u00e9chang\u00e9es, et cela aussi bien techniquement que politiquement, notamment parce que les <em>Trident<\/em> sont effectivement des syst\u00e8mes US sous contr\u00f4le US, avec des t\u00eates nucl\u00e9aires effectivement sous contr\u00f4le US.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est pourquoi les hypoth\u00e8ses franco-britanniques ont d&rsquo;abord un int\u00e9r\u00eat politique, et ont et auront des effets politiques, principalement entre USA et UK, et \u00e0 l&rsquo;int\u00e9rieur du parti conservateur britannique o\u00f9 les tensions sont consid\u00e9rables. (On sait que Fox, l&rsquo;homme du parti atlantiste et pro-US, met implicitement sa d\u00e9mission dans la balance, dans le cas de la force nucl\u00e9aire et de son retard de modernisation.) Notre hypoth\u00e8se est que le Pentagone n&rsquo;acceptera jamais de plein gr\u00e9, \u00e0 son insu ou pas, une solution franco-britannique avec des syst\u00e8mes strat\u00e9giques nucl\u00e9aires qu&rsquo;il contr\u00f4le lui-m\u00eame, ayant pour la France,  quelle que soit sa politique, son pr\u00e9sident, ses ors et ses coutumes,  une m\u00e9fiance atavique sans retour. La poursuite de cette hypoth\u00e8se est que l&rsquo;\u00e9vocation de discussions entre Fran\u00e7ais et Britanniques au sujet de patrouilles nucl\u00e9aires communes va d&rsquo;abord avoir comme effet de consid\u00e9rablement renforcer la tension entre Londres et le Pentagone (et \u00e0 l&rsquo;int\u00e9rieur du parti conservateur, en bonne logique). Comme cet ensemble d&rsquo;\u00e9v\u00e9nements d\u00e9pend essentiellement de questions budg\u00e9taires pressantes du c\u00f4t\u00e9 britannique, devant des perspectives sans grand espoir d&rsquo;am\u00e9lioration, la situation appara\u00eet singuli\u00e8rement d\u00e9licate. Dans l&rsquo;imm\u00e9diat, elle l&rsquo;est plus, \u00e0 notre sens, pour les relations USA-UK que pour des relations o\u00f9 la France elle-m\u00eame serait impliqu\u00e9e. Pour la suite, on verra.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 1er octobre 2010 \u00e0 19H48<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il \u00e9tait donc in\u00e9vitable que l&rsquo;on en parl\u00e2t, sinon qu&rsquo;on l&rsquo;envisage\u00e2t : un certain partage nucl\u00e9aire franco-britannique, au niveau des patrouilles des SNLE (ou SSBN), les sous-marins lanceurs d&rsquo;engins strat\u00e9giques \u00e0 t\u00eates nucl\u00e9aires. Les Britanniques en ont quatre, avec des engins Trident (US), les Fran\u00e7ais en ont quatre \u00e9galement, enti\u00e8rement de leur fait. Ce sont&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[5224,3435,2929,3288,2687,8599,3004,10115,3575,10116,10118,4775],"class_list":["post-72332","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-communes","tag-cooperation","tag-dissuasion","tag-fox","tag-france","tag-liam","tag-nucleaire","tag-patrouilles","tag-royaume-uni","tag-snle","tag-ssbn","tag-trident"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72332","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72332"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72332\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72332"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72332"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72332"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}