{"id":72358,"date":"2010-10-11T06:24:02","date_gmt":"2010-10-11T06:24:02","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/10\/11\/la-nouvelle-bd-du-jsf\/"},"modified":"2010-10-11T06:24:02","modified_gmt":"2010-10-11T06:24:02","slug":"la-nouvelle-bd-du-jsf","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/10\/11\/la-nouvelle-bd-du-jsf\/","title":{"rendered":"La nouvelle BD du JSF"},"content":{"rendered":"<p><p>Aujourd&rsquo;hui, inutile que le meilleur avion de combat du monde existe pour qu&rsquo;il accomplisse sa t\u00e2che grandiose de meilleur avion de combat du monde. Bien entendu, il s&rsquo;agit de l&rsquo;ineffable JSF. Voici donc la nouvelle <em>narrative<\/em>, apr\u00e8s que les Isra\u00e9liens aient sign\u00e9 un contrat pour 20 JSF, pour $3,5 milliards. (Bon, tout cela, des chiffres de bande dessin\u00e9e ; nous ferons les comptes entre 2015 et 2020, si nous existons encore.)<\/p>\n<\/p>\n<p><p>\tDe nombreuses et avis\u00e9es r\u00e9actions \u00e0 ce contrat du si\u00e8cle (20 JSF vendus \u00e0 Isra\u00ebl qui paiera avec l&rsquo;argent de l&rsquo;aide am\u00e9ricaniste \u00e0 Isra\u00ebl, sur les 6.000 exemplaires de vente du JSF op\u00e9rationnels, pr\u00e9sent\u00e9s comme assur\u00e9s en 1998, 2002, 2005, etc.  n&rsquo;en reste plus que 5.980) Nous en choisissons deux.<\/p>\n<\/p>\n<p><p>\t Le <a href=\" http:\/\/www.upi.com\/Business_News\/Security-Industry\/2010\/10\/08\/Israel-buys-F-35-jets-with-eyes-on-Iran\/UPI-30461286554068\/\" class=\"gen\">8 octobre 2010<\/a>, UPI consacre une longue d\u00e9p\u00eache \u00e0 ce contrat, sous le titre plein de sous-entendus (suivons mon regard) : \u00ab<em>Israel buys F-35 jets with eyes on Iran<\/em>\u00bb. On a compris le th\u00e8me, qui est d\u00e9velopp\u00e9 de long en large, avec la description des capacit\u00e9s magiques de cet avion dont les performances vont au-del\u00e0, tr\u00e8s loin dans le temps, de toutes les bandes dessin\u00e9es imaginables Tout de m\u00eame, un court paragraphe, commen\u00e7ant par <em>However<\/em> (toutefois ou n\u00e9anmoins en fran\u00e7ais,  et nous pr\u00e9f\u00e9rons nez en moins) : \u00ab<em>However, Israel is unlikely to take delivery of the first of the fifth- generation fighters until 2015 at the earliest, with completion scheduled for 2017.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Un articulet du Jerusalem <em>Post<\/em> du 10 octobre 2010, rapportant les alarmes des Syriens devant ce contrat qui fait, selon la BD, basculer l&rsquo;\u00e9quilibre des forces au Moyen-Orient<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Syrian Foreign Minister Walid Moallem claimed on Saturday that Israel&rsquo;s recent $3 billion deal to purchase F35 stealth fighter jets from the US poses a serious security threat to the entire Middle East.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>We were told Prime Minister Binyamin Netanyahu is set to announce a settlement construction freeze for an additional two months in exchange for a guarantee that the issue will not come up again and advanced weapons. Now the issue is not the settlement freeze, but the threat on the region&rsquo;s Arab countries, Moallem said Saturday.<\/em>\u00bb<\/p>\n<h4>Notre commentaire<\/h4>\n<p> Du temps b\u00e9ni de la Guerre froide, o\u00f9 l&rsquo;on parlait encore d&rsquo;une quincaillerie existante et o\u00f9 la propagande n&rsquo;avait pas encore achev\u00e9 sa mue immanente en virtualisme, il \u00e9tait de coutume d&rsquo;observer que tout article de la <em>Pravda<\/em> d\u00e9livrait son v\u00e9ritable message au quatri\u00e8me paragraphe. Les trois premiers constituaient l&rsquo;habituelle glose propagandiste sur la ligne du Parti et l&rsquo;univers hallucin\u00e9 mais fort peu exaltant du marxisme-l\u00e9ninisme, et les initi\u00e9s passaient directement au quatri\u00e8me qui d\u00e9taillait la consigne s\u00e9rieuse ou l&rsquo;information importante du texte. Dans la d\u00e9p\u00eache UPI, ce paragraphe est le troisi\u00e8me (\u00ab<em>However, Israel is unlikely to take delivery of the first of the fifth- generation fighters until 2015 at the earliest, with completion scheduled for 2017<\/em>\u00bb). En effet, articuler toute l&rsquo;analyse sur la puissance exceptionnelle du JSF pour une attaque contre l&rsquo;Iran qu&rsquo;on pr\u00e9voit n\u00e9cessairement pour demain matin puisque la bombe iranienne n&rsquo;est en g\u00e9n\u00e9ral qu&rsquo;une question de semaines, et annoncer que l&rsquo;avion ne sera op\u00e9rationnel qu&rsquo;en 2017 (ce qui est une perspective <strong>tr\u00e8s<\/strong> optimiste puisque certains, comme les Norv\u00e9giens, tablent sur 2021), voil\u00e0 qui fait du troisi\u00e8me paragraphe l&rsquo;information principale. Jugera-t-on qu&rsquo;il y a progr\u00e8s d\u00e9cisif par rapport \u00e0 la propagande sovi\u00e9tique ou que le virtualisme est plus sophistiqu\u00e9 et d&rsquo;une substance diff\u00e9rente de la propagande ? Quoi qu&rsquo;il en soit, il est assur\u00e9 que nous sommes entr\u00e9s dans un nouvel \u00e9pisode de la <em>narrative<\/em> du JSF, qui est son entr\u00e9e dans la politique active, sulfureuse, volatile et elle-m\u00eame infiniment virtualiste du Moyen-Orient.<\/p>\n<\/p>\n<p><p>\tLa pr\u00e9sentation de cette vente \u00e0 Isra\u00ebl rel\u00e8ve effectivement d&rsquo;une nouvelle bande dessin\u00e9e racontant la <em>narrative<\/em> g\u00e9n\u00e9rale du JSF. L&rsquo;histoire complexe et tortueuse de la vente du JSF \u00e0 Isra\u00ebl n&rsquo;a, comme on le sait, <strong>rien<\/strong> \u00e0 voir avec l&rsquo;Iran, avec les autres pays arabes, avec la tension au Moyen-Orient, avec les projets \u00e9videmment imminents d&rsquo;attaque d&rsquo;Isra\u00ebl et ainsi de suite. Il s&rsquo;agit pour ce programme aux abois (le JSF) d&rsquo;obtenir un premier client qu&rsquo;on voudrait de r\u00e9f\u00e9rence, et il y a eu trois ans de n\u00e9gociations avant que le Pentagone n&rsquo;arrive \u00e0 imposer cette commande \u00e0 Isra\u00ebl. Il est de notori\u00e9t\u00e9 journalistique de base que l&rsquo;immense majorit\u00e9 du minist\u00e8re de la d\u00e9fense isra\u00e9lien de la d\u00e9fense est oppos\u00e9 \u00e0 cette commande extr\u00eamement co\u00fbteuse, qui lui a \u00e9t\u00e9 impos\u00e9e par le ministre et la direction politique isra\u00e9lienne, lesquels doivent jouer un jeu de mesures agressives dont Washington ne veut pas, et de mesures de concession vis-\u00e0-vis de Washington (l&rsquo;achat du JSF faisant partie de ces derni\u00e8res). La direction isra\u00e9lienne a conclu qu&rsquo;elle ne pouvait \u00e9viter une commande du JSF, \u00e0 cause des pressions du Pentagone, et elle a choisi cette p\u00e9riode o\u00f9 certaines arrangements plus favorables de d\u00e9tail \u00e9taient possibles parce qu&rsquo;Obama a besoin du soutien d&rsquo;Isra\u00ebl (\u00e9lectorat juif) avant les \u00e9lections du 2 novembre. Du coup, tout le monde s&rsquo;entend pour politiser le JSF ; les USA pour montrer qu&rsquo;ils soutiennent Isra\u00ebl (\u00e9lections) ; Isra\u00ebl pour concr\u00e9tiser sa menace contre l&rsquo;Iran ; les pays arabes, notamment les plus radicaux, pour d\u00e9noncer le surarmement d&rsquo;Isra\u00ebl. Rien de tout cela n&rsquo;a le moindre rapport avec la r\u00e9alit\u00e9 puisqu&rsquo;il s&rsquo;agit d&rsquo;une bande dessin\u00e9e et non d&rsquo;un avion, que le JSF n&rsquo;est pas pour demain, que l&rsquo;on ignore ses capacit\u00e9s et que beaucoup doutent avec tant d&rsquo;arguments de la puissance voire de la r\u00e9alit\u00e9 d\u00e9 ces capacit\u00e9s, que m\u00eame la viabilit\u00e9 du programme est r\u00e9guli\u00e8rement mise en question.<\/p>\n<\/p>\n<p><p>\tIl n&rsquo;est pas assur\u00e9 que cette entr\u00e9e dans une nouvelle BD (acteur actif de la politique de tension au Moyen-Orient) renforce r\u00e9ellement le JSF. D&rsquo;une part, elle emprisonne Isra\u00ebl dans une <em>narrative<\/em> du JSF-avion indispensable, alors que l&rsquo;avion est plus que douteux et qu&rsquo;il pompe une partie importante des ressources de d\u00e9fense d&rsquo;Isra\u00ebl (d&rsquo;origine US, certes, mais ressources tout de m\u00eame, qui existaient avant le JSF puisqu&rsquo;elles ont un caract\u00e8re structurel). Elle renforce le caract\u00e8re belliqueux d&rsquo;Isra\u00ebl aux yeux du reste des acteurs sans <strong>rien<\/strong> lui apporter en fait de r\u00e9elles ressources suppl\u00e9mentaires, sinon \u00e9ventuellement du temps de nos petits enfants si le JSF existe d\u00e9j\u00e0. Elle donne bien des arguments aux adversaires d&rsquo;Isra\u00ebl dans la r\u00e9gion, de d\u00e9noncer Isra\u00ebl (et les USA), \u00e9ventuellement de justifier de nouvelles mesures d&rsquo;armement pour eux-m\u00eames sans qu&rsquo;Isra\u00ebl (et les USA) soient en bonne position pour les d\u00e9noncer. Par exemple, la nouvelle des JSF qui arrivent (au rythme de Godot, mais nul ne s&rsquo;y arr\u00eate) ne va-t-elle pas renforcer la position de ceux, tr\u00e8s nombreux, qui, \u00e0 Moscou, critiquent la d\u00e9cision de la direction russe d&rsquo;annuler la livraison de missiles de d\u00e9fense sol-air S-300 \u00e0 l&rsquo;Iran au nom d&rsquo;une solidarit\u00e9 avec l&rsquo;Occident pour les sanctions ? &#8230; Alors que cette solidarit\u00e9 se marque, du c\u00f4t\u00e9 US, par un tel renforcement de la puissance militaire offensive d&rsquo;Isra\u00ebl ? D&rsquo;une fa\u00e7on plus g\u00e9n\u00e9rale, ne renforce-t-on pas ainsi la r\u00e9putation politico-militaire du JSF, ce qui va se traduire en exigences nouvelles sur ses capacit\u00e9s alors que l&rsquo;avion est notoirement en de\u00e7\u00e0 de ses capacit\u00e9s annonc\u00e9es, et sans pour autant renforcer son statut \u00e0 l&rsquo;exportation tant tous les pays d\u00e9j\u00e0 concern\u00e9s par des achats potentiels (comme l&rsquo;\u00e9tait Isra\u00ebl) sont largement avertis de ses innombrables faiblesses ?<\/p>\n<\/p>\n<p><p>\tDe toutes les fa\u00e7ons, dans cet univers cloisonn\u00e9 et <strong>absolument<\/strong> r\u00e9gi par la communication, il para\u00eet impossible de revenir sur cette nouvelle BD du JSF, de faire passer l&rsquo;information que cet avion est loin, tr\u00e8s loin, d&rsquo;\u00eatre le parangon de puissance qu&rsquo;en font les analyses des experts politiques. Le JSF est d\u00e9sormais un formidable outil de puissance, une image effectivement de BD, qui a remplac\u00e9 sa propre r\u00e9alit\u00e9. Est-ce un avantage ?  encore cette question&#8230; On a d\u00e9j\u00e0 vu l&rsquo;avantage de la premi\u00e8re <em>narrative<\/em> d&rsquo;un JSF dominant le XXI\u00e8me si\u00e8cle, \u00e9liminant tous ses concurrents, op\u00e9rationnel d\u00e8s 2008-2009, etc. L&rsquo;in\u00e9vitable retour aux r\u00e9alit\u00e9s se paye cher en termes de r\u00e9putation, de d\u00e9veloppement acc\u00e9l\u00e9r\u00e9 et  b\u00e2cl\u00e9 pour tenter de confirmer la r\u00e9putation, etc. La m\u00eame m\u00e9saventure risque de se reproduire, parce que l&rsquo;avion n&rsquo;existe pas, et que son d\u00e9veloppement r\u00e9el est d\u00e9sormais soumis \u00e0 une autre pression, encore plus d\u00e9formante et exigeante, celle des politiques et de leur agenda sp\u00e9cifique. LM peut se r\u00e9jouir et se convaincre qu&rsquo;ainsi le programme est verrouill\u00e9, et c&rsquo;est vrai pour les trois prochains mois (ce qui correspond \u00e0 la prospective habituelle de LM). En r\u00e9alit\u00e9, avec ce nouveau statut, il va \u00eatre d&rsquo;autant plus surveill\u00e9 dans son d\u00e9veloppement, avec de nouvelles exigences contradictoires (\u00eatre d\u00e9velopp\u00e9 encore plus vite, avoir des capacit\u00e9s encore plus grandes, v\u00e9rifier encore plus pr\u00e9cis\u00e9ment ses capacit\u00e9s,  tout cela, on s&rsquo;en doute, contradictoire et explosif). Le JSF est prisonnier de ses BD successives.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 11 octobre 2010 \u00e0 06H25<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aujourd&rsquo;hui, inutile que le meilleur avion de combat du monde existe pour qu&rsquo;il accomplisse sa t\u00e2che grandiose de meilleur avion de combat du monde. Bien entendu, il s&rsquo;agit de l&rsquo;ineffable JSF. Voici donc la nouvelle narrative, apr\u00e8s que les Isra\u00e9liens aient sign\u00e9 un contrat pour 20 JSF, pour $3,5 milliards. (Bon, tout cela, des chiffres&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3481,3156,4167,3480,4168,2774,250,5637,3747,3867,610],"class_list":["post-72358","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-armements","tag-aux","tag-bande","tag-course","tag-dessinee","tag-israel","tag-jsf","tag-pravda","tag-propagande","tag-syrie","tag-virtualisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72358"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72358\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72358"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72358"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}