{"id":72374,"date":"2010-10-16T06:38:37","date_gmt":"2010-10-16T06:38:37","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/10\/16\/une-campagne-destructurante-en-accord-avec-un-temps-destructure\/"},"modified":"2010-10-16T06:38:37","modified_gmt":"2010-10-16T06:38:37","slug":"une-campagne-destructurante-en-accord-avec-un-temps-destructure","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/10\/16\/une-campagne-destructurante-en-accord-avec-un-temps-destructure\/","title":{"rendered":"Une campagne d\u00e9structurante en accord avec un temps d\u00e9structur\u00e9"},"content":{"rendered":"<p><p>Au moins une <strong>v\u00e9rit\u00e9<\/strong> \u00e9merge de la campagne des <em>mid-terms<\/em> aux USA, deux semaines avant le scrutin du 2 novembre. Cette campagne refl\u00e8te parfaitement, tant du point de vue des \u00e9lecteurs que du point de vue des candidats, que du point de vue des dirigeants (BHO en premier), l&rsquo;\u00e9tat d&rsquo;esprit autant que la situation politique aux USA : confusion, d\u00e9sordre, col\u00e8re, angoisse g\u00e9n\u00e9ralis\u00e9e. On cite ici quelques r\u00e9f\u00e9rences qui illustrent cette observation.<\/p>\n<\/p>\n<p><p>\t La campagne que m\u00e8ne Obama pour soutenir les candidats d\u00e9mocrates est jug\u00e9e comme erratique. <em>Politico.com<\/em> juge cette campagne comme \u00e9tant dans un \u00e9tat similaire \u00e0 celle, d\u00e9sastreuse, de McCain en 2008 (\u00ab<em> Barack Obama in 2010 on the path of John McCain 2008?<\/em>\u00bb, le <a href=\"http:\/\/www.politico.com\/news\/stories\/1010\/43644.html#ixzz12UI7DMvn\" class=\"gen\">15 octobre 2010<\/a>).<\/p>\n<\/p>\n<p><p>\t Il y a un c\u00f4t\u00e9 f\u00e9ministe tr\u00e8s marqu\u00e9, surtout du fait des candidates femmes soutenues par <em>Tea Party<\/em>. Mais ce c\u00f4t\u00e9 f\u00e9ministe n&rsquo;a rien \u00e0 voir avec le mouvement du m\u00eame nom mais avec la revendication de ces femmes exigeant des hommes qui d\u00e9tiennent l&rsquo;essentiel du pouvoir d&rsquo;affronter les probl\u00e8mes et les crises des USA (et de leur laisser de la place pour les y pousser, en donnant l&rsquo;exemple). Cette attitude est r\u00e9sum\u00e9e par l&rsquo;exhortation <em>Man Up !<\/em> (disons debout les hommes !), employ\u00e9e par l&rsquo;une ou l&rsquo;autre. (Voir \u00ab<em>Candidates play man-upsmanship<\/em>\u00bb le <a href=\"http:\/\/www.politico.com\/news\/stories\/1010\/43662.html\" class=\"gen\">15 octobre 2010<\/a> sur <em>Politico.com<\/em>.)<\/p>\n<\/p>\n<p><p>\t Une illustration de cet campagne est donn\u00e9e par le d\u00e9bat t\u00e9l\u00e9vis\u00e9 pour le si\u00e8ge de s\u00e9nateur du Nevada, entre Harry Reid, le puissant <em>leader<\/em> d\u00e9mocrate du S\u00e9nat, et Sharron Angle, la candidate r\u00e9publicaine du <em>Tea Party<\/em> (voir le <em>Daily Telegraph<\/em> le <a href=\"http:\/\/www.telegraph.co.uk\/news\/worldnews\/northamerica\/usa\/8067413\/Senate-Democrat-leader-battling-to-save-Nevada-seat.html\" class=\"gen\">16 octobre 2010<\/a>). Reid a \u00e9t\u00e9 battu dans ce d\u00e9bat, mis en difficult\u00e9 notamment par des questions sur sa fortune acquise durant sa carri\u00e8re de politicien, et cela alors que les sondages donnent Angle victorieuse contre le plus puissant d\u00e9mocrate du Congr\u00e8s.<\/p>\n<\/p>\n<p><p>\t Il y a cet article du New York <em>Times<\/em> du <a href=\"http:\/\/www.nytimes.com\/2010\/10\/15\/us\/politics\/15teaparty.html?hp\" class=\"gen\">14 octobre 2010<\/a>, qui rend compte d&rsquo;une \u00e9tude d\u00e9taill\u00e9e du journal sur les positions g\u00e9n\u00e9rales et l&rsquo;impact de <em>Tea Party<\/em>, consid\u00e9rant <em>de facto<\/em> ce mouvement <em>Tea Party<\/em> comme une sorte de troisi\u00e8me parti et lui accordant une importance et une influence substantielles au Congr\u00e8s apr\u00e8s le scrutin du 2 novembre. Le NYT semble estimer que le regroupement des candidats <em>Tea Party<\/em> dans un <em>caucus<\/em> fera d&rsquo;eux effectivement un troisi\u00e8me parti.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Enough Tea Party-supported candidates are running strongly in competitive and Republican-leaning Congressional races that the movement stands a good chance of establishing a sizeable caucus to push its agenda in the House and the Senate, according to a New York Times analysis.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>With a little more than two weeks till Election Day, 33 Tea Party-backed candidates are in tossup races or running in House districts that are solidly or leaning Republican, and 8 stand a good or better chance of winning Senate seats.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>While the numbers are relatively small, they could exert outsize influence<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>An analysis of each House and Senate race found 138 Tea Party candidates, all Republicans, running for nearly half the Democratic or open seats in the House and a third of those in the Senate <\/em> []<em>Tea Party nominees have performed better than expected in many cases, including races in which the establishment candidates they defeated in the primaries were considered the stronger general election contenders.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t La crainte de l&rsquo;<em>establishment<\/em> du facteur <em>Tea Party<\/em> et du d\u00e9sordre qu&rsquo;il peut amener dans la situation de routine de ce m\u00eame <em>establishment<\/em> est encore refl\u00e9t\u00e9e par un article de <em>DoDBuzz<\/em> du <a href=\"http:\/\/www.dodbuzz.com\/2010\/10\/14\/gop-to-tea-party-dont-cut-defense\/#ixzz12R3DNpIG\" class=\"gen\">14 octobre 2010<\/a> pr\u00e9sentant des objurgations d&rsquo;id\u00e9ologues et d&rsquo;experts r\u00e9publicains orthodoxes demandant \u00e0 <em>Tea Party<\/em> de ne pas chercher \u00e0 <a href=\"http:\/\/www.dedefensa.org\/article-tea_party_contre_moby_dick__14_10_2010.html\" class=\"gen\">r\u00e9duire<\/a> les d\u00e9penses de d\u00e9fense. C&rsquo;est la confirmation que <em>Tea Party<\/em> est un <a href=\"http:\/\/www.dedefensa.org\/article-tea_party_contre_moby_dick__14_10_2010.html\" class=\"gen\">enjeu<\/a> colossal \u00e0 cet \u00e9gard. Les militaires eux-m\u00eames semblent anticiper la temp\u00eate qui menace le Pentagone,  et l&rsquo;anticiper, c&rsquo;est en quelque sorte contribuer \u00e0 la susciter. (Voir <em>Bloomberg.News<\/em> le <a href=\"http:\/\/www.bloomberg.com\/news\/2010-10-13\/pentagon-likely-to-cut-eliminate-more-major-weapons-programs-mullen-says.html\" class=\"gen\">13 octobre 2010<\/a>.)<\/p>\n<h4>Notre commentaire<\/h4>\n<p>Il nous semble de plus en plus confirm\u00e9 qu&rsquo;on ne peut <strong>en aucun cas<\/strong> avancer une analyse des \u00e9v\u00e9nements de l&rsquo;apr\u00e8s-2 novembre bas\u00e9e sur le pronostic et les projections des r\u00e9sultats de ces \u00e9lections. Aucun des faits (des r\u00e9sultats) probables de ces \u00e9lections, telles qu&rsquo;elles se pr\u00e9sentent, ne sera indicatif de la forme, de l&rsquo;essence d&rsquo;une \u00e9volution, d&rsquo;un changement, etc., mais tous renforcent l&rsquo;id\u00e9e que la substance m\u00eame du monde politique washingtonien sera chang\u00e9e. Nous confirmons notre appr\u00e9ciation que les \u00e9lections du 2 novembre ne seront qu&rsquo;une \u00e9tape dans le processus d\u00e9j\u00e0 bien avanc\u00e9 de d\u00e9structuration du syst\u00e8me politique washingtonien. Ce qui se passera apr\u00e8s est du domaine de l&rsquo;inconnu, avec la seule probabilit\u00e9 qu&rsquo;aucun des sch\u00e9mas pr\u00e9c\u00e9dents, y compris d&rsquo;\u00e9lections amenant un bouleversement politique complet, ne peut servir de mod\u00e8le car les bouleversements en question se firent \u00e0 l&rsquo;int\u00e9rieur des normes de l&rsquo;<em>establishment<\/em>.<\/p>\n<\/p>\n<p><p>\tPlus que jamais, <em>Tea Party<\/em> est au centre de toute l&rsquo;attention, et l&rsquo;\u00e9tude du New York <em>Times<\/em> \u00e0 cet \u00e9gard est impressionnante. Le fait majeur de perception est que <em>Tea Party<\/em> est effectivement per\u00e7u comme une entit\u00e9 \u00e0 part (chaque candidat r\u00e9publicain b\u00e9n\u00e9ficiant du soutien de <em>Tea Party<\/em> ou venu de <em>Tea Party<\/em> est labellis\u00e9 automatiquement par les observateurs comme candidat <em>Tea Party<\/em> et non comme candidat r\u00e9publicain). Si les pointages du NYT sont justes, <em>Tea Party<\/em> occupera une position id\u00e9ale, un pied en dedans et un pied en dehors (dans le parti r\u00e9publicain), c&rsquo;est-\u00e0-dire impossible \u00e0 marginaliser d&rsquo;une part puisque dans le parti r\u00e9publicain, impossible \u00e0 r\u00e9cup\u00e9rer d&rsquo;autre part puisque en position d&rsquo;exercer une pression constante de critique et de d\u00e9sordre avec son rassemblement en un groupement autonome informel. Les r\u00e9publicains orthodoxes, pourtant donn\u00e9s victorieux, sont aussi mal \u00e0 l&rsquo;aise que les d\u00e9mocrates dont le moral est catastrophique, avec un Obama \u00e0 la d\u00e9rive. Le r\u00e9sultat pourrait \u00eatre \u00e0 la fois une administration \u00e0 la d\u00e9rive par \u00e9puisement psychologique et un Congr\u00e8s \u00e0 la d\u00e9rive par d\u00e9sordre institutionnalis\u00e9<\/p>\n<\/p>\n<p><p>\tCar, r\u00e9p\u00e9tons-le encore une fois, <em>Tea Party<\/em>, s&rsquo;il s&rsquo;installe avec un certain poids au Congr\u00e8s, n&rsquo;am\u00e8nerait <strong>s\u00fbrement pas<\/strong> une nouvelle orientation pr\u00e9cis\u00e9ment identifi\u00e9e. Il am\u00e8nerait le d\u00e9sordre. <em>Tea Party<\/em> est toujours insaisissable, sans coh\u00e9sion fermement marqu\u00e9, sans programme \u00e9labor\u00e9 sinon son opposition furieuse aux d\u00e9penses publiques qui peut d\u00e9boucher sur des pressions anarchiques fond\u00e9es autant sur l&rsquo;expression d&rsquo;un sentiment public tr\u00e8s fort que sur la d\u00e9magogie naturelle qui va avec. <em>Tea Party<\/em> est bien un ensemble compl\u00e8tement d\u00e9structur\u00e9, mais qui pourrait s&rsquo;implanter dans une force extr\u00eamement structur\u00e9e (le Congr\u00e8s) dont la politique est par contre totalement d\u00e9structurante. Il s&rsquo;agirait alors d&rsquo;une pression d\u00e9structurante exerc\u00e9e contre une puissante structure qui g\u00e9n\u00e8re une politique elle-m\u00eame d\u00e9structurante faite \u00e0 l&rsquo;avantage de l&rsquo;<em>establishment<\/em> au service du syst\u00e8me de l&rsquo;am\u00e9ricanisme. D&rsquo;effets indirects en effets indirects et selon notre th\u00e9orie du contre-feu, c&rsquo;est effectivement le syst\u00e8me de l&rsquo;am\u00e9ricanisme qui est attaqu\u00e9 sans qu&rsquo;ancun des acteurs n&rsquo;ait conscience pr\u00e9cise du r\u00f4le qu&rsquo;il joue et des effets de ce r\u00f4le. (Voir sur cette conception du contre-feu, au <a href=\"http:\/\/www.dedefensa.org\/article-le_desordre_continue_a_s_organiser_03_09_2010.html\" class=\"gen\">3 septembre 2010<\/a> : <em>C&rsquo;est la d\u00e9structuration en cours de l&rsquo;ordre lui-m\u00eame d\u00e9structurant qui domine d&rsquo;une fa\u00e7on furieuse et extr\u00e9miste depuis la fin de la Guerre froide, et surtout depuis 9\/11. La fameuse r\u00e8gle alg\u00e9brique (moins plus moins \u00e9gale plus) tout comme notre affection pour la tactique du contre-feu, ne peuvent que nous conduire \u00e0 nous r\u00e9jouir d&rsquo;un tel d\u00e9sordre, qui s&rsquo;av\u00e8re effectivement organis\u00e9 puisque son effet est de d\u00e9structurer un fonctionnement trompeusement rationnel, au nom d&rsquo;une raison humaine pervertie, pour conduire \u00e0 un affaiblissement dramatique d&rsquo;un syst\u00e8me d\u00e9structurant.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tQuoi qu&rsquo;il en soit, il s&rsquo;agit du champ des hypoth\u00e8ses et les \u00e9lections du 2 novembre restent tr\u00e8s logiquement une \u00e9nigme envelopp\u00e9e de myst\u00e8re ; et nous n&rsquo;en saurons sans doute pas tellement plus le 3 novembre, \u00e0 moins d&rsquo;\u00e9norme surprise, tant il faudra un certain temps pour appr\u00e9cier l&rsquo;impact du ph\u00e9nom\u00e8ne. Par contre, ce qu&rsquo;on peut avancer avec certitude, c&rsquo;est que l&rsquo;\u00e9tat d&rsquo;esprit, la pr\u00e9vision inconsciente de ces \u00e9lections comme on attend une fatalit\u00e9, sont bien qu&rsquo;elles mettront en place une paradoxale structure de d\u00e9sordre au cur de l&rsquo;<em>establishment<\/em>. On pourrait avancer que cette perception \u00e9tant ce qu&rsquo;elle est, et avec quelle puissance, elle aurait d\u00e9j\u00e0 cr\u00e9\u00e9 les conditions pour que, effectivement, et dans la mesure o\u00f9 les r\u00e9sultats sont dans les bornes de ce qu&rsquo;on en attend (voir l&rsquo;\u00e9tude du NYT), ces \u00e9lections seront per\u00e7ues comme installant effectivement cette structure de d\u00e9sordre,  et que, par cons\u00e9quent, avec les effets de la perception sur la psychologie, structure de d\u00e9sordre il y aura<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 16 octobre 2010 \u00e0 06H41<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au moins une v\u00e9rit\u00e9 \u00e9merge de la campagne des mid-terms aux USA, deux semaines avant le scrutin du 2 novembre. Cette campagne refl\u00e8te parfaitement, tant du point de vue des \u00e9lecteurs que du point de vue des candidats, que du point de vue des dirigeants (BHO en premier), l&rsquo;\u00e9tat d&rsquo;esprit autant que la situation politique&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[10037,9861,2631,6214,3356,6579,4141,6625,6109,7069,5953,3099,3818,7114,8256],"class_list":["post-72374","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-angle","tag-caucus","tag-de","tag-desarroi","tag-desordre","tag-destructurant","tag-elections","tag-harry","tag-mid-term","tag-party","tag-perception","tag-psychologie","tag-reid","tag-structure","tag-tea"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72374"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72374\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}