{"id":72390,"date":"2010-10-22T05:43:55","date_gmt":"2010-10-22T05:43:55","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/10\/22\/lobsession-tea-party\/"},"modified":"2010-10-22T05:43:55","modified_gmt":"2010-10-22T05:43:55","slug":"lobsession-tea-party","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/10\/22\/lobsession-tea-party\/","title":{"rendered":"L&rsquo;obsession <em>Tea Party<\/em>"},"content":{"rendered":"<p><p>Voici un texte \u00e0 la fois inattendu et significatif. Il est inattendu parce qu&rsquo;il est publi\u00e9 par le Washington <em>Times<\/em>, en g\u00e9n\u00e9ral favorable au <em>Tea Party<\/em> et qu&rsquo;il pr\u00e9sente ce ph\u00e9nom\u00e8ne non sans une certaine appr\u00e9hension ; il est significatif parce qu&rsquo;il marque bien l&rsquo;obsession qu&rsquo;est en train de devenir aux USA  <em>Tea Party<\/em>, pr\u00e9sent\u00e9 ici dans son option la plus radicale et pr\u00e9sent\u00e9 \u00e9galement (sans aucune intention propagandiste mais plut\u00f4t inconsciemment) comme un courant proche d&rsquo;\u00eatre irr\u00e9sistible. Pourtant, <em>Tea Party<\/em> est loin, tr\u00e8s loin d&rsquo;\u00eatre organis\u00e9 et pr\u00e9sent dans les \u00e9lections en tant que tel jusqu&rsquo;\u00e0 pr\u00e9senter une force justement irr\u00e9sistible, d&rsquo;un point de vue politique classique.<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit d&rsquo;une analyse de Patrice Hill, dans le Washington <em>Times<\/em> du <a href=\"http:\/\/www.washingtontimes.com\/news\/2010\/oct\/20\/tea-party-urges-drastic-cutting\/print\/\" class=\"gen\">20 octobre 2010<\/a>, d&rsquo;une enqu\u00eate de sondage r\u00e9alis\u00e9e par <em>Bloomberg.News<\/em>, au sein de <em>Tea Party<\/em>. La ligne g\u00e9n\u00e9rale d\u00e9gag\u00e9e, la ligne fondamentale et unificatrice de <em>Tea Party<\/em>, c&rsquo;est la r\u00e9duction radicale des d\u00e9penses du gouvernement f\u00e9d\u00e9ral, jusqu&rsquo;\u00e0 parvenir \u00e0 un \u00e9quilibre du budget. Les positions des membres de <em>Tea Party<\/em> sont f\u00e9roces contre les d\u00e9penses du gouvernement, la politique de la Federal Reserve,  avec, sur ce dernier point, une majorit\u00e9 favorable \u00e0 sa suppression (\u00ab<em>The Bloomberg poll found, in fact, that a majority of tea party supporters would like to abolish the Fed<\/em>\u00bb). Les r\u00e9sultats de l&rsquo;enqu\u00eate sont soumis \u00e0 l&rsquo;appr\u00e9ciation d&rsquo;\u00e9conomistes, dont certains craignent qu&rsquo;un tel programme pourrait causer la pire d\u00e9pression de l&rsquo;histoire des Etats-Unis, tandis que d&rsquo;autres approuvent un programme d&rsquo;une telle radicalit\u00e9,  montrant que les positions se radicalisent \u00e9galement dans cette branche de l&rsquo;expertise habituellement plus mesur\u00e9e dans ses diff\u00e9rences.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>But while applauding their budget-cutting zeal, economists are divided over whether their prescription is good medicine for a weak economy. Some say it&rsquo;s reminiscent of President Hoover&rsquo;s drive to balance the budget during the Great Depression  and would backfire this time as well.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>The tea party&rsquo;s demands to balance the budget and reduce the federal deficit aren&rsquo;t merely misguided, but dangerous, and would cause the worst depression in history, said Warren Mosler, a former investment manager and monetary policy expert who describes himself as a former tea party Democrat.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>I have been, and continue to be, a strong supporter of the core tea party values of lower taxes, limited government, competitive market solutions, and a return to personal responsibility, he said. However, their proposals to balance the budget are the same suicidal policies that caused six horrible depressions in the U.S. over the past 200 years.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Contrary to popular belief, we can reduce spending without endangering the republic, said Jerry Jasinowski, economist and former president of the National Association of Manufacturers, suggesting Congress start with unnecessary weapons systems and pork-barrel projects.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>He said the tea party&rsquo;s revulsion against the spending binge in Washington has hit a chord with the public. You can argue all night that the spending is necessary to avert an economic meltdown or keep the nation safe, but no one really believes that, he said. What they do believe is a vast sea of debt must be repaid.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The truth is, Mr. Jasinowski said, the tea party agenda poses a threat to both parties. Their message strikes to the heart of what Washington does best: squander money, he said. It is perhaps the one thing that is truly bipartisan.<\/em>\u00bb<\/p>\n<h4>Notre commentaire<\/h4>\n<p>Ce texte est extr\u00eamement int\u00e9ressant par sa tonalit\u00e9, parce qu&rsquo;il exprime d&rsquo;une certaine fa\u00e7on l&#8217;empire extraordinaire, sous la forme d&rsquo;une influence psychologique irr\u00e9sistible, que <em>Tea Party<\/em> est en train d&rsquo;\u00e9tablir sur le syst\u00e8me politique, alors qu&rsquo;il ne repr\u00e9sente nullement, ni une majorit\u00e9, ni une organisation pouvant justifier un tel empire. Mais ce qui caract\u00e9rise principalement <em>Tea Party<\/em> aujourd&rsquo;hui, ou l&rsquo;image de <em>Tea Party<\/em>, se d\u00e9compose en deux points C&rsquo;est d&rsquo;abord son extraordinaire extr\u00e9misme sur cette question des d\u00e9penses publiques (voir aussi le <em>Progress Report<\/em> de ce <a href=\"http:\/\/pr.thinkprogress.org\/2010\/10\/pr20101021\/index.html\" class=\"gen\">21 octobre 2010<\/a> pour un d\u00e9tail des mesures qui pourraient na\u00eetre de cette politique) ; quand on r\u00e9alise la profondeur et la puissance formidable que constituerait ce programme dans sa compl\u00e8te potentialit\u00e9, on est conduit \u00e0 conclure qu&rsquo;il s&rsquo;agirait d&rsquo;une voie vers la d\u00e9structuration du pays dans son ensemble, d&rsquo;abord par simple disparition, par an\u00e9mie, du gouvernement central (par ailleurs d\u00e9j\u00e0 d\u00e9vor\u00e9 par le service de la dette). Ensuite, pour compl\u00e9ter le cas extraordinaire que constitue <em>Tea Party<\/em>, c&rsquo;est le deuxi\u00e8me point que constitue la r\u00e9alisation que ce mouvement, avec le programme th\u00e9orique dont il est porteur, avec ce qu&rsquo;il peut y avoir de th\u00e9oriquement le plus extr\u00e9miste (car on en vient \u00e0 penser que <em>Tea Party<\/em> est moins extr\u00e9miste que la fa\u00e7on dont il est de plus en plus repr\u00e9sent\u00e9) : <em>Tea Party<\/em> semble constituer une sorte d&rsquo;objet de fascination pour une Am\u00e9rique plong\u00e9e dans la crise psychologique la plus folle qu&rsquo;on puisse imaginer.<\/p>\n<\/p>\n<p><p>\t<em>Tea Party<\/em> devient ainsi une sorte d&rsquo;\u00e9pouvantail \u00e0 la mesure d&rsquo;un pays qui est un continent, qui entretient une conception unique du monde et une force d&rsquo;influence sans pr\u00e9c\u00e9dent, et un \u00e9pouvantail qui jouerait aussi le r\u00f4le d&rsquo;exorciste de la crise folle qui met ce pays-continent, cette conception et cette influence en lambeaux. La perception, la mesure m\u00eame de sa puissance, ne r\u00e9pondent plus \u00e0 aucune logique statistique, politique ou autre. <em>Tea Party<\/em> est le spectre d&rsquo;une Am\u00e9rique qui n&rsquo;existe plus ou d&rsquo;une Am\u00e9rique qui n&rsquo;a jamais exist\u00e9 que dans l&rsquo;un ou l&rsquo;autre pli de l&rsquo;<em>American Dream<\/em> ; en m\u00eame temps, <em>Tea Party<\/em> est l&rsquo;arch\u00e9type de ce que devrait \u00eatre l&rsquo;Am\u00e9rique selon ses principes radicaux originels et, par cons\u00e9quent, le seul mod\u00e8le qui puisse \u00eatre envisag\u00e9, qui semble avoir assez de force pour briser le cycle infernal de la crise. <em>Tea Party<\/em> n&rsquo;existe pas tel qu&rsquo;il est per\u00e7u et il est peut-\u00eatre une mystification, mais tout se passe comme s&rsquo;il existait pourtant aux dimensions qu&rsquo;on dit. Comme <em>Tea Party<\/em> n&rsquo;est rien de v\u00e9ritablement important en soi du point de vue politique classique, rien d&rsquo;une substance vraiment identifiable, cette obsession de lui qui domine la campagne \u00e9lectorale devient un facteur essentiel qui n&rsquo;a plus de r\u00e9el lien avec ce qu&rsquo;est v\u00e9ritablement <em>Tea Party<\/em>. Mais c&rsquo;en est au point o\u00f9 l&rsquo;on ferait l&rsquo;hypoth\u00e8se que <em>Tea Party<\/em> pourrait lui-m\u00eame succomber \u00e0 sa propre influence, et se radicaliser encore par rapport \u00e0 ce qu&rsquo;il est, pour correspondre \u00e0 l&rsquo;image que l&rsquo;inconscient psychologique US a fait de lui.<\/p>\n<\/p>\n<p><p>\tEn un sens, on pourrait dire : qu&rsquo;importent les \u00e9lections et leurs r\u00e9sultats parce que l&rsquo;obsession <em>Tea Party<\/em> est en train de d\u00e9passer <em>Tea Party<\/em> et emm\u00e8nera l&rsquo;Am\u00e9rique sur la voie de <em>Tea Party<\/em>. (Sur les \u00e9lections elles-m\u00eames, il faut signaler un article du <em>Daily Telegraph<\/em> de ce <a href=\"http:\/\/www.telegraph.co.uk\/news\/worldnews\/northamerica\/usa\/us-politics\/8078830\/Midterm-elections-2010-Tea-Party-poised-to-storm-Washington.html\" class=\"gen\">22 octobre 2010<\/a>, o\u00f9 le journal britannique pronostique un ouragan <em>Tea Party<\/em> sur Washington, d\u00e9crivant des candidats soutenus par <em>Tea Party<\/em> ou se ralliant \u00e0 <em>Tea Party<\/em>, qui r\u00e9pondraient compl\u00e8tement aux consignes, ou consignes suppos\u00e9es du mouvement, et seraient capables de compl\u00e8tement d\u00e9structurer, \u00e0 l&rsquo;avantage de <em>Tea Party<\/em>, le fonctionnement du Congr\u00e8s. Le <em>Telegraph<\/em> estime que <em>Tea Party<\/em> formera un bloc d&rsquo;au moins 100 \u00e9lus, qui r\u00e9pondront aux consignes de <em>Tea Party<\/em> et se conduiront <em>de facto<\/em> comme membres d&rsquo;un troisi\u00e8me parti : \u00ab<em>According to analysts, there are 138 Republicans with Tea Party links running for Congress, 129 vying for seats in the House of Representatives and nine in the Senate.<\/em>\u00bb Ces pr\u00e9visions rejoignent celles qui ont d\u00e9j\u00e0 \u00e9t\u00e9 enregistr\u00e9es,  voir notre <em>Bloc-Notes<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-une_campagne_destructurante_en_accord_avec_un_temps_destructure_16_10_2010.html\" class=\"gen\">16 octobre 2010<\/a>.)<\/p>\n<\/p>\n<p><p>\tQuelles sont les perspectives dans ce climat ? Si effectivement <em>Tea Party<\/em> intervient dans les structures l\u00e9gislatives d&rsquo;une fa\u00e7on marquantes, les cons\u00e9quences seraient \u00e9videmment radicales et ne pourraient \u00eatre accept\u00e9s par les groupes oppos\u00e9s \u00e0 ces tendances. Dans la mesure o\u00f9 le gouvernement central serait encore plus paralys\u00e9 qu&rsquo;il n&rsquo;est aujourd&rsquo;hui, o\u00f9 le Congr\u00e8s serait devenu ingouvernable et totalement polaris\u00e9, la logique de la d\u00e9structuration effective du pays serait en marche,  c&rsquo;est-\u00e0-dire la division, la parcellisation, dans un pays dont on sait que la faiblesse fondamentale est justement cette absence d&rsquo;unit\u00e9 et de coh\u00e9sion organiques \u00e0 cause de l&rsquo;existence des Etats de l&rsquo;Union et de l&rsquo;absence d&rsquo;un Etat central de caract\u00e8re r\u00e9galien.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 22 octobre 2010 \u00e0 05H46<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voici un texte \u00e0 la fois inattendu et significatif. Il est inattendu parce qu&rsquo;il est publi\u00e9 par le Washington Times, en g\u00e9n\u00e9ral favorable au Tea Party et qu&rsquo;il pr\u00e9sente ce ph\u00e9nom\u00e8ne non sans une certaine appr\u00e9hension ; il est significatif parce qu&rsquo;il marque bien l&rsquo;obsession qu&rsquo;est en train de devenir aux USA Tea Party, pr\u00e9sent\u00e9&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2604,3907,5757,3090,6767,5623,7069,3099,8256,5630,2804],"class_list":["post-72390","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-des","tag-destructuration","tag-inconscient","tag-influence","tag-obsession","tag-parti","tag-party","tag-psychologie","tag-tea","tag-troisieme","tag-usa"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72390"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72390\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}