{"id":72423,"date":"2010-11-03T18:52:09","date_gmt":"2010-11-03T18:52:09","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/11\/03\/guerre-et-paix-style-midterm\/"},"modified":"2010-11-03T18:52:09","modified_gmt":"2010-11-03T18:52:09","slug":"guerre-et-paix-style-midterm","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/11\/03\/guerre-et-paix-style-midterm\/","title":{"rendered":"Guerre et paix style-<em>midterm<\/em>"},"content":{"rendered":"<p><p>Justin Raimondo fait une chronique int\u00e9ressante et, somme toute, assez \u00e9trange, sur <em>Antiwar.com<\/em>, ce <a href=\"http:\/\/original.antiwar.com\/justin\/2010\/11\/02\/election-2010-a-disaster-for-peace\/\" class=\"gen\">2 novembre 2010<\/a>. Bien entendu, il est question des \u00e9lections.<\/p>\n<\/p>\n<p><p>\tCette chronique se divise en deux sentiments (plut\u00f4t qu&rsquo;en deux parties), compl\u00e8tement \u00e0 l&rsquo;oppos\u00e9. Pour nous (voir plus loin, Notre commentaire), il s&rsquo;agit en r\u00e9alit\u00e9 d&rsquo;une situation <strong>id\u00e9ale<\/strong> Les deux sentiments de Justin, suivis de quelques extraits choisis :<\/p>\n<\/p>\n<p><p>\t D&rsquo;une part, c&rsquo;est un d\u00e9sastre pour la paix (<em>a disaster for p\u00eaace<\/em>), vu le nombre de r\u00e9publicains bellicistes, pseudo-<em>neocons<\/em>, allum\u00e9s du bellicisme, plus pro-isra\u00e9liens que Netanyahou, etc., qui vont peupler les trav\u00e9es de la Chambre notamment.<\/p>\n<\/p>\n<p><p>\t D&rsquo;autre part, la situation pourrait \u00eatre int\u00e9ressante (\u00ab<em>results should be  interesting<\/em>\u00bb), \u00e0 cause des contradictions potentielles qui pourraient venir au jour, des limites des moyens US, de la profondeur de la crise US et ainsi de suite.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>As ForeignPolicy.com puts it:<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Most incoming Tea Party candidates don&rsquo;t focus on foreign policy, but many will owe allegiance to DeMint because he has been filling their campaign coffers. They could be inclined to follow suit with his unilateralist, militaristic worldview, which many see as based on his neoconservative ideology rather than a realistic pursuit of U.S. interests in<\/em> [a] <em>multipolar world order.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>One example of his influence over the tea party candidates: DeMint was an early endorser of Rand Paul, whose move toward neoconnish foreign policy positions provoked my ire in this column. Now that Rand has been elected, will he embrace the neocons, or will he stay true to his nationwide libertarian constituency? Of course, if we were talking about his father, Ron Paul, we would have nothing to worry about. As it is, however <\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>The big problem with a Republican-dominated House is that those GOPers who take an interest in foreign policy issues are invariably hawks: these are the committed neocons, like Cantor and Kyl. The tea partiers, for their part, avoid the issue, focused exclusively as they are deficits, taxes, and budget-cutting.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>There is, however, a silver lining to all this: the Empire is going bankrupt. Our invasion of Iraq is estimated by economist Joseph Stiglitz to cost some 3 trillion dollars, when all is said and done. Neocons Bill Kristol and the heads of the American Enterprise Institute and the Heritage Foundation came out with an op ed warning the tea party types not to go near their precious defense budget with the cost-cutter&rsquo;s knife. But the tea partiers are unlikely to listen to Kristol &#038; Co., or, indeed, any members of the Republican establishment, who, after all, presided over the spendthrift Bush administration all the while proclaiming their support for what they called big government conservatism.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Aside from the fact that the war did not lift us out of the Depression  see Robert Higgs for the real story  this scenario is perfectly credible. As a self-described political pragmatist, the President is prone to taking the easy way out, and while the economy may not improve as war preparations are ratcheted up, this is not likely to deter either Obama or his Keynesian economic advisers, who believe that any and all government spending  including military spending  is the key to recovery.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>In the short term, the contours of the electoral disaster for the antiwar movement are large, but in the mid-to long term the contradictions of the tea party movement may start to rip this winning coalition apart. Are defense expenditures and extravagantly expensive nation-building projects boondoggles, or are they essential for the survival of the Republic? This is a debate that will break out in the GOP sooner rather than later, and the results should be  interesting.<\/em>\u00bb<\/p>\n<h4>Notre commentaire<\/h4>\n<p> D\u00e9sordre, disions-nous et ne cessons de r\u00e9p\u00e9ter D\u00e9sordre, \u00e9galement, dans cette question de politique ext\u00e9rieure avec ses rapports avec la politique int\u00e9rieure, et cela, <strong>\u00e0 l&rsquo;int\u00e9rieur<\/strong> m\u00eame du parti r\u00e9publicain.<\/p>\n<\/p>\n<p><p>\tL&rsquo;alarme initiale dans l&rsquo;article de Raimondo est curieusement d\u00e9mentie par d&rsquo;autres pr\u00e9cisions qui suivent. Personne n&rsquo;ignore que l&rsquo;<em>establishment<\/em> r\u00e9publicain, surtout \u00e0 la Chambre, est mang\u00e9 jusqu&rsquo;\u00e0 l&rsquo;os par l&rsquo;influence isra\u00e9lienne et par l&rsquo;influence des <em>neocons<\/em>. Rien de nouveau dans ce cas, et la Chambre actuelle, qui s&rsquo;ach\u00e8ve le 31 d\u00e9cembre, est du m\u00eame acabit, d&rsquo;autant que les d\u00e9mocrates n&rsquo;ont <strong>jamais<\/strong> jou\u00e9 le moindre r\u00f4le de contrepoids, s&rsquo;alignant aveuglement sur la ligne isra\u00e9lo-<em>neocon<\/em>. Cela dit, la chose ne nous a pas pour autant donn\u00e9 une attaque contre l&rsquo;Iran, malgr\u00e9 de multiples alarmes et de multiples pr\u00e9visions de multiples experts bien renseign\u00e9s \u00e0 cet \u00e9gard. Les m\u00eames fous,  ou \u00ab<em>megalomaniacal neoconservatives who are more in need of mental attention<\/em>\u00bb, selon <a href=\"http:\/\/www.dedefensa.org\/article-kucinich_contre_la_montee_du_nihilisme_us_28_10_2010.html\" class=\"gen\">Dennis Kucinich<\/a>,  seront toujours en service \u00e0 la Chambre qui sera inaugur\u00e9e le 1er janvier 2011.<\/p>\n<\/p>\n<p><p>\tMais deux \u00e9l\u00e9ments tr\u00e8s nouveaux, et tr\u00e8s int\u00e9ressants, seront \u00e9galement pr\u00e9sents. Raimondo les mentionne effectivement, et il ne leur donne pas assez l&rsquo;importance qui est leur dans la tonalit\u00e9 g\u00e9n\u00e9rale de son article.<\/p>\n<\/p>\n<p><p>\t Le Pentagone est dans un \u00e9tat de coma avanc\u00e9, comme on ne cesse de le constater chaque jour (voir le <em>Bloc-Notes<\/em> de ce m\u00eame  <a href=\"http:\/\/www.dedefensa.org\/article-le_pentagone_dans_la_tenaille_du_coming_crash_03_11_2010.html\" class=\"gen\">3 novembre 2010<\/a>), cela avec un budget vertigineux. Rien ne montre que cet Himalaya de $milliards que constitue son budget puisse faire quelque chose pour le monstre, et tout montre que quelques pellet\u00e9es de $milliards de plus ne feraient qu&rsquo;aggraver la situation en alimentant prioritairement l&rsquo;inefficacit\u00e9, le gaspillage, la paralysie bureaucratique et la corruption. Or, c&rsquo;est ce que voudront faire les faucons de la Chambre, donner encore plus d&rsquo;argent au Pentagone Et l&rsquo;effet collat\u00e9ral serait bien entendu d&rsquo;accro\u00eetre encore plus le d\u00e9ficit abyssal du tr\u00e9sor public.<\/p>\n<\/p>\n<p><p>\t Or, <em>Tea Party<\/em> est pr\u00e9sent. Il est vrai que <em>Tea Party<\/em> ne s&rsquo;int\u00e9resse pas vraiment \u00e0 la politique ext\u00e9rieure sinon, dans une certaine confusion et pour une partie seulement de <em>Tea Party<\/em>, pour des professions de foi sur la s\u00e9curit\u00e9 et la puissance US qui ne mangent pas de pain (du point de vue de <em>Tea Party<\/em>). Par contre, les engagements qu&rsquo;absolvent vaguement ces professions de foi mangent, eux, beaucoup, beaucoup d&rsquo;argent, et de l&rsquo;argent public. Sur ce point, par contre, <em>Tea Party<\/em> est ultra-sensible et il vient au Congr\u00e8s pour mettre le hol\u00e0 aux d\u00e9penses publiques. Il est math\u00e9matiquement, c&rsquo;est-\u00e0-dire d&rsquo;une fa\u00e7on comptable, impossible qu&rsquo;il ne se heurte pas \u00e0 un moment ou l&rsquo;autre, \u00e0 la question des d\u00e9penses de d\u00e9fense et \u00e0 ceux qui en sont partisans, justement des r\u00e9publicains comme eux : \u00ab<em>This is a debate that will break out in the GOP sooner rather than later, and the results should be  interesting<\/em>\u00bb, comme l&rsquo;\u00e9crit Raimondo.<\/p>\n<\/p>\n<p><p>\tNous ne croyons pas une seconde que dans un syst\u00e8me si totalement perverti, si totalement gangren\u00e9 par l&rsquo;<em>hubris<\/em> du d\u00e9cha\u00eenement de la force, la question d&rsquo;une politique ext\u00e9rieure pacifi\u00e9e et ouverte au compromis puisse s\u00e9rieusement \u00eatre pos\u00e9e. On ne peut attendre une telle uvre collective d&rsquo;un tel asile psychiatrique. Par contre, la formule de l&rsquo;affrontement interne au parti r\u00e9publicain, sur la v\u00e9ritable politique (r\u00e9duction des d\u00e9penses publiques) qui a donn\u00e9 la victoire au parti r\u00e9publicain, est une formule tr\u00e8s vivace, pleine de fougue et de sant\u00e9, qui peut conduire \u00e0 des affrontements du plus grand int\u00e9r\u00eat,  notamment parce que nombre d&rsquo;\u00e9lus savent que c&rsquo;est sur ce point qu&rsquo;ils sont en accord avec leur \u00e9lectorat. La situation est donc, de ce point de vue, infiniment meilleure qu&rsquo;avec une puissante majorit\u00e9 d\u00e9mocrate qui faisait la m\u00eame politique belliciste en l&rsquo;habillant de mots un peu plus d\u00e9licats que ceux qu&#8217;emploient les bellicistes r\u00e9publicains. <\/p>\n<\/p>\n<p><p>\tNous allons donc nous diriger rapidement, dans ces divers domaines sur plusieurs possibilit\u00e9s,  dont certaines ne s&rsquo;excluent pas entre elles mais peuvent se rajouter et se renforcer.<\/p>\n<\/p>\n<p><p>\t Une accentuation de la situation catastrophique du Pentagone, ajoutant une pression consid\u00e9rable en faveur du mouvement de r\u00e9duction des d\u00e9penses du Pentagone, en cours notamment sous <a href=\"http:\/\/www.dedefensa.org\/article-frank_et_paul_la_main_dans_la_main_06_07_2010.html\" class=\"gen\">la direction<\/a> de Ron Paul et de Barney Frank. Cette situation est \u00e9videmment en connexion directe avec les intentions plus larges de <em>Tea Party<\/em> de r\u00e9duire les d\u00e9penses publiques.<\/p>\n<\/p>\n<p><p>\t Le mouvement g\u00e9n\u00e9ral de <em>Tea Party<\/em> de r\u00e9duction des d\u00e9penses publiques, qui ne vise pas au d\u00e9part la d\u00e9fense, mais qui peut ais\u00e9ment toucher \u00e0 ce domaine pour pouvoir effectivement parvenir \u00e0 des r\u00e9sultats significatifs. C&rsquo;est dans ce cas o\u00f9 les deux possibilit\u00e9s (la pr\u00e9c\u00e9dente et celle-ci) peuvent se rencontrer et s&rsquo;ajouter.<\/p>\n<\/p>\n<p><p>\t Une troisi\u00e8me possibilit\u00e9 est une pouss\u00e9e violente des bellicistes pour forcer \u00e0 un nouvel engagement militaire, notamment contre l&rsquo;Iran. C&rsquo;est possible mais la chose se ferait dans des conditions fort peu avantageuses, \u00e0 cause des probl\u00e8mes \u00e9normes des forces arm\u00e9es US, des erreurs de calcul diplomatique des experts US (voir <a href=\"http:\/\/www.dedefensa.org\/article-arabie_iran_60_milliards_et_double_jeu_02_11_2010.html\" class=\"gen\">l&rsquo;Arabie<\/a>), des chocs internationaux en retour contre les USA. Les cons\u00e9quences seraient consid\u00e9rables, encore plus pour les USA eux-m\u00eames que pour la stabilit\u00e9 du monde, au niveau budg\u00e9taire en g\u00e9n\u00e9ral, voire au niveau de la structure m\u00eame du pays. (On peut \u00e0 cet \u00e9gard rappeler <a href=\"http:\/\/www.dedefensa.org\/article-voici_les_neo-secessionnistes__26_04_2010.html\" class=\"gen\">l&rsquo;avis<\/a> d&rsquo;un n\u00e9o-s\u00e9cessionniste de grande sagesse, qui fait d&rsquo;une attaque contre l&rsquo;Iran une des deux causes possibles d&rsquo;un effondrement brutal de la structure des USA et du syst\u00e8me de l&rsquo;am\u00e9ricanisme.)<\/p>\n<\/p>\n<p><p>\tDans tous les cas, la situation est infiniment plus int\u00e9ressante qu&rsquo;avec les d\u00e9mocrates majoritaires, \u00e0 cause de polarisations multiples, de mont\u00e9es aux extr\u00eames dans tous les sens, de plus en plus antagonistes, \u00e0 l&rsquo;int\u00e9rieur des partis, avec un personnel de plus en plus notoirement indisciplin\u00e9.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 3 novembre 2010 \u00e0 18H54<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Justin Raimondo fait une chronique int\u00e9ressante et, somme toute, assez \u00e9trange, sur Antiwar.com, ce 2 novembre 2010. Bien entendu, il est question des \u00e9lections. Cette chronique se divise en deux sentiments (plut\u00f4t qu&rsquo;en deux parties), compl\u00e8tement \u00e0 l&rsquo;oppos\u00e9. Pour nous (voir plus loin, Notre commentaire), il s&rsquo;agit en r\u00e9alit\u00e9 d&rsquo;une situation id\u00e9ale Les deux sentiments&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[2870,3037,6379,3681,7877,9666,1104,7069,3140,4607,4337,8256],"class_list":["post-72423","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-attaque","tag-contre","tag-exterieure","tag-faucons","tag-frank","tag-liran","tag-neocons","tag-party","tag-paul","tag-politique","tag-raimondo","tag-tea"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72423"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72423\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}