{"id":72456,"date":"2010-11-13T15:32:10","date_gmt":"2010-11-13T15:32:10","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/11\/13\/lordon-et-la-legitimite\/"},"modified":"2010-11-13T15:32:10","modified_gmt":"2010-11-13T15:32:10","slug":"lordon-et-la-legitimite","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/11\/13\/lordon-et-la-legitimite\/","title":{"rendered":"Lordon et la l\u00e9gitimit\u00e9."},"content":{"rendered":"<p><h4>Lordon et la l\u00e9gitimit\u00e9<\/h4>\n<p><a href=\"http:\/\/web.upmf-grenoble.fr\/regulation\/wp\/document\/RR_serieI_2006-1.pdf\" class=\"gen\">http:\/\/web.upmf-grenoble.fr\/regulation\/wp\/document\/RR_serieI_2006-1.pdf<\/a> <\/p>\n<\/p>\n<p><p>\tComme contribution au d\u00e9bat sur la l\u00e9gitimit\u00e9, un article de 2006 de Fr\u00e9d\u00e9ric Lordon intitul\u00e9 \u00ab<em>La l\u00e9gitimit\u00e9 n&rsquo;existe pas<\/em>\u00bb, qu&rsquo;on prendra au choix comme l&rsquo;effort de coh\u00e9rence doctrinale d&rsquo;un chercheur ou, ou\/et, comme abdication intellectuelle devant l&rsquo;id\u00e9al de puissance. L&rsquo;article fait un trentaine de pages et m\u00e9rite la lecture in extenso.<\/p>\n<\/p>\n<p><p>\tExtrait des conclusions<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Si la vie sous le rapport institutionnel est devenue attristante au point d&rsquo;\u00eatre jug\u00e9e intol\u00e9rable, la loi du conatus conduisant les individus \u00e0 repousser ce qu&rsquo;ils jugent \u00eatre un mal, c&rsquo;est-\u00e0-dire ce qu&rsquo;ils imaginent cause de leur tristesse, les conduit par-l\u00e0 m\u00eame \u00e0 d\u00e9noncer leurs renoncements institutionnels pass\u00e9s : rupture avec l&rsquo;institution et soustraction \u00e0 ses rapports. Pour qu&rsquo;il en soit ainsi, il faut donc que se soit produite une modification brutale dans la balance des affects, un d\u00e9placement soudain de la fronti\u00e8re de l&rsquo;acceptable et de l&rsquo;inacceptable, au terme duquel le sujet prend le risque d&rsquo;affronter des puissances qu&rsquo;il craignait jusqu&rsquo;alors  pas seulement d&rsquo;ailleurs celles de l&rsquo;institution elle-m\u00eame, mais aussi celles de la vie hors de l&rsquo;institution et dont l&rsquo;institution le prot\u00e9geait : qu&rsquo;on pense par exemple \u00e0 la rupture d&rsquo;un rapport salarial qui s&rsquo;effectue toujours au prix des affects de crainte li\u00e9s aux incertitudes frappant \u00e0 nouveau la pers\u00e9v\u00e9rance mat\u00e9rielle. Et si l&rsquo;affect de col\u00e8re contre l&rsquo;institution est suffisamment intense, et surtout suffisamment partag\u00e9 pour d\u00e9cider non plus seulement des fuites individuelles, mais des mises en mouvement collectives, alors peut se former une coalition de puissance s\u00e9ditieuse d\u00e9termin\u00e9e \u00e0 la confrontation avec la puissance institutionnelle.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Il est certain que la puissance et le droit de la cit\u00e9 [de l&rsquo;institution, c&rsquo;est moi qui l&rsquo;ajoute] sont amoindris dans la mesure exacte o\u00f9 elle offre elle-m\u00eame \u00e0 un plus grand nombre de sujets des raisons de se liguer (TP, III, 9). Proposition d\u00e9cisive o\u00f9 se concentre la presque totalit\u00e9 de la vision spinoziste du politique, et o\u00f9 tous les mots comptent : la puissance et le droit, car, oui, puissance et droit sont ici une seule et m\u00eame chose ; amoindris, dans la mesure exacte, un plus grand nombre, car tels sont les mots du quantitativisme universel de la puissance : les forces se mesurent, et de leur bilan d&rsquo;ensemble d\u00e9pendent la stabilit\u00e9 ou le mouvement, la reproduction de l&rsquo;obsequium ou sa rupture, le maintien des rapports institutionnels ou la bifurcation d&rsquo;une trajectoire s\u00e9ditieuse. Il n&rsquo;entre aucune esp\u00e8ce de l\u00e9gitimit\u00e9 l\u00e0-dedans, sinon au travers des id\u00e9es vari\u00e9es que s&rsquo;en font les divers droits naturels rassembl\u00e9s sous l&rsquo;institution, et dont les uns, affect\u00e9s joyeusement, ont avantage \u00e0 sa prolongation, et les autres, affect\u00e9s tristement, d\u00e9sirent la crise. Nul int\u00e9r\u00eat \u00e0 entrer dans ces id\u00e9es-l\u00e0  si ce n&rsquo;est pour rendre compte de leur formation car, faut-il le dire, rompre avec la l\u00e9gitimit\u00e9 ne signifie en rien se d\u00e9sint\u00e9resser de l&rsquo;ordre des productions symboliques, tout au contraire : les hommes ne cessant de juger d&rsquo;apr\u00e8s leurs affects, leurs fabrications imaginaires sont surabondantes quoique l&rsquo;ignorance o\u00f9 ils se trouvent des causes qui les d\u00e9terminent les voue \u00e0 ne produire que des id\u00e9es confuses et mutil\u00e9es.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Sous ce registre que Spinoza nomme la connaissance du premier genre, celles de ces id\u00e9es qui tentent de soutenir des revendications de l\u00e9gitimit\u00e9 sont, comme toutes leurs semblables, les id\u00e9es de droits naturels particuliers et de leurs affects particuliers. On peut donc les regarder dans leur engendrement et leur circulation, et c&rsquo;est m\u00eame tr\u00e8s int\u00e9ressant ; mais rien ne commande d&rsquo;y ajouter foi ou s\u00e9rieux. Or n&rsquo;est-ce pas le risque que court celui qui, n&rsquo;\u00e9tant cens\u00e9ment pas partie aux conflits qu&rsquo;il analyse, se hasarde \u00e0 d\u00e9clarer l\u00e9gitime ceci ou cela ? En revanche, comment sont compos\u00e9s les groupes en pr\u00e9sence et quelles puissances respectives ils rassemblent : c&rsquo;est la seule question qui compte en pratique. C&rsquo;est pourquoi il est sans doute vain de s&rsquo;\u00e9puiser \u00e0 diagnostiquer le devenir des institutions par les crit\u00e8res de la l\u00e9gitimit\u00e9.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Lorsqu&rsquo;une institution entre en crise, c&rsquo;est qu&rsquo;elle a rencontr\u00e9, comme y est expos\u00e9 chaque chose, une chose plus puissante qu&rsquo;elle et qui l&rsquo;a d\u00e9truite  et cette chose, ce peut \u00eatre une partie d&rsquo;elle-m\u00eame qui ne se reconna\u00eet plus sous son rapport caract\u00e9ristique et fait maintenant s\u00e9cession. Ce n&rsquo;est pas que l&rsquo;institution est ill\u00e9gitime. C&rsquo;est qu&rsquo;elle est en passe de succomber.<\/em>\u00bb<\/p>\n<\/p>\n<p>\n<p class=\"signature\"><em>GEO<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lordon et la l\u00e9gitimit\u00e9 http:\/\/web.upmf-grenoble.fr\/regulation\/wp\/document\/RR_serieI_2006-1.pdf Comme contribution au d\u00e9bat sur la l\u00e9gitimit\u00e9, un article de 2006 de Fr\u00e9d\u00e9ric Lordon intitul\u00e9 \u00abLa l\u00e9gitimit\u00e9 n&rsquo;existe pas\u00bb, qu&rsquo;on prendra au choix comme l&rsquo;effort de coh\u00e9rence doctrinale d&rsquo;un chercheur ou, ou\/et, comme abdication intellectuelle devant l&rsquo;id\u00e9al de puissance. L&rsquo;article fait un trentaine de pages et m\u00e9rite la lecture in&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[8809,3555,10306,10308],"class_list":["post-72456","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-geo","tag-legitimite","tag-lordon","tag-spinoza"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72456","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72456"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72456\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72456"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72456"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72456"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}