{"id":72617,"date":"2010-12-28T05:51:08","date_gmt":"2010-12-28T05:51:08","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2010\/12\/28\/dialogues-18-le-systeme-en-dedans-et-en-dehors\/"},"modified":"2010-12-28T05:51:08","modified_gmt":"2010-12-28T05:51:08","slug":"dialogues-18-le-systeme-en-dedans-et-en-dehors","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2010\/12\/28\/dialogues-18-le-systeme-en-dedans-et-en-dehors\/","title":{"rendered":"<em>DIALOGUES<\/em>-18 : Le Syst\u00e8me, en dedans et en dehors"},"content":{"rendered":"<p><h2 class=\"common-article2\"><em>DIALOGUES<\/em>-18 : Le Syst\u00e8me, en dedans et en dehors<\/h2>\n<\/p>\n<p><p>\tCe <em>DIALOGUE<\/em> aura une forme originale Au lieu d&rsquo;\u00eatre une r\u00e9ponse ou un encha\u00eenement au <a href=\"http:\/\/www.dedefensa.org\/article-dialogues-17_le_systeme_et_l_impuissance_temporaire__27_11_2010.html\" class=\"gen\">pr\u00e9c\u00e9dent<\/a>, il prendra, avec l&rsquo;accord de Jean-Paul Baquiast, le biais d&rsquo;une r\u00e9flexion de ce m\u00eame Jean-Paul Baquiast, sur le <em>Forum<\/em> du <a href=\"http:\/\/www.dedefensa.org\/forum-puisque_le_systeme_est_un_bloc__20_12_2010.html\" class=\"gen\">20 d\u00e9cembre 2010<\/a>, du texte <em>Faits &#038; Commentaires<\/em> du m\u00eame <a href=\"http:\/\/www.dedefensa.org\/article-puisque_le_systeme_est_un_bloc__20_12_2010.html\" class=\"gen\">20 d\u00e9cembre 2010<\/a>.<\/p>\n<\/p>\n<p><p>\tLa cause de cette modification de proc\u00e9dure est \u00e0 trouver notamment dans la rapidit\u00e9 des \u00e9v\u00e9nements, qui rend difficile de fixer un propos coh\u00e9rent qui puisse para\u00eetre satisfaisant en \u00e9levant un peu le point de vue par rapport aux soubresauts qui secouent l&rsquo;actualit\u00e9. Il a sembl\u00e9 que ce commentaire, qui rafra\u00eechissait effectivement l&rsquo;intervention pr\u00e9c\u00e9dente, permettait de faire progresser le dialogue<\/p>\n<\/p>\n<p><p>\tVoici les propos de Jean-Paul Baquiast<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Philippe Grasset pose ici une question qui est aussi celle des cosmologistes: si je suis inclus dans l&rsquo;univers, comment puis-je esp\u00e9rer en sortir pour d\u00e9crire cet univers de l&rsquo;ext\u00e9rieur et \u00e0 plus forte raison pour esp\u00e9rer construire (ou mod\u00e9liser) un univers diff\u00e9rent? Je dois dire qu&rsquo;avec l&rsquo;hypoth\u00e8se que j&rsquo;avais moi-m\u00eame formul\u00e9e, relative \u00e0 l&rsquo;existence de syst\u00e8mes anthropotechniques qui nous incluent et nous d\u00e9terminent, je me faisais \u00e0 moi-m\u00eame cette objection: comment, en tant qu&rsquo;\u00e9l\u00e9ment d&rsquo;un syst\u00e8me anthropotechnique tel que celui form\u00e9 par des humains \u00e9troitement imbriqu\u00e9es dans les technologies de la communication (ce que Philippe Grasset qualifie de mati\u00e8re d\u00e9cha\u00een\u00e9e), puis-je prendre assez de recul pour juger ce m\u00eame syst\u00e8me anthropotechnique? Il y aurait sans doute des r\u00e9ponses, mais il serait trop long d&rsquo;en discuter ici.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Concernant l&rsquo;\u00e9pisode CableGate, je peux volontiers admettre avec Philippe Grasset l&rsquo;existence d&rsquo;un Syst\u00e8me global comprenant \u00e0 la fois les Etats et les grands pouvoirs \u00e9conomiques d&rsquo;un c\u00f4t\u00e9, d&rsquo;un autre c\u00f4t\u00e9 les activistes tels Assange tentant de p\u00e9n\u00e9trer et diffuser leurs secrets. Mais dans cette hypoth\u00e8se, il n&rsquo;y a pas les mauvais d&rsquo;un c\u00f4t\u00e9 et les bons de l&rsquo;autre. Les deux groupes de forces apparemment antagonistes se confortent les unes les autres. Les attaques des activistes peuvent laisser croire que les Etats sont p\u00e9n\u00e9trables et ne sont donc pas aussi effrayants qu&rsquo;ils apparaissent. A l&rsquo;inverse, les contre-attaques des Etats \u00e0 l&rsquo;\u00e9gard des activistes, au nom de l&rsquo;autorit\u00e9 viol\u00e9e, renforcent les craintes que peuvent inspirer ces m\u00eames activistes aux d\u00e9fenseurs de l&rsquo;ordre. Ceux qui attaquent et ceux qui d\u00e9fendent les Etats se trouvent donc simultan\u00e9ment encourag\u00e9s. De ce fait le Syst\u00e8me global qui les inclut en sort renforc\u00e9.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Pour Philippe Grasset, ce r\u00e9sultat ne provient pas d&rsquo;une volont\u00e9 d\u00e9lib\u00e9r\u00e9e des Etats ou des activistes. Il provient de l&rsquo;autoactivit\u00e9 d&rsquo;un Syst\u00e8me incapable de se repr\u00e9senter lui-m\u00eame \u00e0 lui-m\u00eame et a fortiori de s&rsquo;autopiloter. Il est compos\u00e9 de multiples forces et sa conduite r\u00e9sulte, non d&rsquo;une conspiration, mais de la dynamique due \u00e0 ces forces (syst\u00e8mes du technologisme et syst\u00e8mes de la communication traduisant le d\u00e9cha\u00eenement de la mati\u00e8re&rsquo;). Il n&rsquo;y a pas de direction humaine, donc il n&rsquo;y a pas de conspiration. Le r\u00e9flexe du &lsquo;secret&rsquo; est de type pavlovien, il d\u00e9coule du fait \u00e9vident que le Syst\u00e8me \u00e9tant par d\u00e9finition ferm\u00e9 et se voulant comme tel, il obture spontan\u00e9ment toutes les entr\u00e9es et sorties possibles Il est constitu\u00e9 de forces publiques, priv\u00e9es, bureaucratiques, m\u00e9diatiques, etc., qui, toutes sont au service de cette dynamique sans savoir quel est le but de cette dynamique, qui sont \u00e0 la fois fascin\u00e9es et entra\u00een\u00e9es par le seul fait de sa puissance (id\u00e9al de puissance&rsquo;). Toutes ces forces et les Sapiens qui s&rsquo;y trouvent ne sont pas mauvais en eux-m\u00eames, mais ils le deviennent d\u00e8s lors qu&rsquo;ils sont dans le Syst\u00e8me.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>Dans ces conditions, nous serions conduits, si nous acceptions ce point de vue syst\u00e9mique, \u00e0 nous m\u00e9fier tout autant des Etats que des activistes. Mais alors comment, \u00e9tant nous-m\u00eames inclus dans ce Syst\u00e8me, en sortir pour le juger voire pour envisager un syst\u00e8me diff\u00e9rent? En sortir consisterait \u00e0 refuser de saisir les informations existantes et refuser d&rsquo;en \u00e9mettre nous m\u00eames de nouvelles, autrement dit \u00e0 nous enfermer dans une sorte de cachot, enti\u00e8rement coup\u00e9 du monde. Il s&rsquo;agirait d&rsquo;un suicide que nous ne ferons pas. Il en r\u00e9sulte que si vous me demandiez ce que devrait \u00eatre un Syst\u00e8me diff\u00e9rent de celui que nous critiquons tous ensemble dans nos rares instants de lucidit\u00e9, je serais incapable de vous r\u00e9pondre. <\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Il nous faudra vivre sans doute ind\u00e9finiment dans un monde comportant \u00e0 la fois des Etats de plus en plus referm\u00e9s sur eux-m\u00eames (ou pratiquant la contre information avec de gros moyens) et des activistes tels que WikiLeaks ou OpenLinks, dont d&rsquo;ailleurs nous serons toujours tent\u00e9s de nous demander pour qui ils roulent. Nous pourrons certes qualifier ce monde du terme de leaky world, mais ce ne sera pas n\u00e9cessairement un compliment. Ce monde sera si leaky et fuyant que nous ne pourrons jamais rien y construire de solide, \u00e0 supposer que nous entretenions encore cette ambition d\u00e9risoire.<\/em>\u00bb<\/p>\n<h3>Notre <em>delenda est Cartago<\/em><\/h3>\n<\/p>\n<p><p>\tJe tenterais d&rsquo;\u00eatre le plus clair possible dans un propos dont je sais qu&rsquo;il peut \u00eatre consid\u00e9r\u00e9 comme tr\u00e8s audacieux voire d\u00e9raisonnable, parce que la clart\u00e9 facilite \u00e9videmment la compr\u00e9hension des choses, m\u00eame et surtout pour soi-m\u00eame ; mais parce que, \u00e9galement, cette clart\u00e9 doit \u00eatre le reflet de la simplicit\u00e9 brutale de la situation selon ce que j&rsquo;en per\u00e7ois. La situation est claire parce qu&rsquo;elle est simple et brutale, m\u00eame si elle pourrait para\u00eetre extraordinaire \u00e0 une pens\u00e9e qui accorde la part essentielle et cr\u00e9atrice de l&rsquo;esprit \u00e0 la raison. Ce dernier point introduit le premier principe de mon intervention, qui est de ne pas accorder la part essentielle et cr\u00e9atrice de l&rsquo;esprit \u00e0 la raison mais de r\u00e9pondre, selon mon appr\u00e9ciation, \u00e0 ce que j&rsquo;estime \u00eatre une intuition haute qui n&rsquo;utilise la raison que comme outil. On pourrait, \u00e0 ce point, s&rsquo;exclamer \u00e0 mon propos : au fou ! ; ce \u00e0 quoi je pourrais r\u00e9pondre : montrez-le, simplement (que je suis fou), mais \u00e0 la condition que ce ne soit pas avec la part essentielle et cr\u00e9atrice de l&rsquo;esprit [donn\u00e9e] \u00e0 la raison, qui s&#8217;empresserait de dire : qui ne raisonne pas comme moi est un fou. Je rejette ce point de vue pour des raisons que je juge excellentes et contre un tel rejet l&rsquo;on n&rsquo;a aucun argument p\u00e9remptoire sinon celui de l&rsquo;anath\u00e8me religieux. J&rsquo;ai d\u00e9j\u00e0 dit pourquoi je n&rsquo;accordais plus la moindre confiance \u00e0 la raison humaine comme part essentielle et cr\u00e9atrice de l&rsquo;esprit, puisque c&rsquo;est contre la cr\u00e9ation mal\u00e9fique \u00e0 laquelle elle a contribu\u00e9 de toutes ses forces que nous luttons tous.<\/p>\n<\/p>\n<p><p>\tD&rsquo;o\u00f9 le deuxi\u00e8me principe, qui concerne cette cr\u00e9ation mal\u00e9fique,  disons le Syst\u00e8me. Dans votre remarque, vous vous interrogez sur le fait de l&rsquo;extr\u00eame difficult\u00e9 de pouvoir sortir de ce Syst\u00e8me pour l&rsquo;examiner. Pour mon compte, mon observation sera tr\u00e8s courte, en ceci qu&rsquo;il me para\u00eet inutile de s&rsquo;attarder \u00e0 cette d\u00e9marche de l&rsquo;examen du Syst\u00e8me ; ma religion,  fa\u00e7on de parler,  est faite, et vite faite, car le temps presse. L\u00e0 aussi, je l&rsquo;ai \u00e9crit et r\u00e9crit avec la plus grande clart\u00e9 possible (voir, par exemple, <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_source_de_tous_les_maux_ddecrisis_10_09_2010.html\" class=\"gen\">La source de tous les maux<\/a>). Je dis et je redis qu&rsquo;il n&rsquo;y a <strong>rien<\/strong>, par d\u00e9finition, de fondamental et de sp\u00e9cifique qui soit r\u00e9formable dans lui, dans notre Syst\u00e8me. Sa destruction, c&rsquo;est notre <em>delenda est Cartago<\/em>. De ce deuxi\u00e8me principe, je d\u00e9duis que le Syst\u00e8me est une chose en soi, d&rsquo;une immense puissance, qui n&rsquo;a besoin d&rsquo;aucun participant ou collaborateur fondamental pour contribuer \u00e0 la formation de la substance de cette puissance, et notamment pas les <em>sapiens<\/em>, qui figurent dans la pi\u00e8ce comme des comparses, des acteurs de figuration et ainsi de suite, et des prisonniers bien s\u00fbr,   bref, qui ne sont rien de <strong>substantiel<\/strong> et ne peuvent par cons\u00e9quent tenir aucun r\u00f4le substantiel dans le Syst\u00e8me,  n\u00e9gligeables par d\u00e9finition, pouvant passer d&rsquo;un c\u00f4t\u00e9 ou de l&rsquo;autre, taillables et corv\u00e9ables \u00e0 merci et ainsi de suite..<\/p>\n<\/p>\n<p><p>\tIl y a une multitude d&rsquo;attitudes chez les <em>sapiens<\/em> qui d\u00e9fendent le Syst\u00e8me, autant que chez ceux qui attaquent le Syst\u00e8me. Ils le font tous au nom d&rsquo;une infinit\u00e9 de raisons, conformistes, int\u00e9ress\u00e9es, id\u00e9ologiques et religieuses, passionnelles et vaniteuses, etc. Pour ce qui est de l&rsquo;appr\u00e9ciation critique du Syst\u00e8me, je n&rsquo;ai gu\u00e8re rencontr\u00e9, dans les raisonnements g\u00e9n\u00e9raux, dans les appr\u00e9ciations de combat, dans les prises de position politiques, l&rsquo;argument suprarationnel ou m\u00e9taphysique du Syst\u00e8me, cr\u00e9ation mal\u00e9fique de ce que je nomme pour mon compte le d\u00e9cha\u00eenement de la mati\u00e8re et la source de tous les maux. Pour retrouver une logique acceptable dans ce cadre que je propose, il faut se hausser au niveau de la m\u00e9taphysique et accepter les orientations de l&rsquo;intuition haute. C&rsquo;est ce que je fais, \u00e0 mes risques et p\u00e9rils, mais aussi avec mes arguments contre lesquels la raison avec sa part essentielle et cr\u00e9atrice n&rsquo;a, selon mon point de vue, nulle chose convaincante \u00e0 m&rsquo;offrir dans le spectacle du monde o\u00f9 sa responsabilit\u00e9 est si profond\u00e9ment engag\u00e9e. (Dialogues : Au fou !,  Montrez-le, simplement)<\/p>\n<h3>Du Syst\u00e8me au Syst\u00e8me-en-soi<\/h3>\n<\/p>\n<p><p>\tVous \u00e9crivez : \u00ab<em>Les deux groupes de forces apparemment antagonistes se confortent les unes les autres. Les attaques des activistes peuvent laisser croire que les Etats sont p\u00e9n\u00e9trables et ne sont donc pas aussi effrayants qu&rsquo;ils apparaissent. A l&rsquo;inverse, les contre-attaques des Etats \u00e0 l&rsquo;\u00e9gard des activistes, au nom de l&rsquo;autorit\u00e9 viol\u00e9e, renforcent les craintes que peuvent inspirer ces m\u00eames activistes aux d\u00e9fenseurs de l&rsquo;ordre. Ceux qui attaquent et ceux qui d\u00e9fendent les Etats se trouvent donc simultan\u00e9ment encourag\u00e9s. De ce fait le Syst\u00e8me global qui les inclut en sort renforc\u00e9.<\/em>\u00bb <\/p>\n<\/p>\n<p><p>\tJe comprends sans aucun doute votre logique mais j&rsquo;ai pour ma part une autre perception, et une vision diff\u00e9rente par cons\u00e9quent. Il n&rsquo;y a aucune logique g\u00e9n\u00e9rale, aucun plan, aucune construction dans les attaques des uns et les contre-attaques des autres. Chacun agit selon la logique interne de son groupe, sans r\u00e9el souci de la r\u00e9alit\u00e9 du Syst\u00e8me si seulement il en a conscience,  Syst\u00e8me, ou bien disons plus lourdement pour ce propos, Syst\u00e8me-en-soi, pour bien le d\u00e9terminer comme une chose absolument sp\u00e9cifique (devenue absolument sp\u00e9cifique) ; pourtant chacun est <strong>absolument<\/strong> et <strong>compl\u00e8tement<\/strong> influenc\u00e9 par ce Syst\u00e8me-en-soi qui n&rsquo;a aucune coh\u00e9rence humaine, aucune logique humaine, qui r\u00e9pond en fait \u00e0 l&rsquo;impulsion de son \u00e9norme puissance n\u00e9e du d\u00e9cha\u00eenement de la mati\u00e8re. C&rsquo;est pourquoi, par exemple, je dis et ne cesse de r\u00e9p\u00e9ter que les <a href=\"http:\/\/www.dedefensa.org\/article-des_systemes_antisystemes_aux_systemes_antisysteme__10_12_2010.html\" class=\"gen\">syst\u00e8mes antiSyst\u00e8me<\/a> se forment sans aucune conscience du fait, de la part de ceux qui en font partie. Rien ne peut \u00eatre class\u00e9 selon une logique de combat, en termes humains d&rsquo;affrontement, comme si chaque c\u00f4t\u00e9 avait un plan, une ambition tactique, une conqu\u00eate \u00e0 faire o\u00f9 installer de nouvelles ambitions ; et, de m\u00eame, est-il si difficile de distinguer s&rsquo;il y a vraiment, du point de vue humain, un c\u00f4t\u00e9 contre un autre c\u00f4t\u00e9. Tout cela n&rsquo;a gu\u00e8re d&rsquo;importance en soi puisqu&rsquo;il y a le Syst\u00e8me-en-soi, qui r\u00e8gle tout, justifie tout, qui donne tout son sens aux choses en apparence absurdes ou vaines que nous faisons, et que ce Syst\u00e8me-en-soi se suffit \u00e0 lui-m\u00eame pour utiliser \u00e9ventuellement ces choses en apparence absurdes ou vaines que nous faisons contre lui-m\u00eame, dans son processus d&rsquo;autodestruction d&rsquo;une \u00e9norme puissance<\/p>\n<\/p>\n<p><p>\tIl est manifeste que si le Syst\u00e8me avait pu suivre le conseil de William Kristol (voir le <a href=\"http:\/\/www.dedefensa.org\/article-le_systeme_se_decouvre_et_hurle_de_fureur_04_12_2010.html\" class=\"gen\">4 d\u00e9cembre 2010<\/a> : \u00ab<em>From now on, a policy of no comment about anything in any of these documents should be the absolute rule. No apologies, no complaints, no explanations, no excuses. No present or former government official should deign to discuss anything in these documents. No one in the executive branch should confirm or deny the accuracy of any document<\/em>\u00bb), l&rsquo;affaire <em>WikiLeaks<\/em>&#8211;<em>Cablegate<\/em>-Assange ne serait jamais devenue ce qu&rsquo;elle est, son importance r\u00e9duite d\u00e8s le d\u00e9part par l&rsquo;influence \u00e9norme exerc\u00e9e par cette indiff\u00e9rence feinte du Syst\u00e8me Mais le Syst\u00e8me a ripost\u00e9  et il a fait de <em>WikiLeaks<\/em> une crise nomm\u00e9 <em>Cablegate<\/em>, dont la puissance est consid\u00e9rable et les effets encore \u00e0 mesurer pendant longtemps. En d\u00e9ployant toute sa puissance, le Syst\u00e8me ne s&rsquo;est pas renforc\u00e9, il s&rsquo;est <strong>encore<\/strong> affaibli en retournant sa puissance contre lui-m\u00eame. Il nous a montr\u00e9 que c&rsquo;est bien cela qu&rsquo;il faut attaquer sans plan pr\u00e9con\u00e7u, en la provoquant, en d\u00e9fiant cette puissance pour la retourner contre elle, cette \u00e9norme puissance aveugle qui ne vit que pour se d\u00e9cha\u00eener aveugl\u00e9ment, et qui se d\u00e9chaine aveugl\u00e9ment contre elle-m\u00eame puisque l&rsquo;occasion est bonne&#8230; <\/p>\n<\/p>\n<p><p>\tTout se passe de la sorte, selon une gamme sans fin de sophistication. Si vous prenez la situation objective de la menace d&rsquo;attaque contre l&rsquo;Iran, qui est \u00e9videmment une offensive du Syst\u00e8me (syst\u00e8me de la communication et virtualisme dans ce cas, mais cela a autant de poids qu&rsquo;en d&rsquo;autres domaines), vous voyez bien que le Syst\u00e8me ne cesse de s&rsquo;y \u00e9puiser <strong>tout seul<\/strong>, sans qu&rsquo;il importe de savoir s&rsquo;il y aura attaque ou pas. Ce qu&rsquo;il importe de savoir par contre, c&rsquo;est, comme l&rsquo;envisagent Flynt and Hillary Mann Leverett de la New American Foundation, (le <a href=\"http:\/\/www.huffingtonpost.com\/flynt-and-hillary-mann-leverett\/post_1480_b_800972.html\" class=\"gen\">23 d\u00e9cembre 2010<\/a> sur <em>Huffington.post<\/em>), si le parti r\u00e9publicain ne va pas \u00e9clater sur cette question,  et dans ce cas, si je fais de <em>Tea Party<\/em> un syst\u00e8me antiSyst\u00e8me, je ne le consid\u00e8re certainement pas comme un artefact politique se percevant comme anti-am\u00e9ricaniste (\u00ab<em>Interestingly, one of the few pockets of politically engaged people in the United States who are prepared to raise serious questions about the wisdom of another ill-conceived U.S. military adventure in the Middle East is found within the Tea Party movement <\/em>[] <em>the Tea Party is, in fact, deeply divided on foreign policy<\/em>\u00bb)  <\/p>\n<\/p>\n<p><p>\tIl n&rsquo;y a aucune bataille rang\u00e9e, ceux du Syst\u00e8me contre les adversaires du Syst\u00e8me. Il y a le Syst\u00e8me-en-soi, et, autour, une multitude d&rsquo;agitations dans tous les sens, des forces en action dans diverses directions, des int\u00e9r\u00eats divers, des manipulations, etc. ; la r\u00e9sultante \u00e9vidente en est de plus en plus le grippage et les interf\u00e9rences terrifiantes dans le m\u00e9canisme du Syst\u00e8me. L&rsquo;on sait bien, ou l&rsquo;on devrait le savoir apr\u00e8s l&rsquo;avoir observ\u00e9, que les centres de pouvoir \u00e0 l&rsquo;int\u00e9rieur du Syst\u00e8me-en-soi sont aussi des concurrents entre eux, et parfois des concurrents jusqu&rsquo;\u00e0 la mort. Ces m\u00eames centres sont, seuls avec eux-m\u00eames, autodestructeurs. L&rsquo;\u00e9tat proche de l&rsquo;effondrement du Pentagone, et celui du JSF \u00e0 l&rsquo;int\u00e9rieur du Pentagone, ne sont dus essentiellement \u00e0 aucune attaque ext\u00e9rieure de quiconque. C&rsquo;est cette logique d&rsquo;agression avec effets indirects qu&rsquo;il nous faut suivre, sans plus chercher avant ce qui viendra ensuite ; il faut le faire parce qu&rsquo;il en va de l&rsquo;ultime avatar de l&rsquo;esp\u00e8ce.<\/p>\n<\/p>\n<p><p>\tCe qui nous conduit \u00e0 votre remarque suivante.<\/p>\n<h3>L&rsquo;effondrement du Syst\u00e8me-en-soi nous donnera la clef de l&rsquo;\u00e9nigme<\/h3>\n<\/p>\n<p><p>\tVous vous posez la question : comment trouver une alternative au Syst\u00e8me si nous ne pouvons sortir du Syst\u00e8me ? <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Mais alors comment, \u00e9tant nous-m\u00eames inclus dans ce Syst\u00e8me, en sortir pour le juger voire pour envisager un syst\u00e8me diff\u00e9rent? En sortir consisterait \u00e0 refuser de saisir les informations existantes et refuser d&rsquo;en \u00e9mettre nous m\u00eames de nouvelles, autrement dit \u00e0 nous enfermer dans une sorte de cachot, enti\u00e8rement coup\u00e9 du monde. Il s&rsquo;agirait d&rsquo;un suicide que nous ne ferons pas. Il en r\u00e9sulte que si vous me demandiez ce que devrait \u00eatre un Syst\u00e8me diff\u00e9rent de celui que nous critiquons tous ensemble dans nos rares instants de lucidit\u00e9, je serais incapable de vous r\u00e9pondre.<\/em>\u00bb <\/p>\n<\/p>\n<p><p>\tNous sommes tous \u00e0 l&rsquo;int\u00e9rieur du Syst\u00e8me parce qu&rsquo;aujourd&rsquo;hui le Syst\u00e8me est <strong>tout<\/strong> dans notre vie mat\u00e9rielle, dans l&rsquo;organisation mat\u00e9rielle du monde, et, par cons\u00e9quent, dans ce que ce mat\u00e9rialisme fait peser sur nos pens\u00e9es. Cela est un fait qui justifie vos alarmes mais qui, paradoxalement, me conduit \u00e0 des observations qui r\u00e9duisent notablement l&rsquo;importance de ces alarmes. Puisqu&rsquo;il en est ainsi, puisque la Syst\u00e8me-en-soi est tout, qu&rsquo;il n&rsquo;est que mati\u00e8re et mat\u00e9rialisme qui gouvernent absolument les pens\u00e9es dominantes et imp\u00e9ratives de notre civilisation, il est totalement inutile de songer \u00e0 investiguer \u00e0 son propos, \u00e0 le juger comme vous dites, parce que l&rsquo;\u00e9vidence a d\u00e9j\u00e0 dict\u00e9 le jugement objectif \u00e0 cet \u00e9gard. Ce Syst\u00e8me-en-soi est le Mal-en-soi, et nul besoin de s&rsquo;en \u00e9loigner pour le contempler et en juger ; au contraire, y rester, l&rsquo;\u00e9couter, recueillir ses informations, trouver ses nombreux talons d&rsquo;Achille de ses diverses tentacules, en user pour l&rsquo;attaquer et l&rsquo;attaquer encore.<\/p>\n<\/p>\n<p><p>\tQuant \u00e0 chercher quelque chose \u00e0 mettre \u00e0 la place du Syst\u00e8me-en-soi qui est tout, c&rsquo;est non seulement une t\u00e2che impossible mais une t\u00e2che illogique. Le Syst\u00e8me \u00e9tant tout et ayant la puissance qu&rsquo;on sait, tout ce que vous pourriez imaginer ne ferait qu&#8217;emprunter des \u00e9l\u00e9ments fondamentaux du Syst\u00e8me, donc repartir sur une voie faussaire qui ne ferait que nous faire retomber sur une autre version du m\u00eame Syst\u00e8me. Il faut attendre que le Syst\u00e8me parvienne \u00e0 un \u00e9tat de d\u00e9labrement et d&rsquo;autodestruction telle qu&rsquo;il acc\u00e9l\u00e8re son effondrement par l&rsquo;un ou l&rsquo;autre \u00e9v\u00e9nement d\u00e9cisif (bien entendu, je ne saurais dire lequel) qui, soudain, m\u00e9nagerait une ouverture hors de son emprise. C&rsquo;est lui, le Syst\u00e8me-en-soi, qui, en s&rsquo;effondrant, nous donnera la solution de l&rsquo;\u00e9nigme.<\/p>\n<\/p>\n<p><p>\tMa conviction, que j&rsquo;estime \u00eatre n\u00e9e sous l&rsquo;inspiration de l&rsquo;intuition haute, est absolue \u00e0 cet \u00e9gard. La d\u00e9gradation et l&rsquo;effondrement du Syst\u00e8me sont si rapides que de tels prolongements sont in\u00e9luctables. (Songez \u00e0 la rapidit\u00e9 des choses : Pour 99% des commentateurs, l&rsquo;arriv\u00e9e d&rsquo;Obama annon\u00e7ait une certaine reprise en mains des affaires am\u00e9ricanistes, centre et moteur du Syst\u00e8me ; voyez la d\u00e9gradation qu&rsquo;Obama a amen\u00e9e dans l&rsquo;\u00e9tat du Syst\u00e8me, en <strong>acc\u00e9l\u00e9rant<\/strong> le travail de destruction de GW Bush)<\/p>\n<h3>Il n&rsquo;y a <strong>rien<\/strong> \u00e0 perdre, hormis le pire.<\/h3>\n<\/p>\n<p><p>\tEnfin, vous dites ceci (je souligne de gras le membre de phrase qui me para\u00eet important, notamment pour mener \u00e0 mon propos) :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Il nous faudra vivre sans doute ind\u00e9finiment dans un monde comportant \u00e0 la fois des Etats de plus en plus referm\u00e9s sur eux-m\u00eames (ou pratiquant la contre information avec de gros moyens) et des activistes tels que WikiLeaks ou OpenLinks, dont d&rsquo;ailleurs nous serons toujours tent\u00e9s de nous demander pour qui ils roulent. Nous pourrons certes qualifier ce monde du terme de leaky world, mais ce ne sera pas n\u00e9cessairement un compliment.<\/em> <strong><em>Ce monde sera si leaky et fuyant que nous ne pourrons jamais rien y construire de solide, \u00e0 supposer que nous entretenions encore cette ambition d\u00e9risoire.<\/em><\/strong>\u00bb<\/p>\n<\/p>\n<p><p>\tIl ne nous faut pas vivre dans un monde, fut-il <em>leaky<\/em>, parce que le fait est que nous vivons dans un Syst\u00e8me-en-soi, incoh\u00e9rent pour l&rsquo;entendement humain courant mais bien identifiable pour ce qu&rsquo;il est, sans aucun doute par l&rsquo;intuition haute. Il est nihiliste, il n&rsquo;est men\u00e9 que par sa dynamique de puissance, par l&rsquo;omnipr\u00e9sence de la mati\u00e8re sur l&rsquo;esprit, par tous les artifices possibles, y compris celui d&rsquo;id\u00e9es toutes faites pour justifier sa pr\u00e9sence, son action et sa raison d&rsquo;\u00eatre. Peu importe qui dit quoi et qui fait quoi, qui dit vrai et qui ne dit pas vrai, l&rsquo;essentiel est de distinguer ce qui porte des coups au Syst\u00e8me-en-soi et acc\u00e9l\u00e8re ses processus internes de d\u00e9gradation, d&rsquo;effondrement et d&rsquo;autodestruction. Le Syst\u00e8me-en-soi est la seule r\u00e9f\u00e9rence s\u00fbre, elle est celle du Mal, et tout ce qui va contre lui trouve ainsi sa justification.<\/p>\n<\/p>\n<p><p>\tIl ne s&rsquo;agit pas d&rsquo;une bataille politique, ou d&rsquo;une bataille id\u00e9ologique, il s&rsquo;agit d&rsquo;un bouleversement eschatologique qui engage la civilisation elle-m\u00eame, et sans doute m\u00eame plus encore. L&rsquo;essentiel n&rsquo;est pas de distinguer qui est l&rsquo;ennemi et qui est l&rsquo;ami, mais qui fait le plus de mal au Syst\u00e8me-en-soi Le JSF n&rsquo;est pas mon ami et, politiquement, je souhaiterais sa chute ; mais je souhaite aussi, objectivement dirais-je, qu&rsquo;ils poursuivent son d\u00e9veloppement (!) car la catastrophe \u00e0 laquelle aboutira ce d\u00e9veloppement sera encore plus terrible demain qu&rsquo;aujourd&rsquo;hui, et plus terrible encore apr\u00e8s-demain, mena\u00e7ant d&rsquo;y entra\u00eener le Pentagone lui-m\u00eame. M\u00eame chose pour l&rsquo;Afghanistan : politiquement, nous r\u00e9clamons tous le retrait, mais objectivement, je dirais m\u00eame eschatologiquement, chaque jour pass\u00e9 l\u00e0-bas accentue encore le processus de d\u00e9sagr\u00e9gation et de d\u00e9sint\u00e9gration du syst\u00e8me<\/p>\n<\/p>\n<p><p>\tCe monde est <em>leaky<\/em> pour nous,  mais qu&rsquo;importe nous-m\u00eames dans le monde, nos petites querelles de chapelles, nos d\u00e9bats sur ceci et sur cela&#8230; Ce qui nous importe, c&rsquo;est le Syst\u00e8me-en-soi et lui devient effectivement de moins en moins homog\u00e8ne, de plus en plus dissolu (dans le sens que sa structure mat\u00e9rialiste se dissout), \u00e0 mesure que le monde devient de plus en plus <em>leaky<\/em>, parce que le Syst\u00e8me-en-soi a besoin de structures solides pour conduire \u00e0 terme sa mission de d\u00e9structuration totalitaire. Que nous ne construisions rien de solide <strong>pour l&rsquo;instant<\/strong> n&rsquo;importe pas puisque ce qui importe est que, lui, il se d\u00e9solidifie ; pour nous, par l&rsquo;\u00e9vidence m\u00eame, rien de solide ne peut se faire sur la chose en cours de d\u00e9solidification<\/p>\n<\/p>\n<p><p>\tQue pouvons-nous craindre de ce processus de d\u00e9solidification ? Le d\u00e9sordre et le chaos ?  L&rsquo;ignorance et la sottise ? La mis\u00e8re et l&rsquo;\u00e9conomisme d\u00e9cha\u00een\u00e9 ? La tromperie et le virtualisme ? La bassesse et la m\u00e9diocrit\u00e9 ? <em>Le r\u00e8gne de la quantit\u00e9<\/em> (Ren\u00e9 Gu\u00e9non) ?&#8230; Mais si nous nous consid\u00e9rons dans la perspective m\u00e9tahistorique et chronologique qui importe, nous n&rsquo;avons, aujourd&rsquo;hui, rien, <strong>absolument rien<\/strong> d&rsquo;autre que ces diverses situations. En v\u00e9rit\u00e9, la formule n&rsquo;a jamais \u00e9t\u00e9 si juste : il n&rsquo;y a <strong>rien<\/strong> \u00e0 perdre, hormis le pire.<\/p>\n<h3>L&rsquo;in\u00e9vitable r\u00e9f\u00e9rence m\u00e9taphysique<\/h3>\n<\/p>\n<p><p>\tMais tout cela n&rsquo;est encore rien s&rsquo;il n&rsquo;y avait le reste, qui est une n\u00e9cessaire tentative d&rsquo;explication g\u00e9n\u00e9rale Il faut en venir aux hypoth\u00e8ses concernant le Syst\u00e8me-en-soi. Lui, ce n&rsquo;est pas vraiment notre ennemi, comme s&rsquo;il y avait guerre, soit une guerre en dentelles soit une guerre r\u00e9volutionnaire, avec possibilit\u00e9 de victoire, d&rsquo;armistice, d&rsquo;arrangement ou de paix, comme s&rsquo;il y avait affrontement avec un adversaire \u00e0 notre mesure et chacun choisissant son camp, tout cela ordonn\u00e9 bien entendu par notre sacro-sainte raison humaine, chacun sachant qui est qui et comment vont les choses. Il s&rsquo;agit de la mati\u00e8re ayant atteint une forme de sophistication suffisante pour animer une dynamique d\u00e9vastatrice, qui semble poss\u00e9der les attributs pour conduire cette dynamique, y compris une psychologie propre et une sorte d&rsquo;autonomie, et qui menace effectivement la destruction par la d\u00e9structuration, jusqu&rsquo;\u00e0 l&rsquo;entropie, de l&rsquo;organisation de l&rsquo;univers. Nous sommes d\u00e9finitivement sortis de l&rsquo;histoire pour \u00e9voluer dans l&rsquo;Histoire et dans sa dimension m\u00e9tahistorique, et \u00eatre confront\u00e9s aux \u00e9v\u00e9nements fondamentaux. Les d\u00e9finitions et les mesures courantes n&rsquo;ont plus cours.<\/p>\n<\/p>\n<p><p>\tEncore une fois, je n&rsquo;avance nulle preuve ni ne m&rsquo;attache \u00e0 la moindre d\u00e9monstration, qui sont de peu d&rsquo;int\u00e9r\u00eat pour moi dans une t\u00e2che d&rsquo;analyse qui se s\u00e9pare n\u00e9cessairement du standard. Je vous parle sous l&#8217;empire de l&rsquo;intuition haute, sans rien d\u00e9couvrir d&rsquo;essentiel dans la situation du monde qui contrarie ce choix que j&rsquo;ai fait et la perception qui en r\u00e9sulte. (Au fou !,  Montrez-le, simplement) Quel temps plus que le n\u00f4tre, je vous le demande, n&rsquo;autorise, ne recommande, ne justifie cette sorte d&rsquo;audace de la pens\u00e9e, sinon n&rsquo;y pousse absolument,  et quel signe le plus s\u00fbr \u00e0 cet \u00e9gard que la censure \u00e0 la fois implicite et hyst\u00e9rique appliqu\u00e9e par le Syst\u00e8me contre cette sorte d&rsquo;audace de la pens\u00e9e ? (Le syst\u00e8me se fiche bien des pens\u00e9es \u00e9sot\u00e9riques, voire des substituts de religiosit\u00e9  mises au go\u00fbt du jour postmodernistes, qui ne sont que des imitations \u00e9videmment faussaires des restes de la Tradition, mais nullement que vous l&rsquo;attaquiez, lui, directement, avec des arguments \u00e9chappant \u00e0 l&#8217;empire du d\u00e9cha\u00eenement de la mati\u00e8re, ou de son auxiliaire qu&rsquo;est la raison humaine asservie par sa propre perversion Cela s&rsquo;appelle un exorcisme, et il le sait bien.) Enfin, et plus que tout, quelle voie autre que celle-l\u00e0, celle de l&rsquo;intuition haute, pour sortir du Syst\u00e8me comme vous r\u00e9clamez que l&rsquo;on puisse faire, mais par le Haut bien entendu, pour pouvoir appr\u00e9cier pour ce qu&rsquo;elle est en v\u00e9rit\u00e9 cette chose monstrueuse et voir ce confirmer le jugement port\u00e9 sur elle.<\/p>\n<\/p>\n<p><p>\tIl est bien vrai que ma perception est bien que nous sommes sortis des normes de l&rsquo;histoire selon la vision conventionnelle qu&rsquo;en a la raison humaine, pour embrasser des conditions nouvelles. (Pas des conditions surnaturelles, non, je dis bien nouvelles ; surnaturelles impliquerait que nous prenions le terme naturel de r\u00e9f\u00e9rence selon les normes que notre raison d\u00e9voy\u00e9e par la mati\u00e8re d\u00e9cha\u00een\u00e9e nous impose,  et quant \u00e0 moi, cette raison-l\u00e0 n&rsquo;est plus ma r\u00e9f\u00e9rence, au spectacle du chaos de l&rsquo;univers engendr\u00e9 par cette mati\u00e8re d\u00e9cha\u00een\u00e9e avec elle, la raison, subvertie par cette mati\u00e8re d\u00e9cha\u00een\u00e9e.) C&rsquo;est pour cette raison que je ne cesse de mettre en avant ces diverses positions et ces divers arguments \u00e0 l&rsquo;encontre de cette raison humaine-l\u00e0, telle qu&rsquo;elle s&rsquo;est d\u00e9voy\u00e9e et dont la f\u00e9lonie est av\u00e9r\u00e9e, que je ne cesse de faire appel \u00e0 ces r\u00e9f\u00e9rences \u00e0 la m\u00e9taphysique qui peut elle seule \u00e9lever le regard jusqu&rsquo;\u00e0 la rencontre de l&rsquo;intuition haute, que je ne cesse de tenter d&rsquo;\u00e9clairer le champ du politique \u00e0 la lumi\u00e8re de ce que je pense \u00eatre cette intuition haute. Si nous ne faisons pas cela dans notre vision g\u00e9n\u00e9rale de cette crise immense et sans pr\u00e9c\u00e9dent, notre raison humaine ach\u00e8vera de se perdre dans sa perversion essentielle depuis les quelques si\u00e8cles de la modernit\u00e9, ou elle sombrera dans la folie,  ou les deux, certes, puisque l&rsquo;un et l&rsquo;autre s&rsquo;\u00e9quivalent.<\/p>\n<\/p>\n<p><p>\tLe Syst\u00e8me-en-soi,  ou appelez-le autrement, y compris de son nom initial de d\u00e9cha\u00eenement de la mati\u00e8re,  n&rsquo;est en rien une cr\u00e9ation humaine ; il d\u00e9passe l&rsquo;humain par cons\u00e9quent, et c&rsquo;est en fonction de cela que nous nous devons de l&rsquo;appr\u00e9cier. Il est la marque de la part sombre de l&rsquo;univers, l&rsquo;un des partis dans un affrontement d\u00e9cisif entre des forces elles-m\u00eames d\u00e9cisives dans l&rsquo;histoire de l&rsquo;univers. C&rsquo;est \u00e0 partir de tels cadres de r\u00e9f\u00e9rences, sans chercher n\u00e9cessairement \u00e0 en juger plus <strong>pr\u00e9cis\u00e9ment<\/strong> sur les constituants du ph\u00e9nom\u00e8ne pour \u00e9viter les querelles th\u00e9ologiques sur le sexe des anges, qu&rsquo;il nous faut juger <strong>g\u00e9n\u00e9ralement<\/strong> de la situation dans son ensemble que nous connaissons dans ce temps m\u00e9tahistorique.<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Philippe Grasset<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DIALOGUES-18 : Le Syst\u00e8me, en dedans et en dehors Ce DIALOGUE aura une forme originale Au lieu d&rsquo;\u00eatre une r\u00e9ponse ou un encha\u00eenement au pr\u00e9c\u00e9dent, il prendra, avec l&rsquo;accord de Jean-Paul Baquiast, le biais d&rsquo;une r\u00e9flexion de ce m\u00eame Jean-Paul Baquiast, sur le Forum du 20 d\u00e9cembre 2010, du texte Faits &#038; Commentaires du m\u00eame&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[15],"tags":[2631,8854,9772,5714,10628,2622,8855,10626,2673,7658,3014,10627,6750],"class_list":["post-72617","post","type-post","status-publish","format-standard","hentry","category-dialogues","tag-de","tag-dechainement","tag-guenon","tag-haute","tag-intuitiion","tag-la","tag-matiere","tag-metahistoriques","tag-metaphysique","tag-rene","tag-systeme","tag-systeme-en-soi","tag-temps"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72617"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72617\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}