{"id":72629,"date":"2011-01-03T06:34:41","date_gmt":"2011-01-03T06:34:41","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/01\/03\/les-pronostics-a-court-terme-de-jacques-sapir\/"},"modified":"2011-01-03T06:34:41","modified_gmt":"2011-01-03T06:34:41","slug":"les-pronostics-a-court-terme-de-jacques-sapir","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/01\/03\/les-pronostics-a-court-terme-de-jacques-sapir\/","title":{"rendered":"Les pronostics \u00e0 court terme de Jacques Sapir"},"content":{"rendered":"<p><h4>Les pronostics \u00e0 court terme de Jacques Sapir<\/h4>\n<p><a href=\"http:\/\/www.marianne2.fr\/L-euro-peut-il-survivre-a-la-crise-1-3_a201114.html\" class=\"gen\"> http:\/\/www.marianne2.fr\/L-euro-peut-il-survivre-a-la-crise-1-3_a201114.html<\/a><\/p>\n<\/p>\n<p><p>\t[] \u00ab[C]<em>eci signifie que les attaques des march\u00e9s reprendront d\u00e8s la \u00ab tr\u00eave des confiseurs \u00bb achev\u00e9e. La possibilit\u00e9 que les diff\u00e9rents pays repassent sous la limite des 3% de d\u00e9ficit d&rsquo;ici 2013 est en effet tout simplement nulle. D&rsquo;ailleurs, on constate sur le tableau que cette limite, serait tr\u00e8s insuffisante pour stabiliser la dette en niveau, sauf une forte croissance qui est exclue en raison m\u00eame de ces politiques d&rsquo;ajustements.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Le mouvement est trop g\u00e9n\u00e9ral pour \u00eatre ni\u00e9. Le fait que la R\u00e9publique Tch\u00e8que ait annonc\u00e9 qu&rsquo;elle ne souhaitait pas rejoindre l&rsquo;euro en t\u00e9moigne. \u00c0 part une \u00ab zone Mark \u00bb, incluant les Pays-Bas et la Finlande, on ne voit gu\u00e8re de pays qui soit \u00e9pargn\u00e9. Il est donc faux de vouloir limiter la crise de l&rsquo;euro \u00e0 celle de pays dits p\u00e9riph\u00e9riques. C&rsquo;est bien le cur du m\u00e9canisme de la monnaie unique qui est touch\u00e9.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>M\u00eame si l&rsquo;on arrivait \u00e0 contenir la crise des pays p\u00e9riph\u00e9riques (dont le PIB est assez faible en ce qui concerne la Gr\u00e8ce et le Portugal), on voit dans ces deux graphiques que le ph\u00e9nom\u00e8ne de contamination a jou\u00e9s \u00e0 plein et touche d\u00e9sormais des pays dont la taille et l&rsquo;importance excluent des mesures passag\u00e8res.<\/em>\u00bb <\/p>\n<\/p>\n<p><p>\tEn guise de voeux \u00e9conomiques, sans doute.<\/p>\n<\/p>\n<p>\n<p class=\"signature\"><em>GEO<\/em><\/p>\n<\/p>\n<p><p>\tPS: Meilleurs vux \u00e0 tous quoiqu&rsquo;il en soit.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les pronostics \u00e0 court terme de Jacques Sapir http:\/\/www.marianne2.fr\/L-euro-peut-il-survivre-a-la-crise-1-3_a201114.html [] \u00ab[C]eci signifie que les attaques des march\u00e9s reprendront d\u00e8s la \u00ab tr\u00eave des confiseurs \u00bb achev\u00e9e. La possibilit\u00e9 que les diff\u00e9rents pays repassent sous la limite des 3% de d\u00e9ficit d&rsquo;ici 2013 est en effet tout simplement nulle. D&rsquo;ailleurs, on constate sur le tableau que&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3228,3397,398,8809,6647,7823],"class_list":["post-72629","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-crise","tag-euro","tag-europe","tag-geo","tag-jacques","tag-sapir"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72629"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72629\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}