{"id":72641,"date":"2011-01-06T15:44:02","date_gmt":"2011-01-06T15:44:02","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/01\/06\/levolution-par-les-armes\/"},"modified":"2011-01-06T15:44:02","modified_gmt":"2011-01-06T15:44:02","slug":"levolution-par-les-armes","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/01\/06\/levolution-par-les-armes\/","title":{"rendered":"L&rsquo;\u00e9volution par les armes"},"content":{"rendered":"<p><h2 class=\"common-article\">L&rsquo;\u00e9volution par les armes<\/h2>\n<\/p>\n<p><p>\t6 janvier 2010  Dans notre <em>F&#038;C<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-l_hegemonie_au_gre_de_la_furtivite__31_12_2010.html\" class=\"gen\">31 d\u00e9cembre 2010<\/a> consacr\u00e9 aux nouveaux avions de combat chinois et russes, nous laissions de c\u00f4t\u00e9 la probl\u00e9matique europ\u00e9enne soulev\u00e9e \u00e9ventuellement par cette nouvelle, avec cette observation, qui valait promesse :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>La comparaison est ici limit\u00e9e entre les USA et le bloc Chine-Russie, selon une approche essentiellement strat\u00e9gique h\u00e9rit\u00e9e de la Guerre froide, en mettant \u00e0 part l&rsquo;Europe. Nous devrions proposer prochainement une analyse de la position europ\u00e9enne en fonction de ces nouveaut\u00e9s russes et chinoises.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tNous allons donc essayer d&rsquo;envisager une \u00e9ventuelle \u00e9volution europ\u00e9enne, ou de certains pays d&rsquo;Europe, en fonction de l&rsquo;\u00e9volution que nous constations et envisagions dans ce <em>F&#038;C<\/em>. Auparavant, signalons plusieurs faits,  dont un sera un rappel d&rsquo;une information fort peu connue, jamais confirm\u00e9e officiellement, que nous tenons d&rsquo;une source que nous consid\u00e9rons comme s\u00fbre.<\/p>\n<\/p>\n<p><p>\t La question de la lev\u00e9e de l&#8217;embargo des armes impos\u00e9 par l&rsquo;UE contre la Chine depuis 1989 devient un sujet br\u00fblant. Une d\u00e9p\u00eache AFP, via <em>Spacewar.com<\/em>, le <a href=\"http:\/\/www.spacewar.com\/reports\/EU_could_end_China_arms_embargo_early_2011_report_999.html\" class=\"gen\">30 d\u00e9cembre 2010<\/a>, faisait une rapide analyse du sujet \u00e0 partir d&rsquo;une information parue dans <em>Le Figaro<\/em> (\u00ab<em>A European Union arms embargo clamped on China in 1989 following the Tiananmen crackdown could be lifted in early 2011, Brussels sources told Thursday&rsquo;s edition of France&rsquo;s Le Figaro daily. The lifting of the embargo on all lethal weapons could happen very quickly, a source close to EU foreign policy chief Catherine Ashton told the paper.<\/em>\u00bb) Les diff\u00e9rentes sources cit\u00e9es dans la d\u00e9p\u00eache, toutes venues des milieux europ\u00e9ens, envisageaient avec faveur une telle mesure.<\/p>\n<\/p>\n<p><p>\t  L&rsquo;analyse confirmait notamment que Lady Ashton avait pr\u00f4n\u00e9 une telle mesure comme une d\u00e9marche d&rsquo;affirmation europ\u00e9enne, pr\u00e9sent\u00e9e par elle devant les chefs d&rsquo;Etat et de gouvernement des pays membres. Nous avions observ\u00e9 cette attitude de la Haute Repr\u00e9sentante de l&rsquo;UE dans notre <em>Bloc-Notes<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-ashton_style_wikileaks_songerait-elle_a_exister__20_12_2010.html\" class=\"gen\">20 d\u00e9cembre 2010<\/a>, que nous liions indirectement \u00e0 une autre nouvelle, du <a href=\"http:\/\/www.dedefensa.org\/article-cablegate_et_transparence_allons-y__18_12_2010.html\" class=\"gen\">18 d\u00e9cembre 2010<\/a>, sur une intervention particuli\u00e8rement franche de l&rsquo;ambassadeur de Chine \u00e0 Bruxelles affirmant que l&rsquo;attitude de l&rsquo;Europe dans sa soumission aux USA, notamment sur cette question de l&#8217;embargo, \u00e9tait pitoyable et path\u00e9tique. (Cela, \u00e0 la lumi\u00e8re d&rsquo;un <em>Wiki<\/em>-c\u00e2ble<D>, sur l&rsquo;attitude US vis-\u00e0-vis de l&rsquo;UE et, <strong>surtout<\/strong>, sur l&rsquo;attitude de l&rsquo;UE vis-\u00e0-vis des injonctions US&#8230;)<\/p>\n<\/p>\n<p><p>\t Hier matin, on annon\u00e7ait que Lady Ashton n&rsquo;avait <a href=\"http:\/\/www.dedefensa.org\/article-l_embargo_des_armes_vers_la_chine_n_l_ue_toujours_pitoyable_et_pathetique__06_01_2011.html\" class=\"gen\">pas r\u00e9ussi<\/a> \u00e0 convaincre tous les Etats-membres, notamment et sans surprise, les Britanniques et les anciens pays d&rsquo;Europe de l&rsquo;Est. En m\u00eame temps, on soulignait la p\u00e9n\u00e9tration en cours de nombre de pays de l&rsquo;UE par la Chine, notamment dans le domaine des aides aux tr\u00e9sors publics pour la r\u00e9duction de la dette souveraine Ceci a un rapport contradictoire mais fort \u00e9volutif avec cela. On y reviendra plus loin.  <\/p>\n<\/p>\n<p><p>\t On rappellera \u00e9galement l&rsquo;ach\u00e8vement du march\u00e9 France-Russie sur les navires de projection de force et porte-h\u00e9licopt\u00e8res <em>Mistral<\/em> (Notre <em>Bloc-Notes<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-mistral_france_russie_c_est_fait_30_12_2010.html\" class=\"gen\">30 d\u00e9cembre 2010<\/a>.)<\/p>\n<\/p>\n<p><p>\t Enfin, on mentionnera une information,  celle que nous signalions plus haut comme venue d&rsquo;une tr\u00e8s bonne source,  datant de quelques ann\u00e9es, autour de 2003, sur une visite secr\u00e8te rendu par un haut fonctionnaire des services de s\u00e9curit\u00e9 chinois au pr\u00e9sident Chirac. Le visiteur venait sonder le pr\u00e9sident fran\u00e7ais pour l&rsquo;\u00e9ventualit\u00e9 d&rsquo;un achat de 250 avions de combat <em>Rafale<\/em> par la Chine. Il ne semble pas que le pr\u00e9sident fran\u00e7ais ait envisag\u00e9 s\u00e9rieusement d&rsquo;examiner cette proposition, dont il craignait \u00e9videmment qu&rsquo;elle soulev\u00e2t la fureur des USA. De ce point de vue, il existe certaines circonstances o\u00f9 la France, compte tenu de ses pr\u00e9tentions \u00e0 l&rsquo;ind\u00e9pendance et de ses moyens effectifs de l&rsquo;assurer, balance entre la courte vue, le manque d&rsquo;audace et un r\u00e9flexe d&rsquo;alignement sur les USA. Ce jugement est plus facile aujourd&rsquo;hui qu&rsquo;il ne pouvait l&rsquo;\u00eatre en 2003, sans aucun doute, mais il marquait bien la contradiction de la position fran\u00e7aise vis-\u00e0-vis des USA, s&rsquo;opposant \u00e0 la guerre en Irak telle que les USA la lan\u00e7aient, pour aussit\u00f4t tout faire pour tenter d&rsquo;apaiser les USA alors que cette position d&rsquo;opposition \u00e0 la guerre r\u00e9pondait aux principes d&rsquo;une politique fran\u00e7aise coh\u00e9rente. Cette contradiction fran\u00e7aise est un \u00e9l\u00e9ment d&rsquo;arri\u00e8re-plan important de notre r\u00e9flexion.<\/p>\n<h4>Notre commentaire<\/h4>\n<p>C&rsquo;est sur cette toile de fond, ce canevas, que nous voudrions lancer notre commentaire, d&rsquo;abord en insistant sur un autre \u00e9v\u00e9nement que nous n&rsquo;avons pas mentionn\u00e9, qui est l&rsquo;effondrement de la capacit\u00e9 qualitative, par l&rsquo;effondrement tout court de la capacit\u00e9 de production de syst\u00e8mes d&rsquo;arme avanc\u00e9s des USA. Le JSF n&rsquo;est pas \u00e0 cet \u00e9gard un <em>show<\/em> exceptionnel, mais bien l&rsquo;illustration incontestable d&rsquo;une situation g\u00e9n\u00e9rale.<\/p>\n<\/p>\n<p><p>\t En effet, l&rsquo;hypoth\u00e8se d&rsquo;un effondrement, non seulement de la puissance, mais de la capacit\u00e9 de production de la puissance militaire US, est aujourd&rsquo;hui plausible. Quand nous parlons d&rsquo;effondrement, nous voulons parler de l&rsquo;apparition dans l&rsquo;industrie US de l&rsquo;armement d&rsquo;une r\u00e9elle incapacit\u00e9 de concevoir et de produire un syst\u00e8me d&rsquo;arme moderne, sinon dans des conditions \u00e9conomiques et technologiques si extravagantes et extraordinaires qu&rsquo;elles \u00e9quivalent \u00e0 une r\u00e9elle impuissance et justifient de parler d&rsquo;incapacit\u00e9. Le probl\u00e8me est parfaitement illustr\u00e9 dans les termes les plus bas et les plus communs qui sont ceux de la comptabilit\u00e9, et qui ont \u00e9t\u00e9 largement d\u00e9taill\u00e9s depuis plusieurs ann\u00e9es. Jamais depuis la Deuxi\u00e8me Guerre mondiale le Pentagone n&rsquo;a dispos\u00e9 de budgets d&rsquo;une telle abondance, et jamais il n&rsquo;a aussi peu produit de forces effectives et efficaces. Cette situation est d&rsquo;ores et d\u00e9j\u00e0 effective dans les capacit\u00e9s op\u00e9rationnelles des forces. (Voir les d\u00e9monstrations de Winslow Wheeler, notamment concernant <a href=\"http:\/\/www.dedefensa.org\/article-comptabilite_du_trou_noir_06_09_2010.html\" class=\"gen\">l&rsquo;U.S. Air Force<\/a>.)<\/p>\n<\/p>\n<p><p>\tA cette situation s&rsquo;en ajoute une seconde, dont on assiste \u00e0 l&rsquo;ouverture actuellement, avec l&rsquo;installation du nouveau Congr\u00e8s. Il s&rsquo;agit bien entendu de la situation budg\u00e9taire des USA et de l&rsquo;intention affich\u00e9e des r\u00e9publicains de r\u00e9duire les d\u00e9penses publiques pour tenter de r\u00e9sorber une partie du colossal d\u00e9ficit du gouvernement f\u00e9d\u00e9ral. On sait que cette intention, surtout appuy\u00e9e sur la vague <em>Tea Party<\/em>, a largement d\u00e9bord\u00e9 sur la question de la <a href=\"http:\/\/www.dedefensa.org\/article-republicains_tea_party_deficit_et_pentagone_civil_war__13_11_2010.html\" class=\"gen\">r\u00e9duction<\/a> des d\u00e9penses militaires. Une \u00e9volution g\u00e9n\u00e9rale est en train de se faire, o\u00f9 l&rsquo;on voit m\u00eame les <em>leaders<\/em> r\u00e9publicains comme le chef de la majorit\u00e9 \u00e0 la Chambre <a href=\"http:\/\/www.dedefensa.org\/article-le_pentagone_a_la_soupe_ou_le_pentagone_a_la_loupe_05_01_2011.html \" class=\"gen\">Eric Cantor<\/a>, envisager, ou \u00eatre contraint d&rsquo;envisager effectivement de telles r\u00e9ductions. Du c\u00f4t\u00e9 d\u00e9mocrate, on trouve \u00e9galement une <a href=\"http:\/\/www.dedefensa.org\/article-une_coalition_tea_party-progressistes_contre_moby_dick_11_11_2010.html\" class=\"gen\">aile progressiste<\/a> qui est pr\u00eate \u00e0 soutenir les r\u00e9publicains pour r\u00e9duire le budget du Pentagone. D&rsquo;une fa\u00e7on non concert\u00e9e, mais bien sous la pression des \u00e9vidences et des situations, est en train de se former une union sacr\u00e9e contre les d\u00e9penses militaires \u00e0 l&rsquo;actuel niveau.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est dire si la situation d\u00e9crite plus haut d&rsquo;incapacit\u00e9 et d&rsquo;impuissance du Pentagone a toutes les chances d&rsquo;\u00eatre accentu\u00e9e et acc\u00e9l\u00e9r\u00e9e. Certes, personne ne parle r\u00e9ellement, \u00e0 Washington, d&rsquo;une situation d\u00e9crite [] d&rsquo;incapacit\u00e9 et d&rsquo;impuissance du Pentagone qui signifierait une r\u00e9duction dramatique de la puissance US, mais plus d&rsquo;un parlementaire, notamment de la tendance <em>Tea Party<\/em>, estime que la premi\u00e8re question de s\u00e9curit\u00e9 nationale aujourd&rsquo;hui n&rsquo;est pas la puissance militaire des USA mais la situation du d\u00e9ficit public. Encore une fois, nous r\u00e9p\u00e9tons que nous n&rsquo;attendons pas de ces diverses agitations une r\u00e9duction tr\u00e8s importante mais ordonn\u00e9e du budget du Pentagone, comme le voudraient par exemple les r\u00e9formistes (type <a href=\"http:\/\/www.dedefensa.org\/article-offensive_generale_contre_moby_dick_12_06_2010.html\" class=\"gen\">Paul-Frank<\/a>) ou certains membres de <em>Tea Party<\/em>, mais une bataille f\u00e9roce et d\u00e9sordonn\u00e9e pour le volume des r\u00e9ductions, avec divers int\u00e9r\u00eats et tendances antagonistes, <a href=\"http:\/\/www.dedefensa.org\/article-moby_dick_entre_dans_sa_terra_incognita_22_11_2010.html\" class=\"gen\">aboutissant<\/a> au d\u00e9sordre sinon au chaos,  ce qui est la pire chose qui puisse arriver pour aggraver encore la situation du Pentagone.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est par ce biais de l&rsquo;\u00e9volution de la situation politique washingtonienne que l&rsquo;on peut envisager une \u00e9volution peut-\u00eatre rapide de la situation des relations des USA et de l&rsquo;Europe, par le biais de l&rsquo;OTAN, qui reste la principale courroie de transmission de l&#8217;emprisonnement politique et technologique, et d&rsquo;influence, de l&rsquo;Europe par les USA. La crise budg\u00e9taire de l&rsquo;OTAN, donc les contributions US \u00e0 l&rsquo;OTAN, les investissements militaires US en Europe, vont \u00eatre parmi les cibles possibles de r\u00e9ductions budg\u00e9taires du Pentagone, notamment sous la pression d&rsquo;un Congr\u00e8s dont l&rsquo;\u00e9tat d&rsquo;esprit tend vers l&rsquo;isolationnisme tandis que les bellicistes (le <em>War Party<\/em>) sont tout entier concentr\u00e9s sur l&rsquo;Afghanistan Or l&rsquo;Afghanistan, aux yeux de ce <em>War Party<\/em> (et des autres \u00e0 Washington) n&rsquo;est pas la preuve de l&rsquo;utilit\u00e9 de l&rsquo;OTAN mais au contraire de son inutilit\u00e9, et de la trahison des Europ\u00e9ens de l&rsquo;OTAN pour aider les USA. La seule urgence actuelle de s\u00e9curit\u00e9 nationale est objectivement un argument de plus de d\u00e9sint\u00e9r\u00eat US pour l&rsquo;OTAN. Tout cela p\u00e8sera de son poids lorsque les r\u00e9publicains, qui tiennent les cordons de la bourse ou presque au Congr\u00e8s, vont examiner les budgets militaires US r\u00e9gions par r\u00e9gions et qu&rsquo;ils \u00e9voqueront l&rsquo;ensemble Europe-OTAN.<\/p>\n<\/p>\n<p><p>\tLa suj\u00e9tion europ\u00e9enne aux USA se marque essentiellement par des acquisitions d&rsquo;armement qui impliquent des myriades de liens et d&rsquo;engagements divers qui confortent cette suj\u00e9tion. La principale acquisition en cours, la plus colossale et la plus d\u00e9terminante est celle du JSF, dont la situation ne cesse de <a href=\"http:\/\/www.dedefensa.org\/article-jsf_la_chute_continue_de_plus_en_plus_dure_06_01_2011.html?admin=1\" class=\"gen\">se d\u00e9t\u00e9riorer<\/a>. On comprend aussit\u00f4t que cet aspect de la situation constitue un autre point central de la crise. La coalition JSF-Europe, qui \u00e9tait au d\u00e9part con\u00e7ue comme une strat\u00e9gie d&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-l_europe_de_la_defense_nous_l_avons_vue_et_surtout_entendue_elle_est_americaine_remarques_par_vance_coffman_ceo_lockheed_martin_26_10_2002.html\" class=\"gen\">investissement<\/a> de l&rsquo;Europe par les USA appuy\u00e9e sur une <a href=\"http:\/\/www.dedefensa.org\/article-analysis_context_n58_january_2003_defense_export_the_jsf_ideology_30_03_2003.html\" class=\"gen\">id\u00e9ologie<\/a> d&rsquo;inspiration n\u00e9o-conservatrice revue \u00e0 la sauce plantureuse du complexe militaro-industriel, est le principal moyen dont disposent les USA pour conserver leur main mise technologique, bureaucratique et op\u00e9rationnelle sur les pays europ\u00e9ens de l&rsquo;OTAN. Ce point suffit \u00e0 faire comprendre l&rsquo;importance du destin de cette coalition JSF-Europe. Le programme JSF est au centre de la crise du Pentagone, il sera au centre de la crise budg\u00e9taire que va ouvrir le Congr\u00e8s. Le sort du programme est plus qu&rsquo;incertain et s&rsquo;il y a une certitude c&rsquo;est bien que les int\u00e9r\u00eats des alli\u00e9s engag\u00e9s dans le programme, essentiellement des pays europ\u00e9ens de l&rsquo;OTAN,  ne seront aucunement pris en compte. C&rsquo;est dire si cette situation constitue une opportunit\u00e9 qui n&rsquo;a gu\u00e8re de pr\u00e9c\u00e9dent, \u00e0 l&rsquo;image de la crise US et de la crise du Pentagone, et de la crise du JSF, qui n&rsquo;ont pas de pr\u00e9c\u00e9dents elles non plus.<\/p>\n<\/p>\n<p><p>\tMaintenant, que se passe-t-il de l&rsquo;autre c\u00f4t\u00e9,  non du c\u00f4t\u00e9 europ\u00e9en, qui est inexistant, mais du c\u00f4t\u00e9 qu&rsquo;on a \u00e9voqu\u00e9 dans notre <em>F&#038;C<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-l_hegemonie_au_gre_de_la_furtivite__31_12_2010.html\" class=\"gen\">31 d\u00e9cembre 2010<\/a> concernant la Chine, la Russie et leurs nouveaux avions de combat. Les deux puissances de l&rsquo;Est, chacune de leur c\u00f4t\u00e9 et chacune \u00e0 leur fa\u00e7on, mais dans une occurrence qui pourrait s&rsquo;av\u00e9rer une coordination apr\u00e8s-coup, \u00e9voluent vis-\u00e0-vis de l&rsquo;Europe.<\/p>\n<\/p>\n<p><p>\t La Russie ne cesse de d\u00e9velopper, l&rsquo;une apr\u00e8s l&rsquo;autre, des propositions transeurop\u00e9ennes, qui de s\u00e9curit\u00e9 (Medvedev), qui de grand march\u00e9 de l&rsquo;Atlantique \u00e0 l&rsquo;Oural (Poutine), qui de structures interm\u00e9diaires bas\u00e9es surtout sur la s\u00e9curit\u00e9, notamment avec la France et l&rsquo;Allemagne. Les accord \u00e9conomiques avec l&rsquo;Allemagne sont consid\u00e9rables et l&rsquo;accord finalement r\u00e9alis\u00e9 avec la France sur le BPC porte-h\u00e9licopt\u00e8res <em>Mistral<\/em> reste un \u00e9v\u00e9nement o\u00f9 la quincaillerie sophistiqu\u00e9e, quelles que soient les intentions, a une dimension strat\u00e9gique. D&rsquo;autre part, comme on le voit <a href=\"http:\/\/www.dedefensa.org\/article-start_premiere_dissonance_05_01_2011.html\" class=\"gen\">chaque jour<\/a>, l&rsquo;accord START-II (ou START-3) ne lie nullement la Russie \u00e0 une coop\u00e9ration politique avec les USA mais, au contraire, rouvre la porte \u00e0 de nouvelles pol\u00e9miques sur les antimissiles qui pourraient \u00e0 nouveau secouer l&rsquo;OTAN et l&rsquo;Europe. <\/p>\n<\/p>\n<p><p>\t La Chine a une autre approche dans ce domaine strat\u00e9gique. D&rsquo;une part, elle fait la le\u00e7on aux Europ\u00e9ens sur leur servilit\u00e9 vis-\u00e0-vis des USA, notamment sur cet embargo sur les armes qui est du type symbolique et maintenu \u00e0 bout de bras par l&rsquo;influence US d&rsquo;une fa\u00e7on dont quelques <em>WikiLeaks<\/em> ont r\u00e9v\u00e9l\u00e9 le caract\u00e8re pitoyable et path\u00e9tique pour l&rsquo;Europe. D&rsquo;autre part, elle avance ses pions dans le d\u00e9dale des Etats membres en aidant l&rsquo;un et l&rsquo;autre (la Gr\u00e8ce, le Portugal, l&rsquo;Espagne), c&rsquo;est-\u00e0-dire en rendant les puissances publiques qui, en g\u00e9n\u00e9ral, commandent les grands syst\u00e8mes d&rsquo;arme, d\u00e9bitrices,  et cela, plut\u00f4t dans un sens figur\u00e9 que concret, c&rsquo;est-\u00e0-dire moralement d\u00e9bitrices de la Chine. Pour le domaine qui nous importe, il est acquis que les Chinois veulent parvenir \u00e0 des accords de transferts de technologies a\u00e9rospatiales<\/p>\n<\/p>\n<p><p>\tIl n&rsquo;y a pas de concertation entre les pouss\u00e9es russe et chinoise, il y a une expansion naturelle vers une Europe per\u00e7ue comme de plus en plus faible parce que son protecteur est lui-m\u00eame de plus en plus faible. Si cela sugg\u00e8re des images grossi\u00e8res et d\u00e9gradantes (apr\u00e8s tout, protecteur a un sens dans le milieu de la p\u00e8gre et du trottoir), tant pis pour l&rsquo;Europe,  elle l&rsquo;a bien cherch\u00e9 et s&rsquo;est conduite dans ce sens Mais ce n&rsquo;est pas ce qui nous importe ici.<\/p>\n<h3>Les promesses du destin du JSF<\/h3>\n<\/p>\n<p><p>\tOn le voit, on le comprend, l&rsquo;\u00e9v\u00e9nement principal est \u00e0 l&rsquo;Ouest, aux USA. On le voit et on le comprend, le cas du JSF jouera dans les 2-4 ann\u00e9es un r\u00f4le capital car c&rsquo;est autour de lui que risque de se cristalliser une crise transatlantique majeure autour des fournitures d&rsquo;armement. L&rsquo;affaire est beaucoup plus chaude que nombre d&rsquo;experts et de dirigeants europ\u00e9ens ne l&rsquo;imaginent parce que ces experts et ces dirigeants ne r\u00e9alisent pas le v\u00e9ritable \u00e9tat d&rsquo;esprit des dirigeants et parlementaires US sur cette question. Alors que les Europ\u00e9ens s&rsquo;inqui\u00e8tent de l&rsquo;inattention US vis-\u00e0-vis des Europ\u00e9ens dans l&rsquo;affaire JSF, et qu&rsquo;ils esp\u00e8rent que cela va changer lorsque les USA s&rsquo;apercevront \u00e0 nouveau que les Europ\u00e9ens sont dans le programme, c&rsquo;est le contraire qui risque de se produire. Dans certains milieux washingtoniens, et devant la catastrophe qu&rsquo;est le programme JSF, l&rsquo;attitude vis-\u00e0-vis des Europ\u00e9ens dans ce programme est que les Europ\u00e9ens qui s&rsquo;y trouvent devront payer le prix fort et participer \u00e0 son sauvetage, au moins pour compenser leur absence d&rsquo;engagement en Afghanistan. C&rsquo;est ainsi qu&rsquo;on raisonne dans les salons washingtoniens, avec la si particuli\u00e8re psychologie am\u00e9ricaniste faite autant d&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-une_hypothese_l_inculpabilite_comme_fondement_de_la_psychologie_americaniste_06_05_2006.html\" class=\"gen\">inculpabilit\u00e9<\/a> que d&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-a_cote_de_l_inculpabilite_l_indefectibilite_de_la_psychologie_uset_8747_23_11_2006.html\" class=\"gen\">ind\u00e9fectibilit\u00e9<\/a>. On observe d&rsquo;ailleurs que cet \u00e9tat d&rsquo;esprit interf\u00e8re directement dans la situation \u00e0 l&rsquo;OTAN, qui est, du point de vue budg\u00e9taire, tr\u00e8s sensible pour les USA et tr\u00e8s d\u00e9favorable \u00e0 l&rsquo;entente transatlantique.<\/p>\n<\/p>\n<p><p>\tOn ajoutera que d&rsquo;autres affaires risquent d&#8217;empoisonner encore plus l&rsquo;atmosph\u00e8re, notamment l&rsquo;affaire <a href=\"http:\/\/www.dedefensa.org\/article-le_pentagone_dans_la_tenaille_du_coming_crash_03_11_2010.html\" class=\"gen\">KC-X<\/a> (les nouveaux ravitailleurs en vol de l&rsquo;USAF) dont on conna\u00eet les p\u00e9rip\u00e9ties rocambolesques. Dans tous les cas de figure, apr\u00e8s les innombrables avatars qu&rsquo;on a connus, une d\u00e9cision de l&rsquo;USAF, d&rsquo;ailleurs sans cesse report\u00e9e (actuellement, on parle de f\u00e9vrier 2011, voire d&rsquo;avril), am\u00e8nera une tension transatlantique. Ce sera le cas si l&rsquo;avion d&rsquo;EADS-Airbus n&rsquo;est pas choisi alors que les Europ\u00e9ens jugent que leur offre est la meilleure, et qu&rsquo;ils y verront une manuvre protectionniste ; ce sera le cas si la commande est partag\u00e9e ou si EADS l&#8217;emporte, car il y a de tr\u00e8s fortes chances que Boeing portera aussit\u00f4t l&rsquo;affaire devant le GAO, voire devant les tribunaux, aussi bien pour vices de proc\u00e9dures qu&rsquo;\u00e0 cause de ce que la soci\u00e9t\u00e9 US estime \u00eatre la violation des r\u00e8gles de l&rsquo;OMC par Airbus. Peu importe la validit\u00e9 des cas, ce qui est essentiel est la pol\u00e9mique dans une atmosph\u00e8re \u00e9lectrifi\u00e9e par les exigences de r\u00e9duction du d\u00e9ficit f\u00e9d\u00e9ral.<\/p>\n<\/p>\n<p><p>\tCe dernier point ach\u00e8ve d&rsquo;ailleurs d&rsquo;\u00e9tablir une nouvelle situation aux USA pour les industriels europ\u00e9ens. Jusqu&rsquo;il y a quelques ann\u00e9es, les Europ\u00e9ens voulaient p\u00e9n\u00e9trer sur le march\u00e9 US pour l&rsquo;apport de technologies et pour les gros budgets du Pentagone. Les deux arguments se sont successivement \u00e9rod\u00e9s, \u00e0 mesure de l&rsquo;avancement de la crise du technologisme et de la crise budg\u00e9taire aux USA. Aujourd&rsquo;hui, les USA n&rsquo;ont plus rien de ce paradis des marchands de canons dont r\u00eavaient les Europ\u00e9ens, avec l&rsquo;avantage syst\u00e9matique donn\u00e9 aux industries US ou des conditions draconiennes exig\u00e9es des Europ\u00e9ens, pour des budgets qui d\u00e9pendent de plus en plus de r\u00e9seaux de corruption priv\u00e9s pour les \u00e9normes d\u00e9penses p\u00e9riph\u00e9riques, et de plus en plus surveill\u00e9s et contraints pour ce qui concerne les grands programmes. M\u00eame les Am\u00e9ricano-Britanniques de BAE commencent \u00e0 r\u00e9fl\u00e9chir \u00e0 une strat\u00e9gie d&rsquo;un certain retour vers l&rsquo;Europe.<\/p>\n<\/p>\n<p><p>\tA la lumi\u00e8re de tous ces \u00e9v\u00e9nements, on comprend que l&rsquo;agitation des c\u00f4t\u00e9s russe et chinois prend tout son sens et tout son poids. Quoi qu&rsquo;elle en ait voulu et quelle qu&rsquo;aient \u00e9t\u00e9 ses vell\u00e9it\u00e9s vertueuses, moralisantes et discoureuses, comme on l&rsquo;a vu plus haut et comme on le <a href=\"http:\/\/www.dedefensa.org\/article-l_embargo_des_armes_vers_la_chine_n_l_ue_toujours_pitoyable_et_pathetique__06_01_2011.html\" class=\"gen\">constate<\/a> de plus en plus, l&rsquo;Europe a \u00e9tabli de plus en plus de liens avec la Russie et avec la Chine, et poursuit ce processus qui est dans la nature m\u00eame des crises multiples qui se d\u00e9veloppent,  y compris, le cadre g\u00e9n\u00e9ral de la crise eschatologique qui touche notre civilisation. Les nouvelles concernant les nouveaux avions de combat chinois et russes sont int\u00e9ressantes parce que, d&rsquo;abord, elles se situent dans le contexte transatlantique qu&rsquo;on sait, ensuite parce qu&rsquo;elles t\u00e9moignent d&rsquo;une avanc\u00e9e importante des deux puissances pour les amener au rang de coop\u00e9rantes (avec les Europ\u00e9ens) dans ces domaines. Enfin, et surtout, elles sont importantes parce qu&rsquo;elles se situent dans un contexte g\u00e9n\u00e9ral (celui des crises eschatologiques) o\u00f9 des domaines jusqu&rsquo;ici strictement s\u00e9par\u00e9es (comme l&rsquo;\u00e9conomie et la s\u00e9curit\u00e9 dans le cas russe et surtout chinois) tendent \u00e0 converger jusqu&rsquo;\u00e0 des points d&rsquo;une \u00e9ventuelle fusion constructive. Cette sorte de convergence, avec la possibilit\u00e9 de coop\u00e9rations qui semblaient impensables il y a encore 2 ou 3 ans, semblent concr\u00e8tement moins impensables depuis la vente du <em>Mistral<\/em>, et elles pourraient devenir tr\u00e8s vite concevables et souhaitables,  notamment en fonction de l&rsquo;\u00e9volution de la situation outre-Atlantique.<\/p>\n<\/p>\n<p><p>\tSi nous d\u00e9veloppons ce sujet \u00e0 propos des nouveaux avions de combat russe et chinois, c&rsquo;est parce que c&rsquo;est dans ce domaine que la situation europ\u00e9enne va rapidement devenir int\u00e9ressante et critique, et int\u00e9ressante parce que critique, \u00e0 cause de la catastrophe du JSF. <\/p>\n<\/p>\n<p><p>\t L&rsquo;argument des plus atlantistes parmi les Europ\u00e9ens, ceux qui ne peuvent concevoir que des rapports antagonistes avec la Russie et la Chine, et de servilit\u00e9 avec les USA, \u00e9taient jusqu&rsquo;ici de deux ordres, selon les bonnes (de plus en plus rares) ou mauvaises nouvelles du JSF : les USA sont assez forts pour nous prot\u00e9ger et nous fournir des avions sans \u00e9quivalent au monde, gr\u00e2ce au JSF ; ou bien : certes, le JSF va mal, mais de toutes les fa\u00e7ons tout le monde en est \u00e0 la g\u00e9n\u00e9ration pr\u00e9c\u00e9dente et les F-15, F-16 et F-18 US modernis\u00e9s feront l&rsquo;affaire Le JSF va mal et le premier argument a du plomb dans l&rsquo;aile ; les Russes et les Chinois d\u00e9veloppent de nouveaux avions et le second argument ne vaut gu\u00e8re mieux. Que diront les Polonais volant sur des F-16 dans un \u00e9tat d\u00e9j\u00e0 incertain et avec la pr\u00e9sence discontinue d&rsquo;un escadron de F-16 d\u00e9pass\u00e9s de l&rsquo;USAF (si l&rsquo;USAF en a encore de disponibles), lorsque les Russes aligneront leurs Su-35S puis leurs T-50 ?<\/p>\n<\/p>\n<p><p>\t L&rsquo;autre argument, europ\u00e9en celui-l\u00e0, s&rsquo;\u00e9pargne la charge habituelle de l&rsquo;antagonisme et voit les choses diff\u00e9remment. Il constate la crise US d&rsquo;une part, la n\u00e9cessit\u00e9 pour les pays europ\u00e9ens d&rsquo;une certaine modernisation de leurs forces a\u00e9riennes d&rsquo;autre part. (Nous ne jugeons pas cet argument op\u00e9rationnellement essentiel mais nous le consid\u00e9rons avec faveur pour ses implications <strong>politiques<\/strong>,  nous nous en sommes <a href=\"http:\/\/www.dedefensa.org\/article-les_technologies_de_souverainete_usage_et_utilite_en_temps_de_crise_par_philippe_grasset_29_04_2004.html\" class=\"gen\">souvent<\/a> <a href=\"http:\/\/www.dedefensa.org\/article-une_mission_par_tous_les_temps_rubrique_analyse_volume_23_n03_10_octobre_2007_10_12_2007.html\" class=\"gen\">expliqu\u00e9s<\/a>.) Dans ce cas, il faut envisager d&rsquo;autres voies d&rsquo;\u00e9quipement, et les envisager plut\u00f4t dans un esprit de coop\u00e9ration avec des puissances avec lesquelles on veut \u00e9tablir des liens de coop\u00e9ration.<\/p>\n<\/p>\n<p><p>\t D&rsquo;autres voies d&rsquo;\u00e9quipement, c&rsquo;est d&rsquo;abord l&rsquo;Europe Si la situation envisag\u00e9e implique des tensions avec les USA, comme c&rsquo;est le cas, un avion comme le <em>Gripen<\/em>, qui est tenu par un \u00e9quipement proche de 50% d&rsquo;origine US, est hors-jeu. Les Anglais, qui participent au <em>Typhoon<\/em> et avec lesquels les Fran\u00e7ais favoriseraient une coop\u00e9ration sur d&rsquo;autres programmes,  les Anglais sont les Anglais. Tout d\u00e9pendra de ce qu&rsquo;ils feront de leurs liens avec Washington, et l&rsquo;on comprend de quelles fa\u00e7ons. Pour eux, un tournant europ\u00e9en n\u00e9cessite une rupture avec Washington On verra (certains diraient : c&rsquo;est tout vu ?).<\/p>\n<\/p>\n<p><p>\t Mais ce paysage europ\u00e9en, pour devenir coh\u00e9rent dans le contexte que nous envisageons, avec la situation US en \u00e9volution catastrophique et des rapprochements avec la Russie et avec la Chine, doit effectivement \u00e9voluer d&rsquo;une fa\u00e7on de plus en plus affirm\u00e9e  vers  la voie compl\u00e9mentaire d&rsquo;une coop\u00e9ration avec ces deux derniers pays, assurant une stabilit\u00e9 des relations politiques et d&rsquo;\u00e9ventuels avantages \u00e9conomiques. Au niveau des avions de combat, si la probl\u00e9matique est situ\u00e9e dans le contexte g\u00e9n\u00e9ral qui importe, la chose a sans aucun doute un sens. Et, dans ce cas, une fois de plus, malgr\u00e9 l&rsquo;exceptionnelle m\u00e9diocrit\u00e9 et les palinodies pro-am\u00e9ricanistes de sa direction politique, c&rsquo;est, du c\u00f4t\u00e9 europ\u00e9en, la France qui est politiquement, technologiquement et culturellement la mieux plac\u00e9e, pour toutes les raisons du monde,  c&rsquo;est une fatalit\u00e9 que nous a refil\u00e9e le G\u00e9n\u00e9ral. Au reste, on sait bien que Sarko, qui est un sentimental, ne sait pas r\u00e9sister \u00e0 ses amis Poutine et Medvedev et, s&rsquo;il le faut, il en sera de m\u00eame avec son ami Hu La France a pour elle, dans le domaiune \u00e9voqu\u00e9, le <em>Rafale<\/em>, qui vaut <a href=\"http:\/\/www.dedefensa.org\/article-le_rafale_il_existe_by_jove__10_11_2009.html\" class=\"gen\">ce qu&rsquo;on sait<\/a>, qu&rsquo;elle ne vend pas parce qu&rsquo;elle continue \u00e0 acquiescer aux normes am\u00e9ricanistes du commerce des armes et qu&rsquo;elle entretient une politique ambigu\u00eb \u00e0 cet \u00e9gard, concurrente des USA ici, l\u00e0 amie privil\u00e9gi\u00e9e des USA. La situation que nous envisageons, \u00e0 nouveau, forcerait \u00e0 modifier fondamentalement ces donn\u00e9es.<\/p>\n<\/p>\n<p><p>\tPendant ce temps, peut-\u00eatre l&rsquo;UE commencera-t-elle \u00e0 \u00e9tudier s\u00e9rieusement la question de la lev\u00e9e de l&#8217;embargo des armes vers la Chine. En attendant, un conseil : continuons \u00e0 suivre avec attention le destin du JSF, si prometteur \u00e0 bien des \u00e9gards. <\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00e9volution par les armes 6 janvier 2010 Dans notre F&#038;C du 31 d\u00e9cembre 2010 consacr\u00e9 aux nouveaux avions de combat chinois et russes, nous laissions de c\u00f4t\u00e9 la probl\u00e9matique europ\u00e9enne soulev\u00e9e \u00e9ventuellement par cette nouvelle, avec cette observation, qui valait promesse : \u00abLa comparaison est ici limit\u00e9e entre les USA et le bloc Chine-Russie, selon&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3977,3435,3228,398,2687,250,7383,8635,916,2730,4205,4268,1205],"class_list":["post-72641","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-chine","tag-cooperation","tag-crise","tag-europe","tag-france","tag-jsf","tag-kc-x","tag-mistral","tag-poutine","tag-russie","tag-securite","tag-technologisme","tag-transatlantique"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72641"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72641\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}