{"id":72654,"date":"2011-01-11T06:29:06","date_gmt":"2011-01-11T06:29:06","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/01\/11\/le-j-20-chinois-et-laveu-de-gates\/"},"modified":"2011-01-11T06:29:06","modified_gmt":"2011-01-11T06:29:06","slug":"le-j-20-chinois-et-laveu-de-gates","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/01\/11\/le-j-20-chinois-et-laveu-de-gates\/","title":{"rendered":"Le J-20 chinois et l&rsquo;aveu de Gates"},"content":{"rendered":"<p><p>Partant pour trois jours \u00e0 P\u00e9kin et une visite en Chine, dans l&rsquo;avion qui l&rsquo;y conduisait le 8 janvier, le secr\u00e9taire US \u00e0 la d\u00e9fense Gates a fait quelques confidences aux journalistes qui l&rsquo;accompagnaient. Il a notamment parl\u00e9 du nouveau chasseur chinois \u00e0 capacit\u00e9s furtives <a href=\"http:\/\/www.dedefensa.org\/article-l_hegemonie_au_gre_de_la_furtivite__31_12_2010.html\" class=\"gen\">J-20<\/a>, \u00e0 propos duquel les journalistes l&rsquo;ont interrog\u00e9 avec insistance. (AFP, repris par <em>SpaceWar.com<\/em> du <a href=\"http:\/\/www.spacewar.com\/reports\/US_concerned_over_Chinas_new_weapons_Gates_999.html\" class=\"gen\">8 janvier 2011<\/a>).<\/p>\n<\/p>\n<p><p>\tCe qui nous int\u00e9resse dans l&rsquo;extrait ci-dessous est la position que prend le secr\u00e9taire \u00e0 la d\u00e9fense, d&rsquo;une part sur la capacit\u00e9 de l&rsquo;avion chinois, d&rsquo;autre part sur la r\u00e9action des USA \u00e0 cette nouvelle.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Speaking to reporters en route to Beijing for three days of talks, Gates said the Chinese appeared to have made more progress in building their first stealth fighter jet than previously thought, and that an anti-ship missile posed a potential threat to the US military.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>They clearly have the potential to put some of our capabilities at risk. And we have to pay attention to them, we have to respond appropriately with our own programmes, Gates said.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>But he said the advances in weaponry underlined the importance of building a dialogue with the Chinese military, and added he hoped his visit starting Sunday would lay the ground for deeper defence ties with Asia&rsquo;s rising power. My hope is that, through the strategic dialogue that I&rsquo;m talking about, that maybe the need for some of these capabilities is reduced, Gates said.<\/em>\u00bb<\/p>\n<h4>Notre commentaire<\/h4>\n<p> Il y a trois choses dans les d\u00e9clarations de Gates, dont deux sont \u00e0 mettre en vis-\u00e0-vis et constituent une v\u00e9ritable nouveaut\u00e9 dans l&rsquo;attitude militaire US, et une mesure de l&rsquo;effondrement de cette puissance militaire, et de la perception qu&rsquo;en ont ses chefs.<\/p>\n<\/p>\n<p><p>\t La premi\u00e8re chose est la reconnaissance par Gates de l&rsquo;avancement des capacit\u00e9s chinoises dans le d\u00e9veloppement des avions de combat et des technologies de la furtivit\u00e9 ( plus de progr\u00e8s que nous pensions). Cela contraste avec la premi\u00e8re r\u00e9action (officieuse) du Pentagone, qui avait \u00e9t\u00e9 de minimiser les capacit\u00e9s chinoises et le fait m\u00eame de l&rsquo;apparition du J-20.<\/p>\n<\/p>\n<p><p>\t Deuxi\u00e8me chose, une r\u00e9action assez classique, sur laquelle Gates n&rsquo;insiste pas trop : les Chinois ont la capacit\u00e9 de mettre en \u00e9chec certaines des capacit\u00e9s militaires US et nous devons pr\u00eater attention \u00e0 ce fait, et nous devons r\u00e9agir d&rsquo;une fa\u00e7on appropri\u00e9e avec nos programmes Gates n&rsquo;insiste pas trop parce qu&rsquo;il sait bien qu&rsquo;il n&rsquo;a pas les moyens de son avertissement, le Pentagone \u00e9tant plong\u00e9 dans une crise profonde, notamment budg\u00e9taire, mais m\u00eame conceptuelle et capacitaire, dans le fait m\u00eame d&rsquo;avoir ou de n&rsquo;avoir peut-\u00eatre plus la capacit\u00e9 de produire des avions de combat avanc\u00e9s.<\/p>\n<\/p>\n<p><p>\t Troisi\u00e8me chose, de loin la plus int\u00e9ressante. Aussit\u00f4t apr\u00e8s avoir dit dans les conditions qu&rsquo;on signale qu&rsquo;il fallait envisager certaines mesures de renforcement ou d&rsquo;ajustement, Gates encha\u00eene sur l&rsquo;orientation exactement contraire : le J20, dans ce cas symbole du renforcement et de la capacit\u00e9 militaires chinoises, est pr\u00e9sent\u00e9 comme un argument pour resserrer les liens militaires entre Chine et USA, pour rapprocher les points de vue, pour pacifier au maximum les relations, etc. Dans la rh\u00e9torique US concernant l&rsquo;armement conventionnel, celui qui peut \u00eatre utilis\u00e9, c&rsquo;est une attitude sans pr\u00e9c\u00e9dent de la part d&rsquo;un secr\u00e9taire \u00e0 la d\u00e9fense.<\/p>\n<\/p>\n<p><p>\tNous faisons cette r\u00e9serve (l&rsquo;armement conventionnel, celui qui peut \u00eatre utilis\u00e9) car, au niveau nucl\u00e9aire, cette attitude des USA s&rsquo;est d\u00e9j\u00e0 manifest\u00e9e durant la Guerre froide. Dans les ann\u00e9es 1960 et 1970, devant les progr\u00e8s sovi\u00e9tiques dans l&rsquo;arsenal nucl\u00e9aire strat\u00e9gique jusqu&rsquo;\u00e0 presque un point d&rsquo;\u00e9quilibre avec les USA, la politique strat\u00e9gique US a \u00e9t\u00e9 de rechercher des accords de limitation mutuelle, puis de r\u00e9duction dans les ann\u00e9es 1980 avec Reagan, au lieu de chercher une riposte aux progr\u00e8s sovi\u00e9tiques pour conserver la sup\u00e9riorit\u00e9. Mais il s&rsquo;agissait du nucl\u00e9aire strat\u00e9gique, l&rsquo;arme d&rsquo;an\u00e9antissement faite en principe pour ne pas \u00eatre utilis\u00e9e selon la doctrine McNamara (doctrine MAD), arme d\u00e9j\u00e0 port\u00e9e en potentiel \u00e0 la probabilit\u00e9 d&rsquo;une destruction mutuelle en cas d&rsquo;engagement. Il s&rsquo;agissait donc d&rsquo;arr\u00eater une course \u00e0 l&rsquo;armement absurde, o\u00f9 la sup\u00e9riorit\u00e9 n&rsquo;avait aucun sens. (D&rsquo;o\u00f9 l&rsquo;exclamation fameuse de Kissinger en 1974 face aux chefs militaires US lors des n\u00e9gociations sur l&rsquo;accord SALT-II, pour d\u00e9faire leurs arguments sur la production de nouveaux syst\u00e8mes sup\u00e9rieurs \u00e0 ceux des Sovi\u00e9tiques : \u00ab<em>What, in the name of God, is strategic superiority? What is the significance of it, politically, militarily, operationnally, at this level or number? What do you do with it?<\/em>\u00bb) <\/p>\n<\/p>\n<p><p>\tAu niveau conventionnel, niveau o\u00f9 les armes sont destin\u00e9es \u00e0 \u00eatre employ\u00e9es, l&rsquo;attitude US a <strong>toujours<\/strong> \u00e9t\u00e9 compl\u00e8tement diff\u00e9rente, surtout au niveau de l&rsquo;aviation de combat. La seule r\u00e8gle, depuis 1945, a toujours \u00e9t\u00e9 de maintenir une sup\u00e9riorit\u00e9 qualitative (technologique) sans contestation possible sur tout adversaire potentiel. Le cas s&rsquo;est produit \u00e0 diverses reprises (en 1950 en Cor\u00e9e, en 1965-68 au Vietnam, dans les ann\u00e9es 1970 avec le MiG-25 sovi\u00e9tique, dans les ann\u00e9es 1980 avec les MiG-29 et Su-27 sovi\u00e9tiques, etc.) Chaque fois, une seule attitude \u00e9tait envisag\u00e9e et concevable : l\u00e0 o\u00f9 un signe de r\u00e9duction de la sup\u00e9riorit\u00e9 qualitative US apparaissait, une seule attitude \u00e9tait envisag\u00e9e et aussit\u00f4t d\u00e9velopp\u00e9e, qui \u00e9tait celle de lancer de nouveaux programmes, de nouvelles am\u00e9liorations, pour retrouver une compl\u00e8te sup\u00e9riorit\u00e9 qualitative, par tous les moyens y compris budg\u00e9taires bien entendu.<\/p>\n<\/p>\n<p><p>\tCette fois, Gates a une attitude g\u00e9n\u00e9rale compl\u00e8tement diff\u00e9rente. Certes, il parle de mesures techniques, mais d&rsquo;une fa\u00e7on accessoire. Son principal argument, c&rsquo;est : Entendons-nous avec les Chinois, de fa\u00e7on \u00e0 convaincre <em>de facto<\/em> ces m\u00eames Chinois que leur effort militaire n&rsquo;est pas justifi\u00e9, et, ainsi, esp\u00e9rant ralentir l&rsquo;effort chinois qui met en cause la sup\u00e9riorit\u00e9 technologique US. Il s&rsquo;agit, \u00e0 peine entre les lignes, d&rsquo;un aveu impressionnant, encore une fois compte tenu du domaine sacr\u00e9 pour les USA de la sup\u00e9riorit\u00e9 a\u00e9rienne qualitative Il s&rsquo;agit de l&rsquo;aveu que les USA ne peuvent plus budg\u00e9tairement soutenir un effort de concurrence dans l&rsquo;armement, voire, plus gravement, de l&rsquo;aveu que les USA n&rsquo;ont plus les capacit\u00e9s technologiques et structurelles d&rsquo;un tel effort,  comme en t\u00e9moigne la catastrophe du JSF qui, en plus, s&rsquo;av\u00e8re de plus en plus comme un choix op\u00e9rationnel catastrophique en fait de capacit\u00e9s (dans l&rsquo;hypoth\u00e8se extr\u00eamement contestable o\u00f9 cet avion fonctionnerait) face aux nouveaux avions russes et chinois. On n&rsquo;a pas d&rsquo;aveu plus significatif de la reconnaissance, par celui qui a la charge de la puissance militaire US, de l&rsquo;\u00e9rosion, voire de l&rsquo;effondrement de cette puissance, aussi bien du point de vue op\u00e9rationnel direct que du point de vue des perspectives de d\u00e9veloppements.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 11 janvier 2011 \u00e0 06H27<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Partant pour trois jours \u00e0 P\u00e9kin et une visite en Chine, dans l&rsquo;avion qui l&rsquo;y conduisait le 8 janvier, le secr\u00e9taire US \u00e0 la d\u00e9fense Gates a fait quelques confidences aux journalistes qui l&rsquo;accompagnaient. Il a notamment parl\u00e9 du nouveau chasseur chinois \u00e0 capacit\u00e9s furtives J-20, \u00e0 propos duquel les journalistes l&rsquo;ont interrog\u00e9 avec insistance.&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3977,2803,4655,3984,10705,250,2779,5230,10706,2671],"class_list":["post-72654","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-chine","tag-effondrement","tag-furtivite","tag-gates","tag-j-200","tag-jsf","tag-puissance","tag-superiorite","tag-technollogie","tag-us"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72654","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72654"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72654\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}