{"id":72662,"date":"2011-01-13T12:05:44","date_gmt":"2011-01-13T12:05:44","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/01\/13\/lecheance-fatale-du-systeme-du-technologisme\/"},"modified":"2011-01-13T12:05:44","modified_gmt":"2011-01-13T12:05:44","slug":"lecheance-fatale-du-systeme-du-technologisme","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/01\/13\/lecheance-fatale-du-systeme-du-technologisme\/","title":{"rendered":"L&rsquo;\u00e9ch\u00e9ance fatale du syst\u00e8me du technologisme ?"},"content":{"rendered":"<p><h2 class=\"common-article\">L&rsquo;\u00e9ch\u00e9ance fatale du syst\u00e8me du technologisme ?<\/h2>\n<\/p>\n<p><p>\t12 janvier 2011  Nous revenons sur le cas de l&rsquo;avion de combat chinois J-20 (ou J-XX) apr\u00e8s l&rsquo;avoir abord\u00e9 \u00e0 deux reprises, le <a href=\"http:\/\/www.dedefensa.org\/article-l_hegemonie_au_gre_de_la_furtivite__31_12_2010.html\" class=\"gen\">31 d\u00e9cembre 2010<\/a> et le <a href=\"http:\/\/www.dedefensa.org\/article-le_j-20_chinois_et_l_aveu_de_gates_11_01_2011.html\" class=\"gen\">11 janvier 2011<\/a>, selon des points de vue diff\u00e9rents. Cette fois, nous entendons traiter ce cas d&rsquo;une fa\u00e7on tr\u00e8s g\u00e9n\u00e9rale, non pas du point de vue op\u00e9rationnel et strat\u00e9gique mais du point de vue de sa signification par rapport au Syst\u00e8me, et, notamment et essentiellement, la composante dite du <a href=\"http:\/\/www.dedefensa.org\/article-la_grace_de_l_histoire_cinquieme_partie_02_12_2010.html\" class=\"gen\">syst\u00e8me<\/a> du <a href=\"http:\/\/www.dedefensa.org\/article-cinquieme_partie_la_transversale_du_technologisme_02_12_2010.html\" class=\"gen\">technologisme<\/a> \u00e0 l&rsquo;int\u00e9rieur de ce Syst\u00e8me (que nous nommons aussi le <a href=\"http:\/\/www.dedefensa.org\/article-dialogues-18_le_systeme_en_dedans_et_en_dehors_28_12_2010.html\" class=\"gen\">Syst\u00e8me-en-soi<\/a>).<\/p>\n<\/p>\n<p><p>\tPour cette d\u00e9marche, nous nous r\u00e9f\u00e9rons comme r\u00e9flexion d&rsquo;actualit\u00e9 \u00e0 une analyse en profondeur de ce cas de l&rsquo;avion J-20,  du Dr. Carlo Kopp, de <em>Air Power Australia<\/em> (APA), site devenu c\u00e9l\u00e8bre pour ses analyses techniques et strat\u00e9giques de l&rsquo;aviation de combat actuelle (et site anti-JSF notoire). Kopp est l&rsquo;un des dirigeants du site, un ing\u00e9nieur et un scientifique expert dans les questions technologiques li\u00e9es au radar, \u00e0 la technologie furtive, \u00e0 leur int\u00e9gration dans les situations potentielles de combat, etc.<\/p>\n<\/p>\n<p><p>\tLe <a href=\"http:\/\/www.ausairpower.net\/APA-NOTAM-090111-1.html\" class=\"gen\">9 janvier 2011<\/a>, Kopp a publi\u00e9 une note d&rsquo;analyse en profondeur sur le J-20 et les cons\u00e9quences de l&rsquo;apparition de ce syst\u00e8me d&rsquo;arme,  \u00ab<em>The Strategic Impact of China&rsquo;s J-XX [J-20] Stealth Fighter<\/em>\u00bb La note est extr\u00eamement serr\u00e9e, fouill\u00e9e, techniquement remarquable, confirmant qu&rsquo;APA peut largement soutenir la comparaison avec les centres d&rsquo;analyses officiels ou assimil\u00e9s, sinon les surpasser, avec en plus les avantages d\u00e9cisifs d&rsquo;avoir un personnel sans la m\u00e9diocrit\u00e9 des bureaucrates officiels qui sont d&rsquo;abord tenus \u00e0 un devoir de conformisme, et de n&rsquo;\u00eatre pas soumis aux imp\u00e9ratifs id\u00e9ologiques et politiques du Syst\u00e8me (comme le soutien \u00e0 un concept aussi \u00e9videmment fauss\u00e9e et catastrophique que le JSF). La note conclue que l&rsquo;\u00e9v\u00e9nement de l&rsquo;apparition du J-20 associ\u00e9e \u00e0 d&rsquo;autres nouveaux syst\u00e8mes chinois qui sont signal\u00e9s et \u00e9valu\u00e9s dans le d\u00e9tail par Kopp,  et cela apr\u00e8s ce qu&rsquo;on sait des nouveaux syst\u00e8mes d&rsquo;arme russes,  doit conduire \u00e0 observer que les USA se trouvent dans une position strat\u00e9gique conventionnelle en train de basculer vers la plus extr\u00eame vuln\u00e9rabilit\u00e9, voire l&rsquo;impotence sinon l&rsquo;effondrement. Pour Kopp, tous les syst\u00e8mes d&rsquo;arme US du domaine, sauf le F-22 (dont on conna\u00eet <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_les_tribulations_du_f-22_21_07_2009.html\" class=\"gen\">le sort<\/a> pour l&rsquo;instant), sont potentiellement surclass\u00e9s par les syst\u00e8mes chinois (et russes). Kopp conclut :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The material reality is simple. If the United States does not reverse course in its tactical air fleet and air defence recapitalisation planning, the United States will lose the Pacific Rim to China, with all of the practical and grand strategic consequences which follow from that.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tBien entendu, la probl\u00e9matique du J-20 est envisag\u00e9e dans sa signification la plus large, c&rsquo;est-\u00e0-dire comme symptomatique de l&rsquo;\u00e9tat de la puissance chinoise, de sa capacit\u00e9 g\u00e9n\u00e9rale, de sa base technologique, etc. Et il y a l\u00e0 aussi le constat d&rsquo;une sup\u00e9riorit\u00e9 d&rsquo;ores et d\u00e9j\u00e0 av\u00e9r\u00e9e de la Chine sur les USA, qui est une affirmation radicale, extr\u00eamement inattendue pour la pens\u00e9e conventionnelle et conformiste, et en aucun cas sollicit\u00e9e mais au contraire notablement justifi\u00e9e<\/p>\n<\/p>\n<p><p>\tNous empruntons un passage de l&rsquo;analyse de Kopp qui nous int\u00e9resse particuli\u00e8rement Il marque d&rsquo;une fa\u00e7on pr\u00e9cise la d\u00e9gradation acc\u00e9l\u00e9r\u00e9e des capacit\u00e9s de ma\u00eetrise et de production du syst\u00e8me du technologisme qui est l&rsquo;axe central du Syst\u00e8me-en-soi (le syst\u00e8me de l&rsquo;am\u00e9ricanisme, pour ce cas pratique comme en g\u00e9n\u00e9ral). Ce constat-l\u00e0 est beaucoup plus important pour nous que celui qui concerne les capacit\u00e9s chinoises, comme l&rsquo;on comprendra plus loin, et il rejoint en g\u00e9n\u00e9ral notre analyse \u00e0 propos des capacit\u00e9s fondamentales de productivit\u00e9 de la puissance US sous l&rsquo;inspiration qui s&rsquo;av\u00e8re d\u00e9sormais d\u00e9structurante et subversive du syst\u00e8me du technologisme.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>In terms of China&rsquo;s ability to manufacture and deploy significant numbers of the J-XX [J-20] it is worth observing that in terms of raw bang for buck China&rsquo;s defence industry is outperforming the United States&rsquo; industry by a robust margin. The oft quoted comparisons between the United States and PRC defence budgets produce a misleading picture of the relative scale of investments, especially in terms of equipment recapitalisation. Chinese aggregate defence budgets as cited reflect primarily capital equipment acquisition and support costs, while many infrastructure and personnel costs are born by regional governments. United States budgets tend to carry a significant fraction of operational costs which have been unusually high over the last decade due to the ongoing global conflict with Islamo-fascist insurgent movements.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>The woeful inefficiency of many portions of the United States defence industry, and procurement bureaucracy, is best exemplified by the fact that the underperforming single engine F-35 is now more expensive than the larger and much better twin engine F-22 Raptor, in terms of Unit Procurement Costs. Many other United States programs display similar symptoms, with overpriced and frequently underperforming products. China has a much healthier manufacturing industry than the United States, and a larger pool of highly skilled personnel, in a job market where personnel costs are tightly controlled. China&rsquo;s ability to rapidly develop both the sophisticated J-XX [J-20] and complex KJ-2000 AWACS over the last decade, with little prior depth in the basic technologies involved, shows an efficient and effective R&#038;D environment, and supporting manufacturing base.<\/em> <\/p>\n<\/p>\n<p><p>\t\u00bb<em>The Chengdu J-XX [J-20] thus represents a techno-strategic coup by China, and if deployed in large numbers in a mature configuration, a genuine strategic coup against the United States and its Pacific Rim allies. The development of the Chengdu J-XX [J-20] represents an excellent case study of a well thought out symmetrical techno-strategic response to the United States&rsquo; deployment of stealthy combat aircraft, which no differently to the United States&rsquo; play in the late Cold War and post Cold War period, elicits a disproportionate response in materiel investment to effectively counter<\/em>\u00bb<\/p>\n<h4>Notre commentaire<\/h4>\n<p> L&rsquo;expertise du Dr. Carlo Kopp et d&rsquo;APA est aujourd&rsquo;hui unanimement reconnus et elle ridiculise en g\u00e9n\u00e9ral,  la chose n&rsquo;est pas tr\u00e8s difficile au demeurant,  le conformisme virtualiste des analyses techniques officielles. Cela fait plusieurs ann\u00e9es que Kopp-APA avertissent de la mont\u00e9e des capacit\u00e9s russes et chinoises en mati\u00e8re d&rsquo;avions de combat notamment (et dans d&rsquo;autres domaines essentiels de l&rsquo;armement), contre l&rsquo;obsession catastrophique de la bureaucratie am\u00e9ricaniste-occidentaliste focalis\u00e9e autour du concept du JSF. En d&rsquo;autres mots, on peut prendre l&rsquo;analyse op\u00e9rationnelle, strat\u00e9gique et technologique cit\u00e9e ici pour tr\u00e8s valable et particuli\u00e8rement illustrative d&rsquo;une situation d\u00e9sormais sur la voie de devenir extr\u00eamement inqui\u00e9tante pour la position strat\u00e9gique des USA, en m\u00eame temps qu&rsquo;\u00eatre extr\u00eamement significative.<\/p>\n<\/p>\n<p><p>\tIl sera int\u00e9ressant de voir comment va \u00e9voluer la position officielle US vis-\u00e0-vis des capacit\u00e9s chinoises d&rsquo;une part, vis-\u00e0-vis de leurs int\u00e9r\u00eats industriels et autres \u00e0 l&rsquo;exportation d&rsquo;autre part. Il y a par exemple le cas du Japon. D&rsquo;une part, les propagandistes du Syst\u00e8me, Gates le premier lors de son actuelle visite au Japon et le chroniqueur d&rsquo;<em>Aviation Week &#038; Space Technology<\/em> Robert Wall le <a href=\"http:\/\/www.aviationweek.com\/aw\/blogs\/defense\/index.jsp?plckController=Blog&#038;plckBlogPage=BlogViewPost&#038;newspaperUserId=27ec4a53-dcc8-42d0-bd3a-01329aef79a7&#038;plckPostId=Blog%3a27ec4a53-dcc8-42d0-bd3a-01329aef79a7Post%3ac92fdb6b-91f6-4835-ad25-c44426a5fb5e&#038;plckScript=blogScript&#038;plckElementId=blogDest\" class=\"gen\">12 janvier 2011<\/a>, se sont mis aussit\u00f4t sur le sentier de la guerre pour laisser entendre que le JSF doit \u00eatre achet\u00e9 par le Japon, comme syst\u00e8me d&rsquo;arme n\u00e9cessaire pour affronter le J-20 chinois. D&rsquo;autre part, les planificateurs du Pentagone vont devoir \u00e0 un moment ou l&rsquo;autre en venir \u00e0 l&rsquo;in\u00e9vitable conclusion que le JSF est nettement inf\u00e9rieur, face au J-20, cela en totale contradiction avec leurs arguments en faveur du JSF ; relancera-t-on alors la production du F-22, comme il en est d\u00e9j\u00e0 question ici ou l\u00e0 ? Dans ce cas, le Japon, qui avait d\u00e9j\u00e0 exprim\u00e9 le d\u00e9sir d&rsquo;acheter des F-22 pour en <a href=\"http:\/\/www.dedefensa.org\/article-le_cas_du_f-22_a_la_lumiere_du_soleil_levant_04_05_2007.html?admin=1\" class=\"gen\">2007<\/a>-2008, ne r\u00e9clamera-t-il pas \u00e0 nouveau le F-22 pour ses forces a\u00e9riennes ? D&rsquo;autre part encore, et d&rsquo;une fa\u00e7on plus g\u00e9n\u00e9rale si l&rsquo;on veut, les USA peuvent-ils se d\u00e9mentir \u00e0 ce point et revenir sur la production du F-22, et avec quel argent alors que la r\u00e9duction du budget du Pentagone est partout \u00e0 l&rsquo;ordre du jour et que le JSF ne cesse de drainer des masses budg\u00e9taires consid\u00e9rables \u00e0 cause de son d\u00e9veloppement catastrophique ?<\/p>\n<\/p>\n<p><p>\tComme on voit, la situation du Pentagone est extr\u00eamement difficile, tant au niveau de la communication, qu&rsquo;au niveau des moyens, qu&rsquo;au niveau des r\u00e9alit\u00e9s strat\u00e9giques. Faut-il grossir la menace du J-20 pour obtenir des moyens suppl\u00e9mentaires, et alors minimiser <em>de facto<\/em> les capacit\u00e9s du JSF, et ainsi r\u00e9duire les arguments de promotion de l&rsquo;avion autant \u00e0 l&rsquo;exportation que devant le Congr\u00e8s ? Faut-il appuyer sur les capacit\u00e9s du JSF pour activer sa promotion autant \u00e0 l&rsquo;exportation que devant le Congr\u00e8s, et alors r\u00e9duire d&rsquo;autant les arguments pour un renforcement des forces US avec d&rsquo;autres syst\u00e8mes, tel le F-22 ? De toutes les fa\u00e7ons, les USA peuvent-ils envisager de modifier compl\u00e8tement une politique industrielle et une politique \u00e0 l&rsquo;exportation toute enti\u00e8re ax\u00e9es sur un avion de combat, le JSF ? Pourtant, pourront-ils faire autrement qu&rsquo;essayer de le faire, autant \u00e0 cause de ce que repr\u00e9sentent d\u00e9sormais la Chine et son J-20 pour leur puissance strat\u00e9gique dans le Pacifique et en Asie, qu&rsquo;\u00e0 cause des difficult\u00e9s du JSF ? De quelque fa\u00e7on qu&rsquo;on prenne la question, la puissance militaire des USA se trouve confront\u00e9e \u00e0 ce qui ressemble fort \u00e0 une impasse syst\u00e9mique fondamentale dans le domaine de sa position strat\u00e9gique dominante.<\/p>\n<\/p>\n<p><p>\tEn effet, il s&rsquo;agit bien de strat\u00e9gie. Les progr\u00e8s chinois que d\u00e9taille Kopp sont impressionnants, et on peut certainement accorder \u00e0 cette analyse bien plus de cr\u00e9dits qu&rsquo;\u00e0 celles des analystes du Pentagone qui n&rsquo;ont rien vu venir, qui sont enferm\u00e9s dans leur vision virtualiste marqu\u00e9e du dogme de l&rsquo;invincibilit\u00e9 de la puissance US, qui se retrouvent aujourd&rsquo;hui avec la perspective d&rsquo;une sup\u00e9riorit\u00e9 strat\u00e9gique conventionnelle de la Chine en Asie et dans le Pacifique occidental. La question n&rsquo;est pas ici de d\u00e9terminer la possibilit\u00e9 d&rsquo;un conflit ou de tout autre \u00e9v\u00e9nement brutal de cette sorte, mais bien de d\u00e9terminer le sort de cette \u00e9norme zone d&rsquo;influence jusqu&rsquo;ici domin\u00e9e par les USA, leur flotte et, surtout, leur sup\u00e9riorit\u00e9 a\u00e9rienne. Cette sup\u00e9riorit\u00e9 a\u00e9rienne est tr\u00e8s fortement mise en question, tandis que la flotte US se trouve d\u00e9sormais devant la possibilit\u00e9 de situations tr\u00e8s s\u00e9rieuses \u00e0 cause de nouveaux syst\u00e8mes anti-navires chinois d\u00e9velopp\u00e9s sp\u00e9cifiquement pour d\u00e9truire les porte-avions US et qui inqui\u00e8tent affreusement l&rsquo;U.S. Navy. La question strat\u00e9gique devient alors celle de l&rsquo;influence. Comment les diff\u00e9rents pays de la zone vont-ils se d\u00e9terminer en fonction de ce changement tectonique qui s&rsquo;amorce de l&rsquo;\u00e9quilibre des forces ?<\/p>\n<\/p>\n<p><p>\tMais nous ne cherchons pas vraiment des r\u00e9ponses \u00e0 toutes ces questions, non plus que nous ne cherchons \u00e0 d\u00e9terminer une nouvelle situation strat\u00e9gique, avec des possibilit\u00e9s en cas de conflit, etc. Ce qui nous importe ici est qu&rsquo;il s&rsquo;agit d&rsquo;une situation o\u00f9 des pi\u00e8ces fondamentales sont en train d&rsquo;\u00e9voluer, dans une zone strat\u00e9gique d&rsquo;une importance fondamentale pour les principaux acteurs, o\u00f9 les positions sont tranch\u00e9es dans des postures d&rsquo;affrontement depuis des d\u00e9cennies, o\u00f9 la situation de la Guerre froide n&rsquo;a pratiquement pas chang\u00e9, au contraire de la situation en Europe depuis 1989. Il s&rsquo;agit d&rsquo;un enjeu d&rsquo;une \u00e9norme importance, tel qu&rsquo;il est appr\u00e9ci\u00e9 notamment par le principal acteur, celui qui se trouve dans une position \u00e9trangement asym\u00e9trique, comme il a l&rsquo;habitude d&rsquo;\u00eatre dans d&rsquo;autres zones mais plus encore dans celle-ci, d&rsquo;\u00eatre \u00e0 la fois \u00e9tranger \u00e0 cette zone d&rsquo;un point de vue g\u00e9ographique et culturel, et d&rsquo;une influence strat\u00e9gique et militaire \u00e9crasante dans cette zone.<\/p>\n<h3>Une d\u00e9marche gaulliste<\/h3>\n<\/p>\n<p><p>\tEn effet, si la Chine affronte l&rsquo;Am\u00e9rique d&rsquo;une fa\u00e7on sym\u00e9trique, sur le m\u00eame terrain des armements conventionnels de hautes technologies, contrairement \u00e0 l&rsquo;habitude aujourd&rsquo;hui de chercher des affrontements asym\u00e9triques, par contre les positions strat\u00e9giques sont compl\u00e8tement asym\u00e9triques. Les USA se trouvent en position de domination dans une zone g\u00e9ographique qui leur est compl\u00e8tement \u00e9trang\u00e8re, au contraire de la Chine qui est dans sa zone naturelle, alors que les rapports de puissance entre les deux puissances \u00e9voluent comme l&rsquo;on sait.<\/p>\n<\/p>\n<p><p>\tAinsi l&rsquo;affrontement des syst\u00e8mes d&rsquo;arme du point de vue de leurs capacit\u00e9s, donc de leurs forces d&rsquo;influence \u00e0 terme sur les pays de la zone, implique un enjeu beaucoup plus important que ce simple rapport d&rsquo;armement. D&rsquo;un c\u00f4t\u00e9 (le c\u00f4t\u00e9 US), il y a la puissance brute, la force h\u00e9g\u00e9monique, qui semblait jusqu&rsquo;alors p\u00e9renne mais qui est soudain contest\u00e9e et dont on d\u00e9couvre alors qu&rsquo;elle ne s&rsquo;appuyait sur aucune l\u00e9gitimit\u00e9 ; cette absence de l\u00e9gitimit\u00e9 \u00e9tait n\u00e9gligeable du temps o\u00f9 cette puissance surclassait toutes les autres, elle devient extr\u00eamement embarrassante et \u00e0 terme mortelle si cette sup\u00e9riorit\u00e9 est mise en cause d&rsquo;une fa\u00e7on aussi r\u00e9solue. De l&rsquo;autre c\u00f4t\u00e9, une puissance mondiale qui s&rsquo;affirme, qui cherche moins l&rsquo;h\u00e9g\u00e9monie et l&rsquo;influence que l&rsquo;affirmation de sa puissance dans sa zone normale de voisinage, sinon d&rsquo;influence, ce qui est \u00e0 notre sens le cas de la Chine. (Le reste, notamment les pr\u00e9tendues vis\u00e9es imp\u00e9rialistes de la Chine, est du domaine de la <em>narrative<\/em>. Lorsque la chose est r\u00e9cit\u00e9e par des sp\u00e9cialistes US, l&rsquo;analyse devient comique \u00e0 force de grotesque, pour cette puissance US qui navigue en mode imp\u00e9rialiste depuis plus d&rsquo;un si\u00e8cle.)<\/p>\n<\/p>\n<p><p>\tLes Chinois n&rsquo;ont aucune conception particuli\u00e8re d&rsquo;h\u00e9g\u00e9monie et d&rsquo;id\u00e9al de puissance \u00e0 la mode US  derri\u00e8re le d\u00e9veloppement de leurs armements. Ils le font \u00e0 la mani\u00e8re gaulliste, pour assurer un rang et la permanence d&rsquo;une souverainet\u00e9. C&rsquo;est le contraire de la m\u00e9thodologie et de la philosophie de la mati\u00e8re d\u00e9cha\u00een\u00e9e de l&rsquo;id\u00e9al de puissance des USA, qui d\u00e9veloppent la puissance des armes selon la logique de la pouss\u00e9e du syst\u00e8me du technologisme, par simple dynamique de puissance se traduisant par l&rsquo;influence et la domination. (L&rsquo;exemple gaulliste \u00e0 cet \u00e9gard se trouve dans le cas de la France avec sa force de frappe nucl\u00e9aire des ann\u00e9es 1960, dans les conditions o\u00f9 elle fut con\u00e7ue; la France gaulliste fut ainsi le seul pays \u00e0 d\u00e9velopper une quincaillerie conforme au <em>diktat<\/em> du syst\u00e8me du technologisme et des USA \u00e0 l&rsquo;\u00e9poque, en s&rsquo;appuyant sur et en d\u00e9veloppant parall\u00e8lement une philosophie contraire \u00e0 celle du m\u00eame syst\u00e8me du technologisme et des m\u00eames USA. [Voir <a href=\"http:\/\/www.dedefensa.org\/article-cinquieme_partie_la_transversale_du_technologisme_02_12_2010.html\" class=\"gen\">notre partie<\/a> de <em>La gr\u00e2ce de l&rsquo;Histoire<\/em> sur \u00ab<em>La transversale du technologisme<\/em>\u00bb.]) Dans le cas qui nous occupe, les Chinois ont d\u00e9velopp\u00e9 une quincaillerie, la technologie furtive et divers syst\u00e8mes autour d&rsquo;elle, qui r\u00e9pondent au <em>diktat<\/em> actuel du syst\u00e8me du technologisme et des USA, des moyens militaires en d\u00e9veloppement,  mais ces moyens qui seraient alors retourn\u00e9s contre eux, le syst\u00e8me du technologisme et les USA, leurs conceptions h\u00e9g\u00e9moniques, leur philosophie de puissance. Ce sont donc deux conceptions qui s&rsquo;opposent dans cette opposition strat\u00e9gique entre USA et Chine, dont le facteur central devient alors le sort m\u00eame du syst\u00e8me du technologisme.<\/p>\n<\/p>\n<p><p>\tLes USA sont en Asie et dans le Pacifique occidental au nom de leur puissance,  de l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-notre_11_novembre_11_11_2008.html\" class=\"gen\">id\u00e9al de puissance<\/a> si l&rsquo;on veut bien accepter notre langage. La p\u00e9rennit\u00e9 de leur pr\u00e9sence, de leur influence et de leur h\u00e9g\u00e9monies t\u00e9moigne de la puissance du syst\u00e8me du technologisme et repr\u00e9sente autant tous les caract\u00e8res de ce syst\u00e8me La pr\u00e9sence, l&rsquo;influence, l&rsquo;h\u00e9g\u00e9monie US dans le Pacifique occidental et en Asie, ce sont celles du syst\u00e8me du technologisme et, au-del\u00e0, bien entendu, du Syst\u00e8me lui-m\u00eame, notre fameux Syst\u00e8me-en-soi. Si la puissance chinoise qui commence \u00e0 s&rsquo;affirmer commence \u00e0 supplanter celle des USA, si les USA sont oblig\u00e9s de retraiter dans une position proche de l&rsquo;effondrement,  pour des questions diverses, aussi fondamentales que leurs moyens budg\u00e9taires, leurs choix vici\u00e9s et subversifs de leurs syst\u00e8mes, leur incapacit\u00e9 de produire des syst\u00e8mes avanc\u00e9s,  c&rsquo;est principalement le syst\u00e8me du technologisme que la Chine supplantera et \u00e0 qui elle infligera une d\u00e9faite terrible. (On comprend qu&rsquo;il n&rsquo;est nullement n\u00e9cessaire de bataille dans le sens guerrier dans tout cela, il s&rsquo;agit de l&rsquo;agitation des quincailleries diverses et de la pr\u00e9sence ou de l&rsquo;absence de principes essentiels comme la l\u00e9gitimit\u00e9, la souverainet\u00e9, etc. On notera \u00e9galement, et c&rsquo;est pourquoi nous avons cit\u00e9 cette partie du texte du Dr. Kopp, que l&rsquo;analyse que fait ce dernier du d\u00e9veloppement des syst\u00e8mes chinois constitue une terrible critique directe et indirecte des capacit\u00e9s de conception et de production de la base technologique US, dont il juge qu&rsquo;elle est ridiculis\u00e9e en termes de rapidit\u00e9, d&rsquo;efficacit\u00e9, de qualit\u00e9 et en co\u00fbts, par la base technologique chinoise. Si c&rsquo;est bien le cas, il s&rsquo;agit plus encore d&rsquo;une terrible d\u00e9faite du syst\u00e8me du technologisme, vraiment sans n\u00e9cessit\u00e9 de bataille. Pour nous, bien entendu, c&rsquo;est bien le cas, puisque nous tenons l&rsquo;appareil technologico-industriel des USA dans le domaine de l&rsquo;armement au bord de la paralysie et de l&rsquo;improductivit\u00e9 chronique.)<\/p>\n<\/p>\n<p><p>\tL&rsquo;enjeu va donc, par cons\u00e9quent, bien au-del\u00e0 de simples positions strat\u00e9giques, voire de la position h\u00e9g\u00e9monique des USA, et d&rsquo;une h\u00e9g\u00e9monie en retraite. Dans cette affaire qui, avec le J-20, et l&rsquo;extraordinaire battage de communication qui l&rsquo;a accompagn\u00e9, a pris les allures de grand \u00e9v\u00e9nement strat\u00e9gique et de communication gr\u00e2ce \u00e0 la sagacit\u00e9 de la chronologie des Chinois \u00e0 cet \u00e9gard (premier vol du J-20 alors que Gates \u00e9tait en Chine), c&rsquo;est le statut m\u00eame du syst\u00e8me du technologisme qui est en jeu. Les USA en sont les repr\u00e9sentants, nous dirions, par droit divin. Leur d\u00e9faite en l&rsquo;occurrence, leur recul, l&rsquo;acceptation d&rsquo;une pr\u00e9sence grandissante des Chinois, la crainte des syst\u00e8mes d&rsquo;arme chinois, tout cela constitue autant de reculades et d&rsquo;humiliations inflig\u00e9es au syst\u00e8me du technologisme qui guide la puissance des USA, c&rsquo;est-\u00e0-dire la folle course de puissance d\u00e9structurante du Syst\u00e8me. Naturellement, on liera de fa\u00e7on tr\u00e8s serr\u00e9e ces deux reculs strat\u00e9giques, \u00e9ventuellement ces deux effondrements dans le cadre de cette affaire,  ceux du syst\u00e8me du technologisme et celui des USA eux-m\u00eames. Tout \u00e7a, c&rsquo;est la m\u00eame boutique,  et c&rsquo;est la p\u00e9riode des soldes&#8230;<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00e9ch\u00e9ance fatale du syst\u00e8me du technologisme ? 12 janvier 2011 Nous revenons sur le cas de l&rsquo;avion de combat chinois J-20 (ou J-XX) apr\u00e8s l&rsquo;avoir abord\u00e9 \u00e0 deux reprises, le 31 d\u00e9cembre 2010 et le 11 janvier 2011, selon des points de vue diff\u00e9rents. Cette fois, nous entendons traiter ce cas d&rsquo;une fa\u00e7on tr\u00e8s g\u00e9n\u00e9rale,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3143,8158,10712,3977,2651,249,4655,3650,10654,250,6297,3571,3014,4268],"class_list":["post-72662","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-air","tag-apa","tag-australian","tag-chine","tag-du","tag-f-22","tag-furtivite","tag-hegemonie","tag-j-20","tag-jsf","tag-pacifique","tag-power","tag-systeme","tag-technologisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72662","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72662"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72662\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}