{"id":72673,"date":"2011-01-18T05:58:24","date_gmt":"2011-01-18T05:58:24","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/01\/18\/le-complexe-extension-du-domaine-de-la-lutte\/"},"modified":"2011-01-18T05:58:24","modified_gmt":"2011-01-18T05:58:24","slug":"le-complexe-extension-du-domaine-de-la-lutte","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/01\/18\/le-complexe-extension-du-domaine-de-la-lutte\/","title":{"rendered":"Le Complexe : \u201cextension du domaine de la lutte\u201d"},"content":{"rendered":"<p><p>Un aspect int\u00e9ressant de l&rsquo;\u00e9volution du Complexe, dont on f\u00eate le cinquantenaire de l&rsquo;intronisation (discours du <a href=\"http:\/\/www.dedefensa.org\/article-un_general-president_nous_parle_du_complexe_militaro-industriel_10_08_2005.html\" class=\"gen\">17 janvier 1961<\/a> du pr\u00e9sident Eisenhower), est l&rsquo;entreprise de reclassement des chefs militaires (g\u00e9n\u00e9raux et amiraux) dans la vie civile apr\u00e8s leur mise \u00e0 la retraite. Janine R. Wedel et Linda Keenan viennent de publier un livre (<em>Shadow Elite<\/em>) qui pr\u00e9sente une enqu\u00eate sur cette \u00e9volution. Elles ont publi\u00e9 le <a href=\"http:\/\/www.huffingtonpost.com\/janine-r-wedel\/emshadow-eliteem-eisenhow_b_808410.html\" class=\"gen\">13 janvier 2011<\/a>, sur le site <em>HuffingtonPost<\/em>, un article traitant de ce probl\u00e8me.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>A real culture shift seems to have occurred among some in the military elite, and it mirrors my (Janine&rsquo;s) findings in Shadow Elite, which show a decline in loyalty to institutions such as government. Even in a place like the military, where devotion to the institution is paramount, many of the top players are focused on turning themselves into one-man defense industry moguls, some of them angling for personal rewards even before official retirement. Senator Jack Reed of Rhode Island  a West Point grad  said this to Bryan Bender of the Boston Globe: When I was an officer in the 1970s, most general officers went off to some sunny place and retired&#8230;.Now the definition of success &#8230; is to move on and become successful in the business world.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Bender&rsquo;s must-read investigation just after Christmas examines the activities of the staggering numbers of top generals who retire to highly lucrative consulting or defense industry work. (This tracks alongside the trend in which more and more governing is outside of formal government and, where, for instance, three-quarters of people working for federal government are private contractors.) Lest one think the \u00ab\u00a0rent-a-general\u00a0\u00bb phenomenon is old news, Bender shows that this longtime trend seems to be accelerating:<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>From 2004 through 2008, 80 percent of retiring three- and four-star officers went to work as consultants or defense executives&#8230;[also known as] the &lsquo;rent-a-general&rsquo; business&#8230;That compares with less than 50 percent who followed that path a decade earlier, from 1994 to 1998.<\/em> [In 2007,] <em>thirty-four out of 39 three- and four-star generals and admirals who retired&#8230;are now working in defense roles  nearly 90 percent.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Not only do these generals and admirals profit from their years of privileged access to vital information and connections, but they also receive the deference accorded to them because of their service and those stars. Bender says this automatic deference continues after retirement, with generals often treated in advisory meetings as if they are still holding official roles.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;article met \u00e9galement en \u00e9vidence l&rsquo;extension du domaine de la lutte (ou de l&rsquo;influence) des chefs militaires retrait\u00e9s, vers le monde du syst\u00e8me de la communication, avec l&rsquo;influence qui va avec. Ce point vaut \u00e0 certains de rebaptiser le Complexe en y ajoutant aux dimension militaire et industrielle celle de la communication.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Amplifying their power, these generals are also in hot demand as media analysts. And according to a 2008 New York Times report, [m]ost of the analysts have ties to military contractors vested in the very war policies they are asked to assess on air. Journalist David Barstow later that year painted an indelible portrait in the Times of retired four-star Army General Barry McCaffrey, his swirl of defense consulting activities, and his success in promoting his interests on television: Barstow called it One Man&rsquo;s Military-Industrial-Media Complex.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The influence of McCaffrey and his peers derives from their overlapping, mutually influencing, and perhaps not fully disclosed, roles in pursuit of their own agendas. As they carve out coincidences of interest, their roles morph and blur into one another and ambiguity swirls around their activities.<\/em>\u00bb<\/p>\n<h4>Notre commentaire<\/h4>\n<p> Toutes ces informations ne sont aucunement des r\u00e9v\u00e9lations mais, rassembl\u00e9es et synth\u00e9tis\u00e9es, elles donnent effectivement un constat g\u00e9n\u00e9ral d&rsquo;un changement fondamental dans le r\u00f4le, la structure et l&rsquo;extension du Complexe,  <em>A real culture shift<\/em>, comme il est \u00e9crit. Les chiffres statistiques mentionn\u00e9s rendent compte sans aucune ambigu\u00eft\u00e9 possible de cet \u00e9norme d\u00e9placement d&rsquo;orientation et d&rsquo;activit\u00e9, lorsqu&rsquo;on constate qu&rsquo;en dix ans le nombre d&rsquo;officiers g\u00e9n\u00e9raux \u00e0 la retraite se reclassant dans des activit\u00e9s civiles de pouvoir et d&rsquo;influence est pass\u00e9 de 50% \u00e0 80%, avec 90% dans la seule ann\u00e9e 2007, qui est la derni\u00e8re ann\u00e9e de r\u00e9f\u00e9rence.<\/p>\n<\/p>\n<p><p>\tD&rsquo;autre part, la double orientation maintenant \u00e9vidente de ce reclassement (la communication s&rsquo;\u00e9tant ajout\u00e9e \u00e0 l&rsquo;industrie pure) a \u00e9galement une profonde signification et un puissant impact. On ne peut plus simplement appr\u00e9cier ce reclassement, ou ce blanchiment des militaires dans le civil, comme une simple op\u00e9ration d&rsquo;int\u00e9r\u00eat pour ceux qui la font, mais comme une op\u00e9ration id\u00e9ologique de renforcement du pouvoir et de l&rsquo;influence du Complexe dans le syst\u00e8me de l&rsquo;am\u00e9ricanisme en tant que tel, et, partant, dans le Syst\u00e8me en g\u00e9n\u00e9ral. (Cette op\u00e9ration n&rsquo;est pas le r\u00e9sultat d&rsquo;une organisation, d&rsquo;un dessein, d&rsquo;un complot, mais le simple effet de la dynamique de la puissance et de l&rsquo;influence psychologique d&rsquo;un syst\u00e8me anthropotechnocratique incomparablement homog\u00e8ne.) Les militaires \u00e0 la retraite ne s&rsquo;int\u00e8grent pas dans le Syst\u00e8me, ils changent le Syst\u00e8me au profit du Complexe ; eux-m\u00eames ne sont plus militaires (au sens de soldat) que de nom, \u00e9tant devenus des carri\u00e9ristes uniquement pr\u00e9occup\u00e9s de faire co\u00efncider leurs int\u00e9r\u00eats avec les int\u00e9r\u00eats du Complexe<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit moins d&rsquo;une militarisation du Syst\u00e8me que d&rsquo;une adaptation des militaires \u00e0 l&rsquo;\u00e9volution de la d\u00e9finition de la puissance. A cet \u00e9gard, c&rsquo;est surtout la p\u00e9n\u00e9tration des structures du syst\u00e8me de la communication qui est int\u00e9ressante et importante. Cela correspond au passage \u00e0 ce que nous avons d\u00e9sign\u00e9 comme le passage \u00e0 l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-politique_d_epoque_l_ere_psychopolitique_rubrique_analyse_volume_22_n07_du_10_decembre_2006_25_12_2006.html\" class=\"gen\">\u00e8re psychopolitique<\/a>, avec un changement complet de la d\u00e9finition de la puissance o\u00f9 la communication (information, influence, virtualisme, etc.) joue d\u00e9sormais un r\u00f4le quasiment aussi important que le syst\u00e8me du technologisme. De ce point de vue, les militaires ont assimil\u00e9 la diminution radicale de l&rsquo;importance de la g\u00e9opolitique au profit de la psychopolitique,  et, ce faisant, ils ont tourn\u00e9 l&rsquo;essentiel de leur pouss\u00e9e vers la situation int\u00e9rieure washingtonienne et le pouvoir, tandis que leur pr\u00e9pond\u00e9rance g\u00e9opolitique globale est devenue un fait fig\u00e9 et presque paralys\u00e9 marqu\u00e9 par un gigantisme de plus en plus lourd et co\u00fbteux.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est effectivement ce point qui est le plus important. Les serviteurs du Complexe, les officiers g\u00e9n\u00e9raux en l&rsquo;occurrence, ont d&rsquo;une part \u00e9volu\u00e9 dans le sens d&rsquo;un fractionnement du pouvoir de l&rsquo;am\u00e9ricanisme en assurant de plus en plus leur all\u00e9geance \u00e0 leur centre de pouvoir (le Complexe) au d\u00e9triment des notions de patriotisme, de nationalisme, etc. ; ils ont d&rsquo;autre part si bien r\u00e9ussi cette op\u00e9ration qu&rsquo;ils assurent \u00e0 cette fraction du pouvoir une place de plus en plus pr\u00e9\u00e9minente, de plus en plus \u00e9crasante, au point o\u00f9, de plus en plus, selon les circonstances et les avatars, le Complexe tend \u00e0 se substituer au Syst\u00e8me lui-m\u00eame. Les postes et les positions tenus d\u00e9sormais par les chefs militaires ayant subi le blanchissage du passage dans le civil assurent au Complexe, par le biais de la solidarit\u00e9 et de l&rsquo;unit\u00e9 d&rsquo;action de tous ces reclass\u00e9s, une coh\u00e9sion et une puissance qui d\u00e9passent largement le seul cadre militaire, strat\u00e9gique et de la s\u00e9curit\u00e9 nationale. Aucun autre groupe, f\u00fbt-ce Wall Street ou ce qu&rsquo;on nomme le <em>corporate power<\/em>, ne dispose d&rsquo;une telle coh\u00e9sion et d&rsquo;une telle unit\u00e9 d&rsquo;action, donc d&rsquo;une telle puissance. On peut avancer l&rsquo;hypoth\u00e8se que l&rsquo;influence du Complexe tend de plus en plus, d\u00e9sormais, \u00e0 peser d&rsquo;une mani\u00e8re directive et imp\u00e9rative sur les autres centres de pouvoir, qui lui sont de plus en plus subordonn\u00e9s <em>de facto<\/em>,  compris Wall Street et le <em>corporate power<\/em>,  qui devient, pour ce dernier cas du <em>corporate power<\/em>, une notion de plus en plus vague et de plus en plus \u00e9clat\u00e9e elle-m\u00eame. <\/p>\n<\/p>\n<p><p>\tDu point de vue du Complexe, il s&rsquo;agit d&rsquo;un formidable succ\u00e8s. Par contre, on sera beaucoup plus r\u00e9ticent si l&rsquo;on veut parler du Syst\u00e8me lui-m\u00eame. En investissant le Syst\u00e8me, le Complexe le charge de tous ses caract\u00e8res, notamment le poids \u00e9norme de sa bureaucratie, les pratiques de ses gaspillages, de sa corruption improductive, de son impuissance gestionnaire, de son aveuglement et de l&rsquo;absence de nuances de sa puissance, bref de tout ce qui fait qu&rsquo;on peut envisager aujourd&rsquo;hui, au travers de l&rsquo;impuissance et de la paralysie du Pentagone, un <em>coming crash<\/em> du Pentagone On comprend alors, si le Complexe est devenu la substance principale du Syst\u00e8me, qu&rsquo;un <em>coming crash<\/em> menace \u00e9galement le Syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tDans une telle situation de puissance et d&rsquo;influence, comment peut-on esp\u00e9rer peser sur une politique ext\u00e9rieure compl\u00e8tement militaris\u00e9e, sur des conflits sans fin et entretenus par l&rsquo;impuissance militaire, sur des d\u00e9penses qui nourrissent un d\u00e9ficit colossal et minent litt\u00e9ralement la puissance des USA ? Comment le Congr\u00e8s pourrait-il parvenir \u00e0 imposer des r\u00e9ductions budg\u00e9taires importantes au Pentagone, alors qu&rsquo;il existe un constat de plus en plus g\u00e9n\u00e9ral est que de telles r\u00e9ductions sont devenues imp\u00e9ratives pour sauver le gouvernement f\u00e9d\u00e9ral de l&rsquo;effondrement ? Il le faudrait pourtant, sinon la Chute menace&#8230; L&rsquo;\u00e9volution du Complexe est sans aucun douter un tribut rendu \u00e0 sa puissance extraordinaire,  mais qu&rsquo;importe, si cette puissance est celle de la Chute ? Mieux encore Que le Complexe triomphe encore plus compl\u00e8tement, rendant la Chute effectivement irr\u00e9m\u00e9diable.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 18 janvier 2011 \u00e0 05H56<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un aspect int\u00e9ressant de l&rsquo;\u00e9volution du Complexe, dont on f\u00eate le cinquantenaire de l&rsquo;intronisation (discours du 17 janvier 1961 du pr\u00e9sident Eisenhower), est l&rsquo;entreprise de reclassement des chefs militaires (g\u00e9n\u00e9raux et amiraux) dans la vie civile apr\u00e8s leur mise \u00e0 la retraite. Janine R. Wedel et Linda Keenan viennent de publier un livre (Shadow Elite)&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[6476,10727,7869,3015,3568,5118,2631,5160,3090,7941,4692,2622,3194,10728,5462,3014,10726],"class_list":["post-72673","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-amiraux","tag-ciomplexe","tag-coming","tag-communication","tag-corporate","tag-crash","tag-de","tag-generaux","tag-influence","tag-investissement","tag-keenan","tag-la","tag-pentagone","tag-poower","tag-retraite","tag-systeme","tag-wedell"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72673"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72673\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}