{"id":72703,"date":"2011-01-29T04:47:19","date_gmt":"2011-01-29T04:47:19","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/01\/29\/dialogues-20-la-peur-des-emeutes-des-gouvernements-occidentaux\/"},"modified":"2011-01-29T04:47:19","modified_gmt":"2011-01-29T04:47:19","slug":"dialogues-20-la-peur-des-emeutes-des-gouvernements-occidentaux","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/01\/29\/dialogues-20-la-peur-des-emeutes-des-gouvernements-occidentaux\/","title":{"rendered":"<em>DIALOGUES<\/em>-20 : la peur des \u00e9meutes des gouvernements occidentaux"},"content":{"rendered":"<p><h2 class=\"common-article2\"><em>DIALOGUES<\/em>-20 : la peur des \u00e9meutes des gouvernements occidentaux <\/h2>\n<\/p>\n<p><p>\tLes gouvernements europ\u00e9ens ont certainement peur des mouvements de rue pouvant d\u00e9g\u00e9n\u00e9rer en \u00e9meutes. On l&rsquo;a vu \u00e0 leur r\u00e9action face aux\u00a0\u00bb soul\u00e8vements\u00a0\u00bb sporadiques des \u00ab\u00a0jeunes\u00a0\u00bb r\u00e9cemment. Le bruit avait par exemple couru que Sarkozy avait demand\u00e9 \u00e0 ses conseillers de surveiller comme \u00ab le lait sur le feu \u00bb les \u00e9tudiants qui manifestaient contre l&rsquo;allongement de la dur\u00e9e de travail.  Mais finalement il n&rsquo;a c\u00e9d\u00e9 en rien aux protestations aussi fond\u00e9es qu&rsquo;elles aient \u00e9t\u00e9. Et chacun est rentr\u00e9 dans le rang. Il en a \u00e9t\u00e9 de m\u00eame dans les autres capitales europ\u00e9ennes. <\/p>\n<\/p>\n<p><p>\tAujourd&rsquo;hui, confront\u00e9s aux succ\u00e8s de la foule  ayant obtenu en quelques heures le d\u00e9part de Ben Ali et de sa famille, pourtant incrust\u00e9s profond\u00e9ment dans la soci\u00e9t\u00e9 tunisienne, face aussi aux manifestations croissantes se d\u00e9roulant au Caire ou dans d&rsquo;autres Etats arabes, certains observateurs  recommencent \u00e0 penser que des soul\u00e8vements pacifiques mais massifs pourraient obtenir des changements de gouvernement, voire des changements de r\u00e9gime, y compris dans des pays \u00e0 la longue tradition constitutionnelle comme les Etats-Unis ou les Etats europ\u00e9ens.<\/p>\n<\/p>\n<p><p>\tLe bon sens permet quand m\u00eame d&rsquo;en douter. Le niveau et les modes de vie, en Europe et aux Etats-Unis, ne sont gu\u00e8re comparables \u00e0 ceux des pays du Maghreb et du Moyen-Orient,. M\u00eame si en Occident, le ch\u00f4mage se d\u00e9veloppe, m\u00eame si les injustices tenant aux in\u00e9galit\u00e9s sont de plus en plus mal ressenties, m\u00eame si, pour employer mon cher Philippe votre expression que je partage, le Syst\u00e8me semble en voie de s&rsquo;y effondrer,  on peut douter qu&rsquo;un nombre suffisant de citoyens se rassemblent et manifestent, le temps qu&rsquo;il faudra, pour pr\u00e9cipiter la chute de ce Syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tLes populations, avec l&rsquo;exp\u00e9rience des guerres europ\u00e9ennes,  ont gard\u00e9 le souvenir du chaos complet  r\u00e9sultant de la disparition d&rsquo;un Etat et d&rsquo;une administration, aussi tyranniques qu&rsquo;aient \u00e9t\u00e9 ces structures. Des simulations avaient par ailleurs \u00e9t\u00e9 r\u00e9alis\u00e9es, auxquelles j&rsquo;avais particip\u00e9 au titre d&rsquo;Automates Intelligents, pour \u00e9valuer comment faire face aux cons\u00e9quences d&rsquo;une pand\u00e9mie \u00e0 forte mortalit\u00e9, de type grippal, \u00e9clatant en Europe. D&rsquo;une fa\u00e7on bien pire que du temps de la grande peste, la soci\u00e9t\u00e9 organis\u00e9e pourrait s&rsquo;y dissoudre, quelles que soient les bonnes volont\u00e9s des personnes d\u00e9cid\u00e9es au p\u00e9ril de leur vie \u00e0 assurer la continuit\u00e9 des services essentiels. Rien de tel ne s&rsquo;est encore produit en Tunisie, heureusement, mais la conscience du danger latent reste pr\u00e9sente dans un certain nombre d&rsquo;esprits. <\/p>\n<\/p>\n<p><p>\tEn France, il para\u00eet \u00e9vident que la majorit\u00e9 du corps politique n&rsquo;est pas pr\u00eate \u00e0 courir le risque d&rsquo;une \u00ab\u00a0r\u00e9volution\u00a0\u00bb qui, avant de faire \u00e9merger un ordre nouveau hypoth\u00e9tique, mettrait tout par terre, \u00e0 commencer par les distribanques, les grandes surfaces, les pharmacies, sans parler des propri\u00e9t\u00e9s et des pensions de retraite. On imagine par ailleurs sans peine la prolif\u00e9ration des d\u00e9traqu\u00e9s divers \u00e0 qui cette situation permettrait enfin de passer \u00e0 l&rsquo;acte.  On ne peut pas reprocher aux gens de regarder \u00e0 deux fois avant de se lancer dans l&rsquo;aventure de la r\u00e9volution au sens classique, ou simplement de l&rsquo;encourager. <\/p>\n<\/p>\n<p><p>\tJe ne vois gu\u00e8re que les jeunes exclus provenant des \u00ab\u00a0quartiers\u00a0\u00bb  qui pourraient \u00e9ventuellement marcher sur les centre-villes, comme certains commentateurs l&rsquo;avaient pronostiqu\u00e9 lors des derni\u00e8res \u00e9meutes dites urbaines. Et encore&#8230;Ils auraient trop peur de d\u00e9clencher contre eux une union sacr\u00e9e dont on voit bien les pr\u00e9textes. <\/p>\n<\/p>\n<p><p>\tIl faudrait vraiment que les gouvernements europ\u00e9ens fassent des erreurs \u00e9normes pour dresser contre eux des foules sur le mod\u00e8le tunisien ou \u00e9gyptien.<\/p>\n<\/p>\n<p><p>\tEst-ce \u00e0 dire que surgies des profondeurs et prenant des formes que seuls des t\u00e9moins aussi \u00e9clair\u00e9s que vous seraient capables de d\u00e9tecter, des r\u00e9volutions ne se pr\u00e9pareraient pas dans nos pays? Il s&rsquo;agit d&rsquo;une tr\u00e8s grande question. Si nous r\u00e9pondions par la n\u00e9gative, non seulement nous d\u00e9sesp\u00e9rerions Billancourt, mais nous ent\u00e9rinerions un  postulat tout \u00e0 fait arbitraire selon lequel aucun changement prenant la forme d&rsquo;une mutation se produisant l\u00e0 o\u00f9 nul ne l&rsquo;attend ne serait possible au sein de nos soci\u00e9t\u00e9s, dont les imperfections, pour ne pas dire les perversions, sont de plus en plus visibles et mal support\u00e9es. <\/p>\n<\/p>\n<p><p>\tPour ma part, je suis de ceux qui pensent que quelque chose se pr\u00e9pare, lourd de cons\u00e9quences, dont sans doute nos vies seront affect\u00e9es, mais dont il est difficile aujourd&rsquo;hui d&rsquo;envisager les modalit\u00e9s. L&rsquo;attitude disons scientifique consiste alors \u00e0 rester en alerte, en rassemblant et questionnant tous les indices dont on peut disposer. C&rsquo;est un travail de cette sorte que fait excellemment <em>dedefensa<\/em>, rendant sa lecture quotidienne indispensable. <\/p>\n<\/p>\n<p><p>\tPour notre part \u00e0 tous deux, si ces <em>DIALOGUES<\/em> peuvent nous permettre de pr\u00e9ciser ces hypoth\u00e8ses, nous devons les poursuivre.<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Jean-Paul Baquiast<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>DIALOGUES-20 : la peur des \u00e9meutes des gouvernements occidentaux Les gouvernements europ\u00e9ens ont certainement peur des mouvements de rue pouvant d\u00e9g\u00e9n\u00e9rer en \u00e9meutes. On l&rsquo;a vu \u00e0 leur r\u00e9action face aux\u00a0\u00bb soul\u00e8vements\u00a0\u00bb sporadiques des \u00ab\u00a0jeunes\u00a0\u00bb r\u00e9cemment. Le bruit avait par exemple couru que Sarkozy avait demand\u00e9 \u00e0 ses conseillers de surveiller comme \u00ab le lait&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[15],"tags":[7895,9550,10734],"class_list":["post-72703","post","type-post","status-publish","format-standard","hentry","category-dialogues","tag-baquiast","tag-egypte","tag-tunisie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72703"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72703\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}