{"id":72754,"date":"2011-02-14T04:24:27","date_gmt":"2011-02-14T04:24:27","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/02\/14\/quel-printemps-pour-les-peuples-europeens\/"},"modified":"2011-02-14T04:24:27","modified_gmt":"2011-02-14T04:24:27","slug":"quel-printemps-pour-les-peuples-europeens","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/02\/14\/quel-printemps-pour-les-peuples-europeens\/","title":{"rendered":"Quel printemps pour les peuples europ\u00e9ens?"},"content":{"rendered":"<p><h2 class=\"common-article2\">Quel printemps pour les peuples europ\u00e9ens? <\/h2>\n<\/p>\n<p><p>\tNous avions fait l&rsquo;hypoth\u00e8se, dans notre <em>Ouverture libre<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-le_printemps_des_peuples_les_europeens_vont-ils_suivre_12_02_2011.html\" class=\"gen\">12 f\u00e9vrier 2011<\/a>, \u00ab<em>Le printemps des peuple<\/em>\u00bb, que l&rsquo;exemple des r\u00e9volutions tunisienne et \u00e9gyptienne allait peut-\u00eatre inspirer un certain nombre de peuples du monde jusqu&rsquo;ici priv\u00e9s de libert\u00e9 politique et de droits civiques par des gouvernements autoritaires. Ceci ne r\u00e9soudrait pas n\u00e9cessairement leurs difficult\u00e9s \u00e9conomiques mais y contribuerait. La d\u00e9mocratie rendrait plus difficile la confiscation et le gaspillage des ressources nationales par les cercles du pouvoir. Les individus rendus plus autonomes pourraient mieux participer \u00e0 la cr\u00e9ation de richesses collectives. Plus g\u00e9n\u00e9ralement, ceux qui sont situ\u00e9es au bas des \u00e9chelles sociales auraient davantage de moyens pour se faire entendre. On comprend que de telles perspectives, pour des populations qui ne disposent d&rsquo;aucun de ces avantages, consid\u00e9r\u00e9s comme allant de soi dans les d\u00e9mocraties europ\u00e9ennes, g\u00e9n\u00e8rent un grand enthousiasme collectif. <\/p>\n<\/p>\n<p><p>\tMais nous nous demandions quel type de r\u00e9volution serait susceptible de g\u00e9n\u00e9rer de l&rsquo;enthousiasme collectif  parmi les populations europ\u00e9ennes, puisque celles-ci, globalement, b\u00e9n\u00e9ficient depuis quelques d\u00e9cennies des libert\u00e9s civiques dont sont priv\u00e9es les citoyens vivant dans des dictatures. Or les Europ\u00e9ens, \u00e0 \u00e9couter ceux qui parlent en leur nom, font valoir nombre de sujets de m\u00e9contentements. Beaucoup  de ceux-ci ne sont pas tels qu&rsquo;ils les pousseraient \u00e0 descendre dans les rues pour provoquer une r\u00e9volution \u00e0 l&rsquo;\u00e9gyptienne. Ils sont cependant assez nombreux et importants pour inspirer ce que l&rsquo;on pourrait nommer de fa\u00e7on sommaire un v\u00e9ritable rejet du Syst\u00e8me. On peut donc penser que si des forces r\u00e9volutionnaires hypoth\u00e9tiques proposaient, non des am\u00e9nagements de fa\u00e7ade, mais de v\u00e9ritables mutations dans le Syst\u00e8me politique et \u00e9conomique global, elles pourraient susciter un grand enthousiasme populaire. <\/p>\n<\/p>\n<p><p>\tEncore faudrait-il que ces propositions ne soient pas utopiques. Les citoyens europ\u00e9ens sont suffisamment avertis d&rsquo;un certain nombre de contraintes globales pesant sur l&rsquo;humanit\u00e9 pour ne pas soutenir de programmes proposant par exemple le d\u00e9veloppement continu de la consommation, la diminution radicale du temps de travail  productif ou une \u00e9galit\u00e9 absolue entre r\u00e9gions et couches sociales.  En simplifiant beaucoup, nous pourrions dire que la revendication la plus susceptible de rassembler les populations europ\u00e9ennes concernerait le travail. Il s&rsquo;agirait d&rsquo;abord du droit au travail pour tous, autrement dit le  refus du ch\u00f4mage en train de devenir une v\u00e9ritable plaie, m\u00eame en Europe. Il s&rsquo;agirait ensuite, \u00e0 l&rsquo;int\u00e9rieur de chacune des professions, qu&rsquo;il s&rsquo;agisse du secteur public ou du secteur priv\u00e9, de la conqu\u00eate d&rsquo;une plus grande autonomie \u00e0 l&rsquo;\u00e9gard des hi\u00e9rarchies, des r\u00e9glementations et plus g\u00e9n\u00e9ralement des contraintes impos\u00e9es par un ordre \u00e9conomique lib\u00e9ral ou n\u00e9o-lib\u00e9ral devenu dominant en Europe, dont les inconv\u00e9nients apparaissent bien sup\u00e9rieurs aux avantages.  <\/p>\n<\/p>\n<p><p>\tDu temps o\u00f9 les oppositions de gauche s&rsquo;inspiraient d&rsquo;un marxisme th\u00e9orique, le rem\u00e8de propos\u00e9 aux dysfonctionnement des r\u00e9gimes capitalistes consistait \u00e0 remplacer les \u00ab patrons \u00bb par l&rsquo;Etat ou par des entreprises publiques assurant une r\u00e9partition dite tripartite du pouvoir entre les cadres, les personnels et les usagers. Ceci n&rsquo;a pas donn\u00e9 que de mauvais r\u00e9sultat, puisqu&rsquo;on doit \u00e0 une telle politique, en France, ce qui distingue encore notre pays de ses voisins plus lib\u00e9raux: les services publics de l&rsquo;\u00e9nergie et des transports, le secteur sant\u00e9-social, un certain nombre de grandes entreprises industrielles o\u00f9 l&rsquo;Etat a conserv\u00e9 une certaine participation,. Bien s\u00fbr, tout ceci est actuellement d\u00e9truit syst\u00e9matiquement par le capitalisme financier soutenu par un gouvernement acquis \u00e0 sa cause. Mais l&rsquo;on pourrait envisager qu&rsquo;une \u00ab r\u00e9volution \u00bb adapt\u00e9e aux exigences du temps pr\u00e9sent propose d&rsquo;y revenir. <\/p>\n<\/p>\n<p><p>\tCeci cependant ne serait pas suffisant. La financiarisation syst\u00e9matique de l&rsquo;\u00e9conomie, donnant priorit\u00e9 aux profits sp\u00e9culatifs sur la production de biens et services relevant de l&rsquo;\u00e9conomie dite r\u00e9elle, a mis en place au niveau mondial un syst\u00e8me d&rsquo;appropriation des r\u00e9sultats du travail au profit de nouveaux pouvoirs bien plus exploiteurs que les anciens chefs d&rsquo;entreprises. Les crises \u00e9conomiques r\u00e9centes les ont mis en \u00e9vidence. Il s&rsquo;agit des industries financi\u00e8res, banques, assurances, gestionnaires de march\u00e9s sp\u00e9culatifs. Il s&rsquo;agit aussi des gouvernements et des classes sociales sup\u00e9rieures qui, dans le monde entier, sans exception, se sont associ\u00e9s aux responsables  de ces organismes pour mettre en commun les moyens civils, r\u00e9glementaires et le cas \u00e9ch\u00e9ant militaires permettant de s&rsquo;imposer \u00e0 des populations  sans d\u00e9fense. <\/p>\n<\/p>\n<p><p>\tLes pays dits d\u00e9velopp\u00e9s, comme les pays \u00e9mergents ou ceux qui sont encore sous-d\u00e9velopp\u00e9s, n&rsquo;\u00e9chappent pas \u00e0 cette nouvelle tyrannie. Les Europ\u00e9ens, si aujourd&rsquo;hui ils voulaient renverser les dictateurs qui les oppriment, ne devraient pas se limiter \u00e0 renverser les gouvernements d\u00e9tenteurs du pouvoir politique. Ils devraient renverser parall\u00e8lement les d\u00e9tenteurs du pouvoir \u00e9conomique et social, en tout premier lieu les banques et les institutions financi\u00e8res qui soutiennent la sp\u00e9culation. L&rsquo;ennui est que celles-ci forment un r\u00e9seau sans faille au plan international. Vouloir r\u00e9former l&rsquo;un de ses repr\u00e9sentants entraine la r\u00e9action violente de l&rsquo;ensemble des autres. De plus, les banques et assurances r\u00e9pondent \u00e0 un  besoin ind\u00e9niable, celui de g\u00e9rer et faire circuler les \u00e9pargnes. Elles se sont appuy\u00e9es sur ces services pour d\u00e9velopper leurs activit\u00e9s sp\u00e9culatives et pr\u00e9datrices. Il faudrait donc, dans la perspective d&rsquo;une \u00ab r\u00e9volution \u00bb s&rsquo;en prenant au pouvoir financier, conserver, sous une forme moins pr\u00e9datrice, par exemple mutualis\u00e9e, les activit\u00e9s  utiles de la banque, de l&rsquo;assurance et de la monnaie.  <\/p>\n<\/p>\n<p><p>\tEst-ce \u00e0 dire qu&rsquo;une r\u00e9volution politique visant \u00e0 d\u00e9truire les pouvoirs qui oppriment les citoyens europ\u00e9ens, notamment en les privant de leur droit au travail et \u00e0 la responsabilit\u00e9 dans leur activit\u00e9 professionnelle, serait impossible. Beaucoup de gens le pensent. Le monde est trop complexe, l&rsquo;Europe est imbriqu\u00e9e dans des luttes entre blocs g\u00e9opolitiques bien trop puissants. Il faut se r\u00e9signer \u00e0 subir le ch\u00f4mage, la d\u00e9personnalisation de ce qui reste d&rsquo;activit\u00e9s productrices. Il faut accepter le luxe et le gaspillage dont profite une petite minorit\u00e9 de dominants se soutenant les uns les autres au plan international. Pour notre part, nous ne le pensons pas. Mais pour s&rsquo;en convaincre, il est n\u00e9cessaire de r\u00e9fl\u00e9chir \u00e0 la fa\u00e7on dont se feront les r\u00e9volutions \u00e0 notre \u00e9poque, qui est celle de l&rsquo;Internet et des r\u00e9seaux interactifs, dits du web 2.0. <\/p>\n<h3>Des cyber-activistes cognitifs <\/h3>\n<\/p>\n<p><p>\tLe monde va changer tr\u00e8s vite sous l&rsquo;influence de l&rsquo;\u00e9volution exponentielle des technologies de l&rsquo;information, de l&rsquo;intelligence artificielle et de la robotique autonome (voir notre pr\u00e9sentation du livre de Martin Ford, <em>The Lights in the Tunnel<\/em>, bien inform\u00e9 de ces questions). Ceci entra\u00eenera des cons\u00e9quences profondes sur les processus productifs et l&#8217;emploi, sur le contr\u00f4le impos\u00e9 aux populations mais aussi sur les modes d&rsquo;action des oppositions politiques et syndicales. Aucun pouvoir, aussi tyrannique qu&rsquo;il soit, ne pourra pr\u00e9tendre les neutraliser. Dans les syst\u00e8mes anthropotechniques chaotiques  en conflit qui sont ceux du monde global,  ces oppositions, que ce soit pour d\u00e9truire ou pour construire, s&rsquo;exprimeront n\u00e9cessairement dans et par les r\u00e9seaux. Mais quelle forme prendront-elles?<\/p>\n<\/p>\n<p><p>\tLes r\u00e9volutions tunisienne et \u00e9gyptienne en ont d\u00e9j\u00e0 donn\u00e9 une petite id\u00e9e. On doit se persuader qu&rsquo;une population, m\u00eame lorsqu&rsquo;elle est tr\u00e8s opprim\u00e9e, ne se r\u00e9volte pas spontan\u00e9ment. Il faut qu&rsquo;apparaissent (qu&rsquo;\u00e9mergent) des agitateurs. Ce furent les encyclop\u00e9distes du Tiers Etat avant la r\u00e9volution fran\u00e7aise de 1789, les intellectuels anarchisants des  r\u00e9volutions anti-czaristes avant 1917 ou les militants de la bourgeoisie fran\u00e7aise allant au peuple pour l&rsquo;\u00e9duquer durant l&rsquo;entre deux-guerre. Aujourd&rsquo;hui on commence \u00e0 d\u00e9signer de tels agitateurs par le terme d&rsquo; activistes cognitifs ou, dans la mesure o\u00f9 ils utiliseront massivement les ressources du web, de cyber-activistes cognitifs. <\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit dans les pays pauvres de repr\u00e9sentants des classes moyennes fortement dipl\u00f4mes qui ne trouvent pas leur place sur le march\u00e9 du travail et qui th\u00e9orisent les changements sociaux souhaitables. Mais au lieu de s&rsquo;exprimer comme jadis par les voies traditionnelles du militantisme et de la presse, ils utilisent les r\u00e9seaux interactifs. Ils s&rsquo;en servent non seulement pour pr\u00e9ciser leurs propositions mais pour les diffuser au sein des couches sociales qui ne se r\u00e9volteraient pas spontan\u00e9ment. Les pouvoirs, aussi tyranniques qu&rsquo;ils soient,  peuvent difficilement couper les r\u00e9seaux et neutraliser les serveurs, de plus en plus nombreux, m\u00eame dans les pays pauvres. <\/p>\n<\/p>\n<p><p>\tCeci dit, le terme de cyber-activisites cognitifs pourrait aussi d\u00e9signer, dans les pays d\u00e9velopp\u00e9s, les  innombrables sources qui contestent sur Internet les pouvoirs \u00e9tablis et proposent des solutions alternatives. Tout le bouillonnement en r\u00e9sultant ne s&rsquo;est pas encore concr\u00e9tis\u00e9 par des programmes politiques susceptibles de mobiliser les \u00e9lecteurs ou susciter d&rsquo;\u00e9ventuelles manifestations suivies, mais le mouvement est en marche.  <\/p>\n<\/p>\n<p><p>\tDans les pays d\u00e9velopp\u00e9s cependant, tels les pays europ\u00e9ens, les cyber-activistes cognitifs devront pour toucher les foules d\u00e9passer le niveau de l&rsquo;opposition primaire. Nous avons vu que les probl\u00e8mes \u00e0 r\u00e9soudre sont extr\u00eamement compliqu\u00e9s. Aucune solution ne peut s&rsquo;imposer dans susciter d&rsquo;innombrables d\u00e9bats. L&rsquo;ignorance, l&rsquo;intol\u00e9rance,  spontan\u00e9es ou entretenues,  des citoyens, sont consid\u00e9rables. Pour que les opinions se motivent en profondeur, soit en vue d&rsquo;une expression par la voie de la d\u00e9mocratie repr\u00e9sentative, soit \u00e0 d\u00e9faut dans la rue ou sous d&rsquo;autres formes non pr\u00e9vues par les institutions, un travail de formation, de construction et de dialogue en profondeur  s&rsquo;impose. Pour cela, il ne suffira pas de prise de paroles sur les blogs et moins encore d&rsquo;affirmations abruptes lanc\u00e9es sur twitter. M\u00eame des articles s&rsquo;effor\u00e7ant \u00e0 la p\u00e9dagogie comme le pr\u00e9sent texte ne suffiront pas. <\/p>\n<\/p>\n<p><p>\tNous pensons que les cyber-activistes cognitifs visant \u00e0 faire \u00e9voluer en profondeur les soci\u00e9t\u00e9s europ\u00e9ennes, dans le sens d&rsquo;une v\u00e9ritable r\u00e9volution citoyenne, devront s&rsquo;impliquer de deux fa\u00e7ons supposant un engagement total.<\/p>\n<\/p>\n<p><p>\t La premi\u00e8re et la plus importante consistera \u00e0 exp\u00e9rimenter des modes de production ou de distribution utilisant les nouvelles technologies pour changer en profondeur les activit\u00e9s \u00e9conomiques. Il s&rsquo;agira d&rsquo;enlever du pouvoir aux formes concentr\u00e9es d&rsquo;exploitation soumises aux int\u00e9r\u00eats financiers mondialis\u00e9s pour le redonner \u00e0 des producteurs locaux mutualis\u00e9s. Cela concernera l&rsquo;agriculture, les diverses formes de production industrielles ou artisanales relocalisables, la banque et l&rsquo;assurance mutualistes.  Mais il s&rsquo;agira aussi de repenser les activit\u00e9s de service, y compris celles relevant de la sph\u00e8re publique. Ceux qui auront les moyens ou le courage de se lancer dans de telles exp\u00e9riences devront utiliser syst\u00e9matiquement les ressources de l&rsquo;internet pour faire connaitre et discuter leurs objectifs et leurs r\u00e9sultats. S&rsquo;ils ne le font pas, ils ne p\u00e8seront pas face aux multinationales et aux politiques publiques qui sont \u00e0 leur service. <\/p>\n<\/p>\n<p><p>\tLe second mode d&rsquo;action, plus ludique et facile en apparence, consistera \u00e0 utiliser les ressources de l&rsquo;intelligence artificielle et de la gestion des connaissances en ligne pour int\u00e9resser les citoyens de la base \u00e0 la fa\u00e7on dont des r\u00e9formes, voire des r\u00e9volutions, pourraient am\u00e9liorer leur condition de travailleur et de consommateur de produits culturels. On sait qu&rsquo;aujourd&rsquo;hui, les personnes m\u00eame les plus d\u00e9favoris\u00e9es consacrent beaucoup de leur temps \u00e0 des \u00e9missions de t\u00e9l\u00e9vision qui sont des machines \u00e0 d\u00e9cerveler et \u00e0 soumettre. Il faudrait que des cyber-activistes cognitifs de plus en plus nombreux proposent des produits (par exemple sur le mode des jeux vid\u00e9os) capables de rendre concrets les enjeux et les modes d&rsquo;organisation d&rsquo;une soci\u00e9t\u00e9 europ\u00e9enne devenue en profondeur digne des valeurs qu&rsquo;elle pr\u00e9tend incarner.<\/p>\n<\/p>\n<p><p>\tDe telles propositions, faites rapidement comme c&rsquo;est le cas du pr\u00e9sent article, resteront sans doute incompr\u00e9hensibles \u00e0 beaucoup. Mais nous sommes persuad\u00e9s que certains cyber-activistes cognitifs europ\u00e9ens, ceux que nous pourrions qualifier de citoyens,  ont d\u00e9j\u00e0 r\u00e9fl\u00e9chi  \u00e0 la fa\u00e7on de les concr\u00e9tiser. Bien mieux, ils le font d\u00e9j\u00e0 mais ils n&rsquo;ont pas fait assez d&rsquo;efforts pour se faire connaitre \u00e0 l&rsquo;\u00e9chelle europ\u00e9enne, compte tenu des diff\u00e9rences de langage et de culture propres \u00e0 ce continent qui en sont par ailleurs la richesse.<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Jean-Paul Baquiast<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quel printemps pour les peuples europ\u00e9ens? Nous avions fait l&rsquo;hypoth\u00e8se, dans notre Ouverture libre du 12 f\u00e9vrier 2011, \u00abLe printemps des peuple\u00bb, que l&rsquo;exemple des r\u00e9volutions tunisienne et \u00e9gyptienne allait peut-\u00eatre inspirer un certain nombre de peuples du monde jusqu&rsquo;ici priv\u00e9s de libert\u00e9 politique et de droits civiques par des gouvernements autoritaires. Ceci ne r\u00e9soudrait&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[7895,9550,2879],"class_list":["post-72754","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-baquiast","tag-egypte","tag-revolution"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72754","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72754"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72754\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72754"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72754"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72754"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}