{"id":72759,"date":"2011-02-15T11:46:00","date_gmt":"2011-02-15T11:46:00","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/02\/15\/lenigme-nucleaire-du-sphinx\/"},"modified":"2011-02-15T11:46:00","modified_gmt":"2011-02-15T11:46:00","slug":"lenigme-nucleaire-du-sphinx","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/02\/15\/lenigme-nucleaire-du-sphinx\/","title":{"rendered":"L&rsquo;\u00e9nigme nucl\u00e9aire du Sphinx"},"content":{"rendered":"<p><h2 class=\"common-article\">L&rsquo;\u00e9nigme nucl\u00e9aire du Sphinx<\/h2>\n<\/p>\n<p><p>\t15 f\u00e9vrier 2011  L&rsquo;arm\u00e9e \u00e9gyptienne a pris le pouvoir que lui a offert, avec un empressement contraint, le pr\u00e9sident et ex-dictateur Osni Moubarak. Elle en fait un usage diligent : dissolution du Parlement, suspension de la Constitution, tentative de remise en ordre au Caire et dans le pays, etc. La r\u00e9volution doit s&rsquo;accorder un r\u00e9pit, pensent les militaires.<\/p>\n<\/p>\n<p><p>\tLes commentateurs aussi, ce qui permet d&rsquo;\u00e9ventuellement chercher \u00e0 distinguer les choses au-del\u00e0 de la simple \u00e9ch\u00e9ance de la chute d&rsquo;un dictateur. L&rsquo;arm\u00e9e au pouvoir, cela n&rsquo;a gu\u00e8re de signification pr\u00e9cise en soi, l&rsquo;id\u00e9e variant fortement selon les situations et les pays ; dans ce cas de l&rsquo;Egypte, il para\u00eet acquis que ce corps va exercer sur la vie politique \u00e9gyptienne un poids consid\u00e9rable, directement en principe dans les six mois qui viennent avec la pr\u00e9paration des \u00e9lections et diff\u00e9rentes r\u00e9formes, indirectement, au-del\u00e0, quelle que soit la forme que prendra le nouveau gouvernement de l&rsquo;Egypte. (Y compris, bien entendu, l&rsquo;hypoth\u00e8se du maintien au pouvoir de l&rsquo;arm\u00e9e.) Encore ce sch\u00e9ma doit-il \u00eatre nuanc\u00e9 fortement devant les al\u00e9as consid\u00e9rables qui se manifestent, qui peuvent \u00eatre r\u00e9unis sous le terme du d\u00e9sordre qui pourrait gagner si les m\u00e9contentements divers s&rsquo;exprimant aujourd&rsquo;hui \u00e0 ciel ouvert ne sont pas contenus dans la p\u00e9riode transitoire. Cette r\u00e9serve peut \u00eatre accessoire ou fondamentale, selon le tour que prendront les \u00e9v\u00e9nements durant les prochaines semaines, dans un climat g\u00e9n\u00e9ral dans la r\u00e9gion devenue, sans surprise excessive, extr\u00eamement <a href=\"http:\/\/www.guardian.co.uk\/world\/2011\/feb\/14\/middle-east-iran-bahrain-yemen\" class=\"gen\">volatile<\/a> (Iran, Yemen, Bahrain). Tout cela contient une r\u00e9serve de prolongements inattendus qui peuvent compl\u00e8tement marginaliser ou transformer les analyses faites aujourd&rsquo;hui,  y compris la n\u00f4tre.<\/p>\n<\/p>\n<p><p>\tAvant de passer \u00e0 une analyse plus compl\u00e8te de la situation et de ses possibles d\u00e9veloppements selon un axe qui nous para\u00eet essentiel, nous mettrons en \u00e9vidence un texte portant sur la situation et les \u00e9ventuelles ambitions nucl\u00e9aires de l&rsquo;Egypte. Cela concerne l&rsquo;arm\u00e9e, la puissance de l&rsquo;Egypte, son orientation politique, etc. Mis en ligne sur <em>Huffington.post<\/em> le <a href=\"http:\/\/www.huffingtonpost.com\/joe-cirincione\/egypts-nuclear-dimension_b_822588.html?view=print\" class=\"gen\">13 f\u00e9vrier 2011<\/a>, le texte est de Joe Cirincione, pr\u00e9sident du Ploughshares Fund. Il nous parle des ambitions nucl\u00e9aires de l&rsquo;Egypte, en observant, en guise d&rsquo;introduction : \u00ab<em>As a free Egypt transforms itself, analysts are nervously watching for signs of new nuclear ambitions<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;article explore diff\u00e9rents domaines, portant sur certaines activit\u00e9s inexpliqu\u00e9es de l&rsquo;Egypte en mati\u00e8re nucl\u00e9aire, sur le constat que l&rsquo;Egypte dispose des moyens et de la technologie pour devenir une puissance nucl\u00e9aire (civile, c&rsquo;est-\u00e0-dire potentiellement militaire), sur le rappel que l&rsquo;Egypte joue un r\u00f4le central dans la dynamique de non-prolif\u00e9ration et, surtout, dans la recherche d&rsquo;un accord pour l&rsquo;\u00e9tablissement d&rsquo;une zone d\u00e9nucl\u00e9aris\u00e9e au Moyen-Orient. L&rsquo;essentiel de l&rsquo;article est ainsi suffisamment pr\u00e9sent\u00e9 pour qu&rsquo;on comprenne qu&rsquo;il existe d&rsquo;ores et d\u00e9j\u00e0, dans tous les cas potentiellement, une question nucl\u00e9aire \u00e9gyptienne, un peu \u00e0 la mani\u00e8re de la question nucl\u00e9aire iranienne<\/p>\n<\/p>\n<p><p>\tNous proposons deux extraits de ce texte, qui nous serviront plus loin dans notre raisonnement.<\/p>\n<\/p>\n<p><p>\t Le premier concerne des d\u00e9tails sur les r\u00f4les et positions respectives de divers acteurs \u00e9gyptiens vis-\u00e0-vis du nucl\u00e9aire, avec, constamment, Moubarak jouant le r\u00f4le de frein dans une \u00e9ventuelle dynamique nucl\u00e9aire \u00ab<em>In 1984, Defense Minister Abdel Halim Abu Ghazala sought President Mubarak&rsquo;s approval to begin a nuclear weapons program. Mubarak rebuffed him, but Ghazala began looking into nuclear material supply routes anyway and communicated with Iraqi officials about potential nuclear cooperation. When Mubarak found out, he fired Ghazala.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>WikiLeaks cables contained unconfirmed reports of Cairo turning down black-market offers of nuclear technology from former Soviet states in the early 1990s. In more recent days, however, the Muslim Brotherhood has called for Egypt to develop a nuclear capability that could balance the threat posed by Israel. Mubarak kept a lid on Egyptian nuclear ambitions, but they never entirely disappeared.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Recently, Egypt has begun to accelerate its civilian atomic energy program, calling for international bids to construct the first of four planned nuclear reactors. Though permitted under the Non-Proliferation Treaty (NPT), this could get tricky<\/em><\/p>\n<\/p>\n<p><p>\t D&rsquo;autre part, un passage concernant le r\u00f4le de l&rsquo;Egypte dans la dynamique de non-prolif\u00e9ration (d&rsquo;ailleurs avec ElBaredei, qui est une personnalit\u00e9 politique importante actuellement, qui a dirig\u00e9 l&rsquo;Agence Internationale de l&rsquo;Energie Atomique pendant dix ans). Cette dynamique est particuli\u00e8rement sensible au niveau r\u00e9gional, avec la recherche de l&rsquo;\u00e9tablissement d&rsquo;une zone d\u00e9nucl\u00e9aris\u00e9e au Moyen-Orient.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Egypt has made the creation of a Middle East Free of Weapons of Mass Destruction (WMD) a central goal of its foreign policy. At the NPT Review Conference in 2010, agreement was reached only after all 187 nations agreed to the Egyptian-championed plan for a 2012 conference on the creation of a WMD-free zone in the Middle East.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>While all Middle Eastern nations have committed to participate, much work remains to be done to ensure that the 2012 conference is fruitful. Even before Mubarak fell, David Albright, president of the Institute for Science and International Security, feared that failure to make progress could be a catalyst for [the Egyptians] to leave the NPT. This would be a disaster, as many nations have long followed Egypt&rsquo;s lead on these issues.<\/em>\u00bb<\/p>\n<h4>Notre commentaire<\/h4>\n<p>Depuis l&rsquo;ind\u00e9pendance compl\u00e8te de l&rsquo;Egypte en 1952, l&rsquo;arm\u00e9e joue un r\u00f4le central, sinon exclusif dans l&rsquo;\u00e9volution politique. Mais ce r\u00f4le a notablement \u00e9volu\u00e9 dans son orientation politique, voire dans son essence politique m\u00eame. Il \u00e9tait d&rsquo;essence activiste, anti-colonialiste et nationaliste panarabe avec Nasser (Cas tout \u00e0 fait diff\u00e9rent de la Turquie, par exemple, avec laquelle certains pourraient tenter une analogie ; l&rsquo;arm\u00e9e au pouvoir en Turquie ayant toujours signifi\u00e9 une proximit\u00e9 de l&rsquo;Ouest, et, dans les trois ou quatre derni\u00e8res d\u00e9cennies, jusqu&rsquo;\u00e0 la servilit\u00e9 subventionn\u00e9e. L&rsquo;arm\u00e9e turque, garante du la\u00efcisme d&rsquo;Ataturk, a \u00e9volu\u00e9 n\u00e9cessairement, jusqu&rsquo;\u00e0 r\u00e9cemment, selon une grande proximit\u00e9 id\u00e9ologique objective avec l&rsquo;Ouest, bas\u00e9e sur l&rsquo;hostilit\u00e9 commune au fait religieux islamiste. L&rsquo;arm\u00e9e \u00e9gyptienne est marqu\u00e9e originellement mais fondamentalement par l&rsquo;anti-colonialisme, c&rsquo;est-\u00e0-dire exactement le contraire id\u00e9ologique,  par son hostilit\u00e9 originelle de l&rsquo;Ouest et de l&rsquo;utilisation de ses valeurs par l&rsquo;Ouest pour justifier l&rsquo;asservissement de l&rsquo;Egypte.)<\/p>\n<\/p>\n<p><p>\tAvec Sadate (1969-1981) et \u00e0 partir de cette situation nationaliste-panarabe du nass\u00e9risme, la direction \u00e9gyptienne a \u00e9volu\u00e9 vers un syst\u00e8me de plus en plus tourn\u00e9 vers l&rsquo;Ouest, comme moyen de pacifier le r\u00f4le de l&rsquo;Egypte et de le faire passer de l&rsquo;activisme \u00e0 l&rsquo;apaisement dans ce qu&rsquo;on pouvait esp\u00e9rer devenir un ordre stable et \u00e0 peu pr\u00e8s acceptable pour les uns et les autres, pour les Arabes et selon l&rsquo;influence massive des USA par des moyens directs et avec le moyen indirect fondamental du relais d&rsquo;Isra\u00ebl. Quoi qu&rsquo;on pense de cette tentative de Sadate, le fait est qu&rsquo;elle a totalement \u00e9chou\u00e9, d&rsquo;ailleurs pour des causes le plus souvent ext\u00e9rieures \u00e0 elle. D&rsquo;une part, l&rsquo;influence am\u00e9ricaniste sur la r\u00e9gion, tr\u00e8s puissante mais assez \u00e9quilibr\u00e9e, s&rsquo;est transform\u00e9e en une h\u00e9g\u00e9monie brutale, partisane et d\u00e9s\u00e9quilibr\u00e9e, avec Isra\u00ebl jouant de plus en plus un r\u00f4le agressif dans le m\u00eame sens ; d&rsquo;autre part, le pouvoir, avec Moubarak, a compl\u00e8tement perdu ses origines nass\u00e9riennes et est devenu une oligarchie afich\u00e9e, avec une corruption et un n\u00e9potisme dont on d\u00e9couvre aujourd&rsquo;hui l&rsquo;ampleur extraordinaire. (De ces deux causes, on observera que la seconde n&rsquo;en est pas vraiment une, mais plut\u00f4t une cons\u00e9quence directe de la premi\u00e8re, l&rsquo;am\u00e9ricanisation par le passage de l&rsquo;influence \u00e0 l&rsquo;h\u00e9g\u00e9monie impliquant \u00e9videmment une corruption totale. Le fait principal est l&rsquo;\u00e9volution de l&rsquo;influence devenant h\u00e9g\u00e9monie brutale des USA.)<\/p>\n<\/p>\n<p><p>\tAvec Moubarak, le pouvoir \u00e9gyptien s&rsquo;est institu\u00e9 comme un m\u00e9lange d&rsquo;enrichissement personnel effr\u00e9n\u00e9 des dirigeants, et une politique exactement calibr\u00e9e pour convenir aux forces dominantes contr\u00f4lant la r\u00e9gion (h\u00e9g\u00e9monie US avec relais isra\u00e9lien, omnipr\u00e9sence du conservatisme immobiliste, d\u00e9bouchant sur une guerre contre la terreur devenant en soi une sorte de politique fondamentale qui \u00e9cartait la pr\u00e9occupation de toutes les sp\u00e9cificit\u00e9s, revendications et d\u00e9s\u00e9quilibres internes et externes du pays et de la r\u00e9gion). L&rsquo;Egypte est devenu une puissance parasite sans aucune sp\u00e9cificit\u00e9 politique fondamentale, ou, selon une autre d\u00e9finition, un pays-rentier entretenu par les puissances h\u00e9g\u00e9moniques. Elle a perdu toute personnalit\u00e9, toute sp\u00e9cificit\u00e9, partant toute souverainet\u00e9 fondamentale, le r\u00e9gime perdant parall\u00e8lement toute l\u00e9gitimit\u00e9. (Bien entendu, tout cela sans s&rsquo;attacher \u00e0 la probl\u00e9matique de la d\u00e9mocratisation, dont on comprend qu&rsquo;elle est accessoire par rapport \u00e0 ces structurations et d\u00e9structurations fondamentales, et plus que jamais un enjeu pour la bonne conscience am\u00e9ricaniste-occidentaliste se manifestant de loin en loin, au milieu d&rsquo;une politique de soutien aveugle \u00e0 l&rsquo;ordre h\u00e9g\u00e9monique.)<\/p>\n<\/p>\n<p><p>\tL&rsquo;arm\u00e9e a largement profit\u00e9 de cette \u00e9volution, la chose a \u00e9t\u00e9 suffisamment document\u00e9e  ; et les dirigeants, Moubarak en premier, \u00e9taient tous des militaires Pour autant, nous observerons qu&rsquo;il ne s&rsquo;agissait nullement, ou plus du tout, de l&rsquo;arm\u00e9e au pouvoir. L&rsquo;\u00e9volution de corruption structurelle et psychologique du pouvoir, tout en impliquant l&rsquo;arm\u00e9e, a \u00e9loign\u00e9 la situation dite de l&rsquo;arm\u00e9e au pouvoir, selon l&rsquo;entendement qu&rsquo;on avait pu en avoir du temps de Nasser et de l&rsquo;\u00e9tat d&rsquo;esprit traditionnel de l&rsquo;arm\u00e9e \u00e9gyptienne avec Nasser. Avec le r\u00e9gime Moubarak, l&rsquo;arm\u00e9e profitait du pouvoir et le contr\u00f4lait en partie mais n&rsquo;en \u00e9tait plus partie prenante en tant que telle, tout comme Moubarak, ancien g\u00e9n\u00e9ral, n&rsquo;avait plus rien \u00e0 voir avec la fonction de militaire. La r\u00e9volution a bien fait la d\u00e9monstration de cette situation, <em>a contrario<\/em> dirait-on. L&rsquo;arm\u00e9e a \u00e9t\u00e9 conduite \u00e0 jouer un r\u00f4le soudain plus actif, puis essentiel, et l&rsquo;on s&rsquo;est aper\u00e7u qu&rsquo;elle \u00e9tait beaucoup moins monolithique qu&rsquo;on pouvait le croire, et qu&rsquo;elle \u00e9tait diff\u00e9rente du r\u00e9gime Moubarak, jusqu&rsquo;\u00e0 exiger et obtenir elle-m\u00eame le d\u00e9part de Moubarak et le blocage de sa succession (Omar Souleiman \u00e9cart\u00e9). Aujourd&rsquo;hui, l&rsquo;arm\u00e9e est victorieuse comme force d&rsquo;arbitrage, mais divis\u00e9e ; on devine que la veine nationaliste, ou disons populiste \u00e0-la-Nasser, existe toujours, ou bien rena\u00eet sous la pression des \u00e9v\u00e9nements. Par cons\u00e9quent, l&rsquo;arm\u00e9e succ\u00e9dant \u00e0 Moubarak ne sera pas la poursuite du syst\u00e8me Moubarak sous une autre forme. Ceux qui voient dans la prise du pouvoir par l&rsquo;arm\u00e9e une manipulation de plus des USA, avec l&rsquo;arm\u00e9e toute enti\u00e8re acquise aux USA, n&rsquo;ont pas raison, \u00e0 notre sens ; ils n&rsquo;ont pas raison sur le fond, et, bien s\u00fbr, sur la capacit\u00e9 manipulatrice des USA, qui n&rsquo;ont rien vu et rien compris de cette crise.<\/p>\n<\/p>\n<p><p>\t(Les experts am\u00e9ricanistes, eux, se doutent de quelque chose. Le <a href=\" http:\/\/warincontext.org\/2011\/02\/11\/in-egypt-the-seeds-of-a-new-world-order-and-the-end-of-western-supremacy\/\" class=\"gen\">12 f\u00e9vrier 2011<\/a>, Paul Woodward \u00e9crivait sur son site <MI>War in Context : \u00ab<em>Immediately after Hosni Mubarak resigned, Jake Tapper from ABC News tweeted that he couldn&rsquo;t find anyone in the administration who thought that whatever comes next would be better for U.S. interests than Mubarak had been. The dictator&rsquo;s departure is not being celebrated in Washington. The leaders of the free world have a singular lack of enthusiasm for freedom<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tDans ces conditions g\u00e9n\u00e9rales, avec les divisions au sein de l&rsquo;arm\u00e9e entre conservateurs et r\u00e9formistes, avec la pression populaire (sinon r\u00e9volutionnaire), avec le climat g\u00e9n\u00e9ral de la r\u00e9gion o\u00f9 de nouvelles lignes de fracture tendent \u00e0 rel\u00e9guer au second plan, tr\u00e8s vite, les antagonismes traditionnels institu\u00e9s du type am\u00e9ricanistes-occidentalistes (la civilisation contre le radicalisme islamiste, les vieux dictateurs pourris de l&rsquo;ordre occidentaliste-am\u00e9ricaniste, l&rsquo;omnipr\u00e9sence de l&rsquo;influence USA-Isra\u00ebl, etc.), on peut avancer que l&rsquo;arm\u00e9e au pouvoir en Egypte sera loin de d\u00e9terminer sa ligne en toute s\u00e9curit\u00e9. Elle devra se d\u00e9terminer en fonction de toutes ces forces nouvelles et, pour affirmer son autorit\u00e9 et sa l\u00e9gitimit\u00e9, elle n&rsquo;a qu&rsquo;une voie pour se concilier ces forces : celle de l&rsquo;affirmation nationale, \u00e9ventuellement populiste, de l&rsquo;affirmation de la souverainet\u00e9, etc.,  c&rsquo;est-\u00e0-dire le renforcement de sa fraction r\u00e9formiste-populiste. On peut envisager une sorte de n\u00e9o-nass\u00e9risme adapt\u00e9 aux circonstances actuelles (pas n\u00e9cessairement panarabe, notamment,  nous parlons de l&rsquo;esprit de la chose), \u00e9ventuellement avec une pouss\u00e9e de jeunes officiers type-jeunes Turcs, comme le fut Nasser par rapport \u00e0 N\u00e9guib au d\u00e9but de la prise de pouvoir par l&rsquo;arm\u00e9e en 1952. Dans ces situations fluctuantes o\u00f9 s&rsquo;expriment de puissants courants incontr\u00f4l\u00e9s, les arguments comptables classiques de la corruption am\u00e9ricaniste (l&rsquo;aide militaire, par exemple) perdent beaucoup de leur force, d&rsquo;autant que l&rsquo;affaiblissement de la position des USA conduirait ce pays vers une position de demandeur, selon laquelle l&rsquo;aide militaire US, si elle subsiste, n&rsquo;aurait plus rien \u00e0 voir, en puissance et en efficacit\u00e9, avec le levier d&rsquo;influence qu&rsquo;elle a \u00e9t\u00e9 jusqu&rsquo;ici. Une certaine lib\u00e9ration de l&rsquo;Egypte de la main-mise US sur ce pays sera, \u00e0 un moment ou l&rsquo;autre, au programme de l&rsquo;arm\u00e9e au pouvoir soumise aux influences r\u00e9volutionnaires.<\/p>\n<h3>Hypoth\u00e8ses et effet psychologique<\/h3>\n<\/p>\n<p><p>\tOn a d\u00e9crit l\u00e0 un sch\u00e9ma classique, qui est valable pour le processus mais qui demande \u00e0 \u00eatre actualis\u00e9 selon les circonstances nouvelles. C&rsquo;est l\u00e0 que la question nucl\u00e9aire entre en jeu, en tant que telle autant qu&rsquo;en tant que symbole de la nouvelle situation.<\/p>\n<\/p>\n<p><p>\tLe texte de Cirincione nous pr\u00e9cise que Moubarak a \u00e9t\u00e9 la principale force emp\u00eachant tout programme nucl\u00e9aire s\u00e9rieux, face \u00e0 un parti des militaires qui para\u00eet manifestement tent\u00e9 par la chose. Sur ce point, on voit bien combien Moubarak s&rsquo;\u00e9tait s\u00e9par\u00e9 de ses origines militaires, et l&rsquo;on se permettra de supposer qu&rsquo;il \u00e9tait, en la circonstance, encore plus un vassal z\u00e9l\u00e9 des USA (adversaires \u00e9videmment de ces ambitions nucl\u00e9aires) qu&rsquo;un vertueux amoureux de la non-prolif\u00e9ration. La question soulev\u00e9e par Cirincione n&rsquo;est donc pas inutile ni d\u00e9plac\u00e9e, en fonction de cette situation de l&rsquo;arm\u00e9e au pouvoir telle que nous l&rsquo;avons d\u00e9crite. Pour \u00eatre pr\u00e9cis \u00e0 cet \u00e9gard, on comprend combien une perspective nucl\u00e9aire peut \u00eatre un formidable argument par rapport \u00e0 nos hypoth\u00e8ses sur l&rsquo;\u00e9volution de l&rsquo;arm\u00e9e, parce que le nucl\u00e9aire est, dans ce contexte comme il l&rsquo;est par nature d&rsquo;ailleurs, un tout aussi formidable moyen d&rsquo;affirmation nationale et souveraine.<\/p>\n<\/p>\n<p><p>\tOn d\u00e9couvre alors la perspective qui s&rsquo;ouvre, d&rsquo;autant que l&rsquo;Egypte s&rsquo;est mise en pointe dans la bataille pour l&rsquo;institution d&rsquo;une zone d\u00e9nucl\u00e9aris\u00e9e au Moyen-Orient, qu&rsquo;elle est le <em>leader<\/em> institutionnel de cette pouss\u00e9e. Avec la r\u00e9volution et l&rsquo;arm\u00e9e au pouvoir, Cirincione est totalement justifi\u00e9 d&rsquo;\u00e9voquer l&rsquo;hypoth\u00e8se inverse,  une sortie de l&rsquo;Egypte du NPT et un d\u00e9veloppement du nucl\u00e9aire militaire en cas d&rsquo;\u00e9chec de la pouss\u00e9e conduite par l&rsquo;Egypte pour instituer une zone d\u00e9nucl\u00e9aris\u00e9e. Dans les deux cas \u00e9voqu\u00e9s (zone d\u00e9nucl\u00e9aris\u00e9e ou d\u00e9veloppement nucl\u00e9aire), cela place l&rsquo;Egypte en confrontation directe avec Isra\u00ebl, et en accord avec des pays tels que l&rsquo;Iran et la Turquie. Ainsi le parti des salonnards doit-il \u00eatre rassur\u00e9 : il n&rsquo;est pas n\u00e9cessaire d&rsquo;agiter l&rsquo;\u00e9pouvantail islamiste pour \u00e9voquer la perspective d&rsquo;une d\u00e9stabilisation dont p\u00e2tirait Isra\u00ebl dans le chef de la r\u00e9volution \u00e9gyptienne. (Bien s\u00fbr, il est plus glorieux pour les d\u00eeners en ville de p\u00e9rorer sur la d\u00e9mocratisation, et savoir qui la m\u00e9rite et qui ne la m\u00e9rite pas,  cela passe le temps.)<\/p>\n<\/p>\n<p><p>\tMais cette analyse, on l&rsquo;a dit plus haut, est soumise aux al\u00e9as d&rsquo;une situation g\u00e9n\u00e9rale compl\u00e8tement d\u00e9stabilis\u00e9e. On d\u00e9crit une perspective hypoth\u00e9tique qui prendrait un certain temps, bien entendu, et qui suppose, pour \u00eatre conduite au terme, une situation g\u00e9n\u00e9rale qui ne connaisse pas un trop grand bouleversement. On ne peut dire, bien entendu, que cette hypoth\u00e8se du trop grand bouleversement soit accessoire ou marginale, bien au contraire. Il y a, si l&rsquo;on veut, concurrence entre la situation de la r\u00e9volution \u00e9gyptienne et ses suites (notamment nucl\u00e9aires), o\u00f9 le contr\u00f4le humain est important, et qui peut effectivement d\u00e9velopper l&rsquo;orientation qu&rsquo;on d\u00e9crit ; et la situation d&rsquo;eschatologisation du d\u00e9cha\u00eenement crisique qui touche le monde arabe et le Moyen-Orient, et qui est effectivement hors du contr\u00f4le humain (d&rsquo;o\u00f9 sa caract\u00e9risation eschatologique). C&rsquo;est avec cette r\u00e9serve capitale \u00e0 l&rsquo;esprit qu&rsquo;il faut appr\u00e9cier notre analyse.<\/p>\n<\/p>\n<p><p>\tPar contre, il existe une appr\u00e9ciation beaucoup plus assur\u00e9e, et elle est psychologique. L&rsquo;analyse autour des ambitions nucl\u00e9aires \u00e9gyptiennes est sans aucun doute partout en marche dans les esprits, chez les experts de diverses puissances et pays, notamment en Isra\u00ebl avec son monopole nucl\u00e9aire dans la r\u00e9gion, aux USA, etc. Le texte de Cirincione, en t\u00e9moigne et, d&rsquo;ailleurs, il ne s&rsquo;en cache aucunement : \u00ab<em>As a free Egypt transforms itself, analysts are nervously watching for signs of new nuclear ambitions<\/em>\u00bb En d&rsquo;autres termes, l&rsquo;analyse que nous avons expos\u00e9e, m\u00eame si elle ne se r\u00e9alise pas, m\u00eame si elle avait peu de chances de se r\u00e9aliser selon le jugement de ceux qui privil\u00e9gient l&rsquo;\u00e9volution eschatologique de la situation, produit d&rsquo;ores et d\u00e9j\u00e0 un effet important, notamment psychologique, en exer\u00e7ant une influence sur ceux qui appr\u00e9cient la situation \u00e9gyptienne et se situent par rapport \u00e0 elle.<\/p>\n<\/p>\n<p><p>\tEn ce sens, \u00e0 c\u00f4t\u00e9 de la concr\u00e9tisation encore probl\u00e9matique de l&rsquo;hypoth\u00e8se de cette \u00e9volution \u00e9gyptienne (nucl\u00e9aire) qu&rsquo;on a d\u00e9crite comme l&rsquo;effet possible le plus spectaculaire de la r\u00e9volution, on doit observer qu&rsquo;il existe d&rsquo;ores et d\u00e9j\u00e0 un effet puissant de cette r\u00e9volution, avec ce ph\u00e9nom\u00e8ne psychologique, et un effet d&rsquo;ores et d\u00e9j\u00e0 assur\u00e9e. Cet effet devrait contribuer \u00e0 accro\u00eetre le d\u00e9sordre g\u00e9n\u00e9ral de la situation,  et son eschatologisation, par cons\u00e9quent. Dans ce cas, ce que nous voyions plus haut comme une concurrence de l&rsquo;\u00e9valuation,  l&rsquo;hypoth\u00e8se d&rsquo;une nucl\u00e9arisation de l&rsquo;Egypte et l&rsquo;effet psychologique d&rsquo;ores et d\u00e9j\u00e0 en marche de cette hypoth\u00e8se, devient un compl\u00e9ment, puisque les deux \u00e9v\u00e9nements vont dans le m\u00eame sens, qui est de porter des coups de boutoir \u00e0 l&rsquo;ordre g\u00e9n\u00e9ral impos\u00e9 par le syst\u00e8me \u00e0 la r\u00e9gion.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00e9nigme nucl\u00e9aire du Sphinx 15 f\u00e9vrier 2011 L&rsquo;arm\u00e9e \u00e9gyptienne a pris le pouvoir que lui a offert, avec un empressement contraint, le pr\u00e9sident et ex-dictateur Osni Moubarak. Elle en fait un usage diligent : dissolution du Parlement, suspension de la Constitution, tentative de remise en ordre au Caire et dans le pays, etc. La r\u00e9volution&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[9550,2774,3538,8031,2738,9549,3004,2746],"class_list":["post-72759","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-egypte","tag-israel","tag-militaires","tag-moubarak","tag-nasser","tag-non-proliferation","tag-nucleaire","tag-souverainete"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72759"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72759\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72759"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72759"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}