{"id":72791,"date":"2011-02-26T06:36:33","date_gmt":"2011-02-26T06:36:33","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/02\/26\/uncut-une-special-relationships-contre-les-banques\/"},"modified":"2011-02-26T06:36:33","modified_gmt":"2011-02-26T06:36:33","slug":"uncut-une-special-relationships-contre-les-banques","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/02\/26\/uncut-une-special-relationships-contre-les-banques\/","title":{"rendered":"<em>Uncut<\/em>, une <em>special relationships<\/em> contre les banques"},"content":{"rendered":"<p><p>A chaque jour suffit,  \u00e0 peine,  sa r\u00e9volution, au moins en devenir, et chaque jour nous d\u00e9couvrons une nouvelle pousse printani\u00e8re. Dans les pages du <em>Guardian<\/em> du 25 f\u00e9vrier 2011, nous d\u00e9couvrons <em>Uncut<\/em>, un mouvement citoyen comme l&rsquo;on dirait en langage parisien <em>politically correct<\/em>, et qui l&rsquo;est r\u00e9ellement d&rsquo;ailleurs (citoyen) et nullement pour les <em>talk shows<\/em> t\u00e9l\u00e9 ; <em>Uncut<\/em>, qui s&rsquo;est d\u00e9velopp\u00e9 au Royaume Uni et qui est d\u00e9sormais adopt\u00e9 par les USA. <em>Uncut<\/em> s&rsquo;en prend aux banques, avec des actions d&rsquo;occupation des locaux for\u00e7ant \u00e0 une fermeture temporaire de la banque, alors que la justification de son action initiale est l&rsquo;\u00e9vasion fiscale des grandes corporations (<em>corporate power<\/em>). Il est difficile pour les esprits avis\u00e9s de ne pas voir une corr\u00e9lation, d&rsquo;abord de ce d\u00e9veloppement de <em>Uncut<\/em> aux USA avec les d\u00e9veloppements \u00e0 Madison, dans le Wisconsin (et aussi dans l&rsquo;Ohio, \u00e0 Columbus), ensuite et d&rsquo;une fa\u00e7on plus g\u00e9n\u00e9rale, du d\u00e9veloppement de <em>Uncut<\/em> anglo-saxon avec le mouvement g\u00e9n\u00e9ral antiSyst\u00e8me qui d\u00e9vaste l&rsquo;ordre am\u00e9ricaniste-occidentaliste dans le monde arabe. Dans l&rsquo;esprit de la chose, il y a globalisation en un seul mouvement marqu\u00e9 par une logique antiSyst\u00e8me.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est le <a href=\"http:\/\/www.guardian.co.uk\/uk\/2011\/feb\/18\/ukuncut-grassroots-movement-grows-us?INTCMP=ILCNETTXT3487\" class=\"gen\">18 f\u00e9vrier 2011<\/a> que le <em>Guardian<\/em> p\u00e9cisait d&rsquo;une mani\u00e8re circonstanci\u00e9e le d\u00e9veloppement de <em>UK Uncut<\/em>, ainsi nomm\u00e9 puisqu&rsquo;il s&rsquo;av\u00e9rait, dans le m\u00eame article, que ce mouvement britannique s&rsquo;\u00e9tendait aux USA avec <em>USA Uncut<\/em>.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The co-ordinated occupations of Barclays branches will mark the first national day of action against banks by UK Uncut, which has already forced the temporary closure of more than 100 high street stores. The group has previously targeted companies such as Boots and Vodafone accused of avoiding millions of pounds in tax. Targeting Barclays has proved particularly popular, with more protests planned in large cities as well as smaller towns such as Grimsby, Hastings and Shrewsbury.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>And as campaigners turn their attention to banks, and Barclays in particular, it emerged their Twitter-driven campaign has spread to the United States, where similar protests are being organised under the banner US Uncut. The folks in the UK who decided to stand up, organise and speak out are a daily inspiration to me and the rest of the movement in the States, said Carl Gibson, 23, one of the founders of the first US Uncut group in Jackson, Mississippi.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The message is simple  before you sacrifice hard-working public-sector employees&rsquo; jobs and necessary public programmes, why not first make the richest of the rich pay their fair share in taxes? Gibson, who started the first US group a week ago after reading an article in the Nation, said there were already US Uncut chapters in 20 states and at least 10 demonstrations planned for 26 February  the date of UK Uncut&rsquo;s second day of action against the banks.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe <a href=\"http:\/\/www.guardian.co.uk\/uk\/2011\/feb\/25\/uk-uncut-us-groups-cuts\" class=\"gen\">25 f\u00e9vrier 2011<\/a>, comme d\u00e9j\u00e0 signal\u00e9, le <em>Guardian<\/em> publie un nouvel article o\u00f9 il d\u00e9taille notamment les conditions de l&rsquo;extension d&rsquo;<em>Uncut<\/em> aux USA.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Hundreds of activists in the US are planning to take part in a day of direct action in a move inspired by Britain&rsquo;s fast growing protest group. US Uncut groups have sprung up from New York to Hawaii in the last three weeks and activists will demonstrate against government cuts and corporate tax avoidance in more than 50 cities on Saturday.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The US protest movement was inspired by UK Uncut, an anti-cuts campaign group that has temporarily closed scores of high street stores accused of tax avoidance since it was set up five months ago<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe m\u00eame <a href=\"http:\/\/www.rawstory.com\/rs\/2011\/02\/25\/us-uncut-non-partisan-group-demands-corporations-pay-their-taxes\/\" class=\"gen\">25 f\u00e9vrier 2011<\/a>, <em>RAW Story<\/em> publie un article exclusif o\u00f9 il annonce la journ\u00e9e d&rsquo;action de <em>USA Uncut<\/em> et demande autant une participation maximale que le plus d&rsquo;informations possibles sur cette journ\u00e9e, de la part des participants. Le site <em>RAW Story<\/em>, de tendance progressiste, entend \u00e9galement pr\u00e9senter <em>USA Uncut<\/em> comme un mouvement partiellement concurrent de <em>Tea Party<\/em>, notamment de cette partie de <em>Tea Party<\/em> marqu\u00e9e par ses liens avec des donateurs milliardaires (comme les fr\u00e8res Koch) repr\u00e9sentant les int\u00e9r\u00eats du <em>corporate power<\/em>. <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Corporate tax evasion has evolved into a virtual art form. Two-thirds of US corporations didn&rsquo;t pay so much as a dime in taxes between 1998 and 2005, exploiting a multitude of loopholes, according to a Congressional report.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Targeting corporations who evade taxes turned out to be quite the anti-austerity rallying cry in England, where a new prime minister is pushing painful cuts for working people. Now, that same rallying cry is going out across the United States, where the anti-spending tea party movement has in recent years overshadowed the voices of those who want government to be more active on behalf of the middle class.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>A new non-partisan group called US Uncut  named after UK Uncut  aims in part to challenge the tea party&rsquo;s push for lower corporate taxes. They instead want Congress stop letting wealthy corporations dodge their taxes. This is an issue that has been ignored for way too long, Carl Gibson, a US Uncut spokesman, told Raw Story. Congress has been chipping away and chipping away at corporate responsibility to pay taxes. And now it&rsquo;s gotten to the point where the middle class is being sacrificed on the altar of deficit reduction, while big corporations are getting away with not paying any taxes at all.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The website Wall St. Cheat Sheet found that corporations routinely claim hundreds of millions in tax deductions. In 2009, Bank of America qualified for a $1.9 billion tax benefit, and General Electric a $1.1 billion write-off.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tUn passage int\u00e9ressant de l&rsquo;article de <em>RAW Story<\/em> est une pr\u00e9sentation structurelle et politique du mouvement aux USA, tel qu&rsquo;il a pris forme d&rsquo;une mani\u00e8re qu&rsquo;on doit qualifier objectivement de spontan\u00e9e m\u00eame si c&rsquo;est \u00e0 l&rsquo;exemple du mouvement britannique ; nous nous pla\u00e7ons dans ce cas  selon les normes et les orientations de notre r\u00e9f\u00e9rence du <a href=\"http:\/\/www.dedefensa.org\/article-des_systemes_antisystemes_aux_systemes_antisysteme__10_12_2010.html\" class=\"gen\">syst\u00e8me antiSyst\u00e8me<\/a>. On retrouve les m\u00eames caract\u00e8res d&rsquo;absence de direction hi\u00e9rarchique au profit d&rsquo;une coordination, d&rsquo;absence d&rsquo;organisation structur\u00e9e au profit d&rsquo;une organisation en cellules ind\u00e9pendantes coordonn\u00e9es entre elles (organisation en r\u00e9seaux), d&rsquo;absence d&rsquo;orientation politique marqu\u00e9e selon les crit\u00e8res du Syst\u00e8me au profit d&rsquo;une pression d\u00e9structurante contre les formes existantes du Syst\u00e8me en place (dans le secteur financier), etc.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>US Uncut boasts no central leadership, and appears to be as organic as grassroots movements get. Gibson, 23, of Jacksonville, Mississippi, founded the first chapter. He works a few part-time jobs and confesses to having no prior experience in organizing or in politics. He was inspired by the vibrancy of UK Uncut, and spurred into action after reading an article in The Nation magazine about replicating such a movement in the US.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Is US Uncut a lib\u00e9ral or progressive movement? Absolutely not, Gibson said. This is nonpartisan. We don&rsquo;t endorse any specific political ideology or candidate or party.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The movement will hold its first day of organizing on Saturday, February 26, with demonstrations mainly outside banks in 50 cities. It&rsquo;s expecting crowds in the dozens in the smaller cities and hundreds in some bigger cities. This is our first national day of action, Gibson said. And all of us are coming together to say: before you take away housing subsidies, raise college tuition and fire teachers, just make sure that corporations are paying their fair share in taxes like the rest of us.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The broader goal is to reshape the national debate and challenge the tea party&rsquo;s narrative that government can&rsquo;t do good things for people, and that we can&rsquo;t raise taxes, we can only cut. Maybe there isn&rsquo;t a spending problem. Maybe it&rsquo;s a revenue problem, Gibson said. And it&rsquo;s not that the money&rsquo;s not there. The money is there. It&rsquo;s with these corporations who aren&rsquo;t paying taxes.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl est vrai que c&rsquo;est d&rsquo;abord cette sp\u00e9cificit\u00e9 anglo-saxonne, ou anglo-am\u00e9ricaine (et non anglo-am\u00e9ricaniste dans ce cas), qui nous arr\u00eate. Le symbole est puissant m\u00eame si le mouvement n&rsquo;en est encore qu&rsquo;\u00e0 ses d\u00e9buts (\u00e0 ses d\u00e9buts puisque notre espoir est qu&rsquo;il se d\u00e9veloppe) ; il appara\u00eet comme un double sympathique des fameuses <em>special relationships<\/em>, et cette fois encore sur initiative britannique mais dans un sens infiniment vertueux du point de vue de la lutte contre le Syst\u00e8me. C&rsquo;est en effet ce point de vue (antiSyst\u00e8me) qu&rsquo;il faut privil\u00e9gier, plut\u00f4t que trop s&rsquo;arr\u00eater aux d\u00e9tails des intentions et des modalit\u00e9s d&rsquo;action des uns et des autres. A partir d&rsquo;une sp\u00e9cificit\u00e9 mobilisatrice (d\u00e9nonciation de l&rsquo;\u00e9vasion fiscale), on en vient naturellement \u00e0 la contestation <em>de facto<\/em> de l&rsquo;ordre financier du Syst\u00e8me, avec la mise en cause des monstrueuses actions de sauvegarde des banques responsables de leur propre effondrement et qu&rsquo;on juge innocentes de la chose puisque les tr\u00e9sors publics les ont renflou\u00e9es. Il est excellent que cette contestation vienne de la population des deux pays qui sont les inspirateurs et les ma\u00eetres d&rsquo;uvre de cet ordre financier.<\/p>\n<\/p>\n<p><p>\tD&rsquo;autre part, si le d\u00e9veloppement de <em>UK Uncut<\/em> est int\u00e9ressant en soi, c&rsquo;est son extension inspiratrice \u00e0 <em>USA Uncut<\/em> qui doit retenir l&rsquo;attention, puisque tout ce qui conteste et affaiblit l&rsquo;ordre am\u00e9ricaniste est d&rsquo;une importante centrale. La position attribu\u00e9e \u00e0 <em>USA Uncut<\/em> de concurrent de <em>Tea Party<\/em> n&rsquo;est finalement pas une mauvaise chose. Notre sentiment est que, plut\u00f4t que conduire \u00e0 un affrontement diviseur comme caract\u00e9ristique centrale, cette concurrence va forcer <em>Tea Party<\/em> \u00e0 renforcer son aile populiste pour ne pas trop pr\u00eater le flanc \u00e0 la critique de <em>USA Uncut<\/em>, c&rsquo;est-\u00e0-dire \u00e0 lutter plus fermement contre la p\u00e9n\u00e9tration du mouvement par des fortunes personnelles agissant en relais du <em>corporate power<\/em> ; plut\u00f4t qu&rsquo;une politisation gauche droite (gauche <em>versus<\/em> droite) qui s&rsquo;appuie sur des notions id\u00e9ologiques d\u00e9pass\u00e9es, st\u00e9riles et diviseuses \u00e0 l&rsquo;avantage du Syst\u00e8me, on aurait un renforcement g\u00e9n\u00e9ral de la tendance populiste antiSyst\u00e8me. L&rsquo;apolitisme de <em>USA Uncut<\/em> argument\u00e9 par Gibson est en fait une affirmation politique fondamentale parce qu&rsquo;antiSyst\u00e8me, comme l&rsquo;est <em>Tea Party<\/em> malgr\u00e9 ses affirmations partisanes. Finalement, l&rsquo;importance des antagonismes entre les deux mouvements (le coupons les d\u00e9penses publiques de <em>Tea Party<\/em> contre le r\u00e9partissons d&rsquo;une fa\u00e7ons radicalement diff\u00e9rentes les d\u00e9penses publiques de <em>USA Uncut<\/em>) devrait se r\u00e9duire sous la pression de la dynamique antiSyst\u00e8me qui sous-tend tous ces mouvements.<\/p>\n<\/p>\n<p><p>\tEn effet, nous sommes en plein dans l&rsquo;antiSyst\u00e8me, et le d\u00e9veloppement de <em>Uncut<\/em> montre que l&rsquo;influence de l&rsquo;esprit de cette dynamique donne des fruits int\u00e9ressants. De toutes les fa\u00e7ons, m\u00eame si <em>UK Uncut<\/em> a plusieurs mois d&rsquo;existence (depuis le d\u00e9but de l&rsquo;automne 2010) et pr\u00e9c\u00e8de donc le mouvement d&rsquo;encha\u00eenement crisique commenc\u00e9 en d\u00e9cembre 2010 avec la Tunisie, l&rsquo;influence de ce second et immense mouvement sur le d\u00e9veloppement soudain d&rsquo;<em>Uncut<\/em>, notamment vers les USA, est \u00e9vidente. Le rapport entre <em>USA Uncut<\/em> et la dynamique de contestation lanc\u00e9e avec force \u00e0 Madison, Wisconsin, est manifeste et puissant selon notre point de vue, notamment dans l&rsquo;\u00e9veil contestateur des psychologies impliqu\u00e9es. L&rsquo;esprit est manifestement similaire et renvoie \u00e0 une r\u00e9sistance antiSyst\u00e8me qui est devenue \u00e0 la fois contestatrice et contre-offensive.<\/p>\n<\/p>\n<p><p>\tPar cons\u00e9quent, longue vie \u00e0 <em>Uncut<\/em>, d&rsquo;ailleurs sans garantie absolue que la chose se r\u00e9alise. Mais, dans le climat actuel, les chances sont grandes qu&rsquo;effectivement <em>Uncut<\/em> fleurisse sous ses diverses formes. C&rsquo;est un tribut indirect rendu \u00e0 l&rsquo;explosion psychologique antiSyst\u00e8me qui se manifeste depuis d\u00e9cembre 2010 (la Tunisie) ; c&rsquo;est une affirmation symbolique tr\u00e8s puissante et efficace parce qu&rsquo;elle coupe les ailes \u00e0 la principale d\u00e9fense du Syst\u00e8me qui est de tenter d&rsquo;isoler le mouvement d&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-de_la_chaine_crisique_au_temps_crisique__24_02_2011.html\" class=\"gen\">encha\u00eenement crisique<\/a> sous la seule rubrique pseudo g\u00e9opolitique et certainement moralo-politique d&rsquo;un mouvement de d\u00e9mocratisation du monde arabe, ainsi r\u00e9cup\u00e9r\u00e9 par la soi disant sup\u00e9riorit\u00e9 morale am\u00e9ricaniste-occidentaliste dispens\u00e9e par la rh\u00e9torique mielleusement vertueuse du Syst\u00e8me. La d\u00e9mocratisation est l&rsquo;arme de communication favorite du Syst\u00e8me pour tenter de d\u00e9samorcer la puissance contestatrice, en la r\u00e9duisant \u00e0 un de ses slogans favoris qui a pour t\u00e2che de subvertir cette contestation contre-offensive jusqu&rsquo;\u00e0 l&rsquo;inversion et \u00e0 la dissolution. L&rsquo;amalgame (l&rsquo;axe Le Caire-Madison), par la logique puissante de l&rsquo;esprit de la chose, du mouvement dans les pays arabes et de la contestation populiste au sein du Syst\u00e8me (surtout dans sa partie anglo-saxonne) est un moteur puissant de communication pour renforcer la tendance vitale de la formule syst\u00e8me antiSyst\u00e8me, \u00e0 la mani\u00e8re de l&rsquo;action contre-offensive du syst\u00e8me immunitaire d&rsquo;un corps vivant.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 26 f\u00e9vrier 2011 \u00e0 05H44<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A chaque jour suffit, \u00e0 peine, sa r\u00e9volution, au moins en devenir, et chaque jour nous d\u00e9couvrons une nouvelle pousse printani\u00e8re. Dans les pages du Guardian du 25 f\u00e9vrier 2011, nous d\u00e9couvrons Uncut, un mouvement citoyen comme l&rsquo;on dirait en langage parisien politically correct, et qui l&rsquo;est r\u00e9ellement d&rsquo;ailleurs (citoyen) et nullement pour les talk&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4646,8379,5592,2711,3014,10871,10016],"class_list":["post-72791","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-antisysteme","tag-caire","tag-contestation","tag-le","tag-systeme","tag-uncut","tag-wisconsin"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72791","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72791"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72791\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72791"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72791"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72791"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}