{"id":72797,"date":"2011-02-28T07:08:23","date_gmt":"2011-02-28T07:08:23","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/02\/28\/la-chaine-crisique-et-la-faim-reductionniste\/"},"modified":"2011-02-28T07:08:23","modified_gmt":"2011-02-28T07:08:23","slug":"la-chaine-crisique-et-la-faim-reductionniste","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/02\/28\/la-chaine-crisique-et-la-faim-reductionniste\/","title":{"rendered":"La \u201ccha\u00eene crisique\u201d et la faim r\u00e9ductionniste"},"content":{"rendered":"<p><p>Pourquoi cette s\u00e9rie de crise dans les pays du Maghreb et du Moyen-Orient, pourquoi cette <a href=\"http:\/\/www.dedefensa.org\/article-de_la_chaine_crisique_au_temps_crisique__24_02_2011.html\" class=\"gen\">cha\u00eene crisique<\/a> ? Il y a eu le d\u00e9sir de d\u00e9mocratisation, explication en vogue parmi les dirigeants occidentalistes- am\u00e9ricanistes, ou bien encore, selon les termes plus fleuris de l&rsquo;homme d&rsquo;affaire jordanien Luay Abu-Ghazaleh, <a href=\"http:\/\/www.cnbc.com\/id\/41781874\/\" class=\"gen\">la volont\u00e9 des peuples<\/a>. (Luay Abu-Ghazaleh entend par cette explication que personne ne pourra repousser fondamentalement tant elle est vague et consensuelle, r\u00e9duire d&rsquo;autant le r\u00f4le d&rsquo;Internet,  <em>Facebook<\/em>, <em>Tweeter<\/em> et le reste,  dont il juge qu&rsquo;il a \u00e9t\u00e9 surestim\u00e9.)<\/p>\n<\/p>\n<p><p>\tUne nouvelle explication acquiert droit de cit\u00e9 avec le texte de Peter Popham, dans <em>The Independent<\/em> du <a href=\"http:\/\/www.independent.co.uk\/news\/world\/africa\/the-price-of-food-is-at-the-heart-of-this-wave-of-revolutions-2226896.html\" class=\"gen\">27 f\u00e9vrier 2011<\/a>: l&rsquo;augmentation du prix des denr\u00e9es alimentaires et la faim par cons\u00e9quent. Le d\u00e9veloppement du texte propose un r\u00e9cit des circonstances diverses qui ont conduit \u00e0 des augmentations de denr\u00e9es alimentaires, comme ce fut le cas au d\u00e9but de 2008.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>A similar chain of unconnected farming catastrophes in early 2008 led to a similar outbreak of extreme price volatility around the world which provoked food riots in more than 40 countries, from Haiti to Bangladesh, including Mexico, Uzbekistan and Eritrea but also involving several countries caught up in the present round of uprisings, including Egypt, Yemen, Morocco, Mauritania, Senegal and Zimbabwe. All were among the 80 countries around the world that combine low incomes with food deficits  the need to import food, bringing exposure to wildly fluctuating world market prices. In these poor countries, food purchases can consume 70 per cent of income. The result, when prices of flour and grains shoot up by 30 per cent, is extreme distress  the sort of distress that sends people out into the streets in fury.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Abdolreza Abbassian, FAO&rsquo;s chief economist saw  in his dry, cautious, academic manner  the present turmoil coming. It&rsquo;s getting a little bit uncomfortable, he said back in December. A lot of countries, especially the poorer ones, have to rely so much on world markets. They have to import food at much higher prices. Whether or not this will lead to domestic problems, turmoil, demonstrations, riots, the kind of things we saw in 2008, it is not possible to predict.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>For the poor of the Middle East, the price shocks at the start of this year were like experiencing a second killer earthquake in three years  but unlike with an earthquake, there was someone you could blame. So angry were the food price protesters in Tunisia that, after Mohamed Bouazizi set fire to himself, President Zine el-Abidine Ben Ali declared a state of emergency and promised to reduce the price of food. But it was too little, too late: by mid-January he was gone.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Tunisia&rsquo;s turmoil, warned The Washington Post as the toppled president flew off into exile, has economists worried that we may be seeing the beginning of a second wave of global food riots. As we know now, it turned out somewhat differently. Food riots in 2008, revolutions in 2011  what, where, who is next?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe r\u00e9ductionnisme de cette explication,  la r\u00e9duction d&rsquo;\u00e9v\u00e9nements historiques et m\u00e9tahistoriques \u00e0 l&rsquo;\u00e9conomisme et aux difficult\u00e9s d&rsquo;approvisionnement alimentaires des peuples,  est remarquable dans sa rectitude. Elle proc\u00e8de d&rsquo;une m\u00e9thode g\u00e9n\u00e9rale, qui peut avoir d&rsquo;ailleurs un r\u00f4le r\u00e9troactif non n\u00e9gligeable pour affirmer sa coh\u00e9rence. Dans le cours de son d\u00e9veloppement, Peter Popham, sur la suggestion des experts de la FAO, r\u00e8gle son compte aux diverses explications et appr\u00e9ciations de l&rsquo;importance de l&rsquo;action de Gorbatchev dans l&rsquo;\u00e9v\u00e9nement de la fin de l&rsquo;URSS et du communisme dans les ann\u00e9es 1980, pour ramener cet \u00e9v\u00e9nement consid\u00e9rable au seul cas des r\u00e9coltes de bl\u00e9 malheureuses : \u00ab<em>When grain production collapsed in the Soviet Union during the 1980s and what had been one of the world&rsquo;s greatest grain exporters became a net importer, the resulting surges of anger brought down the whole Communist system within a couple of years  but stopped there.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tR\u00e9ductionnisme est bien le mot qui importe. Le r\u00f4le que jouent les variations des prix des aliments sur les troubles dans un certain nombre de pays est av\u00e9r\u00e9, tout comme le r\u00e9gime des intemp\u00e9ries, les catastrophes naturelles, etc. ; tout comme, bien entendu, le r\u00e9gime politique, la r\u00e9pression, les conditions de pression polici\u00e8re, la corruption visible et devenant insupportable, les in\u00e9galit\u00e9s, les pressions psychologiques, etc. Devant ces \u00e9vidences qui parcellisent d&rsquo;autant ces causes pr\u00e9sent\u00e9es souvent, pour chacune, comme essentielles, il est difficile de souscrire au jugement de Popham faisant du prix des denr\u00e9es alimentaires la cause la plus profonde du grand ph\u00e9nom\u00e8ne politique de la cha\u00eene crisique : \u00ab<em>No one saw the uprisings coming, but their deeper cause isn&rsquo;t hard to fathom.<\/em>\u00bb Lorsqu&rsquo;il \u00e9crit : \u00ab<em>So angry were the food price protesters in Tunisia that, after Mohamed Bouazizi set fire to himself, President Zine el-Abidine Ben Ali declared a state of emergency and promised to reduce the price of food. But it was too little, too late: by mid-January he was gone<\/em>\u00bb,  ne peut-on y voir un raisonnement bien forc\u00e9 et diablement sollicit\u00e9 ? Tirer du fait que l&rsquo;annonce de Ben Ali de la r\u00e9duction du prix des denr\u00e9es alimentaires fut une mesure trop peu trop tard, tant la foule des r\u00e9volt\u00e9s de la faim \u00e9tait furieuse, n&rsquo;est-ce pas choisir le sens du raisonnement le plus incertain et le moins \u00e9vident,  ou bien pourquoi faire simple quand on peut faire compliqu\u00e9,  pour bien boucler son argument ? Car l&rsquo;on pourrait r\u00e9pondre que si ces mesures de r\u00e9duction des prix des denr\u00e9es alimentaires  de Ben Ali n&rsquo;apais\u00e8rent pas la r\u00e9volte, c&rsquo;est simplement que la r\u00e9volte portait sur bien autre chose que sur le prix des denr\u00e9es alimentaires. L&rsquo;on sait, par la lecture de sa derni\u00e8re lettre adress\u00e9e \u00e0 sa m\u00e8re, que Mohamed Bouazizi,  dont l&rsquo;immolation par le feu fut l&rsquo;\u00e9v\u00e9nement d\u00e9clencheur de la cha\u00eene crisique,  s&rsquo;est immol\u00e9 par le feu plus pour des raisons d&rsquo;indignit\u00e9 et d&rsquo;humiliation qu&rsquo;il ne pouvait plus supporter que pour des raisons \u00e9conomiques (Si tu veux savoir pourquoi je m&rsquo;immole, \u00e9crit-il, demande-le \u00e0 notre \u00e9poque). Au mieux, et pour ne pas trop accabler Popham, c&rsquo;est-\u00e0-dire en admettant son argument, ne pourrait-on dire que la cause de ces \u00e9v\u00e9nements est moins la pauvret\u00e9 que le fait que le Syst\u00e8me fabrique une certaine forme de pauvret\u00e9 artificielle pour le plus grand nombre et rend la pauvret\u00e9 insupportable par les conditions g\u00e9n\u00e9rales de pression pour l&rsquo;enrichissement et d&rsquo;injustice emp\u00eachant l&rsquo;enrichissement pour le plus grand nombre qu&rsquo;il cr\u00e9e,  <strong>\u00e0 la fois<\/strong> vous mettant dans telle situation et rendant cette situation insupportable ? M\u00eame dans ce cas, la cause la plus profonde c&rsquo;est bien le Syst\u00e8me et non le prix des denr\u00e9es alimentaires.<\/p>\n<\/p>\n<p><p>\tD&rsquo;autre part, pourquoi ne pas pousser l&rsquo;hypoth\u00e8se dans toutes ses implications puisque la th\u00e8se elle-m\u00eame est une hypoth\u00e8se ? S&rsquo;il y eut des r\u00e9voltes de la faim sans cons\u00e9quences politiques notables en 2008 et s&rsquo;il y a des r\u00e9volutions engendrant un formidable bouleversement politique en 2011, n&rsquo;est-ce pas, plut\u00f4t qu&rsquo;en rester au seul argument du prix des denr\u00e9es alimentaires et s&rsquo;interroger sans r\u00e9pondre sur le myst\u00e8re des cons\u00e9quences diff\u00e9rentes qu&rsquo;engendre le ph\u00e9nom\u00e8ne, que l&rsquo;\u00e9tat d&rsquo;esprit est, en 2011, compl\u00e8tement diff\u00e9rent de ce qu&rsquo;il \u00e9tait en 2008 ? Et ainsi de suite. <\/p>\n<\/p>\n<p><p>\tIl en est de m\u00eame de l&rsquo;argument qui tend \u00e0 r\u00e9duire le r\u00f4le d&rsquo;Internet au profit de celui, fort s\u00e9duisant mais un peu vague, de la volont\u00e9 des peuples qu&rsquo;exprime l&rsquo;homme d&rsquo;affaires Luay Abu-Ghazaleh, Jordanien et tr\u00e8s occidentalis\u00e9, donc tr\u00e8s proche du Syst\u00e8me. On peut tout de m\u00eame s&rsquo;attacher au constat qu&rsquo;en 2008 (pour garder le fil rouge des prix alimentaires) il n&rsquo;y eut gu\u00e8re d&rsquo;interventions d&rsquo;Internet, au contraire de 2011, et qu&rsquo;alors on peut avancer l&rsquo;hypoth\u00e8se que cette intervention d&rsquo;Internet, dans un mode contestataire et antisyst\u00e8me est pour beaucoup, sinon pour l&rsquo;essentiel, dans la r\u00e9v\u00e9lation, sinon m\u00eame <strong>la cr\u00e9ation<\/strong>, de cet \u00e9tat d&rsquo;esprit diff\u00e9rent, qui nous fait passer des r\u00e9voltes de la faim aux r\u00e9volutions Et l&rsquo;on sait combien l&rsquo;attribution d&rsquo;un tel r\u00f4le \u00e0 Internet, \u00e0 cause de sa <a href=\"http:\/\/www.dedefensa.org\/article-rupture_psychologique_19_02_2011.html\" class=\"gen\">dimension psychologique<\/a>, est bien plus d\u00e9stabilisant pour le Syst\u00e8me que n&rsquo;importe quelle autre explication.<\/p>\n<\/p>\n<p><p>\tDans tout cela, il n&rsquo;y a qu&rsquo;une seule pr\u00e9occupation : exon\u00e9rer le Syst\u00e8me d&rsquo;une responsabilit\u00e9 fondamentale qui le mettrait en cause. C&rsquo;est sans doute le plus grand enjeu de communication de la p\u00e9riode actuelle de bouleversement, que cette interpr\u00e9tation qu&rsquo;on en donne. L&rsquo;enjeu est bien, une fois de plus, comme en 2008 (cette fois, pour la crise financi\u00e8re), d&rsquo;\u00e9carter le soup\u00e7on que le Syst\u00e8me est tout entier impliqu\u00e9, pour en rester \u00e0 certaines des cons\u00e9quences de cette implication sans remonter \u00e0 la source. Si l&rsquo;on plaide que les variations des prix des denr\u00e9es alimentaires est la cause des catastrophes qu&rsquo;on observe, pourquoi ne pas s&rsquo;interroger sur la <strong>cause<\/strong> fondamentale de ces variations,  et l&rsquo;on sait bien que, bien autant que les catastrophes naturelles, d&rsquo;ailleurs caus\u00e9es par les cons\u00e9quences de l&rsquo;action du Syst\u00e8me sur l&rsquo;environnement, l&rsquo;on devra faire la part belle aux actions de sp\u00e9culations qui sont la monnaie courante de ce syst\u00e8me, et qui sont singuli\u00e8rement actives pour les denr\u00e9es alilmentaires.<\/p>\n<\/p>\n<p><p>\tMais non,  plus encore que le plus grand enjeu de communication&rsquo; de la p\u00e9riode actuelle de bouleversement, cette question de l&rsquo;interpr\u00e9tation de la cause des \u00e9v\u00e9nements de la cha\u00eene crisique entam\u00e9e avec la Tunisie est le plus grand enjeu tout court de la p\u00e9riode. La v\u00e9ritable et plus grande bataille de cette crisse centrale est sans aucun doute celle de la r\u00e9alisation des responsabilit\u00e9s, donc celle de la mise en cause du Syst\u00e8me. Quand les psychologies auront compl\u00e8tement assimil\u00e9 et accept\u00e9 cette responsabilit\u00e9, la Chute du Syst\u00e8me sera \u00e0 son terme.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 28 f\u00e9vrier 2011 \u00e0 07H09<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pourquoi cette s\u00e9rie de crise dans les pays du Maghreb et du Moyen-Orient, pourquoi cette cha\u00eene crisique ? Il y a eu le d\u00e9sir de d\u00e9mocratisation, explication en vogue parmi les dirigeants occidentalistes- am\u00e9ricanistes, ou bien encore, selon les termes plus fleuris de l&rsquo;homme d&rsquo;affaire jordanien Luay Abu-Ghazaleh, la volont\u00e9 des peuples. (Luay Abu-Ghazaleh entend&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[10879,4646,10859,8294,2631,10877,2604,9550,10880,60,6980,2622,3477,8078,5290,3014,10734],"class_list":["post-72797","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-alimentaires","tag-antisysteme","tag-chaine","tag-crisique","tag-de","tag-denree","tag-des","tag-egypte","tag-faim","tag-internet","tag-interpretation","tag-la","tag-prix","tag-responsabilite","tag-revoltes","tag-systeme","tag-tunisie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72797","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72797"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72797\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72797"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72797"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72797"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}