{"id":72808,"date":"2011-03-03T06:40:27","date_gmt":"2011-03-03T06:40:27","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/03\/03\/dogfight-pour-une-no-fly-zone-ii-ligue-arabe\/"},"modified":"2011-03-03T06:40:27","modified_gmt":"2011-03-03T06:40:27","slug":"dogfight-pour-une-no-fly-zone-ii-ligue-arabe","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/03\/03\/dogfight-pour-une-no-fly-zone-ii-ligue-arabe\/","title":{"rendered":"<em>Dogfight<\/em> pour une <em>No Fly Zone<\/em> (II \u2013 Ligue Arabe)"},"content":{"rendered":"<p><p>Cela \u00e9crit sur la <em>No Fly Zone<\/em> (on parle de toutes les sp\u00e9culations du c\u00f4t\u00e9 de la communaut\u00e9 internationale, c&rsquo;est-\u00e0-dire le bloc am\u00e9ricaniste-occidentaliste et principalement, bien entendu et comme on vient de le lire, au <a href=\"http:\/\/www.dedefensa.org\/article-dogfight_pour_une_no_fly_zone_i_03_03_2011.html?admin=1\" class=\"gen\">Pentagone<\/a>), il se trouve que les Arabes ne l&rsquo;entendent pas pr\u00e9cis\u00e9ment de cette oreille et n&rsquo;entendent nullement que des \u00e9trangers d\u00e9cident d&rsquo;une <em>No Fly Zone<\/em> ou pas au-dessus de la Libye, ni ne l&rsquo;assurent eux-m\u00eames, ou dans tous les cas en prennent la direction. La charge en revient aux pays arabes et aux voisins de la Libye, en l&rsquo;esp\u00e8ce la Ligue Arabe, en coop\u00e9ration avec l&rsquo;Union Africaine des pays africains,  ainsi en a d\u00e9cid\u00e9 la Ligue Arabe, r\u00e9unie au niveau des ministres au Caire, hier <a href=\"http:\/\/english.aljazeera.net\/news\/middleeast\/2011\/03\/20113218130353466.html\" class=\"gen\">2 mars 2011<\/a>, selon le rapport qu&rsquo;en fait <em>AlJazeera.net<\/em>.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The Arab League has said it may impose a no fly zone on Libya in co-ordination with the African Union if fighting continues in Libya. Wednesday&rsquo;s Arab League ministers&rsquo; meeting in Cairo rejected any direct outside military intervention in Libya, where Muammar Gaddafi is trying to put down a revolt threatening his four decades in power. They reiterated their condemnation of his use of force. The Arab resolution called on the Libyan government to respond to the legitimate demands of the Libyan people and to stop bloodshed.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tAmar Moussa, le secr\u00e9taire g\u00e9n\u00e9ral de la Ligue et aussi homme politique \u00e9gyptien qui s&rsquo;est impos\u00e9 comme un candidat potentiel r\u00e9formiste important pour les futures \u00e9lections pr\u00e9sidentielles post-Moubarak, a fortement condamn\u00e9 la Libye officielle (Kadhafi), dont la participation \u00e0 la Ligue est pour l&rsquo;instant suspendue. La Ligue Arabe a donc pris une attitude ferme en rejetant toute intervention \u00e9trang\u00e8re (voyez les yeux qui se tournent vers le bloc am\u00e9ricaniste-occidentaliste, cur et inspirateur de la ci-devant communaut\u00e9 internationale). Ce faisant, elle transforme le d\u00e9bat sur l&rsquo;hypoth\u00e9tique <em>No Fly Zone<\/em> en un d\u00e9bat fondamentalement <strong>politique<\/strong> o\u00f9 la d\u00e9cision est loin d&rsquo;\u00eatre acquise, mais ne revient de toutes les fa\u00e7ons qu&rsquo;aux pays arabes.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Al Jazeera&rsquo;s Ayman Mohyeldin reporting from Egypt&rsquo;s capital, said: At this stage, all the Arab League is going to consider or at least study with the member states of the African Union, the possibility of imposing a no-fly zone over Libya. That obviously depends on a great deal of military capabilities and more importantly what type of fly zone is going to be imposed.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>When I was speaking to an official at the Arab League, he said that imposing a no-fly zone may be detrimental to air traffic over Libya and may not provide the kind of cover that is needed to protect the civilian population.<\/em>\u00bb<\/p>\n<h4>Notre commentaire<\/h4>\n<p>Cette prise de position de la Ligue Arabe est importante, et elle est <strong>politiquement<\/strong> importante,  essentiellement selon deux points de vue tout aussi importants l&rsquo;un que l&rsquo;autre. Cela nous \u00e9loigne, tout en l&rsquo;englobant, de la probl\u00e9matique de la seule <em>No Fly Zone<\/em>.<\/p>\n<\/p>\n<p><p>\t La question de la <em>No Fly Zone<\/em> en Libye est une question sp\u00e9cifiquement arabe. Il ne peut \u00eatre question d&rsquo;une intervention \u00e9trang\u00e8re. Il s&rsquo;agit d&rsquo;une affirmation qui serait sans grande cons\u00e9quence dans d&rsquo;autres circonstances,  les circonstances d&rsquo;avant o\u00f9 la Ligue n&rsquo;avait gu\u00e8re de poids,  mais qui a tout son poids aujourd&rsquo;hui. Elle ressort d&rsquo;une tendance panarabe qui a effectivement, ici, une importance qu&rsquo;elle n&rsquo;aurait pas eu pr\u00e9c\u00e9demment, avant les \u00e9v\u00e9nements de la cha\u00eene crisique lanc\u00e9e en d\u00e9cembre 2010. Les pays arabes veulent, dans ce cas, r\u00e9affirmer une unit\u00e9 politique de leurs directions, partout mises en cause par le grand mouvement dit r\u00e9volutionnaire qui les secoue, et en tentant de r\u00e9affirmer la l\u00e9gitimit\u00e9 de leurs directions politiques. Cette r\u00e9affirmation se fait effectivement en s&rsquo;appuyant sur une mise en cause de l&rsquo;\u00e9tranger (l&rsquo;Ouest), qui se nourrit, tout aussi effectivement, aux tendances panarabes. Cette \u00e9volution introduit subrepticement et indirectement une dimension suppl\u00e9mentaire en impliquant, dans la logique d\u00e9velopp\u00e9e, une certaine responsabilit\u00e9 de l&rsquo;\u00e9tranger dans les \u00e9v\u00e9nements en cours dans le monde arabe (avec la domination corruptrice et d&rsquo;influence, notamment des USA, renfor\u00e7ant et tenant \u00e0 bout de bras des r\u00e9gimes aujourd&rsquo;hui partout contest\u00e9s, sinon renvers\u00e9s).<\/p>\n<\/p>\n<p><p>\t Mais cette position ferme, et unanime semble-t-il, est elle-m\u00eame porteuse d&rsquo;une contradiction sympathique. En effet, lorsqu&rsquo;on \u00e9crit que Les pays arabes veulent, dans ce cas, r\u00e9affirmer une unit\u00e9 politique de leurs directions, partout mises en cause par le grand mouvement dit r\u00e9volutionnaire&rsquo; qui les secoue, on est conduit \u00e0 observer que cette volont\u00e9 se fait au prix d&rsquo;un soutien sans aucune ambigu\u00eft\u00e9 \u00e0 un mouvement (la r\u00e9volte anti-Kadhafi) qui est directement li\u00e9, qui fait partie du grand mouvement dit r\u00e9volutionnaire&rsquo; qui secoue le monde arabe. Autrement dit, les directions politiques de pays comme Bahrein, Oman, le Yement, etc., pour les \u00e9v\u00e9nements en cours qui les mettent en cause, ou comme l&rsquo;Arabie pour ces directions qui sont menac\u00e9es d&rsquo;une telle mise en cause, acclament indirectement, par r\u00e9volte libyenne interpos\u00e9e, les mouvements qui les contestent jusqu&rsquo;\u00e0 r\u00e9clamer leur chute. On reconna\u00eet ais\u00e9ment la patte de Moussa qui, lui, a tout int\u00e9r\u00eat \u00e0 faire reconna\u00eetre sa l\u00e9gitimit\u00e9 \u00e0 la r\u00e9volte g\u00e9n\u00e9rale puisqu&rsquo;il esp\u00e8re en \u00eatre \u00e9ventuellement le porte-parole en Egypte. Du coup, la Ligue Arabe, et c&rsquo;est un grand \u00e9v\u00e9nement apr\u00e8s tout, appara\u00eet comme un soutien du mouvement de r\u00e9volte, ce qui donne effectivement sa l\u00e9gitimit\u00e9 \u00e0 la r\u00e9volte mais place dans une position encore plus d\u00e9licate les directions politiques de ceux de ses membres,  et ils sont nombreux,  qui repr\u00e9sentent l&rsquo;ordre ancien en train d&rsquo;\u00eatre d\u00e9moli.<\/p>\n<\/p>\n<p><p>\t Signalons en compl\u00e9ment, mais compl\u00e9ment qui n&rsquo;est pas sans importance, que cette position de la Ligue Arabe est renforc\u00e9e par un soutien de poids, d&rsquo;un pays musulman non arabe dont l&rsquo;importance est aujourd&rsquo;hui consid\u00e9rable et qui parle en tant que membre de l&rsquo;OTAN. Il s&rsquo;agit de la Turquie. Le Premier ministre Erdogan, en visite en Allemagne, a dit des mots d\u00e9finitifs (\u00e0 l&rsquo;agence Anatolia) \u00e0 propos d&rsquo;une intervention de l&rsquo;OTAN en Libye, qui constitue une r\u00e9f\u00e9rence directe \u00e0 ces \u00e9trangers dont la Ligue Arabe ne veut pas en Libye : \u00ab<em>This would be absurd, NATO has no business being there. We are opposed to such a scenario. Such an eventuality is unthinkable.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tDepuis des d\u00e9cennies, depuis la mort de Nasser, la Ligue Arabe a un r\u00f4le de potiche ou d&rsquo;idiote utile, c&rsquo;est selon, au service de la puissance tut\u00e9llaire des pays arabes, les USA. Aujourd&rsquo;hui, les choses ont compl\u00e8tement chang\u00e9. Le potentiel explosif de la r\u00e9volte en cours dans les pays arabes, l&rsquo;impuissance et la position d\u00e9fensive de l&rsquo;Ouest (des USA) face \u00e0 ce mouvement, redonnent \u00e0 la Ligue une position politique importante et quasiment autonome, d\u00e8s lors qu&rsquo;elle soutient <em>in fine<\/em> cette r\u00e9volte en restaurant ainsi une sorte de l\u00e9gitimit\u00e9 pour elle-m\u00eame qui lui donne une force nouvelle,  et une l\u00e9gitimit\u00e9 qui sera n\u00e9cessairement de forme panarabe. La Ligue, toujours sous l&rsquo;inspiration de Moussa, est sur la voie d&rsquo;effectuer une bonne op\u00e9ration politique, qui l&rsquo;est aussi pour le mouvement de r\u00e9volte (et qui place nombre des membres de la Ligue dans une position difficile,  on ne fait pas d&rsquo;omelettes sans casser des ufs). C&rsquo;est une sorte de donnant-donnant,  tendre \u00e0 donner une l\u00e9gitimation officelle \u00e0 ce mouvement de r\u00e9volte et, en retour, se trouve nimb\u00e9e elle-m\u00eame d&rsquo;une l\u00e9gitimit\u00e9 nouvelle.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 3 mars 2011 \u00e0 06H38<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cela \u00e9crit sur la No Fly Zone (on parle de toutes les sp\u00e9culations du c\u00f4t\u00e9 de la communaut\u00e9 internationale, c&rsquo;est-\u00e0-dire le bloc am\u00e9ricaniste-occidentaliste et principalement, bien entendu et comme on vient de le lire, au Pentagone), il se trouve que les Arabes ne l&rsquo;entendent pas pr\u00e9cis\u00e9ment de cette oreille et n&rsquo;entendent nullement que des \u00e9trangers&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[6911,10859,8294,3555,6902,10040,10833],"class_list":["post-72808","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-arabe","tag-chaine","tag-crisique","tag-legitimite","tag-libye","tag-ligue","tag-moussa"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72808"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72808\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}