{"id":72828,"date":"2011-03-09T14:40:15","date_gmt":"2011-03-09T14:40:15","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/03\/09\/pour-accueillir-la-democratie-israel-veut-plus-darmes-et-de-milliards\/"},"modified":"2011-03-09T14:40:15","modified_gmt":"2011-03-09T14:40:15","slug":"pour-accueillir-la-democratie-israel-veut-plus-darmes-et-de-milliards","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/03\/09\/pour-accueillir-la-democratie-israel-veut-plus-darmes-et-de-milliards\/","title":{"rendered":"Pour accueillir la d\u00e9mocratie, Isra\u00ebl veut plus d&rsquo;armes et de $milliards"},"content":{"rendered":"<p><p>Le Wall Street <em>Journal<\/em> s&rsquo;est enquis aupr\u00e8s du ministre isra\u00e9lien de la d\u00e9fense Ehud Barack des cons\u00e9quences pour Isra\u00ebl, du point de vue militaire et de la s\u00e9curit\u00e9, des \u00e9v\u00e9nements de la cha\u00eene crisique en cours dans les pays arabes de la r\u00e9gion. (Dans le Wall Street <em>Journal<\/em> du <a href=\"http:\/\/online.wsj.com\/article\/SB10001424052748703386704576186861325527354.html?mod=googlenews_wsj#articleTabs%3Darticle\" class=\"gen\">8 mars 2011<\/a>.)<\/p>\n<\/p>\n<p><p>\tPremier constat du ministre, dont la vigueur intellectuelle est connue dans les milieux politiques isra\u00e9liens,  constat particuli\u00e8rement roboratif et original<\/p>\n<\/p>\n<p><p>\t\u00ab<em>It&rsquo;s a historic earthquake&#8230;a movement in the right direction, quite inspired, Mr. Barak said in an interview with The Wall Street Journal, surveying the youthful revolts in Egypt, Tunisia, Libya and the Gulf. It&rsquo;s a movement of the Arab societies toward modernity.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tUn peu plus bas, le m\u00eame Barack fait une confidence \u00e0 ses intervieweurs, \u00e0 propos d&rsquo;une confidence que lui a faite une personnalit\u00e9 \u00e9gyptienne dont il ne veut pas dire le nom, qui n&rsquo;est pas, dit-il, le pr\u00e9sident du conseil militaire qui dirige actuellement l&rsquo;Egypte, le mar\u00e9chal Mohamed Hussein Tantawi. Il pourrait bien s&rsquo;agir d&rsquo;Omar Souleiman, le n\u00b02 de Moubarak qui a \u00e9t\u00e9 brutalement \u00e9limin\u00e9 de la sc\u00e8ne politique \u00e9gyptienne, mais qui garde assez de contacts au niveau politique pour pouvoir donner une analyse s\u00e9rieuse de l&rsquo;\u00e9volution politique pr\u00e9visible de l&rsquo;Egypte dans les prochains mois, dans tous les cas telle que l&rsquo;envisagent les dirigeants militaires. Cette \u00e9volution n&rsquo;est pas exaltante pour Isra\u00ebl, ni pour les USA d&rsquo;ailleurs.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>In the interview, Mr. Barak described a recent warning from another prominent Egyptian, whom he didn&rsquo;t name, that Israel could expect a different attitude unless it moved to make peace with the Palestinians. He told me, We&rsquo;re going to have a really open election&#8230;.Civic parties will hire advisers from the U.S. and Europe and find immediately that what can bring them voters is hostility to America and Israel.&rsquo;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tD&rsquo;o\u00f9 l&rsquo;on d\u00e9duit, comme l&rsquo;a fait Barack lui-m\u00eame, que ce mouvement d\u00e9mocratique si exaltant pr\u00e9sente in\u00e9luctablement un penchant antiam\u00e9ricaniste et anti-isra\u00e9lien fort pr\u00e9occupant pour Isra\u00ebl. D&rsquo;o\u00f9 l&rsquo;on en vient \u00e0 l&rsquo;essentiel pour Barack, qui est la n\u00e9cessit\u00e9 d&rsquo;un renforcement militaire sur le long terme La chose est d\u00e9j\u00e0 chiffr\u00e9e \u00e0 $20 milliards, avec la pr\u00e9cision pour la prochaine g\u00e9n\u00e9ration, ce qui pourrait \u00eatre en r\u00e9alit\u00e9 pour les prochaines dix ann\u00e9es.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The issue of qualitative military edge for Israel becomes more essential for us, and I believe also more essential for you, said Mr. Barak, a former prime minister. It might be wise to invest another $20 billion to upgrade the security of Israel for the next generation or so&#8230;.A strong, responsible Israel can become a stabilizer in such a turbulent region.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Defense analysts say Israel spends about 9% of its gross national product on defense, or roughly $17 billion per year. U.S. military assistance accounts for $3 billion of that. Mr. Barak said Israel faces no imminent threat but would have to increase its spending over the long-term.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tCes constats sont accompagn\u00e9s de la pr\u00e9cisions, en d\u00e9but d&rsquo;article, qu&rsquo;Isra\u00ebl esp\u00e8re fermement que ces $20 milliards suppl\u00e9mentaires viendront bien entendu des USA, dans le cadre d&rsquo;un renforcement de l&rsquo;aide militaire US \u00e0 Isra\u00ebl qui pourrait ainsi passer de $3 \u00e0 $4-$5 milliards par an,  esp\u00e8re-t-il (\u00ab<em>Israel will need to boost military spending and may seek an additional $20 billion in U.S. security assistance to help it manage potential threats stemming from popular upheavals in the Arab world, Defense Minister Ehud Barak said Monday.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tMalgr\u00e9 toute la belle rh\u00e9torique et les habituelles exclamations de bonheur politique devant l&rsquo;extension de la d\u00e9mocratie, la puissance des mouvements en cours pousse \u00e0 l&rsquo;orientation qu&rsquo;on pouvait pr\u00e9voir. Pour l&rsquo;Egypte, elle est irr\u00e9sistiblement de rechercher un <em>leadership<\/em> du monde arabe, peut-\u00eatre partag\u00e9 avec la <a href=\"http:\/\/www.dedefensa.org\/article-la_turquie_homme_fort_de_la_crise_libyenne_et_de_la_chaine_crisique_03_03_2011.html\" class=\"gen\">Turquie<\/a>, qui aura n\u00e9cessairement une coloration panarabe, ou n\u00e9o-panarabe, et qui sera <a href=\"http:\/\/www.dedefensa.org\/article-la_nouvelle_egypte_et_sa_logique_anti-americaniste_17_02_2011.html\" class=\"gen\">n\u00e9cessairement<\/a> distanci\u00e9e d&rsquo;Isra\u00ebl et des USA, sinon hostile \u00e0 ces deux pays, ou disons \u00e0 l&rsquo;axe qu&rsquo;ils forment,  sorte d&rsquo;axe du mal \u00e0 peine att\u00e9nu\u00e9, \u00e0 l&rsquo;envers&#8230;<\/p>\n<\/p>\n<p><p>\tBarack confie dans l&rsquo;interview qu&rsquo;il a pris contact avec le mar\u00e9chal Tantawi pour sonder l&rsquo;attitude des militaires. Le rapport qu&rsquo;il en fait dans l&rsquo;interview est rassurant en surface mais ne dissimule pas sa propre inqui\u00e9tude lorsqu&rsquo;il rapporte une phrase qu&rsquo;il a dite \u00e0 Tantawi, de leur responsabilit\u00e9 commune d&rsquo;\u00e9viter que nos jeunes gens s&rsquo;affrontent \u00e0 nouveau. (\u00ab<em>Messrs. Tantawi and Barak met about 15 years ago and discovered that they had fought on opposite sides in a fierce tank battle in the Sinai desert during the 1973 war. Mr. Barak said he told the Egyptian leader on the phone last month that we have a responsibility to avoid that our young people fight again.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tLa d\u00e9marche de Barack aupr\u00e8s de Tantawi (un coup de t\u00e9l\u00e9phone, autour du 20 f\u00e9vrier) \u00e9tait essentiellement pour s&rsquo;assurer que l&rsquo;Egypte respecterait le trait\u00e9 de paix isra\u00e9lo-\u00e9gyptien de 1979. Barack a obtenu cette garantie de Tantawi, mais le fait m\u00eame de sa d\u00e9marche, et l&rsquo;\u00e9vocation, m\u00eame <em>a contrario<\/em>, d&rsquo;hypoth\u00e8ses d&rsquo;affrontement, montrent que les relations entre les deux pays sont soumises \u00e0 de rudes tensions ; cela serait confirm\u00e9 par l&rsquo;affirmation, par des sources \u00e9gyptiennes ind\u00e9pendantes, que Barack aurait fait \u00e0 Tantawi la suggestion d&rsquo;une rencontre, que Tantawi aurait repouss\u00e9e, dans tous les cas pour l&rsquo;instant pour dire poliment, jugeant la chose pr\u00e9matur\u00e9e. Pourtant, une telle rencontre aurait \u00e9t\u00e9 la meilleure fa\u00e7on de confirmer les assurances de Tantawi au t\u00e9l\u00e9phone, et son refus semble au contraire leur donner une certaine fragilit\u00e9. Tout cela, en plus de la confidence rapport\u00e9e par Barack, semble indiquer que les militaires \u00e9gyptiens sont d\u00e9cid\u00e9s \u00e0 laisser se d\u00e9velopper le processus d\u00e9mocratique en Egypte et qu&rsquo;ils pr\u00e9voient qu&rsquo;effectivement ce processus d\u00e9bouchera sur une r\u00e9elle affirmation panarabe de l&rsquo;Egypte, se traduisant par des relations beaucoup plus incertaines avec Isra\u00ebl.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 9 mars 2011 \u00e0 14H39<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Wall Street Journal s&rsquo;est enquis aupr\u00e8s du ministre isra\u00e9lien de la d\u00e9fense Ehud Barack des cons\u00e9quences pour Isra\u00ebl, du point de vue militaire et de la s\u00e9curit\u00e9, des \u00e9v\u00e9nements de la cha\u00eene crisique en cours dans les pays arabes de la r\u00e9gion. (Dans le Wall Street Journal du 8 mars 2011.) Premier constat du&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[7359,2825,9550,10916,2774,10917],"class_list":["post-72828","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-barak","tag-democratie","tag-egypte","tag-ehud","tag-israel","tag-tantawi"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72828"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72828\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72828"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72828"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}