{"id":72845,"date":"2011-03-15T06:31:14","date_gmt":"2011-03-15T06:31:14","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/03\/15\/japon-dune-crise-lautre\/"},"modified":"2011-03-15T06:31:14","modified_gmt":"2011-03-15T06:31:14","slug":"japon-dune-crise-lautre","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/03\/15\/japon-dune-crise-lautre\/","title":{"rendered":"Japon, d&rsquo;une crise l&rsquo;autre"},"content":{"rendered":"<p><p>En un temps extr\u00eamement court, ce qu&rsquo;on peut d\u00e9crire d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale mais inappropri\u00e9e comme la crise japonaise, est pass\u00e9, pour ce qui est de l&rsquo;essentiel et de la perception qu&rsquo;on en a, du domaine naturel (tremblement de terre et <em>tsunami<\/em>) au domaine humain, avec les cons\u00e9quences de la catastrophe sur le complexe nucl\u00e9aire de production d&rsquo;\u00e9nergie. S&rsquo;il y a des liens \u00e9vidents et brutaux de cause \u00e0 effet entre ce qu&rsquo;on doit d\u00e9sormais distinguer comme deux \u00e9v\u00e9nements, la question nucl\u00e9aire constitue effectivement une v\u00e9ritable seconde crise, encha\u00eenant presque imm\u00e9diatement sur la premi\u00e8re, celle de la catastrophe naturelle. Cela appara\u00eet clairement depuis le prolongement dramatique, hier soir, d&rsquo;une troisi\u00e8me explosion dans l&rsquo;usine nucl\u00e9aire de Fukushima.<\/p>\n<\/p>\n<p><p>\tIl n&rsquo;y aucune n\u00e9cessit\u00e9, pour dresser un tel bilan, de solliciter l&rsquo;explication du go\u00fbt du sensationnel ou d&rsquo;une dramatisation outranci\u00e8re, un peu trop ais\u00e9ment d\u00e9nonc\u00e9 par des commentateurs scientifiques, surtout officiels ou assimil\u00e9s, qui s&#8217;emploient au contraire \u00e0 tenter de minimiser la crise pour la maintenir dans les normes du Syst\u00e8me et \u00e9viter justement une mise en cause du Syst\u00e8me. La r\u00e9alit\u00e9 de l&rsquo;aggravation de la situation japonaise, notamment avec la troisi\u00e8me explosion de Fukushima, est un fait \u00e9vident. Elle est d\u00e9crite ici par le <em>Guardian<\/em> du <a href=\"http:\/\/www.guardian.co.uk\/world\/2011\/mar\/14\/japan-nuclear-fukushima-third-reactor\" class=\"gen\">15 mars 2011<\/a>.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The nuclear crisis in Japan escalated as a third explosion in four days rocked the struggling power plant in the country&rsquo;s stricken north-east, according to its nuclear safety watchdog. Tokyo had already called in international help to tackle the escalating crisis.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Nonessential personnel pulled back from reactor 2 at the Fukushima No 1 power plant as radiation levels rose following the blast at 6.10am Japanese time. The blast appears to be the most serious yet, with Kyodo news agency reporting possible damage to the suppression pool of the containment vessel  increasing the risk of a significant release of radioactive material. The news agency said the safety agency feared radiation was leaking.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>As Tokyo struggled to handle the spiralling crisis, it asked the United Nations nuclear watchdog for expert help and the US nuclear regulatory commission for equipment. Officials also began to distribute potassium iodide, which can help inhibit the uptake of radioactive iodide by the thyroid, to evacuation centres. They have already evacuated hundreds of thousands of residents within a 12-mile radius of the facility<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t<em>The Independent<\/em> du <a href=\"http:\/\/www.independent.co.uk\/news\/world\/asia\/japan-prepares-for-the-worst-2241849.html\" class=\"gen\">15 mars 2011<\/a> observe, selon son titre, que le Japon se pr\u00e9pare au pire. (A cette pr\u00e9cision, on pourrait ajouter telle autre selon laquelle la 7\u00e8me Flotte US, elle aussi, se pr\u00e9pare au pire en s&rsquo;\u00e9loignant de la c\u00f4te japonaise.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Japan battled to save a nuclear power station from going into meltdown yesterday after a third explosion in three days erupted at the damaged plant and fuel rods at a reactor were left fully exposed, with staff now struggling to cool the rods in three reactors.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>While officials sought to reassure the public that the explosion posed no immediate health threat, the latest flurry of incidents has added to an already tense mood and raised concerns about the ability of the authorities to take a proactive grip of the situation. In an indication of the concern about the possible threat from radiation, US authorities relocated vessels from the 7th Fleet operating in Japanese waters off the coast from Fukushima after detecting low-level radiation on 17 crew members who have been taking part in relief operations.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLa description de la situation \u00e0 Tokyo (le <em>Guardian<\/em> du <a href=\"http:\/\/www.guardian.co.uk\/world\/2011\/mar\/14\/tokyo-streets-and-shops-empty\" class=\"gen\">14 mars 2011<\/a>) rend compte d&rsquo;une atmosph\u00e8re alourdie par la peur, d\u00e9crivant ainsi l&rsquo;importance du facteur psychologique \u00ab<em>The dimmed lights in the normally effervescent neighbourhood of Tokyo were eerily appropriate given the mood on Monday, three days into the greatest test of Japan&rsquo;s resilience as a nation since the second world war.<\/em> [] <em>Darkened streets, petrol rationing, a crippled public transport system and empty supermarket shelves are uncharted territory for a city usually teeming with people accustomed to convenience and abundance.<\/em> []  <em>While rescue teams in the Tohoku region uncover hundreds of bodies and officials struggle to cool down a third malfunctioning nuclear reactor 150 miles to the north, all the capital can do is sit tight.<\/em> [] <em>After the gridlock that followed the violent shaking in the city on Friday afternoon, for a moment it seemed that Tokyo would endure little more than momentary inconvenience. But now nerves are beginning to fray after the killer tsunami and the start of the worst nuclear crisis in the country&rsquo;s postwar history.<\/em> [] <em>Across the city, streets normally teeming with office workers about to begin their commute were strangely subdued, although far from empty.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tL&rsquo;atmosph\u00e8re g\u00e9n\u00e9rale de la psychologie dans le pays correspond \u00e0 cette situation dramatique, avec l&rsquo;apparition de la p\u00e9nurie (\u00ab<em>People are surviving on little food and water. Things are simply not coming, Hajime Sato, a government official in Iwate, told Associated Press. He said the prefecture was receiving just a tenth of the food and supplies it needed. We just did not expect such a thing to happen. It&rsquo;s just overwhelming, he said<\/em>\u00bb.) Tout cela se d\u00e9veloppe sur l&rsquo;arri\u00e8re-plan dramatique d&rsquo;une psychologie collective d\u00e9sormais marqu\u00e9e par la crainte d&rsquo;une crise nucl\u00e9aire majeure, avec toute la charge symbolique qu&rsquo;on imagine si forte au Japon, le seul pays de l&rsquo;Histoire touch\u00e9 par une attaque nucl\u00e9aire (atomique). La concr\u00e9tisation formelle de cette angoisse se fait notamment sous la forme d&rsquo;une menace d&rsquo;exode du Nord vers le Sud, voire d&rsquo;une menace d&rsquo;exode du Japon si la crise se poursuit,  avec la bataille psychologique engag\u00e9e pour ne pas c\u00e9der \u00e0 cette menace. (\u00ab<em>An exodus to the southwest and overseas is a future no one here wants to contemplate. There is plenty of anecdotal evidence of foreign residents heading to all air and rail routes leading west and beyond, but the expatriate community, like its Japanese host, is for the most part prepared to sit it out.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tQuels autres domaines solliciter encore pour compl\u00e9ter cette description de la terrible crise o\u00f9 le Japon a \u00e9t\u00e9 pr\u00e9cipit\u00e9 en quatre jours ? Il y a \u00e9videmment le domaine financier, des march\u00e9s et de la Bourse, qui fait effectivement craindre la poursuite logique, c&rsquo;est-\u00e0-dire catastrophique, de la crise dans les domaines structurels de l&rsquo;\u00e9conomie de Syst\u00e8me dont le Japon est un puissant repr\u00e9sentant (\u00ab<em>Japan&rsquo;s central bank injected 15 trillion yen (\u00a3113bn) into money markets to stabilise the country&rsquo;s economy in the wake of the disaster. But the benchmark Nikkei 225 stock average slid 6.2%.<\/em>\u00bb) Il y a m\u00eame le domaine, qui pourrait sembler anecdotique et peu s\u00e9rieux aux esprits forts, des remarques irrationnelles venues de l&rsquo;un ou l&rsquo;autre, comme celle qu&rsquo;a faite \u00e0 Associated Press le gouverneur de Tokyo Shintaro Ishihara, connu pour sa langue d\u00e9li\u00e9 et ses d\u00e9clarations \u00e0 l&#8217;emporte pi\u00e8ce : la crise vue comme une punition divine (\u00ab<em>a punishment from heaven because the Japanese had become greedy<\/em>\u00bb).<\/p>\n<\/p>\n<p><p>\tCe ph\u00e9nom\u00e8ne de la seconde crise, avec le passage de l&rsquo;\u00e9pisode tremblement de terre\/<em>tsunami<\/em> \u00e0 l&rsquo;\u00e9pisode de la crise nucl\u00e9aire, est d&rsquo;une importance \u00e9vidente pour la perception de la crise japonaise. C&rsquo;est sa transformation en un ph\u00e9nom\u00e8ne de <a href=\"http:\/\/www.dedefensa.org\/article-de_la_chaine_crisique_au_temps_crisique__24_02_2011.html\" class=\"gen\">cha\u00eene crisique<\/a>, avec l&rsquo;\u00e9tablissement d&rsquo;une tr\u00e8s forte r\u00e9f\u00e9rence \u00e0 la crise du Syst\u00e8me au travers de la mise en cause de sa dimension technologique (syst\u00e8me du technologisme). Le ph\u00e9nom\u00e8ne d&rsquo;eschatologisation, qu&rsquo;on a <a href=\"http:\/\/www.dedefensa.org\/article-l_europe_exclue_de_l_histoire_comme_les_autres_01_03_2011.html\" class=\"gen\">d\u00e9crit<\/a> \u00e9galement \u00e0 propos de la situation europ\u00e9enne vis-\u00e0-vis de la cha\u00eene crisique d\u00e9velopp\u00e9e dans les pays arabes, se manifeste \u00e9galement ici, mais dans un sens inverse ; l&rsquo;eschatologisation se fait \u00e0 partir d&rsquo;un \u00e9v\u00e9nement catastrophique naturel, eschatologique par d\u00e9finition, vers une situation humaine comme produit du syst\u00e8me du technologisme dans le chef du complexe nucl\u00e9aire de production d&rsquo;\u00e9nergie, en attirant ce complexe plong\u00e9 lui-m\u00eame dans sa crise catastrophique dans le cadre eschatologique \u00e9tabli par cette m\u00eame catastrophe naturelle. Il y a une sorte d&rsquo;int\u00e9gration des crises diverses, dans le cadre d&rsquo;une eschatologisation g\u00e9n\u00e9rale, qui implique le Syst\u00e8me en tant que tel dans un \u00e9v\u00e9nement (la crise japonaise depuis son origine naturelle) dont on ne peut tout de m\u00eame dire que l&rsquo;origine (tremblement de terre et <em>tsunami<\/em>) soit n\u00e9cessairement de sa responsabilit\u00e9&#8230;<\/p>\n<\/p>\n<p><p>\tLes effets sur la psychologie humaine, comme le montrent divers aspects de la situation japonaise, sont terrifiants en sortant cette psychologie du cadre habituel d&rsquo;un \u00e9v\u00e9nement catastrophique accompli contre lequel il importe de se dresser. Alors qu&rsquo;une catastrophe naturelle de cette ampleur est en g\u00e9n\u00e9ral suivie, apr\u00e8s le choc initial, d&rsquo;une mise en place par l&rsquo;\u00e9l\u00e9ment humain regroup\u00e9 par le Syst\u00e8me d&rsquo;une r\u00e9action de sauvegarde et de reconstruction, on se trouve ici pr\u00e9cipit\u00e9 dans un encha\u00eenement catastrophique qui, au contraire, implique dans la catastrophe l&rsquo;\u00e9l\u00e9ment humain lui-m\u00eame, sous la forme du Syst\u00e8me au sein duquel il \u00e9volue. On trouve dans cette situation g\u00e9n\u00e9rale tous les \u00e9l\u00e9ments n\u00e9cessaires pour justifier les jugements les plus extr\u00eames, les plus d\u00e9stabilisants pour la psychologie, y compris celui du gouverneur Shintaro Ishihara sur une punition divine de la rapacit\u00e9 humaine.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 15 mars 2011 \u00e0 06H24<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En un temps extr\u00eamement court, ce qu&rsquo;on peut d\u00e9crire d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale mais inappropri\u00e9e comme la crise japonaise, est pass\u00e9, pour ce qui est de l&rsquo;essentiel et de la perception qu&rsquo;on en a, du domaine naturel (tremblement de terre et tsunami) au domaine humain, avec les cons\u00e9quences de la catastrophe sur le complexe nucl\u00e9aire de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[10859,3228,8294,5274,2651,7548,10164,2808,3014,4268],"class_list":["post-72845","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-chaine","tag-crise","tag-crisique","tag-divine","tag-du","tag-eschatologie","tag-eschatologisation","tag-punition","tag-systeme","tag-technologisme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72845"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72845\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}