{"id":72848,"date":"2011-03-16T17:32:39","date_gmt":"2011-03-16T17:32:39","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/03\/16\/du-catastrophisme-a-lintuition-haute\/"},"modified":"2011-03-16T17:32:39","modified_gmt":"2011-03-16T17:32:39","slug":"du-catastrophisme-a-lintuition-haute","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/03\/16\/du-catastrophisme-a-lintuition-haute\/","title":{"rendered":"Du catastrophisme \u00e0 l&rsquo;intuition haute"},"content":{"rendered":"<p><p>Le gouvernement japonais fut parfait dans ses premi\u00e8res manifestations, le 11 mars 2011. Il h\u00e9rite d&rsquo;un demi-si\u00e8cle de r\u00e9gime lib\u00e9ral sous influence am\u00e9ricaniste, de d\u00e9mocratie de la corruption, tant v\u00e9nale que psychologique, d&rsquo;alignement sans broncher sur les lignes du Syst\u00e8me ; lui-m\u00eame, ce gouvernement, ne peut \u00eatre qu&rsquo;\u00e9gal \u00e0 ses devanciers, que digne du legs qu&rsquo;il a re\u00e7u,  c&rsquo;est-\u00e0-dire indigne en l&rsquo;occurrence Par cons\u00e9quent et apr\u00e8s ce bon d\u00e9but, il appara\u00eet aujourd&rsquo;hui, alors qu&rsquo;il est d\u00e9pass\u00e9 par l&rsquo;ampleur de ce qu&rsquo;il faut bien nommer une catastrophe, au risque d&rsquo;\u00eatre soup\u00e7onn\u00e9 de sacrifier au catastrophisme qui fait vendre, qu&rsquo;il se trouve de plus en plus totalement discr\u00e9dit\u00e9 aux yeux de sa population qui tente d&rsquo;\u00e9chapper aux cons\u00e9quences de la chose. M\u00e9rite-t-il cet opprobre ? La question reste ouverte, mais il se trouve qu&rsquo;il est le repr\u00e9sentant du Syst\u00e8me, de l&rsquo;id\u00e9al de puissance et du syst\u00e8me du technologisme, donc qu&rsquo;il est n\u00e9cessairement d\u00e9sign\u00e9 comme le responsable,  pour la culpabilit\u00e9, on verra plus tard<\/p>\n<\/p>\n<p><p>\tOn ressent cela dans l&rsquo;article de Andrew Gilligan, du <em>Daily Telegraph<\/em>, du <a href=\"http:\/\/www.telegraph.co.uk\/news\/worldnews\/asia\/japan\/8383978\/Japan-earthquake-residents-flee-as-quake-fears-spread.html\" class=\"gen\">15 mars 2011<\/a>. Les gens s&rsquo;enfuient, cherchent un abri, des espaces plus rassurants que ce pi\u00e8ge o\u00f9 se d\u00e9veloppe la catastrophe nucl\u00e9aire. Ils n&rsquo;ob\u00e9issent plus gu\u00e8re aux consignes du gouvernement, dans ce pays pourtant si prompts \u00e0 respecter une discipline nationale presque mystique. Mais tout cela, consignes, discipline, bien entendu d&rsquo;un autre temps Pour le moment, il s&rsquo;agit du d\u00e9sordre, de la fuite, des d\u00e9cisions individuelles devant ce qui est per\u00e7u comme la faillite de l&rsquo;autorit\u00e9 collective dont le comportement ne semble avoir \u00e9t\u00e9, toujours selon cette m\u00eame perception, que de tenter de dissimuler l&rsquo;ampleur de la catastrophe.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The railway station at Nasushiobara, the last one still operating near Japan&rsquo;s nuclear crisis area, was jammed with frightened people. In this ghost town of closed shops and offices, pedestrian-free pavements, and empty petrol pumps, the station was the only place still alive, and the only escape route that most had left.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The Tokyo highway a mile to the west was busy, too  but you needed a lot of petrol to get to Tokyo. At the only garage which still had it, there was a five-hour queue. With radiation now leaking from the stricken plant just down the road, there might not be five hours to spare.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>From the town and the whole surrounding region, on foot, by bicycle and using the last fuel in their tanks, the people came to the railway station, a river turning into a flood as word spread of just how serious the danger now was. I couldn&rsquo;t sleep and I was watching TV, said Noriyuki Fukada, an English teacher. Then it was announced that there would be a government statement at 6.30. I thought, if the government announces something at 6.30am, it cannot be good.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>It wasn&rsquo;t. Radioactive fuel rods in one of the stricken Fukushima nuclear reactors, the official spokesman admitted, were now \u00ab\u00a0fully exposed\u00a0\u00bb, at risk of meltdown, and radiation had escaped into the atmosphere. Ninety per cent of the plant&rsquo;s own staff were evacuated, leaving only a skeleton team fighting off catastrophe. Most serious of all, an explosion the previous day  the plant&rsquo;s third  might have damaged a reactor containment vessel.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The containment vessels are the last barriers between the reactors&rsquo; cores and the outside world, the very things the government has spent the last several days promising will protect us. A few hours later, the chief cabinet secretary, Yukio Edano, appeared on television. Now we are talking about levels [of leakage] that can impact human health. I would like all of you to embrace this information calmly, he said. But the beads of sweat were clearly visible on his own brow.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>By that point, however, I, and a good part of the population of the district around Koriyama, the major town closest to the stricken plant, were getting out. Mr Edano was telling us to stay indoors and keep our windows closed. But old habits of deference to authority were breaking down after days of conflicting and partial information, evacuations and evasions. Many were taking matters into their own hands.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>Mr Fukada, the English teacher, said: People are fed up with being told what to do and treated like fools. The problem with radiation is that you cannot know anything  you depend on the government for the information to save your life. Now we are acting for ourselves, but the worry is that we left it too late.<\/em>\u00bb<\/p>\n<h4>Notre commentaire<\/h4>\n<p>Ce qui nous importe ici est moins un commentaire direct qu&rsquo;une r\u00e9flexion \u00e0 partir de ce que d\u00e9crit Gilligan, qui est un exode en d\u00e9sordre marqu\u00e9 et suscit\u00e9 par la perte de confiance dans les autorit\u00e9s politiques de la nation (\u00ab<em>People are fed up with being told what to do and treated like fools.<\/em> [] <em>Now we are acting for ourselves<\/em>\u00bb). Nous nous souvenons de cette sensation que nous \u00e9prouv\u00e2mes, dans la soir\u00e9e du 11 mars 2011, alors que les diverses cha\u00eenes TV rendaient compte des premiers \u00e9chos de ce qui n&rsquo;\u00e9tait pas encore d\u00e9sign\u00e9 comme une catastrophe. Les experts scientifiques aussit\u00f4t convoqu\u00e9s nous assuraient que l&rsquo;ampleur de la catastrophe n&rsquo;avait nullement emp\u00each\u00e9 le progr\u00e8s humain, par exemple avec l&rsquo;enseignement du <em>tsunami<\/em> de d\u00e9cembre 2004, de mettre sa patte dans la riposte de la civilisation face \u00e0 la d\u00e9vastation naturelle. Le lendemain matin, <em>The Independent<\/em> pouvait \u00e9crire, dans une envol\u00e9e de confiance dans le susdit Progr\u00e8s, que nous avions tenu et bien tenu, que les d\u00e9g\u00e2ts \u00e9taient contenus, les centrales nucl\u00e9aires arr\u00eat\u00e9es et boucl\u00e9es en toute s\u00e9curit\u00e9 et ainsi de suite<\/p>\n<\/p>\n<p><p>\t\u00ab<em>In 1995, a quake of 6.8 magnitude struck in the city of Kobe and killed 6,500. The cost of the damage was equivalent to 2.5 per cent of Japan&rsquo;s GDP at the time. The official response was erratic. The circumstances now are different. The epicentre of the Kobe quake was in an urban area; this time it was out at sea. Nevertheless, the official response appears to have been dramatically better. Four nuclear power stations were automatically shut down when the earthquake occurred. And the damage is less severe than in 1995 since the government increased its spending on earthquake-resistant building structures. Preparation and planning have saved thousands of lives. In our search for meaning, that is probably the only lesson that can be drawn. All mankind can do, when it comes to natural disasters, is prepare itself to cope better when the nightmare becomes reality.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tNous ne pouvions d\u00e9duire et conclure de tels propos que la confirmation du triomphe du Progr\u00e8s, de la science, de l&rsquo;humanit\u00e9 et du Syst\u00e8me ; ce qui nous conduisait \u00e0 noter, pour illustrer ces m\u00eames propos, dans notre texte du <a href=\"http:\/\/www.dedefensa.org\/article-le_japon_la_raison_et_le_systeme_12_03_2011.html\" class=\"gen\">12 mars 2011<\/a> : \u00ab[A]<em>pr\u00e8s tout, tout va presque bien dans le monde en train de devenir le meilleur des mondes possibles,  car le Progr\u00e8s existe toujours, et le Syst\u00e8me avec lui. Bref, comme dirait Bouvard \u00e0 P\u00e9cuchet, ou l&rsquo;inverse, le Progr\u00e8s progresse.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tQuatre jours plus tard,  comme si, apr\u00e8s tout, c&rsquo;\u00e9tait deux ou trois si\u00e8cles apr\u00e8s, comme la distance entre le triomphe du Progr\u00e8s et son effondrement,  on se croirait effectivement dans un autre monde. Un autre expert, ou bien est-ce le m\u00eame parmi ceux qui irradiaient la confiance dans la soir\u00e9e du 11 mars, peut \u00e9crire d&rsquo;une plume furieuse et ac\u00e9r\u00e9e (il s&rsquo;agit de Andrew Schneider, ci-devant <em>Senior Public Health Correspondent<\/em>, sur <em>AOL.News<\/em> le <a href=\"http:\/\/www.aolnews.com\/2011\/03\/16\/when-nuclear-plant-planning-for-the-worst-is-not-enough\/\" class=\"gen\">16 mars 2011<\/a>,  mais cela pourrait \u00eatre Tartempion, ou bien Bouvard <em>and<\/em> P\u00e9cuchet) : \u00ab<em>Japanese and U.S. safety officials say the emergency plans for almost every plant, everywhere, precisely detail every possible response after an earthquake, flood or tsunami and explosion. But as the past five days have shown, these disaster plans seemed fine until reality reared back and slapped them silly, and this is just what happened at the Fukushima Dai-ichi nuclear complex.<\/em>\u00bb Autrement dit : la catastrophe d\u00e9passe tout ce que notre pire catastrophisme, dans ce cas sollicit\u00e9 pour faire des plans, pouvait nous pousser \u00e0 planifier.<\/p>\n<\/p>\n<p><p>\tPour nous-m\u00eames, sans la confiance en soi des experts, nous en tenant \u00e0 quelques donn\u00e9es simples et sans gloire, pour lesquelles nous n&rsquo;avons gu\u00e8re de consid\u00e9ration,  \u00ab<em>quantitativement, selon les donn\u00e9es scientifiques les plus communes et les plus basses dans leurs conceptions<\/em>\u00bb, \u00e9crivions-nous dans notre texte du <a href=\"http:\/\/www.dedefensa.org\/article-la_transversale_tohoku-kadhafi_14_03_2011.html\" class=\"gen\">14 mars 2011<\/a>,  la catastrophe japonaise nous parut assez vite avoir des dimensions bibliques,  selon une image largement employ\u00e9e par les experts du Syst\u00e8me, en d&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_crise_eschatologique_ddecrisis_13_10_2010.html\" class=\"gen\">autres occasions<\/a> que la catastrophe japonaise ne d\u00e9pare pas. Notamment, le fait que le tremblement de terre qui est la cause de tout en l&rsquo;occurrence ait fait bouger de quelques centim\u00e8tres la plan\u00e8te Terre sur son axe, et l&rsquo;archipel nippon de quelques m\u00e8tres, nous parut \u00eatre une donn\u00e9e qui transcendait la pauvret\u00e9 du langage scientifique pour atteindre \u00e0 la puissance formidable du symbole ; et lorsque le symbole atteint \u00e0 une telle puissance, c&rsquo;est qu&rsquo;il a une signification concr\u00e8te pour la situation du monde, et un effet r\u00e9el sur la marche des choses ; ainsi nous r\u00e9f\u00e9rions-nous au symbole, plus qu&rsquo;au catastrophisme qui para\u00eet-il fait vendre, et plus qu&rsquo;aux informations du gouvernement japonais, pour voir dans la catastrophe japonaise un \u00e9v\u00e9nement d&rsquo;une immense importance.<\/p>\n<\/p>\n<p><p>\tPar cons\u00e9quent, une des le\u00e7ons essentielles que nous tirons de ces divers \u00e9pisodes concerne apr\u00e8s tout la perception, la connaissance, la repr\u00e9sentation des choses. Chaque \u00e9v\u00e9nement, chaque ph\u00e9nom\u00e8ne, chaque crise, et celle-l\u00e0 avec toute sa puissance, nous confirment l&rsquo;irr\u00e9m\u00e9diable effondrement de notre Syst\u00e8me, son incapacit\u00e9 d\u00e9sormais av\u00e9r\u00e9e \u00e0 s&rsquo;approcher de la v\u00e9rit\u00e9 dans sa communication sur l&rsquo;\u00e9tat du monde tant il se trouve pris dans ses contradictions, ses langages doubles et triples, ses obsessions de puissance, ses int\u00e9r\u00eats politiques, ses emprisonnements dans des concepts conformistes, dans des terreurs intellectuelles diverses. Par cons\u00e9quent, confirmation \u00e9galement que nous devons nous appuyer sur nos propres moyens, sans plus aucun respect pour une direction politique irr\u00e9m\u00e9diablement corrompue et un <em>establishment<\/em> scientifique irr\u00e9m\u00e9diablement d\u00e9voy\u00e9, les uns et les autres dans la d\u00e9fense d&rsquo;un Syst\u00e8me dont ils sont tous prisonniers. Cela signifie, pour notre compte, qu&rsquo;il nous faut rechercher l&rsquo;aide d\u00e9cisive de l&rsquo;intuition haute dans l&rsquo;appr\u00e9ciation des choses, plut\u00f4t que celle de la notation sur une \u00e9chelle de 1 \u00e0 7 de la gravit\u00e9 de la catastrophe nucl\u00e9aire japonaise. Le symbolisme que nous rappelions plus haut constitue une indication pr\u00e9cieuse \u00e0 cet \u00e9gard, un signe de cette intuition haute, que la catastrophe en cours au Japon rec\u00e8le des m\u00e9canismes d\u00e9stabilisants et d\u00e9structurants fondamentaux, contre notre Syst\u00e8me.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 16 mars 2011 \u00e0 17H33<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le gouvernement japonais fut parfait dans ses premi\u00e8res manifestations, le 11 mars 2011. Il h\u00e9rite d&rsquo;un demi-si\u00e8cle de r\u00e9gime lib\u00e9ral sous influence am\u00e9ricaniste, de d\u00e9mocratie de la corruption, tant v\u00e9nale que psychologique, d&rsquo;alignement sans broncher sur les lignes du Syst\u00e8me ; lui-m\u00eame, ce gouvernement, ne peut \u00eatre qu&rsquo;\u00e9gal \u00e0 ses devanciers, que digne du legs&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[7287,3015,4662,3004,5953,9746,1025],"class_list":["post-72848","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-autorite","tag-communication","tag-japon","tag-nucleaire","tag-perception","tag-symbolisme","tag-tsunami"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72848"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72848\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}