{"id":72854,"date":"2011-03-18T09:27:59","date_gmt":"2011-03-18T09:27:59","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/03\/18\/psychologie-dun-vote-de-lonu\/"},"modified":"2011-03-18T09:27:59","modified_gmt":"2011-03-18T09:27:59","slug":"psychologie-dun-vote-de-lonu","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/03\/18\/psychologie-dun-vote-de-lonu\/","title":{"rendered":"Psychologie d&rsquo;un vote de l&rsquo;ONU"},"content":{"rendered":"<p><p>Commentant avec sa verve coutumi\u00e8re le vote de l&rsquo;ONU (hier soir) autorisant certaines formes d&rsquo;intervention arm\u00e9e contre la Libye (\u00ab<em>un acte flagrant de colonialisme<\/em>\u00bb, pr\u00e9cise-t-il), Kadhafi a annonc\u00e9 dans une interview \u00e0 la TV portugaise que puisque le monde \u00e9tait fou, il le serait \u00e9galement,  et au jeu du on verra qui sera le plus fou, on ne peut pas ne pas consid\u00e9rer qu&rsquo;il a de solides arguments : \u00ab<em>If the world gets crazy with us, we will get crazy too. We will respond. We will make their lives hell because they are making our lives hell. They will never have peace.<\/em>\u00bb Ainsi Kadhafi nous invite-t-il, avec des arguments solides concernant les folies diverses en jeu, dont la sienne en particulier, \u00e0 consid\u00e9rer cet \u00e9v\u00e9nement du point de vue de la psychologie.<\/p>\n<\/p>\n<p><p>\tParticuli\u00e8rement pessimiste \u00e0 propos de cette d\u00e9cision de l&rsquo;ONU provoqu\u00e9e par les Occidentaux, et particuli\u00e8rement par les Britanniques et les Fran\u00e7ais entra\u00eenant des USA plus que r\u00e9ticents, Mary Dejevsky choisit, elle aussi, l&rsquo;aspect psychologique de l&rsquo;\u00e9v\u00e9nement (<em>The Independent<\/em>, le <a href=\"http:\/\/www.independent.co.uk\/opinion\/commentators\/mary-dejevsky\/mary-dejevsky-the-west-still-labours-under-the-shadow-of-iraq-2245016.html\" class=\"gen\">18 mars 2011<\/a>). Elle y distingue le fant\u00f4me finalement toujours en pleine forme de la m\u00eame psychologie qui pr\u00e9sida \u00e0 l&rsquo;aventure irakienne de Bush-Blair et des folies de 2002-2003 Inutile de dire que, l\u00e0 aussi, le 17 mars 2011 \u00e0 New York, cette sorte de folie \u00e9tait bien pr\u00e9sente.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>There have been times in the past 10 days when you could listen to David Cameron in the House of Commons and hear not the voice of the Coalition in 2011, but that of Tony Blair from 2002-3. The same well-spoken urgency, the same high morality, the same sincere concern for his fellow human beings, the same confidence of being on the right side of history. Only the intended beneficiary of the proposed military action is different: the besieged anti-Gaddafi forces in Libya, rather than the Kurds or the Marsh Arabs of Iraq.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>And you might ask, with some incredulity, how could it be  how could it possibly be  that the next-but-one British Prime Minister has somehow managed to escape the inoculating effect of Iraq? Yesterday, David Davis  then shadow home secretary, now a back-bencher  had reinforced Mr Cameron&rsquo;s appeal for Libyan no-fly zone. As Mr Cameron had said deliverable, so Mr Davis said eminently do-able. Simple, easy. That ill-fated cakewalk again. Across the Atlantic the response was a good deal more circumspect.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tEffectivement, les USA sont plus que r\u00e9ticents. Ils ont \u00e0 l&rsquo;esprit la marque de l&rsquo;Irak, \u00e9ventuellement celle de l&rsquo;Afghanistan toujours en cours, ces bourbiers indescriptibles o\u00f9 leur puissance militaire ne cesse de s&rsquo;user jusqu&rsquo;\u00e0 l&rsquo;impotence et la dissolution. Mais les USA ont tout de m\u00eame suivi, malgr\u00e9 les affirmations r\u00e9p\u00e9t\u00e9es de Robert Gates contre l&rsquo;engagement en Libye.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>As momentous events sweep the Arab world, his administration has consistently chosen to follow rather than lead. Pressed by allies to offer early support for the protesters in Egypt, or take sides over the fighting in Libya, the White House offered nothing. The one member of his administration whom Mr Obama retained from the Bush years has been the most publicly cautious. Donald Rumsfeld&rsquo;s successor at the Pentagon, Robert Gates, said that enforcing even a no-fly zone would be tantamount to a declaration of war, concerned about becoming embroiled in another country&rsquo;s civil war.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The post-invasion anarchy in Iraq left its mark. But it is not only this memory that prescribed caution in the US and wariness on the part of Arab opposition groups that might, under other circumstances, have sought American support. At the most basic level, the Iraq war has sapped military capability and money. The US still has almost 50,000 troops deployed there. Nato forces, with the US and Britain supplying by far the largest contingents, are still fighting in Afghanistan. Arguably, Iraq is a reason they are still there a decade on  because operations in Afghanistan took second place, at a key juncture, to Iraq. Whatever the reason, the consequence is that, in combat on two fronts, even the United States cannot spare much more manpower or hardware for use beyond its own borders.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>At a psychological level, Iraq undermined US national confidence, and faith everywhere in US power. What had been sold as a justified and straightforward intervention turned out to be neither. None of the pressure on the US to mount action in North Africa could in any way be described as intelligence-led; on the contrary, the revolts there took the outside world, like almost everyone in the region, by complete surprise<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tD&rsquo;autre part, il est tr\u00e8s ais\u00e9 de montrer combien cette intervention contre Kadhafi, si elle para\u00eet justifi\u00e9e en la consid\u00e9rant du seul point de vue de la situation en Libye, est en r\u00e9alit\u00e9 une partie d&rsquo;un tr\u00e8s vaste domaine, d&rsquo;une cha\u00eene crisique qui touche l&rsquo;Afrique du Nord et le Moyen-Orient, o\u00f9 la situation g\u00e9n\u00e9rale est beaucoup plus contrast\u00e9e que le m\u00e9chant-gentil qui semble d\u00e9finir pour les esprits romantiques de nos dirigeants la situation libyenne. Plac\u00e9e dans ce contexte qui est le seul acceptable, l&rsquo;intervention souffre alors des maux habituels de l&rsquo;ambigu\u00eft\u00e9, de la contradiction, du paradoxe. Dans le <em>Guardian<\/em> du <a href=\"http:\/\/www.guardian.co.uk\/commentisfree\/2011\/mar\/16\/fate-of-arabs-egypt-not-libya\" class=\"gen\">16 mars 2011<\/a>, Seumas Milne observe par exemple combien l&rsquo;attitude occidentaliste est diff\u00e9rente vis-\u00e0-vis de l&rsquo;intervention saoudienne au Bahre\u00efn, faite, comme Kadhafi pour son compte, pour \u00e9craser l&rsquo;opposition d\u00e9mocratique qui s&rsquo;est r\u00e9v\u00e9l\u00e9e dans les derni\u00e8res semaines dans ce pays. Personne n&rsquo;envisage d&rsquo;intervenir contre l&rsquo;Arabie puisque, au contraire, l&rsquo;Arabie qui tente de massacrer l&rsquo;opposition d\u00e9mocratique dans un pays \u00e9tranger, serait accueillie avec sympathie dans la coalition militaire form\u00e9e pour tenter d&#8217;emp\u00eacher Kadhafi de massacrer l&rsquo;opposition d\u00e9mocratique dans son propre pays. Il y a donc massacre et massacre.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Increasingly, US and European politicians and media hawks are insisting it&rsquo;s all because the west has shamefully failed to intervene militarily in support of the Libyan opposition. The Times on Wednesday blamed Barack Obama for snuffing out a dawn of hope by havering over whether to impose a no-fly zone in Libya.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>But Saudi Arabia&rsquo;s dangerous quasi-invasion of Bahrain is a reminder that Libya is very far from being the only place where hopes are being stifled. The west&rsquo;s closest Arab ally, which has declared protest un-Islamic, bans political parties and holds an estimated 8,000 political prisoners, has sent troops to bolster the Bahraini autocracy&rsquo;s bloody resistance to democratic reform.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tSur les cons\u00e9quences et les effets de la nouvelle aventure militariste et moralisatrice qui commence, bien des arguments et des pr\u00e9c\u00e9dents engageraient \u00e0 partager la pr\u00e9diction du Premier ministre turc Erdogan,  une initiative qui serait totalement contre-productive et qui aggraverait le probl\u00e8me. On verra, en attendant que l&rsquo;op\u00e9ration soit d\u00e9clench\u00e9e, puisque op\u00e9ration il y aura sans doute.<\/p>\n<\/p>\n<p><p>\tL&rsquo;essentiel qu&rsquo;on peut aujourd&rsquo;hui observer est que rien ne change dans la psychologie des dirigeants am\u00e9ricanistes-occidentalistes,  avec un b\u00e9mol pour les am\u00e9ricanistes qui, vraiment, commencent \u00e0 sentir le poids de la crise d&rsquo;effondrement de la puissance US. Cette psychologie reste plus que jamais d\u00e9pendante des pressions du Syst\u00e8me, notamment relay\u00e9es par quelques perroquets fard\u00e9s en intellectuels (le super-ministre des affaires \u00e9trang\u00e8res de la r\u00e9publique fran\u00e7aise, BHL), avec pour ces dirigeants une psychologie prisonni\u00e8res de st\u00e9r\u00e9otypes conformistes, de quelques <a href=\"http:\/\/www.dedefensa.org\/article-leurs_dictateurs_etaient_l_avenir_de_l_homme_07_03_2011.html\" class=\"gen\">mots-mati\u00e8re<\/a> qui forcent \u00e0 des pens\u00e9es marqu\u00e9es par l&rsquo;automatisme pavlovien. L\u00e0-dessus, on ajoutera quelques pinc\u00e9es d&rsquo;int\u00e9r\u00eats \u00e9lectoralistes pour l&rsquo;un (notre sautillant Sarko, par exemple) et l&rsquo;ivresse assez pauvre d&rsquo;intellects de dirigeants politiques s&rsquo;imaginant avoir encore quelque influence sur les \u00e9v\u00e9nements politiques.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est \u00e0 notre sens le seul point de vue acceptable, pour l&rsquo;instant, pour appr\u00e9cier une aventure qui, comme d&rsquo;habitude, s&rsquo;appuie sur des bons sentiments dont la manifestation semble justifi\u00e9e par les \u00e9v\u00e9nements, et qui souffre du travers \u00e9pouvantable de ne tenir aucun compte des r\u00e9alit\u00e9s plus larges qui p\u00e8sent sur la situation qu&rsquo;on pr\u00e9tend r\u00e9soudre \u00e0 l&rsquo;avantage de la vertu. L\u00e0 aussi, les v\u00e9ritables caract\u00e8res qui se r\u00e9v\u00e8lent sont ceux de la confusion, du d\u00e9sarroi et, finalement, de la crise g\u00e9n\u00e9rale du Syst\u00e8me qui partout fait sentir sa loi. La Libye n&rsquo;est qu&rsquo;un appendice dans un vaste ensemble de ce <em>perfect storm<\/em> supr\u00eame, que nous avons d\u00e9sign\u00e9,  <a href=\"http:\/\/www.dedefensa.org\/article-perfect_storm_ou_le_super__18_03_2011.html\" class=\"gen\">le Super<\/a>, dont la puissance et les effets formidables sont d&rsquo;une autre nature que les votes \u00e0 l&rsquo;ONU. Cela fait peser un doute profond et accablant sur la nouvelle initiative de cet ordre am\u00e9ricaniste-occidentaliste qui, depuis plus d&rsquo;une d\u00e9cennie (le Kosovo, 1999) de fa\u00e7on visible, directe et extr\u00eamement brutale, nous montre que le d\u00e9sordre et l&rsquo;acc\u00e9l\u00e9ration de la crise g\u00e9n\u00e9rale, sinon l&rsquo;enfer lui-m\u00eame, sont pav\u00e9s de bonnes intentions. La mesure de leur vision politique et de leur intelligence du monde et de sa crise est ainsi prise. D&rsquo;autre part, diront d\u00e9sesp\u00e9r\u00e9ment les partisans de l&rsquo;intervention en Libye,  que pouvait-on faire d&rsquo;autre apr\u00e8s tout ce qui avait \u00e9t\u00e9 dit et promis, devant tant d&rsquo;\u00e9v\u00e9nements \u00e9pouvantables ? L&rsquo;argument est recevable par d\u00e9faut, \u00e0 d\u00e9faut d&rsquo;\u00eatre appr\u00e9ci\u00e9 pour une finesse qu&rsquo;il n&rsquo;a pas ; il a notamment la vertu paradoxale de nous d\u00e9montrer accessoirement que leur pens\u00e9e, celle de nos dirigeants politiques qui font profession d&rsquo;agir, est r\u00e9duite effectivement aux faibles acqu\u00eats des d\u00e9bris d&rsquo;un humanisme path\u00e9tiquement illusoire et bas que leur conc\u00e8de encore une psychologie compl\u00e8tement marqu\u00e9e par cette sorte de folie sans trop d&rsquo;excentricit\u00e9s, celle-ci caract\u00e9ristique de l&#8217;emprisonnement du Syst\u00e8me o\u00f9 ils se d\u00e9battent.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 18 mars 2011 \u00e0 09H23<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Commentant avec sa verve coutumi\u00e8re le vote de l&rsquo;ONU (hier soir) autorisant certaines formes d&rsquo;intervention arm\u00e9e contre la Libye (\u00abun acte flagrant de colonialisme\u00bb, pr\u00e9cise-t-il), Kadhafi a annonc\u00e9 dans une interview \u00e0 la TV portugaise que puisque le monde \u00e9tait fou, il le serait \u00e9galement, et au jeu du on verra qui sera le plus&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3259,3417,10888,3488,5707,9160,8173,3085,4679,6902,10887,3558,4590,3701],"class_list":["post-72854","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-arabie","tag-bhl","tag-fly","tag-hawk","tag-humanisme","tag-humanitarisme","tag-intervention","tag-kosovo","tag-liberal","tag-libye","tag-no","tag-saoudite","tag-sarkozy","tag-zone"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72854"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72854\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}