{"id":72855,"date":"2011-03-19T11:12:29","date_gmt":"2011-03-19T11:12:29","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/03\/19\/contre-le-fou-de-libye-avec-notre-allie-al-qaida\/"},"modified":"2011-03-19T11:12:29","modified_gmt":"2011-03-19T11:12:29","slug":"contre-le-fou-de-libye-avec-notre-allie-al-qaida","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/03\/19\/contre-le-fou-de-libye-avec-notre-allie-al-qaida\/","title":{"rendered":"Contre le \u201cfou de Libye\u201d, avec notre alli\u00e9 al Qa\u00efda\u2026"},"content":{"rendered":"<p><p>Possible partenaire int\u00e9ressant de la <em>coalition of the willing<\/em> (en fran\u00e7ais <em>texto<\/em>), d\u00e9mocratique et anti-Kadhafi, r\u00e9unie ce jour \u00e0 Paris, mais partenaire pourtant pas invit\u00e9 : al Qa\u00efda soi-m\u00eame. Ainsi nous le pr\u00e9cise Richard Spencer, du <em>Daily Telegraph<\/em>, ce <a href=\"http:\/\/www.telegraph.co.uk\/news\/worldnews\/africaandindianocean\/libya\/8391632\/Libya-the-West-and-al-Qaeda-on-the-same-side.html\" class=\"gen\">18 mars 2011<\/a>. <\/p>\n<\/p>\n<p><p>\tSpencer donne nombre de d\u00e9tails pr\u00e9cis et convaincants, qui ne feront sans doute l&rsquo;objet d&rsquo;aucune publicit\u00e9 excessive dans nos chancelleries. BHL, qui a momentan\u00e9ment \u00e9gar\u00e9 le num\u00e9ro de t\u00e9l\u00e9phone de l&rsquo;ambassade isra\u00e9lienne, s&rsquo;interroge quelques secondes sur la signification de cette \u00e9trange expression, al Qa\u00efda, puis il passe aux petits fours.<\/p>\n<\/p>\n<p><p>\tLe court texte de Spencer m\u00e9rite d&rsquo;\u00eatre cit\u00e9 de fa\u00e7on substantielle. On remarquera qu&rsquo;il s&rsquo;appuie notamment sur un <em>Wiki<\/em>-cable qui est parvenu sp\u00e9cifiquement au <em>Telegraph<\/em> . Cela montre l&rsquo;int\u00e9r\u00eat durable de la crise <em>WikiLeaks<\/em>&#8211;<em>Cablerange<\/em> et le choix judicieux qui est fait de la destination des fuites qui se poursuivent. Ce dernier point concerne le <em>Telegraph<\/em>, qui soutient du bout de la plume l&rsquo;intervention autoris\u00e9e par l&rsquo;ONU, montre une certaine prudence vis-\u00e0-vis d&rsquo;une situation de type imbroglio o\u00f9 les divers partis se trouvent fort souvent dans des positions \u00e9tranges, les uns et les autres avec des partenaires \u00e9tranges. Le <em>Telegraph<\/em>, proche de <a href=\"http:\/\/www.dedefensa.org\/article-les_neocons_et_l_ideal_de_puissance__04_02_2011.html\" class=\"gen\">la fraction<\/a> <em>neocon<\/em> qui se m\u00e9fie du mouvement r\u00e9volutionnaire actuel, \u00e0 l&rsquo;image de l&rsquo;analyse qu&rsquo;en fait Isra\u00ebl, trouve qu&rsquo;on fait la part trop belle \u00e0 l&rsquo;ivresse de la d\u00e9mocratisation au Moyen-Orient, avec notamment le risque que les islamistes noyautent tel ou tel mouvement de d\u00e9mocratisation \u00e0 leur avantage. Il faut rappeler que certains r\u00e9gimes arabes, de fort mauvaise r\u00e9putation certes, comme l&rsquo;Alg\u00e9rie et la Syrie, ne cachent pas qu&rsquo;ils livrent des armes \u00e0 Kadhafi parce que leur conviction est que le mouvement anti-Kadhafi contient effectivement des \u00e9l\u00e9ments islamiques dangereux. (BHL, lui, avait montr\u00e9 en f\u00e9vrier, avec les amis Adler et Glucksmann, une grande r\u00e9ticence face au mouvement g\u00e9n\u00e9ral anti-Moubarak, justement \u00e0 cause de cette hypoth\u00e8que islamiste. Il avait encore, \u00e0 cette \u00e9poque, dans son carnet d&rsquo;adresse, le num\u00e9ro de t\u00e9l\u00e9phone de l&rsquo;ambassade d&rsquo;Isra\u00ebl. Par cons\u00e9quent, il est probable qu&rsquo;il le retrouvera.)  <\/p>\n<\/p>\n<p><p>\t\u00bb<em>WikiLeaks cables, independent analysts and reporters have all identified supporters of Islamist causes among the opposition to Col Gaddafi&rsquo;s regime, particularly in the towns of Benghazi and Dernah. An al-Qaeda leader of Libyan origin, Abu Yahya al-Libi, released a statement backing the insurrection a week ago, while Yusuf Qaradawi, the Qatar-based, Muslim Brotherhood-linked theologian issued a fatwa authorising Col Gaddafi&rsquo;s military entourage to assassinate him.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>But they also agree that the leading roles in the revolution are played by a similar cross-section of society as that in Egypt next door  liberals, nationalists, those with personal experience of regime brutality and Islamists who subscribe to democratic principles.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The WikiLeaks cables, initially revealed by The Daily Telegraph and dating from 2008, identified Dernah in particular as a breeding ground for fighters in a number of causes, including Afghanistan and Iraq. The unemployed, disfranchised young men of eastern Libya have nothing to lose and are therefore willing to sacrifice themselves for something greater than themselves by engaging in extremism in the name of religion, the cables quoted a Dernah businessman as saying.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Col Gaddafi has pinpointed the rebels in Dernah as being led by an al-Qaeda cell that has declared the town an Islamic emirate. The regime also casts blame on hundreds of members of the Libyan Islamist Fighting Group released since the group renounced violence two years ago. Although said by the regime to be affiliated to al-Qaeda, most LIFG members have focused only on promoting sharia law in Libya, rejecting a worldwide jihad.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The man running Dernah&rsquo;s defences, Abdelkarim al-Hasadi, was arrested by US forces in Afghanistan in 2002, but says he does not support a Taliban-like state. The rebels&rsquo; political leadership there says it is secular.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tQue d\u00e9duire de ces pr\u00e9cisions qui ont, r\u00e9p\u00e9tons-le, une certaine solidit\u00e9 ? (Bien s\u00fbr, il faut pr\u00e9ciser qu&rsquo;il ne s&rsquo;agit \u00e9videmment pas des premiers bruits dans ce sens, concernant al Qa\u00efda en Libye. Mais les pr\u00e9cisions sont effectivement importantes, et aussi la publication dans un quotidien comme le <em>Daily Telegraph<\/em>.) Premi\u00e8rement, elles ne d\u00e9parent certainement pas l&rsquo;impression de flou g\u00e9n\u00e9ral et artistique qui entoure le <strong>sens politique<\/strong> pr\u00e9cis du mouvement r\u00e9volutionnaire qui balaie le Maghreb et le Moyen-Orient depuis d\u00e9cembre 2010. Deuxi\u00e8mement, cela ne fait pas pour autant de ces indications sur la pr\u00e9sence possible ou probable d&rsquo;islamistes, voire d&rsquo;\u00e9l\u00e9ments d&rsquo;Al Qa\u00efda, des signes de la n\u00e9cessit\u00e9 d&rsquo;une alarme si extr\u00eame qu&rsquo;il faille renverser le jugement g\u00e9n\u00e9ral qui conforte nos \u00e2mes vertueuses et couvrir d&rsquo;opprobre ce mouvement anti-Kadhafi. Ce dernier point, essentiellement parce que l&rsquo;ampleur de la menace et de l&rsquo;influence repr\u00e9sent\u00e9es par al Qa\u00efda, ou ce qui se pare du nom d&rsquo;al Qa\u00efda, nous para\u00eet toujours aussi suspecte aujourd&rsquo;hui qu&rsquo;hier (en 2001-2002), dans l&rsquo;importance apocalyptique qu&rsquo;on lui accorde, en consid\u00e9ration de la part consid\u00e9rable de montage des diverses officines am\u00e9ricanistes-occidentalistes dans la repr\u00e9sentation manipul\u00e9e de la puissance et de la capacit\u00e9 d&rsquo;action de ce mouvement.<\/p>\n<\/p>\n<p><p>\tTroisi\u00e8mement, d&rsquo;une fa\u00e7on plus g\u00e9n\u00e9rale, nous nous en tenons plus que jamais au jugement que l&rsquo;essentiel dans ce mouvement que nous qualifions de cha\u00eene crisique est dans sa capacit\u00e9 de d\u00e9structuration de l&rsquo;ordre existant dans la zone, qui est l&rsquo;enfant incontestable du Syst\u00e8me. Qu&rsquo;une composante d&rsquo;al Qa\u00efda participe \u00e9ventuellement \u00e0 la chose, qu&rsquo;al Qa\u00efda soit un montage plus ou moins consid\u00e9rable, nous importent peu pourvu que la chose (le mouvement de d\u00e9structuration) ait lieu. Que des dirigeants politiques am\u00e9ricanistes-occidentalistes, qui ne peuvent avoir d&rsquo;autres conceptions que celle de la d\u00e9fense du Syst\u00e8me, notamment contre des forces comme celle d&rsquo;al Qa\u00efda pr\u00e9sent\u00e9es pour l&rsquo;occasion comme gigantesques, se trouvent du c\u00f4t\u00e9 d&rsquo;un mouvement o\u00f9 se trouveraient des gens d&rsquo;al Qa\u00efda, et mouvement objectivement d\u00e9structurant de l&rsquo;ordre existant du Syst\u00e8me (notamment par l&rsquo;effet principal des pressions et attaques contre Kadhafi, dans la perception g\u00e9n\u00e9ral qu&rsquo;on a de la cha\u00eene crisique),  cette contradiction \u00e0 plusieurs volets, ou cha\u00eene de contradictions apr\u00e8s tout, n&rsquo;a rien pour nous surprendre ni pour nous alarmer tant la confusion et le d\u00e9sordre sont les caract\u00e8res essentiels des jugements des h\u00e9ros (nos dirigeants politiques) de cette aventure.<\/p>\n<\/p>\n<p><p>\tQuatri\u00e8mement, et c&rsquo;est le dernier point qui reprend la phrase pr\u00e9c\u00e9dente en nous fournissant ainsi un remarquable encha\u00eenement. La pouss\u00e9e de la <em>coalition of the willing<\/em>, le vote contre l&rsquo;ONU, l&rsquo;attaque en cours de pr\u00e9paration contre Kadhafi, ne r\u00e9pondent \u00e0 aucun plan pr\u00e9con\u00e7u, \u00e0 aucune vision construite, \u00e0 aucune machination \u00e9labor\u00e9e contre un homme qui en sait trop. (Tout dirigeant dans les r\u00e9seaux du Syst\u00e8me aujourd&rsquo;hui en sait trop sur tout le monde, comme tout le monde en sait trop sur lui-m\u00eame ; tout cela donnant des opportunit\u00e9s de scandales qui ne valent gu\u00e8re puisque ces scandales sont entach\u00e9s de cette complicit\u00e9 g\u00e9n\u00e9rale o\u00f9 tout le monde a int\u00e9r\u00eat \u00e0 dissimuler, ou dans tous les cas discr\u00e9diter, y compris par des mauvaises r\u00e9putations sur l&rsquo;\u00e9tat de l&rsquo;\u00e9quilibre mental d&rsquo;\u00e9ventuels donneurs, ce que chacun peut avoir \u00e0 dire sur le compte de chacun) Plus platement, la pouss\u00e9e de la <em>coalition of the willing<\/em> r\u00e9pond par cons\u00e9quent \u00e0 des impulsions de communication o\u00f9 la part de perroquets maquill\u00e9s comme BHL n&rsquo;est pas sans importance, avec des int\u00e9r\u00eats divers et particuliers en suppl\u00e9ment (la position pr\u00e9-\u00e9lectorale de Sarko qu&rsquo;il faut redresser). La seule vertu essentielle qu&rsquo;on puisse trouver aux durs de la coalition est justement dans cet aveuglement vis-\u00e0-vis des conditions r\u00e9elles de la crise, laquelle crise r\u00e9pond \u00e0 des courants beaucoup plus hauts que la simple pens\u00e9e qu&rsquo;on doit tout de m\u00eame qualifier d&rsquo;humaine de dirigeants politiques dont le jugement politique est r\u00e9duit aux avatars quotidiens de ce qu&rsquo;on nomme l&rsquo;\u00e9cume des jours. L&rsquo;essentiel est alors que la logique de ces courants est de type d\u00e9structurant et s&rsquo;exerce contre l&rsquo;ordre du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tPour le reste et en fonction de tout ce qui pr\u00e9c\u00e8de, l&rsquo;hypoth\u00e8se d&rsquo;une chute de Kadhafi implique l&rsquo;hypoth\u00e8se secondaire que la situation qui s&rsquo;installerait en Libye restituerait un certain d\u00e9sordre dont les affirmations sur la pr\u00e9sence d&rsquo;al Qa\u00efda sont un signe avant-coureur (et auquel les d\u00e9saccords in\u00e9vitables entre les amis de la <em>coalition of the willing<\/em> ne manqueraient pas de contribuer) ; l\u00e0 aussi, rien \u00e0 redire, puisque ce certain d\u00e9sordre poursuit le travail de d\u00e9structuration qui nous int\u00e9resse, le contraire \u00e9tant l&rsquo;\u00e9tablissement d&rsquo;un ordre se r\u00e9f\u00e9rant \u00e0 l&rsquo;ordre am\u00e9ricaniste-occidentaliste qui servirait, sous une autre forme, les int\u00e9r\u00eats du Syst\u00e8me. Plus que jamais, notre int\u00e9r\u00eat est pour le rythme et la dynamique de la cha\u00eene crisique avec leur caract\u00e8re d\u00e9structurant, nullement pour le sens qu&rsquo;on voudrait lui trouver, qui aboutirait dans les circonstances pr\u00e9sentes qui sont toujours contraintes, \u00e0 une restauration d&rsquo;une fa\u00e7on ou l&rsquo;autre de l&rsquo;ordre du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tEn un mot de conclusion, nous pr\u00e9ciserons que nos observations ne concernent certainement pas, <em>stricto sensu<\/em>, les conditions de la perspective d&rsquo;une guerre, dont l&rsquo;ampleur reste \u00e0 voir et qui est de toutes les fa\u00e7ons d\u00e9j\u00e0 en cours, la <em>coalition of the willing<\/em> ne faisant qu&rsquo;y intervenir \u00e9ventuellement et ne la d\u00e9clenchant nullement. Il nous importe avant tout d&rsquo;\u00e9largir le champ de nos propos, et nos observations concernent donc plut\u00f4t, dans notre chef et selon notre opinion dans tous les cas, la multiplication des points de d\u00e9sordre (un certain d\u00e9sordre) rendant toujours plus difficile de restaurer par le fer et par le feu (par la guerre, justement) un ordre favorable au Syst\u00e8me sous une autre forme et avec les dissimulations qui font l&rsquo;affaire (la d\u00e9mocratisation arrang\u00e9e \u00e0 la sauce-Syst\u00e8me en \u00e9tant une). Les hypoth\u00e8ses s\u00e9rieuses sur la pr\u00e9sence chez les anti-Kadhafi, parmi d&rsquo;autres \u00e9l\u00e9ments qu&rsquo;on dit beaucoup plus fr\u00e9quentables, d&rsquo;al Qa\u00efda ou d&rsquo;\u00e9l\u00e9ments islamistes qui en sont proches au moins pour les conceptions, constituent un facteur de plus pour rendre difficile sinon impossible cette restauration. Il n&rsquo;est pas n\u00e9cessaire pour autant de c\u00e9der \u00e0 la panique grotesque d&rsquo;attribuer \u00e0 l&rsquo;hypoth\u00e9tique Al Qa\u00efda, selon l&rsquo;image qu&rsquo;on en fait, une puissance d\u00e9moniaque \u00e0 la mesure des obsessions apocalyptiques que suscitent chez nos dirigeants l&rsquo;influence du Syst\u00e8me. Tout juste peut-on appr\u00e9cier \u00e0 leur mesure les paradoxes et les contradictions assez ironiques, et dans tous les cas r\u00e9v\u00e9lateurs, qui marquent les regroupements et les alliances <em>ad hoc<\/em> de ce d\u00e9sordre consid\u00e9rable o\u00f9 se d\u00e9bat cette civilisation encapsul\u00e9e dans son Syst\u00e8me.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 19 mars 2011 \u00e0 11H11<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Possible partenaire int\u00e9ressant de la coalition of the willing (en fran\u00e7ais texto), d\u00e9mocratique et anti-Kadhafi, r\u00e9unie ce jour \u00e0 Paris, mais partenaire pourtant pas invit\u00e9 : al Qa\u00efda soi-m\u00eame. Ainsi nous le pr\u00e9cise Richard Spencer, du Daily Telegraph, ce 18 mars 2011. Spencer donne nombre de d\u00e9tails pr\u00e9cis et convaincants, qui ne feront sans doute&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3417,5253,10891,6902,1104,4014,10945,3050,9887,10944],"class_list":["post-72855","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-bhl","tag-coalition","tag-kadhafi","tag-libye","tag-neocons","tag-of","tag-spencer","tag-the","tag-wikileaks","tag-willing"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72855","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72855"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72855\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}