{"id":72865,"date":"2011-03-23T10:23:19","date_gmt":"2011-03-23T10:23:19","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/03\/23\/un-petit-contretemps\/"},"modified":"2011-03-23T10:23:19","modified_gmt":"2011-03-23T10:23:19","slug":"un-petit-contretemps","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/03\/23\/un-petit-contretemps\/","title":{"rendered":"Un petit contretemps"},"content":{"rendered":"<p><h2 class=\"common-article2\">Un petit contretemps<\/h2>\n<\/p>\n<p><p>\tLe soul\u00e8vement du peuple libyen contre le r\u00e9gime totalitaire  de la ploutocratie qadafienne \u00e9tait en voie d&rsquo;\u00e9crasement. Les armes employ\u00e9es contre le peuple libyen ont \u00e9t\u00e9 fournies essentiellement par la France. Un point d&rsquo;inflexion dans l&rsquo;\u00e9volution de la r\u00e9volution libyenne est survenu autour du 3 mars 2011. L&rsquo;avance des insurg\u00e9s depuis la ville de Benghazi vers  l&rsquo;ouest du pays arriv\u00e9e \u00e0 pr\u00e8s d&rsquo;une centaine de kilom\u00e8tres  de Tripoli a \u00e9t\u00e9 arr\u00eat\u00e9e net. Elle a correspondu \u00e0 la visite de 24 heures effectu\u00e9e par l&rsquo;un des fils du dictateur \u00e0 Tel Aviv. Il y est all\u00e9 demander au r\u00e9gime sioniste de lui fournir un mat\u00e9riel anti-\u00e9meute sophistiqu\u00e9, un \u00e9quipement d&rsquo;observation nocturne et des images satellitaires de son propre pays.  De m\u00eame, il a n\u00e9goci\u00e9 un appui logistique au travers des diff\u00e9rentes soci\u00e9t\u00e9s militaires priv\u00e9es dans lesquelles se reconvertissent tr\u00e8s volontiers les anciens officiers de l&rsquo;arm\u00e9e d&rsquo;occupation. Ces ex\u00e9cuteurs de sale besogne sont sollicit\u00e9s en vertu de leur expertise valid\u00e9e en r\u00e9pression de civils, les Palestiniens en Palestine occup\u00e9e en t\u00e9moignent tous les jours.<\/p>\n<\/p>\n<p><p>\tImm\u00e9diatement apr\u00e8s cette visite \u00e9clair, un avion rempli d&rsquo;experts militaires isra\u00e9liens a atterri \u00e0 l&rsquo;a\u00e9roport de Tripoli.<\/p>\n<\/p>\n<p><p>\tLes forces gouvernementales frappaient les villes par air, par voie de terre et de mer mais ne parvenaient pas \u00e0 p\u00e9n\u00e9trer les cit\u00e9s bien d\u00e9fendues par les civils insurg\u00e9s transform\u00e9s en peu de jours en gu\u00e9rilleros. Mesrata n&rsquo;a jamais \u00e9t\u00e9 investie alors m\u00eame qu&rsquo;elle \u00e9tait assi\u00e9g\u00e9e.<\/p>\n<\/p>\n<p><p>\tToutes les tribus, hormis celle des Qdadfas d&rsquo;o\u00f9 est issu le colonel dictateur,  avaient ralli\u00e9 la r\u00e9bellion. Elles sont \u00e0 m\u00eame de contr\u00f4ler les sites d&rsquo;extraction du p\u00e9trole tous \u00e0 leur port\u00e9e en plein d\u00e9sert, y compris d&rsquo;en arr\u00eater la production.<\/p>\n<\/p>\n<p><p>\tCette \u00e9ventualit\u00e9 n&rsquo;a jamais \u00e9t\u00e9 mise en avant par le gouvernement transitoire.<\/p>\n<\/p>\n<p><p>\tLe besoin irr\u00e9pressible de se maintenir au pouvoir est inversement proportionnel \u00e0 la l\u00e9gitimit\u00e9 populaire de l&rsquo;\u00e9quipe au pouvoir, c&rsquo;est bien ce que nous ont d\u00e9montr\u00e9 les r\u00e9centes r\u00e9volutions arabes.<\/p>\n<\/p>\n<p><p>\tArriv\u00e9 au sommet de la hi\u00e9rarchie \u00e0 l&rsquo;occasion d&rsquo;un coup d&rsquo;\u00c9tat, jamais soumis \u00e0 un quelconque suffrage e\u00fbt-il \u00e9t\u00e9 frauduleusement gagn\u00e9, le colonel a fait de la Libye sa propri\u00e9t\u00e9 priv\u00e9e. Il ne peut comprendre que le peuple veut le cong\u00e9dier.<\/p>\n<\/p>\n<p><p>\tL&rsquo;insurrection s&rsquo;est transform\u00e9e en guerre civile asym\u00e9trique.<\/p>\n<\/p>\n<p><p>\tPourquoi a-t-elle pr\u00e9f\u00e9r\u00e9 demander l&rsquo;aide de la communaut\u00e9 internationale&rsquo; plut\u00f4t que de s&rsquo;enqu\u00e9rir de quelques munitions faciles \u00e0 acheminer et tr\u00e8s efficaces contre les tanks et les avions de Qadafi ? A-t-elle \u00e9t\u00e9 d\u00e9stabilis\u00e9e par l&rsquo;aide que le gouvernement alg\u00e9rien, lui qui n&rsquo;a pas h\u00e9sit\u00e9 \u00e0 sacrifier entre 500.000 et un million de ses citoyens dans les ann\u00e9es de guerre civile, a port\u00e9 \u00e0 son oppresseur ?<\/p>\n<\/p>\n<p><p>\tLes circonstances internationales ne sont plus les m\u00eames. L&rsquo;h\u00e9g\u00e9monie \u00e9tasunienne et occidentale de fa\u00e7on g\u00e9n\u00e9rale s&rsquo;effondre depuis les impasses militaires de l&rsquo;Afpak et de l&rsquo;Irak et le d\u00e9labrement \u00e9conomique induit par ses crises financi\u00e8res. La r\u00e9volution arabe une fois commenc\u00e9e se poursuivra, la peur s&rsquo;est dissip\u00e9e \u00e0 la terrible \u00e9cole des enfants de Palestine affrontant des chars des pierres \u00e0 la main.<\/p>\n<\/p>\n<p><p>\tAlors, pourquoi accorder un quelconque cr\u00e9dit d&rsquo;humanitarisme \u00e0 ce machin onusien qui n&rsquo;est jamais venu en aide au plus faible, sinon pour le d\u00e9pouiller au profit des puissances qui le dominent ?<\/p>\n<\/p>\n<p><p>\tLa proc\u00e9dure de demande d&rsquo;aide \u00e0 un pays arabe voisin existe et a \u00e9t\u00e9 convoqu\u00e9e lors de la conqu\u00eate de l&rsquo;Alg\u00e9rie par la France. Le peuple de Tlemcen a demand\u00e9 protection, c&rsquo;est-\u00e0-dire armes et possibilit\u00e9 de refuge, au roi du Maroc qui le lui a accord\u00e9 jusqu&rsquo;au d\u00e9sastre de la bataille d&rsquo;Isly en 1844. Le gouvernement transitoire aurait pu solliciter la puissante arm\u00e9e \u00e9gyptienne.<\/p>\n<\/p>\n<p><p>\tLa facture que va pr\u00e9senter la coalition qui assure l&rsquo;exclusion a\u00e9rienne en Libye va \u00eatre lourde. Les pertes civiles annonc\u00e9es d\u00e8s les premi\u00e8res 24 heures sont d\u00e9j\u00e0 consid\u00e9rables et comment s&rsquo;en \u00e9tonner apr\u00e8s qu&rsquo;il ait \u00e9t\u00e9 d\u00e9montr\u00e9 en Afghanistan, au Pakistan et en Irak l&rsquo;impr\u00e9cision des tirs des missiles hautement intelligents qui ne cessent de tuer des enfants ou de pauvres gens c\u00e9l\u00e9brant un mariage ?<\/p>\n<\/p>\n<p><p>\tLes pays participant \u00e0 la cur\u00e9e ont d\u00fb n\u00e9gocier le contr\u00f4le des ressources p\u00e9troli\u00e8res du pays et donc une ing\u00e9rence politique. L&rsquo;amiral Mc Mullen a d&rsquo;ores et d\u00e9j\u00e0 inform\u00e9 qu&rsquo;une exclusion a\u00e9rienne m\u00eame r\u00e9ussie n&rsquo;aboutira probablement pas \u00e0 la chute de Qadafi sur le mode, \u00ab c&rsquo;est un voyou, mais c&rsquo;est le n\u00f4tre \u00bb.<\/p>\n<\/p>\n<p><p>\tCette exp\u00e9dition en Afrique du Nord consiste-t-elle en une excursion de d\u00e9monstration des capacit\u00e9s de leurs avions de derni\u00e8re g\u00e9n\u00e9ration, mais quel acheteur veulent-ils convaincre des performances des Rafale, Tornado et F-22 ?<\/p>\n<\/p>\n<p><p>\tL&rsquo;appui monnay\u00e9 d&rsquo;Isra\u00ebl \u00e0 Qadafi et l&rsquo;intervention de la France aux c\u00f4t\u00e9s des insurg\u00e9s alors que celle-ci a align\u00e9 tr\u00e8s nettement depuis Sarkozy sur les desiderata  de la politique \u00e9trang\u00e8re isra\u00e9lienne n&rsquo;offre qu&rsquo;une contradiction apparente. L&rsquo;Iran se fournissait bien en armes chez l&rsquo;entit\u00e9 sioniste for\u00e7ant l&#8217;embargo \u00e9tasunien pendant les huit ans de la guerre Iran-Irak. Les affaires n&#8217;emp\u00eachent pas de basses manuvres \u00e9lectoralistes et l&rsquo;avancement de quelques pions en faveur de Total dans un pays que l&rsquo;on aimerait bien d\u00e9vaster et reconstruire.<\/p>\n<\/p>\n<p><p>\tAmr Moussa parlant au nom de la Ligue Arabe, et un peu au sien car il pr\u00e9tend au commandement supr\u00eame en \u00c9gypte, condamne le bombardement occidental des civils alors m\u00eame que la vieille dame n\u00e9e en 1945 avait approuv\u00e9 la demande d&rsquo;une exclusion a\u00e9rienne.<\/p>\n<\/p>\n<p><p>\tL&rsquo;Organisation de l&rsquo;Union Africaine exige l&rsquo;arr\u00eat imm\u00e9diat des frappes occidentales sur la Libye et convoque pour le 25 avril \u00e0 Addis Abeba le ban et l&rsquo;arri\u00e8re ban des organisations internationales pour d\u00e9cider d&rsquo;une action concert\u00e9e envers la Libye, passant outre le r\u00e9sultat permissif  du Conseil de S\u00e9curit\u00e9.<\/p>\n<\/p>\n<p><p>\tClairement le monde est en train d&rsquo;expliquer que nous ne sommes plus dans l&rsquo;\u00e8re de l&rsquo;unilat\u00e9ralisme occidental.<\/p>\n<\/p>\n<p><p>\tCes deux instances auraient pu imposer ou du moins n\u00e9gocier un cessez-le-feu avant les d\u00e9cisions de l&rsquo;ONU.<\/p>\n<\/p>\n<p><p>\tLe petit d\u00e9crochage actuel v\u00e9cu par la r\u00e9volution arabe comme l&rsquo;intervention de la maison des S\u00e9oud au Bahrein et l&rsquo;envoi des gadgets occidentaux tueurs sur la Libye constitue un retard \u00e0 son progr\u00e8s, mais ne lui seront pas un coup fatal.<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Badia Benjelloun<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un petit contretemps Le soul\u00e8vement du peuple libyen contre le r\u00e9gime totalitaire de la ploutocratie qadafienne \u00e9tait en voie d&rsquo;\u00e9crasement. Les armes employ\u00e9es contre le peuple libyen ont \u00e9t\u00e9 fournies essentiellement par la France. Un point d&rsquo;inflexion dans l&rsquo;\u00e9volution de la r\u00e9volution libyenne est survenu autour du 3 mars 2011. L&rsquo;avance des insurg\u00e9s depuis la&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[10959,3953,2774,10891,6902],"class_list":["post-72865","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-badia","tag-benjelloun","tag-israel","tag-kadhafi","tag-libye"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72865","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72865"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72865\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72865"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72865"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72865"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}