{"id":72894,"date":"2011-04-02T10:50:18","date_gmt":"2011-04-02T10:50:18","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/04\/02\/notes-sur-la-chaine-crisique-ddecrisis\/"},"modified":"2011-04-02T10:50:18","modified_gmt":"2011-04-02T10:50:18","slug":"notes-sur-la-chaine-crisique-ddecrisis","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/04\/02\/notes-sur-la-chaine-crisique-ddecrisis\/","title":{"rendered":"Notes sur la cha\u00eene crisique (<em>dde.crisis<\/em>)"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955; font-size:2em\">Notes sur la cha&icirc;ne crisique (<em>dde.crisis<\/em>)<\/h2>\n<\/p>\n<p><p>Le num\u00e9ro dat\u00e9 du <a class=\"gen\" href=\"http:\/\/www.edde.eu\/publication-ddecrisis_du_10_mars_2011.html\">10 mars 2011<\/a> de <em>dde.crisis<\/em> consacre sa rubrique centrale (<em>dedefensa<\/em>) au ph\u00e9nom\u00e8ne d&rsquo;encha&icirc;nement de crises, ou \u00ab\u00a0cha&icirc;ne crisique\u00a0\u00bb, qui s&rsquo;est manifest\u00e9 dans le monde arabo-musulman depuis le 19 d\u00e9cembre 2010. Il s&rsquo;agit de cette s\u00e9rie de crises de formes diff\u00e9rentes, qui s&rsquo;est encha&icirc;n\u00e9e depuis d\u00e9cembre, qui se poursuit actuellement sous des formes \u00e9galement vari\u00e9es.<\/p>\n<\/p>\n<p><p>En pr\u00e9sentant notre analyse, nous entendons d&rsquo;abord montrer ce que nous jugeons comme \u00e9tant deux caract\u00e8res essentiels de ces \u00e9v\u00e9nements : le r\u00f4le fondamental de la psychologie et le ph\u00e9nom\u00e8ne de ce que nous nommons l'\u00a0\u00bbeschatologisation\u00a0\u00bb des crises.<\/p>\n<\/p>\n<p><p>&laquo;<em>Ce n&rsquo;est pas une crise de plus, ou une s\u00e9rie de crises de plus. Nous ne parlons pas ici de l&rsquo;ampleur du ph\u00e9nom\u00e8ne, de son importance politique, etc. Nous entendons parler le moins possible de g\u00e9opolitique, d&rsquo;\u00e9conomie, de strat\u00e9gie, parce qu&rsquo;\u00e0 notre sens ces facteurs ne tiennent que des r\u00f4les secondaires dans le ph\u00e9nom\u00e8ne. Nous entendons parler du syst\u00e8me de la communication et de la psychologie d&rsquo;une part, des forces de la m\u00e9tahistoire et de l&rsquo;\u00e9volution du Syst\u00e8me d&rsquo;autre part.<\/em> [&hellip;] <em>Ce qui se passe,<\/em> [&hellip;] <em>c&rsquo;est l'\u00a0\u00bbeschatologisation\u00a0\u00bb des crises humaines. Il s&rsquo;agit d&rsquo;un raccourci pour compl\u00e9ter notre pr\u00e9sentation du ph\u00e9nom\u00e8ne en signalant que ces crises en apparence humaines \u00e9chappent aux hommes.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Nous observons \u00e9galement que cette cha&icirc;ne crisique n&rsquo;est pas limit\u00e9e au Maghreb et au Moyen-Orient, ou monde arabo-musulman. On peut y inscrire certains \u00e9v\u00e9nements internes aux USA, comme les \u00e9v\u00e9nements de Madison, dans le Wisconsin. L&rsquo;encha&icirc;nement et la rapidit\u00e9 de ces crises suscitent des situations nouvelles et exceptionnelles, donnant tout son sens au ph\u00e9nom\u00e8ne d&rsquo;eschatologisation signal\u00e9 plus haut ; il ne suit pas une \u00e9volution spatiale logique, effectuant des mouvements d&rsquo;expansion et de r\u00e9traction sans gu\u00e8re de logique de continuit\u00e9 pour la raison ; le facteur temporel (rythme des crises) compte bien plus que le facteur spatial (localisation et extension de crises localis\u00e9es).<\/p>\n<\/p>\n<p><p>&laquo;[L]<em>e r\u00e9sultat g\u00e9n\u00e9ral de cette situation est que cette s\u00e9rie de crises, depuis ses d\u00e9but, n&rsquo;a jamais \u00e9t\u00e9 rationalis\u00e9e et d\u00e9finie pr\u00e9cis\u00e9ment, notamment par les directions politiques&hellip;<\/em> [&hellip;] <em>Cette situation perdure aujourd&rsquo;hui, alors que la \u00ab\u00a0cha&icirc;ne crisique\u00a0\u00bb continue \u00e0 \u00eatre d\u00e9vid\u00e9e. Il n&rsquo;y a aucune explication \u00ab\u00a0officielle\u00a0\u00bb, aucune narrative s\u00e9rieuse&#8230; C&rsquo;est bien ce que nous nommons l'\u00a0\u00bbeschatologisation\u00a0\u00bb de la crise. Comme l&rsquo;on disait des guerres, les crises humaines sont choses trop importantes pour \u00eatre confi\u00e9es aux sapiens.<\/em>&raquo;<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Toute prospective est indescriptible<\/h2>\n<\/p>\n<p><p>Confront\u00e9s \u00e0 ces \u00e9v\u00e9nements extraordinaires, les services de renseignement (au sens large) qui assurent la prospective du Syst\u00e8me admettent qu&rsquo;ils n&rsquo;ont rien vu venir et que, fort probablement, ils ne verront rien venir des \u00e9v\u00e9nements de cette sorte qui vont suivre. Nous sommes pass\u00e9s avec ce ph\u00e9nom\u00e8ne dans une \u00e9poque o&ugrave; le flot d&rsquo;informations, &ndash; essentiellement avec le surgissement de ce qu&rsquo;on nomme \u00ab\u00a0les r\u00e9seaux sociaux\u00a0\u00bb type Internet, &ndash; a atteint une telle puissance quantitative qu&rsquo;il rend <strong>indescriptible<\/strong> toute prospective.<\/p>\n<\/p>\n<p><p>Nous sommes pass\u00e9s du dilemme (\u00ab\u00a0quelle information choisir ?\u00a0\u00bb) \u00e0 l&rsquo;impasse (\u00ab\u00a0il y a trop d&rsquo;informations pour avoir &lsquo;le choix de choisir'\u00a0\u00bb). La dynamique quantitative de la communication a \u00e9touff\u00e9 toute perception \u00ab\u00a0qualitative\u00a0\u00bb dans le chef du Syst\u00e8me, retournant contre lui sa principale arme de destruction des structures traditionnelles (identification spatiale des structures pour les attaquer avec une puissance d\u00e9finissable du point de vue quantitatif). Il en r\u00e9sulte que l&rsquo;\u00e9v\u00e9nement d\u00e9fini par l&rsquo;information devient insaisissable puisqu&rsquo;il est indescriptible ; importent d\u00e9sormais les conditions g\u00e9n\u00e9rales de la dynamique de communication qui permettra aux \u00e9v\u00e9nements de se former.<\/p>\n<\/p>\n<p><p>&laquo;<em>Nous ne sommes plus devant le choix entre le qualitatif et le quantitatif (par exemple, identifier l&rsquo;information de valeur ou l&rsquo;information significative, dans la masse quantitative des informations), qui caract\u00e9risait la phase pr\u00e9c\u00e9dente, &ndash; o&ugrave;, d&rsquo;ailleurs, tous ces services de renseignement organis\u00e9s autour des conceptions quantitatives de la modernit\u00e9 n&rsquo;eurent gu\u00e8re de succ\u00e8s; nous sommes devant la disparition compl\u00e8te du qualitatif dans l&rsquo;oc\u00e9an du quantitatif&#8230;<\/em> [&hellip;] <em>C&rsquo;est le constat le plus remarquable de ce processus de crises en s\u00e9rie, de ce que nous nommons \u00ab\u00a0encha&icirc;nement crisique\u00a0\u00bb ou \u00ab\u00a0cha&icirc;ne crisique\u00a0\u00bb. Il n&rsquo;y a pas organisation des \u00e9v\u00e9nements, mais des conditions menant \u00e0 ces \u00e9v\u00e9nements&#8230;<\/em>&raquo;<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Importance de la crise <em>WikiLeaks<\/em>\/<em>Cablegate<\/em><\/h2>\n<\/p>\n<p><p>Le ph\u00e9nom\u00e8ne commenc\u00e9 le 19 d\u00e9cembre 2010 en Tunisie a encha&icirc;n\u00e9 chronologiquement (sans lui \u00eatre li\u00e9 <em>stricto sensu<\/em> comme dans la cha&icirc;ne crisique) sur la crise <em>WikiLeaks<\/em>\/<em>Cablegate<\/em>. Cette crise <em>WikiLeaks<\/em>\/<em>Cablegate<\/em> a achev\u00e9 la compl\u00e8te relativisation de l&rsquo;information, ouvrant le champ au contexte de communication permettant le d\u00e9veloppement de la cha&icirc;ne crisique.<\/p>\n<\/p>\n<p><p>Cette phase capitale correspond \u00e0 une dynamique psychologique enfant\u00e9e par la puissance dynamique du syst\u00e8me de la communication. Dans ce cas, la puissance dynamique du syst\u00e8me de la communication est la source m\u00eame de l&rsquo;\u00e9v\u00e9nement, il le cr\u00e9e litt\u00e9ralement. C&rsquo;est \u00e0 nouveau une occurrence o&ugrave; le syst\u00e8me de la communication, n\u00e9e du Syst\u00e8me g\u00e9n\u00e9ral, se r\u00e9v\u00e8le un Janus agissant contre son g\u00e9niteur.<\/p>\n<\/p>\n<p><p>&laquo;<em>C&rsquo;est \u00e0 ce point que cette dynamique n\u00e9 d&rsquo;un ph\u00e9nom\u00e8ne quantitatif colossal commen\u00e7a \u00e0 se transmuter en des \u00e9v\u00e9nements qui s&rsquo;av\u00e9r\u00e8rent, par comparaison, hautement qualitatifs. Elle exer\u00e7a une influence d\u00e9cisive sur les psychologies en organisant un courant psychologique collectif, au travers des innombrables participants individuels du courant Internet. Ce courant collectif produisit en effet l&rsquo;effet vertueux de rassembler les psychologies isol\u00e9es et d\u00e9sesp\u00e9r\u00e9es, et paralys\u00e9es dans le fatalisme des situations atomis\u00e9es, et de faire na&icirc;tre chez elles une perception collective de leurs propres caract\u00e8res. C&rsquo;est ainsi que naissent des ph\u00e9nom\u00e8nes tels que la psychologie de \u00ab\u00a0la r\u00e9volte possible\u00a0\u00bb, qui impliquent que la psychologie acquiert soudain la conviction, qu&rsquo;elle transmet au comportement, tout cela sans conscience raisonn\u00e9e de la chose, qu&rsquo;une telle aventure (la r\u00e9volte) est d\u00e9sormais dans le champ du possible. Quoi qu&rsquo;il en soit par ailleurs, nous voulons dire objectivement, il reste que cette cr\u00e9ation psychologique, puis cette cr\u00e9ation de l&rsquo;\u00e9v\u00e9nement lui-m\u00eame, ont par rapport \u00e0 la situation qu&rsquo;ils mettent en cause une v\u00e9ritable vertu. Si elles sont n\u00e9es d&rsquo;un ph\u00e9nom\u00e8ne quantitatif, elles acqui\u00e8rent une vertu qualitative en se formant contre des situations n\u00e9es du Syst\u00e8me quantitatif.<\/em>&raquo;<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">La dynamique du flot d&rsquo;informations<\/h2>\n<\/p>\n<p><p>Il y a donc l\u00e0 un ph\u00e9nom\u00e8ne sp\u00e9cifique qui tient \u00e0 la puissance du flot de l&rsquo;information, conduite par la puissance du syst\u00e8me de la communication. La capacit\u00e9 de ce ph\u00e9nom\u00e8ne de cr\u00e9ation de l&rsquo;\u00e9v\u00e9nement &ndash; celui qui est n\u00e9 le 19 d\u00e9cembre 2010 et qui prend la forme de ce que nous d\u00e9signons comme une \u00ab\u00a0cha&icirc;ne crisique\u00a0\u00bb essentielle par son rythme, son aspect temporel &ndash; tient beaucoup plus \u00e0 la dynamique du flot qui le g\u00e9n\u00e8re. Le contenu de l&rsquo;\u00e9v\u00e9nement (\u00ab\u00a0r\u00e9volution\u00a0\u00bb, \u00ab\u00a0printemps arabe\u00a0\u00bb) n&rsquo;a qu&rsquo;une importance anecdotique et dans tous les cas conjoncturelle. L&rsquo;essentiel est la dynamique structurelle qui est ainsi cr\u00e9\u00e9e, qui implique un mouvement continuel mettant continuellement en cause les structures existantes, qui sont les structures du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>&laquo;<em>A c\u00f4t\u00e9 de la psychologie cr\u00e9atrice d&rsquo;\u00e9v\u00e9nements par le seul fait de sa tension et de la mutation des psychologies individuelles en une psychologie collective, il y a le r\u00f4le de l&rsquo;information qui m\u00e9rite notre attention. Dans le cas consid\u00e9r\u00e9, tout s&rsquo;est pass\u00e9 comme si l&rsquo;information comptait moins par son contenu, qui restait informe, contradictoire et d\u00e9sordonn\u00e9 (voir les plaintes des chefs du renseignement US), que par la dynamique que sa disposition, sa vitesse, sa vari\u00e9t\u00e9, les canaux qu&rsquo;elle empruntait ont cr\u00e9\u00e9e&hellip;<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>Ainsi le flot d&rsquo;information devient-il une dynamique autonome, structur\u00e9e, et non plus cet ensemble disparate de donn\u00e9es et de facteurs anarchiques, indiff\u00e9rents, contradictoires, etc. Il acquiert une unicit\u00e9 cr\u00e9atrice, presque une identit\u00e9 propre, qui fait na&icirc;tre la conceptualisation des actes en devenir, \u00e0 qui il manquait l&rsquo;impulsion vitale pour exister. La puissance de ce courant est telle qu&rsquo;il devient le ma&icirc;tre des effets qu&rsquo;il induit, \u00e9cartant la n\u00e9cessit\u00e9 de l&rsquo;organisation, des hi\u00e9rarchies d&rsquo;habitude n\u00e9cessaires aux \u00e9v\u00e9nements. Ainsi aboutit-on \u00e0 des mouvements, bient\u00f4t nomm\u00e9s \u00ab\u00a0r\u00e9volutions\u00a0\u00bb, sans t\u00eate ni unit\u00e9 de but, mais irr\u00e9sistibles dans leur action.<\/em>&raquo;<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Formation du \u00ab\u00a0temps crisique\u00a0\u00bb<\/h2>\n<\/p>\n<p><p>Si l&rsquo;on consid\u00e8re, comme c&rsquo;est notre cas, que nous nous trouvons dans des temps fondamentalement et structurellement nouveaux, o&ugrave; les dynamiques comptent plus que le contenu des effets qu&rsquo;elles g\u00e9n\u00e8rent, o&ugrave; le facteur temporel prend le pas sur le facteur spatial, il importe de cr\u00e9er une nouvelle \u00ab\u00a0nomenclature\u00a0\u00bb pour mieux identifier et comprendre les ph\u00e9nom\u00e8nes impliqu\u00e9s.<\/p>\n<\/p>\n<p><p>Ces concepts nouveaux, nous les nommons \u00ab\u00a0encha&icirc;nement crisique\u00a0\u00bb, pour d\u00e9signer la dynamique que nous identifions, et \u00ab\u00a0cha&icirc;ne crisique\u00a0\u00bb, pour d\u00e9signer l&#8217;empilement acc\u00e9l\u00e9r\u00e9 de crises li\u00e9es entre elles, effectivement comme les maillons d&rsquo;une cha&icirc;ne. C&rsquo;est une diff\u00e9rence fondamentale du ph\u00e9nom\u00e8ne de \u00ab\u00a0structure crisique\u00a0\u00bb, que nous utilisions auparavant, qui d\u00e9signait des crises sans liens directs entre elles, qu&rsquo;on distinguait d&rsquo;un point de vue spatial (quelle crise, o&ugrave;, pourquoi dans telle situation spatiale, etc.). Ce nouvel ensemble cr\u00e9e un caract\u00e8re temporel nouveau : le \u00ab\u00a0temps crisique\u00a0\u00bb, ou un temps historique dont la substance <strong>exclusive<\/strong> est la crise.<\/p>\n<\/p>\n<p><p>&laquo;<em>Ce qui \u00e9tait en germe dans la structure crisique initiale devient une \u00e9vidence structurelle, avec la cha&icirc;ne crisique qui passe ainsi du stade d&rsquo;accident exceptionnel<\/em> [&hellip;] <em>au stade d&rsquo;un aspect dynamique essentiel nouveau du m\u00eame ph\u00e9nom\u00e8ne g\u00e9n\u00e9ral, ph\u00e9nom\u00e8ne \u00e9videmment structurel et fondamental. Les relations internationales, la vie m\u00eame du monde devient fondamentalement crisique, elle ne peut plus s&rsquo;exprimer que par le ph\u00e9nom\u00e8ne de la crise, d\u00e9sormais extraordinairement diversifi\u00e9 et si puissant qu&rsquo;il ne laisse plus la place \u00e0 aucun autre ph\u00e9nom\u00e8ne. Notamment, le ph\u00e9nom\u00e8ne de l&rsquo;apaisement d&rsquo;une crise, de la r\u00e9solution d&rsquo;une crise tend \u00e0 devenir impossible: tout n&rsquo;est plus d\u00e9sormais que crise.<\/em> [&hellip;]<\/p>\n<\/p>\n<p><p>&raquo;<em>Ce foisonnement de crises, qui dans la structure crisique initiale, qui dans la cha&icirc;ne crisique nouvelle venue, qui dans la structure crisique ainsi renouvel\u00e9e et dynamis\u00e9e (ph\u00e9nom\u00e8ne de l&rsquo;extension), tend \u00e0 se rassembler, \u00e0 s&rsquo;unifier, \u00e0 se structurer d&rsquo;une fa\u00e7on fondamentale dans le Grand Un, ou la Grande Une pour dire plus juste: la grande crise g\u00e9n\u00e9rale du Syst\u00e8me. C&rsquo;est la ph\u00e9nom\u00e8ne de la contraction qui, loin d&rsquo;\u00eatre une r\u00e9duction, constitue une synth\u00e8se formidable pour caract\u00e9riser le temps historique que nous vivons.<\/em>&raquo;<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Contraction du temps, acc\u00e9l\u00e9ration de l&rsquo;Histoire<\/h2>\n<\/p>\n<p><p>Le temps crisique est non seulement un temps qui se caract\u00e9rise structurellement par le composant exclusif de la crise, c&rsquo;est aussi un temps dont la dynamique m\u00eame implique l&rsquo;acc\u00e9l\u00e9ration, c&rsquo;est-\u00e0-dire la contraction qui est un facteur qualitatif d&rsquo;enrichissement. Par voie \u00e9vidente de cons\u00e9quence, l&rsquo;Histoire elle-m\u00eame acc\u00e9l\u00e8re, devient plus dense, gagne \u00e9galement en enrichissement.<\/p>\n<\/p>\n<p><p>Ce ph\u00e9nom\u00e8ne se r\u00e9percute sur les \u00e9v\u00e9nements eux-m\u00eames. Leur signification s&rsquo;enrichit, leur substance se pare d&rsquo;une essence qui donne un sens \u00e0 leur existence m\u00eame, hors du sujet qu&rsquo;ils concernent. De quel sens s&rsquo;agit-il ? On le trouve dans le rapport analogique de ces \u00e9v\u00e9nements avec la crise centrale du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>&laquo;<em>L&rsquo;Histoire qui acc\u00e9l\u00e8re, qui gagne en signification fondamentale, qui gagne en puissance cr\u00e9atrice, constitue aussi incontestablement un facteur qualitatif. Ainsi le temps crisique se caract\u00e9rise-t-il lui-m\u00eame par une plus grande richesse, une signification plus haute; il gagne \u00e0 son tour dans le domaine du qualitatif. Il influe alors lui-m\u00eame sur les \u00e9v\u00e9nements dont il est le propagateur, et les transforme en leur donnant une dimension qualitative nouvelle.<\/em> [&hellip;]<\/p>\n<\/p>\n<p><p>&raquo;<em>Ces \u00e9v\u00e9nements d&rsquo;une qualit\u00e9 \u00e9lev\u00e9e, de cette qualit\u00e9 confirm\u00e9e par le cadre du temps crisique et de l&rsquo;acc\u00e9l\u00e9ration de l&rsquo;Histoire o&ugrave; on les situe, ne peuvent affirmer cette qualit\u00e9 que dans une fonction essentielle, qui ne peut \u00eatre que celle de la lutte contre le Syst\u00e8me.<\/em> [&hellip;] <em>Ainsi observe-t-on que les circonstances sp\u00e9cifiques (les \u00e9v\u00e9nements) autant que leur cadre m\u00e9tahistorique et cosmique convergent-ils vers la situation de lutte contre le Syst\u00e8me, et cela constitue effectivement un acte fondamental de renversement, de transmutation des valeurs. Cette lutte s&rsquo;oriente vers la mise en cause fondamentale des facteurs quantitatifs, vers une rupture au profit d&rsquo;un passage vers l&rsquo;aspect qualitatif.<\/em>&raquo;<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Une reproduction de la crise centrale du Syst\u00e8me<\/h2>\n<\/p>\n<p><p>Se pose alors la question de l&rsquo;interpr\u00e9tation et de l&rsquo;identification de ces ph\u00e9nom\u00e8nes dans l&rsquo;\u00e9volution politique que nous observons. Leur caract\u00e8re essentiel \u00e0 cet \u00e9gard est que la rapidit\u00e9 m\u00eame de ces crises, leur importance situ\u00e9e dans le domaine temporel plus que dans le domaine spatial, conduisent \u00e0 une int\u00e9gration de tous les domaines de la situation politique et psychologique au sens le plus large.<\/p>\n<\/p>\n<p><p>Ainsi, plut\u00f4t que nous arr\u00eater \u00e0 leur localisation, \u00e0 leur signification politique conjoncturelle (\u00ab\u00a0r\u00e9volution\u00a0\u00bb, \u00ab\u00a0printemps arabe\u00a0\u00bb), il faut aller \u00e0 leur signification dynamique par rapport \u00e0 la situation du Syst\u00e8me. La signification politique conjoncturelle n&rsquo;est qu&rsquo;un biais pour conduire, par la dynamique temporelle, \u00e0 une int\u00e9gration de tous les domaines de la situation. Par le fait de cette int\u00e9gration totalitaire de tous les domaines de la situation, ces crises constitu\u00e9es en cha&icirc;ne crisique deviennent une reproduction \u00e0 mesure de la crise centrale du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>&laquo;<em>Faire de la cha&icirc;ne crisique actuelle une \u00ab\u00a0r\u00e9volution arabe\u00a0\u00bb, c&rsquo;est se concentrer sur l&rsquo;aspect le plus accessoire du ph\u00e9nom\u00e8ne. Si ce ph\u00e9nom\u00e8ne a pris court dans le monde arabe, c&rsquo;est parce que le temps arabe, avec son importance strat\u00e9gique, avec sa formidable contradiction entre des soci\u00e9t\u00e9s opprim\u00e9es et culturellement confront\u00e9es \u00e0 un syst\u00e8me totalement d\u00e9structurant<\/em> [&hellip;] <em>\u00e9tait en complet d\u00e9s\u00e9quilibre d\u00e9structur\u00e9&#8230; C&rsquo;est donc lui qui a inaugur\u00e9 le temps crisique.<\/em> [&hellip;]<\/p>\n<\/p>\n<p><p>&laquo;<em>L&rsquo;important est qu&rsquo;elle<\/em> [la crise] <strong><em>est<\/em><\/strong><em>, et qu&rsquo;elle est d&rsquo;une fa\u00e7on dynamique; et, par cons\u00e9quent, l&rsquo;effet dynamique qu&rsquo;elle exerce sur le reste. En d&rsquo;autres termes, et pour employer des concepts qui nous sont familiers, l&rsquo;important de cette sorte de crise est son effet dynamique de d\u00e9structuration, \u00e9videmment contre des structures du Syst\u00e8me.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>La seconde cons\u00e9quence est que cette dynamique, qui est l&rsquo;essence de la crise encore plus que sa substance, est une formidable int\u00e9gratrice. Cette pression, cette contraction du temps, entra&icirc;nent que la crise, qu&rsquo;elle d\u00e9marre \u00e0 partir de telle ou telle chose, dans tel ou tel domaine, devient aussit\u00f4t g\u00e9n\u00e9rale et embrasse tous les domaines de la vie sociale, politique et culturelle, et elle embrase toutes les psychologies.<\/em><\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">Une psychologie chang\u00e9e : pas de \u00ab\u00a0retour en arri\u00e8re\u00a0\u00bb<\/h2>\n<\/p>\n<p><p>La cons\u00e9quence de ces diff\u00e9rents facteurs est que la cha&icirc;ne crisique, au lieu d&rsquo;\u00eatre un \u00e9v\u00e9nement spatial limit\u00e9 \u00e0 des situations spatiales elles-m\u00eames limit\u00e9es, devient un \u00e9v\u00e9nement temporel dont la dynamique est g\u00e9n\u00e9rale et fondamentalement antiSyst\u00e8me. Elle devient destructrice des structures du Syst\u00e8me, elle devient d\u00e9structurante de l&rsquo;espace du Syst\u00e8me, dont on sait qu&rsquo;il est lui-m\u00eame constitu\u00e9 en une structure d\u00e9structurante pr\u00e9datrice.<\/p>\n<\/p>\n<p><p>Cette dynamique g\u00e9n\u00e8re un caract\u00e8re d\u00e9finitif, une \u00e9volution \u00ab\u00a0sans retour\u00a0\u00bb parce que la prise de conscience psychologique (pas n\u00e9cessairement consciente) du ph\u00e9nom\u00e8ne change les psychologies et interdit effectivement un retour en arri\u00e8re. On ne peut accepter de revenir vers une situation de Syst\u00e8me lorsque la psychologie a mesur\u00e9 jusqu&rsquo;\u00e0 en \u00eatre chang\u00e9e combien ce Syst\u00e8me est la \u00ab\u00a0<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_source_de_tous_les_maux_ddecrisis_10_09_2010.html\">source de tous les maux<\/a>\u00ab\u00a0.<\/p>\n<\/p>\n<p><p>&laquo;<em>A c\u00f4t\u00e9 de sa puissance dynamique et de la rapidit\u00e9 de son rythme (ce qui renvoie au facteur temps), la cha&icirc;ne crisique repr\u00e9sente plut\u00f4t une occurrence informe quant \u00e0 ses effets politiques et sociaux concr\u00e8tement observ\u00e9s, dans les diff\u00e9rents pays confront\u00e9s \u00e0 des situations et \u00e0 des \u00e9volutions diff\u00e9rentes (ce qui renvoie au facteur espace)&hellip;<\/em> [&hellip;] <em>Par contre, tous les t\u00e9moignages, toutes les enqu\u00eates faites sur place, tendent \u00e0 montrer une conviction d&rsquo;une r\u00e9elle force quant \u00e0 l&rsquo;esprit de la chose, selon l&rsquo;id\u00e9e qu&rsquo;aucun \u00ab\u00a0retour en arri\u00e8re\u00a0\u00bb n&rsquo;est possible.<\/em>&raquo;<\/p>\n<\/p>\n<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955; font-size:1.65em; font-variant:small-caps\">L&rsquo;approche de la rupture cyclique<\/h2>\n<\/p>\n<p><p>La cha&icirc;ne crisique doit nous faire prendre conscience que tout se passe comme si nous approchions de la rupture finale.<\/p>\n<\/p>\n<p><p>Il est probable que cette dynamique temporelle de la cha&icirc;ne crisique \u00e9voluera, en accomplissant son &oelig;uvre antiSyst\u00e8me (destruction de la dimension spatiale du Syst\u00e8me), vers une extinction \u00e0 mesure d&rsquo;elle-m\u00eame, pour d\u00e9boucher, comme si elle en accouchait, sur un nouvel espace, pour s&rsquo;ouvrir \u00e0 un nouvel espace. La prospective redeviendra possible quand le temps crisique aura eu raison du Syst\u00e8me, et le nouvel espace, la nouvelle situation constitueront la r\u00e9sultante d&rsquo;une rupture cyclique avec l&rsquo;effondrement du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>&laquo;<em>Dans cette sorte de situation, on comprend aussit\u00f4t qu&rsquo;on ne peut plus juger selon les crit\u00e8res habituels, anciens et d\u00e9pass\u00e9s; selon ces crit\u00e8res fond\u00e9s sur la g\u00e9opolitique, sur les nations et les groupes de nations, et donc sur l&rsquo;espace; la confusion des positions, des situations, des int\u00e9r\u00eats, des perceptions, interdit cela, en nous montrant combien la logique g\u00e9opolitique n&rsquo;a plus cours. Ainsi l&rsquo;affrontement se porte-t-il sur l&rsquo;essentiel, selon les conceptions qui devraient d\u00e9sormais dominer les situations de l&rsquo;\u00e9poque nouvelle de la crise terminale du Syst\u00e8me; il s&rsquo;agit de l&rsquo;affrontement entre forces structurantes et forces d\u00e9structurantes, avec la force de cet affrontement transf\u00e9r\u00e9e au niveau du rythme et de la dynamique des crises, &ndash; le temps crisique, ou le facteur temporel. Cette situation transcrite en termes m\u00e9tahistoriques, il ne s&rsquo;agit de rien moins que l&rsquo;agonie de ce Syst\u00e8me de la mati\u00e8re d\u00e9cha&icirc;n\u00e9e qui a domin\u00e9 le monde pendant les deux derniers si\u00e8cles, au travers des p\u00e9rip\u00e9ties des h\u00e9g\u00e9monies et des affrontements successifs.<\/em>&raquo;<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notes sur la cha&icirc;ne crisique (dde.crisis) Le num\u00e9ro dat\u00e9 du 10 mars 2011 de dde.crisis consacre sa rubrique centrale (dedefensa) au ph\u00e9nom\u00e8ne d&rsquo;encha&icirc;nement de crises, ou \u00ab\u00a0cha&icirc;ne crisique\u00a0\u00bb, qui s&rsquo;est manifest\u00e9 dans le monde arabo-musulman depuis le 19 d\u00e9cembre 2010. Il s&rsquo;agit de cette s\u00e9rie de crises de formes diff\u00e9rentes, qui s&rsquo;est encha&icirc;n\u00e9e depuis d\u00e9cembre,&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[4646,6911,10462,3015,8294,10987,2631,9550,3100,2622,3178,2789,3014,6750,10734,9887,10016],"class_list":["post-72894","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-antisysteme","tag-arabe","tag-cablegate","tag-communication","tag-crisique","tag-cyclique","tag-de","tag-egypte","tag-information","tag-la","tag-printemps","tag-rupture","tag-systeme","tag-temps","tag-tunisie","tag-wikileaks","tag-wisconsin"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=72894"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/72894\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=72894"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=72894"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=72894"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}