{"id":73023,"date":"2011-05-20T08:24:19","date_gmt":"2011-05-20T08:24:19","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/05\/20\/de-la-seduisante-et-infinie-diversite-des-complots-anti-dsk\/"},"modified":"2011-05-20T08:24:19","modified_gmt":"2011-05-20T08:24:19","slug":"de-la-seduisante-et-infinie-diversite-des-complots-anti-dsk","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/05\/20\/de-la-seduisante-et-infinie-diversite-des-complots-anti-dsk\/","title":{"rendered":"De la s\u00e9duisante et infinie diversit\u00e9 des complots anti-DSK"},"content":{"rendered":"<p><h4>De la s\u00e9duisante et infinie diversit\u00e9 des complots anti-DSK<\/h4>\n<p>Il n&rsquo;y a pas la th\u00e8se du complot dans le cas de l&rsquo;arrestation de Dominique Strauss-Kahn, il y a de nombreuses th\u00e8ses de complots eux-m\u00eames divers et vari\u00e9s. En voici une, assez r\u00e9cente et assez originale, puisqu&rsquo;elle implique notamment les Russes et Poutine. Il s&rsquo;agit de quelques lignes dans <em>Le Monde<\/em> du <a href=\"http:\/\/bigbrowser.blog.lemonde.fr\/2011\/05\/19\/complot-dsk-se-serait-plaint-dune-alliance-franco-russe-pour-le-virer-du-fmi\/#xtor=EPR-32280229-%5BNL_Titresdujour%5D-20110519-%5Bzoneb%5D\" class=\"gen\">19 mai 2011<\/a>, \u00e0 partir d&rsquo;une citation du <em>Nouvel Observateur<\/em>, \u00e0 partir d&rsquo;une d\u00e9claration du d\u00e9put\u00e9 PS Bartolone sur BFM-TV. Ainsi sommes-nous, pour notre compte, le quatri\u00e8me relais de cette d\u00e9claration sur la version franco-russe du complot anti-DSK.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Le d\u00e9put\u00e9 PS Claude Bartolone rapporte ainsi \u00e0 BFM-TV, cit\u00e9e par Le Nouvel Obs, que l&rsquo;ancien patron du FMI lui aurait confi\u00e9, le 29 avril : Attention, il faut \u00eatre tr\u00e8s vigilant, on peut \u00eatre sur \u00e9coute t\u00e9l\u00e9phonique, je sens bien qu&rsquo;actuellement les Russes et notamment Poutine<\/em> [premier ministre russe]<em>, sont les alli\u00e9s de la France pour essayer de me virer du FMI avant que je ne puisse \u00eatre en situation d&rsquo;annoncer<\/em> [ma candidature]<em>.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Je pense que \u00e7a serait une faute pour tous d&rsquo;arriver \u00e0 ce que je sois vir\u00e9 et pas \u00eatre candidat en sortant proprement du FMI, aurait ajout\u00e9 Dominique Strauss-Kahn, toujours selon le pr\u00e9sident du conseil g\u00e9n\u00e9ral de Seine-Saint-Denis, qui l&rsquo;a senti tr\u00e8s attentif \u00e0 tout. Et Claude Bartolone de conclure qu&rsquo;il a \u00e9t\u00e9 compl\u00e8tement d\u00e9contenanc\u00e9 en apprenant dimanche matin l&rsquo;arrestation de DSK.<\/em>\u00bb<\/p>\n<\/p>\n<p>\n<p class=\"signature\"><em>dedefensa.org<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>De la s\u00e9duisante et infinie diversit\u00e9 des complots anti-DSK Il n&rsquo;y a pas la th\u00e8se du complot dans le cas de l&rsquo;arrestation de Dominique Strauss-Kahn, il y a de nombreuses th\u00e8ses de complots eux-m\u00eames divers et vari\u00e9s. En voici une, assez r\u00e9cente et assez originale, puisqu&rsquo;elle implique notamment les Russes et Poutine. Il s&rsquo;agit de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[11128,2890],"class_list":["post-73023","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-bartolone","tag-russes"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73023"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73023\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}