{"id":73024,"date":"2011-05-20T08:53:42","date_gmt":"2011-05-20T08:53:42","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/05\/20\/liquidation-de-geronimo-a-dsk\/"},"modified":"2011-05-20T08:53:42","modified_gmt":"2011-05-20T08:53:42","slug":"liquidation-de-geronimo-a-dsk","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/05\/20\/liquidation-de-geronimo-a-dsk\/","title":{"rendered":"\u201cLiquidation\u201d, \u2013 de <em>Geronimo<\/em> \u00e0 DSK"},"content":{"rendered":"<p><h2 class=\"common-article\">Liquidation,  de <em>Geronimo<\/em> \u00e0 DSK<\/h2>\n<\/p>\n<p><p>\t19 mai 2011  Il est vrai que nous avons \u00e9t\u00e9 frapp\u00e9s, une fois de plus, par la rapidit\u00e9 des \u00e9v\u00e9nements, la liquidation de ben Laden (op\u00e9ration <em>Geronimo<\/em>, les 1er-2 mai) encha\u00eenant tr\u00e8s rapidement sur la liquidation de DSK. Nous ne croyons aucunement que le hasard puisse se manifester, ni le ph\u00e9nom\u00e8ne de la co\u00efncidence, dans le chef des grands courants m\u00e9tahistoriques qui sont confront\u00e9s par leur propre dynamique \u00e0 la folle pouss\u00e9e du Syst\u00e8me, et qui alimentent, de l&rsquo;ext\u00e9rieur, la bataille contre le Syst\u00e8me, essentiellement sinon exclusivement en favorisant son processus d&rsquo;autodestruction. Ainsi avons-nous recherch\u00e9 une proximit\u00e9 de similitude entre les deux \u00e9v\u00e9nements.<\/p>\n<\/p>\n<p><p>\tNous employons \u00e0 dessein ce terme de liquidation pour les deux cas (ben Laden et DSK), non pour d\u00e9signer la possibilit\u00e9 d&rsquo;une volont\u00e9 construite de liquider l&rsquo;un ou l&rsquo;autre personnage, quoi qu&rsquo;il en soit par ailleurs et selon les circonstances, mais pour offrir une correspondance entre deux \u00e9v\u00e9nements qui paraissent, dans leurs circonstances justement, tr\u00e8s diff\u00e9rents (liquidation physique de ben Laden, class\u00e9 comme ennemi du Syst\u00e8me, circonstances exceptionnelles menant \u00e0 l&#8217;emprisonnement de DSK, class\u00e9 comme soutien du Syst\u00e8me). Nous utilisons le terme liquidation pour d\u00e9signer un \u00e9v\u00e9nement structurel dont nous jugerons qu&rsquo;il apporte des effets consid\u00e9rables dans la situation du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tPar cons\u00e9quent, liquidation pour liquidation,  la premi\u00e8re physique et directe, la seconde professionnelle et syst\u00e9mique. Dans les deux cas, le terme, utilis\u00e9 avec des guillemets, indique sa sp\u00e9cificit\u00e9 telle que nous l&rsquo;entendons. Pour nous, il ne s&rsquo;agit en aucun cas d&rsquo;une liquidation physique, par les armes, comme celle de ben Laden, ni d&rsquo;une liquidation professionnelle et politique, voire provoqu\u00e9e pour ceux qui affectionnent les complots (ils sont 57% en France, para\u00eet-il), comme dans le cas de DSK. Il s&rsquo;agit d&rsquo;une liquidation comprise d&rsquo;un point de vue essentiellement symbolique, avec les effets d&rsquo;un \u00e9v\u00e9nement symbolique sur la psychologie, par rapport \u00e0 la place de la chose (ben Laden, DSK) dans le r\u00e9cit g\u00e9n\u00e9ral (la <em>narrative<\/em>) de la Grande crise terminale que nous vivons.<\/p>\n<\/p>\n<p><p>\tNous pr\u00e9cisons aussit\u00f4t ce que nous entendons et ce qui nous importe dans ces \u00e9v\u00e9nements,  et ce qui ne nous importe pas.<\/p>\n<\/p>\n<p><p>\t Pour nous arr\u00eater au fait le plus spectaculaire aujourd&rsquo;hui, nous dirions que les circonstances de la liquidation de DSK n&rsquo;ont pour nous aucun int\u00e9r\u00eat fondamental, par le principe que le fait lui-m\u00eame, fortement symbolique, est infiniment plus important que les circonstances, qui ne sont justement que des accidents de circonstances. La question des complots est particuli\u00e8rement r\u00e9v\u00e9latrice : il y en a dans tous les sens, de toutes les fa\u00e7ons, avec un nombre de coupables pr\u00e9sum\u00e9s assez consid\u00e9rables, pour un nombre de raisons tr\u00e8s diverses et souvent contradictoires. Cette abondance de biens allant dans des sens divers indique plus la situation chaotique de la raison devant l&rsquo;\u00e9v\u00e9nement qu&rsquo;une appr\u00e9ciation convaincante et de r\u00e9elle importance,  m\u00eame s&rsquo;il y a eu <strong>effectivement<\/strong> complot. Pour reprendre la th\u00e8se implicite de Joseph de Maistre sur la R\u00e9volution fran\u00e7aise, lorsque Maistre constate que \u00ab[l]<em>es sc\u00e9l\u00e9rats m\u00eames qui paraissent conduire la r\u00e9volution, n&rsquo;y entrent que comme de simples instruments; et d\u00e8s qu&rsquo;ils ont la pr\u00e9tention de la dominer, ils tombent ignoblement<\/em>\u00bb,  manifestement, Maistre se fiche du tiers comme du quart de savoir quel complot a eu raison des h\u00e9bertistes, de Danton, etc., parce qu&rsquo;il n&rsquo;y a que le fait de leur chute qui importe. Si, demain, on apprend que DSK a \u00e9t\u00e9 victime d&rsquo;un complot mont\u00e9 par les SR am\u00e9ricanistes ou du machiav\u00e9lisme de <a href=\"http:\/\/www.dedefensa.org\/article-de_la_seduisante_et_infinie_diversite_des_complots_anti-dsk_20_05_2011.html\" class=\"gen\">Poutine<\/a>, qu&rsquo;est-ce que cela nous apporterait par rapport au fait fondamental de la liquidation et de la chute ? C&rsquo;est l&rsquo;accessoire par rapport \u00e0 l&rsquo;essentiel, m\u00eame si les constructeurs des hypoth\u00e8ses de tel ou tel complot sont tr\u00e8s satisfaits, de fort bonne foi, et peut-\u00eatre d\u00e9fricheurs d&rsquo;une v\u00e9rit\u00e9 ou l&rsquo;autre. Par cons\u00e9quent, les circonstances ne nous int\u00e9ressent pas.<\/p>\n<\/p>\n<p><p>\t Nous nous sommes beaucoup \u00e9tendus sur le cas DSK, parce que c&rsquo;est le fait du jour, sans aucun doute, et qu&rsquo;il est massivement pr\u00e9sent dans le syst\u00e8me de la communication. Le m\u00eame raisonnement est valable pour nous pour les circonstances de la liquidation de ben Laden, <strong>y compris<\/strong> l&rsquo;hypoth\u00e8se largement d\u00e9velopp\u00e9e d&rsquo;avancer qu&rsquo;il s&rsquo;agit d&rsquo;un faux ben Laden parce que le vrai serait mort depuis 2002. Le fait qui nous int\u00e9resse est que la mort officielle, donc la mort <strong>symbolique<\/strong> de ben Laden, paradoxalement salu\u00e9e comme une victoire fondamentale pour les USA, est en r\u00e9alit\u00e9 un \u00e9v\u00e9nement terriblement d\u00e9stabilisant pour la situation \u00e9tablie depuis 9\/11 dans la mesure o\u00f9 elle nous prive du personnage qui structurait toute la <em>narrative<\/em> du bloc am\u00e9ricaniste-occidentaliste. <\/p>\n<\/p>\n<p><p>\t Tout cela doit \u00eatre consid\u00e9r\u00e9 selon une analyse fondamentale, qui impose une appr\u00e9ciation \u00e0 mesure des deux \u00e9v\u00e9nements. Ces liquidations n&rsquo;ont aucun  int\u00e9r\u00eat du point de vue politique, parce que la politique n&rsquo;a plus d&rsquo;int\u00e9r\u00eat ni d&rsquo;existence r\u00e9elle, rel\u00e9gu\u00e9e qu&rsquo;elle est, aujourd&rsquo;hui, sur les marges du fondement des choses ; parce que <strong>plus personne<\/strong>,  nous insistons sur ce <strong>plus personne<\/strong> avec force et sommes pr\u00eats \u00e0 en discuter avec tous les arguments du monde, dans tous les domaines,  parce que <strong>plus personne<\/strong> ne dirige plus rien de fondamental dans les choses essentielles des \u00e9v\u00e9nements du monde, parce que l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-de_la_chaine_crisique_au_temps_crisique__24_02_2011.html\" class=\"gen\">eschatologisation<\/a> de ces \u00e9v\u00e9nements est partout \u00e9vidente, parce que les multiples interf\u00e9rences, concurrences, heurts, alliances, m\u00e9salliances et d\u00e9salliances des multitudes de pouvoirs au sein du Syst\u00e8me emp\u00eachent absolument l&rsquo;expression d&rsquo;un pouvoir g\u00e9n\u00e9ral capable d&rsquo;organiser une politique g\u00e9n\u00e9rale. Alors, ce qui compte essentiellement, c&rsquo;est la perception de l&rsquo;\u00e9v\u00e9nement et l&rsquo;effet sur la psychologie, et alors les deux liquidations qui nous attachent dans ce texte doivent \u00eatre appr\u00e9ci\u00e9es comme deux \u00e9v\u00e9nements symboliques d&rsquo;une consid\u00e9rable force psychologique.<\/p>\n<\/p>\n<p><p>\t Un autre point \u00e0 mettre en \u00e9vidence dans la poursuite du raisonnement est que ces deux liquidation sont <strong>d\u00e9structurantes pour le syst\u00e8me<\/strong>. C&rsquo;est pourquoi l&rsquo;effet psychologique des deux liquidations sont d&rsquo;abord d\u00e9stabilisantes par rapport aux situations \u00e9tablies qui sont contr\u00f4l\u00e9es par le Syst\u00e8me, sans aucune consid\u00e9ration de valeur et de vertu de ces situations ; m\u00eame si ces situations \u00e9taient mauvaises, ha\u00efssables parce que favorables au Syst\u00e8me, etc., notre perception est justement celle d&rsquo;une d\u00e9stabilisation, cela qui a pour premier effet le d\u00e9sarroi. C&rsquo;est pourquoi nous parlons sans le moindre doute de <a href=\"http:\/\/www.dedefensa.org\/article-dsk_et_le_desarroi_francais_19_05_2011.html\" class=\"gen\">d\u00e9sarroi<\/a>, comme c&rsquo;est le cas fran\u00e7ais \u00e9vident pour DSK. La m\u00eame sorte de d\u00e9sarroi, quoiqu&rsquo;exprim\u00e9 d&rsquo;une autre fa\u00e7on, est perceptible avec le cas ben Laden dont la liquidation met radicalement en cause la <em>narrative<\/em> de la guerre contre la Terreur, c&rsquo;est-\u00e0-dire la <em>narrative<\/em> existentielle de l&rsquo;\u00e9poque depuis 9\/11. On le voit avec le <a href=\"http:\/\/www.dedefensa.org\/article-le_pakistan_transforme_par_geronimo_19_05_2011.html\" class=\"gen\">remplacement<\/a> de l&rsquo;Afghanistan par le Pakistan dans les pr\u00e9occupations US, comme si la guerre en Afghanistan n&rsquo;existait plus gu\u00e8re et que l&rsquo;on se tournait vers la perspective d&rsquo;un conflit avec le Pakistan pour justement combler le vide conceptuel caus\u00e9 par la mort de ben Laden. Cela ne signifie pas qu&rsquo;on soit attrist\u00e9, catastroph\u00e9 par la nouvelle, ou le contraire, mais qu&rsquo;on se trouve soudain dans une situation d\u00e9stabilis\u00e9e par rapport \u00e0 ce qui existait ; cela ne signifie pas qu&rsquo;on prenne position pour ou contre le Syst\u00e8me, mais qu&rsquo;on ressent psychologiquement un bouleversement de la situation \u00e9tablie ; cela ne signifie pas que l&rsquo;attaque du Pakistan est pour demain (il faudrait pouvoir) ni m\u00eame que les USA vont rompre avec le Pakistan, mais bien que tout se passe comme si le monde sans ben Laden avait abouti \u00e0 l&rsquo;\u00e9limination du centre afghan de la crise et \u00e0 la recherche d&rsquo;un centre de substitution, par exemple au Pakistan, tentant par sa proximit\u00e9 et comme lieu de la liquidation de ben Laden Cette d\u00e9stabilisation implique un sentiment de fragilit\u00e9, non pas des gens qui expriment ou ressentent ce d\u00e9sarroi, mais bien un sentiment de fragilit\u00e9 de la situation ainsi d\u00e9stabilis\u00e9es (<em>dito<\/em>, du Syst\u00e8me, qui r\u00e9git cette situation). La multitude de th\u00e9ories de complot dans tous les sens dans le cas de DSK n&rsquo;est pas un signe imp\u00e9ratif qu&rsquo;il y a un complot,  ni le contraire d&rsquo;ailleurs, et l\u00e0 n&rsquo;est pas le propos,  mais un signe que la raison lutte d\u00e9sesp\u00e9r\u00e9ment pour \u00e9carter le d\u00e9sarroi en tentant de la rationaliser la liquidation,  oubliant, la raison, que le d\u00e9sarroi vient du fait lui-m\u00eame (la liquidation) et nullement des circonstances.<\/p>\n<h3>Le Syst\u00e8me et ses verrous<\/h3>\n<\/p>\n<p><p>\tLe Syst\u00e8me qui r\u00e9git le monde aujourd&rsquo;hui est \u00e0 la fois dans une situation de surpuissance extraordinaire, une situation de surpuissance que nous qualifierions d&rsquo;<strong>herm\u00e9tique<\/strong> dans le sens o\u00f9 cette situation est boucl\u00e9e et inexpugnable ; et, en m\u00eame temps, une situation de crise si profonde que nul n&rsquo;en voit ni le terme ni le fond, et qui est essentiellement aliment\u00e9e par le Syst\u00e8me lui-m\u00eame. C&rsquo;est la situation de puissance-impuissance que nous avons souvent constat\u00e9e, dans tous les domaines (r\u00e9cemment, le cas de <a href=\"http:\/\/www.dedefensa.org\/article-la_g4g_involontaire_du_fou_de_libye_destructurer_l_ouest_24_03_2011.html\" class=\"gen\">la Libye<\/a> ou du <a href=\"http:\/\/www.dedefensa.org\/article-pour_le_jsf_comme_pour_le_systeme_le_pire_est_toujours_le_plus_probable_14_05_2011.html\" class=\"gen\">JSF<\/a>), avec l&rsquo;hypoth\u00e8se, \u00e9galement exprim\u00e9e souvent sur ce site, d&rsquo;une dynamique d&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-_it_was_a_very_good_year__03_01_2011.html\" class=\"gen\">autodestruction<\/a>.<\/p>\n<\/p>\n<p><p>\tDans le cas de DSK, nous avons mis <a href=\"http:\/\/www.dedefensa.org\/article-l_homme_broye_et_le_systeme_fou_17_05_2011.html\" class=\"gen\">l&rsquo;accent<\/a> sur la perception par certains d&rsquo;une d\u00e9marche d&rsquo;autodestruction de DSK. Dernier cas en date, William Pfaff, dans un article du <a href=\"http:\/\/www.williampfaff.com\/article.php?storyid=519\" class=\"gen\">18 mai 2011<\/a>, choisit le titre de \u00ab<em>The Self-destruction of Dominique Strauss-Kahn<\/em>\u00bb, et commence son texte par ces mots : \u00ab<em>What can only seem the irresistible self-destruction of Dominique Strauss-Kahn<\/em>\u00bb Notre th\u00e8se est que cette autodestruction n&rsquo;est pas celle de DSK en tant qu&rsquo;individu, mais de DSK en tant que membre \u00e9minent du Syst\u00e8me (directeur du FMI, \u00e9ventuellement futur pr\u00e9sident de la r\u00e9publique fran\u00e7aise). Dans ce cas, nous disons que c&rsquo;est un acte d&rsquo;autodestruction du Syst\u00e8me s&rsquo;exprimant par le biais de DSK. La m\u00eame chose pourrait \u00eatre dite pour la liquidation de ben Laden ; ceux qui l&rsquo;ont d\u00e9cid\u00e9e et accomplie ont cru le faire selon une logique qu&rsquo;on pourrait consid\u00e9rer objectivement comme favorable au Syst\u00e8me, notamment parce qu&rsquo;elle montre la surpuissance du Syst\u00e8me (voir <a href=\"http:\/\/www.dedefensa.org\/article-le_pakistan_transforme_par_geronimo_19_05_2011.html\" class=\"gen\">les ricanements<\/a> de Gates et de Mullen \u00e0 ce propos) ; en r\u00e9alit\u00e9, comme nous l&rsquo;avons montr\u00e9, l&rsquo;op\u00e9ration d\u00e9truit un des facteurs importants de la stabilit\u00e9 structurelle du Syst\u00e8me, notamment appuy\u00e9e sur la <em>narrative<\/em> de la guerre contre la terreur.<\/p>\n<\/p>\n<p><p>\tL&rsquo;herm\u00e9tisme du Syst\u00e8me, mentionn\u00e9e plus haut, est un facteur essentiel de sa surpuissance. Elle a \u00e9t\u00e9 r\u00e9alis\u00e9e, comme c&rsquo;est normal, par un nombre ind\u00e9termin\u00e9e de verrous. Pour nous, ben Laden et DSK repr\u00e9sentaient des verrous de l&rsquo;herm\u00e9tisme du Syst\u00e8me, \u00e0 des titres divers sinon contraires selon leurs positions respectives, sans qu&rsquo;il soit n\u00e9cessaire qu&rsquo;eux-m\u00eames s&rsquo;en expliquent ni m\u00eame le r\u00e9alisent,  mais des verrous sans aucun doute. Les deux verrous ont saut\u00e9, et ils ont saut\u00e9 par l&rsquo;action du Syst\u00e8me. Dans le cas ben Laden, c&rsquo;est \u00e9vident ; dans le cas DSK, ce ne l&rsquo;est pas moins, \u00e0 cause des activit\u00e9s du Syst\u00e8me suscit\u00e9es par diverses caract\u00e9ristiques, jalousies, hypoth\u00e8ses de machinations, etc.,  un DSK menott\u00e9 apr\u00e8s les circonstances rocambolesques de son arrestation, la floraison des complots, le d\u00e9sarroi, la course \u00e0 la direction du FMI dans une situation d&rsquo;extr\u00eame tension financi\u00e8re au sein du Syst\u00e8me, etc. (On ajoutera, accessoirement, l&rsquo;\u00e9limination d&rsquo;un homme qui avait de fortes chances d&rsquo;\u00eatre \u00e9lu pr\u00e9sident en France, et dont on esp\u00e9rait qu&rsquo;il aurait introduit ainsi, d&rsquo;une fa\u00e7on ordonn\u00e9e et assez rassurante, les principes de la globalisation au cur de la structure du pouvoir fran\u00e7ais, qui reste r\u00e9tif \u00e0 cette orientation.)<\/p>\n<\/p>\n<p><p>\tLe r\u00e9sultat de la liquidation, le fait d&rsquo;avoir fait sauter ces deux verrous, sans m\u00eame r\u00e9aliser la chose ni qu&rsquo;il s&rsquo;agissait de verrous, ni r\u00e9aliser que le Syst\u00e8me tient sa surpuissance notamment de son herm\u00e9tisme et des verrous qui l&rsquo;assurent, c&rsquo;est \u00e9videmment un coup port\u00e9 contre cette situation d&rsquo;herm\u00e9tisme. Lorsque nous disons que le Syst\u00e8me est herm\u00e9tique, nous soulignons par l\u00e0 que sa surpuissance s&rsquo;exprime dans les deux voies essentielles de la puissance aujourd&rsquo;hui. Il y a d&rsquo;une part la puissance brute du syst\u00e8me du technologisme, qui est si grande que rien ne peut \u00eatre fait de structurant qui ne passe par les outils de cette puissance que contr\u00f4le, voire qu&rsquo;engendre le Syst\u00e8me, comme seule source de puissance mat\u00e9rielle et technique dans le monde. Il y a d&rsquo;autre part la puissance d&rsquo;influence du syst\u00e8me de la communication, qui d\u00e9termine la perception unique, et donc l&rsquo;\u00e9tat de la psychologie. Cette formule id\u00e9ale d\u00e9termine l&rsquo;herm\u00e9tisme du Syst\u00e8me, qui fait que rien n&rsquo;est possible hors du Syst\u00e8me. Bien entendu, toute cette superbe construction est r\u00e9guli\u00e8rement mise en cause, secou\u00e9e, de plus en plus violemment, par la crise du Syst\u00e8me et sa propre folie, qui fait s&rsquo;interroger sur le fait de savoir si le Syst\u00e8me est capable de se supporter lui-m\u00eame. On a d\u00e9j\u00e0 vu bien des \u00e9l\u00e9ments de cette folie, dont par exemple l&rsquo;utilisation contre lui-m\u00eame du syst\u00e8me de la communication, le ph\u00e9nom\u00e8ne des <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_les_systemes_antisysteme_ddecrisis_17_01_2011.html\" class=\"gen\">syst\u00e8mes antiSyst\u00e8me<\/a>, etc.<\/p>\n<\/p>\n<p><p>\tLa liquidation des verrous (ben Laden, DSK) est un autre aspect de cette d\u00e9marche. Elle apporte un \u00e9l\u00e9ment important dans cette interpr\u00e9tation de la mise en cause de l&rsquo;herm\u00e9tisme du Syst\u00e8me, lequel est une situation de structuration essentielle pour lui. Le Syst\u00e8me tient notamment sa force de son enfermement, donc de l&rsquo;enfermement de toute la puissance possible selon les normes qu&rsquo;il a lui-m\u00eame \u00e9dict\u00e9es. Cet enfermement interdit le recours aux r\u00e9f\u00e9rences ext\u00e9rieures (d&rsquo;o\u00f9 la th\u00e8se-slogan TINA, <em>There Is No Alternative<\/em>) et alimente l&rsquo;id\u00e9e que seul le Syst\u00e8me est possible ; m\u00eame si le Syst\u00e8me repr\u00e9sente, comme c&rsquo;est notre conviction, le mal absolu pour notre situation terrestre du temps m\u00e9tahistorique courant, notamment comme <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_source_de_tous_les_maux_ddecrisis_10_09_2010.html\" class=\"gen\">source de tous les maux<\/a>, sa situation d&rsquo;herm\u00e9tisme permet d&rsquo;\u00e9viter la r\u00e9alisation de cette \u00e9vidence catastrophique pour lui en coupant tout rapport avec d&rsquo;\u00e9ventuelles r\u00e9f\u00e9rences ext\u00e9rieures antagonistes. (Par exemple, cet herm\u00e9tisme constitue, \u00e0 notre sens, une barri\u00e8re efficace contre l&rsquo;acceptation, par les esprits, de l&rsquo;intuition haute qui permet la mise en cause radicale du Syst\u00e8me.) On voit combien cet acte d&rsquo;autodestruction de la liquidation de verrous de son propre herm\u00e9tisme constitue un pas important de plus dans le processus g\u00e9n\u00e9ral d&rsquo;autodestruction.<\/p>\n<\/p>\n<p><p>\tLes liquidations ainsi analys\u00e9es constituent deux initiatives importantes sur la voie de l&rsquo;autodestruction du Syst\u00e8me, qui se traduit en r\u00e9alit\u00e9 par sa d\u00e9structuration,  ou, si l&rsquo;on veut, auto-d\u00e9structuration. Il est impossible d&rsquo;en \u00e9valuer l&rsquo;importance, si tel ou tel \u00e9v\u00e9nement est d\u00e9cisif, etc. L&rsquo;on doit simplement observer que c&rsquo;est un outil nouveau qui s&rsquo;ajoute \u00e0 la panoplie de la d\u00e9marche d&rsquo;auto-d\u00e9structuration\/autodestruction du Syst\u00e8me. L&rsquo;on dirait ainsi qu&rsquo;il y a dans le chef du Syst\u00e8me, comme par un ph\u00e9nom\u00e8ne de compensation relevant d&rsquo;une situation m\u00e9taphysique, autant de puissance, d&rsquo;habilet\u00e9, d&rsquo;efficacit\u00e9, dans sa d\u00e9marche d&rsquo;auto-d\u00e9structuration\/autodestruction que dans la d\u00e9marche d&rsquo;\u00e9tablissement de sa puissance et de sa structure qui a pr\u00e9sid\u00e9 \u00e0 l&rsquo;installation de la position d&rsquo;absolue domination qu&rsquo;il exerce aujourd&rsquo;hui. Il va de soi que cette voie est, bien entendu, la seule qui puisse venir \u00e0 bout de lui ; elle est, si l&rsquo;on ose dire, en bonne voie, et rien ne l&rsquo;arr\u00eatera.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Liquidation, de Geronimo \u00e0 DSK 19 mai 2011 Il est vrai que nous avons \u00e9t\u00e9 frapp\u00e9s, une fois de plus, par la rapidit\u00e9 des \u00e9v\u00e9nements, la liquidation de ben Laden (op\u00e9ration Geronimo, les 1er-2 mai) encha\u00eenant tr\u00e8s rapidement sur la liquidation de DSK. Nous ne croyons aucunement que le hasard puisse se manifester, ni le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[7849,4646,11132,4270,3265,5548,2631,3907,2803,4965,11130,3266,2913,3041,10031,3379,1131,3886,5838,5491,11131,3014,7833,9178,11129],"class_list":["post-73024","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-alternative","tag-antisysteme","tag-auto-destructuration","tag-autodestruction","tag-ben","tag-complots","tag-de","tag-destructuration","tag-effondrement","tag-fmi","tag-hermetisme","tag-laden","tag-les","tag-mal","tag-maux","tag-pakistan","tag-pfaff","tag-reference","tag-source","tag-suicide","tag-surpuissance","tag-systeme","tag-tina","tag-tous","tag-verrous"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73024","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73024"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73024\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73024"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73024"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73024"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}