{"id":73025,"date":"2011-05-21T06:53:10","date_gmt":"2011-05-21T06:53:10","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/05\/21\/portrait-dun-traitre-bho-vu-par-cornel-west\/"},"modified":"2011-05-21T06:53:10","modified_gmt":"2011-05-21T06:53:10","slug":"portrait-dun-traitre-bho-vu-par-cornel-west","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/05\/21\/portrait-dun-traitre-bho-vu-par-cornel-west\/","title":{"rendered":"Portrait d&rsquo;un tra\u00eetre : BHO vu par Cornel West"},"content":{"rendered":"<p><h2 class=\"titleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Portrait d&rsquo;un tra&icirc;tre : BHO vu par Cornel West<\/h2>\n<\/p>\n<p><p>On a d\u00e9j\u00e0 cit\u00e9 le professeur Cornel West, \u00ab\u00a0ic\u00f4ne\u00a0\u00bb de la culture africaine-am\u00e9ricaine, de l&rsquo;int\u00e9gration des Africains-Am\u00e9ricains dans le circuit universitaire du Syst\u00e8me. Cornel West n&rsquo;est certainement pas au-dessus de tout soup\u00e7on. On a lu notamment (voir ce <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-bho_les_noirs_et_2012_11_04_2011.html\">11 avril 2011<\/a>) les propos furieux d&rsquo;un ancien <em>Black Panther<\/em>, Larry Pinkney, contre Cornel West, apr\u00e8s des d\u00e9clarations de ce dernier \u00e0 <em>Russia Today<\/em> (voir le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-bho_execute_par_cornel_west_06_04_2011.html\">6 avril 2011<\/a>) ; West y attaquait Obama en des termes incendiaires, et Pinkney a attaqu\u00e9 \u00e0 son tour West, non pour les attaques de West contre Obama, mais pour avoir auparavant, dans son ancienne jeunesse, trahi le mouvement extr\u00e9miste noir pour s&rsquo;int\u00e9grer au circuit du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>Personne n&rsquo;a vraiment tort dans cette affaire&hellip; Cornel West a effectivement abandonn\u00e9 les extr\u00e9mistes noirs pour rallier le Syst\u00e8me. Pour autant, sa vindicte anti-BHO n&rsquo;est nullement feinte, et il semble bien que le docteur West, \u00e9minent professeur, effectivement \u00ab\u00a0ic\u00f4ne\u00a0\u00bb culturelle de l&rsquo;<em>establishment<\/em> africain-am\u00e9ricain qui voudrait bien cultiver sa diff\u00e9rence tout en b\u00e9n\u00e9ficiant des avantages du Syst\u00e8me, est aussi devenu une excellente r\u00e9f\u00e9rence pour qui entend appr\u00e9cier et comprendre la personnalit\u00e9 et l&rsquo;action d&rsquo;Obama devenu pr\u00e9sident, et la grandeur manifeste de sa trahison de lui-m\u00eame tel qu&rsquo;il s&rsquo;\u00e9tait repr\u00e9sent\u00e9.<\/p>\n<\/p>\n<p><p>En effet, la querelle que fait Pinkney \u00e0 West, si elle est fond\u00e9e, ne nous importe gu\u00e8re. Ce qui nous importe, \u00e0 nous, c&rsquo;est d&rsquo;\u00e9couter Cornel West d\u00e9vider sa ranc&oelig;ur, sa fureur, sa col\u00e8re, face au comportement d&rsquo;Obama dont il fut l&rsquo;un des soutiens les plus pr\u00e9cieux, et dont il s&rsquo;av\u00e8re aujourd&rsquo;hui qu&rsquo;il en est le compagnon le plus compl\u00e8tement trahi. La fureur de West est donc largement charg\u00e9e de sentiments personnels, et peut-\u00eatre du jugement fondamental, port\u00e9 sur lui-m\u00eame, que son ralliement au Syst\u00e8me qui devait s&rsquo;exprimer le plus fondamentalement par son soutien \u00e0 Obama, ne fut qu&rsquo;une vaine trahison des id\u00e9aux de sa jeunesse, puisqu&rsquo;il s&rsquo;est retrouv\u00e9 lui-m\u00eame compl\u00e8tement trahi par BHO, sous la forme d&rsquo;un abandon complet par BHO-devenu-Pr\u00e9sident. C&rsquo;est une histoire de trahisons successives pour des esp\u00e9rances m\u00e9langeant l&rsquo;ambition personnelle et l&rsquo;id\u00e9al reconverti dans le moule du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>Non, tout cela n&rsquo;importe pas vraiment. Ce qui importe en l&rsquo;occurrence, c&rsquo;est que Cornel West, sous le coup du d\u00e9pit, de la frustration, et aussi d&rsquo;une affection et d&rsquo;une estime trahies, s&rsquo;est mis \u00e0 d\u00e9tailler l&rsquo;odyss\u00e9e de ses relations avec BHO. Il d\u00e9crit la chose en d\u00e9tails pour Chris Hedges, de <em>Truthdig.com<\/em>, le <a class=\"gen\" href=\"http:\/\/www.truthdig.com\/report\/item\/the_obama_deception_why_cornel_west_went_ballistic_20110516\/\">16 mai 2011<\/a>. Cela nous donne un portrait haut en couleur, et particuli\u00e8rement <strong>v\u00e9ridique<\/strong>, &ndash; c&rsquo;est l\u00e0 la conviction que nous donne l&rsquo;intuition (haute), &ndash; d&rsquo;un tra&icirc;tre, en l&rsquo;occurrence le 44\u00e8me pr\u00e9sident des Etats-Unis et premier pr\u00e9sident africain-am\u00e9ricain des USA, &ndash; BHO, l&rsquo;homme-Syst\u00e8me, c&rsquo;est-\u00e0-dire l&rsquo;homme qui s&rsquo;est trahi lui-m\u00eame en trahissant les autres.<\/p>\n<\/p>\n<p><p>Nous donnons ci-dessous des extraits importants de ces confidences de West \u00e0 Hedges. Dans son introduction, Hedges met en balance Rahm Emanuel, l&rsquo;homme le plus proche d&rsquo;Obama jusqu&rsquo;\u00e0 son d\u00e9part pour la mairie de Chicago, un \u00ab\u00a0pur produit de la machine politique de Chicago\u00a0\u00bb (bien plus, dans ce cas, qu&rsquo;un agent d&rsquo;Isra\u00ebl), et West, qu&rsquo;il identifie hypoth\u00e9tiquement comme \u00ab\u00a0la voix de sa conscience\u00a0\u00bb d&rsquo;Obama&hellip;<\/p>\n<\/p>\n<p><p>&laquo;<em>Perhaps there was never much of a struggle in Obama&rsquo;s heart. Perhaps West only provided a moral veneer. Perhaps the dark heart of Emanuel was always the dark heart of Obama. Only Obama knows. But we know how the play ends. West is banished like honest Kent in \u00ab\u00a0King Lear.\u00a0\u00bb Emanuel and immoral mediocrities from Lawrence Summers to Timothy Geithner to Robert Gates&mdash;think of Goneril and Regan in the Shakespearean tragedy&mdash;take power. We lose. And Obama becomes an obedient servant of the corporate elite in exchange for the hollow trappings of authority.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>&hellip;Et quoi qu&rsquo;il en soit, voici la description de BHO-Roi Lear, d\u00e9crit par West-\u00ab\u00a0honn\u00eate Kent\u00a0\u00bb, r\u00e9pudi\u00e9 par la cabale des conseillers du roi, et par le roi lui-m\u00eame.<\/p>\n<\/p>\n<p><p>&bull; D&rsquo;abord, la solitude de Cornel West, l&rsquo;homme trahi, l&rsquo;homme victime de ses ambitions d\u00e9\u00e7ues et de ses illusions trahies r\u00e9duites \u00e0 de tristes souvenirs poussi\u00e9reux&hellip;<\/p>\n<\/p>\n<p><p>&laquo;<em>\u00ab\u00a0When you look at a society you look at it through the lens of the least of these, the weak and the vulnerable; you are committed to loving them first, not exclusively, but first, and therefore giving them priority,\u00a0\u00bb says West, the Class of 1943 University Professor of African American Studies and Religion at Princeton University. \u00ab\u00a0And even at this moment, when the empire is in deep decline, the culture is in deep decay, the political system is broken, where nearly everyone is up for sale, you say all I have is the subversive memory of those who came before, personal integrity, trying to live a decent life, and a willingness to live and die for the love of folk who are catching hell. This means civil disobedience, going to jail, supporting progressive forums of social unrest if they in fact awaken the conscience, whatever conscience is left, of the nation. And that&rsquo;s where I find myself now.\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<p><p>&bull; Le commencement de la d\u00e9sillusion, ou la marche vers la trahison d&rsquo;Obama devenu BHO, bient\u00f4t pr\u00e9sident des USA, puis pr\u00e9sident des USA et d\u00e9j\u00e0 tra&icirc;tre.<\/p>\n<\/p>\n<p><p>&laquo;<em>\u00ab\u00a0I was thinking maybe he has at least some progressive populist instincts that could become more manifest after the cautious policies of being a senator and working with<\/em> [<em>Sen. Joe<\/em>] <em>Lieberman as his mentor,\u00a0\u00bb he says. \u00ab\u00a0But it became very clear when I looked at the neoliberal economic team. The first announcement of Summers and Geithner I went ballistic. I said, &lsquo;Oh, my God, I have really been misled at a very deep level.&rsquo; And the same is true for Dennis Ross and the other neo-imperial elites. I said, &lsquo;I have been thoroughly misled, all this populist language is just a facade. I was under the impression that he might bring in the voices of brother Joseph Stiglitz and brother Paul Krugman. I figured, OK, given the structure of constraints of the capitalist democratic procedure that&rsquo;s probably the best he could do. But at least he would have some voices concerned about working people, dealing with issues of jobs and downsizing and banks, some semblance of democratic accountability for Wall Street oligarchs and corporate plutocrats who are just running amuck. I was completely wrong.\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<p><p>&bull; Avec Cornel West, et avec BHO, il y a donc une intense dimension personnelle. Elle donne toute sa valeur au reste du t\u00e9moignage, en instillant l&rsquo;intensit\u00e9 humaine. C&rsquo;est moins de la subjectivit\u00e9 qu&rsquo;on croit, que l&rsquo;intensit\u00e9 des sentiments qui contribueront, si l&rsquo;intuition haute est de la partie, \u00e0 donner une appr\u00e9ciation <strong>vraie<\/strong>&hellip;<\/p>\n<\/p>\n<p><p>&laquo;<em>\u00ab\u00a0There is the personal level,\u00a0\u00bb he says. \u00ab\u00a0I used to call my dear Brother<\/em> [<em>Obama<\/em>] <em>every two weeks. I said a prayer on the phone for him, especially before a debate. And I never got a call back. And when I ran into him in the state Capitol in South Carolina when I was down there campaigning for him he was very kind. The first thing he told me was, &lsquo;Brother West, I feel so bad. I haven&rsquo;t called you back. You been calling me so much. You been giving me so much love, so much support and what have you.&rsquo; And I said, &lsquo;I know you&rsquo;re busy.&rsquo; But then a month and half later I would run into other people on the campaign and he&rsquo;s calling them all the time. I said, wow, this is kind of strange. He doesn&rsquo;t have time, even two seconds, to say thank you or I&rsquo;m glad you&rsquo;re pulling for me and praying for me, but he&rsquo;s calling these other people. I said, this is very interesting. And then as it turns out with the inauguration I couldn&rsquo;t get a ticket with my mother and my brother. I said this is very strange. We drive into the hotel and the guy who picks up my bags from the hotel has a ticket to the inauguration. My mom says, &lsquo;That&rsquo;s something that this dear brother can get a ticket and you can&rsquo;t get one, honey, all the work you did for him from Iowa.&rsquo; Beginning in Iowa to Ohio. We had to watch the thing in the hotel.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>\u00ab\u00a0What it said to me on a personal level,\u00a0\u00bb he goes on, \u00ab\u00a0was that brother Barack Obama had no sense of gratitude, no sense of loyalty, no sense of even courtesy, [no] sense of decency, just to say thank you. Is this the kind of manipulative, Machiavellian orientation we ought to get used to? That was on a personal level.\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<p><p>&bull; L&rsquo;autre trahison, c&rsquo;est la trahison id\u00e9ologique, &ndash; comme si, \u00e0 la lumi\u00e8re de ce qui a \u00e9t\u00e9 d\u00e9j\u00e0 dit, la chose allait de soi. BHO a trahi ses \u00ab\u00a0fr\u00e8res\u00a0\u00bb, il a trahi son destin, il a trahi ce que l&rsquo;intuition haute l&rsquo;exhortait \u00e0 \u00eatre et qu&rsquo;il ne fut pas. Pi\u00e8tre personnage, au bout du compte et du tunnel, lui qui a trahi ses propres vertus, son caract\u00e8re m\u00eame, qui l&rsquo;invitaient \u00e0 un tout autre destin ; pi\u00e8tre h\u00e9ros d&rsquo;une pi\u00e8ce \u00e9crite par un auteur sur le d\u00e9clin.<\/p>\n<\/p>\n<p><p>&laquo;<em>\u00ab\u00a0It became very clear to me as the announcements were being made,\u00a0\u00bb he says, \u00ab\u00a0that this was going to be a newcomer, in many ways like Bill Clinton, who wanted to reassure the Establishment by bringing in persons they felt comfortable with and that we were really going to get someone who was using intermittent progressive populist language in order to justify a centrist, neoliberalist policy that we see in the opportunism of Bill Clinton. It was very much going to be a kind of black face of the DLC<\/em> [<em>Democratic Leadership Council<\/em>]<em>.\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<p><p>&bull; La derni\u00e8re fois qu&rsquo;il rencontra le tra&icirc;tre, en avril 2010, lors d&rsquo;un discours de BHO \u00e0 la Urban League, auquel Cornel West assistait, la chose se passa comme ceci. Tous les \u00e9l\u00e9ments de la trag\u00e9die, de l&rsquo;infamie, de la tromperie, de la trag\u00e9die sont r\u00e9unis&hellip;<\/p>\n<\/p>\n<p><p>&laquo;<em>\u00ab\u00a0He makes a bee line to me right after the talk, in front of everybody,\u00a0\u00bb West says. \u00ab\u00a0He just lets me have it. He says, &lsquo;You ought to be ashamed of yourself, saying I&rsquo;m not a progressive. Is that the best you can do? Who do you think you are?&rsquo; I smiled. I shook his hand. And a sister hollered in the back, &lsquo;You can&rsquo;t talk to professor West. That&rsquo;s Dr. Cornel West. Who do you think you are?&rsquo; You can go to jail talking to the president like that. You got to watch yourself. I wanted to slap him on the side of his head.<\/em>[&hellip;] <em>\u00ab\u00a0It was so disrespectful,\u00a0\u00bb he went on, \u00ab\u00a0that&rsquo;s what I didn&rsquo;t like. I&rsquo;d already been called, along with all<\/em> [<em>other<\/em>] <em>leftists, a \u00ab\u00a0F&rsquo;ing retard\u00a0\u00bb by Rahm Emanuel because we had critiques of the president.\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<p><p>&bull; Voici comment BHO a trahi ses \u00ab\u00a0fr\u00e8res noirs\u00a0\u00bb, et comment Cornel West, \u00ab\u00a0ic\u00f4ne\u00a0\u00bb de la culture africaine-am\u00e9ricaine int\u00e9gr\u00e9e dans le Syst\u00e8me en ressentit une immense tristesse&hellip; D&rsquo;o&ugrave; la question qui nous vient \u00e0 l&rsquo;esprit  : en v\u00e9rit\u00e9, ce premier pr\u00e9sident africain-am\u00e9ricain n&rsquo;est-il pas, au fond de lui-m\u00eame, un v\u00e9ritable <strong>raciste<\/strong>, selon le seul sens acceptable qu&rsquo;on pourrait donner \u00e0 ce mot universellement employ\u00e9, c&rsquo;est-\u00e0-dire syst\u00e9matiquement galvaud\u00e9 pour les avantages du Syst\u00e8me ?<\/p>\n<\/p>\n<p><p>&laquo;<em>\u00ab\u00a0I think my dear brother Barack Obama has a certain fear of free black men,\u00a0\u00bb West says. \u00ab\u00a0It&rsquo;s understandable. As a young brother who grows up in a white context, brilliant African father, he&rsquo;s always had to fear being a white man with black skin. All he has known culturally is white. He is just as human as I am, but that is his cultural formation. When he meets an independent black brother, it is frightening. And that&rsquo;s true for a white brother. When you get a white brother who meets a free, independent black man, they got to be mature to really embrace fully what the brother is saying to them. It&rsquo;s a tension, given the history. It can be overcome. Obama, coming out of Kansas influence, white, loving grandparents, coming out of Hawaii and Indonesia, when he meets these independent black folk who have a history of slavery, Jim Crow, Jane Crow and so on, he is very apprehensive. He has a certain rootlessness, a deracination. It is understandable.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>\u00ab\u00a0He feels most comfortable with upper middle-class white and Jewish men who consider themselves very smart, very savvy and very effective in getting what they want,\u00a0\u00bb he says. \u00ab\u00a0He&rsquo;s got two homes. He has got his family and whatever challenges go on there, and this other home. Larry Summers blows his mind because he&rsquo;s so smart. He&rsquo;s got Establishment connections. He&rsquo;s embracing me. It is this smartness, this truncated brilliance, that titillates and stimulates brother Barack and makes him feel at home. That is very sad for me.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>&bull; Car, en v\u00e9rit\u00e9 et pour en terminer, voici ce qu&rsquo;aurait pu \u00eatre ce tra&icirc;tre qui pr\u00e9f\u00e9ra trahir, et qui aurait pu \u00eatre, pour l&rsquo;honneur des Africains-Am\u00e9ricains, des <em>blacks<\/em>, ce que nous avions d\u00e9sign\u00e9 comme l'\u00a0\u00bb<em>American<\/em> <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-american_gorbatchev_29_10_2008.html\">Gorbatchev<\/a>\u00ab\u00a0, et qu&rsquo;il pr\u00e9f\u00e9ra ne jamais \u00eatre&hellip;<\/p>\n<\/p>\n<p><p>&laquo;<em>\u00ab\u00a0This was maybe America&rsquo;s last chance to fight back against the greed of the Wall Street oligarchs and corporate plutocrats, to generate some serious discussion about public interest and common good that sustains any democratic experiment,\u00a0\u00bb West laments. \u00ab\u00a0We are squeezing out all of the democratic juices we have. The escalation of the class war against the poor and the working class is intense. More and more working people are beaten down. They are world-weary. They are into self-medication. They are turning on each other. They are scapegoating the most vulnerable rather than confronting the most powerful. It is a profoundly human response to panic and catastrophe. I thought Barack Obama could have provided some way out. But he lacks backbone.<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>\u00ab\u00a0Can you imagine if Barack Obama had taken office and deliberately educated and taught the American people about the nature of the financial catastrophe and what greed was really taking place?\u00a0\u00bb West asks. \u00ab\u00a0If he had told us what kind of mechanisms of accountability needed to be in place, if he had focused on homeowners rather than investment banks for bailouts and engaged in massive job creation he could have nipped in the bud the right-wing populism of the tea party folk. The tea party folk are right when they say the government is corrupt. It is corrupt. Big business and banks have taken over government and corrupted it in deep ways&hellip;\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<p><h2 class=\"titleset_c.deepblue\" style=\"color:#0f3955;font-size:1.25em;\">Notre commentaire<\/h2>\n<\/p>\n<p><p>&hellip;On avouera que la chose se termine bien, dans le sens d&rsquo;\u00eatre paradoxale selon la pens\u00e9e-Syst\u00e8me et finalement pas si \u00e9loign\u00e9e de ce qu&rsquo;on jugerait \u00eatre la v\u00e9rit\u00e9 des syst\u00e8mes antiSyst\u00e8me venus d&rsquo;horizons diff\u00e9rents, dont le Syst\u00e8me avait convaincu nos pi\u00e8tres raisons qu&rsquo;ils \u00e9taient irr\u00e9conciliables alors qu&rsquo;ils sont tous n\u00e9cessaires et n\u00e9cessairement <strong>solidaires<\/strong> dans la lutte gigantesque contre le Syst\u00e8me&hellip; Il s&rsquo;agit du <em>satisfecit<\/em> d&rsquo;un professeur africain-am\u00e9ricain, ancien extr\u00e9miste noir et adepte d\u00e9\u00e7u de l&rsquo;int\u00e9gration dans le Syst\u00e8me, donn\u00e9 \u00e0 <em>Tea Party<\/em>, d\u00e9nonc\u00e9 comme \u00ab\u00a0raciste\u00a0\u00bb par l&rsquo;<em>establishment<\/em> lib\u00e9ral, lequel s&rsquo;est rang\u00e9 sous la banni\u00e8re du tra&icirc;tre, le pr\u00e9sident africain-am\u00e9ricain BHO. Des deux, <em>Tea Party<\/em> et BHO, ce serait donc le second qui serait v\u00e9ritablement <strong>raciste<\/strong> ? Qui en douterait, d&rsquo;ailleurs&hellip;<\/p>\n<\/p>\n<p><p>La diatribe du docteur West est magnifique parce qu&rsquo;elle sonne <strong>vrai<\/strong> alors qu&rsquo;elle vient d&rsquo;un personnage qu&rsquo;on pourrait juger comme douteux, comme \u00ab\u00a0collaborateur\u00a0\u00bb du Syst\u00e8me. Mais il n&rsquo;est plus temps de chercher \u00e0 fusiller les \u00ab\u00a0collaborateurs\u00a0\u00bb, comme l&rsquo;on fit <em>in illo tempore<\/em> o&ugrave; l&rsquo;on croyait d\u00e9tenir les clefs des lendemains qui chantent au bout d&rsquo;un peloton d&rsquo;ex\u00e9cution. Nous en avons assez entendu de ces \u00ab\u00a0lendemains\u00a0\u00bb, comme tout cela chantait faux ; aujourd&rsquo;hui, toutes les infamies sont pos\u00e9es sur la table, et le choix peut \u00eatre fait. C&rsquo;est ainsi que les impressions et les descriptions du docteur West, toutes empreintes d&rsquo;amertume et d&rsquo;estime trahie, voire d&rsquo;amour abandonn\u00e9, valent tous les commentaires assur\u00e9s des sp\u00e9cialistes du complot pour comprendre qui est Barack Hussein Obama.<\/p>\n<\/p>\n<p><p>Le 44\u00e8me pr\u00e9sident des Etats-Unis repr\u00e9sente le cas extr\u00eame de la trahison de soi-m\u00eame au nom du Syst\u00e8me, et pour plaire \u00e0 ce Syst\u00e8me, s&rsquo;y int\u00e9grer magnifiquement et jouir des privil\u00e8ges fictifs mais magiques jusqu&rsquo;\u00e0 la fascination malsaine, que le Syst\u00e8me promet, &ndash; et il tient cette promesse, en g\u00e9n\u00e9ral. En ce sens, Obama, par rapport \u00e0 ses propres promesses qu&rsquo;il portait sans qu&rsquo;il le sut express\u00e9ment, repr\u00e9sente un exemple extraordinaire par son extr\u00e9mit\u00e9 d&rsquo;abaissement de soi-m\u00eame. Les circonstances de sa victoire, le sens du discours qu&rsquo;il avait choisi pour y parvenir, les qualit\u00e9s qu&rsquo;il avait montr\u00e9es, indiquaient \u00e9videmment, d&rsquo;une fa\u00e7on imp\u00e9rative, la voie qu&rsquo;il avait \u00e0 suivre. Par faiblesse, par aveuglement consenti \u00e0 cause de refus de l&rsquo;effort de distinguer l&rsquo;audace n\u00e9cessaire, bref par abaissement consenti de lui-m\u00eame, Obama a accompli la trahison la plus compl\u00e8te qu&rsquo;il se pouvait imaginer. Ses qualit\u00e9s \u00e9videntes, par les obligations qu&rsquo;elles lui cr\u00e9aient, font de sa trahison, en plus d&rsquo;\u00eatre ce qu&rsquo;elle est, une infamie d&rsquo;une exceptionnelle grandeur. C&rsquo;est effectivement en ce sens qu&rsquo;on peut d\u00e9signer ce pr\u00e9sident, bien plus que ses pr\u00e9d\u00e9cesseurs encore, comme l&rsquo;homme-Syst\u00e8me accompli.<\/p>\n<\/p>\n<p><p>On ne fera pas ici l&rsquo;inutile proc\u00e8s d&rsquo;un quelconque machiav\u00e9lisme, de calculs tordus, etc., mais bien entendu le proc\u00e8s des faiblesses cach\u00e9es, celles que les qualit\u00e9s humaines peuvent dissimuler lorsque le jugement de soi-m\u00eame se trompe sur soi-m\u00eame. Les habituelles diatribes du type \u00ab\u00a0marionnette de ceci, marionnette de cela\u00a0\u00bb montrent dans son cas, encore plus qu&rsquo;en g\u00e9n\u00e9ral, bien plus la vacuit\u00e9 de la critique que l&rsquo;infamie de celui \u00e0 qui cette critique s&rsquo;adresse. Il n&rsquo;y a nul cynisme chez Obama, il n&rsquo;y a aucune lucidit\u00e9 pour consid\u00e9rer la voie qu&rsquo;il a emprunt\u00e9e ; il n&rsquo;y a nulle contrainte dont il serait prisonnier, parce que ce n&rsquo;est pas de cette fa\u00e7on que fonctionne le Syst\u00e8me, et encore moins le pouvoir que le Syst\u00e8me a \u00e9tabli \u00e0 son avantage ; le Syst\u00e8me nous prend au pi\u00e8ge de nos faiblesses, de nos d\u00e9fauts et de nos mollesses de caract\u00e8re, et cela vaut largement, au centuple, une quelconque contrainte&hellip; Ainsi d&rsquo;Obama, qui en est, aujourd&rsquo;hui encore, \u00e0 se consid\u00e9rer comme un \u00ab\u00a0progressiste\u00a0\u00bb, cela chez un homme qui consid\u00e8re que le \u00ab\u00a0progressisme\u00a0\u00bb est la mesure de la vertu. C&rsquo;est en effet une si grande grossi\u00e8ret\u00e9 de l&rsquo;esprit qu&rsquo;il puisse affirmer <em>in fine<\/em> \u00e0 Cornel West, en 2010, qu&rsquo;il se consid\u00e8re manifestement lui-m\u00eame, dans son action de pr\u00e9sident, comme un \u00ab\u00a0progressiste\u00a0\u00bb. Ce n&rsquo;est certainement pas que nous jugions, pour notre part, que le \u00ab\u00a0progressisme\u00a0\u00bb est effectivement la mesure de la vertu, parce qu&rsquo;il serait plut\u00f4t, pour notre compte, la mesure de la tromperie sur la vertu, &ndash; non, ce qui importe ici, c&rsquo;est d&rsquo;appr\u00e9cier combien l&rsquo;homme qui a fait ce qu&rsquo;il a fait, peut continuer \u00e0 c\u00e9der \u00e0 ses faiblesses jusqu&rsquo;\u00e0 cultiver l&rsquo;illusion d&rsquo;une interpr\u00e9tation si compl\u00e8tement avantageuse, et trompeuse \u00e0 mesure, de son comportement. Obama est un tra&icirc;tre \u00e0 lui-m\u00eame et il l&rsquo;ignore absolument, superbement, et l&rsquo;on dirait enfin qu&rsquo;il l&rsquo;ignore avec une arrogance qui en dit long sur la force de la subversion du Syst\u00e8me, &ndash; et qui en dit aussi long sur les faiblesses humaines, et sur l&rsquo;\u00e9tat de subversion o&ugrave; la raison humaine, dont Obama lui-m\u00eame donne un bel exemple de son usage habile, a \u00e9t\u00e9 plong\u00e9es par l&rsquo;action du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>Mis en ligne le 21 mai 2011 \u00e0 06H52<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Portrait d&rsquo;un tra&icirc;tre : BHO vu par Cornel West On a d\u00e9j\u00e0 cit\u00e9 le professeur Cornel West, \u00ab\u00a0ic\u00f4ne\u00a0\u00bb de la culture africaine-am\u00e9ricaine, de l&rsquo;int\u00e9gration des Africains-Am\u00e9ricains dans le circuit universitaire du Syst\u00e8me. Cornel West n&rsquo;est certainement pas au-dessus de tout soup\u00e7on. On a lu notamment (voir ce 11 avril 2011) les propos furieux d&rsquo;un ancien&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[11135,11133,11027,4807,11134,7069,3424,3014,8256,2837],"class_list":["post-73025","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-africain-americain","tag-blacjk","tag-cornel","tag-integration","tag-panthers","tag-party","tag-racisme","tag-systeme","tag-tea","tag-west"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73025"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73025\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73025"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73025"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}