{"id":73135,"date":"2011-07-01T11:10:51","date_gmt":"2011-07-01T11:10:51","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/07\/01\/le-labyrinthe-de-linformation-et-un-article-de-robert-fisk\/"},"modified":"2011-07-01T11:10:51","modified_gmt":"2011-07-01T11:10:51","slug":"le-labyrinthe-de-linformation-et-un-article-de-robert-fisk","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/07\/01\/le-labyrinthe-de-linformation-et-un-article-de-robert-fisk\/","title":{"rendered":"Le labyrinthe de l&rsquo;information et un article de Robert Fisk"},"content":{"rendered":"<p><p>Il y avait un sommet \u00e0 T\u00e9h\u00e9ran ce dernier week-end, qui r\u00e9unissait du beau monde : les Pakistanais, les Afghans, les Irakiens, les Soudanais. Officiellement, il s&rsquo;agissait d&rsquo;un sommet anti-terreur. Il en avait \u00e9t\u00e9 question, avant sa r\u00e9union, par l&rsquo;interm\u00e9diaire du chroniqueur ex-diplomate indien M K Bhadrakumar, le <a href=\"http:\/\/www.dedefensa.org\/article-afghanistan-ii_les_copains_d_a-bord_ne_restent_pas_inactifs_23_06_2011.html\" class=\"gen\">23 juin 2011<\/a> sur ce site.<\/p>\n<\/p>\n<p><p>\tLe sommet a eu lieu. Quelques textes en ont rendu compte, dont un du m\u00eame M K Bhadrakumar, sur <em>ATimes.com<\/em> le <a href=\"http:\/\/www.atimes.com\/atimes\/Middle_East\/MF28Ak02.html\" class=\"gen\">28 juin 2011<\/a>. Le chroniqueur-diplomate estime que les Iraniens ont remport\u00e9 un succ\u00e8s, en rapprochant les Afghans et les Pakistanais de leur propre position, qui est d&rsquo;organiser une s\u00e9curit\u00e9 commune sur une base r\u00e9gionale, sans les USA et l&rsquo;OTAN<\/p>\n<\/p>\n<p><p>\t\u00ab<em>From the Iranian perspective, a main objective was to forge common thinking with Pakistan and Afghanistan that the continuance of the US and North Atlantic Treaty Organization forces in Afghanistan adversely impacts on all three countries&rsquo; national interests and on regional security and stability. This comes out clearly in the meetings Khamenei had with Zardari and Karzai.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tUn autre texte sur le sommet nous a int\u00e9ress\u00e9. Il s&rsquo;agit du reportage de Robert Fisk, de <em>The Independent<\/em>, le <a href=\"http:\/\/www.independent.co.uk\/news\/world\/middle-east\/ahmadinejad-seizes-on-americas-retreat-at-antiterror-conference-2303229.html\" class=\"gen\">27 juin 2011<\/a>. Dans notre <em>F&#038;C<\/em> du <a href=\"http:\/\/www.dedefensa.org\/article-s_entr_ouvrent_les_portes_sur_l_inconnu__30_06_2011.html\" class=\"gen\">30 juin 2011<\/a>, nous en parlons, mais selon une perspective sp\u00e9cifique qui ne nous concerne pas directement ici, n\u00e9anmoins avec quelques observations qui concernent au contraire la perspective consid\u00e9r\u00e9e ici. Voici ce passage :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Le leitmotiv de l&rsquo;article se trouve dans ces extraits qu&rsquo;on \u00e9gr\u00e8ne, ci-apr\u00e8s, sans n\u00e9cessit\u00e9 de queue ni de t\u00eate, qui t\u00e9moigne du sentiment g\u00e9n\u00e9ral que Fisk a rencontr\u00e9 chez ces dirigeants iraniens, pakistanais, afghans, irakiens, etc. when the US and its Nato partners stage their final retreat from Afghanistan. [] when the West ends its adventure in the graveyard of Empire. [] after the Nato military force goes out of Afghanistan. [] This is a long diplomatic way of saying Phew!  the Americans are going at last and we&rsquo;re all on our own.&rsquo; [] Ayatollah Sayed Ali Khamenei thought the Americans would be gone within three years&rsquo;<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tPlus loin, dans le m\u00eame texte, alors que nous faisons quelques observations sur le sentiment qui se r\u00e9pand de l&rsquo;effacement, pour ne pas dire plus, des USA, notamment dans cette r\u00e9gion, nous ajoutons ceci : \u00ab<em>Mais faisons une pause pour une premi\u00e8re conclusion<\/em> [] <em>Il s&rsquo;agit du constat de l&rsquo;extraordinaire conviction qui semble se r\u00e9pandre comme une tra\u00een\u00e9e de poudre, qui touche m\u00eame des dirigeants politiques (voir le reportage de Fisk sur le sentiment des dirigeants des pays au sommet de T\u00e9h\u00e9ran), que la d\u00e9cision d&rsquo;Obama sur l&rsquo;Afghanistan acte une d\u00e9faite terrible, qui marque la fin du commencement de la fin, avec l&rsquo;acc\u00e9l\u00e9ration de l&rsquo;effondrement<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tIl faut bien noter que ce que nous relevons \u00e0 propos du texte de Fisk, dans ces lignes, n&rsquo;est pas le principal propos de ce texte. D&rsquo;une fa\u00e7on tr\u00e8s diff\u00e9rente, Fisk semble noter toutes ces choses, ces appr\u00e9ciation des dirigeants et officiels du sommet, comme en passant, parce que son propos porte sur son \u00e9valuation morale des pays impliqu\u00e9s. Son t\u00e9moignage est donc d&rsquo;autant plus int\u00e9ressant qu&rsquo;il est involontaire, alors qu&rsquo;on peut \u00eatre s\u00fbr qu&rsquo;un journaliste de sa notori\u00e9t\u00e9, dont la position anti-US et anti-imp\u00e9rialiste est tr\u00e8s connue dans la r\u00e9gion, a certainement recueilli nombre de confidences des dirigeants pr\u00e9sents.<\/p>\n<\/p>\n<p><p>\tIl faut \u00e9galement noter que cet aspect que nous relevons du texte de Fisk ne nous a pas frapp\u00e9 \u00e0 la premi\u00e8re lecture. Ce n&rsquo;est qu&rsquo;en relisant et relisant ce texte que la chose nous est apparue, avec l&rsquo;observation qu&rsquo;elle \u00e9tait enfouie dans la signification de l&rsquo;article en tant que tel, l&rsquo;auteur ne l&rsquo;ayant gu\u00e8re r\u00e9alis\u00e9e lui-m\u00eame parce qu&rsquo;il \u00e9tait int\u00e9ress\u00e9 par un autre aspect. Fisk voulait montrer que les dirigeants des pays concern\u00e9s, r\u00e9unis \u00e0 T\u00e9h\u00e9ran, voulaient reprendre leur destin commun en mains, et qu&rsquo;ils pensaient le faire en profitant de l&rsquo;effacement US ;  et Fisk de se lamenter <em>in petto<\/em> de voir les USA remplac\u00e9s par des semi-dictateurs et des trois quarts corrompus ; mais pour \u00e9mettre cette constatation qui lui venait certainement du fond du cur, et \u00e0 laquelle il tenait, il devait mentionner leur avis unanime que les USA s&rsquo;effa\u00e7aient et ne compteraient plus gu\u00e8re Mais, en v\u00e9rit\u00e9, c&rsquo;est bien l\u00e0 l&rsquo;\u00e9l\u00e9ment sensationnel de ce sommet, cette perception commune d&rsquo;un \u00e9v\u00e9nement d&rsquo;une telle importance, par des dirigeants de pays d&rsquo;une telle importance. Il s&rsquo;agit moins de ce qu&rsquo;on nomme de mani\u00e8re un peu artificielle un d\u00e9codage (d\u00e9couvrir dans un texte une information cach\u00e9e, que l&rsquo;auteur a voulue comme telle pour des raisons qui le regardent, et que l&rsquo;on d\u00e9couvre par certaines habitudes de lecture, connaissance de l&rsquo;auteur, etc.),  que d&rsquo;une mise \u00e0 jour de l&rsquo;information la plus importante du texte, diss\u00e9min\u00e9e dans le texte sans intention de l&rsquo;auteur et qui finit par appara\u00eetre d&rsquo;elle-m\u00eame, par sa propre importance.<\/p>\n<\/p>\n<p><p>\tAinsi est trac\u00e9, nous semble-t-il, le destin de ce qui est une information importante, au gr\u00e9 des humeurs, des prises de conscience ou non, des uns et des autres (y compris de nous en tant que lecteurs). Il y a l\u00e0 un caract\u00e8re extr\u00eame de l&rsquo;insaisissabilit\u00e9 des informations importantes aujourd&rsquo;hui, essentiellement pour deux causes :<\/p>\n<\/p>\n<p><p>\t Les caract\u00e8res extr\u00eamement touffus, sinon confus, des canaux de communication, avec la difficult\u00e9 d&rsquo;identifier les bonnes informations, ou les informations justes qui permettent de servir \u00e0 l&rsquo;\u00e9tablissement de la v\u00e9rit\u00e9 (en r\u00e9alit\u00e9, les informations n&rsquo;ayant pas une estampille officielle en tant que telles, m\u00eame si elles ne sont pas volontairement dissimul\u00e9es). La presse officielle, ou presse-<em>Pravda<\/em>, ou presse-Syst\u00e8me, comprenant notamment les grands quotidiens de r\u00e9f\u00e9rence, les grandes cha\u00eenes TV, etc. sont compl\u00e8tement discr\u00e9dit\u00e9s \u00e0 cet \u00e9gard m\u00eame si leur puissance reste grande et si l&rsquo;on continue \u00e0 affirmer leur influence. Ce d\u00e9clin suit le d\u00e9clin de l&rsquo;information officielle, dont on a dit souvent qu&rsquo;elle a sacrifi\u00e9 la puissance de sa pr\u00e9sentation objective \u00e0 la soi-disant efficacit\u00e9 de la manipulation et du mensonge d\u00e9lib\u00e9r\u00e9 affirm\u00e9s par les officiels eux-m\u00eames. (Donald Rumsfeld, d\u00e8s l&rsquo;automne 2001, \u00e0 propos de l&rsquo;Afghanistan, comme nous le notions en revenant sur le fait le <a href=\"http:\/\/www.dedefensa.org\/article-je_doute_donc_je_suis_13_03_2003.html\" class=\"gen\">13 mars 2003<\/a>.) Il s&rsquo;agit donc d&rsquo;\u00e9valuer la substance des informations en tenant compte de ces diverses r\u00e9f\u00e9rences qui sont en m\u00eame temps des variables incertaines. Il faut tenir compte de la presse-Syst\u00e8me et des d\u00e9clarations officielles, mais en ayant \u00e0 l&rsquo;esprit que l&rsquo;une et l&rsquo;autre ont une fonction nettement n\u00e9gative : en g\u00e9n\u00e9ral, ce qu&rsquo;elles veulent dire est align\u00e9e sur les consignes du Syst\u00e8me, et donc sans rapport, sinon accidentel, avec la v\u00e9rit\u00e9 ; cette r\u00e9f\u00e9rence n\u00e9gative reste tout de m\u00eame une r\u00e9f\u00e9rence, en permettant de situer la valeur de telle ou telle information par d\u00e9duction m\u00e9thodologique antagoniste, avant d&rsquo;envisager un jugement sur leur cr\u00e9dit intrins\u00e8que. Le reste de la recherche de la validit\u00e9 de l&rsquo;information constitue un processus complexe, o\u00f9 l&rsquo;arsenal personnel entre largement en ligne de compte (intuition haute, exp\u00e9rience, prise en compte des facteurs d&rsquo;influence d\u00e9termin\u00e9s par l&rsquo;exp\u00e9rience).<\/p>\n<\/p>\n<p><p>\t Le r\u00f4le fondamental jou\u00e9 de plus en plus par la psychologie et sa perception,  comme c&rsquo;est d&rsquo;ailleurs le cas dans cette information \u00e0 propos de laquelle nous d\u00e9battons. Est-il important que la perception fasse croire \u00e0 un retrait\/un effondrement US, ou importe-t-il plus d&rsquo;attendre d&rsquo;acter le constat de ce retrait\/cet effondrement, lorsqu&rsquo;il sera effectif ? (Si cet effondrement se produit, pr\u00e9cisent les prudents esprits rationnels, dont on peut souvent juger qu&rsquo;ils ne d\u00e9testent pas l&rsquo;influence am\u00e9ricaniste.) Faut-il se pr\u00e9occuper de la disparition in\u00e9luctable du malade d\u00e8s que le maladie est en phase finale d&rsquo;agonie, si l&rsquo;on per\u00e7oit cette phase finale, par diagnostic intuitif appuy\u00e9 sur nombre de facteurs g\u00e9n\u00e9raux, dont nombre d&rsquo;observations intuitives, ou vaut-il mieux attendre le faire-part et l&rsquo;enterrement  ? La presse-Syst\u00e8me, elle, choisit le faire-part et l&rsquo;enterrement, non sans avoir v\u00e9rifi\u00e9 ses sources et r\u00e9affirm\u00e9 la n\u00e9cessit\u00e9 de l&rsquo;objectivit\u00e9, conform\u00e9ment aux consignes du Syst\u00e8me  c&rsquo;est-\u00e0-dire qu&rsquo;elle ne nous dit plus rien de la v\u00e9rit\u00e9 qui nous importe, s&rsquo;en tenant \u00e0 l&rsquo;une ou l&rsquo;autre r\u00e9alit\u00e9 d&rsquo;apparat, ou apparence de r\u00e9alit\u00e9, si possible la plus proche du communiqu\u00e9 officiel. Bien entendu, dans cette approche compl\u00e8tement st\u00e9rile de l&rsquo;information, le facteur psychologique est compl\u00e8tement occult\u00e9, ignor\u00e9, discr\u00e9dit\u00e9, etc., dans la mesure o\u00f9 il constitue <em>per se<\/em> une attaque directe contre la construction d&rsquo;une r\u00e9alit\u00e9 conforme \u00e0 l&rsquo;attitude officielle. Cette attitude de la presse-Syst\u00e8me est pr\u00e9cieuse dans ce sens o\u00f9 elle nous indique avec une quasi-perfection un comportement absolument subversif, et, par cons\u00e9quent, une indication <em>a contrario<\/em> pour d\u00e9terminer la voie de la recherche de la v\u00e9rit\u00e9 de l&rsquo;information, qui doit n\u00e9cessairement tenir compte du facteur psychologique.<\/p>\n<\/p>\n<p><p>\tCes divers \u00e9l\u00e9ments confirment pour nous les conditions nouvelles de l&rsquo;information, apparues ces dix derni\u00e8res ann\u00e9es dans une \u00e9poque aux caract\u00e8res tr\u00e8s changeants et extr\u00eames, avec un syst\u00e8me de la communication d&rsquo;une puissance consid\u00e9rable mais d&rsquo;une ambigu\u00eft\u00e9 \u00e0 mesure. L&rsquo;abondance et l&rsquo;instabilit\u00e9 des r\u00e9f\u00e9rences impliquent qu&rsquo;il n&rsquo;existe plus de r\u00e9f\u00e9rence au sens strict du mot et de la fonction que ce mot recouvre. Les multiples r\u00e9alit\u00e9s manipul\u00e9es, fabriqu\u00e9es et trafiqu\u00e9es affaiblissent dramatiquement le concept de r\u00e9alit\u00e9 et rendent n\u00e9cessaire la recherche d&rsquo;un concept plus haut, le concept de v\u00e9rit\u00e9, o\u00f9 l&rsquo;intuition haute doit jouer un r\u00f4le consid\u00e9rable dans sa d\u00e9termination. Dans la m\u00eame logique, les facteurs constitutifs de cette v\u00e9rit\u00e9 s&rsquo;\u00e9largissent et se haussent, en faisant intervenir bien d&rsquo;autres \u00e9l\u00e9ments que les seuls faits, soumis aux m\u00eames soup\u00e7ons que les r\u00e9alit\u00e9s. Les facteurs de la psychologie et de la conviction y acqui\u00e8rent une place consid\u00e9rable.<\/p>\n<\/p>\n<p><p>\tDans le cas qui nous occupe, nous sommes confront\u00e9s \u00e0 un cas classique d&rsquo;opposition entre la r\u00e9alit\u00e9 (les USA ne se sont pas [encore] effondr\u00e9s <em>stricto sensu<\/em>) et une v\u00e9rit\u00e9 incontestable (la perception de nombre de personnages importants, dans des situations de d\u00e9cision, que <strong>tout se passe<\/strong> comme si les USA s&rsquo;effondraient). Nous estimons qu&rsquo;on doit appr\u00e9cier cela comme une information d&rsquo;une importance consid\u00e9rable, m\u00eame si elle ne figure pas dans la plupart des canaux habituels d&rsquo;information,  <strong>au moins<\/strong> parce que cette information indique qu&rsquo;un certain nombre de ces dirigeants vont prendre des d\u00e9cisions et suivre des politiques influenc\u00e9es par leur perception de la situation des USA. Cette sorte de d\u00e9marche est renforc\u00e9e par la situation d&rsquo;extr\u00eame subjectivit\u00e9 et d&rsquo;extr\u00eame instabilit\u00e9 qui accompagne les \u00e9valuations d&rsquo;autres faits connexes capables d&rsquo;influer sur la question d\u00e9battue, comme, par exemple, la r\u00e9elle capacit\u00e9 de la puissance militaire US qui est aujourd&rsquo;hui une r\u00e9f\u00e9rence absolument incertaine et variable,  entre le jugement quantitatif grossi\u00e8rement extatique des pro-am\u00e9ricanistes pathologiques, et le jugements qualitatif catastrophique sur l&rsquo;\u00e9tat de cette puissance.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 1er juillet 2011 \u00e0 11H10<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il y avait un sommet \u00e0 T\u00e9h\u00e9ran ce dernier week-end, qui r\u00e9unissait du beau monde : les Pakistanais, les Afghans, les Irakiens, les Soudanais. Officiellement, il s&rsquo;agissait d&rsquo;un sommet anti-terreur. Il en avait \u00e9t\u00e9 question, avant sa r\u00e9union, par l&rsquo;interm\u00e9diaire du chroniqueur ex-diplomate indien M K Bhadrakumar, le 23 juin 2011 sur ce site. Le&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3236,3015,2631,3311,3100,2773,2622,3379,3099,5899,3134,3045,3014,5201,5445],"class_list":["post-73135","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-afghanistan","tag-communication","tag-de","tag-fisk","tag-information","tag-iran","tag-la","tag-pakistan","tag-psychologie","tag-realite","tag-robert","tag-sommet","tag-systeme","tag-teheran","tag-verite"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73135"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73135\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}