{"id":73138,"date":"2011-07-02T11:19:24","date_gmt":"2011-07-02T11:19:24","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2011\/07\/02\/de-fukushima-a-los-alamos\/"},"modified":"2011-07-02T11:19:24","modified_gmt":"2011-07-02T11:19:24","slug":"de-fukushima-a-los-alamos","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2011\/07\/02\/de-fukushima-a-los-alamos\/","title":{"rendered":"De Fukushima \u00e0 Los Alamos"},"content":{"rendered":"<p><p>On sait, ou on doit le savoir, que d&rsquo;immenses incendies ravagent actuellement l&rsquo;Ouest et le Sud-Ouest des USA, avec notamment l&rsquo;implication des Etats du Texas, de l&rsquo;Arizona et du Nouveau Mexique. (Voir le texte de <em>TomDispartch.com<\/em> du <a href=\"http:\/\/www.tomdispatch.com\/blog\/175405\/\" class=\"gen\">16 juin 2011<\/a>.) Ces Etats sont par ailleurs touch\u00e9s par la s\u00e9cheresse, ceci (la s\u00e9cheresse) expliquant en bonne partie cela (les incendies), et le tout est directement connect\u00e9 d\u00e9sormais au ph\u00e9nom\u00e8ne du r\u00e9chauffement climatique. Un des aspects importants de ces incendies est leur p\u00e9n\u00e9tration dans le Nouveau Mexique et les menaces qu&rsquo;ils font peser d\u00e9sormais sur le laboratoire de Los Alamos, centre fondamental du d\u00e9veloppement du nucl\u00e9aire militaire US depuis la Deuxi\u00e8me Guerre mondiale. (C&rsquo;est bien s\u00fbr \u00e0 Los Alamos, o\u00f9 plane encore l&rsquo;ombre d\u00e9sol\u00e9e du visage de Robert Oppenheimer, que fut d\u00e9velopp\u00e9e la premi\u00e8re bombe atomique. Le laboratoire est de dimensions colossales puisqu&rsquo;il s&rsquo;agit d&rsquo;une v\u00e9ritable ville de 11.000 habitants, travaillant directement ou indirectement sur les mati\u00e8res nucl\u00e9aires.)<\/p>\n<\/p>\n<p><p>\t C&rsquo;est le <a href=\"http:\/\/edition.cnn.com\/2011\/US\/06\/27\/new.mexico.los.alamos\/index.html?\" class=\"gen\">27 juin 2011<\/a> (CNN.<em>News<\/em>) que fut signal\u00e9e cette menace contre le laboratoire. \u00ab<em>A raging wildfire near the Los Alamos National Laboratory in New Mexico has prompted the evacuation of more than 10,000 residents in the town as firefighters battle hot temperatures and high winds, authorities said Monday.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00bb<em>The fire near the lab has raised concerns about whether hazardous materials kept there are being adequately guarded. Authorities say there are. They have anticipated the problem of fire and they&rsquo;ve taken precautions, Sen. Jeff Bingaman of New Mexico told CNN Monday. The structures that are central to the operation of the laboratory are well protected.<\/em> [] <em>It was closed Monday to nonessential employees and will remain closed on Tuesday because of the risks presented by the fire<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Le <a href=\"http:\/\/news.blogs.cnn.com\/2011\/06\/29\/fire-chief-says-los-alamos-lab-is-safe-from-wildfire\/?iref=allsearch\" class=\"gen\">29 juin 2011<\/a> (toujours CNN.<em>News<\/em>), des d\u00e9clarations officielles \u00e9taient faites pour assurer que le laboratoire \u00e9tait d\u00e9sormais en s\u00e9curit\u00e9, dans tous les cas les mati\u00e8res sensibles qui s&rsquo;y trouvent, notamment les d\u00e9chets nucl\u00e9aires. \u00ab<em>We feel very comfortable that material is secure, Chief Doug Tucker said.<\/em> [] <em>Tucker said that the waste, which is stored in drums, are kept on a blacktop with no vegetation around and are safe from fire. In case the fire was to close in, firefighters were ready to use foam to ensure that nothing would be released into the environment, he said.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Divers articles, \u00e9videmment de sources ind\u00e9pendantes, affirment au contraire la persistance d&rsquo;une r\u00e9elle pr\u00e9occupation pour la s\u00e9curit\u00e9 des mati\u00e8res dangereuses \u00e0 Los Alamos. Le <a href=\"http:\/\/www.naturalnews.com\/z032871_wildfires_plutonium.html\" class=\"gen\">1er juillet 2011<\/a>, le site <em>NatureNews.com<\/em> publie un article dans ce sens, qui met en \u00e9vidence que le danger subsiste et m\u00eame grandit alors que l&rsquo;attitude officielle est \u00e9videmment de communiquer une <em>narrative<\/em> apaisante de l&rsquo;affaire. Les mesures prises (notamment les contre-feux r\u00e9alis\u00e9s autour des lieux de stockage pour \u00e9tablir des zones mortes o\u00f9 le feu principal n&rsquo;a plus d&rsquo;aliments v\u00e9g\u00e9taux) montrent \u00e9videmment une tr\u00e8s grande pr\u00e9occupation de la part des autorit\u00e9s.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Threats of radioactive disaster from what is shaping up to be the largest wildfire in the state&rsquo;s history are escalating, as heavy winds and plenty of dry brush have fueled flames to within 50 feet of New Mexico&rsquo;s Los Alamos National Laboratory (LANL), home of the first atomic bomb. Crews claim there are currently no fires burning on the lab&rsquo;s 36 square mile property, but the entire town of Los Alamos, population 11,000, has been evacuated, and the US Environmental Protection Agency (EPA) is now on radiation alert in the area.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb[T]<em>he current wildfire&rsquo;s proximity to the nuclear facility is particularly troubling because there are about 30,000 55-gallon drums of radioactive plutonium waste on the site that, according to some reports, are not particularly well-protected. The concern is that these drums will get so hot that they&rsquo;ll burst, said Joni Arends, executive director of Concerned Citizens for Nuclear Safety. That would put this toxic material into the plume. It&rsquo;s a concern for everybody.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>EPA is now monitoring for radiation the giant smoke plume that has been building and spreading across the area as a result of the fire. Because the nuclear facility itself has conducted countless nuclear experiments, some experts say that nuclear-contaminated soil, in addition to the waste drums, could also be disrupted by the fire, releasing old, but deadly, radioactive waste into the plume.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>LANL officials claim that everything is under control, and that the nuclear waste drums are at a low risk of catching fire or exploding from high heat because several canyons allegedly separate them from the current location of the fire. Fire officials have also been burning out dead zone areas in between the fire and the plant in the hopes that doing so will eliminate the brush fuel needed by the fire to spread any closer.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tBien \u00e9videmment, une interpr\u00e9tation symbolique des \u00e9v\u00e9nements s&rsquo;impose dans ce cas, mettant en parall\u00e8le <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_fukushima_et_le_reste_ddecrisis_13_04_2011.html\" class=\"gen\">Fukushima<\/a> et Los Alamos. Il y a la m\u00eame provenance des catastrophes naturelles, avec une tr\u00e8s forte probabilit\u00e9 d&rsquo;interf\u00e9rence du r\u00e9chauffement climatique. Il y a la transformation, effective ou mena\u00e7ante, de catastrophes naturelles en catastrophes nucl\u00e9aires. Il y a la dualit\u00e9 antagoniste et hautement symbolique entre le nucl\u00e9aire civil (Fukushima) et le nucl\u00e9aire militaire (Los Alamos), et les lieux historiques antagonistes (Los Alamos, o\u00f9 fut produite la bombe atomique qui fut largu\u00e9e sur le Japon en ao\u00fbt 1945, sur Hiroshima et sur Nagasaki,  seules attaques nucl\u00e9aires effectives de l&rsquo;histoire). Ajouterait-on qu&rsquo;il y a la m\u00eame attitude des autorit\u00e9s qui cherchent essentiellement \u00e0 dissimuler la v\u00e9ritable nature de la situation, et \u00e0 la banaliser pour emp\u00eacher que cette situation devienne un foyer (!) de critiques et de mises en cause politiques.<\/p>\n<\/p>\n<p><p>\tL&rsquo;incendie de Los Alamos contribue \u00e0 l&rsquo;\u00e9largissement en cours du spectre des interpr\u00e9tations de cette cat\u00e9gorie nouvelle, fondamentalement eschatologique et fondamentalement li\u00e9e aux activit\u00e9s du Syst\u00e8me, des crises m\u00ealant un aspect naturel et un aspect sociologique, politique et technologique, tous ces aspects se nourrissant les uns les autres. On y ajoute bien entendu la dimension eschatologique propre au nucl\u00e9aire, une dimension eschatologique catastrophique cr\u00e9\u00e9e par le <em>sapiens<\/em> lui-m\u00eame. Le cocktail est redoutable, le pire qu&rsquo;on puisse imaginer, et met en \u00e9vidence la marche irr\u00e9sistible de l&rsquo;eschatologisation des crises,  et \u00e0 quelle vitesse ! Il est acquis que la plupart des catastrophes naturelles d&rsquo;importance vont d\u00e9sormais \u00eatre directement per\u00e7ues comme connect\u00e9es \u00e0 la crise climatique, dans le cadre de la catastrophe environnementale ; elles sont et seront directement li\u00e9es aux activit\u00e9s et \u00e0 la crise du Syst\u00e8me, conduisant aussit\u00f4t \u00e0 une dimension politique, sinon id\u00e9ologique, avec des mouvements de contestation, sinon de r\u00e9volte. La connexion est d\u00e9sormais fermement \u00e9tablie, donnant \u00e0 la crise du Syst\u00e8me et de notre contre-civilisation l&rsquo;ampleur et l&rsquo;universalit\u00e9 qu&rsquo;elle m\u00e9rite.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMise en ligne le 2 juillet 2011 \u00e0 11H19<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>On sait, ou on doit le savoir, que d&rsquo;immenses incendies ravagent actuellement l&rsquo;Ouest et le Sud-Ouest des USA, avec notamment l&rsquo;implication des Etats du Texas, de l&rsquo;Arizona et du Nouveau Mexique. (Voir le texte de TomDispartch.com du 16 juin 2011.) Ces Etats sont par ailleurs touch\u00e9s par la s\u00e9cheresse, ceci (la s\u00e9cheresse) expliquant en bonne&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4766,3409,11258,7548,10164,3004],"class_list":["post-73138","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-atomique","tag-bombe","tag-catastrophes","tag-eschatologie","tag-eschatologisation","tag-nucleaire"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73138"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73138\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}