{"id":73169,"date":"2012-05-30T12:24:24","date_gmt":"2012-05-30T12:24:24","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/05\/30\/un-instant-magique-de-la-verite-du-monde\/"},"modified":"2012-05-30T12:24:24","modified_gmt":"2012-05-30T12:24:24","slug":"un-instant-magique-de-la-verite-du-monde","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/05\/30\/un-instant-magique-de-la-verite-du-monde\/","title":{"rendered":"Un \u201cinstant magique\u201d de la v\u00e9rit\u00e9 du monde"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Un instant magique de la v\u00e9rit\u00e9 du monde<\/h3>\n<\/p>\n<p><p>\tLes \u00e9volutions diplomatiques autour du massacre de Houla valent bien les \u00e9volutions des circonstances du m\u00eame massacre (voir ce <a href=\"http:\/\/www.dedefensa.org\/article-_volution_caract_ristique_des_circonstances_du_massacre_30_05_2012.html\" class=\"gen\">30 mai 2012<\/a>). Elles sont particuli\u00e8rement significatives du c\u00f4t\u00e9 am\u00e9ricaniste, notamment par les circonvolutions <strong>int\u00e9rieures<\/strong> de la position officielle, montrant bien que, pour Obama, la Syrie (comme l&rsquo;Iran) est d&rsquo;abord une bataille int\u00e9rieure. (Les \u00e9lections pr\u00e9sidentielles, certes.) Dans ce cas, et sans surprise pour nous, la coh\u00e9rence diplomatique, la coh\u00e9sion du gouvernement Obama, la v\u00e9rit\u00e9 de la situation en prennent pour leurs grades souvent brillants. Il s&rsquo;agit de manuvrer, rien d&rsquo;autre, pour \u00e9viter de pr\u00eater le flanc \u00e0 quelque critique que ce soit. En m\u00eame temps, on retrouve, comme par effet-miroir, tous les caract\u00e8res des incoh\u00e9rences du bloc BAO<\/p>\n<\/p>\n<p><p>\t Le <a href=\"http:\/\/www.guardian.co.uk\/world\/2012\/may\/28\/houla-massacre-us-military-warns\" class=\"gen\">28 mai 2012<\/a>, le <em>Guardian<\/em> se r\u00e9jouissait de l&rsquo;interview \u00e0 <em>Fox.News<\/em> du g\u00e9n\u00e9ral Dempsey, pr\u00e9sident du comit\u00e9 des chefs d&rsquo;\u00e9tat-major. Le g\u00e9n\u00e9ral Dempsey prenait une position notablement diff\u00e9rente, sinon <strong>contraire<\/strong>, \u00e0 celle qu&rsquo;il avait soutenue avec son commandant de th\u00e9\u00e2tre, le commandant de CENTCOM, au d\u00e9but de mars, lorsque ces chefs militaires annonc\u00e8rent qu&rsquo;une action militaire en Syrie apparaissait hautement probl\u00e9matique. (Voir le <a href=\"http:\/\/www.dedefensa.org\/article-les_etoiles_us_ne_brillent_guere_d_enthousiasme_belliciste_08_03_2012.html\" class=\"gen\">8 mars 2012<\/a> et encore le <a href=\"http:\/\/www.dedefensa.org\/article-le_pentagone_realise_les_limites_de_sa_puissance_08_03_2012.html\" class=\"gen\">8 mars 2012<\/a>.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>General Martin Dempsey, the chairman of the joint chiefs of staff, said that following the UN security council&rsquo;s condemnation of the slaughter  in which more than 100 people were killed, many of them children  there needed to be increased diplomatic pressure on Damascus. But he added that the US would be prepared to act militarily if it was asked to do so. There is always a military option, he told Fox News. You&rsquo;ll always find military leaders to be somewhat cautious about the use of force, because we&rsquo;re never entirely sure what comes out on the other side. But that said, it may come to a point with Syria because of the atrocities.<\/em> []<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Dempsey was asked if there is a place in Syria for the Libya model, in which Nato led a bombing campaign ostensibly to protect civilian areas but which swiftly evolved into action directly in support of the rebels. I&rsquo;m sure there are some things that we did in Libya that could be applicable in a Syria environment or Syria scenario. But I&rsquo;m very cautious about templates, he said.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tQuelle version accepter ? Celle de mars, o\u00f9 l&rsquo;intervention semble illusoire et tr\u00e8s risqu\u00e9e, ou celle d&rsquo;aujourd&rsquo;hui ? Pour r\u00e9pondre, on comparera le canal de ces d\u00e9clarations : devant le Congr\u00e8s, Dempsey d\u00e9posait sous serment, avec son commandant de CENTCOM ; avec <em>FoxNews<\/em>, ce n&rsquo;est qu&rsquo;une interview Au reste, le <em>Guardian<\/em> nous renseigne obligeamment lorsqu&rsquo;il place, entre son rapport des d\u00e9clarations de Dempsey, des remarques concernant l&rsquo;obligation tactique pour Obama de para\u00eetre dur, ou pr\u00eat \u00e0 l&rsquo;\u00eatre s&rsquo;il le faut, pour faire pi\u00e8ce aux critiques de son possible adversaire r\u00e9publicain, le s\u00e9millant Mitt Romney qui r\u00e9p\u00e8te obligeamment ce que lui soufflent ses conseillers <em>neocons<\/em>. \u00ab<em>Romney accused Obama of weakness and disparaged his support for efforts by the former UN secretary general, Kofi Annan, to revive a failing peace plan. He said Washington should instead arm opposition groups. After nearly a year and a half of slaughter, it is far past time for the United States to begin to lead and put an end to the Assad regime. President Obama can no longer ignore calls from congressional leaders in both parties to take more assertive steps, he said.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t A la lumi\u00e8re de ce qui pr\u00e9c\u00e8de, on admirera la gr\u00e2ce de la courbe \u00e0 180\u00b0 que repr\u00e9sente la d\u00e9claration du porte-parole de la Maison-Blanche concernant l&rsquo;hypoth\u00e8se d&rsquo;une intervention militaire en Syrie, ce <a href=\"http:\/\/en.rian.ru\/world\/20120530\/173744640.html\" class=\"gen\">30 mai 2012<\/a> (dans <em>Russia Today<\/em>), deux jours apr\u00e8s l&rsquo;intervention de Dempsey. Une militarisation du conflit ? Hypoth\u00e8se absurde, \u00e0 rejeter Ce qui est finalement assez ironique, c&rsquo;est que cette d\u00e9claration commence, comme un \u00e9cho pr\u00e9cis\u00e9ment ironique, par la m\u00eame id\u00e9e pr\u00e9cis\u00e9ment que la d\u00e9claration du g\u00e9n\u00e9ral Dempsey (Il y a toujours une option militaire, L&rsquo;intervention militaire est toujours une option),  pour arriver \u00e0 nous dire le contraire. <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Military intervention in Syria is always an option but at this time it is not the right course as it would lead to greater chaos, greater carnage, U.S. White House spokesman Jay Carney said. We do not believe that militarization, further militarization of the situation in Syria at this point is the right course of action, Carney told a daily press briefing.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>President Barack Obama administration&rsquo;s top spokesman said the United States intends to keep working with the UN Security Council and UN peace envoy Kofi Annan to find ways to pressure Syrian leader Bashar al-Assad to end his military crackdown on citizens and resign from his post. Carney also called this weekend&rsquo;s massacre in the Syrian town of Houla a horrifying testament to this regime&rsquo;s depravity.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t On ajoutera \u00e0 ce morceau de choix l&rsquo;intervention du d\u00e9partement d&rsquo;\u00c9tat, avec une d\u00e9claration de Victoria Nuland, la porte-parole. Manifestement, le d\u00e9partement d&rsquo;\u00c9tat a pour mission, sur la m\u00eame ligne que la Maison-Blanche (pas d&rsquo;intervention \u00e9trang\u00e8re, soutien du plan Annan), d&rsquo;amener la Russie dans le camp du bloc BAO. (Ou bien de lui rappeler son <a href=\"http:\/\/www.dedefensa.org\/article-hyst_ries_pour_nombre_de_massacres_29_05_2012.html\" class=\"gen\">accord secret<\/a> selon <em>DEBKAFiles<\/em> ?) Son raisonnement est simple : les Russes veulent une enqu\u00eate circonstanci\u00e9e sur le massacre, bravo ; ils nous rejoindront donc, parce que cette enqu\u00eate montrera la responsabilit\u00e9 d&rsquo;Assad (\u00ab<em>We are appreciative of the fact that the Russians are willing to have a full investigation, because we think it&rsquo;s undisputable what that investigation is going to show It&rsquo;s going to show that these were regime-sponsored thugs who went into villages, went into homes and killed children at point-blank range and their parents, and that they &#8211; responsibility goes right back to the Assad regime. So you know, from that perspective, is this going to be a turning point in Russian thinking? We hope so.<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tCe don de double vue (r\u00e9sultat de l&rsquo;enqu\u00eate connu par avance) est int\u00e9ressant autant que troublant. On fait cette observation en rappelant que les USA soutenaient la premi\u00e8re version anti-Assad du massacre, en provenance des rebelles (les victimes tu\u00e9es par les obus des chars d&rsquo;Assad), avant de s&rsquo;en remettre \u00e0 la seconde version (des milices d&rsquo;Assad massacrant des villageois dans leurs villages, les \u00e9gorgeant, tirant \u00e0 bout portant par balles, etc.). A chaque fois, ils savent \u00e0 l&rsquo;avance le r\u00e9sultat d&rsquo;une hypoth\u00e9tique enqu\u00eate<\/p>\n<\/p>\n<p><p>\t Il n&#8217;emp\u00eache,  les vux de Noland sur un rapprochement de la Russie des pays du bloc BAO rencontrent un certain flottement du c\u00f4t\u00e9 russe, l\u00e0 aussi dans les interpr\u00e9tations de certaines d\u00e9clarations russes, faites par le c\u00f4t\u00e9 russe. On en entend l&rsquo;\u00e9cho, m\u00eame dans un texte de <em>Russia Today<\/em>, du <a href=\"http:\/\/www.rt.com\/news\/massacre-syria-intervention-europe-544\/\" class=\"gen\">30 mai 2012<\/a>, qui met en \u00e9vidence un possible changement radical de la position russe (\u00ab<em>The weekend massacre in Houla seems to have become a turning point for Russia&rsquo;s rhetoric on the Syrian crisis<\/em>\u00bb), en citant une d\u00e9claration de Lavrov apr\u00e8s sa rencontre avec l&rsquo;Anglais Hague,  d\u00e9claration qu&rsquo;on ne trouve pas dans le rapport de Tass du <a href=\"http:\/\/en.rian.ru\/russia\/20120528\/173715314.html\" class=\"gen\">28 mai 2012<\/a>,  malgr\u00e9 son aspect sensationnel quoique \u00e9galement curieux (\u00ab<em>The government bears the main responsibility for what is going on Any government in any country bears responsibility for the security of its citizens<\/em>\u00bb, aurait donc dit Lavrov : comment le gouvernement syrien peut-il assurer la s\u00e9curit\u00e9 de ses citoyens s&rsquo;il ne peut intervenir l\u00e0 o\u00f9 il veut et comme il veut, lorsqu&rsquo;il juge cette s\u00e9curit\u00e9 menac\u00e9e, alors que de tels mouvements lui sont interdits ?). D&rsquo;ailleurs, en conclusion de sa d\u00e9p\u00eache, RT rend compte de l&rsquo;incertitude compl\u00e8te o\u00f9 l&rsquo;on se trouve dans la d\u00e9termination de la responsabilit\u00e9 du massacre, malgr\u00e9 le don de double vue de Noland, ce qui rend d&rsquo;autant plus \u00e9trange ce qui est dit pr\u00e9c\u00e9demment de l&rsquo;attitude de la Russie.<\/p>\n<\/p>\n<p><p>\tLa m\u00eame attitude russe est mise en \u00e9vidence par <em>DEBKAFiles<\/em>,  dr\u00f4le de rencontre avec RT,  dans un rapport du <a href=\"http:\/\/www.debka.com\/article\/22038\/Russian-arms-ship-turned-away-from-Syria-President-Putin's-first-misstep-\" class=\"gen\">29 mai 2012<\/a>, plein d&rsquo;impr\u00e9cations inhabituelles (pour <em>DEBKAFiles<\/em>) contre le plus grand tyran de tous les temps du moment. Pour <em>DEBKAFiles<\/em>, du moins en d\u00e9but de texte, la partie est jou\u00e9e, et Poutine manuvre pour se d\u00e9sengager. \u00ab<em>Lavrov tried to save his government&rsquo;s reputation by declaring out of the blue that Moscow no longer backs Bashar Assad and his regime and fully endorses the UN envoy Kofi Annan&rsquo;s mission.<\/em>\u00bb Bon, <em>DEBKAFiles<\/em> brode un peu en pr\u00e9sentant cela comme un \u00e9v\u00e9nement extraordinaire : Lavrov a dit que la premi\u00e8re priorit\u00e9 \u00e9tait de r\u00e9tablir l&rsquo;ordre plut\u00f4t que de soutenir l&rsquo;un ou l&rsquo;autre, ce qui a toujours \u00e9t\u00e9 la politique officielle russe, et qu&rsquo;il soutenait le plan Annan, ce que la Russie a fait <a href=\"http:\/\/www.dedefensa.org\/article-syrie_kofi_annan_entre_en_scene_25_02_2012.html\" class=\"gen\">d\u00e8s l&rsquo;origine<\/a>, ayant \u00e9t\u00e9 un des premiers pays \u00e0 susciter,  contre le bloc BAO au d\u00e9part,  la mission Annan. D&rsquo;ailleurs, la fin du rapport de <em>DEBKAFiles<\/em>, qui cite le cas d&rsquo;un bateau russe plein d&rsquo;armes pour la Syrie qui les garde \u00e0 bord pour l&rsquo;instant, montre plut\u00f4t un Poutine en attente qu&rsquo;un Poutine l\u00e2chant Assad.<\/p>\n<\/p>\n<p><p>\t  Et d&rsquo;ailleurs, parlant de la mission Annan que tout le monde soutient, alors que presque tout le monde condamne la Syrie de Assad, que penser du citoyen international Kofi Annan qui d\u00e9clare (<em>PressTV.com<\/em>, le <a href=\"http:\/\/www.presstv.ir\/detail\/2012\/05\/29\/243725\/syria-cooperating-with-un-annan-says\/\" class=\"gen\">29 mai 2012<\/a>), apr\u00e8s avoir rencontr\u00e9 le plus grand tyran de tous les temps&rsquo; du moment,  rien de moins que ceci, enfer et damnation : \u00ab<em>In my meeting with the president, I expressed appreciation for the cooperation that the Syrian government had extended to the UN, enabling us to deploy the military observers quickly<\/em> [] <em>The Security Council has made clear the need for these killings to be investigated and for those responsible to be held accountable. I also note that the government of Syria is organizing its own investigation and that is very encouraging.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Il y a aussi les comp\u00e8res europ\u00e9ens de la tragi-com\u00e9die, ou trag\u00e9die-bouffe, qu&rsquo;est la Syrie. Un rapport de <em>EUObserver<\/em> du <a href=\"http:\/\/euobserver.com\/24\/116400-\" class=\"gen\">29 mai 2012<\/a> annonce que rien, absolument rien n&rsquo;a chang\u00e9 dans la politique europ\u00e9enne vis-\u00e0-vis de la Syrie, qui reste dans une prudente expectative, apr\u00e8s comme avant le massacre. Le rapport RT cit\u00e9 plus haut parle au contraire d&rsquo;une volont\u00e9 quasi-g\u00e9n\u00e9rale des Europ\u00e9ens d&rsquo;en d\u00e9coudre,  <em>Saber-rattling in Europe<\/em> ; d&rsquo;accord, mais o\u00f9 est pr\u00e9cis\u00e9ment le sabre ? Quelles forces la puissante Europe pr\u00e9tend-elle aligner pour d\u00e9barquer au Levant et r\u00e9tablir l&rsquo;ordre au profit des islamistes qui se sont r\u00e9v\u00e9l\u00e9s comme des anges d\u00e9mocrates ? Fort intelligemment pour ses d\u00e9buts de type normal, Hollande cite Bernard-Henry Levy ; nous voil\u00e0 rassur\u00e9s, la France ne perdra pas si vite sa posture exceptionnellement exceptionnelle. Le ministre belge des affaires \u00e9trang\u00e8res, l&rsquo;excellent Didier Randers, de Li\u00e8ge la cit\u00e9 ardente, annonce que la Belgique participera \u00e0 toute exp\u00e9ditions contre la Syrie ; touchante Belgique, qui n&rsquo;aime rien tant que les exp\u00e9ditions de la communaut\u00e9 internationale d\u00e9j\u00e0 bien form\u00e9es et assur\u00e9es, auxquelles elle pourrait se joindre r\u00e9solument. Mais o\u00f9 se trouve cette communaut\u00e9 internationale arm\u00e9e jusqu&rsquo;aux dents ? Ont-ils donc entendu le porte-parole du pr\u00e9sident Obama  ?<\/p>\n<\/p>\n<p><p>\tAinsi sommes-nous au fond du shaker agit\u00e9 vigoureusement pour nous donner un cocktail de divers d\u00e9sordres rehauss\u00e9s d&rsquo;un zeste consid\u00e9rable de chaos. Il n&rsquo;y a plus aucune coh\u00e9rence ni la moindre coh\u00e9sion, ni la moindre ligne directrice dans ce tourbillon. Les relations internationales et la diplomatie qui pr\u00e9tend aller avec se trouvent aujourd&rsquo;hui dans un <strong>instant magique<\/strong> o\u00f9 le d\u00e9sordre dans lequel elles sont plong\u00e9es parvient enfin \u00e0 atteindre le degr\u00e9 de d\u00e9sordre qu&rsquo;on observe en Syrie, sur le terrain.<\/p>\n<\/p>\n<p><p>\tOn s&rsquo;abstiendra donc de toute consid\u00e9ration politique, encore moins d&rsquo;hypoth\u00e8ses strat\u00e9giques et de prospective g\u00e9ostrat\u00e9gique. Nous nous contenterons plut\u00f4t d&rsquo;observer qu&rsquo;on se trouve \u00e0 un point o\u00f9 les pressions du Syst\u00e8me pour conduire une politique de surpuissance nihiliste assortie de son prolongement autodestructeur donnent un r\u00e9sultat exceptionnel de clart\u00e9 : la clart\u00e9 du d\u00e9sordre qui se r\u00e9v\u00e8le en cet instant comme la r\u00e8gle universelle de ce monde en chute acc\u00e9l\u00e9r\u00e9e. Bien entendu, tout cela \u00e9voluera dans les prochains jours, et l&rsquo;affaire se d\u00e9cantera \u00e9videmment, et l&rsquo;on aura l&rsquo;impression de se r\u00e9tablir. Mais l\u00e0, en cet instant, nous avons la r\u00e9v\u00e9lation de la paradoxale structure de d\u00e9sordre (structure et d\u00e9sordre ensemble, miracle-Syst\u00e8me) qui est aujourd&rsquo;hui la substance m\u00eame des relations internationales. Fixons cet <strong>instant magique<\/strong> dans notre m\u00e9moire, avant qu&rsquo;une certaine dynamique de contr\u00f4le et de coh\u00e9rence semble reprendre le dessus, car ce n&rsquo;est <strong>rien<\/strong> d&rsquo;autre qu&rsquo;un <strong>instant de v\u00e9rit\u00e9<\/strong>,  en ce sens que cet instant nous r\u00e9v\u00e8le, l&rsquo;espace d&rsquo;un instant, la v\u00e9rit\u00e9 de la situation du monde.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 30 mai 2012 \u00e0 12H26<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un instant magique de la v\u00e9rit\u00e9 du monde Les \u00e9volutions diplomatiques autour du massacre de Houla valent bien les \u00e9volutions des circonstances du m\u00eame massacre (voir ce 30 mai 2012). Elles sont particuli\u00e8rement significatives du c\u00f4t\u00e9 am\u00e9ricaniste, notamment par les circonvolutions int\u00e9rieures de la position officielle, montrant bien que, pour Obama, la Syrie (comme l&rsquo;Iran)&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4270,3934,11461,3356,398,3203,14853,2830,916,14857,2730,11131,3867,3014],"class_list":["post-73169","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-autodestruction","tag-chaos","tag-debka","tag-desordre","tag-europe","tag-hollande","tag-houla","tag-lavrov","tag-poutine","tag-randers","tag-russie","tag-surpuissance","tag-syrie","tag-systeme"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73169","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73169"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73169\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73169"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73169"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73169"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}