{"id":73185,"date":"2012-06-07T13:47:32","date_gmt":"2012-06-07T13:47:32","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/06\/07\/la-deroute-des-usa-se-poursuit-en-amerique-du-sud\/"},"modified":"2012-06-07T13:47:32","modified_gmt":"2012-06-07T13:47:32","slug":"la-deroute-des-usa-se-poursuit-en-amerique-du-sud","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/06\/07\/la-deroute-des-usa-se-poursuit-en-amerique-du-sud\/","title":{"rendered":"La d\u00e9route des USA se poursuit en Am\u00e9rique du Sud"},"content":{"rendered":"<p><h2 class=\"common-article2\">La d\u00e9route des USA se poursuit en Am\u00e9rique du Sud<\/h2>\n<\/p>\n<p><p>\tL&rsquo;agence chinoise Xinhua a publi\u00e9 le <a href=\"http:\/\/french.news.cn\/monde\/2012-06\/06\/c_131634802.htm\" class=\"gen\">6 juin<\/a> un article signalant le retrait de quatre pays sud-am\u00e9ricains  le Venezuela, la Bolivie, le Nicaragua et l&rsquo;Equateur  du Trait\u00e9 interam\u00e9ricain d&rsquo;assistance r\u00e9ciproque (TIAR), un accord h\u00e9misph\u00e9rique de d\u00e9fense mutuelle sign\u00e9 en 1947 connu \u00e9galement sous le nom de Trait\u00e9 de Rio. Cette annonce a \u00e9t\u00e9 faite dans le cadre de la 42\u00e8me Assembl\u00e9e g\u00e9n\u00e9rale de l&rsquo;Organisation des Etats am\u00e9ricains (OEA), qui s&rsquo;est cl\u00f4tur\u00e9e mardi dans la ville bolivienne de Cochabamba. <\/p>\n<\/p>\n<p><p>\tLe motif ? La guerre des Malouines qui opposa l&rsquo;Argentine au Royaume-Uni durant laquelle les USA apport\u00e8rent leur soutien au Royaume-Uni au lieu de soutenir l&rsquo;Argentine.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Dans leur d\u00e9claration, les quatre pays ont indiqu\u00e9 que le Trait\u00e9 de Rio regroupant 22 membres avait \u00e9t\u00e9 cr\u00e9\u00e9 comme un m\u00e9canisme de d\u00e9fense collective du continent, soulignant que ce trait\u00e9 avait cependant d\u00e9montr\u00e9 ses limites lorsque la Grande-Bretagne avait attaqu\u00e9 l&rsquo;Argentine en 1982 dans la tentative de reconqu\u00e9rir les \u00eeles Malouines (\u00eeles Falkland pour la Grande-Bretagne).<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Un pays membre du Trait\u00e9 de Rio a \u00e9paul\u00e9 l&rsquo;attaque (contre l&rsquo;Argentine), ont-ils relev\u00e9, faisant allusion aux Etats-Unis. Les quatre pays en question ont d\u00e9cid\u00e9 de se retirer du Trait\u00e9, arguant que les Etats-Unis n&rsquo;\u00e9taient plus dignes d&rsquo;\u00eatre membre de cette organisation r\u00e9gionale.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tA l&rsquo;\u00e9poque (comme aujourd&rsquo;hui) les USA \u00e9taient partag\u00e9s entre deux trait\u00e9s : celui du Rio et celui de l&rsquo;OTAN qui les liaient aux deux protagonistes du conflit. Certes dans les deux cas, la r\u00e9daction de l&rsquo;article 5 pr\u00e9cise que chaque pays signataire est libre de choisir la forme de soutien qu&rsquo;il apporte au pays agress\u00e9 (de la simple condamnation verbale \u00e0 l&rsquo;intervention militaire). Mais de l\u00e0 \u00e0 prendre le parti d&rsquo;un des deux camps et contrevenir \u00e0 ses obligations envers l&rsquo;autre, il y a un gouffre, gouffre qui n&rsquo;importait gu\u00e8re \u00e0 l&rsquo;\u00e9poque quand la puissance des USA et le contexte de guerre froide \u00e9taient suffisants pour masquer ces entorses au droit international. Mais aujourd&rsquo;hui la puissance des USA a suffisamment diminu\u00e9 pour que resurgissent ces fant\u00f4mes du pass\u00e9. <\/p>\n<\/p>\n<p><p>\tClairement la crise des Malouines r\u00e9activ\u00e9e par la pr\u00e9sidente argentine, Mme Cristina Fernandez de Kirchner, au demeurant largement soutenue en Am\u00e9rique du Sud comme \u00e9voqu\u00e9 ici le <a href=\"http:\/\/www.dedefensa.org\/article-l_axe_evita-mossadegh_21_04_2012.html\" class=\"gen\">21 avril dernier<\/a>, continue \u00e0 se d\u00e9velopper. Moins de deux mois apr\u00e8s le d\u00e9sastreux <a href=\"http:\/\/www.dedefensa.org\/article-constat_de_d_route_et_vertu_de_bho_17_04_2012.html\" class=\"gen\">Sommet des Am\u00e9riques<\/a>, une nouvelle \u00e9tape vient d&rsquo;\u00eatre franchie avec le retrait des quatre pays membre de l&rsquo;Alliance bolivarienne pour les Am\u00e9riques (ALBA). Cette crise continue donc \u00e0 se d\u00e9velopper \u00e0 un rythme \u00e9lev\u00e9 et met en lumi\u00e8re ce th\u00e8me de d\u00e9sint\u00e9gration des USA et du Syst\u00e8me : les engagements internationaux multiples et contradictoires.<\/p>\n<\/p>\n<p><p>\tLes USA sont-ils contents que les quatre membres de l&rsquo;ALBA leur simplifient la t\u00e2che en prenant l&rsquo;initiative de torpiller l&rsquo;un des trait\u00e9s ? Rien n&rsquo;est moins s\u00fbr. De m\u00eame il est m\u00eame probable qu&rsquo;ils n&rsquo;aient toujours pas accept\u00e9 que l&rsquo;Organisation de Coop\u00e9ration de Shanga\u00ef   qui se r\u00e9unit actuellement  leur ait refus\u00e9 le statut d&rsquo;observateur qu&rsquo;elle vient tout juste d&rsquo;accorder <a href=\"http:\/\/french.news.cn\/chine\/2012-06\/07\/c_131637373.htm\" class=\"gen\">\u00e0 l&rsquo;Afghanistan<\/a>. Pourtant, ces d\u00e9cisions et refus sont autant de limites salutaires qui leur permettant de librement tenir ce discours agressif. La logique du Syst\u00e8me est par nature incapable d&rsquo;accepter toute limite.<\/p>\n<\/p>\n<p>\n<p class=\"signature\"><em>Bilbo<\/em><\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La d\u00e9route des USA se poursuit en Am\u00e9rique du Sud L&rsquo;agence chinoise Xinhua a publi\u00e9 le 6 juin un article signalant le retrait de quatre pays sud-am\u00e9ricains le Venezuela, la Bolivie, le Nicaragua et l&rsquo;Equateur du Trait\u00e9 interam\u00e9ricain d&rsquo;assistance r\u00e9ciproque (TIAR), un accord h\u00e9misph\u00e9rique de d\u00e9fense mutuelle sign\u00e9 en 1947 connu \u00e9galement sous le nom&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[2947,8842,2651,9333,3300],"class_list":["post-73185","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-amerique","tag-bilbo","tag-du","tag-malouines","tag-sud"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73185","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73185"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73185\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73185"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73185"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73185"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}