{"id":73191,"date":"2012-06-11T06:38:28","date_gmt":"2012-06-11T06:38:28","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/06\/11\/la-raison-devenue-idiote-utile-de-laffectivite\/"},"modified":"2012-06-11T06:38:28","modified_gmt":"2012-06-11T06:38:28","slug":"la-raison-devenue-idiote-utile-de-laffectivite","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/06\/11\/la-raison-devenue-idiote-utile-de-laffectivite\/","title":{"rendered":"La raison devenue \u201cidiote utile\u201d de l&rsquo;affectivit\u00e9"},"content":{"rendered":"<p><h2 class=\"titleset_a.deepblue\" style=\"color:#0f3955;font-size:2em;\">La raison devenue \u00ab\u00a0idiote utile\u00a0\u00bb de l&rsquo;affectivit\u00e9<\/h2>\n<\/p>\n<p><p>11 juin 2012 &ndash; Les deux ont coutume de ne pas s&rsquo;aimer beaucoup, comme deux vieilles <em>stars<\/em> jalouses de leur gloire ancienne. Il n&#8217;emp\u00eache, sur <strong>ce point fondamental de la forme<\/strong> de la politique ext\u00e9rieure US, des relations internationales \u00e0 l&rsquo;aune de cette monstruosit\u00e9 qu&rsquo;est le bloc am\u00e9ricaniste-europ\u00e9annistes (bloc BAO), Zbigniew Brzezinski et Henry Kissinger, vieux routiers de la <em>realpolitik<\/em> pure et dure, sont compl\u00e8tement d&rsquo;accord&hellip; Donc, apr\u00e8s <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-kissinger_le_principe_et_le_d_sordre_du_monde_05_06_2012.html\">Kissinger<\/a>, voici Brzezinski.<\/p>\n<\/p>\n<p><p>&hellip;Qu&rsquo;on nous pardonne, d&rsquo;ailleurs, si ce fut avant : l&rsquo;intervention de Brzezinski pr\u00e9c\u00e8de celle de Kissinger du 2 juin 2012, mais ce n&rsquo;est qu&rsquo;en lisant un rapport de <em>PressTV.com<\/em> du <a class=\"gen\" href=\"http:\/\/www.presstv.ir\/detail\/2012\/06\/07\/245028\/brzezinski-dont-be-emotional-on-syria\/\">7 juin 2012<\/a> que nous sommes revenus \u00e0 l&rsquo;\u00e9mission <em>Morning Joe<\/em> de MSNBC, o&ugrave; Brzezinski \u00e9tait un des invit\u00e9s, le <a class=\"gen\" href=\"http:\/\/dailycaller.com\/2012\/05\/30\/zbigniew-brzezinski-syrian-conflict-not-as-horrible-or-as-dramatic-as-it-is-portrayed\/#ixzz1x7rQPANs\">30 mai 2012<\/a>. Nous ne pensons certainement pas que le nouveau massacre en Syrie, celui d&rsquo;un village proche de la ville de Hama, change quoi que ce soit aux opinions exprim\u00e9es par les deux hommes, sinon pour les renforcer encore&hellip;<\/p>\n<\/p>\n<p><p>Quoi qu&rsquo;il en soit, les deux r\u00e9agissent aux r\u00e9actions de \u00ab\u00a0la communaut\u00e9 internationale\u00a0\u00bb, <em>dito<\/em> du bloc BAO, aux \u00e9v\u00e8nements de Syrie. Si nous employons ce terme de \u00ab\u00a0communaut\u00e9 internationale\u00a0\u00bb, c&rsquo;est \u00e0 dessein, car il permet d&rsquo;illustrer le probl\u00e8me que nous voulons traiter&hellip; Le bloc BAO s&rsquo;arroge \u00e0 lui-m\u00eame cette personnalit\u00e9 implicitement per\u00e7ue comme vertueuse, &ndash; la \u00ab\u00a0communaut\u00e9 internationale\u00a0\u00bb, &ndash; parce qu&rsquo;il attend de cette fiction, &ndash; le bloc BAO n&rsquo;est pas cette chose insaisissable qu&rsquo;est la \u00ab\u00a0communaut\u00e9 internationale\u00a0\u00bb, &ndash; qu&rsquo;elle le grandisse en sagesse et le conforte en l\u00e9gitimit\u00e9. Au reste, cette pr\u00e9tention montrerait plut\u00f4t l&rsquo;errement de l&rsquo;esprit et l&rsquo;ill\u00e9gitimit\u00e9 de la substance, autant que la vanit\u00e9 pr\u00e9tentieuse, \u00e9galement de l&rsquo;ordre du pathologique, du bloc BAO, de se percevoir comme un tout, comme une repr\u00e9sentation finie de la communaut\u00e9 humaine. En un sens, ce label auto-attribu\u00e9 est lui-m\u00eame un aveu de sa propre subversion, de son destin faussaire et autodestructeur, &ndash; et aussi, on le verra plus loin et principalement, le signe de son versement complet dans l&rsquo;affectivit\u00e9 comme moteur fondamental du jugement.<\/p>\n<\/p>\n<p><p>Brzezinski ne pense certainement pas en ces termes dans la mesure o&ugrave; il reste un esprit compl\u00e8tement am\u00e9ricaniste, et, par cons\u00e9quent, \u00ab\u00a0am\u00e9ricanisto-centr\u00e9\u00a0\u00bb. Mais on pourrait dire que cette question plus large de la structure et de la texture m\u00eame des relations internationales ne l&rsquo;int\u00e9resse pas. Comme Kissinger pour ce cas, ce qui lui importe c&rsquo;est la caract\u00e8re exemplaire de la crise syrienne pour ce qu&rsquo;elle r\u00e9v\u00e8le de la pratique <strong>courante<\/strong> des relations internationales par les Occidentaux (le bloc BAO pour nous), de sa transformation par rapport \u00e0 la fa\u00e7on dont lui-m\u00eame (comme Kissinger) pratiqua ces relations. Il ne parle pas d&rsquo;une transformation de l&rsquo;essence de la chose, mais plut\u00f4t de la d\u00e9cadence de la chose par rapport \u00e0 ce qu&rsquo;elle fut. C&rsquo;est justement l&rsquo;int\u00e9r\u00eat de ces propos par rapport \u00e0 l&rsquo;\u00e9troitesse du cadre o&ugrave; il les place : la puissance de son propos montre bien que ce cadre qui leur assigne est insuffisant pour rendre compte de la puissance du ph\u00e9nom\u00e8ne, &ndash; et c&rsquo;est bien cela qui nous int\u00e9resse&hellip;<\/p>\n<\/p>\n<p><p>Nous allons donc citer Brzezinski, comme technicien et expert av\u00e9r\u00e9s des relations internationales. (Nous laissons de cot\u00e9 le jugement moral qu&rsquo;on peut porter sur lui, comme sur Kissinger bien entendu, &ndash; et jugement moral d&rsquo;ailleurs bien connu et entendu. L\u00e0 n&rsquo;est pas le propos, car ce jugement moral ne doit en aucun cas interf\u00e9rer sur l&rsquo;aspect fondamental de l&rsquo;objet qui occupe exclusivement notre r\u00e9flexion : ni Brzezinski, ni Kissinger, mais bien l&rsquo;essence des relations internationales, et sa perversion et sa dissolution, encore plus que sa d\u00e9cadence.) Le compte-rendu des d\u00e9clarations de Brzezinski se trouve sur <em>The Daily Caller<\/em>, de Jeff Poor, du <a class=\"gen\" href=\"http:\/\/dailycaller.com\/2012\/05\/30\/zbigniew-brzezinski-syrian-conflict-not-as-horrible-or-as-dramatic-as-it-is-portrayed\/#ixzz1x7rQPANs\">30 mai 2012<\/a>.<\/p>\n<\/p>\n<p><p>&laquo;<em>Council on Foreign Relations President Richard Haas, Brzezinski&rsquo;s co-panelist on the morning program, asked if one of the appropriate measures would be for Syria&rsquo;s neighbors in the Middle East to withdraw their diplomats from Russia to show their disapproval of Moscow&rsquo;s support for Syria. \u00ab\u00a0I don&rsquo;t think the Russians will be terribly impressed by that,\u00a0\u00bb Brzezinski said. \u00ab\u00a0Ambassadors will be gone and what has changed in Syria is the consequence. I think the fact of the matter this issue is extraordinarily sensitive.\u00a0\u00bb<\/em><\/p>\n<\/p>\n<p><p>&raquo;<em>\u00ab\u00a0At the same time,\u00a0\u00bb he added, \u00ab\u00a0it is not as horrible or as dramatic as it is portrayed. If you look at the world in recent years, the horrible war in Sri Lanka, the killings in Rwanda, and the deaths in Libya and so forth. You know, let&rsquo;s have a sense of proportion here. This is a neurologic part of the world in which all of a sudden if we are not intelligent about it we can create a nexus between a difficult internal problem which has not assumed huge proportions yet and a regional problem and a global problem which involves our relationships with the other major powers, particularly Russia, but also the negotiations with Iran over the nuclear problem.\u00a0\u00bb<\/em> [&hellip;]<\/p>\n<\/p>\n<p><p>&raquo;<em> \u00ab\u00a0It&rsquo;s not going to be solved by recalling ambassadors from Moscow or telling the Russians they are acting like thugs,\u00a0\u00bb he said. \u00ab\u00a0The fact of the matter is unless there is international cooperation which results in some proposal that the Assad government can live with, and which involves some sort of supervised effort to establish some domestic consensus, this conflict is going to go on. And let&rsquo;s not exaggerate this conflict.\u00a0\u00bb<\/em> [&hellip;] <em>He said that the Syrian uprising is distinct from other conflicts because violence isn&rsquo;t widespread geographically, the army has remained intact and the business elite has remained supportive of the Assad government.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>D&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, les autres personnes, des experts \u00e9galement, qui participaient \u00e0 cette table ronde, dont David Ignatius, du Washington <em>Post<\/em>, se r\u00e9cri\u00e8rent. Ils insist\u00e8rent, contre l&rsquo;avis de Brzezinski, sur l&rsquo;aspect horrible de la violence, comme le massacre de Houla, sugg\u00e9rant comme allant de soi que cette violence venait du r\u00e9gime Assad et qu&rsquo;elle \u00e9tait presque sans \u00e9quivalent&#8230; La r\u00e9action de Brzezinski est manifestement exc\u00e9d\u00e9e.<\/p>\n<\/p>\n<p><p>&laquo;<em> \u00ab\u00a0Don&rsquo;t put me in a position of defending brutality and knifing people,\u00a0\u00bb Brzezinski said. \u00ab\u00a0Frankly, that&rsquo;s not the issue. We do know these things happen, and they are horrible. They also happened on a much larger scale in many other countries in which we have not intervened. My point here is we are dealing in a region with which all of these issues are interconnected. And if we act simply on the basis of emotion and sort of vague threats that the Russians have to be forced to be good boys, we&rsquo;re going to produce a region-wide outbreak in which the issues within Syria will become linked with the conflict between the Saudis and the Shiites. Iraq will become destabilized. Iran will be involved. The Israelis on the side are also interested in not having a particularly strong Syria. So they are watching here carefully. \u00ab\u00a0We are watching the breakdown of negotiations with Iran on top of it,\u00a0\u00bb he continued. \u00ab\u00a0And we&rsquo;ll have a major international problem on our hands with political and economic consequences that are very serious. And what I hear is a lot of emotion and sloganeering. But I haven&rsquo;t heard what the secret plans of the White House is conceiving actually are on how they&rsquo;re going to be implemented unless we get international cooperation on it.\u00a0\u00bb<\/em>&raquo;<\/p>\n<\/p>\n<p><p>&hellip;Brzezinski va plus loin que Kissinger en un sens, bien qu&rsquo;il soit sur la m\u00eame ligne de critique fondamentale, parce qu&rsquo;il se fait (le sait-il ou non ?) psychologue, tandis que Kissinger reste un expert qui joue \u00e0 l&rsquo;historien. Ce que Brzezinski met en proc\u00e8s, c&rsquo;est la sensibilit\u00e9, l&rsquo;affectivit\u00e9, qui remplace la froide raison, la mesure du monde qui permet d&rsquo;appr\u00e9cier un acte, si vil et monstrueux qu&rsquo;il paraisse \u00e0 la sensibilit\u00e9, dans la globalit\u00e9 du contexte politique. Nous pouvons douter que cette \u00ab\u00a0froide raison\u00a0\u00bb soit, chez lui, temp\u00e9r\u00e9e par un jugement plus haut portant sur le fondement m\u00e9taphysique de la chose, notamment par rapport \u00e0 ce qui est infect\u00e9 par la source du Mal, mais on doit lui reconna&icirc;tre qu&rsquo;il laisse la porte ouverte, par sa m\u00e9thode, \u00e0 cette \u00e9chapp\u00e9e vers le haut. On entend Brzezinski, avec sa physionomie coupante comme une lame de rasoir, fulminer en subissant les geignements des autres (le valet du pouvoir Ignatius en premier) : \u00ab\u00a0Ne m&rsquo;enfermez pas dans vos geignements moralisateurs prolif\u00e9rant sur le monceau de cadavres du jour !\u00a0\u00bb (&laquo;<em>Don&rsquo;t put me in a position of defending brutality and knifing people,<\/em> [&hellip;] <em>Frankly, that&rsquo;s not the issue&hellip;<\/em>&raquo;) &hellip;Et puisqu&rsquo;il nous laisse une \u00e9chapp\u00e9e vers le haut, il serait indigne que nous n&rsquo;en profitions pas.<\/p>\n<\/p>\n<p><p>La critique des deux anciens, qui ont \u00e9galement pratiqu\u00e9 la <em>realpolitik<\/em> et savent ce que sont les monceaux de cadavres puisque leurs politiques en produisirent plus qu&rsquo;\u00e0 leur tour, savent aussi qu&rsquo;on ne peut laisser une politique se d\u00e9terminer par le sentiment \u00e9prouv\u00e9 par rapport \u00e0 ces monceaux de cadavres (y compris et <strong>surtout<\/strong> si l&rsquo;on en porte soi-m\u00eame la responsabilit\u00e9). Dans l&rsquo;absolu de la raison politique, l&rsquo;argument qui peut para&icirc;tre ignominieux sous la plume d&rsquo;un Kissinger, si l&rsquo;on c\u00e8de au moralisme sentimental, selon lequel il vaut mieux parfois, et parfois souvent, ne pas r\u00e9agir impulsivement \u00e0 un monceaux de cadavres aujourd&rsquo;hui pour n&rsquo;en pas susciter dix demain, cet argument ne peut \u00eatre discut\u00e9&hellip; Or, il se trouve qu&rsquo;aujourd&rsquo;hui, on ne peut m\u00eame pas dire de cet argument qu&rsquo;il est discut\u00e9, on doit dire qu&rsquo;il est honni, d\u00e9nonc\u00e9, crach\u00e9, <strong>vomi<\/strong> comme un sacril\u00e8ge. La r\u00e9flexion politique s&rsquo;est r\u00e9duite, \u00e0 l&rsquo;image de la t\u00eate d&rsquo;un ennemi des Jivaros, \u00e0 la taille de la r\u00e9flexion du bouffon m\u00e9taphysique qu&rsquo;est ce BHL, aujourd&rsquo;hui grand penseur de cette \u00e9poque, le d\u00e9l\u00e9gu\u00e9 indestructible et inoxydable charg\u00e9 de la d\u00e9coration intellectuelle du Syst\u00e8me, docteur Faust en carton m\u00e2ch\u00e9 ou en papier bouilli c&rsquo;est selon, de l&rsquo;ultime acte tragi-comique que veut bien nous pr\u00e9senter le Syst\u00e8me sur la sc\u00e8ne de son th\u00e9\u00e2tre de l&rsquo;absurde.<\/p>\n<\/p>\n<p><p>&hellip;Mais justement, s&rsquo;agit-il de \u00ab\u00a0r\u00e9flexion\u00a0\u00bb (\u00ab\u00a0La r\u00e9flexion politique s&rsquo;est r\u00e9duite&hellip;\u00a0\u00bb, etc.) dans le sens o&ugrave; la raison intervient ? La raison peut-elle, est-elle encore en \u00e9tat d&rsquo;intervenir ?<\/p>\n<\/p>\n<p><h3 class=\"subtitleset_b.deepblue\" style=\"color:#0f3955;font-size:1.65em;font-variant:small-caps;\">Constance de leur \u00ab\u00a0psychologie terroris\u00e9e\u00a0\u00bb<\/h3>\n<\/p>\n<p><p>Brzezinski ne s&rsquo;en cache pas : on ne peut pas intervenir selon une r\u00e9action \u00e9motionnelle&hellip; &laquo;<em>And if we act simply on the basis of \u00e9motion<\/em>&hellip; [&hellip;] <em>And what I hear is a lot of emotion and sloganeering&hellip;.<\/em>&raquo; L\u00e0-dessus, Brzezinski, qui est un homme inform\u00e9 \u00e0 Washington et qui est un soutien de la politique ext\u00e9rieure des USA d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, ajoute, pour renforcer son constat, qu&rsquo;il n&rsquo;y a aujourd&rsquo;hui avec la Syrie qu&rsquo;une r\u00e9action \u00e9motionnelle, qu&rsquo;il n&rsquo;y a aucun plan secret de la Maison-Blanche, rien du tout de construit rationnellement, &ndash; ce qui impliquerait \u00e9videmment la r\u00e9action rationnelle dont il d\u00e9plore l&rsquo;absence : &laquo;<em>But I haven&rsquo;t heard what the secret plans of the White House is conceiving actually are on how they&rsquo;re going to be implemented unless we get international cooperation on it.<\/em>&raquo;<\/p>\n<\/p>\n<p><p>Il y a deux aspects dans cette r\u00e9action, pour notre r\u00e9flexion.<\/p>\n<\/p>\n<p><p>&bull; Le premier est la signification <strong>politique<\/strong> de cette r\u00e9action de Brzezinski, coupl\u00e9e \u00e0 la r\u00e9action de Kissinger d\u00e9j\u00e0 mentionn\u00e9e (et d&rsquo;ailleurs r\u00e9p\u00e9t\u00e9e, puisque d\u00e8s le <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-la_syrie_fait_sortir_kissinger_de_ses_gonds_05_04_2012.html\">5 avril 2012<\/a>, Kissinger critiquait d\u00e9j\u00e0 violemment les appels \u00e0 l&rsquo;intervention en Syrie). Ces r\u00e9actions sont si fortes, si affirm\u00e9es, qu&rsquo;on peut conclure sans crainte d&rsquo;erreur qu&rsquo;un Brzezinski, cet Am\u00e9ricain d&rsquo;origine polonaise et visc\u00e9ralement anti-russe, est aujourd&rsquo;hui bien plus proche de la politique syrienne de la Russie que de la politique du bloc BAO ; quant \u00e0 Kissinger, plus encore, lui qui n&rsquo;a jamais cach\u00e9 un penchant cynique pour le r\u00e9alisme rationnel des politiques russe et chinoise, particuli\u00e8rement muscl\u00e9es du temps du communisme&hellip;<\/p>\n<\/p>\n<p><p>&bull; On peut en d\u00e9duire tr\u00e8s raisonnablement, en tenant compte de la notori\u00e9t\u00e9 des deux hommes et de leur loyaut\u00e9 \u00e0 la cause am\u00e9ricaniste, de leur absence compl\u00e8te de scrupules pour soutenir cette politique quand ils la jugent efficace, qu&rsquo;ils d\u00e9montrent indirectement, dans la capacit\u00e9 de leur jugement et de leur exp\u00e9rience autant que de la connaissance des arcanes du Syst\u00e8me qu&rsquo;ils d\u00e9couvrent dans cette circonstance aussi strat\u00e9giquement nu que le roi, qu&rsquo;il n&rsquo;y a effectivement aucune approche construite, rationnelle justement, \u00e0 la crise syrienne dans le chef de la direction politique am\u00e9ricaniste. On peut sans la moindre h\u00e9sitation avancer l&rsquo;affirmation que cette situation est similaire dans les autres pays importants du bloc BAO, notamment au Royaume-Uni et en France.<\/p>\n<\/p>\n<p><p>&bull; Le second aspect est plus structurel, et d\u00e9coule \u00e9videmment du premier en nous permettant de passer au plan psychologique, voire plus profond\u00e9ment, au plan de la situation psychologique des directions politiques du bloc BAO par rapport \u00e0 l&rsquo;influence <strong>active<\/strong> du Syst\u00e8me consid\u00e9r\u00e9 en tant qu&rsquo;entit\u00e9 \u00e0 pr\u00e9tention m\u00e9taphysique. Il s&rsquo;agit du constat de l&rsquo;effacement complet de la raison en tant que force structurante du jugement dans les attitudes politiques de ces directions vis-\u00e0-vis de la crise syrienne. Il n&rsquo;est donc plus question, en v\u00e9rit\u00e9, d&rsquo;attitudes politiques mais d&rsquo;attitudes psychologiques comme d\u00e9tonateur d&rsquo;une situation effectivement m\u00e9tahistorique.<\/p>\n<\/p>\n<p><p>Le constat est effectivement que l&rsquo;effacement d&rsquo;une <strong>raison efficace<\/strong>, une raison \u00ab\u00a0loyale \u00e0 la perception de la r\u00e9alit\u00e9\u00a0\u00bb, ouvre la porte au d\u00e9ferlement de l'\u00a0\u00bbaffect\u00a0\u00bb en termes psychologiques, ou pure affectivit\u00e9, dans les r\u00e9actions \u00e0 la situation de Syrie. Cet affect n&rsquo;est \u00e9videmment pas suscit\u00e9 par un plan de manipulation puisqu&rsquo;on a vu que la raison, qui seule peut produire humainement de tels plans, est absente dans son r\u00f4le habituel de rangement des ambitions et des projets humains. L&rsquo;affect pr\u00e9pond\u00e9rant dans ces r\u00e9actions est donc la cause autant que le produit des manipulations innombrables qui caract\u00e9risent le compte-rendu de la v\u00e9rit\u00e9 de la situation syrienne, qui est bien entendu une v\u00e9rit\u00e9 compl\u00e8tement fabriqu\u00e9e, &ndash; litt\u00e9ralement, selon notre jargon, une <em>narrative<\/em>. Il s&rsquo;agit d&rsquo;une auto-manipulation, ou techniquement d&rsquo;une auto-m\u00e9sinformation, suscit\u00e9es par une affectivit\u00e9 qui a compl\u00e8tement pris le dessus dans l&rsquo;attitude psychologique, et qui affecte l&rsquo;observation des faits et le jugement selon des normes id\u00e9ologiques de type hyst\u00e9rique elles-m\u00eames v\u00e9hicul\u00e9es dans la psychologie avant d&rsquo;\u00eatre transcrites en \u00ab\u00a0id\u00e9es\u00a0\u00bb de type-standard et homog\u00e9n\u00e9is\u00e9es (droits de l&rsquo;homme, humanitarisme, etc.).<\/p>\n<\/p>\n<p><p>(Cette auto-manipulation est facilit\u00e9e par un aspect technique non n\u00e9gligeable, qui est l&rsquo;atmosph\u00e8re cr\u00e9\u00e9e par le syst\u00e8me de la communication, tel qu&rsquo;il est lui-m\u00eame int\u00e9gr\u00e9 dans cette m\u00eame auto-manipulation et cette auto-m\u00e9sinformation. L&rsquo;usage massif d&rsquo;informations d\u00e9form\u00e9es par la presse-Syst\u00e8me selon le processus qu&rsquo;on a vu, de toutes les fa\u00e7ons sans le moindre esprit critique qui dispara&icirc;t avec la raison, la <strong>rapidit\u00e9<\/strong> du processus de la communication qui interdit toute distance vis-\u00e0-vis du soi-disant fait expos\u00e9 et la <strong>rapidit\u00e9<\/strong> de la r\u00e9action \u00e9motive standard par cons\u00e9quent, la profusion de l&#8217;emploi des m\u00eames images, la standardisation des r\u00e9actions d&rsquo;affectivit\u00e9 devant ce kal\u00e9idoscope ultra-rapide des m\u00eames \u00e9l\u00e9ments de communication pr\u00e9sent\u00e9s comme strictement objectifs, etc., tout cela cr\u00e9e cette atmosph\u00e8re immens\u00e9ment favorable \u00e0 la r\u00e9action affective, et seulement affective. Cette atmosph\u00e8re agit comme un compl\u00e9ment, sinon d\u00e9cisif, dans tous les cas tr\u00e8s efficace, pour le ph\u00e9nom\u00e8ne constat\u00e9.)<\/p>\n<\/p>\n<p><p>Il s&rsquo;agit d&rsquo;une situation caract\u00e9ristique de la psychologie de nos directions politiques, que nous avons d\u00e9j\u00e0 abord\u00e9e dans notre texte du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-leur_psychologie_terroris_e_16_04_2012.html\">16 avril 2012<\/a> (\u00ab\u00a0LEUR psychologie terroris\u00e9e\u00a0\u00bb), et que nous d\u00e9veloppons dans notre num\u00e9ro de <em>dde.crisis<\/em> du 10 juin 2012. Nous parlons donc d&rsquo;une <em>terrorisation<\/em> (terme anglais) des psychologies des directions politiques, essentiellement depuis le 11 septembre 2001. (Cela, quelle qu&rsquo;ait \u00e9t\u00e9 la participation de ces directions politiques \u00e0 l&rsquo;organisation des attentats de 9\/11, &ndash; nous parlons d&rsquo;un processus qui \u00e9chappe, l\u00e0 aussi, \u00e0 la ma&icirc;trise de l&rsquo;esprit humain, et aboutirait dans ce cas hypoth\u00e9tique, \u00e0 une \u00ab\u00a0auto-<em>terrorisation<\/em>\u00a0\u00bb des psychologies des directions politiques par elles-m\u00eames.) Le r\u00e9sultat de cette situation de <em>terrorisation<\/em> de la psychologie est une d\u00e9gradation extraordinairement acc\u00e9l\u00e9r\u00e9e des capacit\u00e9s d&rsquo;une raison d\u00e9j\u00e0 largement subvertie par l&rsquo;influence du Syst\u00e8me. La raison subvertie et extr\u00eamement d\u00e9grad\u00e9e n&rsquo;est plus qu&rsquo;un \u00ab\u00a0outil technique\u00a0\u00bb au service de l&rsquo;affectivit\u00e9 (au service du Syst\u00e8me par cons\u00e9quent, par d\u00e9l\u00e9gation) pour construire la <em>narrative<\/em> et organiser l&rsquo;action \u00e0 l&rsquo;int\u00e9rieur de cette <em>narrative<\/em> ; et m\u00eame, dans le chef de cette m\u00eame raison r\u00e9duite au r\u00f4le d'\u00a0\u00bboutil utile\u00a0\u00bb comme on dit \u00ab\u00a0idiot utile\u00a0\u00bb, organiser la dissimulation de sa propre subversion et de sa propre d\u00e9gradation&hellip;<\/p>\n<\/p>\n<p><p>Les \u00e9v\u00e8nements acc\u00e9l\u00e8rent cette d\u00e9gradation de la raison, de l&rsquo;esprit en g\u00e9n\u00e9ral, de la politique qui en est le produit. Ils mettent en lumi\u00e8re, par eux-m\u00eames, les effets des r\u00e9actions catastrophiques d&rsquo;une raison ainsi d\u00e9grad\u00e9e suscitant des politiques \u00e0 mesure, et laissant la place au plus bas des composant de l&rsquo;activit\u00e9 psychique g\u00e9n\u00e9rale, qui est l&rsquo;affectivit\u00e9. (L&rsquo;affectivit\u00e9 n&rsquo;a de r\u00e9elle valeur que lorsqu&rsquo;elle est contr\u00f4l\u00e9e par la raison, et \u00e9clair\u00e9e par l&rsquo;intuition haute, ce qui lui donne noblesse et substance. Ce n&rsquo;est bien entendu pas le cas dans notre situation, mais plut\u00f4t une situation de compl\u00e8te inversion \u00e0 cet \u00e9gard.) Cette situation g\u00e9n\u00e9rale est appuy\u00e9e sur l&rsquo;id\u00e9ologie maximaliste, absolue, nihiliste, l&rsquo;id\u00e9ologie pour elle-m\u00eame, qui est l&rsquo;extr\u00eame et le cul de sac \u00e0 la fois d&rsquo;une chose (l&rsquo;id\u00e9ologie) qui est de toutes les fa\u00e7ons une construction de l&rsquo;affectivit\u00e9 pour faire accepter sous le couvert de la raison et d&rsquo;un habillage d&rsquo;une belle apparence logique ou morale, une politique absolument pervertie. (R\u00e9sumons : l&rsquo;id\u00e9ologie, ou la compl\u00e8te perversion de la politique par l&rsquo;affectivit\u00e9.)<\/p>\n<\/p>\n<p><p>Les \u00e9v\u00e8nements du \u00ab\u00a0printemps arabe\u00a0\u00bb suivant la catastrophe de la crise de 2008 qui, tous deux, d\u00e9montrent rationnellement la faillite et l&rsquo;effondrement complets du Syst\u00e8me, ont achev\u00e9 cet effondrement de la raison dans le chef des directions politiques. Dans ce cas, l&rsquo;influence active, sinon consciente du Syst\u00e8me est \u00e0 son z\u00e9nith : il s&rsquo;agit d&#8217;emp\u00eacher par tous les moyens la moindre occurrence o&ugrave; l&rsquo;esprit du <em>sapiens<\/em>-serviteur peuplant les directions politiques et les \u00ab\u00a0\u00e9lites\u00a0\u00bb qui les soutiennent pourrait se douter de cet \u00e9tat catastrophique du Syst\u00e8me. Il n&rsquo;y a donc plus de raison efficace et active chez nos dirigeants et dans nos \u00e9lites, mais des raisons totalement subverties et d\u00e9grad\u00e9es m\u00eame par rapport \u00e0 cette situation de perversion. Plus aucun r\u00e9gulateur n&rsquo;existe pour emp\u00eacher le d\u00e9ferlement de l&rsquo;affectivit\u00e9 selon des termes et des orientations suscit\u00e9s par cette m\u00eame affectivit\u00e9. Seuls quelques esprits retors, exp\u00e9riment\u00e9s, bronz\u00e9s par l&rsquo;exp\u00e9rience de la politique dite \u00ab\u00a0r\u00e9aliste\u00a0\u00bb, d&rsquo;une pratique puissante d&rsquo;une action rationnelle bien que le plus souvent sans le moindre scrupule et dans l&rsquo;int\u00e9r\u00eat du Syst\u00e8me, une raison litt\u00e9ralement cuirass\u00e9e d&rsquo;un cuir \u00e9pais et difficile \u00e0 entamer, comme celles d&rsquo;un Kissinger et d&rsquo;un Brzezinski, seuls ces quelques esprits r\u00e9sistent au d\u00e9ferlement de l&rsquo;affectivit\u00e9. Leur r\u00e9putation et leur position dans le Syst\u00e8me, qu&rsquo;ils ont fort efficacement servi, emp\u00eachent qu&rsquo;on \u00e9touffe leur fureur.<\/p>\n<\/p>\n<p><p>Maintenant, il reste la cause, au moins op\u00e9rationnelle sinon fondamentale de ce d\u00e9cha&icirc;nement, de la raison subvertie et d\u00e9grad\u00e9e laissant la voie libre \u00e0 l&rsquo;affectivit\u00e9. Notre hypoth\u00e8se est plus que jamais la m\u00eame, et touche au domaine m\u00e9taphysique. Elle se r\u00e9f\u00e8re \u00e0 ce que nous nommons le \u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb, la g\u00e9n\u00e9ration spontan\u00e9e du Syst\u00e8me comme courroie de transmission de ce d\u00e9cha&icirc;nement, enfin ce d\u00e9cha&icirc;nement n&rsquo;\u00e9tant pas autre chose que l&rsquo;installation du Mal comme facteur dominant de notre contre-civilisation. Comme \u00e0 l&rsquo;origine de la s\u00e9quence (le \u00ab\u00a0<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_crise_de_la_raison_humaine_ddecrisis_18_07_2010.html\">persiflage<\/a>\u00a0\u00bb du XVIII\u00e8me si\u00e8cle), cette force d\u00e9structurante et dissolvante dont le but est l&rsquo;entropisation du monde, sait qu&rsquo;elle n&rsquo;a pas de meilleur moyen de se transmuter en force terrestre de dissolution que la psychologie du <em>sapiens<\/em>. Elle en use et, d\u00e9sormais, en abuse&hellip; Car c&rsquo;est bien l&rsquo;\u00e9vidence qui s&rsquo;impose : cette course folle, o&ugrave; la raison humaine qui \u00e9tait \u00e0 l&rsquo;origine faite pour recevoir la lumi\u00e8re de l&rsquo;intuition haute est d\u00e9sormais pr\u00e9cipit\u00e9e dans les abysses de sa subversion et de sa d\u00e9gradation, ne fait qu&rsquo;acc\u00e9l\u00e9rer la transmutation de la dynamique de surpuissance en dynamique d&rsquo;autodestruction. Certains acteurs, qui sont moins touch\u00e9s que ceux du bloc BAO par cette effrayante \u00e9volution, se chargeront volontairement ou non d&rsquo;acc\u00e9l\u00e9rer le processus, &ndash; on parle des Russes, des Chinois, des Iraniens et de quelques autres. Ni\u00e8me tentative du processus du \u00ab\u00a0d\u00e9cha&icirc;nement de la Mati\u00e8re\u00a0\u00bb d&rsquo;aller \u00e0 son terme, la crise syrienne pr\u00e9sente une opportunit\u00e9 pas loin d&rsquo;\u00eatre parfaite d&rsquo;y parvenir. Il y aura du sang, du feu et des larmes, et, peut-\u00eatre, l&rsquo;un de ces vastes \u00e9v\u00e8nements comme l&rsquo;est une guerre majeure \u00e0 l&rsquo;\u00e9chelle du monde, pour accomplir ce destin. Comme l&rsquo;on sait, nous sommes dans un Moment m\u00e9tahistorique de l&rsquo;histoire, un de ces Moments dont parle <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-la_haine_du_principe_du_principe__31_05_2012.html\">le comte Joseph<\/a>, &ndash; \u00e0 peine et dans tous les cas fort humblement modifi\u00e9 par nous-m\u00eames, pour la bonne cause :<\/p>\n<\/p>\n<p><p>&laquo;<em>&hellip;Sans doute, la Providence n&rsquo;a pas besoin de punir dans le temps pour justifier ses voies ; mais, \u00e0<\/em> [certaines \u00e9poques,] <strong><em>elle se met \u00e0 notre port\u00e9e<\/em><\/strong><em>, et punit comme un tribunal humain.<\/em>&raquo;<\/p>\n<\/p>\n<p><h4>Note de mise \u00e0 jour : 10 novembre 2014<\/h4>\n<\/p>\n<p><p>Revenant tr\u00e8s r\u00e9cemment, \u00e0 propos d&rsquo;un texte du <a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/article-ce_congr_s-l_est-il_le_commencement_de_la_fin__10_11_2014.html\">10 novembre 2014<\/a>, sur ce texte ci-dessus du 11 mai 2012, un de nos lecteurs, monsieur Michel Donceel, a propos\u00e9 fort justement (<a class=\"gen\" href=\"http:\/\/www.dedefensa.org\/forum-la_raison_devenue_idiote_utile_de_l_affectivit__11_06_2012.html\">Voir<\/a> le <em>Forum<\/em> de ce texte) le terme d'\u00a0\u00bbaffectivisme\u00a0\u00bb plut\u00f4t que le terme d'\u00a0\u00bbaffectivit\u00e9\u00a0\u00bb que nous employions. Il a parfaitement raison, selon une perspective qui, \u00e0 notre sens, m\u00e9riterait un d\u00e9bat. Nous le remercions de sa suggestion, ainsi bien entendu que son amie de laquelle vient au premier chef cette proposition.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La raison devenue \u00ab\u00a0idiote utile\u00a0\u00bb de l&rsquo;affectivit\u00e9 11 juin 2012 &ndash; Les deux ont coutume de ne pas s&rsquo;aimer beaucoup, comme deux vieilles stars jalouses de leur gloire ancienne. Il n&#8217;emp\u00eache, sur ce point fondamental de la forme de la politique ext\u00e9rieure US, des relations internationales \u00e0 l&rsquo;aune de cette monstruosit\u00e9 qu&rsquo;est le bloc am\u00e9ricaniste-europ\u00e9annistes&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[14892,12672,4270,1006,2631,8854,5808,9054,3736,2622,3041,8855,4321,12164,3099,11131,14877],"class_list":["post-73191","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-affect","tag-affectivisme","tag-autodestruction","tag-brzezinski","tag-de","tag-dechainement","tag-idiot","tag-inversion","tag-kissinger","tag-la","tag-mal","tag-matiere","tag-narrative","tag-outil","tag-psychologie","tag-surpuissance","tag-utile"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73191"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73191\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}