{"id":73209,"date":"2012-06-20T07:26:16","date_gmt":"2012-06-20T07:26:16","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/06\/20\/notes-sur-la-flotte-sebastopol-et-la-syrie-et-lenjeu-supreme\/"},"modified":"2012-06-20T07:26:16","modified_gmt":"2012-06-20T07:26:16","slug":"notes-sur-la-flotte-sebastopol-et-la-syrie-et-lenjeu-supreme","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/06\/20\/notes-sur-la-flotte-sebastopol-et-la-syrie-et-lenjeu-supreme\/","title":{"rendered":"Notes sur la flotte, S\u00e9bastopol et la Syrie, et l&rsquo;enjeu supr\u00eame"},"content":{"rendered":"<p><h2 class=\"common-article\">Notes sur la flotte, S\u00e9bastopol et la Syrie, et l&rsquo;enjeu supr\u00eame<\/h2>\n<\/p>\n<p><p>\tLa question du renforcement en armements et de la pr\u00e9sence ou pas de forces \u00e9trang\u00e8res officielles en Syrie, notamment des grandes puissances (essentiellement la Russie et le bloc BAO) prend une importance grandissante dans la crise syrienne. Cette question doit \u00eatre toujours envisag\u00e9e sur deux plans : celui de la communication (qui correspond au syst\u00e8me de la communication) et celui des affaires militaires elles-m\u00eames (qui correspond au syst\u00e8me du technologisme). <\/p>\n<\/p>\n<p><p>\tBien entendu, il est aussi n\u00e9cessaire de la placer dans un contexte plus large, qui est, du point de vue op\u00e9rationnel, celui de la <a href=\"http:\/\/www.dedefensa.org\/article-poutine_et_obama_c_te_c_te_et_face_face_19_06_2012.html\" class=\"gen\">rencontre<\/a> entre Poutine et Obama \u00e0 Mexico, en marge du G20. La question de la Syrie a supplant\u00e9 toutes les autres, en raison de son  urgence et de sa priorit\u00e9. Ainsi y a-t-il, dans le contexte plus large que nous signalons, l&rsquo;aspect conceptuel qui traduit l&rsquo;aspect op\u00e9rationnel du sommet Poutine-Obama. Il appara\u00eet que cette crise syrienne pr\u00e9sente de plus en plus les caract\u00e9ristiques du d\u00e9tonateur qui pourrait conduire au d\u00e9cha\u00eenement g\u00e9n\u00e9ral de la <a href=\"http:\/\/www.dedefensa.org\/article-la_crise_haute_03_02_2012.html\" class=\"gen\">crise<\/a> <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_crise_haute_ddecrisis_20_02_2012.html\" class=\"gen\">haute<\/a>.<\/p>\n<h3>Tensions entre State et Pentagone<\/h3>\n<\/p>\n<p><p>\tOn peut dire que l&rsquo;affaire des h\u00e9licopt\u00e8res d&rsquo;attaque russes a \u00e9t\u00e9 le premier cas sp\u00e9cifique, clairement document\u00e9 et d\u00e9velopp\u00e9 sur la question d&rsquo;envoi d&rsquo;armements, envoi officiel ou \u00e0 ciel ouvert portant sur des armements majeurs, au contraire d&rsquo;innombrables op\u00e9rations <em>covert<\/em> (dissimul\u00e9es) de cette sorte (<a href=\"http:\/\/www.dedefensa.org\/article-marche_a_la_russe_29_03_2012.html\" class=\"gen\">des deux c\u00f4t\u00e9s<\/a>).<\/p>\n<\/p>\n<p><p>\tOn a vu le d\u00e9tail de cette affaire (le <a href=\"http:\/\/www.dedefensa.org\/article-moscou-damas-hillary_et_les_h_licopt_res_irresponsables_15_06_2012.html\" class=\"gen\">15 juin 2012<\/a>), o\u00f9 la partie am\u00e9ricaniste a \u00e9t\u00e9 victime de ses affrontements inter-d\u00e9partementaux et de l&rsquo;hyst\u00e9rie politique du d\u00e9partement d&rsquo;\u00c9tat. Les tentatives pour tenter de r\u00e9parer les d\u00e9g\u00e2ts, du fait de l&rsquo;inimitable New York <em>Times<\/em>, tel que rapport\u00e9es par Tony Cartalucci (<em>Land Destroyer<\/em>, le <a href=\"http:\/\/landdestroyer.blogspot.be\/2012\/06\/us-attempting-to-trigger-full-proxy-war.html\" class=\"gen\">17 juin 2012<\/a>), ont fait plus de mal que de bien \u00e0 la cause am\u00e9ricaniste en inventant une op\u00e9ration coordonn\u00e9e de propagande (ce qui n&rsquo;est pas le meilleur argument), qui est une version contredite par le r\u00f4le hostile du Pentagone. Le <em> senior defense department official<\/em> cit\u00e9 semblerait venir \u00e0 l&rsquo;aide de Clinton, \u00e9ventuellement, mais c&rsquo;est pour l&rsquo;enfoncer un peu plus dans son entreprise de propagande avort\u00e9e. On ne s&rsquo;aime gu\u00e8re, en ce moment, entre le Pentagone et State.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>In New York Times&rsquo; Copters in Syria May Not Be New, U.S. Officials Say, a senior defense department official admitted when US Secretary of State Hillary Clinton made her fraudulent claim regarding Russian weapon shipments, she put a little spin on it to put the Russians in a difficult position. The New York Times continued by stating, Mrs. Clinton&rsquo;s claim about the helicopters, administration officials said, is part of a calculated effort to raise the pressure on Russia to abandon President Bashar al-Assad, its main ally in the Middle East, indicative of the campaign of propaganda and lies orchestrated by the US State Department, the British Foreign Office, and Western and Gulf State news outlets around the world to demonize both the Syrian government and its extensive allies around the world, contrary to the facts on the ground.<\/em>\u00bb<\/p>\n<h3>Les Russes arrivent !<\/h3>\n<\/p>\n<p><p>\tUne autre affaire est apparue et s&rsquo;est d\u00e9velopp\u00e9e depuis le 15 juin, qui est celle du d\u00e9placement de certaines unit\u00e9s de la flotte russe de la Mer Noire, de S\u00e9bastopol (enclave russe et base navale en Ukraine) vers le port\/la base russe de Tartus, en Syrie.<\/p>\n<\/p>\n<p><p>\tIl y a eu d&rsquo;abord un rapport de NBC.<em>News<\/em>, le <a href=\"http:\/\/worldnews.msnbc.msn.com\/_news\/2012\/06\/15\/12238938-us-official-russia-sends-troops-to-syria-as-peace-hopes-fade?lite\" class=\"gen\">15 juin 2012<\/a>, citant des officiels militaires US, c&rsquo;est-\u00e0-dire des sources officieuses du Pentagone,  cette fois, Clinton n&rsquo;est pas concern\u00e9e. Il s&rsquo;agissait de l&rsquo;annonce que la Russie avait d&rsquo;ores et d\u00e9j\u00e0 envoy\u00e9 un navire vers la base de Tartus, transportant des troupes de l&rsquo;infanterie de marine qui seraient charg\u00e9es de la d\u00e9fense du p\u00e9rim\u00e8tre de la base.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Russia is sending armed troops to Syria amid escalating violence there, United States military officials told NBC News Friday, in a move certain to frustrate Western efforts to put pressure on the regime of President Bashir Assad.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tLe <a href=\"http:\/\/www.debka.com\/article\/22088\/Big-powers-move-in-on-Syria-Russian-troops-for-Tartus-US-forces-ready-to-go\" class=\"gen\">16 juin 2012<\/a>, dans un rapport mettant en \u00e9vidence que l&rsquo;intervention militaire US en Syrie n&rsquo;\u00e9tait plus une question de si&rsquo; mais de quand&rsquo;, <em>DEBKAFiles<\/em> reprenait une information d\u00e9j\u00e0 publi\u00e9e le 15 juin (dans son domaine payant). A partir du rapport NBC, <em>DEBKAFiles<\/em> annon\u00e7ait que le navire transportant des troupes d&rsquo;infanterie de marine aborderait le port de Tartus dans les heures qui viennent.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>A contingent of Russian special forces is on its way to Syria to guard the Russian navy&rsquo;s deep-water port at the Syria&rsquo;s Mediterranean coastal town of Tartus, Pentagon officials informed US NBC TV Friday, June 15. They are coming by ship. According to DEBKAfile&rsquo;s sources, the contingent is made up of naval marines and is due to land in Syria in the coming hours.<\/em>\u00bb<\/p>\n<h3>L&rsquo;\u00e9tat-major russe fait de la comunication<\/h3>\n<\/p>\n<p><p>\tMais auparavant, selon les dates et heures de publication (en fonction du d\u00e9calage horaire), l&rsquo;\u00e9tat-major g\u00e9n\u00e9ral russe avait fait des d\u00e9clarations officielles contredisant les informations formelles diffus\u00e9es par les sources cit\u00e9es ci-dessus,  sans n\u00e9cessairement en contredire l&rsquo;esprit : oui, il est bien question de l&rsquo;envoi de troupes et d&rsquo;armements, mais la mission n&rsquo;est nullement entam\u00e9e&#8230; Les pr\u00e9cisions \u00e9taient donn\u00e9es de fa\u00e7on intentionnelle, avec comme premier but de communication de mettre en cause la qualit\u00e9 des informations venues, selon l&rsquo;\u00e9tat-major russes, des services de renseignement du Pentagone, la DIA. (Tass, le <a href=\"http:\/\/www.itar-tass.com\/en\/c32\/448445.html\" class=\"gen\">15 juin 2012<\/a>.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>A number of warships of the Russian Black Sea Fleet are prepared to go to Syria, the Russian General Staff told Itar-Tass on Friday. The Mediterranean Sea is a zone of the Black Sea Fleet responsibility. Hence, warships may go there in the case it is necessary to protect the Russian logistics base in Tartous, Syria, it said. Several warships of the Russian Black Sea Fleet, including large landing ships with marines aboard, are fully prepared to go on the voyage, he said. The Cesar Kunikov large landing ship of the Russian Black Sea Fleet, which is returning from Italian Messina to base, passed the Bosporus Strait on Friday. It will return to Sevastopol on Saturday, the staff said.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb[<em>The Russian General Staff <\/em>] <em>strongly denied U.S. media reports claiming that a Black Sea Fleet warship had already headed for Tartous. All the ships are staying in Sevastopol but the Cesar Kunikov large landing ship. Either the U.S. intelligence service works poorly or they have a poor knowledge of geography, the source said.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tEn compl\u00e9ment de ce qui pr\u00e9c\u00e8de, <em>Russia Today<\/em> publiait, le <a href=\"http:\/\/www.rt.com\/news\/syria-russian-ship-home-026\/\" class=\"gen\">17 juin 2012<\/a>, un article reprenant des \u00e9l\u00e9ments de Novosti sur la pr\u00e9sence tranquille et apais\u00e9e, dans le port de S\u00e9bastopol, des unit\u00e9s annonc\u00e9es par les m\u00e9dias du bloc BAO comme ayant quasiment atteint Tartus<\/p>\n<\/p>\n<p><p>\t\u00ab<em>The US media cited intelligence sources as saying last Sunday that the landing ship Nikolay Filchenkov was traveling to the Russian naval base in Tartus, Syria. The vessel was said to be carrying arms and a unit of amphibious commando troops, who would be used to secure the Russian base in the troubled country from a possible attack. The vessel, however, is still in Sevastopol, the home of the Russian Black Sea Fleet, as a journalist from the Russian news agency RIA Novosti witnessed. The ship is not even loaded, as apparent by its draft, the report says<\/em>\u00bb<\/p>\n<h3>Les Russes ne se cachent de rien<\/h3>\n<\/p>\n<p><p>\tLe m\u00eame <a href=\"http:\/\/www.debka.com\/article\/22090\/Russia-flies-anti-air-anti-ship-missiles-to-Assad-as-its-fleet-heads-to-Tartus\" class=\"gen\">17 juin 2012<\/a>, <em>DEBKAFiles<\/em> remet \u00e7a. Le site isra\u00e9lien \u00e9vacue rapidement la fausse nouvelle Pentagone-NBC qu&rsquo;il avait relay\u00e9e en donnant quelques informations de son cru  pour montrer la qualit\u00e9 de son r\u00e9seau (arriv\u00e9e \u00e0 Tartus dans les heures qui viennent), en mentionnant vaguement cette annonce ; mais l&rsquo;essentiel de l&rsquo;information de <em>DEBKAFiles<\/em> est de relayer les d\u00e9clarations \u00e0 Tass de l&rsquo;\u00e9tat-major g\u00e9n\u00e9ral russe, pour pouvoir \u00e9laborer une approche nouvelle, selon deux th\u00e8mes.<\/p>\n<\/p>\n<p><p>\tLe premier est le constat que les Russes am\u00e8nent, ou vont amener, de tr\u00e8s nombreux syst\u00e8mes pour compl\u00e9ter le r\u00e9seau anti-a\u00e9rien syrien, avec des armements tr\u00e8s avanc\u00e9s. Divers d\u00e9tails sont donn\u00e9s, tous tr\u00e8s impressionnants quant \u00e0 la qualit\u00e9 et \u00e0 la puissance des syst\u00e8mes. <em>DEBKAFiles<\/em> constate que les Russes ne se cachent pas de leurs intentions d&rsquo;armer les Syriens, comme l&rsquo;indiquent les d\u00e9clarations de l&rsquo;\u00e9tat-major g\u00e9n\u00e9ral. <em>DEBKAFiles<\/em> cite \u00e9galement celles, en date du 16 juin, de Anatoly P. Isaykine, directeur of <em>Rosoboronexport<\/em>, l&rsquo;organisme national de contr\u00f4le des exportations, parlant des syst\u00e8mes que va recevoir la Syrie : \u00ab<em>I would like to say these mechanisms are really good means of defense, a reliable defense against attacks from air or sea. This is not a threat, but whoever is planning an attack should think about this<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t<em>DEBKAFiles<\/em> aurait aussi bien pu citer Lavrov qui, tout au long de la semaine derni\u00e8re, d\u00e9mentait l&rsquo;envoi d&rsquo;h\u00e9licopt\u00e8res d&rsquo;attaque en pr\u00e9cisant que la Russie s&rsquo;en tenait \u00e0 l&rsquo;ex\u00e9cution en cours. Il pr\u00e9cisait invariablement que ces contrats portaient sur l&rsquo;\u00e9quipement de la d\u00e9fense anti-a\u00e9rienne syrienne, qui n&rsquo;a rien \u00e0 voir avec les combats terrestres contre l&rsquo;opposition, et tout avec la pr\u00e9vention d&rsquo;une possible intervention \u00e9trang\u00e8re, actuellement non autoris\u00e9e par l&rsquo;ONU (alors que les Russes estiment que la vente de ce type sp\u00e9cifique d&rsquo;armes n&rsquo;est pas couverte par l&#8217;embargo sur les armes de combat des affrontements en cours).<\/p>\n<h3>Situation confuse \u00e0 Vladivostock<\/h3>\n<\/p>\n<p><p>\tOn pourrait alors consid\u00e9rer que le texte de <em>Russia Today<\/em>, le <a href=\"http:\/\/www.rt.com\/news\/russia-ships-syria-089\/\" class=\"gen\">18 juin 2012<\/a>, confirme bien l&rsquo;envoi de navires vers Tartus, mais nullement ceux que croyaient avoir rep\u00e9r\u00e9s les SR occidentaux. Cela pourrait signifier qu&rsquo;une fois men\u00e9e \u00e0 bien l&rsquo;op\u00e9ration de communication (tenter de mettre en \u00e9vidence la fausset\u00e9 des informations du bloc BAO), l&rsquo;op\u00e9ration militaire de renforcement, autre volet de l&rsquo;affaire, est ou serait lanc\u00e9e. Pourtant, on remarque, dans l&rsquo;extrait cit\u00e9 ci-dessous, encore quelques r\u00e9serves qui semblent en contradiction avec l&rsquo;information principale<\/p>\n<\/p>\n<p><p>\t\u00ab<em>It is being reported that large Russian amphibious naval ships are steaming toward the Syrian port of Tartus, where Russian civilians and naval infrastructure are under threat from ongoing civil disorder. \u00ab\u00a0The crews of the Nikolay Filchenkov, Ceasar Kunikov and SB-15 tugboat  together with the marine units they carry  are capable of protecting security of Russian citizens and evacuating a part of the property of the logistics base,\u00a0\u00bb a source at the Russian Navy General Staff told Interfax-AVN on Monday.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>But according to an officer stationed with the Black Sea Fleet, the Nikolay Filchenkov and Ceasar Kunikov are still sitting in dock in Sevastopol. Moreover, the crew is said to be on regular service duty and are under no emergency orders. He pointed out, however, that Russian naval ships must be prepared to dispatch anywhere in the world in 12 hours notice.<\/em>\u00bb<\/p>\n<h3>En passant par le G20<\/h3>\n<\/p>\n<p><p>\tRevenons \u00e0 l&rsquo;analyse de <em>DEBKAFiles<\/em> du <a href=\"http:\/\/www.debka.com\/article\/22090\/Russia-flies-anti-air-anti-ship-missiles-to-Assad-as-its-fleet-heads-to-Tartus\" class=\"gen\">17 juin 2012<\/a>, dont nous disions qu&rsquo;elle d\u00e9veloppait deux th\u00e8mes \u00e0 partir des informations reprises, et plus ou moins r\u00e9par\u00e9es apr\u00e8s les m\u00e9sinformations de l&rsquo;analyse pr\u00e9c\u00e9dente. Avec le deuxi\u00e8me th\u00e8me, nous nous transportons au Mexique, au G20.<\/p>\n<\/p>\n<p><p>\tLe second th\u00e8me fixe comme point diplomatique central la rencontre Poutine-Obama en marge du G20, o\u00f9 les deux puissances pourraient tenter de s&rsquo;entendre sur la Syrie, ou constater leur d\u00e9saccord, ce qui conduirait \u00e0 une extension du conflit. (L&rsquo;analyse est \u00e9crit avant la rencontre.) A cette lumi\u00e8re, estime <em>DEBKAFiles<\/em>, les livraisons d&rsquo;armes russes \u00e0 la Syrie constitueraient une garantie pour la Russie en cas d&rsquo;\u00e9chec. Nous avons une interpr\u00e9tation diff\u00e9rente, qui est double (avec l&rsquo;un des volets se formant \u00e0 mesure que se d\u00e9roule l&rsquo;op\u00e9ration), qui peut \u00e9ventuellement \u00eatre compl\u00e9mentaire : d&rsquo;une part, la haute visibilit\u00e9 choisie par les Russes pour leurs livraisons \u00e0 la Syrie agirait comme une mise en garde adress\u00e9e au bloc BAO en g\u00e9n\u00e9ral, sur le tr\u00e8s grand s\u00e9rieux avec lequel la Russie entend assurer la d\u00e9fense de la Syrie face \u00e0 une intervention \u00e9trang\u00e8re. D&rsquo;autre part, toute cette op\u00e9ration, avec la confusion qui la caract\u00e9rise, peut aussi et m\u00eame d&rsquo;abord ressembler \u00e0 une op\u00e9ration de communication d&rsquo;un type nouveau. <\/p>\n<\/p>\n<p><p>\tD&rsquo;une fa\u00e7on g\u00e9n\u00e9rale, l&rsquo;observation politique de <em>DEBKAFiles<\/em> rejoint la logique de notre texte du <a href=\"http:\/\/www.dedefensa.org\/article-m_ditations_de_poutine_04_06_2012.html\" class=\"gen\">4 juin 2012<\/a>, dans lequel nous envisagions que les Russes pourraient changer nettement de politique, en d\u00e9cidant d&rsquo;abandonner le r\u00f4le de faiseur de paix qui leur a rapport\u00e9 jusqu&rsquo;ici plus de plaies et de bosses que de lauriers. L\u00e0 aussi, nous fixions la rencontre de Mexico comme un des \u00e9v\u00e8nements  d\u00e9cisifs.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Il y a certainement encore des points d&rsquo;interrogation, et l&rsquo;un des principaux est la v\u00e9ritable position d&rsquo;Obama, qui continue \u00e0 \u00eatre une \u00e9nigme parce que son habilet\u00e9 politicienne, sa distance des choses, son art exceptionnel de manipulation des forces politiques \u00e0 Washington et, surtout, des forces antagonistes au sein de son administration, ont dissimul\u00e9 sa v\u00e9ritable pens\u00e9e,  si, d&rsquo;ailleurs, il a une autre pens\u00e9e que celle de sa r\u00e9\u00e9lection. Poutine et les Russes ont gard\u00e9 un certain penchant pour Obama, et peut-\u00eatre esp\u00e8rent-ils encore quelque indication importante de sa part sur les crises en d\u00e9bat. Pour cette raison, la rencontre Poutine-Obama en marge du G20, dans deux semaines au Mexique, apr\u00e8s le refus de Poutine d&rsquo;une rencontre au G8, sera d&rsquo;une grande importance \u00e0 cet \u00e9gard.<\/em>\u00bb<\/p>\n<h3>Obama et sa feuille de route-Syst\u00e8me<\/h3>\n<\/p>\n<p><p>\tFinalement, comme on l&rsquo;a vu, cette rencontre Poutine-Obama n&rsquo;a \u00e9t\u00e9 d&rsquo;une grande importance que dans la mesure o\u00f9 elle a, en quelque sorte, confirm\u00e9 une certaine impotence d&rsquo;Obama dans le cadre de son administration, de sa position proche de l&rsquo;\u00e9lection pr\u00e9sidentielle, prisonni\u00e8re du Syst\u00e8me en g\u00e9n\u00e9ral. (Voir le <a href=\"http:\/\/www.dedefensa.org\/article-poutine_et_obama_c_te_c_te_et_face_face_19_06_2012.html\" class=\"gen\">19 juin 2012<\/a>.) Comme le r\u00e9sume fort bien Paul Craig Roberts, Obama fera ce qu&rsquo;il peut pour suivre Poutine, mais il reste qu&rsquo;il repr\u00e9sente le programme du <em>regime change<\/em> Obama a sa feuille de route, qui lui est donn\u00e9e par le Syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tC&rsquo;est pourquoi l&rsquo;annonce d&rsquo;un exercice conjoint Russie-Chine-Iran en Syrie m\u00eame, au cours d&rsquo;une op\u00e9ration massive terrestre et navale, impliquant 90.000 hommes, 400 avions et 900 chars \u00e9clata (le 19 juin) comme, disons, un coup de tonnerre silencieux La presse-Syst\u00e8me s&rsquo;en garda d&rsquo;abord comme de la peste, ignorant s&rsquo;il s&rsquo;agissait de lard et de cochon, d&rsquo;autant (pour elle, la presse-Syst\u00e8me), que la nouvelle venait de l&rsquo;agence iranienne semi-officielle FARS (le <a href=\"http:\/\/english.farsnews.com\/newstext.php?nn=9103082690\" class=\"gen\">19 juin 2012<\/a>). <em>DEBKAFiles<\/em> suivit aussit\u00f4t l&rsquo;affaire dans une nouvelle exclusive, curieusement dat\u00e9e du <a href=\"http:\/\/www.debka.com\/article\/22094\/Russia-China-Iran-plan-to-stage-in-Syria-biggest-Mid-East-maneuver\" class=\"gen\">18 juin 2012<\/a> au soir, puis le Jerusalem <em>Post<\/em> le <a href=\"http:\/\/www.debka.com\/article\/22094\/Russia-China-Iran-plan-to-stage-in-Syria-biggest-Mid-East-maneuver\" class=\"gen\">19 juin 2012<\/a>, ainsi que la TV saoudienne <em>Al-Arabiya<\/em>. Divers sites suivirent le nouvelle, pendant que rien d&rsquo;officiel,  ni confirmation, ni d\u00e9menti,  ne venaient, dans tous les cas dans les premi\u00e8res 24 heures, des pays concern\u00e9s.<\/p>\n<h3>Coup de tonnerre silencieux<\/h3>\n<\/p>\n<p><p>\tEn effet, nous parlons de coup de tonnerre silencieux parce que nul ne sait d&rsquo;o\u00f9 vient une telle id\u00e9e de manuvre, o\u00f9 elle nous conduit, ce qu&rsquo;il en est pr\u00e9cis\u00e9ment, mais aussi parce qu&rsquo;une telle \u00e9vocation, au moment o\u00f9 le sommet Poutine-Obama confirme que la crise va se poursuivre m\u00eame si le pr\u00e9sident US semble selon certaines sources de bonne volont\u00e9, fait na\u00eetre dans les esprits la possibilit\u00e9 <strong>formidable<\/strong>, m\u00eame si elle que de communication, d&rsquo;une pr\u00e9sence militaire chinoise au Moyen-Orient. Communication, nouvelle \u00e0 confirmer ou nouvelle d\u00e9mentie, peu importe,  l&rsquo;image \u00e9tait l\u00e0, elle est l\u00e0, et elle va commencer \u00e0 se d\u00e9velopper, \u00e0 porter ses fruits sp\u00e9culatifs.<\/p>\n<\/p>\n<p><p>\tTout cela paraissait-il extravagant ? Qui pouvait le dire ? Le d\u00e9partement d&rsquo;Etat qui annonce l&rsquo;arriv\u00e9e d&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-moscou-damas-hillary_et_les_h_licopt_res_irresponsables_15_06_2012.html\" class=\"gen\">h\u00e9licopt\u00e8res d&rsquo;attaque<\/a> Mi-24 <em>Hind<\/em> vendus neufs \u00e0 la Syrie, est le jour m\u00eame contredit par le Pentagone et doit revenir sur sa d\u00e9claration ; le Pentagone annonce l&rsquo;arriv\u00e9e \u00e0 Tartus de deux navires russes qui sont encore \u00e0 quai \u00e0 S\u00e9bastopol Qui peut encore donner des le\u00e7ons d&rsquo;exactitude, de v\u00e9racit\u00e9, de cr\u00e9dibilit\u00e9, dans le chaudron libyen ? Il semble que nous soyons arriv\u00e9s \u00e0 un nud infranchissable, \u00e0 la d\u00e9monstration de l&rsquo;impasse o\u00f9 se trouve le syst\u00e8me de la communication en tant que moteur de r\u00e9f\u00e9rence de l&rsquo;information au service du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tAlors, les Chinois en manuvres en Syrie ? <em>Chi lo sa<\/em>? Et qui vivra verra (Et l&rsquo;on devinait d&rsquo;ores et d\u00e9j\u00e0 que les Chinois ne doivent pas \u00eatre m\u00e9contents que cette nouvelle se r\u00e9pande, quelle que soit sa v\u00e9racit\u00e9. Dans tous les cas, elle substantive, au niveau de l&rsquo;information, une riposte chinoise aux intentions US de mettre en place une nouvelle strat\u00e9gie de pression militaire contre la Chine, avec l&rsquo;U.S. Navy croisant dans les mers qui bordent la Chine comme si elle \u00e9tait au large de la Californie.) Hier, en fin d&rsquo;apr\u00e8s-midi, la Syrie d\u00e9mentait la nouvelle (voir Novosti, le <a href=\"http:\/\/fr.rian.ru\/defense\/20120619\/195092663.html\" class=\"gen\">19 juin 2012<\/a>). L&rsquo;affaire est-elle close ? <em>Chi lo sa<\/em>? Une source comme <em>DEBKAFiles<\/em> continuait (le <a href=\"http:\/\/www.debka.com\/article\/22096\/-US-Russia-Deploy-in-Syria--Double-Prey-for-Al-Qaeda\" class=\"gen\">19 juin 2012<\/a>) \u00e0 tenir la perspective de l&rsquo;exercice pour s\u00e9rieuse, observant que la sc\u00e8ne d&rsquo;une confrontation majeure \u00e9tait ainsi mise en place,  dont les terroristes islamistes d&rsquo;al Qa\u00efda seraient les premiers b\u00e9n\u00e9ficiaires.<\/p>\n<h3>L&rsquo;accus\u00e9 devient le manipulateur<\/h3>\n<\/p>\n<p><p>\tIl nous semble qu&rsquo;\u00e0 partir de ce d\u00e9sordre que nous avons d\u00e9crit sur les mouvements de la flotte, d&rsquo;armements divers, de manuvres annonc\u00e9es et \u00e0 peine divulgu\u00e9es, est en train de s&rsquo;\u00e9baucher une nouvelle phase de la guerre de communication,  en Syrie, certes, mais aussi d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale. Peut-\u00eatre pourrait-on penser en effet qu&rsquo;il s&rsquo;agit d&rsquo;une nouvelle forme de guerre de communication en train d&rsquo;\u00eatre ma\u00eetris\u00e9e, dans ce cas par les Russes et leurs alli\u00e9s,  sans, d&rsquo;ailleurs, qu&rsquo;il l&rsquo;ait cherch\u00e9e pr\u00e9cis\u00e9ment.<\/p>\n<\/p>\n<p><p>\tCe qui est remarquable, c&rsquo;est comment, en l&rsquo;espace de quelques jours, les Russes sont pass\u00e9s de la position d&rsquo;accus\u00e9s indirects dans la crise (pour la perception-Syst\u00e8me, fausse mais tr\u00e8s puissante, qu&rsquo;ils \u00e9taient du c\u00f4t\u00e9 d&rsquo;Assad, imm\u00e9diatement condamn\u00e9 comme coupable des massacres) \u00e0 la position de quasi-manipulateurs de la crise, en jouant litt\u00e9ralement avec le d\u00e9placement ou non de leurs navires. Ils peuvent d&rsquo;autant mieux le faire qu&rsquo;en toutes choses (d\u00e9placement de navires, armements d\u00e9fensifs sol-air, base de Tartus qu&rsquo;ils louent l\u00e9galement, etc.), ils s&rsquo;estiment \u00eatre dans les limites de la l\u00e9galit\u00e9 internationale.<\/p>\n<\/p>\n<p><p>\tOn observera que des cas qu&rsquo;on pourrait juger comme similaires, mais tr\u00e8s sporadiques et tr\u00e8s sp\u00e9cifiques, se sont d\u00e9j\u00e0 produits. Il y a eu, en 2007, le cas peu connu mais qui aurait d\u00fb \u00eatre fameux du porte-avions volants (le USS <em>Enterprise<\/em>) de l&rsquo;U.S. Navy envoy\u00e9 en renfort au large de l&rsquo;Iran, et que l&rsquo;U.S. Navy fit volontairement tra\u00eener, parfois perdu dans une escale ou l&rsquo;autre, parce que l&rsquo;\u00e9tat-major \u00e9tait oppos\u00e9 \u00e0 une attaque. (Voir les <a href=\"http:\/\/www.dedefensa.org\/article-le_porte-avions_volant_18_07_2007.html\" class=\"gen\">18 juillet 2007<\/a> et <a href=\"http:\/\/www.dedefensa.org\/article-pour_en_terminer_avec_le_porte-avions_volant__03_08_2007.html\" class=\"gen\">3 ao\u00fbt 2007<\/a>.)<\/p>\n<h3>Nouvelle forme de guerre de communication<\/h3>\n<\/p>\n<p><p>\tIl s&rsquo;agit ici d&rsquo;un cas nouveau de la guerre de communication, o\u00f9 le syst\u00e8me de la communication manipule \u00e0 son avantage les productions du syst\u00e8me du technologisme (la quincaillerie, navires de guerre, armements), pour provoquer confusion et incertitude et influencer les politiques des partenaires (comme disent les Russes des pays du bloc BAO) vers le m\u00eame d\u00e9sordre. C&rsquo;est une technique quasiment oppos\u00e9e \u00e0 la politique de la canonni\u00e8re, dont l&rsquo;U.S. Navy (en temps normal, cette fois) est coutumi\u00e8re avec ses d\u00e9placements visibles et tr\u00e8s ponctuels de groupes de porte-avions.<\/p>\n<\/p>\n<p><p>\tDans ce cas classique, ce sont les productions du syst\u00e8me du technologisme qui manipulent le syst\u00e8me de la communication et donnent clairement aux directions politiques l&rsquo;option de la guerre comme une menace pour peser sur l&rsquo;\u00e9volution politique de la crise concern\u00e9e. Dans le cas actuel, le poids des Russes, mais aussi leurs manuvres, visent \u00e0 accentuer le d\u00e9sordre au sein du bloc BAO Les Russes prennent leur revanche de la phase pr\u00e9c\u00e9dente de la guerre de communication avec les massacres instantan\u00e9ment mis au d\u00e9bit du gouvernement Assad. Du coup, ce qui pourrait \u00eatre une nouvelle forme de guerre de communication tend \u00e0 supplanter, dans tous les cas pour le temps que dure la phase o\u00f9 elle se manifeste, la r\u00e9alit\u00e9 mat\u00e9rielle des forces en pr\u00e9sence ou des forces en d\u00e9placement dont elle se sert pour se manifester.<\/p>\n<h3>L&rsquo;enjeu supr\u00eame est d\u00e9sormais pr\u00e9sent<\/h3>\n<\/p>\n<p><p>\tBien entendu, il reste une question essentielle, qui est celle de savoir si l&rsquo;on en reste au stade de cette forme de guerre de communication ou bien si ce stade de la guerre de communication ne fait que pr\u00e9parer la possibilit\u00e9 de passer \u00e0 un affrontement r\u00e9el, bien entendu de type militaire o\u00f9 les forces du syst\u00e8me du technologisme jouent \u00e0 nouveau un r\u00f4le essentiel. Il est \u00e9vident que cette question est compl\u00e8tement justifi\u00e9e dans la situation actuelle de la crise syrienne.<\/p>\n<\/p>\n<p><p>\tEn fait, une telle s\u00e9quence de cette sorte nouvelle de la guerre de communication d\u00e9bouche sur une alternative. Ou bien, elle provoque un coup d&rsquo;arr\u00eat de la mont\u00e9e de la tension en ayant manifest\u00e9, au niveau de la communication, la r\u00e9alit\u00e9 de l&rsquo;enjeu qui peut \u00eatre un affrontement au plus haut niveau, avec une force suffisante pour qu&rsquo;on recherche un certain apaisement ; ou bien, si cet apaisement n&rsquo;est pas suscit\u00e9, elle renforce \u00e9videmment la possibilit\u00e9 de l&rsquo;affrontement, avec la communication qui devient la simple pr\u00e9figuration de la r\u00e9alit\u00e9 de cet affrontement, et l&rsquo;on approche de l&rsquo;enjeu supr\u00eame.<\/p>\n<\/p>\n<p><p>\tA cet \u00e9gard, il semble que le climat pr\u00e9sent, avec la pr\u00e9dominance de l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-la_raison_devenue_idiote_utile_de_l_affectivit__11_06_2012.html\" class=\"gen\">affectivit\u00e9<\/a> pour guider le jugement, ne soit pas les conditions requises pour le premier terme de l&rsquo;alternative, qu&rsquo;il le soit au contraire pour le second. A ce moment, ce passage de guerre de communication d&rsquo;une nouvelle forme aura eu comme effet de lancer une mobilisation des esprits, notamment dans la population d&rsquo;un pays comme la Russie o\u00f9 apparaissent les premiers sondages (voir ce rapport de <em>PressTV.com<\/em>, le <a href=\"http:\/\/www.presstv.ir\/detail\/2012\/06\/19\/247006\/russians-oppose-intervention-in-syria\/\" class=\"gen\">19 juin 2012<\/a>) montrant des sentiments qui suivent la ligne de la politique russe. Il suffirait d&rsquo;une aggravation soudaine de la crise dans le sens qu&rsquo;on \u00e9voque pour voir s&rsquo;affirmer en Russie une mobilisation des esprits.<\/p>\n<\/p>\n<p><p>\tDans ce cas, la crise syrienne s&rsquo;ouvre sur toutes les possibilit\u00e9s, y compris les plus graves, r\u00e9percutant notamment l&rsquo;\u00e9cho de l&rsquo;avertissement nucl\u00e9aire de Medvedev du <a href=\"http:\/\/www.dedefensa.org\/article-avertissement_nucl_aire_de_la_russie_au_g8_18_05_2012.html\" class=\"gen\">18 mai 2012<\/a>.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notes sur la flotte, S\u00e9bastopol et la Syrie, et l&rsquo;enjeu supr\u00eame La question du renforcement en armements et de la pr\u00e9sence ou pas de forces \u00e9trang\u00e8res officielles en Syrie, notamment des grandes puissances (essentiellement la Russie et le bloc BAO) prend une importance grandissante dans la crise syrienne. Cette question doit \u00eatre toujours envisag\u00e9e sur&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[3228,5531,6294,7932,2645,5714,3851,3004,6208,916,3056,3867],"class_list":["post-73209","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-crise","tag-enjeu","tag-flotte","tag-g20","tag-guerre","tag-haute","tag-mondiale","tag-nucleaire","tag-obama","tag-poutine","tag-supreme","tag-syrie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73209","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73209"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73209\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73209"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73209"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73209"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}