{"id":73248,"date":"2012-07-09T06:18:09","date_gmt":"2012-07-09T06:18:09","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/07\/09\/echos-dun-fourth-of-july\/"},"modified":"2012-07-09T06:18:09","modified_gmt":"2012-07-09T06:18:09","slug":"echos-dun-fourth-of-july","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/07\/09\/echos-dun-fourth-of-july\/","title":{"rendered":"\u00c9chos d&rsquo;un <em>Fourth of July<\/em>"},"content":{"rendered":"<p><h2 class=\"common-article\">\u00c9chos d&rsquo;un <em>Fourth of July<\/em><\/h2>\n<\/p>\n<p><p>\t9 (4) juillet 2012  Certains jours, lorsque nous nous levons, aux matines sonnantes comme tous les jours, l&rsquo;ampleur de la t\u00e2che suscite un instant d&rsquo;accablement. (Chez certains, l&rsquo;angoisse du jour est du petit matin, avant d&rsquo;entamer la t\u00e2che. C&rsquo;est toujours notre cas.) Ce matin-l\u00e0, l&rsquo;angoisse naquit aussit\u00f4t de d\u00e9couvrir, de mani\u00e8re palpable, \u00e0 mesure presque directe, combien le terme ampleur avait tout son formidable poids pour d\u00e9finir notre t\u00e2che : tant de nouvelles, de commentaires, de chroniques, allant toutes dans le sens de notre catastrophe g\u00e9n\u00e9rale, jusqu&rsquo;\u00e0 vous donner le vertige. (L&rsquo;Internet, dans certaines circonstances, vous donne, par la puissance m\u00eame de son acc\u00e8s \u00e0 l&rsquo;information dans un volume colossal, ce sentiment d&rsquo;angoisse avec le vertige qui peut aller avec, tant vous d\u00e9couvrez l&rsquo;incroyable multitude des nouvelles, dans lesquelles il vous faudra distinguer ce qui est \u00e0 prendre et ce qui est \u00e0 laisser. Sa vertu de libert\u00e9 et d&rsquo;abondance d&rsquo;information, brusquement vous accable. C&rsquo;est un moment fugace mais c&rsquo;est tout de m\u00eame un moment qui p\u00e8se) A cette lumi\u00e8re s\u00e9pulcrale, l&rsquo;annonce triomphale de la d\u00e9couverte de la <em>God particle<\/em> par le CERN nous apparaissait plut\u00f4t comme une ironie sarcastiquement sublime, bien que l&rsquo;humanit\u00e9, celle qui croit en la science, dut para\u00eet-il en \u00eatre fier. (Themis Bowcock, dans le <em>Guardian<\/em> du <a href=\"http:\/\/www.guardian.co.uk\/commentisfree\/2012\/jul\/04\/higgs-boson-discovery-giant-leap\" class=\"gen\">4 juillet 2012<\/a> : \u00ab<em>The Higgs boson discovery is another giant leap for humankind  The Cern discovery of the Higgs particle is up there with putting man on the moon  something all humanity can be proud of<\/em>\u00bb) Tout \u00e7a pour \u00e7a ? Leur <em>God particle<\/em> pour en arriver o\u00f9 nous en sommes aujourd&rsquo;hui ? (Est-ce Dieu ou est-ce le Diable qui en rit d\u00e9j\u00e0<D>? Enqu\u00eate)<\/p>\n<\/p>\n<p><p>\tEnfin, puisqu&rsquo;il s&rsquo;agissait pour l&rsquo;essentiel des nouvelles du 4 juillet 2012, nous nous tourn\u00e2mes vers la Grande R\u00e9publique, celle qui continue \u00e0 nourrir les illusions de certains par les promesses \u00e9puis\u00e9es de son <em>American Dream<\/em> pulv\u00e9ris\u00e9e dans sa folie, celle qui continue \u00e0 entretenir les frayeurs de quelques autres par les d\u00e9bris aveugles de sa  puissance m\u00e9canique tournant folle. Le 4 juillet est la f\u00eate de la c\u00e9l\u00e9bration de la Grande R\u00e9publique et leur <em>Veteran&rsquo;s Day<\/em>. C&rsquo;est donc aussi la c\u00e9l\u00e9bration du Syst\u00e8me, des illusions du Syst\u00e8me, de la critique du Syst\u00e8me et de la r\u00e9sistance au Syst\u00e8me, puisque la Grande R\u00e9publique est le cur et le moteur profonds du Syst\u00e8me. Nous d\u00e9cid\u00e2mes de choisir ce qui nous paraissait le plus significatif, \u00e0 partir de quelques noms connus, de quelques \u00e9v\u00e8nements \u00e9vidents, avec cette intention retrouv\u00e9e de repousser la masse d&rsquo;informations que nous offre l&rsquo;Internet pour effectuer le <strong>choix<\/strong> que nous dicte l&rsquo;<strong>intuition haute<\/strong>. Ainsi \u00e9carte-t-on l&rsquo;angoisse, en faisant le pari du libre choix dans l&rsquo;information du monde,  qui est l&rsquo;expression dans notre temps, le libre choix de l&rsquo;information, de notre libre-arbitre ; cela, en s&rsquo;appuyant sur ce qu&rsquo;on poss\u00e8de de lumi\u00e8re int\u00e9rieure de soi et d&rsquo;exp\u00e9rience accumul\u00e9e de la pratique d&rsquo;une vie, \u00e9tant l&rsquo;ouverture \u00e0 ce qu&rsquo;on juge \u00eatre la juste impulsion de l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-dialogues-14_de_l_intuition_haute_13_11_2010.html\" class=\"gen\">intuition haute<\/a>.<\/p>\n<\/p>\n<p><p>\t Voici d&rsquo;abord un long texte de Chris Hedges, sur <em>Truthdig.org<\/em>, le <a href=\"http:\/\/www.truthdig.com\/report\/print\/time_to_get_crazy_20120702\/\" class=\"gen\">2 juillet 2012<\/a>, sous le titre \u00ab<em>Time to Get Crazy<\/em>\u00bb. A partir de l&rsquo;histoire symbolique de la vie et de la mort du grand chef indien (<em>Native American<\/em>) <em>Crazy Horse<\/em>, tu\u00e9 \u00e0 coups de ba\u00efonnette le 5 septembre 1877, un panorama complet de cette production diabolique du <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_source_de_tous_les_maux_ddecrisis_10_09_2010.html\" class=\"gen\">d\u00e9cha\u00eenement de la Mati\u00e8re<\/a> qu&rsquo;est le capitalisme lanc\u00e9 dans son propre d\u00e9cha\u00eenement, d\u00e9pla\u00e7ant ses propres limites jusqu&rsquo;\u00e0 la marche vers l&rsquo;entropisation. On comprend, dans la parabole, qu&rsquo;il s&rsquo;agit de la description du Syst\u00e8me, dans sa corruption, sa tromperie, sa rapacit\u00e9, sa haine du <a href=\"http:\/\/www.dedefensa.org\/article-la_haine_du_principe_du_principe__31_05_2012.html\" class=\"gen\">Principe<\/a>, sa marche vers l&rsquo;entropisation. C&rsquo;\u00e9tait l&rsquo;Am\u00e9rique du <em>Gilded Age<\/em> (1865-1890), mais c&rsquo;est bien s\u00fbr le monde et l&rsquo;univers d&rsquo;aujourd&rsquo;hui, d\u00e9cha\u00een\u00e9 dans le terme de son cycle de la surpuissance s&rsquo;ab\u00eemant dans l&rsquo;autodestruction.<\/p>\n<\/p>\n<p><p>\t Sur le m\u00eame site <em>Truthdig.org<\/em>, Amy Goodman publiait le <a href=\"http:\/\/www.truthdig.com\/report\/item\/climate_change_this_is_just_the_beginning_20120703\/<D\" class=\"gen\">3 juillet 2012<\/a> un texte sur les catastrophes climatiques qui s&rsquo;abattent actuellement sur l&rsquo;Am\u00e9rique, des immenses incendies du Colorado (que les pompiers eux-m\u00eames qualifient de <a href=\"http:\/\/www.rawstory.com\/rs\/2012\/07\/04\/firefighter-colorado-wildfire-almost-surreal\/\" class=\"gen\">surr\u00e9els<\/a>, comme s&rsquo;ils parlaient du feu de l&rsquo;enfer) jusqu&rsquo;\u00e0 l&rsquo;ouragan <em>Derecho<\/em> qui a form\u00e9 une \u00e9trange marche en ligne droite de l&rsquo;Illinois en Virginie (23 morts et un million et demi de personnes priv\u00e9es d&rsquo;\u00e9lectricit\u00e9). La National Oceanic and Atmospheric Administration (NOAA) \u00e9crit que le printemps de 2012 \u00ab<em>marked the largest temperature departure from average of any season on record for the contiguous United States.<\/em> [] <em>These record temperatures in May, have been so dramatically different that they establish a new neighborhood apart from the historical year-to-date temperatures.<\/em>\u00bb Si vous le voulez bien, nous laisserons de c\u00f4t\u00e9 le complot des partisans du cas de l&rsquo;intervention humaine dans le changement climatique pour nous en tenir \u00e0 l&rsquo;\u00e9vocation de ce spectacle qui, dans la Grande R\u00e9publique et ailleurs, marque la formidable d\u00e9connexion entre les conditions naturelles du monde telles qu&rsquo;elles \u00e9voluent, pour quelque raison que ce soit, et les conditions chaotiques d&rsquo;un Syst\u00e8me qui semblerait ne pouvoir subsister, et accomplir son destin, que lorsqu&rsquo;il aurait r\u00e9duit les conditions du monde \u00e0 la mesure de l&rsquo;entropisation du monde qu&rsquo;il veut nous imposer. Sans parler de complot, ce mot qui nous accable tous, consciemment ou inconsciemment, on dira que c&rsquo;est aveuglement pur par soumission au Syst\u00e8me de ne  pas voir les liens d&rsquo;an\u00e9antissement du monde qui lient le Syst\u00e8me aux conditions g\u00e9n\u00e9rales du monde. D\u00e9cha\u00eenement de la Mati\u00e8re, certes, avec \u00e0 l&rsquo;origine notre ironie supr\u00eame,  dont il faudrait que nous soyons fiers, para\u00eet-il,  de la particule divine animant l&rsquo;\u00e9nergie dont nous faisons aujourd&rsquo;hui la puissance d\u00e9cha\u00een\u00e9e qui consume le monde. Il est bon de savoir, au Jour de l&rsquo;Effondrement, d&rsquo;o\u00f9 est partie la chose.<\/p>\n<\/p>\n<p><p>\t Quelques \u00e9chos, \u00e9galement, de diverses manifestations pour ce 4 juillet, protestations diverses, o\u00f9 il appara\u00eet que le mouvement <em>Occupy<\/em>, entre autres, se poursuit sous d&rsquo;innombrables formes et d&rsquo;innombrables fa\u00e7ons. (Voir <em>PressTV.com<\/em> ce <a href=\"http:\/\/www.presstv.ir\/detail\/2012\/07\/04\/249387\/99percenters-hold-philadelphia-demo\/\" class=\"gen\">4 juillet 2012<\/a>, pour les manifestations du 4 juillet. Voir les <a href=\"http:\/\/occupywallst.org\/\" class=\"gen\">sites<\/a> <em>Occupy<\/em> pour diverses informations.) Le mouvement a acquis sa vitesse de croisi\u00e8re, il s&rsquo;est install\u00e9 dans la vie courante, et il a d\u00e9j\u00e0 produit un <a href=\"http:\/\/www.occudoc.org\/#!home\/BlankPage_0\" class=\"gen\">documentaire<\/a> qui est un gros succ\u00e8s, sur le lancement du mouvement \u00e0 l&rsquo;automne dernier,  d&rsquo;o\u00f9 son nom, <em>American Autumn<\/em>,  ce qui nous rappelle le film du vieux John Ford, sur l&rsquo;extinction de la race <em>Native American<\/em> sous la pouss\u00e9e du Syst\u00e8me, et son titre tragique de <em>Cheyenne Autumn<\/em>. Il faut m\u00eame tenir pour significatif de l&rsquo;air du temps qu&rsquo;un site aussi exotique que <em>WhatDoesItMean<\/em>, qui est une fabrique d&rsquo;informations extraordinaires pour entretenir notre imagination cr\u00e9ative, s&rsquo;oriente r\u00e9solument, depuis quelques semaines, vers la diffusion descriptives d&rsquo;\u00e9v\u00e8nements extraordinaires d&rsquo;affrontements, de r\u00e9voltes, voire de pr\u00e9misses de la seconde Guerre Civile aux USA (voir le <a href=\"http:\/\/www.whatdoesitmean.com\/index1586.htm\" class=\"gen\">11 juin 2012<\/a> et,  justement !  le <a href=\"http:\/\/www.whatdoesitmean.com\/index1591.htm\" class=\"gen\">4 juillet 2012<\/a>). Manifestement, c&rsquo;est bien cette sorte d&rsquo;\u00e9v\u00e8nements que guette l&rsquo;esprit<\/p>\n<\/p>\n<p><p>\t Nous avons m\u00eame retrouv\u00e9 ce que nous avions compl\u00e8tement rat\u00e9 et que nous avait rappel\u00e9 une de nos lectrices-contributrices (voir le <a href=\"http:\/\/www.dedefensa.org\/article-tel_qu_il_est_vermoulu_et_titubant_05_07_2012.html\" class=\"gen\">5 juillet 2012<\/a>),  la plus grande arnaque financi\u00e8re de l&rsquo;histoire, venue sans surprise de la <em>City<\/em> londonienne,  \u00ab<em>Indeed, the scandal effects an $800 trillion dollar market  10 times the size of the real world economy<\/em>\u00bb (voir le <a href=\"http:\/\/www.washingtonsblog.com\/2012\/07\/the-biggest-banking-scam-in-world-history.html\" class=\"gen\">5 juillet 2012<\/a>). Et comme titrait (le <a href=\"http:\/\/www.reddit.com\/r\/videos\/comments\/w1w9i\/the_biggest_financial_scam_in_the_history_of_the\/\" class=\"gen\">5 juillet 2012<\/a>) le site <em>Reddit.com<\/em>, sans aucun doute : \u00ab<em>The biggest financial scam in the history of the world has just been revealed<\/em> <strong><em>and no one is paying attention<\/em><\/strong>\u00bb<\/p>\n<\/p>\n<p><p>\t\u00ab[N]<em>o one is paying attention<\/em>\u00bb,  c&rsquo;est juste mais ce n&rsquo;est pas tout \u00e0 fait vrai. Il appara\u00eet tr\u00e8s clairement que la description pr\u00e9cise, le commentaire direct, l&rsquo;appr\u00e9ciation, m\u00eame furieuse, du fait, et cela autant de fois qu&rsquo;il y en a dans le nombre astronomique d&rsquo;\u00e9v\u00e8nements impliqu\u00e9s, sont en train de devenir impuissants \u00e0 en rendre compte \u00e0 leur exacte valeur, dans une tentative vaine de leur donner leur v\u00e9ritable signification. Les quelques r\u00e9f\u00e9rences, les \u00e9v\u00e8nements rapidement d\u00e9crits ci-dessus pour f\u00eater leur <em>Fourth of July<\/em> (et Dieu sait s&rsquo;il y en a d&rsquo;autres, et Dieu sait s&rsquo;il y en a eu depuis le 4 juillet), font imm\u00e9diatement sentir qu&rsquo;il s&rsquo;agit d&rsquo;un poids impossible \u00e0 porter. La description <strong>directe<\/strong> et <strong>compl\u00e8te<\/strong> de la crise de notre univers, qui est aussi la crise de cette monstrueuse entit\u00e9 que nous nommons Syst\u00e8me, est d&rsquo;un tel poids qu&rsquo;il faudrait un Atlas pour le supporter, plus encore que le porter. Contemplant cet amoncellement de choses formidables qui nous sont rendues d\u00e9sormais ais\u00e9ment accessibles, pour qui veut s&rsquo;en donner la peine, et une peine qui n&rsquo;est pas tr\u00e8s grande sauf pour le temps qu&rsquo;elle consume, on se trouve rapidement comme le <em>sapiens<\/em> de la <a href=\"http:\/\/www.youtube.com\/watch?v=2yfePu67xoI&#038;fb_source=message\" class=\"gen\">caverne<\/a> de Platon brusquement sorti de l&rsquo;obscurit\u00e9 trompeuse o\u00f9 il a v\u00e9cu et contemplant soudain le soleil, et aussit\u00f4t aveugl\u00e9 dans une immense souffrance bien plus qu&rsquo;\u00e9clair\u00e9 par cet astre pourtant connu pour porter les vertus de la v\u00e9rit\u00e9. M\u00eame ceux qui sont habitu\u00e9s \u00e0 enqu\u00eater tout au long de l&rsquo;Internet sur les affaires du monde, m\u00eame ceux-l\u00e0 ressentent cette terrible souffrance,  et d&rsquo;ailleurs ceux-l\u00e0 plus que les autres encore,  l&rsquo;angoisse du petit matin de travail<\/p>\n<\/p>\n<p><p>\tAussit\u00f4t convoqu\u00e9e, la raison nous dit que tout est perdu,  alors, \u00e0 quoi bon tenter de comprendre, sinon de savoir ? Ou bien, elle rechigne, vous parle de dissimulation, de manoeuvres, de tromperies et de complots, et pour contrer ce qu&rsquo;elle croit \u00eatre une <em>narrative<\/em> fabrique sa propre <em>narrative<\/em> ; ou bien, elle nie tout, en bloc, et vous traite de proph\u00e8te de malheur, et sifflote : Tout va tr\u00e8s bien, madame la marquise.<\/p>\n<\/p>\n<p><p>\tMais la raison n&rsquo;a pas toujours raison, et m\u00eame fort peu ces derniers temps. Nous n&rsquo;avons pas emmen\u00e9 le lecteur jusqu&rsquo;ici pour lui dire tout net : Circulez, il n&rsquo;y a rien \u00e0 voir.<\/p>\n<h3>Poser la question, c&rsquo;est y r\u00e9pondre<\/h3>\n<\/p>\n<p><p>\tSi nous avons choisi leur <em>Fourth of July<\/em> et la Grande R\u00e9publique pour lancer ce propos et, en v\u00e9rit\u00e9, l&rsquo;<strong>\u00e9largir<\/strong> au-del\u00e0 d&rsquo;eux-m\u00eames, c&rsquo;est parce qu&rsquo;on y trouve tout r\u00e9sum\u00e9 de notre immense trag\u00e9die \u00e0 l&rsquo;\u00e9chelle d&rsquo;un univers qui hurle de souffrance sous les coups d&rsquo;un Syst\u00e8me s&rsquo;agitant furieusement comme une b\u00eate bless\u00e9e \u00e0 mort,  comme la B\u00eate elle-m\u00eame&#8230; Ainsi le d\u00e9cor est-il plant\u00e9 : nous parlons de leur Am\u00e9rique mais nous parlons en v\u00e9rit\u00e9 de notre monde <em>as a whole<\/em>, de notre civilisation (contre-civilisation), du Syst\u00e8me, de notre catastrophe. Et ce que nous \u00e9voquons, finalement, ce n&rsquo;est pas tant l&rsquo;id\u00e9e d&rsquo;un spectacle impossible \u00e0 d\u00e9crire tant les faits de la catastrophe s&rsquo;accumulent et seraient impossibles \u00e0 rapporter ; ce que nous \u00e9voquons et m\u00eame d\u00e9crivons, c&rsquo;est bien notre angoisse, celle du petit matin de travail comme celle qui ne nous quitte jamais tout \u00e0 fait, parce qu&rsquo;il s&rsquo;agit davantage d&rsquo;un spectacle <strong>impossible \u00e0 supporter<\/strong> que d&rsquo;un spectacle impossible \u00e0 d\u00e9crire. Nous vivons dans l&rsquo;insupportable pour nous-m\u00eames plus que dans l&rsquo;insupportabilit\u00e9 des choses et du monde, et c&rsquo;est cela qu&rsquo;il nous faut tout de m\u00eame supporter<\/p>\n<\/p>\n<p><p>\tCes remarques signifient que nous pla\u00e7ons la probl\u00e9matique que nous tentons d&rsquo;exprimer dans un autre domaine que celui de l&rsquo;information, de la communication, etc. ; dans un autre domaine que celui de la censure contre la libert\u00e9 de l&rsquo;information, puisqu&rsquo;il est manifeste par ailleurs que tous les acc\u00e8s sont aujourd&rsquo;hui possibles \u00e0 toutes les informations n\u00e9cessaires pour qui sait enqu\u00eater. Le domaine dans lequel nous nous pla\u00e7ons,  et cela n&rsquo;\u00e9tonnera personne parmi les lecteurs r\u00e9guliers de ce site,  est manifestement celui de la psychologie, et plus pr\u00e9cis\u00e9ment dit, des effets sur la psychologie de ces torrents d&rsquo;information d\u00e9crivant l&rsquo;\u00e9tat du monde ; c&rsquo;est bien cela, plus la question des effets sur la psychologie de l&rsquo;\u00e9tat du monde que de la perception que cette psychologie a de l&rsquo;\u00e9tat du monde ; car la psychologie, elle, dans sa vertu de perception sans conscience sourcilleuse ou fatigu\u00e9e, ne s&rsquo;y trompe pas&#8230;<\/p>\n<\/p>\n<p><p>\tCette question sur l&rsquo;\u00e9tat du monde est d\u00e9pass\u00e9e, et le monde nous le montre chaque jour, comme on l&rsquo;a vu ce <em>Fourth of July<\/em>. Il ne fait aucun doute pour nous que tous, nous sommes constamment agress\u00e9s et accabl\u00e9s, au niveau de notre psychologie, d&rsquo;une mani\u00e8re directe ou indirecte, par cette v\u00e9rit\u00e9 de l&rsquo;\u00e9tat du monde, quelle que soit la r\u00e9sistance que nous opposons \u00e0 cette perception. Cette id\u00e9e de la r\u00e9sistance que nous opposons se r\u00e9f\u00e8re au concept de r\u00e9sistance compl\u00e8tement subverti et inverti, compl\u00e8tement faussaire, par rapport \u00e0 la v\u00e9ritable signification que nous donnons \u00e0 ce concept (voir le <a href=\"http:\/\/www.dedefensa.org\/article-r_sistance_et_autodestruction_02_07_2012.html\" class=\"gen\">2 juillet 2012<\/a>). Dans ce cas, la r\u00e9sistance que nous opposons  est un fait de l&rsquo;esprit, de la raison qui prend partie, qui est plus ou moins subvertie, qui \u00e9chafaude des <em>narrative<\/em> auxquelles elle se soumet, tandis que la perception dont nous parlons est du domaine de la psychologie, c&rsquo;est-\u00e0-dire selon un processus incontr\u00f4lable parce que non consciemment manipulable. Les \u00e9v\u00e8nements qui s&rsquo;imposent \u00e0 notre psychologie sont d&rsquo;une telle force et exercent une telle pression que, dans cet affrontement entre la perception inconsciente de notre psychologie et la r\u00e9sistance d&rsquo;une raison fond\u00e9e sur l&rsquo;utilisation de la falsification de cette perception, c&rsquo;est la premi\u00e8re qui s&rsquo;impose absolument parce que le ph\u00e9nom\u00e8ne s&rsquo;est d\u00e9plac\u00e9 prioritairement au niveau de la perception inconsciente contre laquelle l&rsquo;esprit et la raison falsifi\u00e9e ne peuvent rien.<\/p>\n<\/p>\n<p><p>\tCertes, dans notre chef, \u00e0 nous <em>dedefensa.org<\/em> comme \u00e0 nombre de domaines de l&rsquo;Internet qui se constituent en antiSyst\u00e8me, ce fait est moins \u00e9vident dans la mesure o\u00f9 notre raison est beaucoup plus proche de la perception de la psychologie et refuse d&rsquo;une fa\u00e7on affirm\u00e9e et offensive, comme l&rsquo;acte <strong>vrai<\/strong> de la vraie r\u00e9sistance, l&rsquo;utilisation des m\u00e9thodes faussaires comme les <em>narrative<\/em>. L&rsquo;expression employ\u00e9e plus haut de la r\u00e9sistance que nous opposons devrait \u00e9videmment s&rsquo;exprimer, pour d\u00e9crire justement la situation dans notre chef, comme la r\u00e9sistance qu&rsquo;<strong>ils<\/strong> opposent. Ce n&rsquo;est pas pour autant que nous ne percevons pas le ph\u00e9nom\u00e8ne ainsi d\u00e9crit, notamment de plus en plus manifeste chez nombre de sujets qui se trouvent de plus en plus confront\u00e9s \u00e0 cette pression de la perception contre leur adh\u00e9sion rationnelle-faussaire aux <em>narrative<\/em> faussaires du Syst\u00e8me. Gr\u00e2ce \u00e0 notre position dans cette vraie r\u00e9sistance, nous ressentons et mesurons, comme nous l&rsquo;avons vu pr\u00e9c\u00e9demment, et bien entendu d&rsquo;une fa\u00e7on aussi lucide que sont aveugles ceux qui opposent une r\u00e9sistance \u00e0 la perception de leurs psychologies, le poids formidable que cette perception fait peser sur nos psychologies, donc sur nos esprits. L&rsquo;angoisse du petit matin est en r\u00e9alit\u00e9 un \u00e9tat second qui sous-tend d\u00e9sormais toute notre psychologie comme une v\u00e9ritable d\u00e9finition fondamentale de son fonctionnement ; et nous savons que si elle n&rsquo;est pas per\u00e7ue, \u00e0 cause de tel ou tel artifice, chez ceux qui opposent une r\u00e9sistance \u00e0 la perception de la v\u00e9rit\u00e9 du monde, elle n&rsquo;en est pas moins bien pr\u00e9sente, derri\u00e8re son maquillage de circonstance. Notre psychologie, aujourd&rsquo;hui, <strong>\u00e0 tous<\/strong>, est en soi l&rsquo;angoisse pure. (On sait bien que, chez certains, essentiellement nos dirigeants, cette angoisse se traduire par une <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_terrorisation_de_la_psychologie_ddecrisis_18_06_2012.html\" class=\"gen\">terrorisation<\/a> de l&rsquo;esprit, qui est la substantivation de l&rsquo;agr\u00e9ment d&rsquo;\u00eatre emprisonn\u00e9 par cette angoisse sans en conna\u00eetre le fondement, sans <strong>vouloir en conna\u00eetre<\/strong> le fondement, et en exprimant des r\u00e9actions hypomaniaques jusqu&rsquo;\u00e0 l&rsquo;hyst\u00e9rie. [Qui ne songerait \u00e0 la p\u00e9tulante <a href=\"http:\/\/www.dedefensa.org\/article-les_nerfs_florissants_d_hillary_l_hallucin_e_07_07_2012.html\" class=\"gen\">Hillary<\/a> ?]) <\/p>\n<\/p>\n<p><p>\tL&rsquo;on comprend bien, relevant d&rsquo;un tour d&rsquo;horizon d&rsquo;un <em>Fourth of July<\/em>, dans la quatri\u00e8me ann\u00e9e d&rsquo;une crise dans la crise (branche un peu plus spectaculaire de la crise g\u00e9n\u00e9rale, qui a acc\u00e9l\u00e9r\u00e9 cette crise g\u00e9n\u00e9rale \u00e0 partir de 2008) dont on nous jurait <a href=\"http:\/\/www.dedefensa.org\/article-l_etrange_optimisme_sans_espoir__23_05_2009.html\" class=\"gen\">neuf mois plus tard<\/a> qu&rsquo;elle \u00e9tait r\u00e9solue, l&rsquo;in\u00e9luctabilit\u00e9 de la poursuite et de l&rsquo;acc\u00e9l\u00e9ration, sans cesse, de tous ces chocs, de toutes ces fureurs agressives, de cette pression sans cesse en augmentation que produit la poursuite de la crise g\u00e9n\u00e9rale devenant <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_crise_haute_ddecrisis_20_02_2012.html\" class=\"gen\">crise haute<\/a>. Alors, la perspective qui appara\u00eet in\u00e9luctable est celle de quelque chose que nous nommerions une <strong>impasse psychologique<\/strong> devenant n\u00e9cessairement une <strong>catastrophe psychologique<\/strong>. Nous voulons exprimer par ces expressions d&rsquo;<strong>impasse psychologique<\/strong> devenant <strong>catastrophe psychologique<\/strong> une situation extr\u00eame de tension, jusqu&rsquo;\u00e0 la rupture. Il s&rsquo;agit de la tension entre la psychologie, qui re\u00e7oit la charge formidable de tous ces faits impossibles \u00e0 d\u00e9crire (ces crises sans fin devenant super-crises enchev\u00eatr\u00e9es, ces \u00e9v\u00e8nements devenus catastrophiques et per\u00e7us comme tels, ces pr\u00e9visions catastrophiques), et l&rsquo;esprit qui ne peut plus absorber tout cela, qui accueille ces crises comme des choses devenus faits presque banalis\u00e9s,  escroquerie sur un march\u00e9 de $800.000 milliards, qui soul\u00e8ve \u00e0 peine l&rsquo;int\u00e9r\u00eat,  l&rsquo;esprit qui ne peut pas ou ne veut pas, qui accepte l&rsquo;id\u00e9e de la crise g\u00e9n\u00e9rale mais est oblig\u00e9 d&rsquo;en \u00e9carter certains aspects, qui refuse l&rsquo;id\u00e9e de la crise g\u00e9n\u00e9rale mais constate partout ses signes indubitables, etc. Cette tension, quelle qu&rsquo;en soit la g\u00e9om\u00e9trie, entre la psychologie et l&rsquo;esprit, est une chose terrible qui ne cesse de s&rsquo;accro\u00eetre et qui ne peut pas ne pas d\u00e9boucher sur une rupture,  <strong>impasse psychologique<\/strong> devenant <strong>catastrophe psychologique<\/strong><\/p>\n<\/p>\n<p><p>\tBien entendu, parlant de psychologie, nous parlons de ce domaine autonome de la perception auquel nous accordons une importance consid\u00e9rable, et non de sa caricature pavlovienne, plus basse que la psychologie animale, dont on fait la tarte \u00e0 la cr\u00e8me des variations de leur Dieu-march\u00e9, la psychologie r\u00e9duit \u00e0 la variation de la comptabilit\u00e9 des investisseurs et des <em>traders<\/em>. (Cette psychologie-l\u00e0 n&rsquo;a jamais rien r\u00e9gl\u00e9 et a toujours \u00e9t\u00e9 \u00e0 la remorque des \u00e9v\u00e8nements spasmodiques du Dieu-march\u00e9. Elle n&rsquo;est rien, et m\u00eame plus manipulatrice : quel r\u00f4le jouent aujourd&rsquo;hui les march\u00e9s dans la crise ? Au contraire, ce sont eux qui sont manipul\u00e9s, comme dans le cas de la strat\u00e9gie iranienne qui est de faire monter le prix sp\u00e9culatif du p\u00e9trole par des agitations et gesticulations diverses autour du d\u00e9troit d&rsquo;Ormouz, pour affaiblir les pays du bloc BAO, et d\u00e9courager une attaque des USA dont la strat\u00e9gie se r\u00e9sume pour l&rsquo;essentiel \u00e0 la tactique de r\u00e9\u00e9lection d&rsquo;un pr\u00e9sident gardant un il attentif sur le prix de l&rsquo;essence \u00e0 la pompe.) <\/p>\n<\/p>\n<p><p>\tL&rsquo;\u00e9tat du monde est un chaos immense et sans frein, comme nous le voyions au petit matin de ce <em>Fourth of July<\/em>. Il s&rsquo;y ajoute l&rsquo;\u00e9trange circonstance que ceux qui nous avertissent des dangers de ce chaos et pr\u00e9tendent lutter contre lui, les dirigeants politiques des pays du bloc BAO, sont les premiers acteurs et cr\u00e9ateurs, et pourvoyeurs de ce chaos. (Mais l&rsquo;on comprend, lorsqu&rsquo;on sait le fonctionnement du Syst\u00e8me, que ce cas \u00e9trange est en r\u00e9alit\u00e9 une circonstance non seulement logique, mais in\u00e9luctable.) La grande question sp\u00e9culative g\u00e9n\u00e9rale qui vient d&rsquo;abord \u00e0 l&rsquo;esprit concerne en g\u00e9n\u00e9ral l&rsquo;\u00e9volution <strong>\u00e9v\u00e8nementielle<\/strong> de ce chaos, et le moment, et de quelle fa\u00e7on, il se fixera d\u00e9finitivement en un immense \u00e9v\u00e9nement de rupture (d&rsquo;effondrement). Ce que nous envisageons et observons ici, nous, c&rsquo;est que le chaos, le <strong>v\u00e9ritable chaos<\/strong>, se trouve en v\u00e9rit\u00e9 dans notre psychologie, qu&rsquo;il est devenu l&rsquo;essence de nous-m\u00eames. Nous (nous, les vrais r\u00e9sistants), nous le <strong>savons<\/strong> d\u00e9j\u00e0, qui intuitivement, qui obscur\u00e9ment, et depuis beau temps, avec notre angoisse du petit matin. Eux, les autres, ceux qui opposent une r\u00e9sistance&rsquo; \u00e0 la perception de la v\u00e9rit\u00e9 du monde, ils vont l&rsquo;apprendre, ils sont <strong>en train<\/strong> de l&rsquo;apprendre. <\/p>\n<\/p>\n<p><p>\tNous tenons qu&rsquo;il est justifi\u00e9 d&rsquo;avancer l&rsquo;hypoth\u00e8se que ce fait,  le chaos dans notre psychologie jusqu&rsquo;\u00e0  l&rsquo;<strong>impasse psychologique<\/strong> devenant <strong>catastrophe psychologique<\/strong>,  serait plus important que le chaos \u00e9v\u00e8nementiel du monde, et qu&rsquo;il m\u00e8nerait \u00e0 une rupture qui serait la source, l&rsquo;\u00e9l\u00e9ment d\u00e9clencheur, le d\u00e9tonateur de l&rsquo;effondrement Observer cela, c&rsquo;est poser la question qui vient in\u00e9vitablement lorsqu&rsquo;on observe que le chaos se trouve dans notre psychologie, et y r\u00e9pondre certes  chaos cr\u00e9ateur ou pas ? Et l&rsquo;on sait alors que l&rsquo;angoisse du petit matin n&rsquo;est pas en vain.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9chos d&rsquo;un Fourth of July 9 (4) juillet 2012 Certains jours, lorsque nous nous levons, aux matines sonnantes comme tous les jours, l&rsquo;ampleur de la t\u00e2che suscite un instant d&rsquo;accablement. (Chez certains, l&rsquo;angoisse du jour est du petit matin, avant d&rsquo;entamer la t\u00e2che. C&rsquo;est toujours notre cas.) Ce matin-l\u00e0, l&rsquo;angoisse naquit aussit\u00f4t de d\u00e9couvrir, de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[3834,6045,9535,3392,4356,3228,7394,2891,5714,2951,14949,6941,5757,8397,14950,3452,11493,5953,14951,3099,3741,4029,2755],"class_list":["post-73248","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-angoisse","tag-catastrophe","tag-chris","tag-climatique","tag-crazy","tag-crise","tag-generale","tag-grande","tag-haute","tag-hedge","tag-horse","tag-impasse","tag-inconscient","tag-intuition","tag-libor","tag-matin","tag-occupy","tag-perception","tag-petit","tag-psychologie","tag-psychologique","tag-republique","tag-resistance"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73248"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73248\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}