{"id":73261,"date":"2012-07-17T12:43:29","date_gmt":"2012-07-17T12:43:29","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/07\/17\/lete-dernier\/"},"modified":"2012-07-17T12:43:29","modified_gmt":"2012-07-17T12:43:29","slug":"lete-dernier","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/07\/17\/lete-dernier\/","title":{"rendered":"L&rsquo;\u00e9t\u00e9 dernier"},"content":{"rendered":"<p><h2 class=\"common-article\">L&rsquo;\u00e9t\u00e9 dernier<\/h2>\n<\/p>\n<p><p>\tL&rsquo;\u00e9t\u00e9 dernier se rappellera-t-il \u00e0 nous qui sommes noy\u00e9s dans un ciel qui ne sait plus retenir ses ond\u00e9es quand ne s&rsquo;en abattent pas des torrents qui nous lavent et nous laissent inond\u00e9s de lessives bleues intempestives ?<\/p>\n<\/p>\n<p><p>\tL&rsquo;\u00e9t\u00e9 dernier, nous nous assoupissions  \u00e0 l&rsquo;ombre ti\u00e9die des eucalyptus, doucement les apr\u00e8s-midi d\u00e9roulaient leur attente de la fin du jour pour que s&rsquo;\u00e9tanche enfin dans une explosion de dattes et de coriandre la soif consentie.<\/p>\n<\/p>\n<p><p>\tLe 6 ao\u00fbt, le monde apprenait que Standart and Poor&rsquo;s, une agence de notation am\u00e9ricaine certifi\u00e9e pour \u00e9valuer les risques qu&rsquo;une firme ou un organisme et bient\u00f4t les \u00c9tats fassent d\u00e9faut vis-\u00e0-vis de ses bailleurs de fonds abaissait la cote de l&rsquo;\u00c9tat f\u00e9d\u00e9ral \u00e9tasunien de AAA \u00e0 AA+. Il d\u00e9couvrait avec stupeur que le suzerain \u00e9tait faillible.<\/p>\n<\/p>\n<p><p>\tL&rsquo;horizon s&rsquo;il avait \u00e9t\u00e9 vu vers le couchant n&rsquo;\u00e9tait empreint pourtant d&rsquo;aucune s\u00e9r\u00e9nit\u00e9. La possibilit\u00e9 d&rsquo;un d\u00e9classement de la cote de cr\u00e9dit du gouvernement \u00e9tasunien \u00e9tait \u00e9voqu\u00e9e d\u00e8s 2004. (1) N&rsquo;e\u00fbt \u00e9t\u00e9 leur puissance militaire, ils d\u00e9pensent \u00e0 eux seuls plus de la moiti\u00e9 du budget militaire de la plan\u00e8te depuis des d\u00e9cennies, la perte  de leurs A aurait eu lieu plus t\u00f4t.<\/p>\n<\/p>\n<p><p>\tDepuis, une croissance <a href=\"http:\/\/fr.euronews.com\/2012\/07\/03\/economie-us-le-fmi-abaisse-ses-previsions-de-croissance\/\" class=\"gen\">tr\u00e8s modeste<\/a> accompagn\u00e9e d&rsquo;une absence de r\u00e9forme fiscale malgr\u00e9 les coupes dans les budgets sociaux n&rsquo;offre pas les conditions d&rsquo;esp\u00e9rer l&rsquo;initiation d&rsquo;une r\u00e9sorption de <a href=\"http:\/\/www.les-crises.fr\/la-dette-americaine\/\" class=\"gen\">la dette<\/a> marqu\u00e9e dans son \u00e9volution d&rsquo;une inflexion tr\u00e8s nette entre 2008 et 2009 pour le sauvetage des institutions financi\u00e8res priv\u00e9es.<\/p>\n<\/p>\n<p><p>\tLa s\u00e9curit\u00e9 des Jeux Olympiques a \u00e9t\u00e9 retir\u00e9e \u00e0 la <a href=\"http:\/\/www.guardian.co.uk\/sport\/2012\/jul\/12\/london-2012-g4s-security-crisis\" class=\"gen\">firme g\u00e9ante G4S<\/a> transnationale et transcontinentale, employant plus de 500000 personnes de par le monde, c\u00e9l\u00e8bre pour fournir ses services dans les centres de d\u00e9tention des prisonniers politiques palestiniens pendant que des missiles sol-air ont \u00e9t\u00e9 d\u00e9ploy\u00e9s pour <a href=\"http:\/\/french.news.cn\/photo\/2012-07\/14\/c_131715654_4.htm\" class=\"gen\">prot\u00e9ger<\/a> certains sites \u00e0 Londres.<\/p>\n<\/p>\n<p><p>\tVoici une s\u00e9quence de plus o\u00f9 se joue \u00e0 guichets ouverts devant des foules inertes la sc\u00e8ne de l&rsquo;\u00c9tat impuissant d\u00e9l\u00e9guant sa souverainet\u00e9 \u00e0 une entreprise priv\u00e9e elle-m\u00eame d\u00e9faillante car hypertrophi\u00e9e et min\u00e9e par le profit et l&rsquo;exhibition d&rsquo;un mat\u00e9riel militaire de d\u00e9fense disproportionn\u00e9 et d\u00e9risoirement inad\u00e9quat pour la circonstance \u00e0 l&rsquo;usage de ces m\u00eames foules g\u00e9r\u00e9es par l&rsquo;hypnose m\u00e9diatique.<\/p>\n<\/p>\n<p><p>\tDes trombes d\u00e9trempent la terre qui refuse cette eau estivale inopportune, Libor inclus,  nous obligeant \u00e0 patauger entre flaques et marigots, et \u00e9viter ruines et d\u00e9combres \u00e9l\u00e9ments r\u00e9siduels encore disponibles du d\u00e9cor occidental.<\/p>\n<\/p>\n<p><p>\tStagnation.<\/p>\n<\/p>\n<p><p>\tCroissance n\u00e9gative.<\/p>\n<\/p>\n<p><p>\tPour la premi\u00e8re fois, la demande en \u00e9nergie fossile du monde \u00e9mergent&rsquo;  exc\u00e8dera celle du monde occidental l&rsquo;an prochain.<\/p>\n<\/p>\n<p><p>\tCe petit indice peut \u00eatre annonciateur d&rsquo;un bouleversement total du march\u00e9 du p\u00e9trole, autant dire une inversion de la marche du monde.<\/p>\n<\/p>\n<p><p>\tLe <a href=\"http:\/\/www.ft.com\/intl\/cms\/s\/0\/0d6ac7c0-cbfb-11e1-aac1-00144feabdc0.html#axzz20X0WKyIz\" class=\"gen\">besoin<\/a> des pays n&rsquo;appartenant pas \u00e0 l&rsquo;OCDE sera de 47 millions barils jour versus 600.000 barils jours pour les membres du club de l&rsquo;OCDE.<\/p>\n<\/p>\n<p><p>\tL&rsquo;augmentation de la demande globale mondiale en barils est pass\u00e9e de 700.000 par jour en 2011 \u00e0 800.000 en 2012 et est pr\u00e9vue \u00e0 1 million en 2013 dans le contexte de d\u00e9pression de l&rsquo;eurozone et de la stagnation des Us(a)-Japon.<\/p>\n<\/p>\n<p><p>\tLe prix du baril est volatile, sanctions contre l&rsquo;Iran et sp\u00e9culation d\u00e9brid\u00e9e obligent, mais cette volatilit\u00e9 se maintient dans un couloir de valeurs hautes.<\/p>\n<\/p>\n<p><p>\tCette tension sur son prix a au moins un double effet, l&rsquo;enrichissement des producteurs, dont fait partie malgr\u00e9 tout l&rsquo;Iran, m\u00eame contraint dans le petit tunnel de ses d\u00e9bouch\u00e9s.<\/p>\n<\/p>\n<p><p>\tElle surtout rend profitable l&rsquo;exploitation de r\u00e9serves de p\u00e9trole moins faciles d&rsquo;acc\u00e8s que celles de l&rsquo;Orient arabe et licite l&rsquo;extraction de p\u00e9trole de qualit\u00e9 moindre, plus lourd et soufr\u00e9.<\/p>\n<\/p>\n<p><p>\tL&rsquo;int\u00e9r\u00eat strat\u00e9gique pour la r\u00e9gion va d\u00e9cliner.<\/p>\n<\/p>\n<p><p>\tLe reflux est d\u00e9j\u00e0 entam\u00e9.<\/p>\n<\/p>\n<p><p>\tL&rsquo;installation des bases \u00e9tasuniennes en Australie face \u00e0 la Chine, les guerres en Afrique en t\u00e9moignent. L&rsquo;agitation qataro-s\u00e9oudienne aussi.<\/p>\n<\/p>\n<p><p>\tLe pantin Sark\u00f6si et son d\u00e9l\u00e9gu\u00e9 chevelu au poitrail d\u00e9nud\u00e9 ont ex\u00e9cut\u00e9 la partition libyenne dans l&rsquo;ignorance du contenu du livret dans son ensemble. La nouvelle marionnette normalis\u00e9e semble actionn\u00e9e au fil de la m\u00eame rh\u00e9torique en Syrie, impotente et aveugle, engonc\u00e9e dans une Europe que lui barre une Allemagne engag\u00e9e depuis des d\u00e9cennies vers son levant russe.<\/p>\n<\/p>\n<p><p>\tDans moins d&rsquo;une d\u00e9cennie, les Palestiniens recouvriront leur patrie pleine et enti\u00e8re, ouverte \u00e0 tous ses citoyens. Ils auront su r\u00e9sister.<\/p>\n<\/p>\n<p><p>\tCette r\u00e9gion du monde aura perdu son int\u00e9r\u00eat strat\u00e9gique. L&rsquo;annonce cette semaine d&rsquo;un d\u00e9put\u00e9 du Likoud qu&rsquo;une assistance isra\u00e9lienne est fournie aux r\u00e9fugi\u00e9s syriens en Turquie souligne ave ostentation l&rsquo;ing\u00e9rence de l&rsquo;entit\u00e9 sioniste t\u00e9tanis\u00e9e par la mont\u00e9e islamiste dans la r\u00e9gion et livr\u00e9e bient\u00f4t \u00e0 elle-m\u00eame quand son tuteur <a href=\"http:\/\/www.israelnationalnews.com\/News\/News.aspx\/157842#.UAKSkBzqStA\" class=\"gen\">taille<\/a> dans son budget. De plus, son march\u00e9 de la s\u00e9curit\u00e9, c&rsquo;est-\u00e0-dire la vente d&rsquo;armements, s&rsquo;essouffle depuis que l&rsquo;Inde <a href=\"http:\/\/www.haaretz.com\/business\/india-blacklists-israel-military-industries-for-10-years-1.416993\" class=\"gen\">refuse<\/a> pour une dizaine d&rsquo;ann\u00e9es de commercer avec les entreprises isra\u00e9liennes pour corruption majeure av\u00e9r\u00e9e. <\/p>\n<\/p>\n<p><p>\tLa puissance imp\u00e9riale qui avait nou\u00e9 l\u00e0 sa destin\u00e9e h\u00e9g\u00e9monique parce que son \u00e9conomie \u00e9tait bas\u00e9e machine \u00e0 explosion mise au point par un certain Benz consommatrice de p\u00e9trole s&rsquo;est \u00e9puis\u00e9e de l&rsquo;exercice vain de cette puissance m\u00eame, traduite en pacotilles qui rouillent fich\u00e9es dans un cimeti\u00e8re de ferrailles.<\/p>\n<\/p>\n<p><p>\tAlors, cet \u00e9t\u00e9, un vent d&rsquo;Est \u00e9claircira-t-il les nu\u00e9es amoncel\u00e9es et furieuses ?<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Badia Benjelloun<\/p>\n<\/p>\n<h4>Note<\/h4>\n<p>(1)  <em>La crise du capitalisme am\u00e9ricain<\/em>, Paul Jorion, page 17, \u00e9ditions du Croquant.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00e9t\u00e9 dernier L&rsquo;\u00e9t\u00e9 dernier se rappellera-t-il \u00e0 nous qui sommes noy\u00e9s dans un ciel qui ne sait plus retenir ses ond\u00e9es quand ne s&rsquo;en abattent pas des torrents qui nous lavent et nous laissent inond\u00e9s de lessives bleues intempestives ? L&rsquo;\u00e9t\u00e9 dernier, nous nous assoupissions \u00e0 l&rsquo;ombre ti\u00e9die des eucalyptus, doucement les apr\u00e8s-midi d\u00e9roulaient leur&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[3953,6152,5252,3600],"class_list":["post-73261","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-benjelloun","tag-consommation","tag-dette","tag-petrole"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73261"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73261\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}