{"id":73262,"date":"2012-07-17T13:54:47","date_gmt":"2012-07-17T13:54:47","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/07\/17\/lavrov-et-leur-chantage\/"},"modified":"2012-07-17T13:54:47","modified_gmt":"2012-07-17T13:54:47","slug":"lavrov-et-leur-chantage","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/07\/17\/lavrov-et-leur-chantage\/","title":{"rendered":"Lavrov et leur \u201cchantage\u201d"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Lavrov et leur chantage<\/h3>\n<\/p>\n<p><p>\tLe ministre russe des affaires \u00e9trang\u00e8res Serguei Lavrov, m\u00eame s&rsquo;il garde son sang-froid et la mesure de l&rsquo;expression, n&rsquo;h\u00e9site pas moins \u00e0 d\u00e9noncer les m\u00e9thodes de chantage du bloc BAO pour obtenir l&rsquo;autorisation implicite de pouvoir enfin lancer sa guerre en Syrie, c&rsquo;est-\u00e0-dire essentiellement avoir la t\u00eate du pr\u00e9sident syrien Assad. On trouve dans les m\u00e9thodes d\u00e9nonc\u00e9es un curieux m\u00e9lange hallucin\u00e9, de sauvagerie et de conformisme formaliste,  pouvoir enfin lancer sa guerre et\/ou avoir la t\u00eate d&rsquo;Assad, mais avec la b\u00e9n\u00e9diction des instances vertueuses de la communaut\u00e9 internationale. Lavrov a pr\u00e9cis\u00e9, comme allant de soi, que la Russie (et la Chine avec elle) ne c\u00e9derait pas au chantage et ferait usage, s&rsquo;il le faut, de son droit de veto.<\/p>\n<\/p>\n<p><p>\tLavrov a donn\u00e9 ces pr\u00e9cisions lors d&rsquo;une conf\u00e9rence de presse, hier <a href=\"http:\/\/en.rian.ru\/russia\/20120716\/174629132.html\" class=\"gen\">16 juillet 2012<\/a> (voir Novosti), en marge de ses conversations avec Kofi Annan qui se trouve \u00e0 Moscou. (Annan rencontrait Poutine aujourd&rsquo;hui.)<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Russia sees elements of blackmail in the West&rsquo;s linking of new sanctions against Syria with the extension of the international observer mission there, Foreign Minister Sergei Lavrov said on Monday, and said it was unrealistic to expect Moscow to force President Assad to step down.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em> To our great distress, we see elements of blackmail, Lavrov said. They tell us, if you don&rsquo;t give us an agreement on accepting the<\/em> [<em>UN Security Council<\/em>] <MI>resolution  on Article 7 of the United Nations, then we will refuse to prolong the UN Observer Mission mandate, he added, ahead of a meeting with the UN&rsquo;s special envoy on Syria, Kofi Annan. The unarmed observers were sent to Syria following a UN Security Council vote in April, to observe compliance with Annan&rsquo;s peace plan. Moscow thinks such an approach is absolutely counterproductive and dangerous because to use the observers as bargaining chips is inadmissable, Lavrov said.<\/p>\n<\/p>\n<p><p>\tLe cas est assez simple : le bloc BAO entend faire voter une r\u00e9solution (propos\u00e9e par les principaux acolytes, USA en retrait) de demandes type-ultimatum faites \u00e0 la Syrie \u00e0 satisfaire dans les 10 jours, avec parall\u00e8lement des sanctions contre la m\u00eame Syrie impliquant l&rsquo;Article 7 de la charte de l&rsquo;ONU, lequel article implique lui-m\u00eame l&rsquo;\u00e9ventuel usage de moyens militaires dans certains cas. Il y a deux ou trois semaines (on s&rsquo;y perd entre leurs d\u00e9clarations p\u00e9remptoires) le ministre fran\u00e7ais Fabius affirmait que l&rsquo;on se fichait bien des r\u00e9sultats de la conf\u00e9rence de Gen\u00e8ve (qui ne pr\u00e9voit en rien la mise \u00e0 l&rsquo;\u00e9cart d&rsquo;Assad), que l&rsquo;on trouverait <em>subito presto<\/em> un moyen de s&rsquo;autoriser \u00e0 soi-m\u00eame une intervention militaire, et que ce moyen serait la r\u00e9f\u00e9rence \u00e0 l&rsquo;Article 7. Quant aux Russes, semblait laisser entendre Fabius, ils devront s&rsquo;y faire Face \u00e0 cette r\u00e9solution du bloc BAO qui ne se cache pas d&rsquo;\u00eatre ce qu&rsquo;elle machine, les Russes ont pr\u00e9sent\u00e9 leur propre r\u00e9solution qui concerne le renouvellement de la mission Annan. (Apr\u00e8s sa rencontre avec Poutine aujourd&rsquo;hui, Tass annon\u00e7ait, ce m\u00eame <a href=\"http:\/\/www.itar-tass.com\/en\/c32\/474257.html\" class=\"gen\">17 juillet 2012<\/a>, que Kofi Annan soutenait la demande russe de reconduction de sa mission, donc qu&rsquo;il soutenait la r\u00e9solution propos\u00e9e par les Russes.)<\/p>\n<\/p>\n<p><p>\tLe bloc BAO a ripost\u00e9 en disant qu&rsquo;il ne voterait la reconduction de la mission Annan que si les Russes (et les Chinois) votaient sa propre r\u00e9solution. On pourrait avancer que la d\u00e9marche signifie ceci : Nous ne voterons la poursuite de la mission Annan pour la paix impliquant toutes les parties (y compris le monstrueux Assad) que si vous votez notre r\u00e9solution dont le but r\u00e9el et affirm\u00e9 est de liquider Assad aussi vite que possible et, au bout du compte et si n\u00e9cessaire, de nous permettre d&rsquo;intervenir militairement (si possible avec votre aide) pour r\u00e9aliser ce programme de liquidation de l&rsquo;homme et de son r\u00e9gime. Implacable logique du bloc BAO.<\/p>\n<\/p>\n<p><p>\tLavrov nomme cela un chantage et pr\u00e9cise que la Russie ne change pas de position, d\u00fbt-il en co\u00fbter la fin de la mission Annan. Nous, nous attendons avec int\u00e9r\u00eat une riposte diplomatique ferme aux propos du Russe-<em>moujik<\/em> Lavrov qui ose traiter les membres civilisateurs du bloc BAO de ma\u00eetres-chanteurs. Dans le monde diplomatique, c&rsquo;est une insulte inacceptable. Qu&rsquo;attendent Fabius, Hague &#038; Hillary pour riposter et dire vertement son fait \u00e0 ce Lavrov-l\u00e0 ? Il faut exiger une riposte et s&rsquo;int\u00e9resser \u00e0 la forme que prendrait cette riposte, \u00e0 la fa\u00e7on dont ces diplomaties mod\u00e8les r\u00e9futeraient la caract\u00e9risation insultante qui leur est appliqu\u00e9e de ma\u00eetre-chanteurs, aux arguments qu&rsquo;ils avanceraient, \u00e0 l&rsquo;\u00e9claircissement qu&rsquo;ils apporteraient \u00e0 leur position.<\/p>\n<\/p>\n<p><p>\tEn attendant, Lavrov poursuit son uvre de cent fois remettre sur le m\u00e9tier l&rsquo;habituelle mise au point sur la politique russe en Syrie, en qualifiant d&rsquo;irr\u00e9aliste la demande des ma\u00eetres-chanteurs faite \u00e0 la Russie, de simplement pr\u00e9ciser \u00e0 Assad qu&rsquo;il doit partir, comme pr\u00e9vu dans la <em>narrative<\/em> : \u00ab<em>They tell us that we should persuade Assad to step down of his own free will. This is simply unrealistic, Lavrov said. He will not leave  not because we are protecting him, but because he has the support of a very significant part of the country&rsquo;s population. We will accept any decision by the Syrian people on who will govern Syria, as long as it comes from the Syrians themselves,<\/em>\u00bb En passant, Lavrov nous annonce qu&rsquo;il s&rsquo;inqui\u00e8te de l&rsquo;introduction en Syrie, de bonnes sources semble-t-il dire, d&rsquo;une v\u00e9ritable troisi\u00e8me force, une composante islamiste extr\u00eamement puissante d\u00e9sormais  : \u00ab<em>It is worrying that, according to multiple eyewitnesses, a so-called third force in the form of Al-Qaida and extremist organizations close to it has become active, Lavrov said. This is a tendency that has been observed in other parts of the region and threatens security.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tTout cela n&rsquo;int\u00e9resse gu\u00e8re le bloc BAO. Lorsque vous rencontrez, disons un ambassadeur ou un haut fonctionnaire du Quai dans un cocktail du genre, disons pour f\u00eater le 14 juillet, que vous lui dites que la question de la Syrie m\u00e9riterait tout de m\u00eame d&rsquo;\u00eatre d\u00e9battue, vous vous entendez r\u00e9pondre, sur un ton de comploteur imp\u00e9ratif, que la Syrie, c&rsquo;est tabou. La source qui nous a inform\u00e9 de cela poursuit en observant : \u00ab<em>Moi, je croyais que le tabou, c&rsquo;\u00e9tait r\u00e9serv\u00e9 aux sectes, \u00e0 certaines religions intol\u00e9rantes, \u00e0 cette sorte de chose, mais pas au d\u00e9bat sur la politique \u00e9trang\u00e8re qu&rsquo;on peut poursuivre dans la discr\u00e9tion d&rsquo;une r\u00e9ception bon chic bon genre<\/em>\u00bb Eh bien, non, ces temps-l\u00e0 de la tol\u00e9rance dans l&rsquo;\u00e9change des id\u00e9es, ce temps-l\u00e0 est fini. Le temps presse, d&rsquo;ailleurs, et il n&rsquo;est plus temps de r\u00e9fl\u00e9chir,  c&rsquo;est tabou&#8230; Cet \u00e9pisode tr\u00e8s anecdotique, renvoyant \u00e0 de nombreuses situations de cette sorte dans le cadre de la crise syrienne, indique qu&rsquo;on se trouve dans un territoire intellectuel quasiment paralys\u00e9 et fig\u00e9, o\u00f9 il n&rsquo;est plus question de d\u00e9battre. Il ne peut nullement \u00eatre avanc\u00e9 pour autant que les certitudes et les r\u00e9solutions sont \u00e0 la mesure de cette fixation des choses. Il est av\u00e9r\u00e9, au travers de diverses confidences, que la direction socialiste fran\u00e7aise n&rsquo;avait absolument pas pr\u00e9par\u00e9 ses dossiers de politique ext\u00e9rieure avant son arriv\u00e9e au pouvoir, qu&rsquo;elle s&rsquo;est trouv\u00e9e devant des situations inattendues pour elle, qui suscitent des incertitudes graves au plus haut niveau, mais cela n&rsquo;appara\u00eet nulle part, dans aucune position publique (la Syrie, c&rsquo;est tabou). Une situation assez proche existe en Allemagne, o\u00f9 l&rsquo;on ne cesse d&rsquo;\u00e9carter en th\u00e9orie l&rsquo;id\u00e9e d&rsquo;une intervention ext\u00e9rieure en Syrie, et o\u00f9 l&rsquo;on cosigne une proposition de r\u00e9solution dont la logique, dans les circonstances qu&rsquo;on sait, y m\u00e8ne tout droit<\/p>\n<\/p>\n<p><p>\tTout cela, y compris l&rsquo;\u00e9pisode du chantage, commence <strong>vraiment<\/strong> \u00e0 agacer les Russes. Des effets se font sentir au niveau de l&rsquo;Iran, car les Russes ont le sens de ce que Kissinger nommait le <em>linkage<\/em>, c&rsquo;est-\u00e0-dire les effets d&rsquo;une m\u00e9sentente dans un domaine de la politique \u00e9trang\u00e8re sur les autres domaines de cette politique \u00e9trang\u00e8re. Les premiers signes d&rsquo;une position nouvelle des Russes dans le groupe P5+1 qui n\u00e9gocie avec l&rsquo;Iran se font sentir, eux-m\u00eames prenant leurs distances des repr\u00e9sentants du bloc BAO pour se rapprocher des positions iraniennes. Les bureaucraties du bloc BAO concentr\u00e9es sur ce domaine n&rsquo;y comprennent rien parce que, le nez sur le guidon, exclusivement int\u00e9ress\u00e9es \u00e0 la question iranienne, elles ont \u00e0 peine entendu parler de la Syrie et des d\u00e9saccords avec la Russie dans ce domaine. C&rsquo;est le fameux cloisonnement des sujets, la compartimentation qui interdisent les vues d&rsquo;ensemble et la mesure de la globalisation de la catastrophe. Les Russes, eux, savent de quoi ils retournent. La m\u00e9sentente sur la Syrie, si elle se poursuit et s&rsquo;aggrave comme cela semble bien probable, va empoisonner toutes les relations avec ce pays.<\/p>\n<\/p>\n<p><p>\tPartout, autour de cette crise monstrueusement grossie par tant de moyens artificiels, les ench\u00e8res ne cessent de monter. Elles sont d\u00e9j\u00e0 tr\u00e8s hautes, sur le terrain avec l&rsquo;intensification des combats et la transformation des troubles en une vraie guerre civile ; tr\u00e8s hautes, du c\u00f4t\u00e9 du bloc BAO o\u00f9 aucune concession ne semble possible. Elles sont en train de devenir tr\u00e8s hautes du c\u00f4t\u00e9 russe.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 17 juillet 2012 \u00e0 13H42<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lavrov et leur chantage Le ministre russe des affaires \u00e9trang\u00e8res Serguei Lavrov, m\u00eame s&rsquo;il garde son sang-froid et la mesure de l&rsquo;expression, n&rsquo;h\u00e9site pas moins \u00e0 d\u00e9noncer les m\u00e9thodes de chantage du bloc BAO pour obtenir l&rsquo;autorisation implicite de pouvoir enfin lancer sa guerre en Syrie, c&rsquo;est-\u00e0-dire essentiellement avoir la t\u00eate du pr\u00e9sident syrien Assad.&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[4202,10206,2687,8173,2830,14965,3478,3099,5812,14966,3867],"class_list":["post-73262","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-assad","tag-bloquee","tag-france","tag-intervention","tag-lavrov","tag-maitres-chanteurs","tag-onu","tag-psychologie","tag-resolution","tag-surresponsabilite","tag-syrie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73262","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73262"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73262\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73262"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73262"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73262"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}