{"id":73266,"date":"2012-07-20T04:58:51","date_gmt":"2012-07-20T04:58:51","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/07\/20\/si-vis-pacem-para-bellum\/"},"modified":"2012-07-20T04:58:51","modified_gmt":"2012-07-20T04:58:51","slug":"si-vis-pacem-para-bellum","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/07\/20\/si-vis-pacem-para-bellum\/","title":{"rendered":"<em>Si vis pacem, para bellum<\/em>"},"content":{"rendered":"<p><h2 class=\"common-article2\"><em>Si vis pacem, para bellum<\/em><\/h2>\n<\/p>\n<p><p>\tLe site Ria Novosti a annonc\u00e9 ce <a href=\"http:\/\/fr.rian.ru\/politique\/20120718\/195390600.html\" class=\"gen\">18 juillet 2012<\/a> que le budget de la d\u00e9fense russe augmenterait de plus de 25% en 2013. Cette augmentation est suffisamment importante pour qu&rsquo;on lise l&rsquo;ensemble de la d\u00e9p\u00eache :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>En 2013, les d\u00e9penses du budget f\u00e9d\u00e9ral pour la d\u00e9fense nationale augmenteront de 25,8% par rapport \u00e0 l&rsquo;ann\u00e9e pr\u00e9c\u00e9dente, lit-on mercredi sur le site Web officiel du minist\u00e8re russe des Finances. Par ailleurs, les d\u00e9penses pour la s\u00e9curit\u00e9 nationale grimperont de 9%. Le minist\u00e8re a rendu publics mercredi les grands axes de la politique budg\u00e9taire pour 2013 ainsi que le projet de budget f\u00e9d\u00e9ral pour 2014-2015. En vertu du document, l&rsquo;ann\u00e9e prochaine, la Russie r\u00e9duira les d\u00e9penses budg\u00e9taires dans les domaines de la sant\u00e9 publique, l&rsquo;\u00e9ducation, la culture, la production cin\u00e9matographique, la politique sociale ainsi que l&rsquo;\u00e9conomie nationale.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tAinsi donc la croissance du budget militaire se fera aux d\u00e9triments d&rsquo;autres budgets pourtant sensibles comme la sant\u00e9 (pourtant un  probl\u00e8me important impactant directement la d\u00e9mographie russe) ou l&rsquo;\u00e9conomie nationale (toujours fortement touch\u00e9e par la corruption). D&rsquo;apr\u00e8s <a href=\"http:\/\/tempsreel.nouvelobs.com\/education\/20120718.AFP3216\/la-russie-augmente-le-budget-de-la-defense-reduit-celui-de-la-sante-en-2013.html\" class=\"gen\">Le Nouvel Obs<\/a>, l&rsquo;augmentation devrait \u00eatre de 18.2% en 2014 et 3.4% en 2015. L&rsquo;une des raisons de cette forte augmentation serait d&rsquo;assurer une solde d\u00e9cente aux militaires, qui pour le moment sont quelque peu sous-pay\u00e9s (et donc peu motiv\u00e9s).<\/p>\n<\/p>\n<p><p>\tCette nouvelle pourrait para\u00eetre anodine si elle n&rsquo;\u00e9tait en total contraste avec l&rsquo;attitude russe de 2009, o\u00f9 le budget militaire avait <a href=\"http:\/\/fr.rian.ru\/defense\/20090212\/120106117.html\" class=\"gen\">baiss\u00e9 de 15%<\/a> pour cause de crise \u00e9conomique. On rappellera toutefois qu&rsquo;en 2008 il y eut des d\u00e9penses exceptionnelles dues \u00e0 l&rsquo;interm\u00e8de olympique en G\u00e9orgie. La Russie renforce donc son arm\u00e9e avec un effort particulier pour les deux prochaines ann\u00e9es. Y aurait-il urgence pour le Kremlin ?<\/p>\n<\/p>\n<p>\n<p class=\"signature\"><em>Bilbo<\/em><\/p>\n<\/p>\n<p><p>\tPS : Le Pentagone serait bien incapable d&rsquo;encaisser une baisse de 15% des d\u00e9penses et on peut \u00eatre s\u00fbr qu&rsquo;il utilisera ce genre d&rsquo;information face au Congr\u00e8s.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si vis pacem, para bellum Le site Ria Novosti a annonc\u00e9 ce 18 juillet 2012 que le budget de la d\u00e9fense russe augmenterait de plus de 25% en 2013. Cette augmentation est suffisamment importante pour qu&rsquo;on lise l&rsquo;ensemble de la d\u00e9p\u00eache : \u00abEn 2013, les d\u00e9penses du budget f\u00e9d\u00e9ral pour la d\u00e9fense nationale augmenteront de&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[14],"tags":[2894,8842,3127,3164,2884,2730],"class_list":["post-73266","post","type-post","status-publish","format-standard","hentry","category-ouverture-libre","tag-armee","tag-bilbo","tag-budget","tag-militaire","tag-russe","tag-russie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73266","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73266"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73266\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73266"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73266"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73266"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}