{"id":73286,"date":"2012-07-30T06:09:39","date_gmt":"2012-07-30T06:09:39","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/07\/30\/erdogan-veut-faire-entrer-la-turquie-dans-locs\/"},"modified":"2012-07-30T06:09:39","modified_gmt":"2012-07-30T06:09:39","slug":"erdogan-veut-faire-entrer-la-turquie-dans-locs","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/07\/30\/erdogan-veut-faire-entrer-la-turquie-dans-locs\/","title":{"rendered":"Erdogan veut faire entrer la Turquie dans l&rsquo;OCS"},"content":{"rendered":"<p><h3 class=\"titrebloc\">Erdogan veut faire entrer la Turquie dans l&rsquo;OCS<\/h3>\n<\/p>\n<p><p>\tL&rsquo;\u00e9volution de la Turquie d&rsquo;Erdogan, ces deux derni\u00e8res ann\u00e9es, est un des cas les plus remarquables, les plus inattendus et les plus incertains des relations internationales,  ou plut\u00f4t, devrions-nous dire, du chaos international,  et ceci expliquant cela. La derni\u00e8re initiative en date d&rsquo;Erdogan en rajoute l\u00e0-dessus. Il s&rsquo;agit de la volont\u00e9 affirm\u00e9e mais assez discr\u00e8tement proclam\u00e9e du Premier ministre turc d&rsquo;obtenir l&rsquo;adh\u00e9sion de la Turquie \u00e0 l&rsquo;Organisation de Coop\u00e9ration de Shanghai (OCS), bas\u00e9e sur l&rsquo;axe Moscou-P\u00e9kin. L&rsquo;OCS constitue (dit d&rsquo;une fa\u00e7on sch\u00e9matis\u00e9) une sorte d&rsquo;organisation anti-OTAN, ou bien, d\u00e9crite d&rsquo;une fa\u00e7on plus audacieusement symbolis\u00e9e, une OTAN anti-OTAN. Erdogan a demand\u00e9 \u00e0 Poutine, lors de sa visite \u00e0 Moscou le 19 juillet, de soutenir cette demande, et Poutine a promis son appui. <\/p>\n<\/p>\n<p><p>\tErdogan a fait cette r\u00e9v\u00e9lation lors d&rsquo;une interview \u00e0 la cha\u00eene de t\u00e9l\u00e9vision <em>Channel 24<\/em>, tel que le rapporte notamment le site <em>BakuToday.net<\/em> le <a href=\"http:\/\/www.bakutoday.net\/turkey-wants-to-become-a-member-of-sco.html\" class=\"gen\">26 juillet 2012<\/a>. La d\u00e9claration d&rsquo;Erdogan est cit\u00e9e, annon\u00e7ant la nouvelle d&rsquo;une fa\u00e7on assez inattendue, comme un d\u00e9tail en passant \u00ab<em>Although we have done much for European integration and even created a separate Ministry, but French President Sarkozy and Chancellor Merkel blocked the process. Before the arrival of Sarkozy and Merkel, I participated in the summits of EU leaders. After the decision was made to minimize the relationship with us. But we have not suffered from it. Now everything is in front of the eyes, where Europe is where we are. Remains to be seen whether Europe until the year 2023. I invited Putin to accept Turkey into the SCO, and he promised me to consider this matter with other partners for this organization, said Erdogan<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tSur son <em>Blog<\/em> nomm\u00e9 <em>Indian PunchLine<\/em>, notre ami M K Bhadrakumar reprend la nouvelle, ce <a href=\"http:\/\/blogs.rediff.com\/mkbhadrakumar\/2012\/07\/28\/turkey-seeks-sco-membership\/\" class=\"gen\">28 juillet 2012<\/a>, non sans noter cette curieuse fa\u00e7on dont Erdogan l&rsquo;introduit, comme simple annexe, ou cons\u00e9quence on ne saurait dire, du comportement de l&rsquo;Europe vis-\u00e0-vis de la Turquie.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>In his interview, Erdogan said during his visit to Moscow earlier this month, he solicited support from President Vladimir Putin for the Turkish move. Erdogan rationalised the Turkish move in a curious way  as if it stemmed from the European Union&rsquo;s disdainful attitude toward Turkey&rsquo;s longstanding dream of membership of that organization, rather than as an intrinsic move in terms of the SCO&rsquo;s attraction.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>There was a touch of bitterness in the way he put it, alongside the schadenfreude that the Europeans themselves are in a mess nowadays. China and Russia would estimate that Erdogan follows an independent foreign policy and Turkish economy is doing well, and, in principle, Turkey makes a good partner for SCO. But, a full member?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tM K Bhadrakumar examine les diff\u00e9rents aspects de cette demande de la Turquie, et ce que cela signifierait d&rsquo;avoir la Turquie comme membre de l&rsquo;OCS. Il y a alors les innombrables enchev\u00eatrements d&rsquo;influences, de pression, d&rsquo;alliances et de partenariats, entre les diff\u00e9rents pays du Caucase et des confins de l&rsquo;Europe et de l&rsquo;Asie, la foultitude des pays-stan de l&rsquo;ancienne URSS et associ\u00e9s, avec les non moins nombreux projets d&rsquo;ol\u00e9oducs tous plus strat\u00e9giques les uns que les autres, les Grands Jeux divers et ainsi de suite. Toute cette complication permet de s\u00e9curiser nombre de th\u00e9ories sans trop risquer gros. Reste, pour l&rsquo;affaire de la Turquie et de l&rsquo;adh\u00e9sion \u00e0 l&rsquo;OCS, les choses <strong>vraiment<\/strong> essentielles.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Here, complications arise. Turkey is a NATO power and both SCO and the Western alliance would need to ponder how Turkey could belong to two security organizations at the same time, which compete for influence in the Eurasian space. The United States has so far failed in its SCO bid<\/em> [] <\/p>\n<\/p>\n<p><p>\t\u00bb<em>In the final analysis, Moscow would have an ambivalent stance. Erdogan may need to clarify where exactly Turkey stands with regard to the United States&rsquo; regional strategies. Turkey, after all, allowed the deployment of the US missile defence system on its soil, which has strategic implications for Russia. Turkey and Russia do not see eye to eye on Syria and the Middle Eastern upheaval in general. Of course, the Middle Eastern situation is evolving and it is not inconceivable that the Turkish and Russian interests may get reconciled eventually. Ankara and Moscow are in consultation regarding various approaches to a transition&rsquo; of power in Damascus and the jury is still out.<\/em> [] <em>In geopolitical terms, all things said, what stands out is Turkey&rsquo;s grand conception of its future role in world politics. The SCO membership would bring Turkey into a partnership with Russia and China, while at the same time it continues as a strong ally of the US and a NATO power and enjoys a customs union with the EU<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tA tout cela, M K Bhadrakumar ajoute la question de l&rsquo;adh\u00e9sion indienne, d\u00e9j\u00e0 pos\u00e9e par l&rsquo;Inde. L&rsquo;initiative turque va sans aucun doute rendre le probl\u00e8me pressant pour l&rsquo;Inde : que va faire l&rsquo;Inde ? Chercher \u00e0 acc\u00e9l\u00e9rer son processus d&rsquo;adh\u00e9sion ? Pour elle aussi, se poserait la question d&rsquo;une clarification strat\u00e9gique, essentiellement son attitude vis-\u00e0-vis des USA.<\/p>\n<\/p>\n<p><p>\tEn attendant, il s&rsquo;agit de comprendre la d\u00e9marche pour <strong>ce qu&rsquo;elle est<\/strong>, hors de toute appr\u00e9ciation interpr\u00e9tative, nuances, divination des arri\u00e8re-pens\u00e9es et autres. Il reste par cons\u00e9quent qu&rsquo;Erdogan demande \u00e0 Poutine de soutenir sa demande d&rsquo;adh\u00e9sion \u00e0 une organisation qui regroupe les puissances adversaires du bloc BAO ; il se fait l&rsquo;oblig\u00e9 de Poutine dans une mati\u00e8re hautement strat\u00e9gique qui, si elle aboutissait, le classerait, au moins, parmi les suspects de l&rsquo;OTAN, si pas les ennemis de l&rsquo;OTAN. Or, d&rsquo;une part la Turquie fait partie de l&rsquo;OTAN, avec l&rsquo;un ou l&rsquo;autre gage strat\u00e9gique \u00e0 cet \u00e9gard, en faveur de la grande politique-Syst\u00e8me du bloc BAO (le d\u00e9ploiement des anti-missiles BMDE \u00e9tant le principal) ; d&rsquo;autre part, la Turquie est l&rsquo;une des premi\u00e8res parmi les amis de la Syrie, et donc n\u00e9cessairement dans le <em>bandwagon<\/em> du bloc BAO. Cela est-il compatible avec une adh\u00e9sion \u00e0 l&rsquo;OCS ?<\/p>\n<\/p>\n<p><p>\tD&rsquo;autre part et <em>a contrario<\/em>, jusqu&rsquo;\u00e0 l&rsquo;affaire syrienne, et au moins depuis d\u00e9but 2009 (et m\u00eame depuis la guerre entre la G\u00e9orgie et la Russie [voir le <a href=\"http:\/\/www.dedefensa.org\/article-la_singuliere_position_de_la_turquie_18_08_2008.html\" class=\"gen\">18 ao\u00fbt 2008<\/a>]), la Turquie suivait un cours tr\u00e8s original qui l&rsquo;\u00e9loignait, d\u00e9cisivement semblait-il, du bloc BAO et la rapprochait au moins de la Russie. Sa position extr\u00eamement <a href=\"http:\/\/www.dedefensa.org\/article-le_franc-parler_de_la_turquie_08_01_2009.html\" class=\"gen\">critique<\/a> d&rsquo;Isra\u00ebl, avec <a href=\"http:\/\/www.dedefensa.org\/article-heurs_et_malheurs_de_la_paranoia_01_06_2010.html\" class=\"gen\">les incidents<\/a> qui ont suivi, en portait t\u00e9moignage. (Au reste, et malgr\u00e9 son \u00e9volution r\u00e9cente, la Turquie reste toujours en froid polaire avec Isra\u00ebl.) Selon cette logique-l\u00e0, la Turquie \u00e9tait naturellement promise \u00e0 se rapprocher de l&rsquo;OCS, et, d&rsquo;ailleurs, la Turquie a effectivement particip\u00e9 au r\u00e9cent sommet de l&rsquo;Organisation (voir le <a href=\" http:\/\/www.dedefensa.org\/article-notes_sur_le_sommet_de_l_ocs_de_p_kin_delhi_11_06_2012.html\" class=\"gen\">11 juin 2012<\/a>), comme partenaire de dialogue. Mais le statut de membre \u00e0 part enti\u00e8re va beaucoup plus loin et introduit un facteur compl\u00e8tement nouveau et compl\u00e8tement inattendu. (On lira par exemple la chronique du m\u00eame M K Bhadrakumar, du <a href=\"http:\/\/www.atimes.com\/atimes\/Middle_East\/NG24Ak01.html\" class=\"gen\">23 juillet 2012<\/a>, sur <em>Atimes.com<\/em>, qui prenait en compte la visite d&rsquo;Erdogan \u00e0 Moscou, mais sans mentionner le facteur de l&rsquo;adh\u00e9sion \u00e0 l&rsquo;OCS, chronique beaucoup trop pessimiste \u00e0 notre sens, donnant le grand r\u00f4le aux USA en tenant pour acquise l&rsquo;intervention d&rsquo;Isra\u00ebl en Syrie \u00e0 propos du chimique syrien et ainsi de suite, toutes choses <strong>compl\u00e8tement<\/strong> remise en question depuis.)<\/p>\n<\/p>\n<p><p>\tPlut\u00f4t que nous \u00e9puiser \u00e0 d&rsquo;innombrables hypoth\u00e8ses dans tous les sens, appuy\u00e9es sur toutes les informations du jour, sur les analyses aussi nombreuses que contradictoires et incontr\u00f4lables, proclamons aussit\u00f4t notre clause d&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-de_l_inconnaissance_du_systeme_13_07_2011.html\" class=\"gen\">inconnaissance<\/a>,  pour en rester au fait jug\u00e9 important par nous (la demande d&rsquo;adh\u00e9sion \u00e0 l&rsquo;OCS), apr\u00e8s avoir observ\u00e9 que les zigzag et variations de la politique turque peuvent tout aussi bien d\u00e9couler finalement du chaos que sont devenues les relations internationales que de plans divers et contradictoires. Cette annonce d&rsquo;Erdogan faite sous forme d&rsquo;allusion extr\u00eamement tordue \u00e0 l&rsquo;acte fondamental de sa demande d&rsquo;adh\u00e9sion \u00e0 l&rsquo;OCS, o\u00f9 il s&rsquo;engage vis-\u00e0-vis de Moscou,  chose extr\u00eamement s\u00e9rieuse pour Erdogan, la Russie,  tout cela montre qu&rsquo;il tient \u00e0 signaler cet acte fondamental tout en ayant conscience de son incongruit\u00e9 par rapport \u00e0 l&rsquo;\u00e9volution chaotique de la Syrie. Pour nous, s&rsquo;il faut choisir entre l&rsquo;engagement turc dans l&rsquo;affaire syrienne et la demande d&rsquo;adh\u00e9sion \u00e0 l&rsquo;OCS, c&rsquo;est le second cas qui d\u00e9passe largement le premier en importance. L&rsquo;attitude de la Turquie vis-\u00e0-vis de la Syrie se confirme pour ce qu&rsquo;elle fut au d\u00e9part, \u00e0 la fois une <a href=\"http:\/\/www.dedefensa.org\/article-la_politique_syrienne_de_la_turquie_29_02_2012.html\" class=\"gen\">question personnelle<\/a> et une question d&rsquo;orgueil national, mais qui s&rsquo;est bient\u00f4t trouv\u00e9e transform\u00e9e en une \u00e9norme cause, \u00e0 l&rsquo;image du gonflement d\u00e9mesur\u00e9e et absolument chaotique de la crise syrienne, bien au-del\u00e0 de sa v\u00e9ritable signification, et avec l&rsquo;affirmation de l&rsquo;apparence d&rsquo;un r\u00e9alignement de la Turquie sur les USA. Par contre, le tournant vers l&rsquo;OCS porte sa signification \u00e9vidente qu&rsquo;Erdogan voudrait tenter de regagner du terrain perdu dans l&rsquo;ind\u00e9pendance de sa politique, et prendre ses distances des USA en se rapprochant de l&rsquo;axe Moscou-P\u00e9kin. Voil\u00e0 \u00e0 quoi conduit la lecture la plus simple des facteurs fondamentaux du cas Erdogan-Moscou-OCS, en \u00e9cartant les multiples interf\u00e9rences qui, des informations non confirm\u00e9es, des commentaires hypoth\u00e9tiques et des complots variables, forment un bruit assourdissant emp\u00eachant l&rsquo;esprit d&#8217;embrasser la v\u00e9rit\u00e9 du monde, et que seule la d\u00e9marche d&rsquo;inconnaissance peut \u00e9carter. <\/p>\n<\/p>\n<p><p>\tLa d\u00e9marche d&rsquo;Erdogan ne nous dit rien de sa position concernant la Syrie, qui devient <strong>secondaire<\/strong>, comme la crise syrienne l&rsquo;est elle-m\u00eame et pour ce qu&rsquo;elle est elle-m\u00eame, mais tout du besoin o\u00f9 il se sent de r\u00e9\u00e9quilibrer sa position vis-\u00e0-vis des USA (et de l&rsquo;OTAN) et de l&rsquo;axe Moscou-P\u00e9kin (et de l&rsquo;OCS), en faveur du second Quoi qu&rsquo;il en soit, la perception simple qui convient nous laisse avec deux perspectives possibles :<\/p>\n<\/p>\n<p><p>\t La question des rapports de la Turquie avec l&rsquo;OTAN si l&rsquo;adh\u00e9sion de la Turquie \u00e0 l&rsquo;OCS \u00e9volue. Si la Russie et la Chine veulent vraiment se dresser face au danger de la politique de d\u00e9structuration du Syst\u00e8me, ils doivent tout faire pour acc\u00e9l\u00e9rer cette adh\u00e9sion de la Turquie. L&rsquo;OTAN se trouvera confront\u00e9e, le jour o\u00f9 la chose se ferait, avec un probl\u00e8me in\u00e9dit et explosif.<\/p>\n<\/p>\n<p><p>\t La question soulev\u00e9e \u00e9galement par M K Bhadrakumar est une autre grande perspective de sp\u00e9culation : la situation de l&rsquo;Inde si l&rsquo;adh\u00e9sion de la Turquie progresse. L&rsquo;Inde veut aussi adh\u00e9rer \u00e0 l&rsquo;OCS, et elle devrait juger assez difficile pour son statut que la Turquie y soit admise et pas elle ; et les Russes et les Chinois comprendraient cela, certes  \u00ab<em>The big question is how Turkey&rsquo;s search for SCO membership would impact on India&rsquo;s claim<\/em>\u00bb, observe M K Bhadrakumar ; il r\u00e9pond en citant la prudence de l&rsquo;attentisme chinois (maintenir \u00e0 distance les deux adh\u00e9sions). Nous y voyons une attitude de diplomate, et percevons pour notre part que les \u00e9v\u00e9nement, qui n&rsquo;ont rien \u00e0 voir avec l&rsquo;attentisme chinois, pourraient forcer la Chine, notamment, \u00e0 sortir de son attentisme \u00e0 cet \u00e9gard.<\/p>\n<\/p>\n<p><\/p>\n<p><p>\tMis en ligne le 30 juillet 2012 \u00e0 07H08<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erdogan veut faire entrer la Turquie dans l&rsquo;OCS L&rsquo;\u00e9volution de la Turquie d&rsquo;Erdogan, ces deux derni\u00e8res ann\u00e9es, est un des cas les plus remarquables, les plus inattendus et les plus incertains des relations internationales, ou plut\u00f4t, devrions-nous dire, du chaos international, et ceci expliquant cela. La derni\u00e8re initiative en date d&rsquo;Erdogan en rajoute l\u00e0-dessus. Il&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[2],"tags":[3934,3977,3737,398,11201,3378,7714,8405,584,916,2730,5508,3867,2613],"class_list":["post-73286","post","type-post","status-publish","format-standard","hentry","category-bloc-notes","tag-chaos","tag-chine","tag-erdogan","tag-europe","tag-inconnaissance","tag-inde","tag-international","tag-ocs","tag-otan","tag-poutine","tag-russie","tag-shanghai","tag-syrie","tag-turquie"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73286"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73286\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73286"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73286"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}