{"id":73292,"date":"2012-07-31T12:01:31","date_gmt":"2012-07-31T12:01:31","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/07\/31\/notes-sur-la-syrie-narrative-tournant-et-hubris\/"},"modified":"2012-07-31T12:01:31","modified_gmt":"2012-07-31T12:01:31","slug":"notes-sur-la-syrie-narrative-tournant-et-hubris","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/07\/31\/notes-sur-la-syrie-narrative-tournant-et-hubris\/","title":{"rendered":"Notes sur la Syrie, \u2013 <em>narrative<\/em>, \u201ctournant\u201d et <em>hubris<\/em>"},"content":{"rendered":"<p><h2 class=\"common-article\">Notes sur la Syrie,  <em>narrative<\/em>, tournant et <em>hubris<\/em><\/h2>\n<\/p>\n<p><p>\tPlusieurs traits remarquables sont \u00e0 mettre en \u00e9vidence dans l&rsquo;\u00e9volution de la crise syrienne. Nous en d\u00e9taillons ci-dessous quelques-uns, pour pouvoir mieux introduire une rapide r\u00e9flexion sur ce que nous percevons de la nature de l&rsquo;\u00e9volution de cette crise.<\/p>\n<\/p>\n<p><p>\tLe point de d\u00e9part, \u00e0 la fois des constats que nous faisons, \u00e0 la fois des r\u00e9flexions que nous proposons, s&rsquo;appuie sur notre affirmation d\u00e9j\u00e0 plusieurs fois r\u00e9p\u00e9t\u00e9e de l&rsquo;inflation grotesque de la crise syrienne. Les explications g\u00e9opolitiques de son importance, le plus souvent de la part des adversaires du bloc BAO, viennent toujours apr\u00e8s que cette importance \u00e9norme se soit exprim\u00e9e, dans la manufacture m\u00eame, de communication, de la crise (et nullement avant qu&rsquo;elle n&rsquo;\u00e9clate). C&rsquo;est une d\u00e9marche classique de la raison subvertie au Syst\u00e8me, y compris chez ceux qui font profession d&rsquo;\u00eatre antiSyst\u00e8me.<\/p>\n<\/p>\n<p><p>\tIl s&rsquo;agit en r\u00e9alit\u00e9, par rapport \u00e0 d&rsquo;autres remous, d&rsquo;une crise <em>per se<\/em> d&rsquo;importance tr\u00e8s moyenne. Mais l&rsquo;appr\u00e9ciation qui en a \u00e9t\u00e9 faite, l&rsquo;intervention massive de la communication, l&rsquo;influence massive de ces \u00e9l\u00e9ments sur la psychologie, les \u00e9volutions qui en d\u00e9coulent, ont compl\u00e8tement <strong>transmut\u00e9<\/strong> la crise syrienne. Il s&rsquo;agit d\u00e9sormais d&rsquo;une crise symbolique et de communication exprimant, non pas l&rsquo;importance de la Syrie, mais la crise fondamentale du Syst\u00e8me. Ainsi Washington vient-il en premi\u00e8re ligne.<\/p>\n<h3>\u00c9chec du <em>marketing<\/em>-massacre<\/h3>\n<\/p>\n<p><p>\tLes sites et chroniqueurs sp\u00e9cialis\u00e9s dans le d\u00e9pistage des montages de la <em>narrative<\/em> du bloc BAO sur la situation syrienne semblent atteindre une conclusion g\u00e9n\u00e9rale : il y a un tournant dans la communication sur la crise syrienne, dans le sens o\u00f9 la v\u00e9rit\u00e9 de la situation s&rsquo;affirme. Il s&rsquo;agit, dans ce cas, de la mise en \u00e9chec de ce qu&rsquo;on d\u00e9signe sous l&rsquo;expression aimable de politique du <em>marketing<\/em>-massacre, \u00e9pisode et tactique anti-Assad fondamentales de ces derniers mois.<\/p>\n<\/p>\n<p><p>\t Le site <em>Moon of Alabama<\/em> (MoA) pour les amis, effectivement sp\u00e9cialis\u00e9 dans ce domaine, indique, le <a href=\"http:\/\/www.moonofalabama.org\/2012\/07\/syria-a-turn-in-western-media-coverage.html\" class=\"gen\">28 juillet 2012<\/a>, sous le titre \u00ab<em>Syria: A Turn In<\/em> <strong><em>Western<\/em><\/strong> <em>Media Coverage?<\/em>\u00bb : \u00ab<em>There seems to be slight turn in the western media coverage of Syria. Here in Germany the press has now more reports showing the rebels as what they really are: traveling jihadists and foreign paid rabble<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Saman Mohammadi, le <a href=\"http:\/\/disquietreservations.blogspot.co.uk\/2012\/07\/flipping-script-western-medias-syria.html\" class=\"gen\">29 juillet 2012<\/a> sur son site <em>The Excavator<\/em>, repris sur <em>Infowars<\/em> le m\u00eame <a href=\"\/%E2%80%AAhttp:\/\/www.infowars.com\/flipping-the-script-the-western-medias-syria-propaganda-is-falling-apart\/%E2%80%AC\" class=\"gen\">29 juillet 2012<\/a> , sous le titre \u00ab<em>Flipping The Script: The Western Media&rsquo;s Syria Propaganda Is Falling Apart<\/em>\u00bb : \u00ab<em>The establishment media no longer has a monopoly on reality. Official lies are challenged, buried truths are dug up, and objective reality is preserved. The magician&rsquo;s tricks have been revealed by spoilers in the crowd. The global alternative media is rising and it is an engine of peace, liberation, understanding, and sanity. Even mainstream media figures are forced to admit that they have been lying to the world about nearly everything and that their warmongering views are not mainstream<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Effectivement, diverses sources dans la presse-Syst\u00e8me commencent \u00e0 donner des t\u00e9moignages et des appr\u00e9ciations d\u00e9favorables aux rebelles, donc s&rsquo;\u00e9cartant r\u00e9solument de la ligne-Syst\u00e8me. Le site MoA signale le <em>blog<\/em> d&rsquo;Alex Thomson, de la TV <em>Channel Four<\/em>, par exemple ce <a href=\"http:\/\/blogs.channel4.com\/alex-thomsons-view\/syria\/2469\" class=\"gen\">28 juillet 2012<\/a>. (Alex Thomson a de toutes les fa\u00e7ons eu depuis longtemps une attitude tr\u00e8s inhabituelle par rapport \u00e0 la presse-Syst\u00e8me. On se rappelle son intervention sur <em>Russia Today<\/em>, le <a href=\"http:\/\/www.dedefensa.org\/article-un_t_moignage_essentiel_d_un_journaliste_en_syrie_09_06_2012.html\" class=\"gen\">9 juin 2012<\/a>. [Le nom de Thompson \u00e9tait alors erron\u00e9ment orthographi\u00e9, sur ce site, avec un p, qu&rsquo;il n&rsquo;a pas en r\u00e9alit\u00e9 : il s&rsquo;agit bien d&rsquo;Alex Thomson.])<\/p>\n<\/p>\n<p><p>\t Les lib\u00e9raux progressistes eux-m\u00eames, sp\u00e9cifiquement la faction dominante des interventionnistes(<em>liberal hawks<\/em>) commencent \u00e0 craindre l&rsquo;influence, dans leur propre camp, de ceux qui sont rest\u00e9s antiguerre, qui se trouvent renforc\u00e9s par le changement \u00e9vident du cours de l&rsquo;information. D&rsquo;o\u00f9 des appels de plus en plus pressants au regroupement, si n\u00e9cessaire en plaidant la cause d&rsquo;une insurrection qui, pour r\u00e9ussir, devrait se d\u00e9barrasser du soutien int\u00e9ress\u00e9 des imp\u00e9ralistes (USA en t\u00eate). (Voir l&rsquo;article de Richard Seymour, dans le <em>Guardian<\/em> du <a href=\"http:\/\/www.guardian.co.uk\/commentisfree\/2012\/jul\/26\/antiwar-left-syria-uprising\" class=\"gen\">26 juillet 2012<\/a> : \u00ab<em>The anti-war left&rsquo;s concerns over Syria are understandable, but ill-founded  There may have been outside attempts to hijack the Syria uprising, but evidence suggests this is still a popular revolution<\/em>\u00bb.)<\/p>\n<\/p>\n<p><p>\t\u00a0Le <em>Guardian<\/em>, jusqu&rsquo;alors porte-drapeau de l&rsquo;interventionnisme maximaliste, se signale \u00e9galement par tel article estimant qu&rsquo;un compromis est possible, selon une fraction de l&rsquo;opposition moins int\u00e9ress\u00e9e \u00e0 faire le proc\u00e8s d&rsquo;Assad qu&rsquo;\u00e0 faire cesser les violences (voir le <a href=\"http:\/\/www.guardian.co.uk\/commentisfree\/2012\/jul\/29\/syria-route-of-compromise\" class=\"gen\">29 juillet 2012<\/a>), tel autre mettant l&rsquo;accent sur la p\u00e9n\u00e9tration d&rsquo;al Qa\u00efda, notamment dans la bataille d&rsquo;Alep (voir le <a href=\"http:\/\/www.guardian.co.uk\/world\/2012\/jul\/30\/al-qaida-rebels-battle-syria\" class=\"gen\">31 juillet 2012<\/a>).<\/p>\n<h3>Diversification et \u00e9volution de la crise<\/h3>\n<\/p>\n<p><p>\tIl est certes \u00e9vident que des nouvelles importantes, nous dirions objectives, ont tr\u00e8s largement secou\u00e9 la <em>narrative<\/em> g\u00e9n\u00e9rale et rendu de plus en plus difficile son \u00e9nonc\u00e9 imperturbable. On en a vu quelques exemples venus d&rsquo;Allemagne, particuli\u00e8rement marquants, le <a href=\"http:\/\/www.dedefensa.org\/article-pourquoi_pas_al_qa_da_dans_l_otan__25_07_2012.html\" class=\"gen\">25 juillet 2012<\/a>.<\/p>\n<\/p>\n<p><p>\tIl y a donc un changement de tendance perceptible, qui concerne la description des rebelles particuli\u00e8rement. Il s&rsquo;agit de l&rsquo;appr\u00e9ciation, dite d&rsquo;abord par le ministre des affaires \u00e9trang\u00e8res russe Lavrov, qu&rsquo;al Qa\u00efda (tout ce qui se regroupe sous ce label) est devenu le troisi\u00e8me acteur de la crise, \u00e0 c\u00f4t\u00e9 du r\u00e9gime Assad et de l&rsquo;opposition acceptable \u00e0 ce r\u00e9gime. Et cette intrusion constitue \u00e9videmment un tr\u00e8s grave d\u00e9menti de la th\u00e8se humanitariste de la <em>narrative<\/em> du bloc BAO.<\/p>\n<\/p>\n<p><p>\tCe changement nous para\u00eet irr\u00e9versible \u00e0 cause de l&rsquo;\u00e9volution de la crise sur le terrain, de sa transformation en guerre civile,  cette qualification devant \u00eatre accept\u00e9e m\u00eame s&rsquo;il y a des \u00e9l\u00e9ments ext\u00e9rieurs \u00e0 la Syrie. Il y a de toutes les fa\u00e7ons des \u00e9l\u00e9ments syriens qui s&rsquo;affrontent, sur lesquels se greffent des interventions ext\u00e9rieures, et, d\u00e8s lors que les op\u00e9rations ont pris le tour qu&rsquo;on leur voit, on peut parler de guerre civile. Une analogie historique du mod\u00e8le,  analogie op\u00e9rationnelle et m\u00e9thodologique, mais en aucun cas id\u00e9ologique et g\u00e9opolitique,  est la guerre civile d&rsquo;Espagne de 1936. Mais il y avait en 1936-1939 <strong>beaucoup plus<\/strong> de sp\u00e9cificit\u00e9s propres \u00e0 l&rsquo;\u00e9v\u00e8nement pour arguer de son importance ; la grande diff\u00e9rence de la guerre civile syrienne est l&rsquo;<strong>\u00e9norme<\/strong> importance de la communication, qui donne \u00e0 cet \u00e9v\u00e9nement un poids refl\u00e9tant bien plus fortement encore les tensions ext\u00e9rieures \u00e0 lui-m\u00eame, et les tensions globales principalement,  et la principale d&rsquo;entre elles, qui est la crise terminale du Syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tCette importance op\u00e9rationnelle nouvelle du conflit rend quasiment impossible de faire subsister la <em>narrative<\/em> du bloc BAO concernant les rebelles, parce que ceux-ci sont d\u00e9sormais plus visibles et identifiables. Cela va d\u00e9gager la crise syrienne d&rsquo;une partie importante de sa gangue de terrorisation des psychologies.<\/p>\n<h3>Alep, la m\u00e8re de toutes les batailles ?<\/h3>\n<\/p>\n<p><p>\tIl est toujours risqu\u00e9 d&rsquo;utiliser l&rsquo;expression la m\u00e8re de tous les batailles, inaugur\u00e9 par Saddam en 1991. Les rebelles l&rsquo;ont employ\u00e9e pour la bataille d&rsquo;Alep, sans aucun doute parce qu&rsquo;ils \u00e9taient s\u00fbrs de l&#8217;emporter tr\u00e8s rapidement, d&rsquo;une fa\u00e7on d\u00e9cisive.<\/p>\n<\/p>\n<p><p>\tQu&rsquo;est-ce que signifie \u00eatre s\u00fbr, dans de telles occurrences ? \u00c9ventuellement, \u00e9couter sa propre <em>narrative<\/em> et se prendre \u00e0 y croire ? Ou y croire avant m\u00eame de la diffuser ? La th\u00e8se actuellement la plus admise est bien qu&rsquo;effectivement les rebelles, mais aussi leurs divers parrains attendaient beaucoup et surtout <strong>tr\u00e8s rapidement<\/strong> de la bataille d&rsquo;Alep. Il est vrai que, la semaine derni\u00e8re, Hillary Clinton assurait, tr\u00e8s s\u00fbre d&rsquo;elle, que les rebelles avan\u00e7aient partout et qu&rsquo;ainsi allait pouvoir \u00eatre cr\u00e9\u00e9e, <em>de facto<\/em> dirait-on ironiquement, une zone rebelle qui pourrait devenir une <em>no fly zone<\/em>, laquelle assurerait une intervention en douceur ; ce serait une sorte de nouvelle version de l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-mcfaul_ambassadeur-syst_me_moscou_15_06_2012.html\" class=\"gen\">agression douce<\/a>.<\/p>\n<\/p>\n<p><p>\tLes nouvelles, telles qu&rsquo;on peut les collecter semblent dire que la bataille d&rsquo;Alep n&rsquo;a pas tenu ce qu&rsquo;elle promettait de ce point de vue. La m\u00e8re de toutes les batailles ? Oiseau de mauvais augure pour qui utilise l&rsquo;expression<\/p>\n<h3>Croire soi-m\u00eame \u00e0 sa propre <em>narrative<\/em> ?<\/h3>\n<\/p>\n<p><p>\tIl semble que <em>DEBKAFiles<\/em> ait, ce <a href=\"http:\/\/www.debka.com\/article\/22223\/The-bid-for-Syria's-first-safe-haven-in-Aleppo-region-is-thwarted\" class=\"gen\">30 juillet 2012<\/a>, une version d\u00e9taill\u00e9e des r\u00e9actions de ceux qui attendaient une victoire <strong>tr\u00e8s rapide<\/strong> \u00e0 Alep pour pouvoir mettre un pied en Syrie, en se pla\u00e7ant dans la dynamique de communication de l&rsquo;\u00e9v\u00e8nement. L\u00e0 aussi, il semblerait que la <em>narrative<\/em> fasse des ravages, y compris dans les rangs de ceux qui la manipulent et qui, entre eux, finissent pas y croire.<\/p>\n<\/p>\n<p><p>\tLes d\u00e9tails donn\u00e9s par le texte de <em>DEBKAFiles<\/em>, notamment concernant l&rsquo;identit\u00e9 des forces rebelles \u00e0 Alep (des extr\u00e9mistes type-al Qa\u00efda) donnent du cr\u00e9dit \u00e0 cette version, compte tenu des <a href=\"http:\/\/www.dedefensa.org\/article-la_syrie_de_al_qaida_a_debkafiles__13_02_2012.html\" class=\"gen\">connexions<\/a> du site. L&rsquo;on se trouve dans le cas de figure o\u00f9 Isra\u00ebl ne veut pas entendre parler d&rsquo;une victoire rebelle, qui serait islamiste, et ses sources ont alors int\u00e9r\u00eat \u00e0 diffuser au maximum les informations disponibles \u00e0 cet \u00e9gard.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Monday morning, Saudi and Qatari intelligence officers, based in Free Syrian Army headquarters at Apaydin in the southwest Turkish Hatay region, were forced to admit that Bashar Assad&rsquo;s army had smashed their plan for a safe haven in the Aleppo area. Territory was to have been seized by rebels and converted into the base of the forward FSA command and the seat of a transitional government, in the same way as the Benghazi rebel headquarters was established in 2011 six months before Muammar Qaddafi&rsquo;s overthrow.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>The FSA&rsquo;s Saudi and Qatari backers said they had received from Washington a qualified undertaking to share in the defense of a safe haven if one could be established and to diversify its aid to the rebels. Last week, US Secretary of State Hillary Clinton remarked: More and more territory is being taken. It will eventually result in a safe haven inside Syria. Sources in Washington then reported the Obama administration to be weighing options for more direct involvement in the Syrian civil war if the rebels were able to wrest enough territory for a safe haven.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>So certain were the Saudis that their Aleppo scheme would succeed that Saturday, July 28, they convened a meeting of Arab UN delegations in Cairo to formulate the text of a motion for the UN Security Council to recognize the safe havens rising in Syria and calling on UN members to support them.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>That step has proved premature in the light of anti-Assad forces inability to hold out against the government&rsquo;s military onslaught  an inability partly attributed by DEBKAfile&rsquo;s military sources to chaotic relations within the insurrectionist movement. The battle for Aleppo is being fought mainly by a splinter rebel group which rejects the authority of the FSA command in Turkey and refuses to obey its orders. It is led by Col. Abdel Jabbar al-Okaidi, who claims to represent the FSA. However, most of his fighters do not belong to the main rebel force but to a radical Islamic militia calling itself Banner of Islam. Many of them are al Qaeda jihadis arriving in Syria from Iraq and Libya.<\/em>\u00bb<\/p>\n<h3>Le vague artistique de Panetta<\/h3>\n<\/p>\n<p><p>\tLes commentaires officiels les plus circonstanci\u00e9s concernant la bataille d&rsquo;Alep ont \u00e9t\u00e9 ceux du secr\u00e9taire \u00e0 la d\u00e9fense (US) Leon Panetta, et l&rsquo;on note alors le fait que Panetta reste plut\u00f4t vague quant au sort de la bataille. La <em>narrative<\/em> humanitaire, qui n&rsquo;a plus gu\u00e8re de massacres sign\u00e9s et authentifi\u00e9s \u00e0 se mettre sous la dent, tombe dans l&rsquo;argument le plus grossier : toute attaque, toute bataille des forces d&rsquo;Assad en Syrie est simplement class\u00e9e attaque contre le peuple syrien, et le reste \u00e0 l&rsquo;avenant. (Observation de Alex Thomson r\u00e9pondant \u00e0 une question : \u00ab<em>But why is the Syrian army shelling its own people? You could just as easily ask why are the rebels using the Syrian people as human shields? It&rsquo;s a dirty civil war and the rebels sometimes choose to fight in residential areas<\/em>\u00bb)<\/p>\n<\/p>\n<p><p>\tAlors, victoire ou d\u00e9faite \u00e0 Alep ? <em>Antiwar.com<\/em> remarque \u00e0 propos des d\u00e9clarations de Panetta (le <a href=\"http:\/\/news.antiwar.com\/2012\/07\/29\/syrian-rebels-send-mixed-messages-on-aleppo-fighting\/&#8236;\" class=\"gen\">30 juillet 2012<\/a>) :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Secretary of Defense Leon Panetta appeared to try to avoid guessing which of the two was going to happen, and instead insisted only that Aleppo would be a nail in Assad&rsquo;s coffin in some vague manner, and will assure that his regime is going to be ousted. Whether Assad needs to be ousted for losing Aleppo or ousted for winning Aleppo is just a detail<\/em>\u00bb<\/p>\n<h3>Le Washington <em>Post<\/em> perd patience<\/h3>\n<\/p>\n<p><p>\tCette position assez vague de Panetta refl\u00e8te plut\u00f4t un \u00e9tat d&rsquo;esprit Peut-\u00eatre <em>PressTV.com<\/em> a-t-il raison lorsqu&rsquo;il \u00e9crit (le <a href=\"http:\/\/www.presstv.ir\/detail\/2012\/07\/29\/253425\/us-rages-at-syria-success-against-rebels\/\" class=\"gen\">29 juillet 2012<\/a>) \u00ab<em>US rages at Syria forces success against rebels in Aleppo<\/em>\u00bb. Mais l&rsquo;indice le plus important est certainement l&rsquo;\u00e9ditorial du Washington <em>Post<\/em> (WP) du <a href=\"http:\/\/www.washingtonpost.com\/opinions\/a-time-for-leadership-on-syria\/2012\/07\/27\/gJQA2v8mEX_story.html\" class=\"gen\">28 juillet 2012<\/a>, qui constitue une des formes favorites de message du Syst\u00e8me \u00e0 ses divers employ\u00e9s.<\/p>\n<\/p>\n<p><p>\tL&rsquo;\u00e9ditorial se lit simplement comme le temps de la patience est pass\u00e9e. Il prend manifestement en compte l&rsquo;hypoth\u00e8se que la bataille d&rsquo;Alep ne sera pas gagn\u00e9e, ou pour le moins ne sera pas gagn\u00e9e de toutes les fa\u00e7ons comme elle aurait d\u00fb l&rsquo;\u00eatre, et il d\u00e9roule la <em>narrative<\/em> d\u00e9j\u00e0 signal\u00e9e, selon laquelle la contre-attaque des forces du r\u00e9gime contre les rebelles est une agression d\u00e9lib\u00e9r\u00e9e contre le peuple syrien. Le WP commence \u00e0 regarder d&rsquo;un il diablement critique la paralysie de l&rsquo;administration et il prend argument du fractionnement des rebelles pour promouvoir un engagement US d\u00e9cid\u00e9, pour remettre de l&rsquo;ordre dans tout cela avec la finesse culturelle et id\u00e9ologique qui caract\u00e9rise les interventions US,  et parce qu&rsquo;il n&rsquo;y a qu&rsquo;un seul but possible, qui est la chute de Assad. (\u00ab<em>But if the administration is committed to Mr. Assad&rsquo;s downfall, those weaknesses argue for more, not less, U.S. involvement, to get a better read on opposition forces and to encourage those less inclined toward sectarianism<\/em>\u00bb) <\/p>\n<\/p>\n<p><p>\tMalgr\u00e9 toutes les prudences (!) de langage du WP, l&rsquo;exhortation est l\u00e0, et sans la moindre allusion \u00e0 l&rsquo;ONU et aux contraintes internationales : \u00ab<em>No one is arguing for a Libyan-style intervention into Syria at this point. But the United States and its NATO allies could begin contingency planning for a no-fly zone, now that Mr. Assad is deploying aircraft against the opposition. Instead of providing only non-lethal support, such as medical supplies and communications gear, America could help supply weapons to the outgunned opposition fighters. It could work with Turkey and other allies to set up havens for them. All of these moves contain risks. But those must be weighed against the danger of inaction  a long civil war that could spill across Syria&rsquo;s borders.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>Yes, this is an election season, and Americans are fatigued from a decade of war. But global leadership does not take a timeout, and sometimes it has to lead toward a consensus, not wait for one to form. The United States has been, and will remain, the one indispensable nation in world affairs, the president declared in a speech last week. Fine words.<\/em>\u00bb<\/p>\n<h3>De la Syrie \u00e0 Washington<\/h3>\n<\/p>\n<p><p>\tAlors, tournant ou pas ? Les \u00e9l\u00e9ments sont en place. Pour l&rsquo;essentiel, la situation dans sa perspective \u00e9volutive n&rsquo;a brusquement plus grand&rsquo;chose \u00e0 voir avec ce qui se passe en Syrie pour l&rsquo;imm\u00e9diat, y compris le sort de la bataille d&rsquo;Alep, mais avec ce qui se passe \u00e0 Washington.<\/p>\n<\/p>\n<p><p>\tCe qu&rsquo;on nomme aimablement, ou emphatiquement, l&rsquo;Empire, est aux abois. (Nous, nous parlons du Syst\u00e8me.) Cette situation n&rsquo;est pas suscit\u00e9e par la Syrie, ni par rien d&rsquo;autre d&rsquo;ext\u00e9rieur, mais par le Syst\u00e8me lui-m\u00eame, par la perception de sa dynamique d&rsquo;autodestruction directement g\u00e9n\u00e9r\u00e9e par sa dynamique de surpuissance. Dans de telles conditions, toutes les op\u00e9rations en cours sont susceptibles, \u00e0 un moment ou l&rsquo;autre, d&rsquo;\u00eatre fortement influenc\u00e9es par cet \u00e9tat de la psychologie, qui oscille entre l&rsquo;indiff\u00e9rence arrogante, l&rsquo;auto-terrorisation et l&rsquo;hyst\u00e9rie. C&rsquo;est aujourd&rsquo;hui le cas de la Syrie, qui a \u00e9volu\u00e9 en roues libres \u00e0 Washington pendant plusieurs mois, vivant sur l&rsquo;illusion que l&rsquo;agression douce de la <em>narrative<\/em> suffirait, que les Russes s&rsquo;aligneraient et que les Fran\u00e7ais et les Britanniques feraient l&rsquo;essentiel du travail (les pressions US sur la France et le Royaume-Uni ont \u00e9t\u00e9 tr\u00e8s fortes ces derniers mois pour r\u00e9gler l&rsquo;affaire syrienne.) Pour l&rsquo;essentiel, le <em>show<\/em> hyst\u00e9rique d&rsquo;Hillary faisait l&rsquo;affaire.<\/p>\n<\/p>\n<p><p>\tD\u00e9sormais, tout est peut-\u00eatre en train de changer : la <em>narrative<\/em> humanitariste anti-Assad a du plomb dans l&rsquo;aile, on trouve du al Qa\u00efda partout, les troubles deviennent une guerre, on parle de l&rsquo;armement chimique. L&rsquo;Empire s&rsquo;y croit encore et s&rsquo;\u00e9broue dans un sursaut d&rsquo;<em>hubris<\/em>, en d\u00e9couvrant cette nouvelle situation. Si les choses se poursuivent dans cette voie, bient\u00f4t on ne prendra plus de gants : il faut la t\u00eate d&rsquo;Assad, non plus \u00e0 cause de la <em>narrative<\/em> et de la cause humanitaire par ailleurs si mal en point, mais parce qu&rsquo;on ne r\u00e9siste pas \u00e0 l&rsquo;Empire, point final. Les experts trouveront de belles th\u00e9ories g\u00e9opolitiques pour rationaliser cette saute d&rsquo;humeur furieuse.<\/p>\n<\/p>\n<p><p>\tD&rsquo;autre part, Obama, jusqu&rsquo;alors prudent et allergique \u00e0 la guerre, pourrait bien admettre que cette voie s&rsquo;impose pour contrer les avanc\u00e9es de Romney en <a href=\"http:\/\/www.ynetnews.com\/articles\/0,7340,L-4261901,00.html\" class=\"gen\">visite<\/a> en <a href=\"http:\/\/www.telegraph.co.uk\/news\/worldnews\/mitt-romney\/9439416\/Mitt-Romney-Israelis-richer-than-Palestinians-because-of-hand-of-providence.html\" class=\"gen\">Isra\u00ebl<\/a>, avec une rh\u00e9torique extr\u00e9miste qui stup\u00e9fie m\u00eame Hillary Clinton. Attaqu\u00e9 pour sa mollesse sur l&rsquo;Iran, Obama pourrait bien conclure qu&rsquo;il ne peut se permettre de l&rsquo;\u00eatre \u00e9galement sur la Syrie. La direction am\u00e9ricaniste ne conna\u00eet plus de bornes dans sa d\u00e9magogie vis-\u00e0-vis de ses divers parrains et vis-\u00e0-vis de l&rsquo;extr\u00e9misme-Syst\u00e8me.<\/p>\n<h3>L&rsquo;<em>hubris<\/em> de l&rsquo;usine \u00e0 gaz<\/h3>\n<\/p>\n<p><p>\tMais tout cela, au milieu de tout ce qu&rsquo;on sait fort bien du Syst\u00e8me, se r\u00e9sumerait finalement d&rsquo;un mot pour la partie am\u00e9ricaniste : <em>hubris<\/em>, ce mot grec d\u00e9signant un orgueil extr\u00eame, une arrogance confinant \u00e0 la pathologie de la puissance. Il ne leur reste que cela, \u00e0 Washington, au coeur du Syst\u00e8me. Il est par cons\u00e9quent \u00e0 envisager, sinon \u00e0 pr\u00e9voir que Washington va se trouver d\u00e9cha\u00een\u00e9, ces prochaines semaines, par une fi\u00e8vre de guerre, avec les McCain, les <em>neocons<\/em> et les \u00e9ditos du WP. Washington ne peut supporter qu&rsquo;un accident humain s&rsquo;oppose \u00e0 son <em>hubris<\/em>, et cet accident,  Assad en l&rsquo;occurrence,  doit dispara\u00eetre.<\/p>\n<\/p>\n<p><p>\tMais tout cela, c&rsquo;est <strong>aussi<\/strong> une <em>narrative<\/em>, l&rsquo;ultime en v\u00e9rit\u00e9 Il reste ce point essentiel, qui est l&rsquo;\u00e9vidence de tout, que cet <em>hubris<\/em> est celui d&rsquo;une caricature d&rsquo;Empire r\u00e9duit \u00e0 une grotesque usine \u00e0 gaz, \u00e0 la d\u00e9route catastrophique d&rsquo;une puissance qui n&rsquo;est plus. Dans ce cas qui est av\u00e9r\u00e9, la Syrie telle qu&rsquo;elle est en train d&rsquo;\u00e9voluer, telle qu&rsquo;elle pourrait \u00eatre consid\u00e9r\u00e9e par cet <em>hubris<\/em> pathologique, pourrait \u00eatre l&rsquo;aventure qu&rsquo;on attend, par o\u00f9 s&rsquo;engouffrerait Washington pour s&rsquo;engager dans sa chute finale Les <em>narrative<\/em> d&rsquo;Empire ont toujours quelque chose de final dans leur programme, que ce soit la lutte ou la chute.<\/p>\n<\/p>\n<p><p>\tL&rsquo;<em>hubris<\/em> washingtonien fourni par le Syst\u00e8me pourrait pousser Washington \u00e0 l&rsquo;aventure militaire en Syrie, avec toutes les cons\u00e9quences qu&rsquo;on peut commencer \u00e0 imaginer. L&rsquo;<em>hubris<\/em> washingtonien pourrait alors se r\u00e9v\u00e9ler comme l&rsquo;ultime cadeau empoisonn\u00e9,  autodestruction garantie et bient\u00f4t achev\u00e9e,  que le Syst\u00e8me se serait fait \u00e0 lui-m\u00eame.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notes sur la Syrie, narrative, tournant et hubris Plusieurs traits remarquables sont \u00e0 mettre en \u00e9vidence dans l&rsquo;\u00e9volution de la crise syrienne. Nous en d\u00e9taillons ci-dessous quelques-uns, pour pouvoir mieux introduire une rapide r\u00e9flexion sur ce que nous percevons de la nature de l&rsquo;\u00e9volution de cette crise. Le point de d\u00e9part, \u00e0 la fois des&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[3936,11890,4270,11461,11156,6244,6197,14994,4242,9604,6776,3867,3014,3248],"class_list":["post-73292","post","type-post","status-publish","format-standard","hentry","category-analyse","tag-al","tag-alep","tag-autodestruction","tag-debka","tag-demagogie","tag-hubris","tag-panetta","tag-presidentiielles","tag-qaida","tag-rebelles","tag-romney","tag-syrie","tag-systeme","tag-washington"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73292"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73292\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}