{"id":73309,"date":"2012-08-09T05:45:03","date_gmt":"2012-08-09T05:45:03","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/08\/09\/oui-pourquoi-pas-1939\/"},"modified":"2012-08-09T05:45:03","modified_gmt":"2012-08-09T05:45:03","slug":"oui-pourquoi-pas-1939","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/08\/09\/oui-pourquoi-pas-1939\/","title":{"rendered":"\u2026Oui, pourquoi pas 1939 ?"},"content":{"rendered":"<p><h2 class=\"common-article\">Oui, pourquoi pas 1939 ?<\/h2>\n<\/p>\n<p><p>\t9 ao\u00fbt 2012  Le <a href=\"http:\/\/www.dedefensa.org\/article-sont-ils_en_1914__03_08_2012.html\" class=\"gen\">3 ao\u00fbt 2012<\/a>, nous terminions notre <em>F&#038;C<\/em> sur une interrogation, suivant l&rsquo;affirmation d&rsquo;un grand chef militaire (le SACEUR de l&rsquo;OTAN) selon laquelle \u00ab[n]<em>ous sommes en 1914<\/em>\u00bb : \u00ab<em>Il n&#8217;emp\u00eache que l&rsquo;analogie historique de 1914 est int\u00e9ressante pour un autre propos et nous y reviendrons. (Car pourquoi pas 1939 ? Apr\u00e8s tout, on parle aussi bien de septembre ou octobre pour une attaque, et si 1914 c&rsquo;est la guerre le 4 ao\u00fbt, 1939 c&rsquo;est la guerre le 1er septembre)<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tNous faisons l\u00e0 une interpr\u00e9tation symbolique des r\u00e9f\u00e9rences utilis\u00e9es par les acteurs de la crise g\u00e9n\u00e9rale et terminale du Syst\u00e8me, selon une approche intuitive de notre sujet. Dans le chaos continu du flot d&rsquo;informations distordues et manipul\u00e9es dans tous les sens, g\u00e9n\u00e9r\u00e9es par l&rsquo;abondance des <em>narrative<\/em> et l&rsquo;action ambivalente (type-<a href=\"http:\/\/www.dedefensa.org\/article-dialogues-13_de_la_sublimite_du_systeme_de_la_communication_08_11_2010.html\" class=\"gen\">Janus<\/a>) du syst\u00e8me de la communication, le symbolisme historique est un biais int\u00e9ressant pour atteindre \u00e0 la v\u00e9rit\u00e9 notamment psychologique de la situation ; parce qu&rsquo;il est non manipul\u00e9 par d\u00e9finition, parce qu&rsquo;il est per\u00e7u en dehors du syst\u00e8me de la communication et souvent exprim\u00e9 d&rsquo;une mani\u00e8re non \u00e9labor\u00e9 et donc hors de cette influence. Nous allons donc poursuivre le texte cit\u00e9 par une observation plus en profondeur, \u00e0 la fois psychologique et m\u00e9tahistorique, \u00e0 propos de la Grande Guerre<N; par cons\u00e9quent, par ce qui, \u00e0 notre sens, d\u00e9termine, d'ailleurs inconsciemment mais d'une mani\u00e8re significative, le choix de l'analogie de 1914 plut\u00f4t que le choix de 1939.<\/p>\n<\/p>\n<p><p>\t( Cela, malgr\u00e9 les g\u00e2teries de communication, d&rsquo;un tr\u00e8s grand attrait publicitaire : se r\u00e9f\u00e9rer \u00e0 1939, du bon c\u00f4t\u00e9 bien entendu, c&rsquo;est \u00e9voquer Munich, l&rsquo;immonde et indicible Hitler avec tout ce qui va avec, et l\u00e0 contre, couronn\u00e9s de l&rsquo;anneau des saints et de la vertu d\u00e9mocratique, muscl\u00e9e et anglo-saxonne, Churchill, la croisade des am\u00e9ricanistes-occidentalistes, l&rsquo;Am\u00e9rique, Glenn Miller et Hollywood, et ainsi de suite. [Pas de place pour les <em>ruskofs<\/em>, toute la place aux <em>yankees<\/em> : voir le <a href=\"http:\/\/www.dedefensa.org\/article-en_souvenir_de_vous_16_02_2003.html\" class=\"gen\">16 f\u00e9vrier 2003<\/a>.] Au reste, on sait bien que, souvent ces derni\u00e8res ann\u00e9es, face aux Hitlers de service, que ce soit Milosevic, Saddam, le terrorisme islamiste, etc., c&rsquo;est bien 1939, Munich &#038; compagnie qui furent sollicit\u00e9s, jusqu&rsquo;\u00e0 la <em>narrative<\/em> exaltante des islamo-fascistes. Beaucoup plus juteux, beaucoup plus vendable On se souviendra qu&rsquo;en ses heures triomphantes, en 2002-2003, le bloc BAO, c&rsquo;est-\u00e0-dire essentiellement les USA et alors sans la France \u00e0 laquelle \u00e9tait revenue le sens de sa dignit\u00e9 s\u00e9culaire, l&rsquo;analogie pour la grande guerre \u00e0 venir,  celle de l&rsquo;Irak, \u00e0 quoi succ\u00e9derait en cascade la conqu\u00eate de six autres pays, tout cela <a href=\"http:\/\/www.dedefensa.org\/article-sept_guerres_victorieuses_en_5_ans_05_03_2007.html\" class=\"gen\">boucl\u00e9<\/a> en 2006,  l&rsquo;analogie \u00e9tait bien 1939, Churchill, la d\u00e9testation des Munichois dont Chirac \u00e9tait chef de file et ainsi de suite. GW Bush avait fait installer un buste du grand homme \u00e0 la Maison-Blanche et les <em>neocons<\/em> ne juraient que par Churchill-sanctifi\u00e9 C&rsquo;\u00e9tait 1939, vous dit-on, et l h\u00e9ro\u00efsme commen\u00e7ait \u00e0 Munich ! (Et il s&rsquo;y arr\u00eatait, au fait.) Ce bouleversement du r\u00e9flexe analogique et symbolique est une <strong>indication fondamentale<\/strong>, on le verra plus loin.)<\/p>\n<\/p>\n<p><p>\tOn sait que la Grande Guerre est un des \u00e9v\u00e8nements fondamentaux de notre th\u00e8se m\u00e9tahistorique du <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_source_de_tous_les_maux_ddecrisis_10_09_2010.html\" class=\"gen\">d\u00e9cha\u00eenement de la Mati\u00e8re<\/a>. Nous avons d\u00e9crit \u00e0 plusieurs reprises, sous des angles diff\u00e9rents, ces conceptions que nous avons de ce conflit, soit au travers de la bataille de Verdun (voir notamment le <a href=\"http:\/\/www.dedefensa.org\/article-verdun_et_les_3_cercles_de_l_enfer_11_07_2009.html\" class=\"gen\">11 juillet 2009<\/a>), soit directement \u00e0 propos de la Grande Guerre elle-m\u00eame.<\/p>\n<\/p>\n<p><p>\tOn trouvera, rassembl\u00e9s en un texte plac\u00e9 dans la rubrique <em>La gr\u00e2ce de l&rsquo;Histoire<\/em>, divers extraits de nos diverses publications sur le sujet,  Verdun &#038; la Grande Guerre,  ce <a href=\"http:\/\/www.dedefensa.org\/article-de_la_grande_guerre_09_08_2012.html\" class=\"gen\">9 ao\u00fbt 2012<\/a>. On verra, dans ces nombreux extraits, que notre approche fondamentale de la Grande Guerre peut \u00eatre expliqu\u00e9e sur deux plans de cette fa\u00e7on.<\/p>\n<\/p>\n<p><p>\t La <strong>cause<\/strong> fondamentale de la Grande Guerre ne peut pas renvoyer \u00e0 des explications historique de type classique. C&rsquo;est pourquoi les causes conjoncturelle de la grande Guerre, dans l&rsquo;historiographie classique, sont tr\u00e8s contest\u00e9es et tr\u00e8s diverses. Certains vont m\u00eame jusqu&rsquo;\u00e0 juger l&rsquo;\u00e9v\u00e9nement inexplicable, absurde, etc. Pour nous, toutes les causes avanc\u00e9es, si elles existent,  et elles existent en g\u00e9n\u00e9ral, certes,  sont insuffisantes pour <strong>engendrer<\/strong> la Grande Guerre ; en un sens, la Grande Guerre est un \u00e9v\u00e9nement trop important, trop fondamental, pour \u00eatre contenu dans toutes les causes historiques qui sont avanc\u00e9es ; la diff\u00e9rence est de l&rsquo;ordre de la substance : la Grande Guerre les contient mais comme des appendices accessoires, car l&rsquo;essentiel est ailleurs Nous interpr\u00e9tons cette situation dans les divers extraits propos\u00e9s, notamment \u00e0 l&rsquo;image des quelques phrases ci-dessous,  et l&rsquo;on comprend <strong>bien entendu<\/strong> que la force principale (d\u00e9mographique, industrielle, culturelle, militaire, <strong>conceptuelle<\/strong> enfin) qui produisait ce bouleversement tellurique pr\u00e9cipitant le conflit et le rendant in\u00e9vitable, et qui lui donnerait son aspect terrible, c&rsquo;\u00e9tait l&rsquo;Allemagne. Cette puissance, \u00e0 cette \u00e9poque \u00e9quivalent et mod\u00e8le europ\u00e9ens de l&rsquo;am\u00e9ricanisme, \u00e9tait l&rsquo;\u00e9x\u00e9cutrice et le porte-drapeau de l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-notre_11_novembre_11_11_2008.html\" class=\"gen\">id\u00e9al de puissance<\/a> per\u00e7u comme le moteur d&rsquo;un courant m\u00e9tahistorique fondamental exprimant m\u00e9tapolitiquement le d\u00e9cha\u00eenement de la Mati\u00e8re<\/p>\n<\/p>\n<p><p>\t\u00ab<em>La Grande Guerre a \u00e9clat\u00e9 parce que la r\u00e9alit\u00e9 g\u00e9ographique, ethnologique et psychologique de l&rsquo;Europe \u00e9tait pr\u00e9cipit\u00e9e dans le d\u00e9s\u00e9quilibre, parce que la dynamique d\u00e9termin\u00e9e par ses composants et exprim\u00e9e dans sa politique et son \u00e9conomie \u00e9tait devenue insupportable. L&rsquo;Europe \u00e9tait entra\u00een\u00e9e dans une dynamique de d\u00e9structuration.<\/em> [] <em>Le ph\u00e9nom\u00e8ne de l&rsquo;imm\u00e9diat avant-guerre jusqu&rsquo;\u00e0 la Grande Guerre pourrait solliciter l&rsquo;analogie de la catastrophe tellurique ; il ressemble \u00e0 ce ph\u00e9nom\u00e8ne de la cro\u00fbte terrestre qui se craquelle, se fend et \u00e9clate enfin sous la pression des forces du feu d\u00e9cha\u00een\u00e9es par le cur en fusion du monde<\/em><\/p>\n<\/p>\n<p><p>\tLa puissance m\u00eame de cette explication que nous proposons explique que le principal sentiment de la principale structure mise en cause,  la France, certes, la nation structurante par excellence,  envisageait les bruits annonciateurs de conflit comme quelque chose d&rsquo;in\u00e9luctable, comme une fatalit\u00e9 d&rsquo;une force en mouvement qui contraignait tout le reste. Cette force-l\u00e0 ne pouvait \u00eatre qu&rsquo;allemande, explicit\u00e9e d&rsquo;ailleurs dans cette citation de cette lettre de Rathenau au chancelier von Bulow en 1909 : \u00ab<em>Il y a un autre facteur important, auquel en Allemagne nous ne pr\u00eatons pas toujours attention : c&rsquo;est l&rsquo;impression que fait l&rsquo;Allemagne vue du dehors ; on jette le regard sur cette<\/em> <strong><em>chaudi\u00e8re europ\u00e9enne<\/em><\/strong> (<em>c&rsquo;est moi qui souligne<\/em> [\u00e9crit von Bulow, en commentaire de la lettre de Rathenau]<em>), on y voit, entour\u00e9e de nations qui ne bougent plus, un peuple toujours au travail et capable d&rsquo;une \u00e9norme expansion physique ; huit cent mille Allemands de plus chaque ann\u00e9e ; \u00e0 chaque lustre, un accroissement presque \u00e9gal \u00e0 la population des pays scandinaves ou de la Suisse ; et l&rsquo;on se demande combien de temps la France, o\u00f9 se fait le vide, pourra r\u00e9sister \u00e0 la pression atmosph\u00e9rique de cette population.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tEt l&rsquo;on trouvera encore, dans les extraits propos\u00e9s, les \u00e9l\u00e9ments qui faisaient de cette puissante chaudi\u00e8re europ\u00e9enne pr\u00eate \u00e0 exploser un facteur de bouleversement civilisationnel, s&rsquo;adressant directement \u00e0 la m\u00e9tahistoire. Une puissance industrielle et technologique en expansion inou\u00efe (alors \u00e0 l&rsquo;image des USA), une id\u00e9ologie expansionniste et d\u00e9vorante (le pangermanisme), une culture progressiste de rupture, envisageant un monde compl\u00e8tement nouveau et une dissolution de tous les cadres anciens,  en un mot, la folle course d&rsquo;une postmodernit\u00e9 avant l&rsquo;heure, non plus conduite par le Progr\u00e8s, mais entra\u00eenant le Progr\u00e8s sur son aire.<\/p>\n<\/p>\n<p><p>\t Par cons\u00e9quent, la Grande Guerre ne pouvait \u00eatre que ce ph\u00e9nom\u00e8ne dans l&rsquo;ordre de l&rsquo;affrontement n\u00e9 du d\u00e9cha\u00eenement de la Mati\u00e8re, ou encore dans l&rsquo;affrontement de la d\u00e9structuration contre les structures. Comme nous l&rsquo;\u00e9crivons encore : \u00ab<em>La Grande Guerre ne se d\u00e9finit ni ne se comprend par des id\u00e9es parce qu&rsquo;elle est d&rsquo;abord mati\u00e8re, et mati\u00e8re en fureur. C&rsquo;est une guerre r\u00e9volutionnaire au sens que sugg\u00e8re Guglielmo Ferrero quand il analyse la campagne d&rsquo;Italie de Bonaparte.<\/em> [] <em>Ce ne sont pas les id\u00e9es qui fomentent les r\u00e9volutions mais la destruction des structures existantes par la brutalit\u00e9 de la guerre qui rend possible, sinon facile, sinon \u00e9vidente comme un tourbillon fou aspire dans le vide qu&rsquo;il cr\u00e9e tout ce qu&rsquo;il happe dans sa dynamique, la p\u00e9n\u00e9tration des id\u00e9es r\u00e9volutionnaires sous la forme du diktat du d\u00e9sordre bien plus encore que du conqu\u00e9rant ; c&rsquo;est la puissance m\u00e9canique qui compte et cr\u00e9e l&rsquo;illusion de l&rsquo;ordre (qu&rsquo;on le nomme r\u00e9volutionnaire, sovi\u00e9tique, plus tard lib\u00e9ral, qu&rsquo;importe les \u00e9tiquettes qui sont justement ces id\u00e9es entr\u00e9es par effraction) ; c&rsquo;est la puissance des armes et du maniement de ces armes, la fa\u00e7on dont on r\u00e9duit l&rsquo;adversaire en d\u00e9truisant physiquement les structures qu&rsquo;il a fabriqu\u00e9es, et non la soi-disant puissance des id\u00e9es ; c&rsquo;est l&rsquo;inverse de l&rsquo;harmonie et donc de l&rsquo;ordre.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tA cet \u00e9gard, la Grande Guerre fut absolument terrifiante \u00e0 cause de la disposition de progr\u00e8s technologique d\u00e9cisifs (le canon, la mitrailleuse), qui allaient physiquement contribuer \u00e0 fixer toutes les structures, et les d\u00e9truire m\u00e9thodiquement, \u00e0 les d\u00e9structurer, \u00e0 les dissoudre sous les coups de la mitraille. Et ce constat est bien que la description de cette bataille d&rsquo;an\u00e9antissement, c&rsquo;est <strong>aussi<\/strong> une parabole pour la psychologie, les murs, la politique, la culture, la communication et la civilisation,  qui, en cette occasion, acheva de se faire contre-civilisation apr\u00e8s qu&rsquo;on nous eut annonc\u00e9 que, d\u00e9sormais, les civilisations \u00e9taient mortelles. Ainsi notre interpr\u00e9tation est-elle bien celle d&rsquo;un affrontement titanesque entre les forces d\u00e9structurantes et les structures de la civilisation appuy\u00e9es sur ce que l&rsquo;on pouvait retrouver de la Tradition. Lapparence est que les structures avaient tenu, au prix d&rsquo;un h\u00e9ro\u00efsme inou\u00ef, comme la bataille de Verdun en pr\u00e9sente l&rsquo;arch\u00e9type, mais la r\u00e9alit\u00e9 fut que l&rsquo;\u00e9puisement de cette victoire ouvrit la voie \u00e0 la guerre suivante et \u00e0 ses folies id\u00e9ologiques, et \u00e0 l&rsquo;invasion du monde par l&rsquo;installation du Syst\u00e8me \u00e0 partir de son centre am\u00e9ricaniste, \u00e0 l&rsquo;inversion des interpr\u00e9tations faisant des USA une puissance d&rsquo;apaisement, de contr\u00f4le, une puissance structurante,  les USA, un comble !<\/p>\n<\/p>\n<p><p>\tLa guerre de 1939 (1941 pour les USA,  on prend toujours son temps avant de sauver le monde) est au contraire une guerre au parcours connu par avance, que l&rsquo;on vit venir de loin, qui en un sens ne r\u00e9servait aucune surprise (sinon les p\u00e9rip\u00e9ties strat\u00e9giques et tactiques). Nul ne doutait qu&rsquo;il s&rsquo;agirait d&rsquo;une guerre gigantesque, \u00e9videmment de dimension mondiale, avec des moyens m\u00e9caniques et industriels colossaux, avec en action des id\u00e9ologies extr\u00eames et dont la sauvagerie \u00e9tait av\u00e9r\u00e9e Les instruments \u00e9taient connus, les buts recherch\u00e9s par chacun \u00e9taient assur\u00e9s, les perspectives imaginables et envisageables m\u00eame si le parcours \u00e9tait terrible ; la victoire elle-m\u00eame \u00e9tait appr\u00e9hend\u00e9e dans toutes ses dimensions, avec d\u00e9j\u00e0 l&rsquo;apr\u00e8s-guerre pr\u00e9par\u00e9 par les vainqueurs dont la division antagoniste ne faisait aucun doute. D\u00e8s ao\u00fbt 1940, selon le t\u00e9moignage de Maurice Schuman, de Gaulle, qui avait compris tout cela, ne s&rsquo;inqui\u00e8tait plus de la guerre dont il embrassait ais\u00e9ment le sch\u00e9ma, mais de l&rsquo;apr\u00e8s-guerre ; ce pourquoi, ses principaux adversaires furent les Anglo-Saxons Il y avait dans cette guerre une dimension id\u00e9ologique implacable mais bien identifi\u00e9e, et une dimension de communication \u00e0 mesure, impliquant la propagande, la <em>narrative<\/em>, etc. Tout \u00e9tait \u00e9crit, y compris l&rsquo;horreur absolue, d\u00e9j\u00e0 identifi\u00e9e.<\/p>\n<\/p>\n<p><p>\tDans la Quatri\u00e8me Partie du Premier Livre de <em>La gr\u00e2ce de l&rsquo;Histoire<\/em> (voir le <a href=\"http:\/\/www.dedefensa.org\/article-cinquieme_partie_la_transversale_du_technologisme_02_12_2010.html\" class=\"gen\">2 d\u00e9cembre 2010<\/a>), nous d\u00e9finissons effectivement la Deuxi\u00e8me Guerre mondiale, qui fut si compl\u00e8tement am\u00e9ricaniste bien que les USA n&rsquo;aient nullement \u00e9t\u00e9, et de loin, le facteur d\u00e9cisif de la victoire qu&rsquo;on en a fait, comme une sorte de film sorti des studios d&rsquo;Hollywood,  c&rsquo;est dire si les choses \u00e9taient connues d&rsquo;avance D&rsquo;ailleurs, nous ne faisons qu&#8217;emprunter cette id\u00e9e \u00e0 un professeur am\u00e9ricain qui en a fait une th\u00e8se, puis un livre  :<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Des studios du cin\u00e9matographe, nous passons ais\u00e9ment \u00e0 la r\u00e9alit\u00e9 puisque la r\u00e9alit\u00e9 est d\u00e9sormais celle qui sort des studios, et rien d&rsquo;autre ne s&rsquo;y peut comparer en v\u00e9rit\u00e9. Le professeur George H. Roeder Jr., qui est professeur of liberal art, dont l&rsquo;image du cin\u00e9matographe fait partie, et nullement historien, nous pr\u00e9sente la Deuxi\u00e8me Guerre mondiale sous les traits d&rsquo;une guerre censur\u00e9e; mais bien au-del\u00e0 de cet aspect somme toute conjoncturel, il nous instruit dans ses remarques introductives de ceci qui r\u00e9sume notre propos \u00e0 merveille: La Deuxi\u00e8me Guerre mondiale fut le premier film dans lequel chaque Am\u00e9ricain pouvait avoir un r\u00f4le.<\/em> [&#8230;] <em>La Deuxi\u00e8me Guerre mondiale offrit \u00e0 chaque citoyen<\/em> [am\u00e9ricain] <em>le double r\u00f4le de spectateur et de participant. George H. Roeder Jr. nous dit bien plus de la r\u00e9elle substance de l&rsquo;\u00e9v\u00e9nement de la Deuxi\u00e8me Guerre mondiale, de sa puissance et de son influence sur la psychologie am\u00e9ricaniste (et sur le renforcement de l&rsquo;am\u00e9ricanisation de la psychologie des Am\u00e9ricains), dans cette fa\u00e7on cin\u00e9matographique&rsquo; de l&rsquo;aborder<\/em> [] <em>Il ne s&rsquo;agit pas ici de signaler un \u00e0-c\u00f4t\u00e9, un aspect int\u00e9ressant mais tout de m\u00eame marginal de la perception du grand conflit, notamment chez les Am\u00e9ricains mais \u00e9galement sur les terres ext\u00e9rieures. Au contraire, nous pr\u00e9tendons d\u00e9crire la substance de la chose, telle qu&rsquo;elle fut model\u00e9e par la communication. L&rsquo;appr\u00e9ciation de George H. Roeder Jr., si elle para\u00eet sortir du laboratoire original mais limit\u00e9 du sp\u00e9cialiste, concerne au contraire l&rsquo;enti\u00e8ret\u00e9 du ph\u00e9nom\u00e8ne. La politique g\u00e9n\u00e9rale, les appr\u00e9ciations des dirigeants de cette politique, du moins ceux qui sont acquis au syst\u00e8me, montrent une transcription en des concepts s\u00e9rieux&rsquo; de cette fa\u00e7on de percevoir l&rsquo;\u00e9v\u00e9nement. Il s&rsquo;agit d&rsquo;une v\u00e9ritable mise en sc\u00e8ne de l&rsquo;Histoire dans laquelle croit entrer l&rsquo;Am\u00e9rique, alors que ce qu&rsquo;elle fait est de tenter d&rsquo;annexer l&rsquo;Histoire pour la faire traiter&rsquo; par les r\u00e9giments de sc\u00e9naristes de Hollywood ; pour un certain temps, quelques d\u00e9cennies au moins, on put consid\u00e9rer que le tour avait r\u00e9ussi, passe-passe certes, mais dans le cadre s\u00e9rieux de l&rsquo;industrie cin\u00e9matographique. Dans tous les cas, il s&rsquo;agit de convenir que la communication, l\u00e0 encore, constitue l&rsquo;arme absolue de l&rsquo;am\u00e9ricanisme<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tAinsi en fut-il, par cons\u00e9quent, de la r\u00e9f\u00e9rence de 1939 qui accompagna les premi\u00e8res ann\u00e9es de la s\u00e9quence historique, devenue m\u00e9tahistorique actuelle, commenc\u00e9e en 2001-2003. 1939, au contraire de 1914 aujourd&rsquo;hui, ce fut l&rsquo;installation paroxystique de la <em>narrative<\/em> pr\u00e9valant jusqu&rsquo;\u00e0 la crise de 2008, et qui a influ\u00e9 directement sur l&rsquo;aspect faussaire des conditions influant directement sur la situation actuelle, notamment avec la sensation de la puissance triomphante et irr\u00e9sistible du bloc BAO ; ce fut l&rsquo;installation d&rsquo;une <em>narrative<\/em> des id\u00e9es, ou id\u00e9ologies, qui sont autant de faux-nez pour habiller sur un mode pimpant le <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_source_de_tous_les_maux_ddecrisis_10_09_2010.html\" class=\"gen\">d\u00e9cha\u00eenement de la Mati\u00e8re<\/a>,  attendu que l&rsquo;on sait bien que ce sont les bonnes id\u00e9ologies qui triomph\u00e8rent et qui triomphent toujours. Cette p\u00e9riode est d\u00e9finitivement d\u00e9pass\u00e9e, avec l&rsquo;apparition des limites dramatiques de la puissance du bloc BAO, passant de la perspective faussaire du triomphe \u00e0 celle de la chute. Ainsi le choix de l&rsquo;analogie de 1914 (\u00ab<em>Nous sommes en 1914<\/em>\u00bb), au lieu de celle de 1939, est pour nous, au travers du symbolisme qu&rsquo;il implique hors de toute manipulation et de toute \u00e9laboration, d&rsquo;une signification psychologique et m\u00e9tahistorique puissante. Ceux qui la font, qui sont pr\u00e9tendument du camp du Bien, savent bien, au fond d&rsquo;eux-m\u00eames, que ce choix r\u00e9v\u00e8le la fin de la <em>narrative<\/em> triomphante et la prise en compte de l&rsquo;ab\u00eeme profond o\u00f9 vont les pr\u00e9cipiter la course folle qui nous emporte d\u00e9sormais.<\/p>\n<h3>Aspect fondamental de l&rsquo;approche symbolique<\/h3>\n<\/p>\n<p><p>\tNous tenons donc que l&rsquo;importance du symbole du choix de 1914 est consid\u00e9rable, par la valeur m\u00eame de l&rsquo;approche symbolique, d&rsquo;une part ; dans la mesure, d&rsquo;autre part, o\u00f9 toute autre approche, plus rationnelle, plus document\u00e9e, sur la possibilit\u00e9 d&rsquo;un conflit majeur et ce que serait ce conflit, est absolument impossible aujourd&rsquo;hui. Comme on l&rsquo;a dit, tous les esprits, et particuli\u00e8rement ceux qui sont r\u00e9put\u00e9s les mieux inform\u00e9s, sont submerg\u00e9s par des courants de communication contradictoires, faussaires, parcellaires, etc., en m\u00eame temps qu&rsquo;il sont souvent sinon en permanence soumis \u00e0 des agressions contre leurs psychologies qui faussent absolument leur perception. Toute la politique qui en \u00e9mane, les analyses et les prospectives qui en sont d\u00e9duites, sont soumises \u00e0 des d\u00e9formations inou\u00efes, qui disqualifient absolument le mode de pens\u00e9e courant dans les directions politiques et alentour, dans les conditions actuelles.<\/p>\n<\/p>\n<p><p>\tLa voie du symbolisme est alors tr\u00e8s int\u00e9ressante, dans la mesure o\u00f9 elle restitue l&rsquo;acc\u00e8s, par une approche codifi\u00e9e et une psychologie qui \u00e9chappe de cette fa\u00e7on \u00e0 l&rsquo;autocensure, \u00e0 des pens\u00e9es profondes et encore insoumises \u00e0 la pression faussaire g\u00e9n\u00e9rale, et donc restitue une certaine v\u00e9rit\u00e9 de la situation. Par cons\u00e9quent, le choix de l&rsquo;analogie de 1914, au lieu de l&rsquo;analogie de 1939, devient tr\u00e8s significatif. Ce choix doit \u00eatre envisag\u00e9 avec pr\u00e9cision et, justement, du point de vue d&rsquo;un jugement tr\u00e8s rationnel dans notre chef. Dans la situation pr\u00e9sente, la raison doit \u00eatre utilis\u00e9e particuli\u00e8rement pour appr\u00e9cier des d\u00e9marches habituellement disqualifi\u00e9es parce que jug\u00e9es irrationnelles, qui restent irrationnelles ou pas peu importe, mais qui acqui\u00e8rent une grande v\u00e9rit\u00e9 par rapport \u00e0 la catastrophe faussaire qui frappe toutes les voies normales de communication, et l&rsquo;information charri\u00e9es par elles, vers nos directions politiques.<\/p>\n<\/p>\n<p><p>\tA partir de ces constats sur l&rsquo;aspect symbolique du choix envisag\u00e9 pour l&rsquo;analogie historique, il importe de comprendre ce que recouvre, \u00e9galement en termes de symbole, la dimension historique, strat\u00e9gique et op\u00e9rationnelle de 1914 plut\u00f4t que celle de 1939, et l&rsquo;\u00e9tat psychologique que r\u00e9v\u00e8le cette situation. C&rsquo;est l\u00e0 que nous rejoignons l&rsquo;interpr\u00e9tation que nous donnons de la Grande Guerre, en v\u00e9rifiant de la sorte la v\u00e9rit\u00e9 du symbole. Il est assur\u00e9 que, dans tout esprit d&rsquo;un militaire ou d&rsquo;un soldat de carri\u00e8re avec une certaine exp\u00e9rience historique, de m\u00eame que dans l&rsquo;esprit de tout id\u00e9ologue, la date de 1914 renvoie \u00e0 une situation d&rsquo;incertitude, \u00e0 <strong>un saut dans l&rsquo;inconnu<\/strong>, \u00e0 une \u00e9volution impr\u00e9vue et inattendue des \u00e9v\u00e8nements guerriers, \u00e0 une guerre ou \u00e0 un \u00e9v\u00e9nement assimil\u00e9 dont les causes sont confuses, les buts impr\u00e9cis, les perspectives incertaines et \u00e9ventuellement extraordinaires sinon terrifiantes. On en conclura, en nous r\u00e9f\u00e9rant au rappel des circonstances dans ann\u00e9es 2001-2003 jusque 2008, avec la rupture marqu\u00e9e par cette ann\u00e9e, qu&rsquo;il y a <strong>aussi<\/strong> un changement fondamental dans l&rsquo;\u00e9tat d&rsquo;esprit des acteurs militaires, strat\u00e8ges, id\u00e9ologues, etc., dans les domaines de la strat\u00e9gie et de la forme de la guerre, et dans la perception du destin du Syst\u00e8me par cons\u00e9quent. Cela nous laisse un champ nouveau pour interpr\u00e9ter les conditions conflictuelles envisag\u00e9es aujourd&rsquo;hui, dans la structure crisique g\u00e9n\u00e9rale et le d\u00e9cha\u00eenement des <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_chaine_crisique_ddecrisis_02_04_2011.html\" class=\"gen\">cha\u00eenes<\/a> <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_deuxi_me_cha_ne_crisique__06_08_2012.html\" class=\"gen\">crisiques<\/a>.<\/p>\n<\/p>\n<p><p>\tCela nous conduit \u00e0 observer d&rsquo;une fa\u00e7on g\u00e9n\u00e9rale qu&rsquo;il est totalement insuffisant, lorsqu&rsquo;un grand chef militaire appartenant aux r\u00e9seaux et aux forces du bloc BAO vous dit \u00ab<em>Nous sommes en 1914<\/em>\u00bb, de s&rsquo;en tenir \u00e0 l&rsquo;hypoth\u00e8se d&rsquo;un conflit, f\u00fbt-il g\u00e9n\u00e9ral, ou mondial, \u00e0 l&rsquo;image de la Grande Guerre. L&rsquo;hypoth\u00e8se que nous devons d\u00e9velopper, \u00e0 partir de la r\u00e9f\u00e9rence inspiratrice de l&rsquo;intuition haute qui nous conduit, est bien que ce constat de l&rsquo;analogie de 1914 concerne le caract\u00e8re du conflit de 1914 tel que nous avons tent\u00e9 de la d\u00e9finir. Ce que nous annonce cette image (\u00ab<em>Nous sommes en 1914<\/em>\u00bb) est la perspective <strong>tr\u00e8s rapide<\/strong>, sinon <strong>d&rsquo;ores et d\u00e9j\u00e0<\/strong> en cours, d&rsquo;une situation conflictuelle autour de l&rsquo;immense question de la d\u00e9structuration du monde. Puisque nous avons d\u00e9fini la Grande Guerre comme le premier conflit moderne de d\u00e9structuration, avec forces d\u00e9structurantes et forces structurantes qui s&rsquo;affrontent sous une forme n\u00e9cessairement titanesque, c&rsquo;est dans cette direction qu&rsquo;il faut proposer une prospective.  Cela serait donc une r\u00e9p\u00e9tition de 1914, mais d&rsquo;un 1914 qui n&rsquo;a strictement rien \u00e0 voir avec nos livres d&rsquo;histoire si sages et si rassurants, avec l&rsquo;interpr\u00e9tation historiographique courante, acad\u00e9mique, id\u00e9ologique, g\u00e9ostrat\u00e9gique, militaire (tactique et strat\u00e9gique), etc. Nous parlons de 1914 comme d&rsquo;un conflit o\u00f9 la dimension m\u00e9taphysique pr\u00e9sente dans la probl\u00e9matique de la d\u00e9structuration du monde constitue une explication fondamentale, et l&rsquo;effet sur les psychologies par le ph\u00e9nom\u00e8ne de la communication relayant la puissance inou\u00efe du conflit \u00e9tant lui-m\u00eame d&rsquo;une puissance inou\u00efe. La diff\u00e9rence m\u00e9thodologique par rapport \u00e0 l&rsquo;analogie de 1914 se trouverait dans la <strong>rapidit\u00e9<\/strong> du processus, beaucoup plus \u00e9lev\u00e9e aujourd&rsquo;hui o\u00f9 le syst\u00e8me de la communication est devenue l&rsquo;acteur majeur de la puissance et de l&rsquo;interpr\u00e9tation de la puissance.<\/p>\n<\/p>\n<p><p>\tNous disons donc que lorsqu&rsquo;ils disent \u00ab<em>Nous sommes en 1914<\/em>\u00bb, ils nous disent qu&rsquo;ils se trouvent face \u00e0 l&rsquo;inconnu le plus profond, le plus sombre et le plus cr\u00e9pusculaire, car <strong>eux-m\u00eames ne savent pas ce que nous savons<\/strong>, notamment \u00e0 propos du Syst\u00e8me dont ils sont les jouets. De m\u00eame,  et en parlant pour notre compte dans ce cas,   qu&rsquo;il est av\u00e9r\u00e9 qu&rsquo;en 1914 nous ne savions pas vers o\u00f9 nous nous dirigions, avec cette pr\u00e9cision essentielle que nous ne savions pas que nous ne savions pas, de m\u00eame est-il av\u00e9r\u00e9 qu&rsquo;aujourd&rsquo;hui nous ne savons pas vers o\u00f9 nous nous nous dirigeons, avec cette pr\u00e9cision essentielle que nous savons que nous ne savons pas. (R\u00e9f\u00e9rence aux <em>unknown unknows<\/em> de <a href=\"http:\/\/www.dedefensa.org\/article-notre_monde_des_unknown_unknowns__11_04_2011.html\" class=\"gen\">Rumsfeld<\/a>.) Certains verront dans cette diff\u00e9rence un progr\u00e8s ; c&rsquo;est le cas si l&rsquo;on se tient du c\u00f4t\u00e9 de ceux qui veulent la destruction du Syst\u00e8me, ce qui est manifestement dans le sens de notre propos. Par contre, du c\u00f4t\u00e9 de ceux qui sont au service du Syst\u00e8me, qui sont habitu\u00e9s \u00e0 la n\u00e9cessit\u00e9 de la connaissance prospective pour le contr\u00f4le de leur destin\u00e9e artificielle et manipul\u00e9e, se trouve dans cette connaissance de l&rsquo;inconnaissance de notre avenir tr\u00e8s proche la source d&rsquo;une panique de la psychologie, d&rsquo;un affaiblissement d\u00e9cisif de cette psychologie. Cet \u00e9tat psychologique est de la sorte qui ne pourra qu&rsquo;accentuer la possibilit\u00e9 de r\u00e9actions erron\u00e9es, furieuses, catastrophiques pour le parti repr\u00e9sent\u00e9. Notre cas est exactement contraire, nous qui faisons vertu de l&rsquo;<a href=\"http:\/\/www.dedefensa.org\/article-de_l_inconnaissance_du_systeme_13_07_2011.html\" class=\"gen\">inconnaissance<\/a> ; la connaissance par avance de notre inconnaissance ne peut en aucun cas nous troubler.<\/p>\n<\/p>\n<p><p>\tLa seule certitude de notre intuition, qui tient \u00e0 ce symbolisme du \u00ab<em>Nous sommes en 1914<\/em>\u00bb, est que l&rsquo;affrontement qui se pr\u00e9cipite sera <strong>n\u00e9cessairement<\/strong> celui des forces d\u00e9structurantes contre les forces structurantes, comme ce fut le cas en 1914. Pour cette raison et nous arr\u00eatant \u00e0 un cas conjoncturel \u00e9vident comme exemple de la situation que nous voulons pr\u00e9senter, nous privil\u00e9gions cette analyse que le conflit du bloc BAO contre l&rsquo;Iran, d\u00e9j\u00e0 commenc\u00e9 puisqu&rsquo;on peut le faire remonter \u00e0 1980, est bien caract\u00e9ris\u00e9 par une constante d\u00e9marche d\u00e9structurante (voir le <a href=\"http:\/\/www.dedefensa.org\/article-l_iran_est_en_guerre_depuis_quand__07_08_2012.html\" class=\"gen\">7 ao\u00fbt 2012<\/a>) : \u00ab<em>Le r\u00e9sultat politique est effectivement une guerre constante men\u00e9e par les USA, depuis 1979, contre l&rsquo;Iran, mais substantiv\u00e9e elle-m\u00eame hors de la notion de guerre au travers de l&rsquo;extraction des objectifs de cette guerre du contexte structurant de l&rsquo;Iran ; cela revient finalement \u00e0 faire une guerre, sous diverses formes, contre l&rsquo;entit\u00e9 structur\u00e9e que constitue l&rsquo;Iran souverain et l\u00e9gitime, mais par d\u00e9faut, sans reconna\u00eetre en aucune fa\u00e7on l&rsquo;existence m\u00eame de l&rsquo;Iran souverain et l\u00e9gitime, en tant qu&rsquo;entit\u00e9 structur\u00e9e.<\/em> [] <em>Dans la d\u00e9marche-Syst\u00e8me de l&rsquo;am\u00e9ricanisme, ce qui est le plus important c&rsquo;est l&rsquo;hostilit\u00e9 aux valeurs structurantes, bien plus que l&rsquo;hostilit\u00e9 \u00e0 l&rsquo;Iran lui-m\u00eame.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tA ce constat, nous ajouterons que les adversaires de cette d\u00e9marche-Syst\u00e8me (am\u00e9ricaniste) opposent naturellement, au travers de divers modes d&rsquo;action, une action structurantes par logique de situation, parce qu&rsquo;ils s&rsquo;adaptent et s&rsquo;opposent aux pouss\u00e9es d\u00e9structurantes dont ils per\u00e7oivent \u00e9videmment qu&rsquo;elles sont le fait d&rsquo;un Syst\u00e8me devenu fou en passant du mode de la surpuissance au mode de l&rsquo;autodestruction. Ces adversaires sont tr\u00e8s variables et n&rsquo;ont aucune identification d&rsquo;\u00e9tiquette, de nationalit\u00e9, d&rsquo;id\u00e9ologie ; c&rsquo;en est de cette fa\u00e7on qu&rsquo;on peut consid\u00e9rer que les Iraniens tiennent aujourd&rsquo;hui, pour la s\u00e9quence consid\u00e9r\u00e9e, le m\u00eame r\u00f4le qu&rsquo;eurent en 1916 les soldats fran\u00e7ais de Verdun face \u00e0 l&rsquo;ouragan d\u00e9structurant de l&rsquo;artillerie install\u00e9e pour d\u00e9structurer et dissoudre litt\u00e9ralement cette bataille d&rsquo;an\u00e9antissement. La seule n\u00e9cessit\u00e9 est leur fonction antiSyst\u00e8me.<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Nous sommes en 1914<\/em>\u00bb : ce mot n&rsquo;indique qu&rsquo;une chose, que l&rsquo;intensit\u00e9 de la bataille avec le Syst\u00e8me est en train d&rsquo;atteindre un de ces paroxysmes qui peut signaler qu&rsquo;il s&rsquo;agit de l&rsquo;affrontement final. Nous trahirions tout notre travail et le fruit de notre intuition, en ne pr\u00e9cisant pas que c&rsquo;est notre opinion et qu&rsquo;en cette mati\u00e8re le Syst\u00e8me, l&rsquo;enfant du d\u00e9cha\u00eenement de la Mati\u00e8re, est d\u00e9j\u00e0 battu. La cause en est qu&rsquo;il porte en lui-m\u00eame sa propre mort, qui ne peut \u00eatre compar\u00e9 \u00e0 la mort que nous pourrions rencontrer, parce que la mort du Syst\u00e8me est quelque chose qui \u00e9chappe au destin de la Tradition ; elle <strong>ne peut \u00eatre<\/strong> que celle de l&rsquo;an\u00e9antissement dans sa propre infamie, de la dissolution dans sa propre entropisation.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oui, pourquoi pas 1939 ? 9 ao\u00fbt 2012 Le 3 ao\u00fbt 2012, nous terminions notre F&#038;C sur une interrogation, suivant l&rsquo;affirmation d&rsquo;un grand chef militaire (le SACEUR de l&rsquo;OTAN) selon laquelle \u00ab[n]ous sommes en 1914\u00bb : \u00abIl n&#8217;emp\u00eache que l&rsquo;analogie historique de 1914 est int\u00e9ressante pour un autre propos et nous y reviendrons. (Car pourquoi&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[15009,4646,4270,868,707,2631,8854,3907,2891,2645,10274,2622,8855,3836,584,3312,11131,6161],"class_list":["post-73309","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-15009","tag-antisysteme","tag-autodestruction","tag-bush","tag-churchill","tag-de","tag-dechainement","tag-destructuration","tag-grande","tag-guerre","tag-janus","tag-la","tag-matiere","tag-munich","tag-otan","tag-saceur","tag-surpuissance","tag-verdun"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73309"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73309\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}