{"id":73319,"date":"2012-08-14T09:32:07","date_gmt":"2012-08-14T09:32:07","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/08\/14\/le-bloc-bao-fremit-sur-son-est\/"},"modified":"2012-08-14T09:32:07","modified_gmt":"2012-08-14T09:32:07","slug":"le-bloc-bao-fremit-sur-son-est","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/08\/14\/le-bloc-bao-fremit-sur-son-est\/","title":{"rendered":"Le bloc BAO fr\u00e9mit sur son Est"},"content":{"rendered":"<p><h2 class=\"common-article\">Le bloc BAO fr\u00e9mit sur son Est<\/h2>\n<\/p>\n<p><p>\t14 ao\u00fbt 2012  Les d\u00e9clarations ambigu\u00ebs, ampoul\u00e9es et alambiqu\u00e9es du pr\u00e9sident polonais \u00e0 propos du r\u00e9seau antimissiles US (voir le <a href=\"http:\/\/www.dedefensa.org\/article-les_petits_pas_confus_mais_significatifs_des_suppl_tifs__06_08_2012.html\" class=\"gen\">6 ao\u00fbt 2012<\/a> et encore le <a href=\"http:\/\/www.dedefensa.org\/article-le_cas_polonais_et_la_russie_06_08_2012.html\" class=\"gen\">6 ao\u00fbt 2012<\/a>) ont provoqu\u00e9 quelques remous, discrets mais significatifs. Elles ont \u00e9t\u00e9 suivies de d\u00e9clarations, notamment, du ministre polonais de la d\u00e9fense, capitalisant sur l&rsquo;intention affich\u00e9e et r\u00e9p\u00e9t\u00e9e de la France, ces derni\u00e8res semaines, de relancer la d\u00e9fense europ\u00e9enne, d&rsquo;abord sous la forme concr\u00e8te du Triangle de Weimar. (Voir, par exemple, sur <em>Bruxelles2<\/em> qui tient la chronique de ces \u00e9v\u00e8nements europ\u00e9ens, le <a href=\"http:\/\/www.bruxelles2.eu\/defense-ue\/capacites-milit--exercices-ue\/accord-sur-le-battlegroup-de-weimar.html\" class=\"gen\">5 juillet 2012<\/a> et le <a href=\"http:\/\/www.bruxelles2.eu\/defense-ue\/defense-ue-droit-doctrine-politique\/la-relance-du-triangle-de-weimar.html\" class=\"gen\">8 ao\u00fbt 2012<\/a>.)<\/p>\n<\/p>\n<p><p>\t Donc, le <a href=\"http:\/\/fr.rian.ru\/world\/20120811\/195647727.html<\/p>\n<\/p>\n<p><p>\t17:48 11\/08\/2012&Prime; class=\u00a0\u00bbgen\u00a0\u00bb>11 ao\u00fbt 2012<\/a> (Novosti), le ministre de la d\u00e9fense polonais annonce que la Pologne voudrait d\u00e9velopper son propre r\u00e9seau antimissile. Tomasz Siemoniak parle de la France et de l&rsquo;Allemagne, pour la coop\u00e9ration, et mentionne vaguement d&rsquo;autres alli\u00e9s de la Pologne. On comprend que l&rsquo;id\u00e9e qui vient \u00e0 l&rsquo;esprit s&rsquo;arr\u00eate naturellement aux deux premiers cit\u00e9s, soit le sch\u00e9ma du Triangle de Weimar, comme le montre d&rsquo;ailleurs le titre de la d\u00e9p\u00eache Novosti (\u00ab<em> Varsovie souhaite cr\u00e9er un bouclier antimissile avec Paris et Berlin<\/em>\u00bb). Siemoniak : \u00ab<em>Nous souhaitons le faire en coop\u00e9ration avec la France, l&rsquo;Allemagne et d&rsquo;autres alli\u00e9s de la Pologne. L&rsquo;OTAN soutient ces initiatives permettant d&rsquo;atteindre ensemble un certain niveau de d\u00e9fense. Il s&rsquo;agit d&rsquo;une d\u00e9fense intelligente. Cette coop\u00e9ration s&rsquo;impose lorsque les projets sont si on\u00e9reux<\/em>\u00bb. On note combien cette d\u00e9claration est, selon un n\u00e9ologisme sans intention de nuire, <em>transatlantically correct<\/em> : aucune allusion \u00e0 ce que d&rsquo;aucuns jugeraient \u00eatre de l&rsquo;amertume antiam\u00e9ricaniste du pr\u00e9sident, r\u00e9f\u00e9rence vertueuse \u00e0 l&rsquo;OTAN selon la consigne, et jusqu&rsquo;\u00e0 la suggestion que le Triangle peut tr\u00e8s bien s&rsquo;\u00e9largir \u00e0 un carr\u00e9 \u00e9ventuellement rectangulaire, \u00e0 un pentagone (oups) \u00e0 5 ou 6 c\u00f4t\u00e9s et au-del\u00e0, avec de nombreux autres alli\u00e9s. R\u00eavons un peu puis passons \u00e0 autre chose.<\/p>\n<\/p>\n<p><p>\tS&rsquo;il n&rsquo;y avait que cela, y compris les agitations fran\u00e7aises autour du Triangle, cela ne mangerait pas beaucoup de pain et l&rsquo;on pourrait en rester l\u00e0. Mais il y a autre chose, du c\u00f4t\u00e9 anglo-saxon, quelques agitations tr\u00e8s vite alarm\u00e9es suivant les d\u00e9clarations du pr\u00e9sident polonais qui, elles, avaient soulev\u00e9 un voile sur le sacril\u00e8ge de d\u00e9clarer erron\u00e9 le fait d&rsquo;avoir pass\u00e9 accord avec les USA en <a href=\"http:\/\/www.dedefensa.org\/article-la_m_che_est-elle_allum_e_22_08_2008.html\" class=\"gen\">ao\u00fbt 2008<\/a>,  accord depuis devenu caduc, avec les pertes et profits (surtout les premi\u00e8res) au frais de la princesse polonaise.<\/p>\n<\/p>\n<p><p>\t Il y a eu d&rsquo;abord cet article dramatique du <em>Daily Telegraph<\/em> du <a href=\"http:\/\/www.telegraph.co.uk\/news\/worldnews\/europe\/poland\/9456610\/Polish-president-accuses-Obama-of-betraying-Poland.html\" class=\"gen\">6 ao\u00fbt 2012<\/a>, traduisant lestement les propos du pr\u00e9sident Komorowski. D&rsquo;abord le titre, avec le mot terrible de trahison (\u00ab<em>The Polish president has accused Barack Obama of betraying Poland by cancelling a promised missile defence system<\/em>\u00bb) Prestement, le <em>Daily Telegraph<\/em> transforme l&rsquo;intervention du pr\u00e9sident polonais en une trahison washingtonienne de la Pologne face \u00e0 la Russie, ce qui conduit \u00e0 un vertigineux imbroglio d&rsquo;interpr\u00e9tations et de sollicitations des choses Le r\u00e9seau BMDE, par la pr\u00e9sence US en Pologne qu&rsquo;il impliquerait, devient un instrument de protection de la Pologne contre la Russie. C&rsquo;est l&rsquo;habituelle interpr\u00e9tation-sollicitation antagoniste, antirusse, des durs transatlantiques et autres <em>neocons<\/em>, de la version officielle des capacit\u00e9s du r\u00e9seau BMDE par rapport \u00e0 la protection de la Pologne, que ce soit dans sa version officielle anti-iranienne, que ce soit m\u00eame dans sa version interpr\u00e9tative d&rsquo;orientation directe antirusse. (Avec le BMDE, nous sommes dans le domaine des missiles strat\u00e9giques alors que la Pologne est sur la fronti\u00e8re russe, et que l&rsquo;\u00e9ventuelle menace viendrait bien plus des missiles tactiques courts <em>Iskander<\/em> SS-26 et du reste, y compris les b\u00eates chars bien connus, avec lesquels le BMDE n&rsquo;a aucun rapport.) Du coup, l&rsquo;affaire prend \u00e9galement une dimension pol\u00e9mique et \u00e9lectoraliste, en se r\u00e9f\u00e9rant aux querelles sans fin autour des th\u00e8ses <em>neocons<\/em> ; cela, d&rsquo;autant plus clairement que le <em>Telegraph<\/em> y va de son rappel de la visite de Romney en Pologne, une semaine avant les d\u00e9clarations du pr\u00e9sident polonais<\/p>\n<\/p>\n<p><p>\t\u00ab<em>Last week, Mitt Romney used a visit to Warsaw to condemn Russia as a country where the desire to be free is met with brutal oppression in a bid to establish hawkish credentials ahead of the US elections. The Republican candidate has accused President Obama of abandoning Poland by cancelling the missile defence plan in order to aid his much-criticised attempt to reset relations with Moscow.<\/p>\n<\/p>\n<p><p>\tMr Obama&rsquo;s decision to scrap George W Bush&rsquo;s original missile shield dismayed the Polish government, especially as many Poles saw it as an attempt to appease Russia, Poland&rsquo;s historical and Cold War foe.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Sur la m\u00eame piste antagoniste, antirusse, \u00e9ventuellement anti-Obama,  mais aussi anti-europ\u00e9nne, nouvelle dimension,  on citera un texte assez d\u00e9cousu, accroche d&rsquo;un texte payant, de F. Michael Maloof de la Lettre d&rsquo;Information G2, rachet\u00e9e par le site <em>World Net Daily<\/em> (WND) Que du beau monde ! <a href=\"http:\/\/rightweb.irc-online.org\/profile\/maloof_f_michael\/\" class=\"gen\">F. Michael Maloof<\/a> est un personnage \u00e9minemment douteux, qui semble porter ses diverses compromissions comme autant de d\u00e9corations de campagnes glorieuses, avec plusieurs CV amovibles et tous de type <em>narrative<\/em>, l&rsquo;une ou l&rsquo;autre casserole de corruption, lui-m\u00eame pr\u00e9sent\u00e9 dans le texte, sans rire, comme <em>a former senior security policy analyst in the office of the secretary of defense<\/em> Ce qu&rsquo;il reste d&rsquo;assur\u00e9, c&rsquo;est que Maloof, qui \u00e9tait du programme <em>Office of Special Plans<\/em> de Rumsfeld en 2001-2003 (OSP, fabrication sp\u00e9ciale des <em>narrative<\/em> sur les armes de destruction massive de Saddam, voir le <a href=\"http:\/\/www.dedefensa.org\/article-la_bataille_des_armes_de_destruction_massive_14_05_2003.html\" class=\"gen\">14 mai 2003<\/a>), qui est rest\u00e9 constamment un homme de Richard Perle, est marqu\u00e9e \u00e0 la culotte pour ses parcours de corruption et d&rsquo;extr\u00e9misme <em>neocon<\/em>. Le texte de Maloof prend en compte l&rsquo;initiative fran\u00e7aise du Triangle de Weimar mais passe sous silence la d\u00e9claration du pr\u00e9sident polonais, qu&rsquo;il ignore certainement. (Le texte de la Lettre G2 est ant\u00e9rieur au texte cit\u00e9, sur WND, le <a href=\"http:\/\/www.wnd.com\/2012\/08\/eu-nations-looking-at-nato-substitute\/\" class=\"gen\">10 ao\u00fbt 2012<\/a>. De toutes les fa\u00e7ons, les initiatives et d\u00e9clarations qui ne viennent pas de Washington, selon les normes washingtoniennes, mettent toujours un certain temps \u00e0 franchir l&rsquo;obstacle des psychologies et perceptions \u00e9paisses des esprits am\u00e9ricanistes coul\u00e9s dans l&rsquo;extr\u00e9misme provincialiste.)<\/p>\n<\/p>\n<p><p>\tLa d\u00e9marche appara\u00eet clairement comme celle d&rsquo;une avant-garde annonciatrice \u00e9ventuelle (Maloof ne travaille que sur consigne) d&rsquo;une alarme et d&rsquo;une alerte face \u00e0 des projets suppos\u00e9s subversifs de d\u00e9fense europ\u00e9enne et par cons\u00e9quent d&rsquo;attaque contre l&rsquo;OTAN ; ces projets venant une fois de plus de la France (<em>France once again<\/em>),  pauvre France, malgr\u00e9 tous ses efforts \u00ab<em>France once again is pushing the notion of a common European defense force. Three countries  Poland, Germany and France  are often referred to as the Weimar Triangle nations, according to a report in Joseph Farah&rsquo;s G2 Bulletin.<\/em><\/p>\n<\/p>\n<p><p>\t\u00bb<em>French Defense Minister Jean-Yves Le Drian said that a coordinated effort by these countries for a common European defense also would assist in defense spending cuts and pooling military capacities of the European countries. The call for a common European defense comes as Europeans see the United States shifting its emphasis more toward the Asia-Pacific region. Until now, the U.S. has been the lead country in maintaining the North Atlantic Treaty Organization. But many now are questioning whether it needs to exist.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t Une autre intervention, venue de milieux transatlantiques plus mod\u00e9r\u00e9s, de ceux qui cherchent \u00e0 \u00e9viter toute dissension transatlantique en m\u00eame temps que des pressions trop fortes entre partenaires pouvant mettre en danger l&rsquo;\u00e9quilibre de suj\u00e9tion des Europ\u00e9ens vis-\u00e0-vis des USA jug\u00e9 d\u00e9licat,  en l&rsquo;occurrence le German Marshall Fund. L&rsquo;expert Michal Baranowski, du GMF, se charge de tenter de nous rassurer, mais avec des pr\u00e9cisions qui peuvent s&rsquo;av\u00e9rer indirectement inqui\u00e9tantes. (L&rsquo;article, publi\u00e9 le <a href=\"http:\/\/blog.gmfus.org\/2012\/08\/11\/polish-missile-defense-plan-puts-poland-first\/\" class=\"gen\">11 ao\u00fbt 2012<\/a>, ne prend pas en compte la r\u00e9cente d\u00e9claration du ministre de la d\u00e9fense polonais sur une coop\u00e9ration au moins avec la France et l&rsquo;Allemagne.) A propos de la d\u00e9claration du pr\u00e9sident polonais, Baranowski \u00e9crit : \u00ab<em>While some saw the statement as a rejection of U.S. President Barack Obama&rsquo;s proposed missile defense system, others viewed it as a sign of  Poland&rsquo;s weakening military alliance with the United States. Both arguments are misleading.<\/em>\u00bb Pourtant, un peu plus loin, ce m\u00eame Baranowski \u00e9crit \u00e0 propos du changement de plans du BMDE d\u00e9cid\u00e9 par Obama en 2010, ceci qui pourrait \u00eatre interpr\u00e9t\u00e9 \u00e0 la fois comme un rejet du plan d&rsquo;Obama et comme une tendance \u00e0 l&rsquo;affaiblissement de l&rsquo;alliance militaire de la Pologne avec les USA : \u00ab<em>The abrupt shift in American policy has raised doubts of the US commitment to Poland.<\/em>\u00bb Enfin, pour terminer, Baranowski nous donne des explications techniques qui ne sont pas inint\u00e9ressantes, mais qui nous conduisent \u00e0 consid\u00e9rer en prolongement politique de ses conclusions, \u00e9galement techniques et dont il ne tire, lui, aucune cons\u00e9quence politique : 1) que la Pologne n&rsquo;est plus du tout int\u00e9ress\u00e9e par les interventions ext\u00e9rieures (Irak, Afghanistan) dont les USA ont fait la t\u00e2che principale de l&rsquo;OTAN comme suppl\u00e9tive de leurs entreprises, mais par sa propre s\u00e9curit\u00e9 ; et 2) que cette s\u00e9curit\u00e9 passe par des syst\u00e8mes de d\u00e9fense tactiques de diff\u00e9rentes ampleurs, mais certainement pas strat\u00e9giques, ce qui n&rsquo;implique pas une opposition au BMDE mais pour le moins, un d\u00e9sint\u00e9r\u00eat navrant de la Pologne pour la chose, au contraire de sa position initiale. <\/p>\n<\/p>\n<p><p>\t\u00ab<em>Komorowski&rsquo;s call for the creation of Polish missile defense is not about Polish-American relations, but about the future of Poland&rsquo;s security. Poland needs stronger anti-aircraft and anti short and medium missile defenses independent of any proposed American MD system. The two systems are complimentary, not competing. The announcement reflects an increasing confidence and affluence of a country that is increasingly able to rely on its own strength for its security. Furthermore, prioritizing anti-missile defense reveals the Polish government&rsquo;s growing focus on the primacy of territorial defense over expeditionary capabilities. The Polish MD system is to be financed from the savings of winding down the war in Afghanistan, and from the growth of military budget over the coming years related to Poland&rsquo;s economic growth (Polish law mandates that 1.95% of GDP is spent on defense). According to initial estimates, it would be a pricy program, costing 8 to 15 billion zl ($3-5 billion) over the next 10 years. Such costs would lower Poland&rsquo;s appetite and ability to take part in expensive expeditionary missions. But with its increased focus on its own territory, don&rsquo;t expect Poland to eagerly step up, as it did in Iraq and Afghanistan, if another hot spot boils over somewhere else in the world.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tVoil\u00e0 \u00e0 peu pr\u00e8s et approximativement l&rsquo;\u00e9tat de la question ; avec les diverses voies explor\u00e9es et, surtout, ouvertes \u00e0 des exploitations politiques, ou politiciennes ; avec, partout, des psychologies en apparence align\u00e9es sur les pr\u00e9occupations communes (la ligne du parti, ou la ligne BAO) mais nourrissant en r\u00e9alit\u00e9, sur leurs propres situations, des pr\u00e9occupations tr\u00e8s diff\u00e9rentes. Il existe m\u00eame, comme c&rsquo;est la coutume entre les partenaires transatlantiques, des ruptures de perception dissimul\u00e9es qui peuvent ressurgir. La Pologne, \u00e9l\u00e9ment \u00e0 la fois essentiel du dispositif <strong>europ\u00e9en<\/strong> de l&rsquo;OTAN d&rsquo;apr\u00e8s la Guerre froide, mais aussi \u00e9l\u00e9ment excentr\u00e9 et psychologiquement tr\u00e8s instable, pourrait avec cette intervention avoir ouvert une des nombreuses bo\u00eetes de Pandore rang\u00e9es dans le corridor des salles de d\u00e9lib\u00e9ration du bloc BAO.<\/p>\n<h3>Vertu antiSyst\u00e8me du d\u00e9sordre (suite)<\/h3>\n<\/p>\n<p><p>\tQuelle est la cause de l&rsquo;intervention polonaise,  que nous serions tent\u00e9s de d\u00e9crire comme l&rsquo;interf\u00e9rence polonaise ? Nous aurions tendance \u00e0 en chercher l&rsquo;explication dans les associations qu&rsquo;on peut faire entre la crise syrienne et l&rsquo;implication du bloc BAO dans cette crise d&rsquo;une part, et la position et l&rsquo;attitude de la Russie d&rsquo;autre part. D&rsquo;une certaine fa\u00e7on, l&rsquo;ancien Premier ministre fran\u00e7ais Fran\u00e7ois Fillon donne indirectement l&rsquo;explication de la chose (dans <em>Le Figaro<\/em> du <a href=\"http:\/\/www.lefigaro.fr\/international\/2012\/08\/12\/01003-20120812ARTFIG00173-un-peu-de-courage-monsieur-le-president.php\" class=\"gen\">13 ao\u00fbt 2012<\/a>), avec une orientation diff\u00e9rente tenant aux diff\u00e9rences diplomatiques et g\u00e9ographiques de la France et de la Pologne. Apr\u00e8s avoir longuement et curieusement dissert\u00e9 sur la crise syrienne, sur l&rsquo;attitude russe, sur la n\u00e9cessit\u00e9 de s&rsquo;entendre avec la Russie en lui faisant abandonner sa position dans la crise syrienne, cela tout en reconnaissant la validit\u00e9 de nombre de ses arguments (?), Fillon \u00e9crit sur la fin de son article,  <strong>passant brusquement<\/strong> au th\u00e9\u00e2tre europ\u00e9en,  selon une logique qui pourrait \u00e9galement se d\u00e9velopper <a href=\"http:\/\/www.dedefensa.org\/article-l_etrange_europe_face_a_poutine_05_03_2012.html\" class=\"gen\">chez les Russes<\/a> eux-m\u00eames, et pas vraiment pour notre confort : \u00ab<em>Si j&rsquo;\u00e9tais Fran\u00e7ois Hollande, je prendrais l&rsquo;avion maintenant pour Moscou, si possible avec Angela Merkel, et je chercherais \u00e0 offrir \u00e0 la Russie de v\u00e9ritables garanties sur sa s\u00e9curit\u00e9 et sur une relation de confiance avec l&rsquo;Otan, qui doit inclure la question de la d\u00e9fense antimissile \u00e0 laquelle les Russes doivent \u00eatre r\u00e9ellement associ\u00e9s. L&rsquo;ours russe n&rsquo;est dangereux que quand il a peur. Offrons-lui sans d\u00e9tour la perspective d&rsquo;un accord historique d&rsquo;association avec l&rsquo;Europe.<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\t(Notons, en passant, l&rsquo;optimisme roboratif de l&rsquo;excellent Fillon qui semble que croire que Hollande, voire Hollande-Merkel sont capables, \u00e0 eux seuls, d&rsquo;apporter \u00e0 la Russie la proposition d&rsquo;une <strong>v\u00e9ritable<\/strong> association dans le programme des antimissiles A-t-il d\u00e9j\u00e0 entendu parler du Pentagone, Fillon ? A moins qu&rsquo;il ne songe \u00e0 un programme qui ne soit ni OTAN ni US, et dans ce cas,  d\u00e9veloppez, Fillon, d\u00e9veloppez, c&rsquo;est int\u00e9ressant Peut-\u00eatre m\u00eame auriez-vous vous-m\u00eame d\u00e9j\u00e0 lanc\u00e9 l&rsquo;affaire, dont tous les \u00e9l\u00e9ments \u00e9taient d\u00e9j\u00e0 pr\u00e9sents, avant votre d\u00e9part de Matignon, non ? Dites-nous vite, et informez-en le pr\u00e9sident Hollande, ou l&rsquo;inverse&#8230;)<\/p>\n<\/p>\n<p><p>\tSelon notre hypoth\u00e8se, les Polonais raisonnent de la m\u00eame fa\u00e7on mais selon une conclusion tr\u00e8s diff\u00e9rente tenant aux diff\u00e9rences qu&rsquo;on a vues plus haut : plut\u00f4t que chercher une entente avec les Russes, mettre l&rsquo;accent sur la s\u00e9curit\u00e9 de la Pologne sans pour autant d\u00e9signer un adversaire potentiel. (Ce sont les autres, comme on le lit ici et l\u00e0, qui trouvent l&rsquo;adversaire assur\u00e9 de la Pologne : la Russie, certes.) L&rsquo;ironie est qu&rsquo;ils se tournent vers des partenaires europ\u00e9ens qui se trouvent dans des positions ambigu\u00ebs vis-\u00e0-vis de la Russie. On a vu un aspect d&rsquo;une opinion fran\u00e7aise l\u00e0-dessus, et l&rsquo;on peut arguer que les Allemands, encore plus que les Fran\u00e7ais, ne d\u00e9sirent pas du tout une attitude de confrontation avec la Russie. Mais la proposition polonaise doit \u00eatre consid\u00e9r\u00e9e du point de vue politique et nullement technique, ni militaire certes. Au contraire de la seconde fa\u00e7on de voir qui conduit \u00e0 un d\u00e9bat de quincaillerie qui tournerait n\u00e9cessairement \u00e0 la machinerie antirusse, la premi\u00e8re constitue le cas d&rsquo;un processus troublant l&rsquo;alignement impeccable des membres europ\u00e9ens du bloc BAO, selon diverses consid\u00e9rations. (Bien \u00e9videmment, tout ce qui est \u00e9voqu\u00e9 ci-dessous rel\u00e8ve de l&rsquo;hypoth\u00e8se et n&rsquo;est envisag\u00e9 en rien du point de vue d&rsquo;une possible r\u00e9alisation ; par contre, l&rsquo;\u00e9volution de la psychologie est, elle, bien possible.)<\/p>\n<\/p>\n<p><p>\t L&rsquo;agitation polonaise concerne la s\u00e9curit\u00e9 de la Pologne, certes, mais <strong>surtout<\/strong> elle s&rsquo;accompagne de deux facteurs mis en \u00e9vidence directement ou indirectement par Baranowski : le d\u00e9sint\u00e9r\u00eat pour les aventures ext\u00e9rieures et un certain d\u00e9sint\u00e9r\u00eat pour le BMDE USA-OTAN, qui n&rsquo;est plus consid\u00e9r\u00e9 comme un garant de la s\u00e9curit\u00e9 de la Pologne.<\/p>\n<\/p>\n<p><p>\t Pour substantiver cette orientation, la Pologne \u00e9voque une coop\u00e9ration avec l&rsquo;Allemagne et la France, cela correspondant aux efforts fran\u00e7ais pour ressusciter le Triangle de Weimar. L\u00e0 encore, il faut consid\u00e9rer la dimension politique de la proposition, et constater qu&rsquo;aucun des deux partenaires envisag\u00e9s ne tient \u00e0 envisager, de quelque fa\u00e7on que ce soit, un projet antirusse, tout comme la Pologne sans doute. Autrement dit, le projet devient \u00e9vocateur d&rsquo;une dimension de d\u00e9fense europ\u00e9enne avec, comme perspective \u00e9ventuelle et pour l&rsquo;instant assez po\u00e9tique, un grand pacte de s\u00e9curit\u00e9 avec la Russie. A cette lumi\u00e8re, la d\u00e9marche polonaise n&rsquo;est pas antirusse mais peut, au contraire, \u00eatre celle de la recherche, ou bien simplement de l&rsquo;\u00e9vocation d&rsquo;un arrangement avec les Russes si les Franco-Allemands s&rsquo;y int\u00e9ressent<\/p>\n<\/p>\n<p><p>\t Mais il se trouve que les agitations polonaises ont provoqu\u00e9 et provoquent,  et, peut-\u00eatre plus encore, vont provoquer des r\u00e9actions dans la dimension anglo-saxonne. Ces r\u00e9actions entrent dans le d\u00e9bat interne anglo-saxonne, qui se r\u00e9sume en g\u00e9n\u00e9ral \u00e0 une constante pouss\u00e9e extr\u00e9miste, d&rsquo;inspiration <em>neocon<\/em> ou assimil\u00e9e. En g\u00e9n\u00e9ral, cette pouss\u00e9e extr\u00e9miste s&rsquo;appuie sur l&rsquo;argument conjugu\u00e9 des USA ne prot\u00e9geant pas assez ou abandonnant la Pologne face \u00e0 la Russie ; il est \u00e9videmment antirusse en substance. Un autre argument appara\u00eet, qui est l&rsquo;argument antieurop\u00e9en (contre une d\u00e9fense europ\u00e9enne autonome se d\u00e9veloppant contre l&rsquo;OTAN), dans lequel la Pologne n&rsquo;appara\u00eet qu&rsquo;accessoirement. Que les deux arguments puissent \u00e9ventuellement \u00eatre contradictoires n&rsquo;a aucune importance, la pouss\u00e9e extr\u00e9miste \u00e9cartant la logique au profit de la radicalisation.<\/p>\n<\/p>\n<p><p>\t Cette pouss\u00e9e de radicalisme id\u00e9ologique devrait \u00e9videmment \u00eatre renforc\u00e9e par l&rsquo;intense dimension mercantile qu&rsquo;on trouve dans ces milieux extr\u00e9mistes li\u00e9s \u00e0 l&rsquo;industrie d&rsquo;armement. Toutes les esquisses de projets europ\u00e9ens faisant r\u00e9f\u00e9rence implicite \u00e0 des syst\u00e8mes europ\u00e9ens, comme les diverses d\u00e9clarations polonaises, impliquent dans la partie anglo-saxonne et l&rsquo;industrie d&rsquo;armement dans ce cas une r\u00e9action contraire, de type hyst\u00e9rique et furieux, autour des syst\u00e8mes et organisations essentiellement US. (Cette r\u00e9action serait d&rsquo;autant plus cors\u00e9e qu&rsquo;on sait l&rsquo;\u00e9tat path\u00e9tique de l&rsquo;industrie de d\u00e9fense US, croulant sous les centaines de $milliards et pourtant affol\u00e9s \u00e0 l&rsquo;id\u00e9e de la <a href=\"http:\/\/www.dedefensa.org\/article-vade_retro_veritas_22_05_2012.html\" class=\"gen\">s\u00e9questration<\/a> dont elle serait menac\u00e9e.) Dans ce cas, des projets nationaux, de coop\u00e9ration ou de d\u00e9fense europ\u00e9enne, m\u00eame s&rsquo;ils se pr\u00e9sentent comme compl\u00e9mentaires au projet g\u00e9n\u00e9ral BMDE n\u00e9cessairement d&rsquo;ob\u00e9dience US, sont per\u00e7us comme antagonistes et doivent \u00eatre \u00e9limin\u00e9s. La russophobie accompagn\u00e9e d&rsquo;europ\u00e9anophobie impliquent des pressions renouvel\u00e9es en faveur du BMDE strat\u00e9gique OTAN\/am\u00e9ricaniste, pr\u00e9sent\u00e9 comme suffisant, n\u00e9cessairement int\u00e9gr\u00e9, sous contr\u00f4le US, etc., et impliquant d&rsquo;\u00e9ventuels autres syst\u00e8mes selon la m\u00eame logique d&#8217;emprisonnement. <\/p>\n<\/p>\n<p><p>\t  La cons\u00e9quence politique et politicienne probable, aux USA, en pleine ann\u00e9e \u00e9lectorale et dans un d\u00e9bat int\u00e9rieur totalement inexistant et bloqu\u00e9, pourrait \u00eatre de relancer la question maximaliste et schizophr\u00e9nique de la s\u00e9curit\u00e9. L&rsquo;affaire polonaise serait un bon argument, puisqu&rsquo;on y trouve p\u00eale-m\u00eale la russophobie, l&rsquo;europ\u00e9anophobie US, le syst\u00e8me antimissile avec ses prolongements dans la crise iranienne et ainsi de suite. Un axe de campagne tout trouv\u00e9 pour Romney et son \u00e9quipe ultra-<em>neocon<\/em>, qui pousserait Obama, dont on conna\u00eet l&rsquo;\u00e9lectoralisme et la sensibilit\u00e9 sur les questions de s\u00e9curit\u00e9, lui-m\u00eame vers la surench\u00e8re. Cela impliquerait une mobilisation otanienne, des pressions sur la Pologne, \u00e9ventuellement sur l&rsquo;Allemagne, des accusations ironiques contre les pauvres Fran\u00e7ais qui ne cessent de d\u00e9velopper leur politique d&rsquo;alignement atlantiste mais qui ne craignent pas les contradictions schizophr\u00e9niques avec un argumentaire comme celui de Fillon, lui-m\u00eame schizophr\u00e9nique, qui d\u00e9clare \u00e0 nouveau que tout, en Europe, passe par une entente avec la Russie<\/p>\n<\/p>\n<p><p>\tOn observera qu&rsquo;il n&rsquo;y a rien de coh\u00e9rent, ni de constructif \u00e0 sortir de tout cela. Nous disons simplement que l&rsquo;initiative polonaise et le malaise qu&rsquo;\u00e9prouve ce pays, \u00e0 la fois inquiet pour sa s\u00e9curit\u00e9, hostile aux aventures ext\u00e9rieures, soucieux \u00e0 la fois de se prot\u00e9ger contre la Russie et de s&rsquo;arranger avec la Russie (schizophr\u00e9nie, l\u00e0 aussi), peuvent susciter des remous en Europe. Cela vaut d&rsquo;autant plus que la nouvelle pr\u00e9sidence Hollande est elle-m\u00eame soucieuse de faire quelque chose au niveau europ\u00e9en, dans le sens de la d\u00e9fense et de la s\u00e9curit\u00e9, et que son opposition pousse dans ce sens,  les uns et les autres semblant ne pas saisir les contradictions entre cette nouvelle tendance et celle qui, depuis 2009, pr\u00e9vaut d&rsquo;un alignement complet au sein du bloc BAO par toutes les initiatives europ\u00e9ennes (retour dans l&rsquo;OTAN) et p\u00e9riph\u00e9riques (Libye, Syrie). L\u00e0 aussi r\u00e8gne la schizophr\u00e9nie, qui est la marque op\u00e9rationnelle d&rsquo;une psychologie <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_terrorisation_de_la_psychologie_ddecrisis_18_06_2012.html\" class=\"gen\">terroris\u00e9e<\/a> et fonctionnant sur un mode <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_maniaco-depression_du_monde_ddecrisis_19_01_2012.html\" class=\"gen\">maniaco-d\u00e9pressif<\/a> sous les pressions contradictoires impos\u00e9e par le Syst\u00e8me.<\/p>\n<\/p>\n<p><p>\tTout cela est aujourd&rsquo;hui un sch\u00e9ma classique et connu, depuis 2008 particuli\u00e8rement, depuis que les relations transatlantiques classiques se sont transform\u00e9es en une unification (une ossification) des politiques (voir le <a href=\"http:\/\/www.dedefensa.org\/article-g_n_alogie_et_v_rit_du_bloc_bao__23_06_2012.html\" class=\"gen\">23 juin 2012<\/a>) sous le sigle que nous utilisons de bloc BAO. Cette unification ossifi\u00e9e constitue \u00e0 la fois un bloc intangible dans le domaine de la politique \u00e0 suivre, maximaliste et construite sur une (des) <em>narrative<\/em> ; mais \u00e9galement un bloc fragile, qui suppose l&rsquo;adh\u00e9sion aveugle de tous aux impulsions du Syst\u00e8me. L&rsquo;inqui\u00e9tude polonaise est un facteur nouveau, important, en fonction de la sensibilit\u00e9 de ce pays aux situations g\u00e9ographiques et strat\u00e9giques, et de son importance,  tant en lui-m\u00eame, qu&rsquo;\u00e0 l&rsquo;int\u00e9rieur du bloc, \u00e0 l&rsquo;int\u00e9rieur de l&rsquo;OTAN, et par ses relations symboliques avec les USA que les extr\u00e9mistes US jugeront menac\u00e9es \u00e0 cette occasion. La complexit\u00e9 de la question, qu&rsquo;on a rapidement d\u00e9taill\u00e9e ci-dessus, les contradictions nombreuses dans les diff\u00e9rents axes expos\u00e9s, la pression des crises ext\u00e9rieures (Syrie) sur le bloc BAO, \u00e0 l&rsquo;heure o\u00f9 ces crises se trouvent bloqu\u00e9es et d\u00e9couvrent l&rsquo;impuissance et la strat\u00e9gie fautive du bloc, tout cela constitue une sorte de bouilloire en \u00e9bullition qui pourrait contribuer \u00e0 faite d\u00e9marrer un d\u00e9bat violent, antagoniste et agressif \u00e0 la moindre occasion. Tous les pays du bloc sont en crise, tous sont lanc\u00e9s dans des politiques agressives comme autant de fuites en avant, tous ont des int\u00e9r\u00eats qu&rsquo;ils proclament communs et qui sont en fait divergents sinon antagonistes, tous souffrent des m\u00eames pathologies psychologies et des m\u00eames d\u00e9formations de perception mais op\u00e9rant dans des sens diff\u00e9rents qui se r\u00e9v\u00e9leraient en cas de tension. Les conditions sont tr\u00e8s favorables \u00e0 une crise interne du bloc, et la s\u00e9curit\u00e9 est un bon terrain pour cela. Pour cette raison, l&rsquo;\u00e9veil polonais \u00e0 l&rsquo;inqui\u00e9tude tous azimuts est une nouvelle int\u00e9ressante, qui peut susciter, dans des circonstances un tant soit peu favorables comme on en voit tant aujourd&rsquo;hui, des prolongements de crise interne au bloc tr\u00e8s int\u00e9ressantes.<\/p>\n<\/p>\n<p><p>\tEncore une fois, il n&rsquo;est pas question ici d&rsquo;avancer une perspective constructive, de faire miroiter la possibilit\u00e9 d&rsquo;une d\u00e9fense europ\u00e9enne, selon une logique qui avait sa justification dans les ann\u00e9es 1991-1999 mais qui n&rsquo;a plus aucun fondement aujourd&rsquo;hui. La consigne, la tendance n\u00e9cessaires aujourd&rsquo;hui, c&rsquo;est l&rsquo;introduction du d\u00e9sordre dans un bloc que les contraintes du Syst\u00e8me maintiennent de plus en plus difficilement dans un moule qui ne souffre aucune d\u00e9rogation, aucune nuance. Nous r\u00e9p\u00e9tons donc qu&rsquo;il n&rsquo;y a rien de coh\u00e9rent, ni de constructif \u00e0 sortir de tout cela, et nous ajoutons que c&rsquo;est aussi bien car seul, aujourd&rsquo;hui, le d\u00e9sordre de r\u00e9action (antiSyst\u00e8me) peut donner quelque effet que ce soit dont on puisse attendre un prolongement b\u00e9n\u00e9fique. Il ne s&rsquo;agit pas de rechercher un nouvel ordre, y compris et soi-disant europ\u00e9en, qui serait n\u00e9cessairement capt\u00e9 et dig\u00e9r\u00e9 par l&rsquo;ordre schizophr\u00e8ne et pathologique du bloc BAO, du Syst\u00e8me ; il de s&rsquo;agit pas de construire mais de d\u00e9truire ; il ne s&rsquo;agit pas de proposer (n\u00e9cessairement par rapport au Syst\u00e8me, ce qui signifie n\u00e9cessairement l&rsquo;absorption par le Syst\u00e8me) mais de s&rsquo;opposer (\u00eatre antiSyst\u00e8me). Concevoir de la sorte n&rsquo;implique <strong>en rien<\/strong> une perspective nihiliste, mais exactement son contraire ; il s&rsquo;agit d&rsquo;une perspective r\u00e9aliste tenant compte de l&rsquo;extraordinaire herm\u00e9tisme du Syst\u00e8me, de cette loi de subversion et de dissolution que le Syst\u00e8me impose \u00e0 ceux dont il dispose compl\u00e8tement. Tout ce qui peut entamer cet ordre de fer, ordre inverti, \u00e0 la fois de nihilisme et d&rsquo;entropisation, est une chose bonne et recommandable. Le d\u00e9sordre introduit dans cet ordre fait l&rsquo;affaire ; qu&rsquo;il soit polonais serait du meilleur aloi possible, tant les Polonais ont l&rsquo;art de la trag\u00e9die et la pratique de la dramatisation historique.<\/p>\n<\/p>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le bloc BAO fr\u00e9mit sur son Est 14 ao\u00fbt 2012 Les d\u00e9clarations ambigu\u00ebs, ampoul\u00e9es et alambiqu\u00e9es du pr\u00e9sident polonais \u00e0 propos du r\u00e9seau antimissiles US (voir le 6 ao\u00fbt 2012 et encore le 6 ao\u00fbt 2012) ont provoqu\u00e9 quelques remous, discrets mais significatifs. Elles ont \u00e9t\u00e9 suivies de d\u00e9clarations, notamment, du ministre polonais de la&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[2748,4056,4314,2631,8972,2687,3203,11441,1104,2827,6776,2730,11367,15020,3867,2842,4828,15021],"class_list":["post-73319","post","type-post","status-publish","format-standard","hentry","category-faits-et-commentaires","tag-allemagne","tag-antimissiles","tag-bmde","tag-de","tag-fillon","tag-france","tag-hollande","tag-maloof","tag-neocons","tag-pologne","tag-romney","tag-russie","tag-sequestration","tag-siemoniak","tag-syrie","tag-trahison","tag-triangle","tag-wiemar"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73319"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73319\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}