{"id":73328,"date":"2012-08-19T05:11:30","date_gmt":"2012-08-19T05:11:30","guid":{"rendered":"https:\/\/new.dedefensa.org\/index.php\/2012\/08\/19\/chronique-du-19-courant-bilan\/"},"modified":"2012-08-19T05:11:30","modified_gmt":"2012-08-19T05:11:30","slug":"chronique-du-19-courant-bilan","status":"publish","type":"post","link":"https:\/\/new.dedefensa.org\/index.php\/2012\/08\/19\/chronique-du-19-courant-bilan\/","title":{"rendered":"Chronique du 19 courant\u2026 Bilan"},"content":{"rendered":"<p><h2 class=\"common-article2\">Chronique du 19 courant Bilan<\/h2>\n<\/p>\n<p><p>\tCe 19 ao\u00fbt 2012&#8230; Entamer cette nouvelle rubrique comme l&rsquo;on dit d&rsquo;une nouvelle cat\u00e9gorie de textes, un nouveau genre par rapport aux habitudes du site, comme l&rsquo;on met le pied sur une <em>terra incognita<\/em> J&rsquo;y entre avec r\u00e9solution et avec prudence, avec enthousiasme et avec incertitude, avec assurance et avec h\u00e9sitation,  selon les moments, certes. Voici un texte de pr\u00e9sentation d&rsquo;une nouvelle s\u00e9rie r\u00e9guli\u00e8re d&rsquo;articles, pouvait-on lire le <a href=\"http:\/\/www.dedefensa.org\/article-chronique_du_19_courant_pr_sentation_19_07_2012.html\" class=\"gen\">19 juillet 2012<\/a>, dans le texte introductif de la s\u00e9rie ; voici <strong>ma<\/strong> pr\u00e9sentation serais-je tent\u00e9 d&rsquo;\u00e9crire. Apr\u00e8s bien des r\u00e9ticences concernant la fa\u00e7on de s&rsquo;y mettre et de s&rsquo;y lancer, j&rsquo;ai finalement trouv\u00e9 l&rsquo;assurance de concevoir qu&rsquo;il serait bon que le th\u00e8me en f\u00fbt mon m\u00e9tier, cette passion qui l&rsquo;anime, ce sacerdoce qu&rsquo;il suscite, cette transmutation qui fit de lui bien plus qu&rsquo;un m\u00e9tier, et tout cela qui m\u00e8ne et justifie <em>dedefensa.org<\/em> et moi-m\u00eame \u00e0 la fois. Sur le soir d&rsquo;une vie, il peut arriver qu&rsquo;on en vienne \u00e0 juger qu&rsquo;il n&rsquo;est pas sans int\u00e9r\u00eat, et presque d&rsquo;un int\u00e9r\u00eat tragique pour mon compte, d&rsquo;envisager d&rsquo;ouvrir la voie \u00e0 quelque chose de neuf en rassemblant les \u00e9l\u00e9ments d&rsquo;un jugement et d&rsquo;une perspective historique de cet acte d&rsquo;\u00e9crire, chaque jour, inlassablement, sur la situation du monde et sur la recherche de la v\u00e9rit\u00e9 du monde. (L&rsquo;un ne va pas sans l&rsquo;autre, la situation du monde et la v\u00e9rit\u00e9 du monde, et tr\u00e8s vite la technique devient exp\u00e9rience, et ce qui \u00e9tait le but d&rsquo;un esprit inexp\u00e9riment\u00e9 \u00e0 la recherche de son destin devient l&rsquo;outil de l&rsquo;esprit parvenu \u00e0 la conscience de son destin.) D&rsquo;une certaine fa\u00e7on, ce serait une mani\u00e8re originale d&rsquo;entamer une chronique, nouveau cycle d&rsquo;\u00e9crits, que de commencer ainsi par ce qui serait une forme de <strong>bilan<\/strong> Commencer au d\u00e9but par la fin, ou bien la fin n&rsquo;est-elle que l&rsquo;origine du recommencement.  <\/p>\n<\/p>\n<p><p>\tJ&rsquo;ai commenc\u00e9 ce m\u00e9tier, c&rsquo;est-\u00e0-dire l&rsquo;exercice de cette passion d&rsquo;\u00e9crire sur la situation du monde, en novembre 1967 pr\u00e9cis\u00e9ment. Ces derni\u00e8res ann\u00e9es s&rsquo;est peu \u00e0 peu form\u00e9 puis renforc\u00e9 mon jugement jusqu&rsquo;\u00e0 l&rsquo;extr\u00eame conviction, qu&rsquo;il n&rsquo;y a pas d&rsquo;activit\u00e9 qui ait connu, dans ce laps de temps, une plus formidable r\u00e9volution dans sa technicit\u00e9, et surtout dans son esprit m\u00eame jusqu&rsquo;\u00e0 <strong>changer de nature<\/strong>, que cette activit\u00e9 fondamentale d&rsquo;\u00e9crire,  je veux dire, lorsque l&rsquo;on fait de sa vie l&rsquo;acte pur de l&rsquo;esprit, l&rsquo;acte d&rsquo;\u00e9crire pour tenter de comprendre ce que dissimule au fond de lui-m\u00eame le spectacle du monde. La cause en est ce bouleversement qui a affect\u00e9 ce grand domaine de la communication entre les esprits et les choses de l&rsquo;esprit, passant du vague syst\u00e8me de communication qu&rsquo;on ne d\u00e9signait m\u00eame pas ainsi <em>in illo tempore<\/em>, \u00e0 un <a href=\"http:\/\/www.dedefensa.org\/article-dialogues-13_de_la_sublimite_du_systeme_de_la_communication_08_11_2010.html\" class=\"gen\">syst\u00e8me de la communication<\/a>, envisag\u00e9 ici d&rsquo;une fa\u00e7on tr\u00e8s sp\u00e9cifique et tr\u00e8s pr\u00e9cise aujourd&rsquo;hui, comme les lecteurs du site le savent bien.<\/p>\n<\/p>\n<p><p>\tIl est peu utile de s&rsquo;attarder \u00e0 d\u00e9tailler les changements extraordinaires entre cette \u00e9poque de mes d\u00e9buts et notre aujourd&rsquo;hui, en volume d&rsquo;information, en rapidit\u00e9 d&rsquo;acc\u00e8s \u00e0 ces informations, en multiplication g\u00e9om\u00e9trique des sources disponibles jusqu&rsquo;aux plus extraordinaires, en opportunit\u00e9 de s\u00e9lection de ces informations. Tout le monde r\u00e9alise ces changements mais je ne crois pas qu&rsquo;on <strong>mesure<\/strong> commun\u00e9ment leur r\u00e9elle signification, jusqu&rsquo;\u00e0 cette hypoth\u00e8se, qui ne fait plus aucun doute d\u00e9sormais pour moi, que ce formidable changement quantitatif a r\u00e9ussi \u00e0 accoucher d&rsquo;un changement qualitatif fondamental. La chose est sugg\u00e9r\u00e9e dans l&rsquo;id\u00e9e de l&rsquo;opportunit\u00e9 de s\u00e9lection de ces informations, qui indique bien cette inversion vertueuse. Le flot quantitatif se d\u00e9cha\u00eenant jusqu&rsquo;\u00e0 la quasi-asphyxie par \u00e9touffement, il est apparu qu&rsquo;il importait de r\u00e9agir en op\u00e9rant une op\u00e9ration inverse qui est la s\u00e9lection, l&rsquo;\u00e9limination, le choix, etc., de ces sources ; tout cela fond\u00e9 sur l&rsquo;exp\u00e9rience, la pratique et l&rsquo;intuition toujours en \u00e9veil, et l&rsquo;on comprend bien qu&rsquo;il s&rsquo;agit alors d&rsquo;une d\u00e9marche qualitative de ma\u00eetrise du d\u00e9ferlement quantitatif. Cette d\u00e9marche qualitative n&rsquo;est pas fixe, elle est toujours en \u00e9veil, pour s&rsquo;adapter, \u00e9voluer en pleine vigueur constante, face au flot quantitatif qui ne cesse pas, et selon l&rsquo;\u00e9volution des \u00e9v\u00e8nements qui sollicite elle-m\u00eame cette adaptation. Elle s&rsquo;est renforc\u00e9e, s&rsquo;est justifi\u00e9e, en m\u00eame temps qu&rsquo;elle a trouv\u00e9 ses racines fondamentales dans l&rsquo;\u00e9volution structurelle de l&rsquo;activit\u00e9. Elle constitue, je crois, un ph\u00e9nom\u00e8ne extraordinaire parce qu&rsquo;elle \u00e9tablit un lien entre la mati\u00e8re (l&rsquo;aspect quantitatif) et l&rsquo;esprit (l&rsquo;aspect qualitatif), et l&rsquo;une des rares occurrences dans cette \u00e9poque accouch\u00e9e par le <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_la_source_de_tous_les_maux_ddecrisis_10_09_2010.html\" class=\"gen\">d\u00e9cha\u00eenement de la Mati\u00e8re<\/a> o\u00f9 l&rsquo;esprit soudain riposte, et soudain soumet la Mati\u00e8re \u00e0 son avantage. Je ne veux jamais oublier cette le\u00e7on que la chose est possible, car sans cela comment esp\u00e9rer continuer ?<\/p>\n<\/p>\n<p><p>\tEn 1967,  reprenons cette ann\u00e9e puisque c&rsquo;est celle de mes d\u00e9buts,  un journaliste (les guillemets s&rsquo;expliqueront d&rsquo;eux-m\u00eames, plus loin) disposait pour son information courante des agences de presse ; des reportages et interviews qu&rsquo;il pouvait faire ou qu&rsquo;on pouvait faire dans sa r\u00e9daction, qui \u00e9taient \u00e9videmment limit\u00e9s en nombre, en espace et, souvent, en qualit\u00e9 ; de l&rsquo;acc\u00e8s aux autres journaux, revues, documents divers, etc., l\u00e0 aussi limit\u00e9s en nombre, et d&rsquo;une disposition allong\u00e9e en temps, bien entendu jamais compl\u00e9t\u00e9e par les difficult\u00e9s d&rsquo;acc\u00e8s et l&rsquo;obsolescence. Il y avait enfin le domaine des sources, impliquant des rapports privil\u00e9gi\u00e9s avec des partenaires, des contacts install\u00e9s dans une activit\u00e9 et acceptant sous le couvert de l&rsquo;anonymat, par int\u00e9r\u00eat, d\u00e9sir d&rsquo;influence, estime, etc., de livrer des informations en g\u00e9n\u00e9ral \u00e9trang\u00e8res au domaine public. Le journaliste \u00e9tait certes un acteur original mais restait un acteur passif, d\u00e9pendant de donn\u00e9es et de facteurs incontr\u00f4lables par lui-m\u00eame, et en g\u00e9n\u00e9ral tr\u00e8s limit\u00e9s. Lorsqu&rsquo;il pouvait esp\u00e9rer atteindre une certaine connaissance interne de son domaine de travail (celui o\u00f9 il avait ses sources), il le faisait n\u00e9cessairement en se sp\u00e9cialisant de plus en plus,  connaissances de plus en plus affut\u00e9es et d\u00e9taill\u00e9es mais n\u00e9cessairement de plus en plus restreintes, et de plus en plus li\u00e9es au sujet consid\u00e9r\u00e9. L\u00e0 aussi il restait passif, parce que, enferm\u00e9 dans un domaine pr\u00e9cis, il rencontrait des partenaires n\u00e9cessairement mieux inform\u00e9s que lui. Dans tous les cas, cette passivit\u00e9 impliquait une position collat\u00e9rale, qui \u00e9tait aussi une position de d\u00e9pendance : m\u00eame lorsqu&rsquo;il \u00e9tait tr\u00e8s critique, le journaliste restait comme un appendice du syst\u00e8me,  lequel, \u00e0 mon sens, ne m\u00e9ritait pas encore la majuscule qu&rsquo;on lui met aujourd&rsquo;hui dans <em>dedefensa.org<\/em>, puisqu&rsquo;on rencontrait en son sein une certaine diversit\u00e9, une certaine autonomie possible, etc. D&rsquo;autre part, la vision du journaliste restait n\u00e9cessairement parcellaire, restreinte \u00e0 l&rsquo;imm\u00e9diatet\u00e9 ; pour faire plus large, plus ample, \u00e9ventuellement plus haut ou plus profond c&rsquo;est selon, il fallait passer aux grandes disciplines universitaires,  historiens, politologues, philosophes, etc., elles-m\u00eames enferm\u00e9es dans leurs sp\u00e9cialisations dont l&rsquo;exposition n&rsquo;\u00e9tait pas d\u00e9pouill\u00e9e d&rsquo;une arrogance qui n&rsquo;en facilitait pas l&rsquo;acc\u00e8s. Ainsi fonctionnait la technique du fractionnisme, encore dissimul\u00e9e, qui permet d&#8217;emp\u00eacher dans notre \u00e9poque postmoderniste que le regard puisse embrasser la situation du monde dans toute sa vastitude, qui est la voie vers la v\u00e9rit\u00e9 du monde. <\/p>\n<\/p>\n<p><p>\tJ&rsquo;ai donc connu cette situation, o\u00f9 l&rsquo;on se trouvait notamment,  je prends l&rsquo;exemple le plus glorieux et en principe le plus professionnel des sources,  en pr\u00e9sence de fonctionnaires, de hauts fonctionnaires, militaires ou civils, de ces gens qui font partie de ce qu&rsquo;on nomme nos \u00e9lites, ici dans le domaine de la politique et de la s\u00e9curit\u00e9 au sens large. Ce n&rsquo;\u00e9tait pas vraiment une situation d&rsquo;inf\u00e9riorit\u00e9 affirm\u00e9e ni de suj\u00e9tion affich\u00e9e mais c&rsquo;\u00e9tait bien une situation o\u00f9 ces gens-l\u00e0, les journalistes, dont je faisais partie en v\u00e9rit\u00e9, recueillaient les donn\u00e9es, les avis, les affirmations, comme si nous \u00e9tions,  c&rsquo;est le cas de le dire, n&rsquo;est-ce pas, au bout d&rsquo;une source, attendant avec reconnaissance le jaillissement de l&rsquo;eau,  j&rsquo;allais dire l&rsquo;eau b\u00e9nite Il y avait incontestablement une position implicite, impalpable, mais r\u00e9elle de subordination, pour ce qui concernait le mat\u00e9riel lui-m\u00eame (l&rsquo;information) ; cela n&rsquo;engageait <strong>en rien<\/strong> les deux interlocuteurs,  ce point d\u00e9pendant des caract\u00e8res et d&rsquo;autres facteurs divers,  mais d\u00e9crivait, je dirais objectivement, une situation \u00e0 laquelle il \u00e9tait souvent tentant de s&rsquo;abandonner compl\u00e8tement. (Il y avait de la vanit\u00e9 dans le chef de ces journalistes d&rsquo;\u00eatre ainsi inform\u00e9s en <em>a-parte<\/em> par ces autorit\u00e9s anonymes, et les sources, elles-m\u00eames flatt\u00e9es par cette sorte de contact, s&rsquo;y entendaient pour donner \u00e0 leurs interlocuteurs la sensation d&rsquo;\u00eatre \u00e0 leur propre niveau,  \u00e9change de vulgaires proc\u00e9d\u00e9s, si l&rsquo;on veut.) <\/p>\n<\/p>\n<p><p>\tLes choses ont \u00e9volu\u00e9, on s&rsquo;en doute, durant la d\u00e9cennie des ann\u00e9es 1990, au rythme du d\u00e9veloppement de l&rsquo;Internet comme moyen d&rsquo;information, et aussi au rythme brutal des \u00e9v\u00e8nements politiques,  comme s&rsquo;il y avait un lien de parent\u00e9 entre l&rsquo;\u00e9croulement du communisme et le triomphe du lib\u00e9ralisme, le d\u00e9veloppement de l&rsquo;Internet, avec comme enjeu le d\u00e9veloppement tr\u00e8s rapide du syst\u00e8me de la communication et l&rsquo;arriv\u00e9e \u00e0 sa maturit\u00e9 de surpuissance et bient\u00f4t d&rsquo;autodestruction du Syst\u00e8me,  et il y a certes un lien, sacrebleu ! Le grand basculement et le grand \u00e9v\u00e9nement \u00e0 l&rsquo;int\u00e9rieur de cette \u00e9volution, la <strong>rupture<\/strong> qui sanctionne cette \u00e9volution, de mon point de vue sans le moindre doute, ce fut la guerre du Kosovo. C&rsquo;est durant cet \u00e9v\u00e9nement long de plus de deux mois (du 24 mars au 4 juin 1999) que l&rsquo;on d\u00e9couvrit, pour ceux que la d\u00e9marche int\u00e9ressait, que l&rsquo;on pouvait se tenir inform\u00e9, et diablement bien inform\u00e9, du cours des choses sans passer par les canaux habituels d&rsquo;information,  les agences de presse et la presse standard,  ce que l&rsquo;on nommera presse-<em>Pravda<\/em> et presse-Syst\u00e8me plus tard,  et par les sources officielles, exprim\u00e9es publiquement ou plus anonymement mais toujours selon les standards de l&rsquo;information officielle. Le paradoxe est que ce tournant, qui employait les moyens en plein d\u00e9veloppement de l&rsquo;Internet et qui donna \u00e0 ces moyens une impulsion absolument in\u00e9dite et inattendue, fut d\u00fb \u00e0 ceux, ou une partie de ceux qui allaient constituer, aussit\u00f4t apr\u00e8s, le parti de la guerre, ou <em>War Party<\/em>, aussit\u00f4t apr\u00e8s le 11 septembre 2001, avec des indications s\u00e9rieuses d\u00e8s le printemps 2001 ; ceux qui ont \u00e9t\u00e9 une des forces les plus actives dans un rapport de soumission au d\u00e9veloppement catastrophique du Syst\u00e8me&#8230; En effet, le parti r\u00e9publicain aux USA et ceux qui le soutenaient, encore une fois uni avant la rupture de 9\/11 en une opinion anti-interventionniste, voire isolationniste, s&rsquo;opposa le plus qu&rsquo;il put \u00e0 la participation US \u00e0 la guerre du Kosovo, qu&rsquo;il attribuait justement \u00e0 l&rsquo;aile interventionniste des lib\u00e9raux-progressistes (les <em>liberal hawks<\/em>, qui se sont \u00e0 nouveau manifest\u00e9s avec la Libye et la Syrie). Ainsi, pendant toute la guerre du Kosovo, les deux principales sources d&rsquo;information selon mon jugement et d&rsquo;apr\u00e8s la pratique de la chose, avec quelques autres compl\u00e8mentairement, furent <em>Antiwar.com<\/em> (on sait ce que ces gens sont devenus, rest\u00e9s fid\u00e8les \u00e0 eux-m\u00eames) et,  \u00f4 surprise r\u00e9trospective,  <em>STRATFOR<\/em>, alors en pleine opposition \u00e0 la guerre (on sait ce que ces gens se sont r\u00e9v\u00e9l\u00e9s \u00eatre,  on lit le rappel de la chose le <a href=\"http:\/\/www.dedefensa.org\/article-notes_sur_le_gouffre_stratfor__29_02_2012.html\" class=\"gen\">29 f\u00e9vrier 2012<\/a>). C&rsquo;\u00e9taient les deux ailes du parti r\u00e9publicain, encore unies avant de se s\u00e9parer pour devenir ennemis jur\u00e9s entre l&rsquo;aile pal\u00e9o-conservatrice rest\u00e9e isolationniste et non-interventionniste, et l&rsquo;aile n\u00e9o-conservatrice, devenue unilat\u00e9raliste et farouchement interventionniste.<\/p>\n<\/p>\n<p><p>\tEt \u00e0 partir de l\u00e0, tout fut diff\u00e9rent car plus rien ne fut comme avant. La guerre du Kosovo, qui avait consacr\u00e9 de nouveaux moyens de parvenir, pour ceux qui le veulent, \u00e0 la v\u00e9rit\u00e9 du monde, avait d\u00e9pouill\u00e9 les voix officielles de la pompe de l&rsquo;objectivit\u00e9 et de leur pr\u00e9tention \u00e0 la v\u00e9rit\u00e9,  jusqu&rsquo;\u00e0 para\u00eetre nues, ces voix, comme le roi du m\u00eame tonneau. (Voir un peu plus tard l&rsquo;aveu de <a href=\"http:\/\/www.dedefensa.org\/article-je_doute_donc_je_suis_13_03_2003.html\" class=\"gen\">Rumsfeld<\/a>.) Aujourd&rsquo;hui, je ne sacrifierais pas une journ\u00e9e de mon temps pour pouvoir parler un quart d&rsquo;heure avec un quelconque ministre des affaires \u00e9trang\u00e8res, comme j&rsquo;aurais fait bien entendu, et au-del\u00e0, en 1967 ; si l&rsquo;on parle du commun des ministres, je sais qui il est, ce qu&rsquo;il pense et ce qu&rsquo;il dira, et surtout je sais ce qu&rsquo;il ne peut plus \u00eatre, ni penser, ni dire. Alors, on le laisse \u00e0 son image et qu&rsquo;il aille jouer avec cette poussi\u00e8re.<\/p>\n<\/p>\n<p><p>\tAinsi, d\u00e8s lors que fut connue la chose, l&rsquo;\u00e9v\u00e8nement dont je parle, la messe \u00e9tait dite. Ceux qui avaient choisi leur camp, et l&rsquo;on sait duquel je parle, \u00e9taient pr\u00eats \u00e0 la bataille Et \u00e0 partir de l\u00e0, on abandonna le terme de journaliste d\u00e9pouill\u00e9 de ses guillemets, lui et sa d\u00e9froque taill\u00e9e sur mesure, pour celui de chroniqueur, puis d&rsquo;historien et de m\u00e9tahistorien de l&rsquo;imm\u00e9diat. Le constat formidable de cette \u00e9poque \u00e0 nulle autre pareille se dessinait que, d\u00e9sormais, l&rsquo;Histoire devenue m\u00e9tahistoire pouvait se d\u00e9chiffrer presque au jour le jour des \u00e9v\u00e8nements du monde auxquels nos moyens nouveaux donnaient acc\u00e8s, et cette d\u00e9marche appuy\u00e9e sur l&rsquo;exp\u00e9rience et avec l&rsquo;aide sans quoi rien n&rsquo;est possible de l&rsquo;intuition haute. Ce regard-l\u00e0, du journaliste devenu chroniqueur et m\u00e9tahistorien, qui d\u00e9pend de l&rsquo;acuit\u00e9 du choix qu&rsquo;on fait, rend compte de l&rsquo;aspect qualitatif, du service de l&rsquo;esprit dont je parlais plus haut.<\/p>\n<\/p>\n<p><p>\tUn champ nouveau s&rsquo;est ouvert. Le m\u00e9tier de journaliste dispara\u00eet, corps et bien avec ses guillemets, dans le linceul confortable de la presse-Syst\u00e8me. Apparus en plein jour, leur bassesse et le vide de leur conscience vous laissent stup\u00e9faits ; ma conviction est qu&rsquo;ils ne s&rsquo;en remettront jamais, les journalistes-Syst\u00e8me. Alors, c&rsquo;est \u00e0 nous d&rsquo;agir, de faire, et la chose est \u00e0 la fois exaltante et \u00e9crasante. Il s&rsquo;agit du domaine de l&rsquo;Internet, o\u00f9 s&rsquo;est install\u00e9 le syst\u00e8me de la communication, d&rsquo;o\u00f9 nous contemplons la r\u00e9volution du domaine, dont le terme est alors \u00e0 prendre dans son sens litt\u00e9ral, astronomique ; avec ce domaine et avec ce moyen de l&rsquo;Internet, nous avons effectu\u00e9 un tour complet pour revenir au point fondamental de tout cycle m\u00e9tahistorique, \u00e0 sa fin et en son d\u00e9but, o\u00f9 nous disposons de tous les attributs et tous les moyens correspondant \u00e0 la technicit\u00e9 du temps pour pouvoir juger avec une audace inou\u00efe de la pens\u00e9e, et presque dans l&rsquo;imm\u00e9diatet\u00e9 du temps, de la r\u00e9elle signification de ce temps que nous vivons, qui est m\u00e9tahistorique et qui, pour cette raison, mobilise ainsi toutes nos capacit\u00e9s. Il faut \u00eatre convaincu que c&rsquo;est parce que ce temps est si exceptionnel que nous disposons d&rsquo;un tel outil pour tenter de le saisir et de le comprendre. C&rsquo;est une responsabilit\u00e9 \u00e9crasante et exaltante.<\/p>\n<\/p>\n<p><p>\tLa chose n&rsquo;est pas simple. L&rsquo;Internet est encombr\u00e9 de tout ce qu&rsquo;il est possible de concevoir, jusqu&rsquo;\u00e0 l&rsquo;inconcevable ; les fous, les escrocs, les m\u00e9diocres, les mythomanes, les aventuriers, les provocateurs, les illumin\u00e9s, les journalistes reconvertis, les comploteurs, les malades, les simples d&rsquo;esprit, les visionnaires, les proph\u00e8tes, les pr\u00eacheurs et les p\u00eacheurs, bref toute cette Cour des Miracles postmoderniste comme vous et moi C&rsquo;est dans cette affluence extraordinaire o\u00f9 pourtant se trouve l&rsquo;une ou l&rsquo;autre voie fondamentale pour la compr\u00e9hension du monde qu&rsquo;il faut se frayer un chemin qui soit de cette veine, et pers\u00e9v\u00e9rer, et <strong>tenir<\/strong> absolument. Il n&rsquo;y a pas, aujourd&rsquo;hui, de consigne plus droite et plus haute, et c&rsquo;est la gloire de notre libert\u00e9 de s&rsquo;y tenir absolument.<\/p>\n<\/p>\n<p>\n<p class=\"signature\">Philippe Grasset<\/p>\n<\/p>\n<h4>Notes en forme de <em>Post-Scriptum<\/em><\/h4>\n<p>Il \u00e9tait \u00e9crit, le dernier <a href=\"http:\/\/www.dedefensa.org\/article-chronique_du_19_courant_pr_sentation_19_07_2012.html\" class=\"gen\">19 courant<\/a>,  ceci  : \u00ab<em>Je crois que, souvent, ou bien parfois je ne sais, le texte de cette Chronique du 19 courant sera termin\u00e9e par cette Note en forme de Post Scriptum&rsquo; dont le r\u00f4le sera de clore le texte par un rappel de la situation des donations, ce 19 courant Habile, n&rsquo;est-ce pas ?<\/em>\u00bb<\/p>\n<\/p>\n<p><p>\tHabile, je ne sais pas, vraiment Mais, bref, cela est dit, \u00e9crit, recopi\u00e9. Consultez la barre de comptage mise en place \u00e0 partir d&rsquo;aujourd&rsquo;hui, comme l&rsquo;habituel signal d&rsquo;alarme,  aidez-nous et merci pour votre aide.<\/p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chronique du 19 courant Bilan Ce 19 ao\u00fbt 2012&#8230; Entamer cette nouvelle rubrique comme l&rsquo;on dit d&rsquo;une nouvelle cat\u00e9gorie de textes, un nouveau genre par rapport aux habitudes du site, comme l&rsquo;on met le pied sur une terra incognita J&rsquo;y entre avec r\u00e9solution et avec prudence, avec enthousiasme et avec incertitude, avec assurance et avec&hellip;&nbsp;<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"","neve_meta_content_width":0,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":"","jetpack_post_was_ever_published":false},"categories":[18],"tags":[11598,4646,5943,5993,12981,2980,11007,2981,7099,2651,60],"class_list":["post-73328","post","type-post","status-publish","format-standard","hentry","category-archivesphg","tag-11598","tag-antisysteme","tag-appel","tag-bilan","tag-chronique","tag-comptage","tag-courant","tag-dedefensa-org","tag-donations","tag-du","tag-internet"],"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/comments?post=73328"}],"version-history":[{"count":0,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/posts\/73328\/revisions"}],"wp:attachment":[{"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/media?parent=73328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/categories?post=73328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/new.dedefensa.org\/index.php\/wp-json\/wp\/v2\/tags?post=73328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}